{"id":140835,"date":"2012-01-13T17:35:20","date_gmt":"2012-01-13T16:35:20","guid":{"rendered":"http:\/\/www.madrimasd.org\/blogs\/universo\/?p=140835"},"modified":"2012-01-13T19:38:25","modified_gmt":"2012-01-13T18:38:25","slug":"claves-de-la-taxonomia-de-suelos-en-espanol-2010-ya-se-encuentra-de-libre-acceso-en-internet","status":"publish","type":"post","link":"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/01\/13\/140835","title":{"rendered":"Claves de la Taxonom\u00eda de Suelos en Espa\u00f1ol 2010 ya se encuentra de libre Acceso en Internet"},"content":{"rendered":"<p style=\"text-align: justify;\">Ya os comentamos hace aproximadamente un a\u00f1o que <a title=\"Enlace permanente: La Nueva Clave de la Taxonom\u00eda Americana de Suelos ya se encuentra accesible en Internet\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/12\/29\/137106\">la nueva clave de la Taxonom\u00eda Americana de Suelos ya se encontraba accesible en Internet<\/a>. Sin embargo, nos refer\u00edamos a la <span style=\"color: #3366ff;\"><strong><em>edici\u00f3n en suahili<\/em><\/strong>. <strong>Recientemente<\/strong> <\/span>Luis A. Hern\u00e1ndez, de la USDA-NRCS, ha informado a la secretar\u00eda de la SECS, y m\u00e1s concretamente a su secretaria Irene Ortiz Bernad, que las<span style=\"color: #3366ff;\"> <strong>Claves para la Taxonom\u00eda de Suelos<\/strong> <strong>2010, traducida al Espa\u00f1ol\u00a0 ya se encuentra de libre acceso en el ciberespacio<\/strong><\/span> (ver enlace al final del post). Tal tarea ha sido llevada a cabo por\u00a0 nuestros colegas mexicanos Carlos A. Ortiz-Solorio, Mar\u00eda del Carmen Guti\u00e9rrez-Castorena y Edgar V. Guti\u00e9rrez-Castorena, a los que debemos agradecer su esfuerzo. Obviamente los miembros de la SECS ya tienen conocimiento de este nuevo e imprescindible documento por las alertas que env\u00eda Irene, como dejo constancia al final de esta entrega. En consecuencia, este post est\u00e1 destinado a difundir la noticia entre <span style=\"color: #3366ff;\"><strong>los edaf\u00f3logos hispanoparlantes<\/strong> <\/span>que aun no se encuentren debidamente informados por sus respectivas sociedades nacionales, o que no est\u00e9n adscritos a ninguna de ellas. <span style=\"color: #3366ff;\"><strong>Nuestra opini\u00f3n sobre las novedades que incluye fue expuesta en el post de 2010 (primer enlace)<\/strong><\/span>, en donde os d\u00e1bamos noticias de las mismas. Tambi\u00e9n cabe mencionar que, en aras de incorporarse a la modernidad, <span style=\"color: #3366ff;\"><strong>la versi\u00f3n inglesa\u00a0en un<em> e-book<\/em> (libro electr\u00f3nico), tambi\u00e9n se encuentra a disposici\u00f3n del p\u00fablico gratuitamente, en las direcciones Web que os ofrezco abajo<\/strong><\/span>.<\/p>\n<p style=\"text-align: justify;\">\u00a0<img decoding=\"async\" class=\"ngg-singlepic ngg-left\" src=\"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-content\/blogs.dir\/42\/files\/1123\/claves-taxonomia-americana-de-suelos-2010-espanol.jpg\" alt=\"claves-taxonomia-americana-de-suelos-2010-espanol\" width=\"288\" height=\"336\" \/><a class=\"shutterset_\" title=\"Claves para la Taxonom\u00eda de Suelos 2010, traducida al Espa\u00f1ol  ya se encuentra de libre Acceso en el ciberespacio\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-content\/blogs.dir\/42\/files\/1123\/claves-taxonomia-americana-de-suelos-2010-espanol.jpg\"><\/a><\/p>\n<p style=\"text-align: justify;\">Como os indicamos ya en aquel post de 2010,<span style=\"color: #3366ff;\"> <strong>la principal novedad de esta onceava viene explicitada en negrita en el siguiente p\u00e1rrafo de las susodichas claves<\/strong><\/span>:<\/p>\n<p style=\"text-align: justify;\"><!--more--><\/p>\n<p style=\"text-align: justify;\"><em>La publicaci\u00f3n de las Claves para la Taxonom\u00eda de Suelos tiene dos prop\u00f3sitos: proporcionar las claves taxon\u00f3micas necesarias para la clasificaci\u00f3n de suelos en una forma tal que se puedan usar f\u00e1cilmente en el campo y dar a conocer a los usuarios del sistema taxon\u00f3mico los cambios m\u00e1s recientes del sistema. <strong>La onceava edici\u00f3n de las Claves para la Taxonom\u00eda de Suelos incorpora<\/strong> todos los cambios aprobados desde la publicaci\u00f3n de la segunda edici\u00f3n de la Taxonom\u00eda de Suelos: Un Sistema B\u00e1sico de Clasificaci\u00f3n de Suelos para hacer e interpretar Levantamientos de Suelos (1999).<strong> <\/strong><strong>Uno de los cambios m\u00e1s significativos de la onceava edici\u00f3n es la adici\u00f3n de los sub\u00f3rdenes Wassents y Wassists para Entisols e Histosols subacuosos.<\/strong><\/em><\/p>\n<p><span style=\"color: #008000;\"><strong>Juan Jos\u00e9 Ib\u00e1\u00f1ez<\/strong><\/span><\/p>\n<p><a href=\"http:\/\/soils.usda.gov\/technical\/classification\/tax_keys\/index.html\">Claves para la Taxonom\u00eda de Suelos, Onceava Edici\u00f3n, 2010<\/a><\/p>\n<p><span style=\"color: #008080;\"><strong>Citaci\u00f3n recomendada<\/strong>:<\/span> Soil Survey Staff. 2010. Claves para la Taxonom\u00eda de Suelos, 11th ed. USDA-Natural Resources Conservation Service, Washington, DC.<\/p>\n<p><span style=\"color: #008080;\"><strong>Entidad que edita<\/strong><\/span>:<\/p>\n<p>Soil Survey Staff; Departamento de Agricultura de los Estados Unidos; Servicio de Conservaci\u00f3n de Recursos Naturales; Onceava Edici\u00f3n, 2010<\/p>\n<p><span style=\"color: #008080;\"><strong>Mensaje recibido desde la secretar\u00eda de la SECS<\/strong><\/span><\/p>\n<p>Estimados socios de la SECS:\u00a0<\/p>\n<p>Luis A. Hern\u00e1ndez, CPSC, CPSSC de la Region 16 Team Leader \/ State Soil Scientist, del USDA-NRCS, nos informa de que la versi\u00f3n que sale cada cuatro a\u00f1os de la Soil Taxonomy est\u00e1 disponible en espa\u00f1ol, de lo que os informo por si puede ser de vuestro inter\u00e9s.<\/p>\n<p><span style=\"color: #008080;\"><strong>Enlace para adquirir el documento<\/strong><\/span><br \/>\n<a href=\"http:\/\/soils.usda.gov\/technical\/classification\/tax_keys\/index.html\" target=\"_blank\">http:\/\/soils.usda.gov\/technical\/classification\/tax_keys\/index.html<\/a><\/p>\n<p>Un cordial saludo,\u00a0<br \/>\nIrene Ortiz Bernad<\/p>\n<p style=\"text-align: justify;\">Secretaria General de la SECS. Departamento de Edafolog\u00eda y Qu\u00edmica Agr\u00edcola; Facultad de Ciencias. Universidad de Granada. Campus de Fuentenueva, s\/n Granada (Spain) 18071<\/p>\n<h3>Im\u00e1genes Relacionadas:<\/h3>","protected":false},"excerpt":{"rendered":"<p>Ya os comentamos hace aproximadamente un a\u00f1o que la nueva clave de la Taxonom\u00eda Americana de Suelos ya se encontraba accesible en Internet. Sin embargo, nos refer\u00edamos a la edici\u00f3n en suahili. Recientemente Luis A. Hern\u00e1ndez, de la USDA-NRCS, ha informado a la secretar\u00eda de la SECS, y m\u00e1s concretamente a su secretaria Irene Ortiz Bernad, que las Claves para la Taxonom\u00eda de Suelos 2010, traducida al Espa\u00f1ol\u00a0 ya se encuentra de libre acceso en el ciberespacio (ver enlace al final del post). Tal tarea ha sido llevada a cabo por\u00a0 nuestros colegas mexicanos Carlos A. Ortiz-Solorio, Mar\u00eda del Carmen\u2026<\/p>\n","protected":false},"author":26,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0},"categories":[584,597,615,601],"tags":[46709,10107,47191,10108],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":4}},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Ya os comentamos hace aproximadamente un a\u00f1o que la nueva clave de la Taxonom\u00eda Americana de Suelos ya se encontraba accesible en Internet. Sin embargo, nos refer\u00edamos a la edici\u00f3n en suahili. Recientemente Luis A. Hern\u00e1ndez, de la USDA-NRCS, ha informado a la secretar\u00eda de la SECS, y m\u00e1s concretamente a su secretaria Irene Ortiz\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Juan Jos\u00e9 Ib\u00e1\u00f1ez\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/01\/13\/140835\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Un Universo invisible bajo nuestros pies - Los suelos y la vida\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Claves de la Taxonom\u00eda de Suelos en Espa\u00f1ol 2010 ya se encuentra de libre Acceso en Internet - Un Universo invisible bajo nuestros pies\" \/>\n\t\t<meta property=\"og:description\" content=\"Ya os comentamos hace aproximadamente un a\u00f1o que la nueva clave de la Taxonom\u00eda Americana de Suelos ya se encontraba accesible en Internet. Sin embargo, nos refer\u00edamos a la edici\u00f3n en suahili. Recientemente Luis A. Hern\u00e1ndez, de la USDA-NRCS, ha informado a la secretar\u00eda de la SECS, y m\u00e1s concretamente a su secretaria Irene Ortiz\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/01\/13\/140835\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2012-01-13T16:35:20+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2012-01-13T18:38:25+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/juan.j.marti.14\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Claves de la Taxonom\u00eda de Suelos en Espa\u00f1ol 2010 ya se encuentra de libre Acceso en Internet - Un Universo invisible bajo nuestros pies\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Ya os comentamos hace aproximadamente un a\u00f1o que la nueva clave de la Taxonom\u00eda Americana de Suelos ya se encontraba accesible en Internet. Sin embargo, nos refer\u00edamos a la edici\u00f3n en suahili. Recientemente Luis A. Hern\u00e1ndez, de la USDA-NRCS, ha informado a la secretar\u00eda de la SECS, y m\u00e1s concretamente a su secretaria Irene Ortiz\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2012\\\/01\\\/13\\\/140835#blogposting\",\"name\":\"Claves de la Taxonom\\u00eda de Suelos en Espa\\u00f1ol 2010 ya se encuentra de libre Acceso en Internet - Un Universo invisible bajo nuestros pies\",\"headline\":\"Claves de la Taxonom\\u00eda de Suelos en Espa\\u00f1ol 2010 ya se encuentra de libre Acceso en Internet\",\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"http:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/wp-content\\\/blogs.dir\\\/42\\\/files\\\/1123\\\/claves-taxonomia-americana-de-suelos-2010-espanol.jpg\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2012\\\/01\\\/13\\\/140835\\\/#articleImage\"},\"datePublished\":\"2012-01-13T17:35:20+01:00\",\"dateModified\":\"2012-01-13T19:38:25+01:00\",\"inLanguage\":\"es-ES\",\"commentCount\":3,\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2012\\\/01\\\/13\\\/140835#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2012\\\/01\\\/13\\\/140835#webpage\"},\"articleSection\":\"Documentos sobre Edafolog\\u00eda + Instituciones + Enlaces, Filosof\\u00eda, Historia y Sociolog\\u00eda de la Edafolog\\u00eda, Notas Breves de Prensa, Taxonom\\u00edas y Clasificaciones, 2010, Claves de la Taxonom\\u00eda de Suelos Americana, Libre Acceso en Internet, traducci\\u00f3n al Espa\\u00f1ol\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2012\\\/01\\\/13\\\/140835#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/documentos-sobre-edafologia-instituciones-enlaces#listItem\",\"name\":\"Documentos sobre Edafolog\\u00eda + Instituciones + Enlaces\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/documentos-sobre-edafologia-instituciones-enlaces#listItem\",\"position\":2,\"name\":\"Documentos sobre Edafolog\\u00eda + Instituciones + Enlaces\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/documentos-sobre-edafologia-instituciones-enlaces\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2012\\\/01\\\/13\\\/140835#listItem\",\"name\":\"Claves de la Taxonom\\u00eda de Suelos en Espa\\u00f1ol 2010 ya se encuentra de libre Acceso en Internet\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2012\\\/01\\\/13\\\/140835#listItem\",\"position\":3,\"name\":\"Claves de la Taxonom\\u00eda de Suelos en Espa\\u00f1ol 2010 ya se encuentra de libre Acceso en Internet\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/documentos-sobre-edafologia-instituciones-enlaces#listItem\",\"name\":\"Documentos sobre Edafolog\\u00eda + Instituciones + Enlaces\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#organization\",\"name\":\"Un Universo invisible bajo nuestros pies\",\"description\":\"Los suelos y la vida\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/files\\\/2022\\\/02\\\/logo.png\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2012\\\/01\\\/13\\\/140835\\\/#organizationLogo\",\"width\":217,\"height\":72},\"image\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2012\\\/01\\\/13\\\/140835\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/juan.j.marti.14\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo\",\"name\":\"Juan Jos\\u00e9 Ib\\u00e1\\u00f1ez\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2012\\\/01\\\/13\\\/140835#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/387f3a100385573d8f42ce2a3211fd1c?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Juan Jos\\u00e9 Ib\\u00e1\\u00f1ez\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2012\\\/01\\\/13\\\/140835#webpage\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2012\\\/01\\\/13\\\/140835\",\"name\":\"Claves de la Taxonom\\u00eda de Suelos en Espa\\u00f1ol 2010 ya se encuentra de libre Acceso en Internet - Un Universo invisible bajo nuestros pies\",\"description\":\"Ya os comentamos hace aproximadamente un a\\u00f1o que la nueva clave de la Taxonom\\u00eda Americana de Suelos ya se encontraba accesible en Internet. Sin embargo, nos refer\\u00edamos a la edici\\u00f3n en suahili. Recientemente Luis A. Hern\\u00e1ndez, de la USDA-NRCS, ha informado a la secretar\\u00eda de la SECS, y m\\u00e1s concretamente a su secretaria Irene Ortiz\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2012\\\/01\\\/13\\\/140835#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\"},\"datePublished\":\"2012-01-13T17:35:20+01:00\",\"dateModified\":\"2012-01-13T19:38:25+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#website\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/\",\"name\":\"Un Universo invisible bajo nuestros pies\",\"description\":\"Los suelos y la vida\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Claves de la Taxonom\u00eda de Suelos en Espa\u00f1ol 2010 ya se encuentra de libre Acceso en Internet - Un Universo invisible bajo nuestros pies","description":"Ya os comentamos hace aproximadamente un a\u00f1o que la nueva clave de la Taxonom\u00eda Americana de Suelos ya se encontraba accesible en Internet. Sin embargo, nos refer\u00edamos a la edici\u00f3n en suahili. Recientemente Luis A. Hern\u00e1ndez, de la USDA-NRCS, ha informado a la secretar\u00eda de la SECS, y m\u00e1s concretamente a su secretaria Irene Ortiz","canonical_url":"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/01\/13\/140835","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/01\/13\/140835#blogposting","name":"Claves de la Taxonom\u00eda de Suelos en Espa\u00f1ol 2010 ya se encuentra de libre Acceso en Internet - Un Universo invisible bajo nuestros pies","headline":"Claves de la Taxonom\u00eda de Suelos en Espa\u00f1ol 2010 ya se encuentra de libre Acceso en Internet","author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author"},"publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#organization"},"image":{"@type":"ImageObject","url":"http:\/\/www.madrimasd.org\/blogs\/universo\/wp-content\/blogs.dir\/42\/files\/1123\/claves-taxonomia-americana-de-suelos-2010-espanol.jpg","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/01\/13\/140835\/#articleImage"},"datePublished":"2012-01-13T17:35:20+01:00","dateModified":"2012-01-13T19:38:25+01:00","inLanguage":"es-ES","commentCount":3,"mainEntityOfPage":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/01\/13\/140835#webpage"},"isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/01\/13\/140835#webpage"},"articleSection":"Documentos sobre Edafolog\u00eda + Instituciones + Enlaces, Filosof\u00eda, Historia y Sociolog\u00eda de la Edafolog\u00eda, Notas Breves de Prensa, Taxonom\u00edas y Clasificaciones, 2010, Claves de la Taxonom\u00eda de Suelos Americana, Libre Acceso en Internet, traducci\u00f3n al Espa\u00f1ol"},{"@type":"BreadcrumbList","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/01\/13\/140835#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo#listItem","position":1,"name":"Home","item":"https:\/\/www.madrimasd.org\/blogs\/universo","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/documentos-sobre-edafologia-instituciones-enlaces#listItem","name":"Documentos sobre Edafolog\u00eda + Instituciones + Enlaces"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/documentos-sobre-edafologia-instituciones-enlaces#listItem","position":2,"name":"Documentos sobre Edafolog\u00eda + Instituciones + Enlaces","item":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/documentos-sobre-edafologia-instituciones-enlaces","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/01\/13\/140835#listItem","name":"Claves de la Taxonom\u00eda de Suelos en Espa\u00f1ol 2010 ya se encuentra de libre Acceso en Internet"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/01\/13\/140835#listItem","position":3,"name":"Claves de la Taxonom\u00eda de Suelos en Espa\u00f1ol 2010 ya se encuentra de libre Acceso en Internet","previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/documentos-sobre-edafologia-instituciones-enlaces#listItem","name":"Documentos sobre Edafolog\u00eda + Instituciones + Enlaces"}}]},{"@type":"Organization","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#organization","name":"Un Universo invisible bajo nuestros pies","description":"Los suelos y la vida","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/","logo":{"@type":"ImageObject","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/01\/13\/140835\/#organizationLogo","width":217,"height":72},"image":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/01\/13\/140835\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/juan.j.marti.14"]},{"@type":"Person","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo","name":"Juan Jos\u00e9 Ib\u00e1\u00f1ez","image":{"@type":"ImageObject","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/01\/13\/140835#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/387f3a100385573d8f42ce2a3211fd1c?s=96&d=mm&r=g","width":96,"height":96,"caption":"Juan Jos\u00e9 Ib\u00e1\u00f1ez"}},{"@type":"WebPage","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/01\/13\/140835#webpage","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/01\/13\/140835","name":"Claves de la Taxonom\u00eda de Suelos en Espa\u00f1ol 2010 ya se encuentra de libre Acceso en Internet - Un Universo invisible bajo nuestros pies","description":"Ya os comentamos hace aproximadamente un a\u00f1o que la nueva clave de la Taxonom\u00eda Americana de Suelos ya se encontraba accesible en Internet. Sin embargo, nos refer\u00edamos a la edici\u00f3n en suahili. Recientemente Luis A. Hern\u00e1ndez, de la USDA-NRCS, ha informado a la secretar\u00eda de la SECS, y m\u00e1s concretamente a su secretaria Irene Ortiz","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#website"},"breadcrumb":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/01\/13\/140835#breadcrumblist"},"author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author"},"creator":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author"},"datePublished":"2012-01-13T17:35:20+01:00","dateModified":"2012-01-13T19:38:25+01:00"},{"@type":"WebSite","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#website","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/","name":"Un Universo invisible bajo nuestros pies","description":"Los suelos y la vida","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Un Universo invisible bajo nuestros pies - Los suelos y la vida","og:type":"article","og:title":"Claves de la Taxonom\u00eda de Suelos en Espa\u00f1ol 2010 ya se encuentra de libre Acceso en Internet - Un Universo invisible bajo nuestros pies","og:description":"Ya os comentamos hace aproximadamente un a\u00f1o que la nueva clave de la Taxonom\u00eda Americana de Suelos ya se encontraba accesible en Internet. Sin embargo, nos refer\u00edamos a la edici\u00f3n en suahili. Recientemente Luis A. Hern\u00e1ndez, de la USDA-NRCS, ha informado a la secretar\u00eda de la SECS, y m\u00e1s concretamente a su secretaria Irene Ortiz","og:url":"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/01\/13\/140835","og:image":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png","og:image:secure_url":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png","article:published_time":"2012-01-13T16:35:20+00:00","article:modified_time":"2012-01-13T18:38:25+00:00","article:publisher":"https:\/\/www.facebook.com\/juan.j.marti.14","twitter:card":"summary","twitter:title":"Claves de la Taxonom\u00eda de Suelos en Espa\u00f1ol 2010 ya se encuentra de libre Acceso en Internet - Un Universo invisible bajo nuestros pies","twitter:description":"Ya os comentamos hace aproximadamente un a\u00f1o que la nueva clave de la Taxonom\u00eda Americana de Suelos ya se encontraba accesible en Internet. Sin embargo, nos refer\u00edamos a la edici\u00f3n en suahili. Recientemente Luis A. Hern\u00e1ndez, de la USDA-NRCS, ha informado a la secretar\u00eda de la SECS, y m\u00e1s concretamente a su secretaria Irene Ortiz","twitter:image":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png"},"aioseo_meta_data":{"post_id":"140835","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":null,"isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","tabs":null,"priority":null,"frequency":null,"local_seo":null,"created":"2022-06-03 16:14:52","updated":"2026-05-26 17:07:53","limit_modified_date":false,"ai":null,"breadcrumb_settings":null,"seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/documentos-sobre-edafologia-instituciones-enlaces\" title=\"Documentos sobre Edafolog\u00eda + Instituciones + Enlaces\">Documentos sobre Edafolog\u00eda + Instituciones + Enlaces<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tClaves de la Taxonom\u00eda de Suelos en Espa\u00f1ol 2010 ya se encuentra de libre Acceso en Internet\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.madrimasd.org\/blogs\/universo"},{"label":"Documentos sobre Edafolog\u00eda + Instituciones + Enlaces","link":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/documentos-sobre-edafologia-instituciones-enlaces"},{"label":"Claves de la Taxonom\u00eda de Suelos en Espa\u00f1ol 2010 ya se encuentra de libre Acceso en Internet","link":"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/01\/13\/140835"}],"_links":{"self":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts\/140835"}],"collection":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/comments?post=140835"}],"version-history":[{"count":17,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts\/140835\/revisions"}],"predecessor-version":[{"id":141122,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts\/140835\/revisions\/141122"}],"wp:attachment":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/media?parent=140835"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/categories?post=140835"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/tags?post=140835"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}