{"id":141646,"date":"2012-05-22T12:26:37","date_gmt":"2012-05-22T11:26:37","guid":{"rendered":"http:\/\/www.madrimasd.org\/blogs\/universo\/?p=141646"},"modified":"2012-05-22T12:26:37","modified_gmt":"2012-05-22T11:26:37","slug":"lixisoles-geografia-ambiente-y-paisaje","status":"publish","type":"post","link":"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/05\/22\/141646","title":{"rendered":"Lixisoles: Geograf\u00eda, Ambiente y Paisaje"},"content":{"rendered":"<p style=\"text-align: justify;\">Como ya os comentamos en el post anterior, los <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/05\/09\/141636\">Lixisoles<\/a> son <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2006\/10\/15\/46305\" target=\"_blank\"><span style=\"color: #0000ff; font-size: small;\">suelos zonales<\/span><\/a> <span style=\"font-size: small;\"><span style=\"text-decoration: underline;\"><span style=\"color: #0000ff;\">cuya formaci\u00f3n se encuentra condicionada por el clima<\/span><\/span>. Sus principales diferencias respecto a otros grupos de suelos de referencia de la WRB <span style=\"color: #3366ff;\"><strong>con perfiles modales A\/Bt\/C<\/strong><\/span> estriba en poseer arcillas de baja actividad (poca capacidad de retener nutrientes y agua) aunque si atesoran elementos qu\u00edmicos para el desarrollo de las plantas. En cualquier caso, sus propiedades <span style=\"color: #3366ff;\"><strong>no les hacen muy aptos para la producci\u00f3n agropecuaria<\/strong><\/span>, salvo en lo que concierne a cultivos poco exigentes<strong>. <span style=\"color: #3366ff;\">A nivel mundial se ubican fundamentalmente en el este de Latinoam\u00e9rica y este del continente africano<\/span><\/strong><span style=\"color: #3366ff;\">. <span style=\"color: #333333;\">Se calcula que cubren unos <\/span><strong>435 millones de hect\u00e1reas de la edafosfera global<\/strong>,<\/span> como narraremos posteriormente. Seguimos pues con nuestro <\/span><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/curso-basico-tipos-de-suelos-del-mundo\" target=\"_blank\"><span style=\"color: #0000ff; font-size: small;\">curso b\u00e1sico sobre los tipos de suelos de mundo<\/span><\/a><span style=\"font-size: small;\">.\u00a0 El texto que abajo exponemos ha sido traducido al espa\u00f1ol castellano realizada <span style=\"color: #3366ff;\"><strong>por Javier Manr\u00edquez Cos\u00edo<\/strong> <\/span>de la monograf\u00eda \u201c<a href=\"http:\/\/www.fao.org\/DOCREP\/003\/Y1899E\/Y1899E00.HTM\" target=\"_blank\">Lecture notes on the major soils of the world<\/a>.<\/span><span style=\"font-family: Times New Roman; font-size: small;\"> <\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: small;\"> <img decoding=\"async\" class=\"ngg-singlepic ngg-center\" src=\"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-content\/blogs.dir\/42\/files\/370\/lixisol.gif\" alt=\"lixisoles mapa del Mundo\" \/><\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"color: #0000ff; font-size: small;\">Mapa de los Lixisoles del Mundo. Fuente: FAO<\/span><\/p>\n<p><span style=\"font-family: Times New Roman; font-size: small;\"> <!--more--><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #008080;\"><strong><span style=\"font-size: small;\">DISTRIBUCI\u00d3N REGIONAL DE LOS LIXISOLES <\/span><\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: small;\">Los Lixisoles<span style=\"color: #3366ff;\"> <strong>se encuentran en regiones c\u00e1lidas templadas, tropicales y subtropicales, estacionalmente secas, sobre superficies del Pleistoceno o m\u00e1s antiguas<\/strong><\/span>. Estos suelos cubren un \u00e1rea total de cerca <span style=\"color: #3366ff;\"><strong>de 435 millones de hect\u00e1reas, de las cuales, m\u00e1s de la mitad est\u00e1n en el este de \u00c1frica y zona sub Saheliana, casi una cuarta parte en Centro y Sudam\u00e9rica y las restantes, en <\/strong><\/span>el subcontinente Indio y el sureste de Asia y Australia. <span style=\"color: #3366ff;\"><strong>Como los Lixisoles son una introducci\u00f3n reciente en la clasificaci\u00f3n del suelo, su extensi\u00f3n total no esta bien cuantificada a\u00fan<\/strong><\/span>.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #008080;\"><strong><span style=\"font-size: small;\">ASOCIACIONES CON OTROS GRUPOS DE SUELOS DE REFERENCIA <\/span><\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: small;\">Los Lixisoles <span style=\"color: #3366ff;\"><strong>se encuentran junto<\/strong> <\/span>con otros suelos que tienen un horizonte subsuperficial \u00c1rgico, tales como<span style=\"color: #3366ff;\"> <strong>los Alisoles, Acrisoles y Luvisoles<\/strong><\/span>. Las diferencias entre estos Grupos de Suelos de Referencia y los Lixisoles est\u00e1n basadas en sus diferentes propiedades anal\u00edticas, <span style=\"color: #3366ff;\"><strong>por lo que su clasificaci\u00f3n puede llegar a ser problem\u00e1tica en el campo<\/strong><\/span>. La situaci\u00f3n es m\u00e1s complicada por el hecho de que <strong><span style=\"color: #3366ff;\">la mayor\u00eda de los Lixisoles son probablemente poligen\u00e9ticos. Aparecen  particularmente bien representados sobre viejas superficies erosionadas o deposicionales donde durante el Pleistoceno alternaron periodos \u00e1ridos y h\u00famedos<\/span>.<\/strong> Los <span style=\"color: #3366ff;\"><strong>Lixisoles en \u00e1reas que atesoran rocas<\/strong> (materiales parentales)<\/span><strong><span style=\"color: #3366ff;\"> b\u00e1sicas ocurren junto con Nitisoles, Vertisoles, Planosoles, Plintosoles y Gleysoles en \u00e1reas de depresi\u00f3n o llanuras. Los Lixisoles ubicados en antiguas \u00e1reas de los escudos que actualmente aparecen en los tr\u00f3picos h\u00famedos se encuentran junto con Ferralsoles<\/span>. <\/strong>En este caso \u00faltimo caso os Ferralsoles se ubican en zonas geomorfol\u00f3gicamente m\u00e1s estables, mientras que los Lixisoles lo hacen en zonas m\u00e1s afectadas por la erosi\u00f3n o susceptibles de ser  rejuvenecidas, como lo son las laderas que sobrepasan una cierta pendiente o inclinaci\u00f3n. Lixisoles en valles se localizan mayoritariamente en las posiciones altas de las laderas, terrazas fluviales altas (es decir, las m\u00e1s antiguas) mientras que en las j\u00f3venes o bajas suelen formarse <span style=\"color: #3366ff;\"><strong>Luvisoles o Cambisoles<\/strong><\/span>, es decir suelos m\u00e1s j\u00f3venes y aptos con vistas a la producci\u00f3n agropecuaria. Los Lixisoles <span style=\"color: #3366ff;\"><strong>sobre viejos abanicos aluviales<\/strong><\/span>, en regiones tropicales, pueden aparecer asociados a los <span style=\"color: #3366ff;\"><strong>Plintosoles<\/strong>,<\/span> cuando existen depresiones fisiogr\u00e1ficas que dan lugar a que se almacene el agua.<\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: small;\"> <img decoding=\"async\" class=\"ngg-singlepic ngg-center\" src=\"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-content\/blogs.dir\/42\/files\/145\/lixisolplintico-unex.jpg\" alt=\"lixisolplintico-unex\" \/><\/span><\/p>\n<p style=\"text-align: center;\"><a href=\"http:\/\/www1.unex.es\/eweb\/edafo\/SEL1Lixisoles.htm\" target=\"_blank\"><span style=\"color: #0000ff; font-size: small;\">Lixisoles Pl\u00ednticos. Fuente: Universidad de Extremadura, \u00c1rea de Edafologi\u00e1 y Qu\u00edmica Agr\u00edcola<\/span><\/a><\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: small;\"> <img decoding=\"async\" class=\"ngg-singlepic ngg-center\" src=\"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-content\/blogs.dir\/42\/files\/370\/lixisoldistriamer-fuente-unex.jpg\" alt=\"lixisoldistriamer-fuente-unex\" width=\"332\" height=\"343\" \/><\/span><\/p>\n<p style=\"text-align: center;\"><a href=\"http:\/\/www1.unex.es\/eweb\/edafo\/SEL1Lixisoles.htm\" target=\"_blank\"><span style=\"color: #0000ff; font-size: small;\">Mapa de distribuci\u00f3n de los Lixisoles en Latinoam\u00e9rica. Fuente: Universidad de Extremadura, \u00c1rea de Edafolog\u00eda y Qu\u00edmica Agr\u00edcola<\/span><\/a><\/p>\n<p><span style=\"font-size: small;\"> <\/span><\/p>\n<h3><span style=\"color: #800000; font-size: small;\">WRB 2006-2007<\/span><\/h3>\n<p style=\"text-align: justify;\"><span style=\"color: #008080;\"><strong><span style=\"font-size: small;\">Distribuci\u00f3n regional de Lixisoles<\/span><\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: small;\">Los Lixisoles se encuentran en regiones estacionalmente secas tropicales, subtropicales y templado c\u00e1lidas sobre superficies del Pleistoceno o m\u00e1s antiguas. Estos suelos cubren un \u00e1rea total de alrededor de 435 millones ha, de las cuales m\u00e1s de la mitad ocurren en Africa sub-Saheliana y del Este, alrededor de un cuarto en Am\u00e9rica del Sur y Central, y el resto en el subcontinente Indio y en el Sudeste Asi\u00e1tico y Australia.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #008000;\"><strong><span style=\"font-size: small;\">Francisco Javier Manr\u00edquez Cos\u00edo y Juan Jos\u00e9 Ib\u00e1\u00f1ez<\/span><\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #008080;\"><strong>Material\u00a0 Bibliogr\u00e1fico<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.fao.org\/nr\/land\/soils\/soil\/en\" target=\"_blank\">P\u00e1gina Web de la WRB<\/a><\/p>\n<p style=\"text-align: justify;\"><a href=\"ftp:\/\/ftp.fao.org\/docrep\/fao\/011\/a0510s\/a0510s00.pdf\" target=\"_blank\">Clasificaci\u00f3n WRB 2006-2007<\/a><\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.fao.org\/DOCREP\/003\/Y1899E\/Y1899E00.HTM\" target=\"_blank\">Lecture notes on the major soils of the world<\/a> (versi\u00f3n personal traducida al espa\u00f1ol por Javier Manr\u00edquez Cos\u00edo)<\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.inegi.org.mx\/prod_serv\/contenidos\/espanol\/bvinegi\/productos\/integracion\/especiales\/BoletinSNEIG\/2010\/Bsnieg14_b.pdf\" target=\"_blank\">Los suelos de Latinoam\u00e9rica: retos y oportunidades de uso y estudio<\/a> (ir al titulo correspondiente) Autores: Francisco Bautista, Alfred J. Zinck y Silke Cram. Bolet\u00edn del Sistema Nacional de Informaci\u00f3n Estad\u00edstica y Geogr\u00e1fica: VII(3) Septiembre-Diciembre 2009, p\u00e1ginas 94-142<\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/eusoils.jrc.ec.europa.eu\/esdb_archive\/eusoils_docs\/other\/EUR23439.pdf\" target=\"_blank\">Soils of the European Union<\/a> (en Ingles)<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #008080;\"><strong>Post Previos y a Publicar en Breve de Nuestro Curso B\u00e1sico Tipos de Suelos del Mundo<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/06\/23\/136471\" target=\"_blank\">Los Suelos del Mundo y Su clasificaci\u00f3n (WRB). Curso B\u00e1sico sobre Clasificaci\u00f3n de Suelos<\/a><\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/06\/28\/136476\" target=\"_blank\">Suelos Minerales Condicionados por la Topograf\u00eda o Fisiograf\u00eda: Leptosoles, Regosoles, Fluvisoles y Gleysoles<\/a><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #008080;\"><strong>Post Previos y a Publicar en Breve de Nuestro Curso B\u00e1sico Tipos de Suelos del Mundo hasta marzo\u00a0de 2012<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/06\/23\/136471\" target=\"_blank\">Los Suelos del Mundo y Su clasificaci\u00f3n (WRB). Curso B\u00e1sico sobre Clasificaci\u00f3n de Suelos<\/a><\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/06\/28\/136476\" target=\"_blank\">Suelos Minerales Condicionados por la Topograf\u00eda o Fisiograf\u00eda: Leptosoles, Regosoles, Fluvisoles y Gleysoles<\/a><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #008080;\"><strong>Leptosoles<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/07\/06\/136490\" target=\"_blank\">Leptosoles<\/a>; <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/07\/13\/136682\" target=\"_blank\">Leptosoles: Geograf\u00eda Ambiente y Paisaje<\/a>; <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/07\/28\/136691\" target=\"_blank\">Leptosoles Uso y Manejo<\/a>;<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/08\/04\/136695\" target=\"_blank\">Leptosoles en Latinoam\u00e9rica<\/a>; <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/08\/11\/136703\" target=\"_blank\">Leptosoles en Europa<\/a>; <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/08\/22\/136503\" target=\"_blank\">Tipos de Leptosoles y sus Mapas de Distribuci\u00f3n en Europa<\/a><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #008080;\"><strong>Regosoles<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/09\/02\/136720\" target=\"_blank\">Regosoles<\/a>;\u00a0 <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/09\/09\/136869\" target=\"_blank\">Regosoles: Geograf\u00eda, Ambiente y Paisaje<\/a>; <a title=\"Enlace permanente a Regosoles: Uso y Manejo\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/09\/16\/136876\" target=\"_blank\">Regosoles: Uso y Manejo<\/a>: <a title=\"Enlace permanente a Regosoles en Latinoam\u00e9rica\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/09\/24\/136882\" target=\"_blank\">Regosoles en Latinoam\u00e9rica<\/a>; <a title=\"Enlace permanente a Regosoles en Europa\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/10\/28\/136908\" target=\"_blank\">Regosoles en Europa<\/a>; <a title=\"Enlace permanente a Tipos de Regosoles y sus Mapas de Distribuci\u00f3n en Europa(WRB 1998)\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/11\/04\/136894\" target=\"_blank\">Tipos de Regosoles y sus Mapas de Distribuci\u00f3n en Europa(WRB 1998)<\/a><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #008080;\"><strong>Fluvisoles<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><a title=\"Enlace permanente a Paisajes Aluviales No Costeros de las Redes Fluviales (WRB 1998)\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/01\/06\/137193\" target=\"_blank\">Paisajes Aluviales No Costeros de las Redes Fluviales (WRB 1998)<\/a>; <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/01\/13\/137830\" target=\"_blank\">Deltas, Estuarios y Marismas<\/a>; <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/01\/19\/137847\" target=\"_blank\">Geoformas de las L\u00edneas de Costa Generadas por la Din\u00e1mica Marina (WRB-FAO 2000)<\/a>, <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/01\/26\/137868\" target=\"_blank\">Fluvisoles<\/a>, <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/02\/02\/138188\" target=\"_blank\">Fluvisoles ti\u00f3nicos<\/a>, <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/02\/01\/137894\" target=\"_blank\">Distribuci\u00f3n geogr\u00e1fica de los Fluvisoles<\/a>, <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/02\/03\/137903\" target=\"_blank\">Fluvisoles uso y manejo<\/a>, <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/02\/04\/137912\" target=\"_blank\">Fluvisoles en Latinoam\u00e9rica<\/a>, <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/02\/07\/137923\" target=\"_blank\">Fluvisoles en Europa<\/a>, <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/02\/08\/137936\" target=\"_blank\">Mapas de los tipos de suelos de Europa (WRB 1998)<\/a><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #008080;\"><strong>Gleysoles<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/02\/16\/138132\" target=\"_blank\">Gleysoles<\/a>; <a title=\"Enlace permanente a Gleysoles: Geograf\u00eda Ambiente y Paisaje\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/02\/24\/138158\" target=\"_blank\">Gleysoles: Geograf\u00eda Ambiente y Paisaje<\/a> <a title=\"Enlace permanente a Gleysoles: Uso y Manejo\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/02\/25\/138174\" target=\"_blank\">Gleysoles: Uso y Manejo<\/a>, <a title=\"Enlace permanente a Gleysoles en Latinoam\u00e9rica\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/02\/28\/138196\" target=\"_blank\">Gleysoles en Latinoam\u00e9rica<\/a>, <a title=\"Enlace permanente a Gleysoles en Europa\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/03\/01\/138204\" target=\"_blank\">Gleysoles en Europa<\/a>, <a title=\"Enlace permanente a Tipos de Gleysoles y sus Mapas de Distribuci\u00f3n en Europa\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/03\/03\/138117\" target=\"_blank\">Tipos de Gleysoles y sus Mapas de Distribuci\u00f3n en Europa<\/a><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #008080;\"><strong>Stagnosoles (WRB 2006-2007)<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/03\/17\/138151\" target=\"_blank\">Stagnosoles<\/a><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #008080;\"><strong>Histosoles<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><a title=\"Enlace permanente a Histosoles (WRB 1998): Las Turberas\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/03\/30\/138691\" target=\"_blank\">Histosoles (WRB 1998): Las Turberas<\/a>; <a title=\"Enlace permanente a Histosoles (Turberas): Geograf\u00eda, Ambiente y Paisaje\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/04\/05\/138702\" target=\"_blank\">Histosoles (Turberas): Geograf\u00eda, Ambiente y Paisaje<\/a>; <a title=\"Enlace permanente a Histosoles Uso y Manejo (Turberas) (WRB 1998)\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/04\/06\/138714\" target=\"_blank\">Histosoles Uso y Manejo (Turberas) (WRB 1998)<\/a>; <a title=\"Enlace permanente a Histosoles en Latinoam\u00e9rica Tropical\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/04\/08\/138760\" target=\"_blank\">Histosoles en Latinoam\u00e9rica Tropical<\/a>; <a title=\"Enlace permanente a Histosoles en Europa (Turberas)\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/04\/11\/138742\" target=\"_blank\">Histosoles en Europa (Turberas)<\/a>; <a title=\"Enlace permanente a Tipos de Histosoles y sus Mapas de Distribuci\u00f3n en Europa (WRB 1998)\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/04\/20\/138751\" target=\"_blank\">Tipos de Histosoles y sus Mapas de Distribuci\u00f3n en Europa (WRB 1998)<\/a><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #008080;\"><strong>Cambisoles<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/06\/09\/139388\" target=\"_blank\">Cambisoles<\/a>; <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/06\/15\/139402\" target=\"_blank\">Cambisoles: Geograf\u00eda Ambiente y Paisaje<\/a>; <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/06\/22\/139434\" target=\"_blank\">Cambisoles: Uso y Manejo<\/a>; <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/06\/23\/139458\" target=\"_blank\">Cambisoles en Latinoam\u00e9rica<\/a>;\u00a0 <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/06\/30\/139418\" target=\"_blank\">Cambisoles en Europa<\/a>; <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/07\/07\/139426\" target=\"_blank\">Tipos de Cambisoles y Sus Mapas de Distribuci\u00f3n en Europa<\/a><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #008080;\"><strong>Arenosoles<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><a title=\"Enlace permanente a Dunas y Paisajes Arenosos (WRB 1998)\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/07\/12\/139706\" target=\"_blank\">Dunas y Paisajes Arenosos (WRB 1998)<\/a>; <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/07\/13\/139746\" target=\"_blank\">Arenosoles<\/a>; <a title=\"Enlace permanente a Arenosoles: Geograf\u00eda Ambiente y Paisaje\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/07\/18\/139756\" target=\"_blank\">Arenosoles: Geograf\u00eda; Ambiente y Paisaje<\/a>; <a title=\"Enlace permanente a Arenosoles: Uso y Manejo\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/07\/21\/139772\" target=\"_blank\">Arenosoles: Uso y Manejo<\/a>; <a title=\"Enlace permanente a Arenosoles en Latinoam\u00e9rica\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/07\/28\/139786\" target=\"_blank\">Arenosoles en Latinoam\u00e9rica<\/a>; <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/08\/04\/139794\" target=\"_blank\">Arenosoles en Europa<\/a>; <a title=\"Enlace permanente a Tipos de Arenosoles y sus Mapas de Distribuci\u00f3n en Europa\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/08\/11\/139800\" target=\"_blank\">Tipos de Arenosoles y sus Mapas de Distribuci\u00f3n en Europa<\/a><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #008080;\"><strong>Vertisoles<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><a title=\"Enlace permanente a Paisajes Arcillosos (WRB, 1998)\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/09\/29\/139981\" target=\"_blank\">Paisajes Arcillosos (WRB, 1998)<\/a>, <a title=\"Enlace permanente a Microrelieve Gilgai  (Vertisoles, WRB, 1998)\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/10\/04\/140078\" target=\"_blank\">Microrelieve Gilgai (Vertisoles, WRB, 1998)<\/a>, <a title=\"Enlace permanente a Vertisoles (WRB, 1998)\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/10\/06\/140062\" target=\"_blank\">Vertisoles (WRB, 1998)<\/a>, <a title=\"Enlace permanente a Vertisoles: Geograf\u00eda, Ambiente y Paisaje\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/10\/13\/140087\" target=\"_blank\">Vertisoles: Geograf\u00eda, Ambiente y Paisaje<\/a>, <a title=\"Enlace permanente a Vertisoles: Uso y Manejo\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/10\/21\/140108\" target=\"_blank\">Vertisoles: Uso y Manejo<\/a>, <a title=\"Enlace permanente a Vertisoles en Latinoam\u00e9rica\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/10\/28\/140114\" target=\"_blank\">Vertisoles en Latinoam\u00e9rica<\/a>, <a title=\"Enlace permanente a Vertisoles en La UE y el Continente Europeo\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/11\/01\/140049\" target=\"_blank\">Vertisoles en La UE y el Continente Europeo<\/a>, <a title=\"Enlace permanente a Tipos de Vertisoles y sus Mapas de Distribuci\u00f3n en Europa\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/11\/11\/140053\" target=\"_blank\">Tipos de Vertisoles y sus Mapas de Distribuci\u00f3n en Europa<\/a><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #008080;\"><strong>Andosoles<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/11\/16\/140617\" target=\"_blank\">Paisajes Volc\u00e1nicos<\/a>, <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/11\/23\/140258\" target=\"_blank\">Andosoles<\/a>, <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/12\/02\/140627\" target=\"_blank\">Andosoles: geograf\u00eda ambiente y paisaje<\/a>, <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/12\/20\/140649\" target=\"_blank\">Andosoles Uso y Manejo<\/a>, <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/01\/17\/140659\" target=\"_blank\">Andosoles en Latinoam\u00e9rica<\/a>, <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/01\/25\/140135\" target=\"_blank\">Andosoles en Europa<\/a>, <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/01\/25\/140135\" target=\"_blank\">Andosoles en Europa\u00a0 y los Suelos de Islandia<\/a>, <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/02\/02\/140142\" target=\"_blank\">Tipos de Andosoles y sus mapas de distribuci\u00f3n en Europa<\/a><strong> <\/strong><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #008080;\"><strong>Luvisoles<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/02\/28\/141085\">Luvisoles<\/a>, <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/03\/15\/141095\">Luvisoles: geograf\u00eda ambiente y paisaje<\/a>, <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/03\/23\/141101\">Luvisoles Uso y Manejo<\/a>; <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/03\/27\/141109\">Luvisoles en Latinoam\u00e9rica<\/a>, <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/04\/03\/141236\">Luvisoles en Europa<\/a>, <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/04\/07\/141248\">Tipos<br \/>\nde Luvisoles y sus mapas de distribuci\u00f3n en Europa<\/a>.<\/p>\n<p><span style=\"color: #008080;\"><strong>Alisoles<\/strong><\/span><\/p>\n<p><a title=\"Enlace permanente a Alisoles (WRB, 1998)\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/04\/19\/141598\">Alisoles (WRB, 1998)<\/a>; <a title=\"Enlace permanente a Alisoles: Geograf\u00eda Ambiente y Paisaje\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/04\/25\/141607\">Alisoles: Geograf\u00eda Ambiente y Paisaje<\/a>, <a title=\"Enlace permanente: Alisoles: Uso y Manejo\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/05\/03\/141613\">Alisoles: Uso y Manejo<\/a>.<br \/>\n<span style=\"color: #008080;\"><strong>Lixisoles<\/strong><\/span><\/p>\n<p><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/05\/09\/141636\">Lixisoles<\/a><\/p>\n<h3>Im\u00e1genes Relacionadas:<\/h3>","protected":false},"excerpt":{"rendered":"<p>Como ya os comentamos en el post anterior, los Lixisoles son suelos zonales cuya formaci\u00f3n se encuentra condicionada por el clima. Sus principales diferencias respecto a otros grupos de suelos de referencia de la WRB con perfiles modales A\/Bt\/C estriba en poseer arcillas de baja actividad (poca capacidad de retener nutrientes y agua) aunque si atesoran elementos qu\u00edmicos para el desarrollo de las plantas. En cualquier caso, sus propiedades no les hacen muy aptos para la producci\u00f3n agropecuaria, salvo en lo que concierne a cultivos poco exigentes. A nivel mundial se ubican fundamentalmente en el este de Latinoam\u00e9rica y este\u2026<\/p>\n","protected":false},"author":160,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0},"categories":[603,1929,604],"tags":[46744,47248,46840,1815],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":4}},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Como ya os comentamos en el post anterior, los Lixisoles son suelos zonales cuya formaci\u00f3n se encuentra condicionada por el clima. Sus principales diferencias respecto a otros grupos de suelos de referencia de la WRB con perfiles modales A\/Bt\/C estriba en poseer arcillas de baja actividad (poca capacidad de retener nutrientes y agua) aunque si\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Juan Jose Ib\u00e1\u00f1ez  y Francisco Javier Manr\u00edquez Cosio\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/05\/22\/141646\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Un Universo invisible bajo nuestros pies - Los suelos y la vida\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Lixisoles: Geograf\u00eda, Ambiente y Paisaje - Un Universo invisible bajo nuestros pies\" \/>\n\t\t<meta property=\"og:description\" content=\"Como ya os comentamos en el post anterior, los Lixisoles son suelos zonales cuya formaci\u00f3n se encuentra condicionada por el clima. Sus principales diferencias respecto a otros grupos de suelos de referencia de la WRB con perfiles modales A\/Bt\/C estriba en poseer arcillas de baja actividad (poca capacidad de retener nutrientes y agua) aunque si\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/05\/22\/141646\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2012-05-22T11:26:37+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2012-05-22T11:26:37+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/juan.j.marti.14\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Lixisoles: Geograf\u00eda, Ambiente y Paisaje - Un Universo invisible bajo nuestros pies\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Como ya os comentamos en el post anterior, los Lixisoles son suelos zonales cuya formaci\u00f3n se encuentra condicionada por el clima. Sus principales diferencias respecto a otros grupos de suelos de referencia de la WRB con perfiles modales A\/Bt\/C estriba en poseer arcillas de baja actividad (poca capacidad de retener nutrientes y agua) aunque si\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2012\\\/05\\\/22\\\/141646#blogposting\",\"name\":\"Lixisoles: Geograf\\u00eda, Ambiente y Paisaje - Un Universo invisible bajo nuestros pies\",\"headline\":\"Lixisoles: Geograf\\u00eda, Ambiente y Paisaje\",\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/juanjosibezyfranciscojaviermanriquezcosio#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"http:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/wp-content\\\/blogs.dir\\\/42\\\/files\\\/370\\\/lixisol.gif\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2012\\\/05\\\/22\\\/141646\\\/#articleImage\"},\"datePublished\":\"2012-05-22T12:26:37+01:00\",\"dateModified\":\"2012-05-22T12:26:37+01:00\",\"inLanguage\":\"es-ES\",\"commentCount\":25,\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2012\\\/05\\\/22\\\/141646#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2012\\\/05\\\/22\\\/141646#webpage\"},\"articleSection\":\"Carpeta sobre Paisajes de Suelos y los Suelos en el Paisaje, Curso B\\u00e1sico: Tipos de Suelos del Mundo, Geograf\\u00eda de Suelos y Megaedafolog\\u00eda, geograf\\u00eda de suelos, Lixisoles, mapa del mundo, Suelos de Latinoam\\u00e9rica\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2012\\\/05\\\/22\\\/141646#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/carpeta-sobre-paisajes-de-suelos-y-los-suelos-en-el-paisaje#listItem\",\"name\":\"Carpeta sobre Paisajes de Suelos y los Suelos en el Paisaje\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/carpeta-sobre-paisajes-de-suelos-y-los-suelos-en-el-paisaje#listItem\",\"position\":2,\"name\":\"Carpeta sobre Paisajes de Suelos y los Suelos en el Paisaje\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/carpeta-sobre-paisajes-de-suelos-y-los-suelos-en-el-paisaje\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2012\\\/05\\\/22\\\/141646#listItem\",\"name\":\"Lixisoles: Geograf\\u00eda, Ambiente y Paisaje\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2012\\\/05\\\/22\\\/141646#listItem\",\"position\":3,\"name\":\"Lixisoles: Geograf\\u00eda, Ambiente y Paisaje\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/carpeta-sobre-paisajes-de-suelos-y-los-suelos-en-el-paisaje#listItem\",\"name\":\"Carpeta sobre Paisajes de Suelos y los Suelos en el Paisaje\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#organization\",\"name\":\"Un Universo invisible bajo nuestros pies\",\"description\":\"Los suelos y la vida\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/files\\\/2022\\\/02\\\/logo.png\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2012\\\/05\\\/22\\\/141646\\\/#organizationLogo\",\"width\":217,\"height\":72},\"image\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2012\\\/05\\\/22\\\/141646\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/juan.j.marti.14\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/juanjosibezyfranciscojaviermanriquezcosio#author\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/juanjosibezyfranciscojaviermanriquezcosio\",\"name\":\"Juan Jose Ib\\u00e1\\u00f1ez  y Francisco Javier Manr\\u00edquez Cosio\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2012\\\/05\\\/22\\\/141646#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fb970ba39345138010f6a98cf960b8eb?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Juan Jose Ib\\u00e1\\u00f1ez  y Francisco Javier Manr\\u00edquez Cosio\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2012\\\/05\\\/22\\\/141646#webpage\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2012\\\/05\\\/22\\\/141646\",\"name\":\"Lixisoles: Geograf\\u00eda, Ambiente y Paisaje - Un Universo invisible bajo nuestros pies\",\"description\":\"Como ya os comentamos en el post anterior, los Lixisoles son suelos zonales cuya formaci\\u00f3n se encuentra condicionada por el clima. Sus principales diferencias respecto a otros grupos de suelos de referencia de la WRB con perfiles modales A\\\/Bt\\\/C estriba en poseer arcillas de baja actividad (poca capacidad de retener nutrientes y agua) aunque si\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2012\\\/05\\\/22\\\/141646#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/juanjosibezyfranciscojaviermanriquezcosio#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/juanjosibezyfranciscojaviermanriquezcosio#author\"},\"datePublished\":\"2012-05-22T12:26:37+01:00\",\"dateModified\":\"2012-05-22T12:26:37+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#website\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/\",\"name\":\"Un Universo invisible bajo nuestros pies\",\"description\":\"Los suelos y la vida\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Lixisoles: Geograf\u00eda, Ambiente y Paisaje - Un Universo invisible bajo nuestros pies","description":"Como ya os comentamos en el post anterior, los Lixisoles son suelos zonales cuya formaci\u00f3n se encuentra condicionada por el clima. Sus principales diferencias respecto a otros grupos de suelos de referencia de la WRB con perfiles modales A\/Bt\/C estriba en poseer arcillas de baja actividad (poca capacidad de retener nutrientes y agua) aunque si","canonical_url":"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/05\/22\/141646","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/05\/22\/141646#blogposting","name":"Lixisoles: Geograf\u00eda, Ambiente y Paisaje - Un Universo invisible bajo nuestros pies","headline":"Lixisoles: Geograf\u00eda, Ambiente y Paisaje","author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/juanjosibezyfranciscojaviermanriquezcosio#author"},"publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#organization"},"image":{"@type":"ImageObject","url":"http:\/\/www.madrimasd.org\/blogs\/universo\/wp-content\/blogs.dir\/42\/files\/370\/lixisol.gif","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/05\/22\/141646\/#articleImage"},"datePublished":"2012-05-22T12:26:37+01:00","dateModified":"2012-05-22T12:26:37+01:00","inLanguage":"es-ES","commentCount":25,"mainEntityOfPage":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/05\/22\/141646#webpage"},"isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/05\/22\/141646#webpage"},"articleSection":"Carpeta sobre Paisajes de Suelos y los Suelos en el Paisaje, Curso B\u00e1sico: Tipos de Suelos del Mundo, Geograf\u00eda de Suelos y Megaedafolog\u00eda, geograf\u00eda de suelos, Lixisoles, mapa del mundo, Suelos de Latinoam\u00e9rica"},{"@type":"BreadcrumbList","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/05\/22\/141646#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo#listItem","position":1,"name":"Home","item":"https:\/\/www.madrimasd.org\/blogs\/universo","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/carpeta-sobre-paisajes-de-suelos-y-los-suelos-en-el-paisaje#listItem","name":"Carpeta sobre Paisajes de Suelos y los Suelos en el Paisaje"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/carpeta-sobre-paisajes-de-suelos-y-los-suelos-en-el-paisaje#listItem","position":2,"name":"Carpeta sobre Paisajes de Suelos y los Suelos en el Paisaje","item":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/carpeta-sobre-paisajes-de-suelos-y-los-suelos-en-el-paisaje","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/05\/22\/141646#listItem","name":"Lixisoles: Geograf\u00eda, Ambiente y Paisaje"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/05\/22\/141646#listItem","position":3,"name":"Lixisoles: Geograf\u00eda, Ambiente y Paisaje","previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/carpeta-sobre-paisajes-de-suelos-y-los-suelos-en-el-paisaje#listItem","name":"Carpeta sobre Paisajes de Suelos y los Suelos en el Paisaje"}}]},{"@type":"Organization","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#organization","name":"Un Universo invisible bajo nuestros pies","description":"Los suelos y la vida","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/","logo":{"@type":"ImageObject","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/05\/22\/141646\/#organizationLogo","width":217,"height":72},"image":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/05\/22\/141646\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/juan.j.marti.14"]},{"@type":"Person","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/juanjosibezyfranciscojaviermanriquezcosio#author","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/juanjosibezyfranciscojaviermanriquezcosio","name":"Juan Jose Ib\u00e1\u00f1ez  y Francisco Javier Manr\u00edquez Cosio","image":{"@type":"ImageObject","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/05\/22\/141646#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/fb970ba39345138010f6a98cf960b8eb?s=96&d=mm&r=g","width":96,"height":96,"caption":"Juan Jose Ib\u00e1\u00f1ez  y Francisco Javier Manr\u00edquez Cosio"}},{"@type":"WebPage","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/05\/22\/141646#webpage","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/05\/22\/141646","name":"Lixisoles: Geograf\u00eda, Ambiente y Paisaje - Un Universo invisible bajo nuestros pies","description":"Como ya os comentamos en el post anterior, los Lixisoles son suelos zonales cuya formaci\u00f3n se encuentra condicionada por el clima. Sus principales diferencias respecto a otros grupos de suelos de referencia de la WRB con perfiles modales A\/Bt\/C estriba en poseer arcillas de baja actividad (poca capacidad de retener nutrientes y agua) aunque si","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#website"},"breadcrumb":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/05\/22\/141646#breadcrumblist"},"author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/juanjosibezyfranciscojaviermanriquezcosio#author"},"creator":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/juanjosibezyfranciscojaviermanriquezcosio#author"},"datePublished":"2012-05-22T12:26:37+01:00","dateModified":"2012-05-22T12:26:37+01:00"},{"@type":"WebSite","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#website","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/","name":"Un Universo invisible bajo nuestros pies","description":"Los suelos y la vida","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Un Universo invisible bajo nuestros pies - Los suelos y la vida","og:type":"article","og:title":"Lixisoles: Geograf\u00eda, Ambiente y Paisaje - Un Universo invisible bajo nuestros pies","og:description":"Como ya os comentamos en el post anterior, los Lixisoles son suelos zonales cuya formaci\u00f3n se encuentra condicionada por el clima. Sus principales diferencias respecto a otros grupos de suelos de referencia de la WRB con perfiles modales A\/Bt\/C estriba en poseer arcillas de baja actividad (poca capacidad de retener nutrientes y agua) aunque si","og:url":"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/05\/22\/141646","og:image":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png","og:image:secure_url":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png","article:published_time":"2012-05-22T11:26:37+00:00","article:modified_time":"2012-05-22T11:26:37+00:00","article:publisher":"https:\/\/www.facebook.com\/juan.j.marti.14","twitter:card":"summary","twitter:title":"Lixisoles: Geograf\u00eda, Ambiente y Paisaje - Un Universo invisible bajo nuestros pies","twitter:description":"Como ya os comentamos en el post anterior, los Lixisoles son suelos zonales cuya formaci\u00f3n se encuentra condicionada por el clima. Sus principales diferencias respecto a otros grupos de suelos de referencia de la WRB con perfiles modales A\/Bt\/C estriba en poseer arcillas de baja actividad (poca capacidad de retener nutrientes y agua) aunque si","twitter:image":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png"},"aioseo_meta_data":{"post_id":"141646","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":null,"isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","tabs":null,"priority":null,"frequency":null,"local_seo":null,"created":"2022-06-03 16:21:46","updated":"2026-05-26 17:17:56","limit_modified_date":false,"ai":null,"breadcrumb_settings":null,"seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/carpeta-sobre-paisajes-de-suelos-y-los-suelos-en-el-paisaje\" title=\"Carpeta sobre Paisajes de Suelos y los Suelos en el Paisaje\">Carpeta sobre Paisajes de Suelos y los Suelos en el Paisaje<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tLixisoles: Geograf\u00eda, Ambiente y Paisaje\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.madrimasd.org\/blogs\/universo"},{"label":"Carpeta sobre Paisajes de Suelos y los Suelos en el Paisaje","link":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/carpeta-sobre-paisajes-de-suelos-y-los-suelos-en-el-paisaje"},{"label":"Lixisoles: Geograf\u00eda, Ambiente y Paisaje","link":"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/05\/22\/141646"}],"_links":{"self":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts\/141646"}],"collection":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/users\/160"}],"replies":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/comments?post=141646"}],"version-history":[{"count":12,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts\/141646\/revisions"}],"predecessor-version":[{"id":141986,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts\/141646\/revisions\/141986"}],"wp:attachment":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/media?parent=141646"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/categories?post=141646"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/tags?post=141646"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}