{"id":142177,"date":"2013-01-11T13:41:30","date_gmt":"2013-01-11T12:41:30","guid":{"rendered":"http:\/\/www.madrimasd.org\/blogs\/universo\/?p=142177"},"modified":"2013-01-11T13:41:30","modified_gmt":"2013-01-11T12:41:30","slug":"los-microrganismos-del-suelo-y-la-alimentacion-humana","status":"publish","type":"post","link":"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/01\/11\/142177","title":{"rendered":"Los Microrganismos del Suelo y la Alimentaci\u00f3n Humana"},"content":{"rendered":"<p style=\"text-align: justify;\"><span style=\"color: #3366ff;\"><strong>Los microrganismos son los seres vivos m\u00e1s abundantes del planeta y se encuentran por todas partes<\/strong><\/span>, siendo a la postre <span style=\"color: #3366ff;\"><strong>un componente indispensable de la vida y del\u00a0propio ser humano<\/strong><\/span>. El ecosistema que conforman estos bichitos en cada cuerpo es lo que denominamos el <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2008\/04\/08\/88543\" target=\"_blank\"><span style=\"color: #0000ff;\">microbioma<\/span><\/a>, y reiteremos que sin \u00e9l no podr\u00edamos sobrevivir, por cuanto <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2006\/07\/04\/33569\" target=\"_blank\"><span style=\"color: #0000ff;\">un cuerpo\u00a0tambi\u00e9n es un ecosistema<\/span><\/a>. Empero <span style=\"color: #3366ff;\"><strong>lo mismo le ocurre a todos los seres multicelulares y algunos unicelulares<\/strong><\/span>. Por lo tanto, cuando ingerimos alimentos (es decir otros organismos) tambi\u00e9n lo hacemos con los microbios que albergan. Y tal proceso es natural en la biosfera. <span style=\"color: #3366ff;\"><strong>Resulta que los suelos y sedimentos son los ambientes que m\u00e1s microrganismos atesoran<\/strong>. <strong>No pod\u00eda ser de otra forma<\/strong><\/span>. En el medio ed\u00e1fico se <span style=\"color: #3366ff;\"><strong>metaboliza todo lo que se vierte en \u00e9l, tranform\u00e1ndolo finalmente en nutrientes y elementos qu\u00edmicos<\/strong><\/span>. Estos dan lugar al reciclado que denominamos <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/09\/13\/137119\" target=\"_blank\"><span style=\"color: #0000ff;\">ciclos biogeoqu\u00edmicos<\/span><\/a>. Sin ellos la biosfera se colapsar\u00eda. Por esta sencilla raz\u00f3n, cuando paseamos por un paisaje natural sin presencia humana, no observamos un escenario repleto de detritus a medio descomponer, en putrefacci\u00f3n. El ser humano ha evolucionado en este entorno sin mayores problemas. De hecho, ya hemos reiterado que <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/04\/26\/135819\" target=\"_blank\"><span style=\"color: #0000ff;\">cuando consumimos suelo<\/span><\/a>, es decir la denominada <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2009\/07\/15\/121824\" target=\"_blank\"><span style=\"color: #0000ff;\">geofagia<\/span><\/a>, solemos fortalecer las defensas de nuestro organismo contra los pat\u00f3genos, al margen de paliar, a menudo, deficiencias en elementos minerales. Lamentablemente en los \u00faltimos tiempos, tanto la prensa cient\u00edfica, como los propios expertos y rotativos generales, comienzan a confundir la velocidad con el tocino. Ya comentamos que <span style=\"color: #3366ff;\"><strong>una disparatada concepci\u00f3n del suelo<\/strong> <\/span>auspiciada por nuestra sociedad industrial consiste en considerar que<span style=\"color: #3366ff;\"> <strong>el medio ed\u00e1fico es un esplendido e <\/strong><\/span><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2008\/02\/26\/85393\" target=\"_blank\"><span style=\"color: #0000ff;\">inagotable vertedero<\/span><\/a> al que, con o sin cuidado, echamos todo tipo de inmundicias. <span style=\"color: #3366ff;\"><strong>Y al hacerlo, lo envenenamos<\/strong>. <strong>A la postre luego diremos que el suelo alberga un sinf\u00edn de pat\u00f3genos, que atentan contra nuestro bienestar. La realidad resulta ser completamente diferente<\/strong>. <strong>Cuando vertimos sustancias peligrosas envenenamos este recurso natural y a la larga toda la cadena tr\u00f3fica, por lo cual el ciclo se cierra al da\u00f1ar nuestros propios cuerpos<\/strong><\/span>. Y esto es lo que ocurre al regar con las <span style=\"color: #3366ff;\"><strong>aguas residuales <\/strong><\/span>(AR). Obviamente, <span style=\"color: #3366ff;\"><strong>las no depuradas<\/strong> <\/span>son peligros\u00edsimas, aunque las que s\u00ed lo han sido (ARD) tampoco se encuentran\u00a0exentas de depararnos desagradables sorpresas. En cualquier caso, todos lo pa\u00edses contienen, en mayor o menor medida aguas residuales no depuradas (ARND). Eso si, <span style=\"color: #3366ff;\"><strong>en los Estados poco desarrollados y en los emergentes, el riego con estos elixires suele ser pr\u00e1ctica habitual<\/strong><\/span>, acarreando las consecuencias mencionadas. Por otro lado, <span style=\"color: #3366ff;\"><strong>la globalizaci\u00f3n que ha dado paso a una circulaci\u00f3n poco vigilada de los alimentos alrededor de todo el mundo<\/strong>, <strong>propiciando que los que se encuentran envenenados circulen con bastante facilidad de unos puntos a otros del planeta<\/strong> <\/span>generando serios<span style=\"color: #3366ff;\"> <strong>problemas de salud p\u00fablica<\/strong> <\/span>en todo tipo de Estados, aunque los pobres siempre salen perdiendo en t\u00e9rminos comparativos, como siempre. <span style=\"color: #3366ff;\"><strong>Y es aqu\u00ed en donde la noticia que expongo hoy se me antoja tremendamente desafortunada. En aras de la divulgaci\u00f3n cient\u00edfica no se debe asimilar suelos con riesgo para la salud, ya que\u00a0en realidad resulta ser todo lo contrario<\/strong><\/span>. Eso s\u00ed, <span style=\"color: #3366ff;\"><strong>cuando el sucio y descuidado ser humano acumula excrementos de todo tipo en su h\u00e1bitat <\/strong><\/span>(llam\u00e9mosla biosfera o Gaia), <span style=\"color: #3366ff;\"><strong>este deviene en vertedero<\/strong><\/span>. Del mismo modo, <span style=\"color: #3366ff;\"><strong>al usar el \u00faltimo para la producci\u00f3n de alimentos, es problema se encuentra servido encima de nuestras mesas<\/strong><\/span>. Sin embargo, <strong><span style=\"color: #3366ff;\">el ciudadano poco informado tambi\u00e9n es un peligro<\/span><\/strong>. Expongamos un ejemplo (\u2026)<\/p>\n<p style=\"text-align: center;\"><img decoding=\"async\" class=\"ngg-singlepic ngg-center\" src=\"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-content\/blogs.dir\/42\/files\/163\/soil-microbes-fuente-piremongolia.jpg\" alt=\"soil-microbes-fuente-piremongolia\" width=\"495\" height=\"349\" \/><\/p>\n<p style=\"text-align: center;\"><span style=\"color: #0000ff;\">Microrganismos del suelo. Fuentes<\/span>: <a href=\"http:\/\/www.denniskunkel.com\/\" target=\"_blank\"><span style=\"color: #0000ff;\">http:\/\/www.denniskunkel.com\/<\/span><\/a>y <a href=\"http:\/\/piremongolia.wordpress.com\/2011\/07\/05\/dont-treat-my-soil-like-dirt\/\" target=\"_blank\"><span style=\"color: #0000ff;\">piremongolia<\/span><\/a><\/p>\n<p style=\"text-align: justify;\"><!--more--><\/p>\n<p style=\"text-align: justify;\">Hace ya muchos a\u00f1os, en el extremo de <span style=\"color: #3366ff;\"><strong>una playa<\/strong><\/span>, flu\u00edan <span style=\"color: #3366ff;\"><strong>aguas residuales no depuradas<\/strong> <\/span>de una poblaci\u00f3n cercana. Su temperatura\u00a0 era ostensiblemente superior que la del mar. Pues bien, all\u00ed <span style=\"color: #3366ff;\"><strong>madres muy atentas<\/strong><span style=\"color: #333333;\">, <\/span><\/span>en todo lo concerniente al cuidado de sus reto\u00f1os <span style=\"color: #3366ff;\"><strong>iban a ba\u00f1arlos<\/strong><\/span>. Un d\u00eda las increp\u00e9 sobre los riesgos que conllevaban tales esmeros. Inmediatamente varias de ellas, muy indignadas, comentaron que <span style=\"color: #3366ff;\"><strong>lo hac\u00edan por el bien de las criaturas, ya que como el agua estaba caliente, los peque\u00f1os no sufr\u00edan y como corolario lloraban menos<\/strong><\/span>. Y as\u00ed el riesgo de enfermar a la crianza incrementaba exponencialmente. Obviamente no me hicieron caso alguno y perseveraron esa procelosa higiene\/divertimento. Sin <span style=\"color: #008000;\">comentarios (\u2026).<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #3366ff;\"><strong>No se pueden redactar notas <\/strong><strong>como la que ofrecemos hoy por cuanto confunden al ciudadano. Los \u201cmalos\u201d somos nosotros, los humanos, que<\/strong> <strong>regamos con todo tipo de sustancias y organismos peligrosos al suelo<\/strong><\/span>, como residuos solidos urbanos <span style=\"color: #333333;\">(RSU), ARND y ARD. Si bien estas \u00faltimas pueden considerarse como un mal inevitable en nuestra sociedad, las dos primeras no. <span style=\"color: #3366ff;\"><strong>Y cuando comes sobre la basura (\u2026.) y cuando lo que era sano lo haces enfermar (\u2026.) y cuando luego el experto acusa a un recurso natural de ser peligroso (\u2026.) pues resulta que todo esto es tan kafkiano como<\/strong> <\/span>para ponerse a temblar.<span style=\"color: #3366ff;\"> <strong>La divulgaci\u00f3n cient\u00edfica no puede caminar\u00a0 por estos derroteros tan sucios y confundentes<\/strong><\/span><\/span>.<\/p>\n<p><strong><span style=\"color: #008000;\">Juan Jos\u00e9 Ib\u00e1\u00f1ez<\/span><\/strong><\/p>\n<h2 style=\"text-align: justify;\"><a href=\"http:\/\/www.madrimasd.org\/informacionidi\/noticias\/noticia.asp?id=52857&amp;origen=notiweb&amp;dia_suplemento=viernes\" target=\"_blank\"><strong><span style=\"color: #0000ff;\">Los bichitos que comemos<\/span><\/strong><\/a><strong> <\/strong><\/h2>\n<p style=\"text-align: justify;\"><strong>Donde m\u00e1s microbios hay es en el suelo<\/strong><strong>, por la acci\u00f3n de la gravedad a pesar de su reducida masa; <\/strong><strong>en los alimentos hay una peque\u00f1a parte y los fondos marinos se presentan como \u00abun incre\u00edble mundo a explorar\u00bb, <\/strong><strong>ha relatado a Efe el Dr. Alfonso V. Carrascosa, especializado en microbiolog\u00eda de los alimentos del <\/strong><a title=\"www.csic.es\" href=\"http:\/\/www.csic.es\/web\/guest\/centros-de-investigacion1\/-\/centro\/597105\" target=\"_blank\"><strong>Instituto de Investigaci\u00f3n en Ciencias de la Alimentaci\u00f3n CIAL<\/strong><\/a><strong> (del CSIC). <\/strong><\/p>\n<p style=\"text-align: justify;\">FUENTE | <a href=\"http:\/\/www.efeverde.com\/\" target=\"_blank\">EFEverde<\/a>25\/05\/2012.<\/p>\n<p style=\"text-align: justify;\"><strong>De esta inmensa cantidad de bichitos se conocen menos del 0,1% y no se sabe el n\u00famero de especies que hay en los alimentos<\/strong>.<\/p>\n<p><strong>Los microbios que comemos son bacterias, levaduras y mohos y los hay buenos, como los probi\u00f3ticos, y malos o muy malos<\/strong>, como el serotipo de la bacteria <em>Escherichia coli<\/em>(E.coli), llamado O104:H4, que caus\u00f3 hace un a\u00f1o el brote epid\u00e9mico del s\u00edndrome ur\u00e9mico hemol\u00edtico en Alemania, con unas 50 muertes y una crisis en Espa\u00f1a por una primera informaci\u00f3n falsa de que el origen estaba en el pepino.<\/p>\n<p><strong>Estos seres vivos est\u00e1n en los alimentos<\/strong>, seg\u00fan Carrascosa, debido a que \u00abcomen lo mismo que nosotros\u00bb, de ah\u00ed que la industria alimentaria haya desarrollado m\u00e9todos para controlar su expansi\u00f3n, porque pueden alterar los alimentos o causar da\u00f1o en el consumidor por ser pat\u00f3genos.<\/p>\n<p><strong>Los microbios malos, causantes de parte de las enfermedades gastrointestinales, se pueden clasificar seg\u00fan el da\u00f1o en dos grandes grupos: los que intoxican<\/strong> -no hace falta com\u00e9rselos vivos, dejan una toxina en el alimento que luego da\u00f1a al organismo- y los que toxiinfectan -para da\u00f1ar han de comerse vivos-,como O104:H4.<\/p>\n<p><strong>El cuerpo humano aplica para defenderse de estos pat\u00f3genos &#8216;barreras&#8217; como la saliva o el \u00e1cido clorh\u00eddrico del est\u00f3mago<\/strong>, pero no siempre son eficaces al 100% porque los hay muy resistentes o con dosis infectivas muy bajas, como la citada cepa de E.coli, cuyo reservorio universal es el est\u00f3mago de las vacas.<\/p>\n<p><strong>\u00bfY c\u00f3mo lleg\u00f3 esta cepa a las semillas germinadas de ensaladas en restaurantes alemanes?<\/strong><\/p>\n<p>Para Carrascosa, \u00absin duda alguna <strong>por error<\/strong> <strong>en los controles alimenticios<\/strong> de Alemania\u00bb. \u00abEl principal error es que se produjera la crisis alimentaria y, ese es alem\u00e1n, al que ha de sumarse el enorme error pol\u00edtico en la gesti\u00f3n de esta crisis, que fue por segunda vez alem\u00e1n y en absoluto espa\u00f1ol\u00bb, ha remachado.<\/p>\n<p><strong>E.coli O104:H4 se encuentra en el intestino y, por tanto, en las heces de las vacas -se conoce como la bacteria de las hamburguesas-, y apareci\u00f3 en las semillas previsiblemente por contaminaci\u00f3n a trav\u00e9s del abono o el agua de riego<\/strong>. Las semillas, provenientes de Egipto, eran procesadas y distribuidas por una empresa alemana productora de semillas germinadas.<\/p>\n<p>\u00abLo l\u00f3gico es que hubiera habido un control de calidad sobre esa materia prima porque as\u00ed lo exige la legislaci\u00f3n europea\u00bb, ha dicho este doctor, quien ha apuntado: \u00abla responsable \u00faltima es la empresa que procesa y suministra las semillas a los restaurantes\u00bb, dado que seg\u00fan la normativa europea vigente las empresas han de aplicar sistemas de seguridad del tipo APPCC (An\u00e1lisis de Peligros y Puntos Cr\u00edticos de Control).<\/p>\n<p>\u00c9stos trazan la seguridad desde la obtenci\u00f3n de la materia prima hasta que llega al consumidor, una tecnolog\u00eda de obst\u00e1culos que se va poniendo a los alimentos para que los microbios pat\u00f3genos no terminen causando da\u00f1o.<\/p>\n<p>\u00abQue las semillas vinieran de Egipto no exculpa para nada a la empresa alemana\u00bb, ha subrayado este cient\u00edfico, quien ha lamentado que a\u00fan no se sepa en qu\u00e9 se basaron las autoridades alemanas para culpar primeramente Espa\u00f1a.<\/p>\n<p>En Espa\u00f1a se han ido aprobando reales decretos para adecuar las leyes europeas de implantaci\u00f3n del APPCC y, seg\u00fan Carrascosa, a\u00fan se pueden seguir haciendo cosas.<\/p>\n<p><strong>La administraci\u00f3n tiene la obligaci\u00f3n de vigilar que las empresas aplican los controles de seguridad e implementan adecuadamente<\/strong> los APPCC, seg\u00fan este cient\u00edfico, quien ha afirmado que con crisis como la de Alemania \u00abconviene tomar nota\u00bb, aunque sean poco frecuentes los fallos.<\/p>\n<p>\u00ab<strong>No hay que bajar la guardia e, incluso, seguir avanzando en la seguridad\u00bb, seg\u00fan Carrascosa, quien ha apuntado que habr\u00eda que evaluar si hay que revisar el real decreto que establece el l\u00edmite m\u00e1ximo de presencia de microbios en el esti\u00e9rcol<\/strong>.<\/p>\n<p style=\"text-align: justify;\">Mucha m\u00e1s claridad se encuentra en el siguiente post que os recomiendo leer: <a title=\"Enlace permanente: El brote de los brotes: un mal ejemplo de cobertura medi\u00e1tica y de crisis alimentaria\" href=\"http:\/\/www.madrimasd.org\/blogs\/alimentacion\/2012\/05\/24\/130943\" target=\"_blank\"><strong>El brote de los brotes un mal ejemplo de cobertura medi\u00e1tica y de crisis alimentaria<\/strong><\/a><strong> <\/strong><\/p>\n<p style=\"text-align: justify;\">Publicado por <a title=\"Entradas de Centro de Vigilancia Sanitaria Veterinaria (VISAVET)\" href=\"http:\/\/www.madrimasd.org\/blogs\/alimentacion\/author\/alimentacion\" target=\"_blank\"><strong>Centro de Vigilancia Sanitaria Veterinaria (VISAVET)<\/strong><\/a>el <strong>24 mayo, 2012<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Un a\u00f1o despu\u00e9s, el brote alem\u00e1n de <em>Escherichia coli<\/em> sigue siendo un ejemplo de lo que no se debe hacer en una crisis alimentaria. Entre otras cosas, se le puso a toda prisa un nombre inadecuado y da\u00f1ino: la \u201ccrisis del pepino espa\u00f1ol\u201d. No obstante, tambi\u00e9n tiene sus consecuencias positivas: un nuevo proyecto financiado por la UE para hacer frente a amenazas epid\u00e9micas, y un nuevo enfoque de la seguridad alimentaria global (\u2026)<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>(\u2026)La hip\u00f3tesis m\u00e1s s\u00f3lida apunta al riego con aguas residuales de origen humano contaminadas con el <em>E. coli<\/em> causante del brote<\/strong>. No obstante: \u00bfpor qu\u00e9 no ha habido casos en Egipto? Y si a\u00fan no se conoce este dato, \u00bfc\u00f3mo pudo se\u00f1alarse entonces tan r\u00e1pida e infundadamente a los pepinos espa\u00f1oles? (\u2026) <strong>la p\u00e9sima gesti\u00f3n llevada a cabo por las autoridades competentes y los medios de comunicaci\u00f3n, todos ellos a la b\u00fasqueda urgente pero perversa de justificaciones y titulares<\/strong>, respectivamente. Demasiados interrogantes (\u2026).<\/p>\n<h3>Im\u00e1genes Relacionadas:<\/h3>","protected":false},"excerpt":{"rendered":"<p>Los microrganismos son los seres vivos m\u00e1s abundantes del planeta y se encuentran por todas partes, siendo a la postre un componente indispensable de la vida y del\u00a0propio ser humano. El ecosistema que conforman estos bichitos en cada cuerpo es lo que denominamos el microbioma, y reiteremos que sin \u00e9l no podr\u00edamos sobrevivir, por cuanto un cuerpo\u00a0tambi\u00e9n es un ecosistema. Empero lo mismo le ocurre a todos los seres multicelulares y algunos unicelulares. Por lo tanto, cuando ingerimos alimentos (es decir otros organismos) tambi\u00e9n lo hacemos con los microbios que albergan. Y tal proceso es natural en la biosfera. Resulta\u2026<\/p>\n","protected":false},"author":26,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0},"categories":[596,613,592],"tags":[46910,46745],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":4}},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Los microrganismos son los seres vivos m\u00e1s abundantes del planeta y se encuentran por todas partes, siendo a la postre un componente indispensable de la vida y del propio ser humano. El ecosistema que conforman estos bichitos en cada cuerpo es lo que denominamos el microbioma, y reiteremos que sin \u00e9l no podr\u00edamos sobrevivir, por cuanto\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Juan Jos\u00e9 Ib\u00e1\u00f1ez\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/01\/11\/142177\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Un Universo invisible bajo nuestros pies - Los suelos y la vida\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Los Microrganismos del Suelo y la Alimentaci\u00f3n Humana - Un Universo invisible bajo nuestros pies\" \/>\n\t\t<meta property=\"og:description\" content=\"Los microrganismos son los seres vivos m\u00e1s abundantes del planeta y se encuentran por todas partes, siendo a la postre un componente indispensable de la vida y del propio ser humano. El ecosistema que conforman estos bichitos en cada cuerpo es lo que denominamos el microbioma, y reiteremos que sin \u00e9l no podr\u00edamos sobrevivir, por cuanto\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/01\/11\/142177\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2013-01-11T12:41:30+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2013-01-11T12:41:30+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/juan.j.marti.14\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Los Microrganismos del Suelo y la Alimentaci\u00f3n Humana - Un Universo invisible bajo nuestros pies\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Los microrganismos son los seres vivos m\u00e1s abundantes del planeta y se encuentran por todas partes, siendo a la postre un componente indispensable de la vida y del propio ser humano. El ecosistema que conforman estos bichitos en cada cuerpo es lo que denominamos el microbioma, y reiteremos que sin \u00e9l no podr\u00edamos sobrevivir, por cuanto\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2013\\\/01\\\/11\\\/142177#blogposting\",\"name\":\"Los Microrganismos del Suelo y la Alimentaci\\u00f3n Humana - Un Universo invisible bajo nuestros pies\",\"headline\":\"Los Microrganismos del Suelo y la Alimentaci\\u00f3n Humana\",\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"http:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/wp-content\\\/blogs.dir\\\/42\\\/files\\\/163\\\/soil-microbes-fuente-piremongolia.jpg\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2013\\\/01\\\/11\\\/142177\\\/#articleImage\"},\"datePublished\":\"2013-01-11T13:41:30+01:00\",\"dateModified\":\"2013-01-11T13:41:30+01:00\",\"inLanguage\":\"es-ES\",\"commentCount\":3,\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2013\\\/01\\\/11\\\/142177#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2013\\\/01\\\/11\\\/142177#webpage\"},\"articleSection\":\"Biolog\\u00eda y Ecolog\\u00eda del Suelo, Fertilidad de Suelos y Nutrici\\u00f3n Vegetal, Los Suelos y la Salud, microorganismos del suelo, salud p\\u00fablica\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2013\\\/01\\\/11\\\/142177#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/los-suelos-y-la-salud#listItem\",\"name\":\"Los Suelos y la Salud\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/los-suelos-y-la-salud#listItem\",\"position\":2,\"name\":\"Los Suelos y la Salud\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/los-suelos-y-la-salud\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2013\\\/01\\\/11\\\/142177#listItem\",\"name\":\"Los Microrganismos del Suelo y la Alimentaci\\u00f3n Humana\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2013\\\/01\\\/11\\\/142177#listItem\",\"position\":3,\"name\":\"Los Microrganismos del Suelo y la Alimentaci\\u00f3n Humana\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/los-suelos-y-la-salud#listItem\",\"name\":\"Los Suelos y la Salud\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#organization\",\"name\":\"Un Universo invisible bajo nuestros pies\",\"description\":\"Los suelos y la vida\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/files\\\/2022\\\/02\\\/logo.png\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2013\\\/01\\\/11\\\/142177\\\/#organizationLogo\",\"width\":217,\"height\":72},\"image\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2013\\\/01\\\/11\\\/142177\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/juan.j.marti.14\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo\",\"name\":\"Juan Jos\\u00e9 Ib\\u00e1\\u00f1ez\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2013\\\/01\\\/11\\\/142177#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/387f3a100385573d8f42ce2a3211fd1c?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Juan Jos\\u00e9 Ib\\u00e1\\u00f1ez\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2013\\\/01\\\/11\\\/142177#webpage\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2013\\\/01\\\/11\\\/142177\",\"name\":\"Los Microrganismos del Suelo y la Alimentaci\\u00f3n Humana - Un Universo invisible bajo nuestros pies\",\"description\":\"Los microrganismos son los seres vivos m\\u00e1s abundantes del planeta y se encuentran por todas partes, siendo a la postre un componente indispensable de la vida y del propio ser humano. El ecosistema que conforman estos bichitos en cada cuerpo es lo que denominamos el microbioma, y reiteremos que sin \\u00e9l no podr\\u00edamos sobrevivir, por cuanto\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2013\\\/01\\\/11\\\/142177#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\"},\"datePublished\":\"2013-01-11T13:41:30+01:00\",\"dateModified\":\"2013-01-11T13:41:30+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#website\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/\",\"name\":\"Un Universo invisible bajo nuestros pies\",\"description\":\"Los suelos y la vida\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Los Microrganismos del Suelo y la Alimentaci\u00f3n Humana - Un Universo invisible bajo nuestros pies","description":"Los microrganismos son los seres vivos m\u00e1s abundantes del planeta y se encuentran por todas partes, siendo a la postre un componente indispensable de la vida y del propio ser humano. El ecosistema que conforman estos bichitos en cada cuerpo es lo que denominamos el microbioma, y reiteremos que sin \u00e9l no podr\u00edamos sobrevivir, por cuanto","canonical_url":"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/01\/11\/142177","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/01\/11\/142177#blogposting","name":"Los Microrganismos del Suelo y la Alimentaci\u00f3n Humana - Un Universo invisible bajo nuestros pies","headline":"Los Microrganismos del Suelo y la Alimentaci\u00f3n Humana","author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author"},"publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#organization"},"image":{"@type":"ImageObject","url":"http:\/\/www.madrimasd.org\/blogs\/universo\/wp-content\/blogs.dir\/42\/files\/163\/soil-microbes-fuente-piremongolia.jpg","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/01\/11\/142177\/#articleImage"},"datePublished":"2013-01-11T13:41:30+01:00","dateModified":"2013-01-11T13:41:30+01:00","inLanguage":"es-ES","commentCount":3,"mainEntityOfPage":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/01\/11\/142177#webpage"},"isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/01\/11\/142177#webpage"},"articleSection":"Biolog\u00eda y Ecolog\u00eda del Suelo, Fertilidad de Suelos y Nutrici\u00f3n Vegetal, Los Suelos y la Salud, microorganismos del suelo, salud p\u00fablica"},{"@type":"BreadcrumbList","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/01\/11\/142177#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo#listItem","position":1,"name":"Home","item":"https:\/\/www.madrimasd.org\/blogs\/universo","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/los-suelos-y-la-salud#listItem","name":"Los Suelos y la Salud"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/los-suelos-y-la-salud#listItem","position":2,"name":"Los Suelos y la Salud","item":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/los-suelos-y-la-salud","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/01\/11\/142177#listItem","name":"Los Microrganismos del Suelo y la Alimentaci\u00f3n Humana"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/01\/11\/142177#listItem","position":3,"name":"Los Microrganismos del Suelo y la Alimentaci\u00f3n Humana","previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/los-suelos-y-la-salud#listItem","name":"Los Suelos y la Salud"}}]},{"@type":"Organization","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#organization","name":"Un Universo invisible bajo nuestros pies","description":"Los suelos y la vida","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/","logo":{"@type":"ImageObject","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/01\/11\/142177\/#organizationLogo","width":217,"height":72},"image":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/01\/11\/142177\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/juan.j.marti.14"]},{"@type":"Person","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo","name":"Juan Jos\u00e9 Ib\u00e1\u00f1ez","image":{"@type":"ImageObject","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/01\/11\/142177#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/387f3a100385573d8f42ce2a3211fd1c?s=96&d=mm&r=g","width":96,"height":96,"caption":"Juan Jos\u00e9 Ib\u00e1\u00f1ez"}},{"@type":"WebPage","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/01\/11\/142177#webpage","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/01\/11\/142177","name":"Los Microrganismos del Suelo y la Alimentaci\u00f3n Humana - Un Universo invisible bajo nuestros pies","description":"Los microrganismos son los seres vivos m\u00e1s abundantes del planeta y se encuentran por todas partes, siendo a la postre un componente indispensable de la vida y del propio ser humano. El ecosistema que conforman estos bichitos en cada cuerpo es lo que denominamos el microbioma, y reiteremos que sin \u00e9l no podr\u00edamos sobrevivir, por cuanto","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#website"},"breadcrumb":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/01\/11\/142177#breadcrumblist"},"author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author"},"creator":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author"},"datePublished":"2013-01-11T13:41:30+01:00","dateModified":"2013-01-11T13:41:30+01:00"},{"@type":"WebSite","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#website","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/","name":"Un Universo invisible bajo nuestros pies","description":"Los suelos y la vida","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Un Universo invisible bajo nuestros pies - Los suelos y la vida","og:type":"article","og:title":"Los Microrganismos del Suelo y la Alimentaci\u00f3n Humana - Un Universo invisible bajo nuestros pies","og:description":"Los microrganismos son los seres vivos m\u00e1s abundantes del planeta y se encuentran por todas partes, siendo a la postre un componente indispensable de la vida y del propio ser humano. El ecosistema que conforman estos bichitos en cada cuerpo es lo que denominamos el microbioma, y reiteremos que sin \u00e9l no podr\u00edamos sobrevivir, por cuanto","og:url":"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/01\/11\/142177","og:image":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png","og:image:secure_url":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png","article:published_time":"2013-01-11T12:41:30+00:00","article:modified_time":"2013-01-11T12:41:30+00:00","article:publisher":"https:\/\/www.facebook.com\/juan.j.marti.14","twitter:card":"summary","twitter:title":"Los Microrganismos del Suelo y la Alimentaci\u00f3n Humana - Un Universo invisible bajo nuestros pies","twitter:description":"Los microrganismos son los seres vivos m\u00e1s abundantes del planeta y se encuentran por todas partes, siendo a la postre un componente indispensable de la vida y del propio ser humano. El ecosistema que conforman estos bichitos en cada cuerpo es lo que denominamos el microbioma, y reiteremos que sin \u00e9l no podr\u00edamos sobrevivir, por cuanto","twitter:image":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png"},"aioseo_meta_data":{"post_id":"142177","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":null,"isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","tabs":null,"priority":null,"frequency":null,"local_seo":null,"created":"2022-06-03 16:33:39","updated":"2026-05-26 17:33:48","limit_modified_date":false,"ai":null,"breadcrumb_settings":null,"seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/los-suelos-y-la-salud\" title=\"Los Suelos y la Salud\">Los Suelos y la Salud<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tLos Microrganismos del Suelo y la Alimentaci\u00f3n Humana\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.madrimasd.org\/blogs\/universo"},{"label":"Los Suelos y la Salud","link":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/los-suelos-y-la-salud"},{"label":"Los Microrganismos del Suelo y la Alimentaci\u00f3n Humana","link":"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/01\/11\/142177"}],"_links":{"self":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts\/142177"}],"collection":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/comments?post=142177"}],"version-history":[{"count":11,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts\/142177\/revisions"}],"predecessor-version":[{"id":143586,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts\/142177\/revisions\/143586"}],"wp:attachment":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/media?parent=142177"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/categories?post=142177"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/tags?post=142177"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}