{"id":142329,"date":"2012-09-07T13:03:30","date_gmt":"2012-09-07T12:03:30","guid":{"rendered":"http:\/\/www.madrimasd.org\/blogs\/universo\/?p=142329"},"modified":"2012-09-07T13:03:30","modified_gmt":"2012-09-07T12:03:30","slug":"podzoles-uso-y-manejo","status":"publish","type":"post","link":"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/09\/07\/142329","title":{"rendered":"Podzoles: Uso y Manejo"},"content":{"rendered":"<p style=\"text-align: justify;\">Los <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/08\/24\/142310\">Podzoles<\/a> <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2006\/10\/15\/46305\">zonales<\/a>\u00a0se ubican en regiones que sufren condiciones <span style=\"color: #3366ff;\"><strong>clim\u00e1ticas poco atractivas<\/strong> <\/span>para la mayor\u00eda de los usos agrarios. Los <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/08\/24\/142310\">Podzoles<\/a> <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2006\/10\/15\/46305\">intrazonales<\/a>\u00a0suelen ser m\u00e1s habitualmente recuperados para la agricultura con labranza que los Podzoles zonales, particularmente en la franja clim\u00e1tica septentrional del bioma templado bajo condiciones m\u00e1s benignas, con un periodo vegetativo de mayor duraci\u00f3n.\u00a0<span style=\"color: #3366ff;\"><strong>Bajo estatus de nutrientes, escasa nivel de humedad disponible para las plantas<\/strong><\/span>, as\u00ed como un <span style=\"color: #3366ff;\"><strong>pH del suelo muy \u00e1cido<\/strong><\/span>, hace a los Podzoles suelos poco aptos con vistas a la agricultura de labranza. <span style=\"color: #3366ff;\"><strong>La toxicidad del Al y la deficiencia de f\u00f3sforo<\/strong><\/span> son otros problemas comunes. <span style=\"color: #3366ff;\"><strong>El arado profundo tiende a \u00a0mejorar<\/strong> <\/span>la capacidad de retenci\u00f3n de humedad del suelo y\/o eliminar un horizonte denso (\u201chardpan\u201d o \u201cduripan\u201d) de iluviaci\u00f3n. Adicionalmente, el <strong><span style=\"color: #3366ff;\">encalado<\/span><span style=\"color: #3366ff;\"> y fertilizaci\u00f3n<\/span><\/strong> son otras medidas paliativas que deben ser adoptadas. <span style=\"color: #3366ff;\"><strong>De no ser as\u00ed, su capacidad de uso queda restringida a un pastoreo extensivo, la repoblaci\u00f3n forestal o dejarlos bajo la vegetaci\u00f3n natural que atesoran<\/strong><\/span>. Muchos Podzoles de Europa fueron ya remozados y fertilizados por las <strong><span style=\"color: #3366ff;\">culturas abor\u00edgenes del continente<\/span><\/strong>, desde hace miles\u00a0 de a\u00f1os, dando\u00a0lugar a los denominados <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2008\/11\/01\/105554\">suelos pl\u00e1cicos<\/a>.<\/p>\n<p style=\"text-align: center;\"><img decoding=\"async\" class=\"ngg-singlepic ngg-center\" src=\"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-content\/blogs.dir\/42\/files\/164\/podzol-uso-fuente-teara.jpg\" alt=\"podzol-uso-fuente-teara\" \/><\/p>\n<p align=\"center\"><span style=\"text-decoration: underline;\"><span style=\"color: #0000ff;\">Pastizal en un Podzol.\u00a0Fuente TEARA<\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #3366ff;\"><strong>La mayor\u00eda de los Podzoles zonales<\/strong> <\/span>se encuentran ubicados bajo bosques. Los <span style=\"color: #3366ff;\"><strong>Podzoles intrazonales en regiones templadas est\u00e1n<\/strong> <\/span>mayoritariamente bajo bosques, landas o brezales (matorrales de eric\u00e1ceas). <span style=\"color: #3366ff;\"><strong>La mayor\u00eda de los Podzoles tropicales sostienen <\/strong><\/span>una vegetaci\u00f3n ligera que recubre s\u00f3lo gradualmente despu\u00e9s de la tumba\/quema. <strong><span style=\"color: #3366ff;\">Por lo general<\/span><\/strong>, Podzoles maduros son mejor usados para <span style=\"color: #3366ff;\"><strong>pastizales extensos<\/strong> <\/span>(de ovejas) o se dejan bajo su <span style=\"color: #3366ff;\"><strong>vegetaci\u00f3n natural<\/strong> <\/span>(cl\u00edmax).<\/p>\n<p align=\"center\"><img decoding=\"async\" class=\"ngg-singlepic ngg-center\" src=\"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-content\/blogs.dir\/42\/files\/164\/paisaje-de-podzol-fuente-osirisnaturaleza.jpg\" alt=\"paisaje-de-podzol-fuente-osirisnaturaleza\" width=\"514\" height=\"365\" \/><\/p>\n<p align=\"center\"><a href=\"http:\/\/my.opera.com\/osirismelisa70\/blog\/index.dml\/tag\/NATURALEZA\">Paisaje de Podzol. Fuente: OSIRISNATURALEZA<\/a><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #800000;\"><strong><!--more--><\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #800000;\"><strong>WRB (2006-2007) traducci\u00f3n oficial de Mabel Susana Pazos<\/strong><\/span><\/p>\n<h3 style=\"text-align: justify;\"><span style=\"color: #800000;\">Manejo y uso de Podzoles<\/span><\/h3>\n<p style=\"text-align: justify;\"><strong>Los Podzoles zonales ocurren en regiones con condiciones clim\u00e1ticas no favorables para la mayor\u00eda de los usos arables de la tierra<\/strong>. Los <strong>Podzoles intrazonales son m\u00e1s frecuentemente recuperados para uso arable que los Podzoles zonales<\/strong>, particularmente los que est\u00e1n <strong>en climas templados<\/strong>. El <strong>bajo nivel de nutrientes, bajo nivel de humedad disponible y el bajo pH <\/strong>hacen a los Podzoles suelos <strong>poco atractivos para la agricultura<\/strong>. <strong>La toxicidad por aluminio<\/strong> <strong>y deficiencia de P <\/strong>son problemas comunes. <strong>La arada profunda<\/strong> (para mejorar la capacidad de almacenamiento de humedad del suelo y\/o <strong>eliminar un horizonte iluvial denso o hardpan<\/strong>), <strong>encalado y fertilizaci\u00f3n<\/strong> son las principales medidas de mejora que se utilizan<strong>. Los elementos traza pueden migrar con los complejos metal\u2013humus<\/strong>. En la regi\u00f3n del Cabo del Oeste de Sud\u00e1frica, <span style=\"color: #3366ff;\"><strong>los huertos y vi\u00f1edos de ra\u00edces profundas sufren menores deficiencias de elementos traza que los cultivos de vegetales con ra\u00edces menos profundas<\/strong><\/span>.<\/p>\n<p style=\"text-align: justify;\"><strong>La mayor\u00eda de los Podzoles zonales est\u00e1n bajo bosque, los Podzoles intrazonales de regiones templadas est\u00e1n principalmente bajo bosques o arbustos (brezos)<\/strong>. <strong><span style=\"color: #3366ff;\">Los Podzoles tropicales normalmente sostienen un bosque ligero que s\u00f3lo se recupera lentamente luego de cortado o incendiado<\/span><\/strong>. Los <strong>Podzoles maduros<\/strong> generalmente son mejor utilizados <strong>para pastoreo extensivo<\/strong> o se dejan ociosos bajo su vegetaci\u00f3n natural (climax).<\/p>\n<p style=\"text-align: center;\">\u00a0<img decoding=\"async\" class=\"ngg-singlepic ngg-center\" src=\"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-content\/blogs.dir\/42\/files\/145\/podzol-albic_placic_podzol-universidad-de-gent-foto-erika-michelli.jpg\" alt=\"podzol-albic_placic_podzol-universidad-de-gent-foto-erika-michelli\" width=\"524\" height=\"425\" \/><\/p>\n<p align=\"center\"><a href=\"http:\/\/www.labsoilscience.ugent.be\/\">Podzol Albic-Placic-Podzol Universidad de Gent, bajo brezal y con\u00edferas.\u00a0Foto Erika Michelli<\/a><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #008000;\"><strong>Francisco Javier Manr\u00edquez Cosio y Juan Jos\u00e9 Ib\u00e1\u00f1ez<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #800000;\"><strong>Material\u00a0 Bibliogr\u00e1fico<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.fao.org\/nr\/land\/soils\/soil\/en\">P\u00e1gina Web de la WRB<\/a><\/p>\n<p style=\"text-align: justify;\"><a href=\"ftp:\/\/ftp.fao.org\/docrep\/fao\/011\/a0510s\/a0510s00.pdf\">Clasificaci\u00f3n WRB 2006-2007<\/a><\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.fao.org\/DOCREP\/003\/Y1899E\/Y1899E00.HTM\">Lecture notes on the major soils of the world<\/a> (versi\u00f3n personal traducida al espa\u00f1ol por Javier Manr\u00edquez Cos\u00edo)<\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.inegi.org.mx\/prod_serv\/contenidos\/espanol\/bvinegi\/productos\/integracion\/especiales\/BoletinSNEIG\/2010\/Bsnieg14_b.pdf\">Los suelos de Latinoam\u00e9rica: retos y oportunidades de uso y estudio<\/a> (ir al titulo correspondiente) Autores: Francisco Bautista, Alfred J. Zinck y Silke Cram. Bolet\u00edn del Sistema Nacional de Informaci\u00f3n Estad\u00edstica y Geogr\u00e1fica: VII(3) Septiembre-Diciembre 2009, p\u00e1ginas 94-142<\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/eusoils.jrc.ec.europa.eu\/esdb_archive\/eusoils_docs\/other\/EUR23439.pdf\">Soils of the European Union<\/a> (en Ingles)<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #800000;\"><strong>Post Previos y a Publicar en Breve de Nuestro Curso B\u00e1sico Tipos de Suelos del Mundo<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\">\u00a0<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/06\/23\/136471\">Los Suelos del Mundo y Su clasificaci\u00f3n (WRB). Curso B\u00e1sico sobre Clasificaci\u00f3n de Suelos<\/a><\/p>\n<p style=\"text-align: justify;\">\u00a0<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/06\/28\/136476\">Suelos Minerales Condicionados por la Topograf\u00eda o Fisiograf\u00eda: Leptosoles, Regosoles, Fluvisoles y Gleysoles<\/a><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #800000;\"><strong>Post Previos y a Publicar en Breve de Nuestro Curso B\u00e1sico Tipos de Suelos del Mundo hasta Julio de 2012<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/06\/23\/136471\">Los Suelos del Mundo y Su clasificaci\u00f3n (WRB). Curso B\u00e1sico sobre Clasificaci\u00f3n de Suelos<\/a><\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/06\/28\/136476\">Suelos Minerales Condicionados por la Topograf\u00eda o Fisiograf\u00eda: Leptosoles, Regosoles, Fluvisoles y Gleysoles<\/a><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #008080;\"><strong>Leptosoles<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/07\/06\/136490\">Leptosoles<\/a>;\u00a0<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/07\/13\/136682\">Leptosoles: Geograf\u00eda Ambiente y Paisaje<\/a>;\u00a0<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/07\/28\/136691\">Leptosoles Uso y Manejo<\/a>;<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/08\/04\/136695\">Leptosoles en Latinoam\u00e9rica<\/a>;\u00a0<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/08\/11\/136703\">Leptosoles en Europa<\/a>;\u00a0<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/08\/22\/136503\">Tipos de Leptosoles y sus Mapas de Distribuci\u00f3n en Europa<\/a><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #008080;\"><strong>Regosoles<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/09\/02\/136720\">Regosoles<\/a>; \u00a0<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/09\/09\/136869\">Regosoles: Geograf\u00eda, Ambiente y Paisaje<\/a>;\u00a0<a title=\"Enlace permanente a Regosoles: Uso y Manejo\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/09\/16\/136876\">Regosoles: Uso y Manejo<\/a>:\u00a0<a title=\"Enlace permanente a Regosoles en Latinoam\u00e9rica\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/09\/24\/136882\">Regosoles en Latinoam\u00e9rica<\/a>;\u00a0<a title=\"Enlace permanente a Regosoles en Europa\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/10\/28\/136908\">Regosoles en Europa<\/a>;\u00a0<a title=\"Enlace permanente a Tipos de Regosoles y sus Mapas de Distribuci\u00f3n en Europa(WRB 1998)\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/11\/04\/136894\">Tipos de Regosoles y sus Mapas de Distribuci\u00f3n en Europa(WRB 1998)<\/a><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #008080;\"><strong>Fluvisoles<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><a title=\"Enlace permanente a Paisajes Aluviales No Costeros de las Redes Fluviales (WRB 1998)\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/01\/06\/137193\">Paisajes Aluviales No Costeros de las Redes Fluviales (WRB 1998)<\/a>;\u00a0<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/01\/13\/137830\">Deltas, Estuarios y Marismas<\/a>;\u00a0<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/01\/19\/137847\">Geoformas de las L\u00edneas de Costa Generadas por la Din\u00e1mica Marina (WRB-FAO 2000)<\/a>,\u00a0<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/01\/26\/137868\">Fluvisoles<\/a>,\u00a0<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/02\/02\/138188\">Fluvisoles ti\u00f3nicos<\/a>,\u00a0<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/02\/01\/137894\">Distribuci\u00f3n geogr\u00e1fica de los Fluvisoles<\/a>,\u00a0<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/02\/03\/137903\">Fluvisoles uso y manejo<\/a>,\u00a0<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/02\/04\/137912\">Fluvisoles en Latinoam\u00e9rica<\/a>,\u00a0<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/02\/07\/137923\">Fluvisoles en Europa<\/a>,\u00a0<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/02\/08\/137936\">Mapas de los tipos de suelos de Europa (WRB 1998)<\/a><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #008080;\">\u00a0<strong>Gleysoles<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/02\/16\/138132\">Gleysoles<\/a>;\u00a0<a title=\"Enlace permanente a Gleysoles: Geograf\u00eda Ambiente y Paisaje\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/02\/24\/138158\">Gleysoles: Geograf\u00eda Ambiente y Paisaje<\/a>\u00a0<a title=\"Enlace permanente a Gleysoles: Uso y Manejo\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/02\/25\/138174\">Gleysoles: Uso y Manejo<\/a>,\u00a0<a title=\"Enlace permanente a Gleysoles en Latinoam\u00e9rica\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/02\/28\/138196\">Gleysoles en Latinoam\u00e9rica<\/a>,\u00a0<a title=\"Enlace permanente a Gleysoles en Europa\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/03\/01\/138204\">Gleysoles en Europa<\/a>,\u00a0<a title=\"Enlace permanente a Tipos de Gleysoles y sus Mapas de Distribuci\u00f3n en Europa\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/03\/03\/138117\">Tipos de Gleysoles y sus Mapas de Distribuci\u00f3n en Europa<\/a><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #008080;\"><strong>Stagnosoles (WRB 2006-2007)<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/03\/17\/138151\">Stagnosoles<\/a><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #008080;\"><strong>Histosoles<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><a title=\"Enlace permanente a Histosoles (WRB 1998): Las Turberas\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/03\/30\/138691\">Histosoles (WRB 1998): Las Turberas<\/a>; <a title=\"Enlace permanente a Histosoles (Turberas): Geograf\u00eda, Ambiente y Paisaje\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/04\/05\/138702\">Histosoles (Turberas): Geograf\u00eda, Ambiente y Paisaje<\/a>; <a title=\"Enlace permanente a Histosoles Uso y Manejo (Turberas) (WRB 1998)\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/04\/06\/138714\">Histosoles Uso y Manejo (Turberas) (WRB 1998)<\/a>; <a title=\"Enlace permanente a Histosoles en Latinoam\u00e9rica Tropical\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/04\/08\/138760\">Histosoles en Latinoam\u00e9rica Tropical<\/a>; <a title=\"Enlace permanente a Histosoles en Europa (Turberas)\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/04\/11\/138742\">Histosoles en Europa (Turberas)<\/a>; <a title=\"Enlace permanente a Tipos de Histosoles y sus Mapas de Distribuci\u00f3n en Europa (WRB 1998)\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/04\/20\/138751\">Tipos de Histosoles y sus Mapas de Distribuci\u00f3n en Europa (WRB 1998)<\/a><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #008080;\"><strong>Cambisoles<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/06\/09\/139388\">Cambisoles<\/a>; <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/06\/15\/139402\">Cambisoles: Geograf\u00eda Ambiente y Paisaje<\/a>; <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/06\/22\/139434\">Cambisoles: Uso y Manejo<\/a>; <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/06\/23\/139458\">Cambisoles en Latinoam\u00e9rica<\/a>;\u00a0 <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/06\/30\/139418\">Cambisoles en Europa<\/a>; <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/07\/07\/139426\">Tipos de Cambisoles y Sus Mapas de Distribuci\u00f3n en Europa<\/a><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #008080;\"><strong>Arenosoles<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><a title=\"Enlace permanente a Dunas y Paisajes Arenosos (WRB 1998)\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/07\/12\/139706\">Dunas y Paisajes Arenosos (WRB 1998)<\/a>; <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/07\/13\/139746\">Arenosoles<\/a>; <a title=\"Enlace permanente a Arenosoles: Geograf\u00eda Ambiente y Paisaje\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/07\/18\/139756\">Arenosoles: Geograf\u00eda; Ambiente y Paisaje<\/a>; <a title=\"Enlace permanente a Arenosoles: Uso y Manejo\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/07\/21\/139772\">Arenosoles: Uso y Manejo<\/a>; <a title=\"Enlace permanente a Arenosoles en Latinoam\u00e9rica\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/07\/28\/139786\">Arenosoles en Latinoam\u00e9rica<\/a>; <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/08\/04\/139794\">Arenosoles en Europa<\/a>; <a title=\"Enlace permanente a Tipos de Arenosoles y sus Mapas de Distribuci\u00f3n en Europa\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/08\/11\/139800\">Tipos de Arenosoles y sus Mapas de Distribuci\u00f3n en Europa<\/a><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #008080;\"><strong>Vertisoles<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><a title=\"Enlace permanente a Paisajes Arcillosos (WRB, 1998)\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/09\/29\/139981\">Paisajes Arcillosos (WRB, 1998)<\/a>, <a title=\"Enlace permanente a Microrelieve Gilgai  (Vertisoles, WRB, 1998)\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/10\/04\/140078\">Microrelieve Gilgai (Vertisoles, WRB, 1998)<\/a>, <a title=\"Enlace permanente a Vertisoles (WRB, 1998)\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/10\/06\/140062\">Vertisoles (WRB, 1998)<\/a>, <a title=\"Enlace permanente a Vertisoles: Geograf\u00eda, Ambiente y Paisaje\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/10\/13\/140087\">Vertisoles: Geograf\u00eda, Ambiente y Paisaje<\/a>, <a title=\"Enlace permanente a Vertisoles: Uso y Manejo\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/10\/21\/140108\">Vertisoles: Uso y Manejo<\/a>, <a title=\"Enlace permanente a Vertisoles en Latinoam\u00e9rica\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/10\/28\/140114\">Vertisoles en Latinoam\u00e9rica<\/a>, <a title=\"Enlace permanente a Vertisoles en La UE y el Continente Europeo\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/11\/01\/140049\">Vertisoles en La UE y el Continente Europeo<\/a>, <a title=\"Enlace permanente a Tipos de Vertisoles y sus Mapas de Distribuci\u00f3n en Europa\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/11\/11\/140053\">Tipos de Vertisoles y sus Mapas de Distribuci\u00f3n en Europa<\/a><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #008080;\"><strong>Andosoles<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/11\/16\/140617\">Paisajes Volc\u00e1nicos<\/a>, <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/11\/23\/140258\">Andosoles<\/a>, <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/12\/02\/140627\">Andosoles: geograf\u00eda ambiente y paisaje<\/a>, <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/12\/20\/140649\">Andosoles Uso y Manejo<\/a>, <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/01\/17\/140659\">Andosoles en Latinoam\u00e9rica<\/a>, <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/01\/25\/140135\">Andosoles en Europa<\/a>, <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/01\/25\/140135\">Andosoles en Europa\u00a0 y los Suelos de Islandia<\/a>, <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/02\/02\/140142\">Tipos de Andosoles y sus mapas de distribuci\u00f3n en Europa<\/a><strong><\/strong><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #008080;\"><strong>Luvisoles<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/02\/28\/141085\">Luvisoles<\/a>, <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/03\/15\/141095\">Luvisoles: geograf\u00eda ambiente y paisaje<\/a>, <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/03\/23\/141101\">Luvisoles Uso y Manejo<\/a>; <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/03\/27\/141109\">Luvisoles en Latinoam\u00e9rica<\/a>, <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/04\/03\/141236\">Luvisoles en Europa<\/a>, <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/04\/07\/141248\">Tipos de Luvisoles y sus mapas de distribuci\u00f3n en Europa<\/a>.<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #008080;\"><strong>Alisoles<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><a title=\"Enlace permanente a Alisoles (WRB, 1998)\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/04\/19\/141598\">Alisoles (WRB, 1998)<\/a>; <a title=\"Enlace permanente a Alisoles: Geograf\u00eda Ambiente y Paisaje\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/04\/25\/141607\">Alisoles: Geograf\u00eda Ambiente y Paisaje<\/a>, <a title=\"Enlace permanente: Alisoles: Uso y Manejo\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/05\/03\/141613\">Alisoles: Uso y Manejo<\/a><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #008080;\"><strong>Lixisoles<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/05\/09\/141636\">Lixisoles<\/a>; <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/05\/22\/141646\">Lixisoles: Geograf\u00eda ambiente y paisaje<\/a>; <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/05\/31\/141657\">Lixisoles: Uso y manejo<\/a><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #008080;\"><strong>Acrisoles<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/06\/07\/142059\">Acrisoles<\/a>, <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/06\/13\/142068\">Acrisoles: geograf\u00eda ambiente y paisaje<\/a>, <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/06\/20\/142080\">Acrisoles Uso y Manejo<\/a>, Acrisoles en Latinoam\u00e9rica, Acrisoles en Europa, Tipos de Acrisoles y sus mapas de distribuci\u00f3n en Europa.<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #008080;\"><strong>Albeluvisoles<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\">Albeluvisoles: Albeluvisoles: Geograf\u00eda, Ambiente y Paisaje; Albeluvisoles: uso y manejo; Albeluvisoles en Europa, Tipos de Acrisoles y sus mapas de distribuci\u00f3n en Europa.<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #008080;\"><strong>Podzoles <\/strong><\/span><\/p>\n<p style=\"text-align: justify;\">Podzoles; Podzoles, Geograf\u00eda, Ambiente y Paisaje<\/p>\n<h3>Im\u00e1genes Relacionadas:<\/h3>","protected":false},"excerpt":{"rendered":"<p>Los Podzoles zonales\u00a0se ubican en regiones que sufren condiciones clim\u00e1ticas poco atractivas para la mayor\u00eda de los usos agrarios. Los Podzoles intrazonales\u00a0suelen ser m\u00e1s habitualmente recuperados para la agricultura con labranza que los Podzoles zonales, particularmente en la franja clim\u00e1tica septentrional del bioma templado bajo condiciones m\u00e1s benignas, con un periodo vegetativo de mayor duraci\u00f3n.\u00a0Bajo estatus de nutrientes, escasa nivel de humedad disponible para las plantas, as\u00ed como un pH del suelo muy \u00e1cido, hace a los Podzoles suelos poco aptos con vistas a la agricultura de labranza. La toxicidad del Al y la deficiencia de f\u00f3sforo son otros problemas\u2026<\/p>\n","protected":false},"author":26,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0},"categories":[1929,613],"tags":[1284,46744,18007,46960],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":4}},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Los Podzoles zonales se ubican en regiones que sufren condiciones clim\u00e1ticas poco atractivas para la mayor\u00eda de los usos agrarios. Los Podzoles intrazonales suelen ser m\u00e1s habitualmente recuperados para la agricultura con labranza que los Podzoles zonales, particularmente en la franja clim\u00e1tica septentrional del bioma templado bajo condiciones m\u00e1s benignas, con un periodo vegetativo de mayor duraci\u00f3n. Bajo\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Juan Jos\u00e9 Ib\u00e1\u00f1ez\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/09\/07\/142329\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Un Universo invisible bajo nuestros pies - Los suelos y la vida\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Podzoles: Uso y Manejo - Un Universo invisible bajo nuestros pies\" \/>\n\t\t<meta property=\"og:description\" content=\"Los Podzoles zonales se ubican en regiones que sufren condiciones clim\u00e1ticas poco atractivas para la mayor\u00eda de los usos agrarios. Los Podzoles intrazonales suelen ser m\u00e1s habitualmente recuperados para la agricultura con labranza que los Podzoles zonales, particularmente en la franja clim\u00e1tica septentrional del bioma templado bajo condiciones m\u00e1s benignas, con un periodo vegetativo de mayor duraci\u00f3n. Bajo\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/09\/07\/142329\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2012-09-07T12:03:30+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2012-09-07T12:03:30+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/juan.j.marti.14\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Podzoles: Uso y Manejo - Un Universo invisible bajo nuestros pies\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Los Podzoles zonales se ubican en regiones que sufren condiciones clim\u00e1ticas poco atractivas para la mayor\u00eda de los usos agrarios. Los Podzoles intrazonales suelen ser m\u00e1s habitualmente recuperados para la agricultura con labranza que los Podzoles zonales, particularmente en la franja clim\u00e1tica septentrional del bioma templado bajo condiciones m\u00e1s benignas, con un periodo vegetativo de mayor duraci\u00f3n. Bajo\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2012\\\/09\\\/07\\\/142329#blogposting\",\"name\":\"Podzoles: Uso y Manejo - Un Universo invisible bajo nuestros pies\",\"headline\":\"Podzoles: Uso y Manejo\",\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"http:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/wp-content\\\/blogs.dir\\\/42\\\/files\\\/164\\\/podzol-uso-fuente-teara.jpg\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2012\\\/09\\\/07\\\/142329\\\/#articleImage\"},\"datePublished\":\"2012-09-07T13:03:30+01:00\",\"dateModified\":\"2012-09-07T13:03:30+01:00\",\"inLanguage\":\"es-ES\",\"commentCount\":15,\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2012\\\/09\\\/07\\\/142329#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2012\\\/09\\\/07\\\/142329#webpage\"},\"articleSection\":\"Curso B\\u00e1sico: Tipos de Suelos del Mundo, Fertilidad de Suelos y Nutrici\\u00f3n Vegetal, Fertilidad, geograf\\u00eda de suelos, Podzoles, uso y manejo\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2012\\\/09\\\/07\\\/142329#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/fertilidad-de-suelos-y-nutricion-vegetal#listItem\",\"name\":\"Fertilidad de Suelos y Nutrici\\u00f3n Vegetal\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/fertilidad-de-suelos-y-nutricion-vegetal#listItem\",\"position\":2,\"name\":\"Fertilidad de Suelos y Nutrici\\u00f3n Vegetal\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/fertilidad-de-suelos-y-nutricion-vegetal\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2012\\\/09\\\/07\\\/142329#listItem\",\"name\":\"Podzoles: Uso y Manejo\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2012\\\/09\\\/07\\\/142329#listItem\",\"position\":3,\"name\":\"Podzoles: Uso y Manejo\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/fertilidad-de-suelos-y-nutricion-vegetal#listItem\",\"name\":\"Fertilidad de Suelos y Nutrici\\u00f3n Vegetal\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#organization\",\"name\":\"Un Universo invisible bajo nuestros pies\",\"description\":\"Los suelos y la vida\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/files\\\/2022\\\/02\\\/logo.png\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2012\\\/09\\\/07\\\/142329\\\/#organizationLogo\",\"width\":217,\"height\":72},\"image\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2012\\\/09\\\/07\\\/142329\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/juan.j.marti.14\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo\",\"name\":\"Juan Jos\\u00e9 Ib\\u00e1\\u00f1ez\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2012\\\/09\\\/07\\\/142329#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/387f3a100385573d8f42ce2a3211fd1c?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Juan Jos\\u00e9 Ib\\u00e1\\u00f1ez\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2012\\\/09\\\/07\\\/142329#webpage\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2012\\\/09\\\/07\\\/142329\",\"name\":\"Podzoles: Uso y Manejo - Un Universo invisible bajo nuestros pies\",\"description\":\"Los Podzoles zonales se ubican en regiones que sufren condiciones clim\\u00e1ticas poco atractivas para la mayor\\u00eda de los usos agrarios. Los Podzoles intrazonales suelen ser m\\u00e1s habitualmente recuperados para la agricultura con labranza que los Podzoles zonales, particularmente en la franja clim\\u00e1tica septentrional del bioma templado bajo condiciones m\\u00e1s benignas, con un periodo vegetativo de mayor duraci\\u00f3n. Bajo\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2012\\\/09\\\/07\\\/142329#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\"},\"datePublished\":\"2012-09-07T13:03:30+01:00\",\"dateModified\":\"2012-09-07T13:03:30+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#website\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/\",\"name\":\"Un Universo invisible bajo nuestros pies\",\"description\":\"Los suelos y la vida\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Podzoles: Uso y Manejo - Un Universo invisible bajo nuestros pies","description":"Los Podzoles zonales se ubican en regiones que sufren condiciones clim\u00e1ticas poco atractivas para la mayor\u00eda de los usos agrarios. Los Podzoles intrazonales suelen ser m\u00e1s habitualmente recuperados para la agricultura con labranza que los Podzoles zonales, particularmente en la franja clim\u00e1tica septentrional del bioma templado bajo condiciones m\u00e1s benignas, con un periodo vegetativo de mayor duraci\u00f3n. Bajo","canonical_url":"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/09\/07\/142329","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/09\/07\/142329#blogposting","name":"Podzoles: Uso y Manejo - Un Universo invisible bajo nuestros pies","headline":"Podzoles: Uso y Manejo","author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author"},"publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#organization"},"image":{"@type":"ImageObject","url":"http:\/\/www.madrimasd.org\/blogs\/universo\/wp-content\/blogs.dir\/42\/files\/164\/podzol-uso-fuente-teara.jpg","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/09\/07\/142329\/#articleImage"},"datePublished":"2012-09-07T13:03:30+01:00","dateModified":"2012-09-07T13:03:30+01:00","inLanguage":"es-ES","commentCount":15,"mainEntityOfPage":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/09\/07\/142329#webpage"},"isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/09\/07\/142329#webpage"},"articleSection":"Curso B\u00e1sico: Tipos de Suelos del Mundo, Fertilidad de Suelos y Nutrici\u00f3n Vegetal, Fertilidad, geograf\u00eda de suelos, Podzoles, uso y manejo"},{"@type":"BreadcrumbList","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/09\/07\/142329#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo#listItem","position":1,"name":"Home","item":"https:\/\/www.madrimasd.org\/blogs\/universo","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/fertilidad-de-suelos-y-nutricion-vegetal#listItem","name":"Fertilidad de Suelos y Nutrici\u00f3n Vegetal"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/fertilidad-de-suelos-y-nutricion-vegetal#listItem","position":2,"name":"Fertilidad de Suelos y Nutrici\u00f3n Vegetal","item":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/fertilidad-de-suelos-y-nutricion-vegetal","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/09\/07\/142329#listItem","name":"Podzoles: Uso y Manejo"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/09\/07\/142329#listItem","position":3,"name":"Podzoles: Uso y Manejo","previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/fertilidad-de-suelos-y-nutricion-vegetal#listItem","name":"Fertilidad de Suelos y Nutrici\u00f3n Vegetal"}}]},{"@type":"Organization","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#organization","name":"Un Universo invisible bajo nuestros pies","description":"Los suelos y la vida","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/","logo":{"@type":"ImageObject","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/09\/07\/142329\/#organizationLogo","width":217,"height":72},"image":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/09\/07\/142329\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/juan.j.marti.14"]},{"@type":"Person","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo","name":"Juan Jos\u00e9 Ib\u00e1\u00f1ez","image":{"@type":"ImageObject","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/09\/07\/142329#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/387f3a100385573d8f42ce2a3211fd1c?s=96&d=mm&r=g","width":96,"height":96,"caption":"Juan Jos\u00e9 Ib\u00e1\u00f1ez"}},{"@type":"WebPage","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/09\/07\/142329#webpage","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/09\/07\/142329","name":"Podzoles: Uso y Manejo - Un Universo invisible bajo nuestros pies","description":"Los Podzoles zonales se ubican en regiones que sufren condiciones clim\u00e1ticas poco atractivas para la mayor\u00eda de los usos agrarios. Los Podzoles intrazonales suelen ser m\u00e1s habitualmente recuperados para la agricultura con labranza que los Podzoles zonales, particularmente en la franja clim\u00e1tica septentrional del bioma templado bajo condiciones m\u00e1s benignas, con un periodo vegetativo de mayor duraci\u00f3n. Bajo","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#website"},"breadcrumb":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/09\/07\/142329#breadcrumblist"},"author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author"},"creator":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author"},"datePublished":"2012-09-07T13:03:30+01:00","dateModified":"2012-09-07T13:03:30+01:00"},{"@type":"WebSite","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#website","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/","name":"Un Universo invisible bajo nuestros pies","description":"Los suelos y la vida","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Un Universo invisible bajo nuestros pies - Los suelos y la vida","og:type":"article","og:title":"Podzoles: Uso y Manejo - Un Universo invisible bajo nuestros pies","og:description":"Los Podzoles zonales se ubican en regiones que sufren condiciones clim\u00e1ticas poco atractivas para la mayor\u00eda de los usos agrarios. Los Podzoles intrazonales suelen ser m\u00e1s habitualmente recuperados para la agricultura con labranza que los Podzoles zonales, particularmente en la franja clim\u00e1tica septentrional del bioma templado bajo condiciones m\u00e1s benignas, con un periodo vegetativo de mayor duraci\u00f3n. Bajo","og:url":"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/09\/07\/142329","og:image":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png","og:image:secure_url":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png","article:published_time":"2012-09-07T12:03:30+00:00","article:modified_time":"2012-09-07T12:03:30+00:00","article:publisher":"https:\/\/www.facebook.com\/juan.j.marti.14","twitter:card":"summary","twitter:title":"Podzoles: Uso y Manejo - Un Universo invisible bajo nuestros pies","twitter:description":"Los Podzoles zonales se ubican en regiones que sufren condiciones clim\u00e1ticas poco atractivas para la mayor\u00eda de los usos agrarios. Los Podzoles intrazonales suelen ser m\u00e1s habitualmente recuperados para la agricultura con labranza que los Podzoles zonales, particularmente en la franja clim\u00e1tica septentrional del bioma templado bajo condiciones m\u00e1s benignas, con un periodo vegetativo de mayor duraci\u00f3n. Bajo","twitter:image":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png"},"aioseo_meta_data":{"post_id":"142329","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":null,"isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","tabs":null,"priority":null,"frequency":null,"local_seo":null,"created":"2022-06-03 11:39:04","updated":"2026-05-26 17:24:55","limit_modified_date":false,"ai":null,"breadcrumb_settings":null,"seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/fertilidad-de-suelos-y-nutricion-vegetal\" title=\"Fertilidad de Suelos y Nutrici\u00f3n Vegetal\">Fertilidad de Suelos y Nutrici\u00f3n Vegetal<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tPodzoles: Uso y Manejo\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.madrimasd.org\/blogs\/universo"},{"label":"Fertilidad de Suelos y Nutrici\u00f3n Vegetal","link":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/fertilidad-de-suelos-y-nutricion-vegetal"},{"label":"Podzoles: Uso y Manejo","link":"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/09\/07\/142329"}],"_links":{"self":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts\/142329"}],"collection":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/comments?post=142329"}],"version-history":[{"count":10,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts\/142329\/revisions"}],"predecessor-version":[{"id":142739,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts\/142329\/revisions\/142739"}],"wp:attachment":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/media?parent=142329"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/categories?post=142329"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/tags?post=142329"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}