{"id":142854,"date":"2013-03-22T16:21:35","date_gmt":"2013-03-22T15:21:35","guid":{"rendered":"http:\/\/www.madrimasd.org\/blogs\/universo\/?p=142854"},"modified":"2013-03-22T16:21:49","modified_gmt":"2013-03-22T15:21:49","slug":"sector-medioambiental-y-economia-de-mercado-un-robo-denominado-acaparamiento-de-tierras","status":"publish","type":"post","link":"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/03\/22\/142854","title":{"rendered":"Sector Medioambiental y Econom\u00eda de Mercado: \u201cUn Robo denominado Acaparamiento de Tierras\u201d"},"content":{"rendered":"<p style=\"text-align: justify;\"><span style=\"color: #3366ff;\"><strong>\u00bfAutorregulaci\u00f3n de los mercados?<\/strong><\/span> Esa cantinela falaz del neoliberalismo econ\u00f3mico que nos vende gato por liebre. Ya sufrimos <span style=\"color: #3366ff;\"><strong>las consecuencias a escala mundial<\/strong><\/span>, con un <span style=\"color: #3366ff;\"><strong>empobrecimiento de la poblaci\u00f3n en general<\/strong><\/span>, pero que oprime sobremanera a\u00a0 los m\u00e1s desfavorecidos. La <span style=\"color: #3366ff;\"><strong>privatizaci\u00f3n \u00a0de las tierras a escala global<\/strong><\/span>, se realiza de diversas formas. <span style=\"color: #3366ff;\"><strong>Por un lado los gobiernos y multinacionales de las grandes potencias adquieren enormes extensiones de los que menos tienen atentando contra la seguridad alimentaria de los pa\u00edses pobres<\/strong><\/span>. Se trata de un <span style=\"color: #3366ff;\"><strong>aprovisionamiento de riquezas de otros Estados con vistas a mantener y\/o hacer crecer las suyas propias<\/strong><\/span>. \u00a0Pero nos encontramos con <span style=\"color: #3366ff;\"><strong>otra modalidad<\/strong><\/span>, \u201caparentemente\u201d no muy\u00a0sospechosa, pero no por ello menos da\u00f1ina. \u00a0\u00a0Nos referimos \u00a0al denominado \u00a0<strong>\u201c<span style=\"color: #008000;\">acaparamiento verde<\/span>\u201d. <\/strong>Nuestro antiguo colaborador R\u00e9gulo Le\u00f3n Arteta nos ha enviado la noticia de la que hablaremos hoy. Y as\u00ed en un p\u00e1rrafo leerse: <span style=\"color: #3366ff;\"><strong><em>grandes extensiones de tierras est\u00e1n siendo apropiadas por la agenda ambiental,<\/em><\/strong><em> <strong>un proceso que ha encontrado gran acogida entre influyentes ONG internacionales de conservaci\u00f3n<\/strong><\/em><\/span>. Empero resulta que, mediante tles iniciativas, la vida de muchos seres humanos comienza a valer menos que nada, en comparaci\u00f3n con la de\u00a0otros seres vivos. Se trata de una\u00a0difusa y torticera concepci\u00f3n de la salud biosf\u00e9rica. Por otro lado, es indudable que el <em>Homo tecnol\u00f3gicos<\/em> ha heredado del pasado sus pasiones nacionalistas, manteniendo, cuando no fomentando, nuestros innatos impulsos instintivamente territoriales. Nos enfrentamos a\u00a0un arma enormemente poderosa, a la hora de manipular a sus ciudadanos descontentos, para el provecho de los viles prop\u00f3sitos de una clase pol\u00edtica y econ\u00f3mica sin escr\u00fapulos<strong>. <span style=\"color: #3366ff;\">Si<\/span> <span style=\"color: #3366ff;\">alguien tiene derecho a ser nacionalista, son justamente las poblaciones ind\u00edgenas pisoteadas una y otra vez durante siglos por los colonialismos transformistas<\/span><\/strong> (da igual las prendas con las que pretendan disfrazarse). \u00a0Dicho de otro modo, resulta que tambi\u00e9n <span style=\"color: #3366ff;\"><strong>en aras de la protecci\u00f3n de la naturaleza <\/strong><span style=\"color: #333333;\">(males como los denominados<\/span><\/span><span style=\"color: #333333;\">,<\/span> <span style=\"color: #333333;\">mercado del carbono<\/span>, producci\u00f3n de biocombustibles, <span style=\"color: #3366ff;\"><span style=\"color: #333333;\">etc.)<\/span> <strong>muchas culturas abor\u00edgenes <\/strong><span style=\"color: #333333;\">que vivian en armon\u00eda con la naturaleza mientras las dejaron tranquilas,<\/span> <strong>son expulsadas de sus tierras mediante coaliciones entre ONG de los pa\u00edses capitalistas, sus movimientos conservacionistas, y muchas almas caritativas con tanta sensibilidad como poca cabeza y menos conocimiento<\/strong> <\/span>de la realidad de este mundo. De uno u otro modo, <span style=\"color: #3366ff;\"><strong>los pa\u00edses empobrecidos venden sus tierras patrias, asegurando<\/strong> <\/span>algo de dinero para hoy y m\u00e1s <span style=\"color: #3366ff;\"><strong>pobreza en el futuro<\/strong><\/span>. Y casi siempre a costa de expulsar hacia un destierro incierto a\u00a0campesinos y pueblos, cuyo \u00fanico pecado ha consistido nacer en pa\u00edses en los que sus\u00a0gobiernos y fuerzas f\u00e1cticas les ignoran y desprecian, cuando no masacran. Si, esos mismos personajes que ensalzan\u00a0sus nacionalidades henchidos de orgullo, al son\u00a0de banderitas e himnos. \u00a0Sin embargo, en la mayor\u00eda de los casos las ra\u00edces de sus gobernantes distan mucho de ser aut\u00f3ctonas. <span style=\"color: #3366ff;\"><strong>Por lo tanto, la brecha ecologista se ahonda entre los Estados m\u00e1s afortunados y los soberanamente desafortunados. Preservar la biosfera es una labor digna de encomio, hasta que se contrapone con los intereses de sus leg\u00edtimos propietarios<\/strong><\/span>. <span style=\"color: #3366ff;\"><strong>Robar a los pobres para mantener el bienestar de los ricos y la biosfera global es otra forma por la que el capitalismo devora tanto la \u00e9tica como la raz\u00f3n<\/strong><\/span>, convirtiendo las presuntas buenas intenciones en acciones sinsentido, por no llamarlas depredadoras. Hablemos claro, a la luz de esta nueva corriente \u00bfecol\u00f3gico-capitalista? <span style=\"color: #3366ff;\"><strong>l<\/strong><\/span><span style=\"color: #3366ff;\"><strong>os movimientos conservacionistas y humanitarios devienen en adl\u00e1teres del poder neoliberal<\/strong><\/span>. El p\u00e1rrafo con el que comienza la noticia\/denuncia no tiene desperdicio. Ve\u00e1moslo:<\/p>\n<p align=\"center\"><span style=\"color: #800000;\"><em>Compren tierra pues no se fabrica m\u00e1s!\u201d El ir\u00f3nico comentario de Mark Twain sobre el boom de la adquisici\u00f3n de tierras en Am\u00e9rica del Norte a finales del siglo XIX sigue siendo tan pertinente hoy como lo fue entonces. M\u00e1s de 100 a\u00f1os m\u00e1s tarde, la magnitud de las compras actuales de tierra a nivel global y la apropiaci\u00f3n de las tierras de los pobladores locales no tiene precedentes desde las adquisiciones coloniales de tierras del siglo XIX y principios del siglo XX.<\/em><\/span><\/p>\n<p style=\"text-align: center;\"><img decoding=\"async\" class=\"ngg-singlepic ngg-center\" src=\"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-content\/blogs.dir\/42\/files\/1123\/aprovisionamiento-de-tierras-ncr-punto-nl.jpg\" alt=\"aprovisionamiento-de-tierras-ncr-punto-nl\" \/><\/p>\n<p align=\"center\"><span style=\"color: #008000;\"><a href=\"http:\/\/www.nrc.nl\/international\/article2253694.ece\/In_Africa,_farm_land_is_used_to_feed_the_rich_countries\"><span style=\"color: #008000;\">Trabajando para los ladrones de tierra y vida. Fuente: ncr.nl<\/span><\/a><\/span><\/p>\n<p><span style=\"color: #008000;\"><strong>Juan Jos\u00e9 Ib\u00e1\u00f1ez<\/strong><\/span><\/p>\n<p><span style=\"color: #008000;\"><!--more--><\/span><\/p>\n<h3 align=\"left\"><strong><a href=\"http:\/\/www.ecoticias.com\/sostenibilidad\/70398\/dos-gran-acaparamiento-verde-tierras\">A la una, a las dos&#8230; El gran acaparamiento verde de tierras<\/a><\/strong><\/h3>\n<p style=\"text-align: justify;\" align=\"left\">Por <a href=\"http:\/\/www.cifor.org\/about-us\/cifor-scientific-staff-profiles\/detail-profile\/staff\/001014.html\" target=\"_blank\">Terry Sunderland<\/a><br \/>\nInvestigador principal, <a href=\"http:\/\/www.cifor.org\" target=\"_blank\">Centro para la Investigaci\u00f3n Forestal Internacional<\/a><\/p>\n<p>\u201c<strong><em>Compren tierra pues no se fabrica m\u00e1s<\/em><\/strong><em>!<\/em>\u201d El ir\u00f3nico comentario de <strong>Mark Twain sobre el boom de la adquisici\u00f3n de tierras en Am\u00e9rica del Norte a finales del siglo XIX sigue siendo tan pertinente hoy como lo fue entonces<\/strong>. M\u00e1s de 100 a\u00f1os m\u00e1s tarde, la magnitud de las compras actuales de tierra a nivel global y la <strong>apropiaci\u00f3n de las tierras de los pobladores locales<\/strong> <strong>no tiene precedentes desde las adquisiciones coloniales de tierras del siglo XIX y principios del siglo XX<\/strong>.<\/p>\n<p style=\"text-align: justify;\" align=\"left\"><strong>Estimulados por el repunte global en el precio de los alimentos hacia finales de la primera d\u00e9cada de 2000, varios pa\u00edses ricos, <\/strong>que dependen de las importaciones de alimentos,<strong> empezaron a comprar grandes extensiones de tierra en el mundo en desarrollo a fin de alcanzar su propia seguridad alimentaria<\/strong>. Adem\u00e1s, con el surgimiento del <strong>mercado de biocombustibles<\/strong>, las plantaciones para la <strong>reforestaci\u00f3n<\/strong> y la creciente expansi\u00f3n de <strong>los cultivos comerciales<\/strong> como la palma aceitera, el control de <strong>grandes extensiones de bosques en el mundo ha sido transferido del Estado a propietarios privados<\/strong>, destruyendo en el proceso valiosos recursos forestales, especialmente la madera.<\/p>\n<p style=\"text-align: justify;\" align=\"left\">Los motores econ\u00f3micos de <a href=\"http:\/\/www.landcoalition.org\/cpl\/CPL-synthesis-report\" target=\"_blank\">esta conversi\u00f3n de tierras han sido ampliamente documentados<\/a>. Los <strong>gobiernos con grandes extensiones de tierras se ver\u00e1n favorecidos con la expansi\u00f3n de la producci\u00f3n agr\u00edcola, a pesar del impacto inmediato sobre sus poblaciones rurales, que <\/strong>con frecuencia <strong>no se benefician de este tipo de desarrollo econ\u00f3mico y enfrentan m\u00e1s bien la anexi\u00f3n de sus tierras consuetudinarias<\/strong>.<\/p>\n<p style=\"text-align: justify;\" align=\"left\">Mientras que el fen\u00f3meno del <strong>\u201cacaparamiento de tierras<\/strong>\u201d, como se lo ha llegado a conocer, <strong>contin\u00faa sin parar, un movimiento, crecientemente m\u00e1s sutil y cuestionable desde el punto de vista \u00e9tico, <\/strong>ha cobrado impulso<strong>. A nivel global, grandes extensiones de tierras est\u00e1n siendo apropiadas por la agenda ambiental,<\/strong> un proceso que ha encontrado gran acogida entre influyentes <strong>ONG<\/strong> internacionales de conservaci\u00f3n. El periodista del diario ingl\u00e9s <em>The Guardian<\/em>, John Vidal, describi\u00f3 este nuevo enfoque a la conservaci\u00f3n como <a href=\"http:\/\/www.guardian.co.uk\/environment\/2008\/feb\/13\/conservation\" target=\"_blank\">\u201cel acaparamiento verde\u201d<\/a>.<\/p>\n<p style=\"text-align: justify;\" align=\"left\">Esta apropiaci\u00f3n de tierras, basada en el medio ambiente, no es un concepto nuevo. A finales de 1980, el entonces fondo <strong>Earthlife<\/strong><a href=\"http:\/\/www.nigeltuersley.com\/Default.aspx?page=80\" target=\"_blank\"> ofrec\u00eda a compradores privados la oportunidad de adquirir un acre del recientemente creado Parque Nacional de Korup en Camer\u00fan<\/a> para garantizar su conservaci\u00f3n a largo plazo. El esquema fracas\u00f3 por diferentes razones, pero a pesar de las limitaciones iniciales que esta iniciativa representaba, la <strong>comercializaci\u00f3n de la naturaleza<\/strong> se ha ido convirtiendo en <strong>el enfoque dominante hacia la conservaci\u00f3n<\/strong>.<\/p>\n<p style=\"text-align: justify;\" align=\"left\">Un ejemplo claro es la propagaci\u00f3n de portales como <a href=\"http:\/\/www.ecosystemmarketplace.com\" target=\"_blank\">Ecosystems Marketplace<\/a>, entre otros, que sostienen que <strong>los mercados para los servicios ecosist\u00e9micos proporcionados por la naturaleza se integrar\u00e1n en un futuro completamente a nuestros sistemas econ\u00f3micos actuales<\/strong>. Y, como John Vidal manifest\u00f3, <strong>la adquisici\u00f3n de tierras con fines de conservaci\u00f3n se ha convertido en dominio exclusivo de los adinerados, interesados en inversiones exclusivas y supuestamente \u00e9ticas<\/strong>.<\/p>\n<p style=\"text-align: justify;\" align=\"left\">En un documento de s\u00edntesis publicado en una <a href=\"http:\/\/www.tandfonline.com\/toc\/fjps20\/39\/2\" target=\"_blank\">reciente edici\u00f3n especial del <em>Journal of Peasant Studies<\/em><\/a>, James Fairhead y sus colegas muestran <strong>el creciente predominio del \u201cacaparamiento verde\u201d y c\u00f3mo el sector del medio ambiente est\u00e1 influyendo en la forma que percibimos y gestionamos la naturaleza<\/strong>. Estos investigadores presentan un an\u00e1lisis revelador que muestra <strong>hasta d\u00f3nde ha llegado el sector ambiental para aceptar la econom\u00eda de mercado, ya sea para<\/strong> <strong>servicios de carbono, biodiversidad o servicios al ecosistema<\/strong>.<\/p>\n<p style=\"text-align: justify;\" align=\"left\">Fairhead y sus colegas argumentan que <strong>la mercantilizaci\u00f3n de la naturaleza ha reflejado una tendencia global hacia el neoliberalismo, en donde el mercado define y supuestamente dicta lo que debemos y no debemos valorar<\/strong>. Por ello, los esquemas de Pagos por Servicios Ambientales (PSE), la Reducci\u00f3n de las Emisiones de Deforestaci\u00f3n y Degradaci\u00f3n de los Bosques (REDD) y otras iniciativas basadas en el mercado han sido incluidas en la agenda de conservaci\u00f3n.<\/p>\n<p style=\"text-align: justify;\" align=\"left\"><strong>Cada vez m\u00e1s, la naturaleza se ha convertido en una fuente de ganancias econ\u00f3micas, generando inesperadas alianzas entre empresas, gobiernos con grandes extensiones de tierras, la industria bancaria, ONG de conservaci\u00f3n internacionales y la comunidad de donantes<\/strong>. A la luz de la reciente p\u00e9rdida de confianza en la industria financiera global y la resultante recesi\u00f3n global, sorprende quiz\u00e1s que nuestras preocupaciones ambientales se vean influenciadas por la necesidad de integrar <strong>mercados para carbono y otros productos naturales<\/strong> a nuestras econom\u00edas. <strong>Todo parece indicar que el dinero habla. \u00bfPero es esto cierto?<\/strong><\/p>\n<p style=\"text-align: justify;\" align=\"left\"><strong>Lamentablemente, los enfoques basados en las finanzas, por m\u00e1s bien intencionados que sean, tienden a pisotear los derechos de la poblaci\u00f3n local<\/strong>. La apropiaci\u00f3n de tierras sin un reconocimiento completo de la tenencia consuetudinaria que los pobladores rurales han disfrutado por siglos tendr\u00e1 sin lugar a dudas consecuencias negativas sobre los medios de vida. Aunque los <a href=\"http:\/\/www.cifor.cgiar.org\/Knowledge\/Publications\/Detail?pid=2800\" target=\"_blank\">enfoques basados en derechos<\/a> para \u201cinfringir el menor da\u00f1o posible\u201d a la gente local est\u00e1n bastante desarrollados desde el punto de vista conceptual, la realidad en el campo es con frecuencia bastante diferente. De ah\u00ed la <a href=\"http:\/\/www.forestsclimatechange.org\/fileadmin\/downloads\/rightsbased12.pdf\" target=\"_blank\">bien documentada resistencia a las iniciativas PSE\/REDD<\/a> <strong>por parte de las poblaciones ind\u00edgenas que ven sus derechos avasallados y sus medios de vida seriamente afectados<\/strong>.<\/p>\n<p style=\"text-align: justify;\" align=\"left\">El <a href=\"http:\/\/www.un.org\/en\/sustainablefuture\/\" target=\"_blank\">principal resultado de Rio +20, donde las \u201ceconom\u00edas verdes\u201d fueron consideradas fundamentales en la agenda de desarrollo sostenible<\/a>, <strong>ha aumentado la percepci\u00f3n de que las soluciones basadas en el mercado son la panacea para los problemas ambientales del mundo<\/strong>. Como resultado, algunos argumentan que <strong>el valor intr\u00ednseco de la naturaleza y el respeto por los medios de vida y los sistemas de conocimiento locales se han perdido frente a<\/strong> enfoques influenciados cada vez m\u00e1s por enfoques de mercado.<\/p>\n<p style=\"text-align: justify;\" align=\"left\"><strong>El sistema global enfocado en el mercado ha estado supuestamente encargado de supervisar la transformaci\u00f3n de casi todos los ecosistemas y biomas de la tierra<\/strong>. Por ello, buscar en la misma fuente soluciones sostenibles y equitativas a nuestros problemas ambientales podr\u00eda parecer cuestionable. Las millones de personas que pronto se quedar\u00e1n sin tierras probablemente estar\u00edan de acuerdo.<\/p>\n<p style=\"text-align: justify;\" align=\"left\"><strong>M\u00e1s informaci\u00f3n<\/strong><\/p>\n<p style=\"text-align: justify;\" align=\"left\">For further reading of \u201cgreen grabbing\u201d please refer to the following link: <a href=\"http:\/\/www.tni.org\/interview\/green-grabbing\" target=\"_blank\">www.tni.org\/interview\/green-grabbing<\/a><\/p>\n<h3>Im\u00e1genes Relacionadas:<\/h3>","protected":false},"excerpt":{"rendered":"<p>\u00bfAutorregulaci\u00f3n de los mercados? Esa cantinela falaz del neoliberalismo econ\u00f3mico que nos vende gato por liebre. Ya sufrimos las consecuencias a escala mundial, con un empobrecimiento de la poblaci\u00f3n en general, pero que oprime sobremanera a\u00a0 los m\u00e1s desfavorecidos. La privatizaci\u00f3n \u00a0de las tierras a escala global, se realiza de diversas formas. Por un lado los gobiernos y multinacionales de las grandes potencias adquieren enormes extensiones de los que menos tienen atentando contra la seguridad alimentaria de los pa\u00edses pobres. Se trata de un aprovisionamiento de riquezas de otros Estados con vistas a mantener y\/o hacer crecer las suyas propias.\u2026<\/p>\n","protected":false},"author":26,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0},"categories":[591,599,605,615,606],"tags":[47339,47340,9962,47308],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":4}},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"\u00bfAutorregulaci\u00f3n de los mercados? Esa cantinela falaz del neoliberalismo econ\u00f3mico que nos vende gato por liebre. Ya sufrimos las consecuencias a escala mundial, con un empobrecimiento de la poblaci\u00f3n en general, pero que oprime sobremanera a los m\u00e1s desfavorecidos. La privatizaci\u00f3n de las tierras a escala global, se realiza de diversas formas. Por un lado\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Juan Jos\u00e9 Ib\u00e1\u00f1ez\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/03\/22\/142854\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Un Universo invisible bajo nuestros pies - Los suelos y la vida\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Sector Medioambiental y Econom\u00eda de Mercado: \u201cUn Robo denominado Acaparamiento de Tierras\u201d - Un Universo invisible bajo nuestros pies\" \/>\n\t\t<meta property=\"og:description\" content=\"\u00bfAutorregulaci\u00f3n de los mercados? Esa cantinela falaz del neoliberalismo econ\u00f3mico que nos vende gato por liebre. Ya sufrimos las consecuencias a escala mundial, con un empobrecimiento de la poblaci\u00f3n en general, pero que oprime sobremanera a los m\u00e1s desfavorecidos. La privatizaci\u00f3n de las tierras a escala global, se realiza de diversas formas. Por un lado\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/03\/22\/142854\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2013-03-22T15:21:35+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2013-03-22T15:21:49+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/juan.j.marti.14\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Sector Medioambiental y Econom\u00eda de Mercado: \u201cUn Robo denominado Acaparamiento de Tierras\u201d - Un Universo invisible bajo nuestros pies\" \/>\n\t\t<meta name=\"twitter:description\" content=\"\u00bfAutorregulaci\u00f3n de los mercados? Esa cantinela falaz del neoliberalismo econ\u00f3mico que nos vende gato por liebre. Ya sufrimos las consecuencias a escala mundial, con un empobrecimiento de la poblaci\u00f3n en general, pero que oprime sobremanera a los m\u00e1s desfavorecidos. La privatizaci\u00f3n de las tierras a escala global, se realiza de diversas formas. Por un lado\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2013\\\/03\\\/22\\\/142854#blogposting\",\"name\":\"Sector Medioambiental y Econom\\u00eda de Mercado: \\u201cUn Robo denominado Acaparamiento de Tierras\\u201d - Un Universo invisible bajo nuestros pies\",\"headline\":\"Sector Medioambiental y Econom\\u00eda de Mercado: \\u201cUn Robo denominado Acaparamiento de Tierras\\u201d\",\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"http:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/wp-content\\\/blogs.dir\\\/42\\\/files\\\/1123\\\/aprovisionamiento-de-tierras-ncr-punto-nl.jpg\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2013\\\/03\\\/22\\\/142854\\\/#articleImage\"},\"datePublished\":\"2013-03-22T16:21:35+01:00\",\"dateModified\":\"2013-03-22T16:21:49+01:00\",\"inLanguage\":\"es-ES\",\"commentCount\":2,\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2013\\\/03\\\/22\\\/142854#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2013\\\/03\\\/22\\\/142854#webpage\"},\"articleSection\":\"Edafolog\\u00eda y Pol\\u00edtica, Etnoedafolog\\u00eda y Conocimiento Campesino, Fraude y Mala Praxis Cient\\u00edfica, Notas Breves de Prensa, Prensa y Pol\\u00edtica Cient\\u00edfica, Aprovisonamiento de tierras, fraude neoliberal, Mala praxis, soberan\\u00eda alimentaria\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2013\\\/03\\\/22\\\/142854#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/edafologia-y-politica#listItem\",\"name\":\"Edafolog\\u00eda y Pol\\u00edtica\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/edafologia-y-politica#listItem\",\"position\":2,\"name\":\"Edafolog\\u00eda y Pol\\u00edtica\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/edafologia-y-politica\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2013\\\/03\\\/22\\\/142854#listItem\",\"name\":\"Sector Medioambiental y Econom\\u00eda de Mercado: \\u201cUn Robo denominado Acaparamiento de Tierras\\u201d\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2013\\\/03\\\/22\\\/142854#listItem\",\"position\":3,\"name\":\"Sector Medioambiental y Econom\\u00eda de Mercado: \\u201cUn Robo denominado Acaparamiento de Tierras\\u201d\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/edafologia-y-politica#listItem\",\"name\":\"Edafolog\\u00eda y Pol\\u00edtica\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#organization\",\"name\":\"Un Universo invisible bajo nuestros pies\",\"description\":\"Los suelos y la vida\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/files\\\/2022\\\/02\\\/logo.png\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2013\\\/03\\\/22\\\/142854\\\/#organizationLogo\",\"width\":217,\"height\":72},\"image\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2013\\\/03\\\/22\\\/142854\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/juan.j.marti.14\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo\",\"name\":\"Juan Jos\\u00e9 Ib\\u00e1\\u00f1ez\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2013\\\/03\\\/22\\\/142854#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/387f3a100385573d8f42ce2a3211fd1c?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Juan Jos\\u00e9 Ib\\u00e1\\u00f1ez\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2013\\\/03\\\/22\\\/142854#webpage\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2013\\\/03\\\/22\\\/142854\",\"name\":\"Sector Medioambiental y Econom\\u00eda de Mercado: \\u201cUn Robo denominado Acaparamiento de Tierras\\u201d - Un Universo invisible bajo nuestros pies\",\"description\":\"\\u00bfAutorregulaci\\u00f3n de los mercados? Esa cantinela falaz del neoliberalismo econ\\u00f3mico que nos vende gato por liebre. Ya sufrimos las consecuencias a escala mundial, con un empobrecimiento de la poblaci\\u00f3n en general, pero que oprime sobremanera a los m\\u00e1s desfavorecidos. La privatizaci\\u00f3n de las tierras a escala global, se realiza de diversas formas. Por un lado\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2013\\\/03\\\/22\\\/142854#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\"},\"datePublished\":\"2013-03-22T16:21:35+01:00\",\"dateModified\":\"2013-03-22T16:21:49+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#website\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/\",\"name\":\"Un Universo invisible bajo nuestros pies\",\"description\":\"Los suelos y la vida\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Sector Medioambiental y Econom\u00eda de Mercado: \u201cUn Robo denominado Acaparamiento de Tierras\u201d - Un Universo invisible bajo nuestros pies","description":"\u00bfAutorregulaci\u00f3n de los mercados? Esa cantinela falaz del neoliberalismo econ\u00f3mico que nos vende gato por liebre. Ya sufrimos las consecuencias a escala mundial, con un empobrecimiento de la poblaci\u00f3n en general, pero que oprime sobremanera a los m\u00e1s desfavorecidos. La privatizaci\u00f3n de las tierras a escala global, se realiza de diversas formas. Por un lado","canonical_url":"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/03\/22\/142854","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/03\/22\/142854#blogposting","name":"Sector Medioambiental y Econom\u00eda de Mercado: \u201cUn Robo denominado Acaparamiento de Tierras\u201d - Un Universo invisible bajo nuestros pies","headline":"Sector Medioambiental y Econom\u00eda de Mercado: \u201cUn Robo denominado Acaparamiento de Tierras\u201d","author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author"},"publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#organization"},"image":{"@type":"ImageObject","url":"http:\/\/www.madrimasd.org\/blogs\/universo\/wp-content\/blogs.dir\/42\/files\/1123\/aprovisionamiento-de-tierras-ncr-punto-nl.jpg","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/03\/22\/142854\/#articleImage"},"datePublished":"2013-03-22T16:21:35+01:00","dateModified":"2013-03-22T16:21:49+01:00","inLanguage":"es-ES","commentCount":2,"mainEntityOfPage":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/03\/22\/142854#webpage"},"isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/03\/22\/142854#webpage"},"articleSection":"Edafolog\u00eda y Pol\u00edtica, Etnoedafolog\u00eda y Conocimiento Campesino, Fraude y Mala Praxis Cient\u00edfica, Notas Breves de Prensa, Prensa y Pol\u00edtica Cient\u00edfica, Aprovisonamiento de tierras, fraude neoliberal, Mala praxis, soberan\u00eda alimentaria"},{"@type":"BreadcrumbList","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/03\/22\/142854#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo#listItem","position":1,"name":"Home","item":"https:\/\/www.madrimasd.org\/blogs\/universo","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/edafologia-y-politica#listItem","name":"Edafolog\u00eda y Pol\u00edtica"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/edafologia-y-politica#listItem","position":2,"name":"Edafolog\u00eda y Pol\u00edtica","item":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/edafologia-y-politica","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/03\/22\/142854#listItem","name":"Sector Medioambiental y Econom\u00eda de Mercado: \u201cUn Robo denominado Acaparamiento de Tierras\u201d"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/03\/22\/142854#listItem","position":3,"name":"Sector Medioambiental y Econom\u00eda de Mercado: \u201cUn Robo denominado Acaparamiento de Tierras\u201d","previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/edafologia-y-politica#listItem","name":"Edafolog\u00eda y Pol\u00edtica"}}]},{"@type":"Organization","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#organization","name":"Un Universo invisible bajo nuestros pies","description":"Los suelos y la vida","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/","logo":{"@type":"ImageObject","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/03\/22\/142854\/#organizationLogo","width":217,"height":72},"image":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/03\/22\/142854\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/juan.j.marti.14"]},{"@type":"Person","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo","name":"Juan Jos\u00e9 Ib\u00e1\u00f1ez","image":{"@type":"ImageObject","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/03\/22\/142854#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/387f3a100385573d8f42ce2a3211fd1c?s=96&d=mm&r=g","width":96,"height":96,"caption":"Juan Jos\u00e9 Ib\u00e1\u00f1ez"}},{"@type":"WebPage","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/03\/22\/142854#webpage","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/03\/22\/142854","name":"Sector Medioambiental y Econom\u00eda de Mercado: \u201cUn Robo denominado Acaparamiento de Tierras\u201d - Un Universo invisible bajo nuestros pies","description":"\u00bfAutorregulaci\u00f3n de los mercados? Esa cantinela falaz del neoliberalismo econ\u00f3mico que nos vende gato por liebre. Ya sufrimos las consecuencias a escala mundial, con un empobrecimiento de la poblaci\u00f3n en general, pero que oprime sobremanera a los m\u00e1s desfavorecidos. La privatizaci\u00f3n de las tierras a escala global, se realiza de diversas formas. Por un lado","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#website"},"breadcrumb":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/03\/22\/142854#breadcrumblist"},"author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author"},"creator":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author"},"datePublished":"2013-03-22T16:21:35+01:00","dateModified":"2013-03-22T16:21:49+01:00"},{"@type":"WebSite","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#website","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/","name":"Un Universo invisible bajo nuestros pies","description":"Los suelos y la vida","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Un Universo invisible bajo nuestros pies - Los suelos y la vida","og:type":"article","og:title":"Sector Medioambiental y Econom\u00eda de Mercado: \u201cUn Robo denominado Acaparamiento de Tierras\u201d - Un Universo invisible bajo nuestros pies","og:description":"\u00bfAutorregulaci\u00f3n de los mercados? Esa cantinela falaz del neoliberalismo econ\u00f3mico que nos vende gato por liebre. Ya sufrimos las consecuencias a escala mundial, con un empobrecimiento de la poblaci\u00f3n en general, pero que oprime sobremanera a los m\u00e1s desfavorecidos. La privatizaci\u00f3n de las tierras a escala global, se realiza de diversas formas. Por un lado","og:url":"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/03\/22\/142854","og:image":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png","og:image:secure_url":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png","article:published_time":"2013-03-22T15:21:35+00:00","article:modified_time":"2013-03-22T15:21:49+00:00","article:publisher":"https:\/\/www.facebook.com\/juan.j.marti.14","twitter:card":"summary","twitter:title":"Sector Medioambiental y Econom\u00eda de Mercado: \u201cUn Robo denominado Acaparamiento de Tierras\u201d - Un Universo invisible bajo nuestros pies","twitter:description":"\u00bfAutorregulaci\u00f3n de los mercados? Esa cantinela falaz del neoliberalismo econ\u00f3mico que nos vende gato por liebre. Ya sufrimos las consecuencias a escala mundial, con un empobrecimiento de la poblaci\u00f3n en general, pero que oprime sobremanera a los m\u00e1s desfavorecidos. La privatizaci\u00f3n de las tierras a escala global, se realiza de diversas formas. Por un lado","twitter:image":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png"},"aioseo_meta_data":{"post_id":"142854","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":null,"isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","tabs":null,"priority":null,"frequency":null,"local_seo":null,"created":"2022-06-03 16:37:39","updated":"2026-05-26 17:38:00","limit_modified_date":false,"ai":null,"breadcrumb_settings":null,"seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/edafologia-y-politica\" title=\"Edafolog\u00eda y Pol\u00edtica\">Edafolog\u00eda y Pol\u00edtica<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tSector Medioambiental y Econom\u00eda de Mercado: \u201cUn Robo denominado Acaparamiento de Tierras\u201d\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.madrimasd.org\/blogs\/universo"},{"label":"Edafolog\u00eda y Pol\u00edtica","link":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/edafologia-y-politica"},{"label":"Sector Medioambiental y Econom\u00eda de Mercado: \u201cUn Robo denominado Acaparamiento de Tierras\u201d","link":"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/03\/22\/142854"}],"_links":{"self":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts\/142854"}],"collection":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/comments?post=142854"}],"version-history":[{"count":8,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts\/142854\/revisions"}],"predecessor-version":[{"id":144031,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts\/142854\/revisions\/144031"}],"wp:attachment":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/media?parent=142854"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/categories?post=142854"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/tags?post=142854"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}