{"id":144452,"date":"2013-09-05T19:04:04","date_gmt":"2013-09-05T18:04:04","guid":{"rendered":"http:\/\/www.madrimasd.org\/blogs\/universo\/?p=144452"},"modified":"2013-09-05T19:04:04","modified_gmt":"2013-09-05T18:04:04","slug":"diversidad-de-suelos-y-diversidad-de-las-especies","status":"publish","type":"post","link":"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/09\/05\/144452","title":{"rendered":"Diversidad de Suelos y Diversidad de las Especies"},"content":{"rendered":"<p style=\"text-align: justify;\">Soy de esos investigadores a los que no les gusta enviar sus <em>papers <\/em>a los gabinetes de prensa con bombo y plantillo intentando a toda costa que le den publicidad para que aparezca en la prensa de car\u00e1cter general. Siento un poco de verg\u00fcenza ajena ante este tipo de actitudes, por mucho que est\u00e9n de moda. Hace unas semanas, en la p\u00e1gina Web de la \u201c<a href=\"https:\/\/www.soils.org\/\">Soil Science Society of America (SSSA)\u201d<\/a> apareci\u00f3 en portada la rese\u00f1a de un art\u00edculo de mi propia cosecha aparecida en una revista de esta sociedad. Fue la que recibi\u00f3 m\u00e1s comentarios positivos, por lo que la editorial me escribi\u00f3 un mail felicit\u00e1ndome. Hasta aqu\u00ed la historia que se suele contar, ocultando los verdaderos entresijos que subyacen bajo estas pomposas propagandas. Finalmente ser\u00e1n, con el tiempo, los propios colegas, con sus citaciones o desd\u00e9n, los que emitan un verdadero veredicto. Os contar\u00e9 en otro post la historia de este y otro <em>paper<\/em> con vistas a que \u00a0valor\u00e9is la tan <span style=\"color: #3366ff;\"><strong>cacareada objetividad de la revisi\u00f3n por pares<\/strong><\/span>. \u00a1No os lo perd\u00e1is!. Vivimos en un mundo repleto de parafernalias en donde el contenido es fagocitado por \u00e9l continente, hecho que detesto. Sin embargo, hace unas horas pens\u00e9 que si hubiera procedido de otro autor, la habr\u00eda comentado, por lo que finalmente he decidido escribir un post de la misma. La rese\u00f1a o nota de prensa de la SSSA os la proporciono abajo.<\/p>\n<p style=\"text-align: center;\"><img decoding=\"async\" class=\"ngg-singlepic ngg-center\" src=\"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-content\/blogs.dir\/42\/files\/1123\/mapa-de-suelos-del-mundo-mi-post-de-vzj.jpg\" alt=\"mapa-de-suelos-del-mundo-mi-post-de-vzj\" width=\"410\" height=\"253\" \/><\/p>\n<p align=\"center\"><span style=\"color: #0000ff;\">Mapa de los suelos del Mundo que apareci\u00f3 en la noticia de la SSSA acompa\u00f1ando, en su d\u00eda, a la nota de prensa<\/span><\/p>\n<p style=\"text-align: justify;\">Investigadores espa\u00f1oles (l\u00e9ase este impresentable administrador de esta bit\u00e1cora) e Italianos (Enrico Feoli, s\u00ed es realmente un gran cient\u00edfico) han publicado un estudio en el que dicen demostrar que <span style=\"color: #3366ff;\"><strong>la diversidad de especies biol\u00f3gicas a escala mundial se encuentra principalmente determinada por la diversidad de los suelos a escala global<\/strong><\/span>. Estos cient\u00edficos llevaron a cabo un an\u00e1lisis del n\u00famero de especies de plantas vasculares, anfibios, reptiles, aves y mam\u00edferos de todos los pa\u00edses del mundo, cotej\u00e1ndolos con el \u00e1rea y n\u00famero de tipos de suelos (edafotaxa) de los mismos, detectando resultados sorprendentes \u00bf\u00bf??. Hasta el momento, en esta clase de estudios, la comunidad cient\u00edfica hab\u00eda detectado <span style=\"color: #3366ff;\"><strong>una clara correlaci\u00f3n entre el \u00e1rea y la diversidad de especies. Sin embargo<\/strong><\/span>, en el art\u00edculo de marras, los autores <span style=\"color: #3366ff;\"><strong>a\u00f1adieron tambi\u00e9n los suelos<\/strong><\/span>.<\/p>\n<p align=\"center\"><span style=\"color: #0000ff;\"><img decoding=\"async\" class=\"ngg-singlepic ngg-center\" src=\"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-content\/blogs.dir\/42\/files\/1123\/sssa-pedodiv-feoli-e-ibanez-2013.jpg\" alt=\"sssa-pedodiv-feoli-e-ibanez-2013\" width=\"393\" height=\"285\" \/><\/span><\/p>\n<p align=\"center\"><span style=\"color: #0000ff;\">Imagen (pantallazo) de la p\u00e1gina Web de la SSSA en donde apareci\u00f3 la noticia<\/span><\/p>\n<p style=\"text-align: justify;\">Los resultados obtenidos por estos investigadores constaron, en primera instancia, que <span style=\"color: #3366ff;\"><strong>todas las variables se encontraban correlacionadas positivamente con un alto nivel de significaci\u00f3n estad\u00edstica<\/strong>. <strong>De aqu\u00ed, pod\u00eda haberse inferido que el \u00e1rea tambi\u00e9n era la principal fuerza determinante de la diversidad los pa\u00edses, ya fuera de especies o edafotaxa. En otras a mayor extensi\u00f3n de un Estado, mayor riqueza de especies. M\u00e1s a\u00fan<\/strong><\/span>, en todos los casos, los ajustes obtenidos para cada una de estas variables, incrementaban con el \u00e1rea conforme a <span style=\"color: #3366ff;\"><strong>una ley de escala o distribuci\u00f3n potencial<\/strong><\/span>, siendo por tanto huella de una presunta <span style=\"color: #3366ff;\"><strong>estructura fractal<\/strong><\/span>. Tal patr\u00f3n ya ha sido corroborado en multitud de ocasiones. <span style=\"color: #3366ff;\"><strong>Sin embargo, la correlaci\u00f3n de las especies de todos los grupos taxon\u00f3micos se correlacionaban m\u00e1s con los suelos que con el \u00e1rea, lo que sugiere que posiblemente la extensi\u00f3n superficial sea una mera variable subrogada de la heterogeneidad ambiental<\/strong> <\/span>de un territorio. En otras palabras <span style=\"color: #3366ff;\"><strong>a mayor \u00e1rea, mayor heterogeneidad ambiental<\/strong>,<\/span> siendo esta \u00faltima la que inducir\u00e1 a que se generen m\u00e1s nichos ecol\u00f3gicos, <span style=\"color: #3366ff;\"><strong>mayor n\u00famero de especies y clases de suelos<\/strong><\/span>. En consecuencia los autores infieren que, <span style=\"color: #3366ff;\"><strong>la diversidad de suelos, obtenidos por inventarios georeferenciados y mapas, debiera ser un mejor predictor del n\u00famero de especies biol\u00f3gicas que el \u00e1rea<\/strong><\/span>, siendo esta \u00faltima la que m\u00e1s utilizada por muchos expertos en biodiversidad al contrario que los edafotaxa. No obstante (&#8230;)<\/p>\n<p style=\"text-align: justify;\"><!--more--><\/p>\n<p style=\"text-align: justify;\">No obstante, <span style=\"color: #3366ff;\"><strong>los autores fueron m\u00e1s all\u00e1 se\u00f1alando que<\/strong> <\/span>hasta la fecha los expertos en biodiversidad suelen justificar estas leyes potenciales o de escala entre el \u00e1rea y el n\u00famero de especies apelando a asunciones de tipo biol\u00f3gico (migraciones, extinciones, etc.). En vista que los edafotaxa ni emigran, ni se extinguen, en el estricto sentido biol\u00f3gico, estos investigadores <span style=\"color: #3366ff;\"><strong>concluyen que debe ponerse en duda la racionalidad impl\u00edcita en la famosa teor\u00eda<\/strong><\/span> de la <a href=\"http:\/\/es.wikipedia.org\/wiki\/Biogeograf\u00eda_de_islas\">biogeograf\u00eda insular<\/a>, <span style=\"color: #3366ff;\"><strong>n\u00facleo de buena parte de las bases te\u00f3ricas sobre las que se sustentan los estudios en biolog\u00eda de la conservaci\u00f3n<\/strong><\/span>.<\/p>\n<p style=\"text-align: justify;\">PD. Cuando se elabor\u00f3 este art\u00edculo ya atesor\u00e1bamos otros datos que avalaban estas conclusiones y ofrec\u00edan un an\u00e1lisis m\u00e1s detallado del problema abordado. Usando <span style=\"color: #3366ff;\"><strong>correlaciones parciales<\/strong> <\/span>se detect\u00f3, que <span style=\"color: #3366ff;\"><strong>la variable espuria resultaba ser justamente el \u00e1rea, que no los suelos<\/strong><\/span>. Del mismo modo, <span style=\"color: #3366ff;\"><strong>la diversidad de los suelos se correlacionaba mejor con las plantas vasculares que<\/strong><\/span> con los taxa animales, como cabr\u00eda esperar: <span style=\"color: #3366ff;\"><strong>a mayor edafodiversidad (pedodiversity) mayor n\u00famero de nichos de plantas vasculares, y cuanto mayor sea el n\u00famero de estas \u00faltimas tanto m\u00e1s elevado la variedad de animales que las consumen<\/strong><\/span>, directa (herb\u00edvoros) o indirectamente (carn\u00edvoros). Estos \u00faltimos an\u00e1lisis se encuentran ya remitidos a otra revista con vistas a su publicaci\u00f3n. <span style=\"color: #3366ff;\"><strong>\u00bfPor qu\u00e9 no los incluimos en el presente paper?<\/strong>.<\/span> No se trataba de sacar la m\u00e1quina de producir <a href=\"http:\/\/www.infodoctor.org\/rafabravo\/fraude.htm\">publicaciones salami<\/a>, sino que a mayor cantidad de datos y narraciones de naturaleza biol\u00f3gica, tanto peor encajar\u00eda el <em>paper<\/em> en una revista de \u201csuelos\u201d, que no de ecolog\u00eda. Sin embargo reitero que ya hablaremos de la esperp\u00e9ntica historia que se encuentra detr\u00e1s de tal publicaci\u00f3n, por lo dem\u00e1s muy sencilla. Resumiendo, una publicaci\u00f3n m\u00e1s.<\/p>\n<p><strong><span style=\"color: #008000;\">Juan Jos\u00e9 Ib\u00e1\u00f1ez \u00a0\u00a0\u00a0\u00a0<\/span>\u00a0\u00a0\u00a0\u00a0\u00a0<\/strong><\/p>\n<h3><strong>\u00a0<\/strong><span style=\"color: #800000;\"><strong>Diversity of soil types can be an indicator of aboveground biodiversity<\/strong><\/span><\/h3>\n<p>Submitted by Schneider Carol&#8230; on Mon, 06\/24\/2013 &#8211; 14:42<\/p>\n<p style=\"text-align: justify;\"><strong>June 24, 2013 &#8212; <\/strong>Threats to vulnerable and endangered species are well recognized. As humans continue to move into ecosystems that are home to a variety of plants and animals, scientists and conservationists look for ways to better understand and measure biodiversity and the impacts people have upon it. It turns out that information about aboveground diversity may come from an unexpected place \u2013 the ground underneath the plants and animals.<\/p>\n<p><em>Digital soil map of the world. Photo courtesy of Food and Agriculture Organization of the United Nations.<\/em><\/p>\n<p style=\"text-align: justify;\">A new study, published in <em>Vadose Zone Journal<\/em>, found that the number of soil types in an area (called the \u201cpedodiversity\u201d) and the biodiversity of that area \u2013 the number of species of vascular plants, amphibians, reptiles, birds, and mammals \u2013 are strongly correlated on a global scale. Additionally, the findings show that pedodiversity could be used as an indicator of biodiversity, which can often be difficult to measure.<\/p>\n<p style=\"text-align: justify;\">In considering the link between the two diversities, the authors, Juan Jos\u00e9 Ib\u00e1\u00f1ez and Enrico Feoli, note that pedodiversity can be seen as a measure of environmental heterogeneity. Therefore, their study suggests that the biodiversity of an area depends on the extent of that area as well as its environmental heterogeneity and the variety of habitats available for plants and animals.<\/p>\n<p style=\"text-align: justify;\">The authors hope that the study will raise interest in the relationship between pedodiversity and biodiversity and motivate other researchers to analyze the connection. They also propose a possible improvement in future studies. While the current classification from the Food and Agricultural Organization considers only the first one or two meters of soil, Ib\u00e1\u00f1ez and Feoli suggest that a system taking into account deeper layers may provide a more robust indicator of biodiversity around the world.<\/p>\n<p style=\"text-align: justify;\">View the abstract at: <a href=\"http:\/\/dx.doi.org\/doi:10.2136\/vzj2012.0186\">http:\/\/dx.doi.org\/doi:10.2136\/vzj2012.0186<\/a><\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.soils.org\/story\/2013\/jun\/mon\/diversity-of-soil-types-can-be-an-indicator-of-aboveground-biodiversity\">https:\/\/www.soils.org\/story\/2013\/jun\/mon\/diversity-of-soil-types-can-be-an-indicator-of-aboveground-biodiversity<\/a><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #800000;\"><strong>Abstract del art\u00edculo Original<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.soils.org\/publications\/vzj\/abstracts\/12\/3\/vzj2012.0186\">Global Relationships of Pedodiversity and Biodiversity<\/a><\/p>\n<ol>\n<li><strong>1.\u00a0\u00a0\u00a0\u00a0 <\/strong><strong>Juan Jos\u00e9\u00a0Ib\u00e1\u00f1ez\u00a0<\/strong><strong><sup>*<\/sup><\/strong><strong> and <\/strong><\/li>\n<li><strong>2.\u00a0\u00a0\u00a0\u00a0 <\/strong><strong>Enrico\u00a0Feoli<\/strong><\/li>\n<\/ol>\n<p>Author Affiliations<\/p>\n<ol>\n<li>a Centro de Investigaciones sobre Desertificaci\u00f3n, CIDE (CSIC-UV), Km 4.5 Apdo. Oficial 46113, Valencia, Spain<\/li>\n<li>b Dep. of Life Sciences, Univ. of Trieste, Via E. Weiss 2, 34127, Trieste, Italy<\/li>\n<\/ol>\n<p><strong>Abstract<\/strong><\/p>\n<p style=\"text-align: justify;\">Biodiversity and pedodiversity conform to the power law at planetary level. The two types of diversity are strongly correlated. When a country has high pedodiversity it has also high biodiversity. A novel \u201csoil\u2013regolith taxonomy\u201d should improve the analysis of pedodiversity\u2013biodiversity relations.<\/p>\n<p style=\"text-align: justify;\">Current studies indicate that biodiversity and pedodiversity may have similar patterns, for example diversity\u2013area relationships. This study examines pedodiversity and biodiversity\u2013area relationships on a global scale using countries as spatial units. The Food and Agricultural Organization (FAO) soil database and International Union for the Conservation of Nature\u2013World Commission on Protected Areas (IUCN\u2013WCMC) biological datasets have been used in this analysis. The results show that biodiversity of biological target groups (the number of species of vascular plants, amphibians, reptiles, birds, mammals, and the total number of species of vertebrates) and pedodiversity (the number of pedotaxa or soil types at the second level of FAO classification) conform to the power law. The two types of diversity are strongly correlated at the global level. When a country has high pedodiversity it has also high biodiversity, and since pedodiversity may be interpreted as an expression of environmental heterogeneity in terms of geological parent material, geomorphology, and climate of a given area, this result suggests that the biodiversity of a country depends both on the extent of its area and on its environmental heterogeneity. We are conscious of the limitations of the results due to the inherent imprecision of the data set used for this study; however, we think that this analysis could motivate interest in continuing to study the pedodiversity\u2013biodiversity relationships with a new pedotaxonomy that would take into consideration the deep regolith layers.<\/p>\n<p>&nbsp;<\/p>\n<h3>Im\u00e1genes Relacionadas:<\/h3>","protected":false},"excerpt":{"rendered":"<p>Soy de esos investigadores a los que no les gusta enviar sus papers a los gabinetes de prensa con bombo y plantillo intentando a toda costa que le den publicidad para que aparezca en la prensa de car\u00e1cter general. Siento un poco de verg\u00fcenza ajena ante este tipo de actitudes, por mucho que est\u00e9n de moda. Hace unas semanas, en la p\u00e1gina Web de la \u201cSoil Science Society of America (SSSA)\u201d apareci\u00f3 en portada la rese\u00f1a de un art\u00edculo de mi propia cosecha aparecida en una revista de esta sociedad. Fue la que recibi\u00f3 m\u00e1s comentarios positivos, por lo que\u2026<\/p>\n","protected":false},"author":26,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0},"categories":[596,614,603,586,618,600],"tags":[46736,20692,46725,15244,20693,47010],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":4}},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Soy de esos investigadores a los que no les gusta enviar sus papers a los gabinetes de prensa con bombo y plantillo intentando a toda costa que le den publicidad para que aparezca en la prensa de car\u00e1cter general. Siento un poco de verg\u00fcenza ajena ante este tipo de actitudes, por mucho que est\u00e9n de\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Juan Jos\u00e9 Ib\u00e1\u00f1ez\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/09\/05\/144452\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Un Universo invisible bajo nuestros pies - Los suelos y la vida\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Diversidad de Suelos y Diversidad de las Especies - Un Universo invisible bajo nuestros pies\" \/>\n\t\t<meta property=\"og:description\" content=\"Soy de esos investigadores a los que no les gusta enviar sus papers a los gabinetes de prensa con bombo y plantillo intentando a toda costa que le den publicidad para que aparezca en la prensa de car\u00e1cter general. Siento un poco de verg\u00fcenza ajena ante este tipo de actitudes, por mucho que est\u00e9n de\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/09\/05\/144452\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2013-09-05T18:04:04+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2013-09-05T18:04:04+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/juan.j.marti.14\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Diversidad de Suelos y Diversidad de las Especies - Un Universo invisible bajo nuestros pies\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Soy de esos investigadores a los que no les gusta enviar sus papers a los gabinetes de prensa con bombo y plantillo intentando a toda costa que le den publicidad para que aparezca en la prensa de car\u00e1cter general. Siento un poco de verg\u00fcenza ajena ante este tipo de actitudes, por mucho que est\u00e9n de\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2013\\\/09\\\/05\\\/144452#blogposting\",\"name\":\"Diversidad de Suelos y Diversidad de las Especies - Un Universo invisible bajo nuestros pies\",\"headline\":\"Diversidad de Suelos y Diversidad de las Especies\",\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"http:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/wp-content\\\/blogs.dir\\\/42\\\/files\\\/1123\\\/mapa-de-suelos-del-mundo-mi-post-de-vzj.jpg\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2013\\\/09\\\/05\\\/144452\\\/#articleImage\"},\"datePublished\":\"2013-09-05T19:04:04+01:00\",\"dateModified\":\"2013-09-05T19:04:04+01:00\",\"inLanguage\":\"es-ES\",\"commentCount\":5,\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2013\\\/09\\\/05\\\/144452#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2013\\\/09\\\/05\\\/144452#webpage\"},\"articleSection\":\"Biolog\\u00eda y Ecolog\\u00eda del Suelo, Biomas del Mundo y la Biodiversidad de Los Pa\\u00edses, Carpeta sobre Paisajes de Suelos y los Suelos en el Paisaje, Diversidad, Complejidad y Fractales, Ecolog\\u00eda y Biogeograf\\u00eda post posteriores a agosto de 2009, Los Suelos las Plantas y la Vegetaci\\u00f3n, Biodiversidad, Biodiversity, edafodiversidad, Escala Global, Global scale, pedodiversity\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2013\\\/09\\\/05\\\/144452#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/diversidad-complejidad-y-fractales#listItem\",\"name\":\"Diversidad, Complejidad y Fractales\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/diversidad-complejidad-y-fractales#listItem\",\"position\":2,\"name\":\"Diversidad, Complejidad y Fractales\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/diversidad-complejidad-y-fractales\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2013\\\/09\\\/05\\\/144452#listItem\",\"name\":\"Diversidad de Suelos y Diversidad de las Especies\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2013\\\/09\\\/05\\\/144452#listItem\",\"position\":3,\"name\":\"Diversidad de Suelos y Diversidad de las Especies\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/diversidad-complejidad-y-fractales#listItem\",\"name\":\"Diversidad, Complejidad y Fractales\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#organization\",\"name\":\"Un Universo invisible bajo nuestros pies\",\"description\":\"Los suelos y la vida\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/files\\\/2022\\\/02\\\/logo.png\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2013\\\/09\\\/05\\\/144452\\\/#organizationLogo\",\"width\":217,\"height\":72},\"image\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2013\\\/09\\\/05\\\/144452\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/juan.j.marti.14\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo\",\"name\":\"Juan Jos\\u00e9 Ib\\u00e1\\u00f1ez\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2013\\\/09\\\/05\\\/144452#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/387f3a100385573d8f42ce2a3211fd1c?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Juan Jos\\u00e9 Ib\\u00e1\\u00f1ez\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2013\\\/09\\\/05\\\/144452#webpage\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2013\\\/09\\\/05\\\/144452\",\"name\":\"Diversidad de Suelos y Diversidad de las Especies - Un Universo invisible bajo nuestros pies\",\"description\":\"Soy de esos investigadores a los que no les gusta enviar sus papers a los gabinetes de prensa con bombo y plantillo intentando a toda costa que le den publicidad para que aparezca en la prensa de car\\u00e1cter general. Siento un poco de verg\\u00fcenza ajena ante este tipo de actitudes, por mucho que est\\u00e9n de\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2013\\\/09\\\/05\\\/144452#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\"},\"datePublished\":\"2013-09-05T19:04:04+01:00\",\"dateModified\":\"2013-09-05T19:04:04+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#website\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/\",\"name\":\"Un Universo invisible bajo nuestros pies\",\"description\":\"Los suelos y la vida\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Diversidad de Suelos y Diversidad de las Especies - Un Universo invisible bajo nuestros pies","description":"Soy de esos investigadores a los que no les gusta enviar sus papers a los gabinetes de prensa con bombo y plantillo intentando a toda costa que le den publicidad para que aparezca en la prensa de car\u00e1cter general. Siento un poco de verg\u00fcenza ajena ante este tipo de actitudes, por mucho que est\u00e9n de","canonical_url":"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/09\/05\/144452","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/09\/05\/144452#blogposting","name":"Diversidad de Suelos y Diversidad de las Especies - Un Universo invisible bajo nuestros pies","headline":"Diversidad de Suelos y Diversidad de las Especies","author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author"},"publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#organization"},"image":{"@type":"ImageObject","url":"http:\/\/www.madrimasd.org\/blogs\/universo\/wp-content\/blogs.dir\/42\/files\/1123\/mapa-de-suelos-del-mundo-mi-post-de-vzj.jpg","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/09\/05\/144452\/#articleImage"},"datePublished":"2013-09-05T19:04:04+01:00","dateModified":"2013-09-05T19:04:04+01:00","inLanguage":"es-ES","commentCount":5,"mainEntityOfPage":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/09\/05\/144452#webpage"},"isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/09\/05\/144452#webpage"},"articleSection":"Biolog\u00eda y Ecolog\u00eda del Suelo, Biomas del Mundo y la Biodiversidad de Los Pa\u00edses, Carpeta sobre Paisajes de Suelos y los Suelos en el Paisaje, Diversidad, Complejidad y Fractales, Ecolog\u00eda y Biogeograf\u00eda post posteriores a agosto de 2009, Los Suelos las Plantas y la Vegetaci\u00f3n, Biodiversidad, Biodiversity, edafodiversidad, Escala Global, Global scale, pedodiversity"},{"@type":"BreadcrumbList","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/09\/05\/144452#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo#listItem","position":1,"name":"Home","item":"https:\/\/www.madrimasd.org\/blogs\/universo","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/diversidad-complejidad-y-fractales#listItem","name":"Diversidad, Complejidad y Fractales"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/diversidad-complejidad-y-fractales#listItem","position":2,"name":"Diversidad, Complejidad y Fractales","item":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/diversidad-complejidad-y-fractales","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/09\/05\/144452#listItem","name":"Diversidad de Suelos y Diversidad de las Especies"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/09\/05\/144452#listItem","position":3,"name":"Diversidad de Suelos y Diversidad de las Especies","previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/diversidad-complejidad-y-fractales#listItem","name":"Diversidad, Complejidad y Fractales"}}]},{"@type":"Organization","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#organization","name":"Un Universo invisible bajo nuestros pies","description":"Los suelos y la vida","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/","logo":{"@type":"ImageObject","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/09\/05\/144452\/#organizationLogo","width":217,"height":72},"image":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/09\/05\/144452\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/juan.j.marti.14"]},{"@type":"Person","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo","name":"Juan Jos\u00e9 Ib\u00e1\u00f1ez","image":{"@type":"ImageObject","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/09\/05\/144452#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/387f3a100385573d8f42ce2a3211fd1c?s=96&d=mm&r=g","width":96,"height":96,"caption":"Juan Jos\u00e9 Ib\u00e1\u00f1ez"}},{"@type":"WebPage","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/09\/05\/144452#webpage","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/09\/05\/144452","name":"Diversidad de Suelos y Diversidad de las Especies - Un Universo invisible bajo nuestros pies","description":"Soy de esos investigadores a los que no les gusta enviar sus papers a los gabinetes de prensa con bombo y plantillo intentando a toda costa que le den publicidad para que aparezca en la prensa de car\u00e1cter general. Siento un poco de verg\u00fcenza ajena ante este tipo de actitudes, por mucho que est\u00e9n de","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#website"},"breadcrumb":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/09\/05\/144452#breadcrumblist"},"author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author"},"creator":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author"},"datePublished":"2013-09-05T19:04:04+01:00","dateModified":"2013-09-05T19:04:04+01:00"},{"@type":"WebSite","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#website","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/","name":"Un Universo invisible bajo nuestros pies","description":"Los suelos y la vida","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Un Universo invisible bajo nuestros pies - Los suelos y la vida","og:type":"article","og:title":"Diversidad de Suelos y Diversidad de las Especies - Un Universo invisible bajo nuestros pies","og:description":"Soy de esos investigadores a los que no les gusta enviar sus papers a los gabinetes de prensa con bombo y plantillo intentando a toda costa que le den publicidad para que aparezca en la prensa de car\u00e1cter general. Siento un poco de verg\u00fcenza ajena ante este tipo de actitudes, por mucho que est\u00e9n de","og:url":"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/09\/05\/144452","og:image":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png","og:image:secure_url":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png","article:published_time":"2013-09-05T18:04:04+00:00","article:modified_time":"2013-09-05T18:04:04+00:00","article:publisher":"https:\/\/www.facebook.com\/juan.j.marti.14","twitter:card":"summary","twitter:title":"Diversidad de Suelos y Diversidad de las Especies - Un Universo invisible bajo nuestros pies","twitter:description":"Soy de esos investigadores a los que no les gusta enviar sus papers a los gabinetes de prensa con bombo y plantillo intentando a toda costa que le den publicidad para que aparezca en la prensa de car\u00e1cter general. Siento un poco de verg\u00fcenza ajena ante este tipo de actitudes, por mucho que est\u00e9n de","twitter:image":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png"},"aioseo_meta_data":{"post_id":"144452","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":null,"isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","tabs":null,"priority":null,"frequency":null,"local_seo":null,"created":"2022-06-03 16:43:36","updated":"2026-05-26 17:47:00","limit_modified_date":false,"ai":null,"breadcrumb_settings":null,"seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/diversidad-complejidad-y-fractales\" title=\"Diversidad, Complejidad y Fractales\">Diversidad, Complejidad y Fractales<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tDiversidad de Suelos y Diversidad de las Especies\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.madrimasd.org\/blogs\/universo"},{"label":"Diversidad, Complejidad y Fractales","link":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/diversidad-complejidad-y-fractales"},{"label":"Diversidad de Suelos y Diversidad de las Especies","link":"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/09\/05\/144452"}],"_links":{"self":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts\/144452"}],"collection":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/comments?post=144452"}],"version-history":[{"count":8,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts\/144452\/revisions"}],"predecessor-version":[{"id":144465,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts\/144452\/revisions\/144465"}],"wp:attachment":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/media?parent=144452"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/categories?post=144452"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/tags?post=144452"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}