{"id":144679,"date":"2013-11-14T14:15:42","date_gmt":"2013-11-14T13:15:42","guid":{"rendered":"http:\/\/www.madrimasd.org\/blogs\/universo\/?p=144679"},"modified":"2013-11-29T14:10:58","modified_gmt":"2013-11-29T13:10:58","slug":"gypsisoles-gipsisoles-geografia-ambiente-y-paisaje","status":"publish","type":"post","link":"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/11\/14\/144679","title":{"rendered":"Gypsisoles (Gipsisoles) Geograf\u00eda Ambiente y Paisaje"},"content":{"rendered":"<p align=\"center\"><img decoding=\"async\" class=\"ngg-singlepic ngg-center\" src=\"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-content\/blogs.dir\/42\/files\/164\/karst-de-yesos-sorbas-almeria-fuente-almeria-natura.jpg\" alt=\"karst-de-yesos-sorbas-almeria-fuente-almeria-natura\" \/><\/p>\n<p align=\"center\"><a href=\"http:\/\/www.almerinatura.com\/paraje-natural-del-karst-en-yesos-de-sorbas\">Karst de Yesos Sorbas Almer\u00eda, que necesariamente no implica la presencia de Gypsisoles. Fuente: Almer\u00eda Natura<\/a><\/p>\n<p style=\"text-align: justify;\">Los <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/11\/07\/144670\">Gypsisoles (Gipsisoles)<\/a>\u00a0y <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/02\/13\/143541\">Calcisoles<\/a> se encuentran en un amplio rango de formaciones fisiogr\u00e1ficas, incluyendo pedimentos, fondos de lagos, terrazas y abanicos aluviales. Los <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/09\/18\/144494\">Durisoles<\/a>, con un horizonte D\u00farico o Petrod\u00farico que est\u00e1 endurecido por s\u00edlice (SiO2), no es exclusivo de las regiones \u00e1ridas, si bien la mayor\u00eda de los Durisoles se ubican en tierras secas, por ejemplo, al lado de Calcisoles o Gipsisoles<strong>. <span style=\"color: #3366ff;\">Los Gipsisoles son exclusivos de regiones \u00e1ridas y semi\u00e1ridas<\/span><\/strong>; su extensi\u00f3n en el mundo\u00a0ha sido calculada en unos de <span style=\"color: #3366ff;\"><strong>100 millones de hect\u00e1reas<\/strong><\/span>. Se trata de edafotaxa dominantes en y alrededor de <span style=\"color: #3366ff;\"><strong>Mesopotamia, en \u00e1reas des\u00e9rticas en el Medio Oriente y rep\u00fablicas Asi\u00e1ticas centrales adyacentes, en los desiertos de Libia y Namibia, en el sureste y centro de Australia y el suroeste de USA<\/strong><\/span>.<\/p>\n<p style=\"text-align: center;\"><img decoding=\"async\" class=\"ngg-singlepic ngg-center\" src=\"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-content\/blogs.dir\/42\/files\/370\/gypsisol-mapa-del-mundo-isric.jpg\" alt=\"gypsisol-mapa-del-mundo-isric\" width=\"480\" height=\"376\" \/><\/p>\n<p style=\"text-align: center;\"><a href=\"http:\/\/www.isric.org\/about-soils\/world-soil-distribution\/gypsisols\">Gypsisoles Mapa del Fundo Fuente ISRIC<\/a><\/p>\n<p align=\"center\"><img decoding=\"async\" class=\"ngg-singlepic ngg-center\" src=\"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-content\/blogs.dir\/42\/files\/164\/paisaje-de-suelos-con-gypsisoles-fuente-esb.jpg\" alt=\"paisaje-de-suelos-con-gypsisoles-fuente-esb\" width=\"459\" height=\"359\" \/><\/p>\n<p align=\"center\"><a href=\"http:\/\/eusoils.jrc.ec.europa.eu\/projects\/soil_atlas\/images\/1-39%2030_img_10.jpg\">Paisaje de Gypsisoles. Fuente European soil Buro<\/a><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #800000;\"><strong>Asociaci\u00f3n con otros grupos de suelos de referencia (\u2026)<\/strong><\/span><\/p>\n<p><!--more--><\/p>\n<p><strong>Asociaci\u00f3n con otros grupos de suelos de referencia (\u2026)<\/strong><\/p>\n<p style=\"text-align: justify;\">\u00a0Los Gipsisoles aparecen en la misma zona clim\u00e1tica de los Calcisoles. En este sentido cabe rese\u00f1ar como la presencia de un horizonte G\u00edpsico o Petrog\u00edpsico es resulta ser una de las principales caracter\u00edsticas de los Gipsisoles, pero la acumulaci\u00f3n de yeso tambi\u00e9n ocurre en otros Suelos de Referencia. <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/10\/06\/140062\">Vertisoles<\/a>, Solonchaks, <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/02\/16\/138132\">Gleysoles<\/a> o Kastanozems, son, a menudo indicadores de la existencia de otros tipos de suelos, cuando contienen yeso, es decir intergrados con el Grupo de Suelos de Referencia de los Gipsisoles, pero no encajan como \u00e9stos porque no tienen otras propiedades de diagn\u00f3stico m\u00e1s que un horizonte G\u00edpsico o Petrog\u00edpsico.<\/p>\n<p style=\"text-align: center;\"><img decoding=\"async\" class=\"ngg-singlepic ngg-center\" src=\"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-content\/blogs.dir\/42\/files\/164\/paisaje-yesos-atacama-fuente-carleton-edu.jpg\" alt=\"paisaje-yesos-atacama-fuente-carleton-edu\" width=\"528\" height=\"357\" \/><\/p>\n<p align=\"center\"><a href=\"http:\/\/serc.carleton.edu\/details\/images\/17328.html\">Paisaje de Yesos en el desierto de Atacama. Fuente Carleton edu<\/a><\/p>\n<p>\u00a0<span style=\"color: #800000;\"><strong>WRB 2006-2007. Traducci\u00f3n Oficial de Mabel Susana Pazos<\/strong><\/span><\/p>\n<p><span style=\"color: #800000;\"><strong>Distribuci\u00f3n regional de Gipsisoles<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\">Los Gipsisoles son exclusivos de regiones \u00e1ridas; su extensi\u00f3n mundial es probablemente del orden de 100 millones ha. Las principales ocurrencias est\u00e1n en y alrededor de la Mesopotamia, en \u00e1reas des\u00e9rticas del Cercano Oriente y rep\u00fablicas adyacentes de Asia Central, en los desiertos de Libia y Namibia, en el sudeste y centro de Australia y en el sudoeste de los Estados Unidos de Norteam\u00e9rica.<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #800000;\"><strong>Material\u00a0 Bibliogr\u00e1fico<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.fao.org\/nr\/land\/soils\/soil\/en\">P\u00e1gina Web de la WRB<\/a><\/p>\n<p style=\"text-align: justify;\"><a href=\"ftp:\/\/ftp.fao.org\/docrep\/fao\/011\/a0510s\/a0510s00.pdf\">Clasificaci\u00f3n WRB 2006-2007<\/a><\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.fao.org\/DOCREP\/003\/Y1899E\/Y1899E00.HTM\">Lecture notes on the major soils of the world<\/a> (versi\u00f3n personal traducida al espa\u00f1ol por Javier Manr\u00edquez Cos\u00edo)<\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.inegi.org.mx\/prod_serv\/contenidos\/espanol\/bvinegi\/productos\/integracion\/especiales\/BoletinSNEIG\/2010\/Bsnieg14_b.pdf\">Los suelos de Latinoam\u00e9rica: retos y oportunidades de uso y estudio<\/a> (ir al titulo correspondiente) Autores: Francisco Bautista, Alfred J. Zinck y Silke Cram. Bolet\u00edn del Sistema Nacional de Informaci\u00f3n Estad\u00edstica y Geogr\u00e1fica: VII(3) Septiembre-Diciembre 2009, p\u00e1ginas 94-142<\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/eusoils.jrc.ec.europa.eu\/esdb_archive\/eusoils_docs\/other\/EUR23439.pdf\">Soils of the European Union<\/a> (en Ingles)<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #800000;\"><strong>Post Previos y a Publicar en Breve de Nuestro Curso B\u00e1sico Tipos de Suelos del Mundo<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\">\u00a0<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/06\/23\/136471\">Los Suelos del Mundo y Su clasificaci\u00f3n (WRB). Curso B\u00e1sico sobre Clasificaci\u00f3n de Suelos<\/a><\/p>\n<p style=\"text-align: justify;\">\u00a0<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/06\/28\/136476\">Suelos Minerales Condicionados por la Topograf\u00eda o Fisiograf\u00eda: Leptosoles, Regosoles, Fluvisoles y Gleysoles<\/a><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #800000;\"><strong>Post Previos y a Publicar en Breve de Nuestro Curso B\u00e1sico Tipos de Suelos del Mundo hasta octubre de 2013<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/06\/23\/136471\">Los Suelos del Mundo y Su clasificaci\u00f3n (WRB). Curso B\u00e1sico sobre Clasificaci\u00f3n de Suelos<\/a><\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/06\/28\/136476\">Suelos Minerales Condicionados por la Topograf\u00eda o Fisiograf\u00eda: Leptosoles, Regosoles, Fluvisoles y Gleysoles<\/a><\/p>\n<p style=\"text-align: justify;\"><strong>Leptosoles<\/strong><\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/07\/06\/136490\">Leptosoles<\/a>;\u00a0<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/07\/13\/136682\">Leptosoles: Geograf\u00eda Ambiente y Paisaje<\/a>;\u00a0<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/07\/28\/136691\">Leptosoles Uso y Manejo<\/a>;<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/08\/04\/136695\">Leptosoles en Latinoam\u00e9rica<\/a>;\u00a0<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/08\/11\/136703\">Leptosoles en Europa<\/a>;\u00a0<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/08\/22\/136503\">Tipos de Leptosoles y sus Mapas de Distribuci\u00f3n en Europa<\/a><\/p>\n<p style=\"text-align: justify;\"><strong>Regosoles<\/strong><\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/09\/02\/136720\">Regosoles<\/a>; \u00a0<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/09\/09\/136869\">Regosoles: Geograf\u00eda, Ambiente y Paisaje<\/a>;\u00a0<a title=\"Enlace permanente a Regosoles: Uso y Manejo\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/09\/16\/136876\">Regosoles: Uso y Manejo<\/a>:\u00a0<a title=\"Enlace permanente a Regosoles en Latinoam\u00e9rica\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/09\/24\/136882\">Regosoles en Latinoam\u00e9rica<\/a>;\u00a0<a title=\"Enlace permanente a Regosoles en Europa\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/10\/28\/136908\">Regosoles en Europa<\/a>;\u00a0<a title=\"Enlace permanente a Tipos de Regosoles y sus Mapas de Distribuci\u00f3n en Europa(WRB 1998)\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/11\/04\/136894\">Tipos de Regosoles y sus Mapas de Distribuci\u00f3n en Europa(WRB 1998)<\/a><\/p>\n<p style=\"text-align: justify;\"><strong>Fluvisoles<\/strong><\/p>\n<p style=\"text-align: justify;\"><a title=\"Enlace permanente a Paisajes Aluviales No Costeros de las Redes Fluviales (WRB 1998)\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/01\/06\/137193\">Paisajes Aluviales No Costeros de las Redes Fluviales (WRB 1998)<\/a>;\u00a0<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/01\/13\/137830\">Deltas, Estuarios y Marismas<\/a>;\u00a0<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/01\/19\/137847\">Geoformas de las L\u00edneas de Costa Generadas por la Din\u00e1mica Marina (WRB-FAO 2000)<\/a>,\u00a0<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/01\/26\/137868\">Fluvisoles<\/a>,\u00a0<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/02\/02\/138188\">Fluvisoles ti\u00f3nicos<\/a>,\u00a0<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/02\/01\/137894\">Distribuci\u00f3n geogr\u00e1fica de los Fluvisoles<\/a>,\u00a0<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/02\/03\/137903\">Fluvisoles uso y manejo<\/a>,\u00a0<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/02\/04\/137912\">Fluvisoles en Latinoam\u00e9rica<\/a>,\u00a0<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/02\/07\/137923\">Fluvisoles en Europa<\/a>,\u00a0<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/02\/08\/137936\">Mapas de los tipos de suelos de Europa (WRB 1998)<\/a><\/p>\n<p style=\"text-align: justify;\">\u00a0<strong>Gleysoles<\/strong><\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/02\/16\/138132\">Gleysoles<\/a>;\u00a0<a title=\"Enlace permanente a Gleysoles: Geograf\u00eda Ambiente y Paisaje\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/02\/24\/138158\">Gleysoles: Geograf\u00eda Ambiente y Paisaje<\/a>\u00a0<a title=\"Enlace permanente a Gleysoles: Uso y Manejo\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/02\/25\/138174\">Gleysoles: Uso y Manejo<\/a>,\u00a0<a title=\"Enlace permanente a Gleysoles en Latinoam\u00e9rica\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/02\/28\/138196\">Gleysoles en Latinoam\u00e9rica<\/a>,\u00a0<a title=\"Enlace permanente a Gleysoles en Europa\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/03\/01\/138204\">Gleysoles en Europa<\/a>,\u00a0<a title=\"Enlace permanente a Tipos de Gleysoles y sus Mapas de Distribuci\u00f3n en Europa\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/03\/03\/138117\">Tipos de Gleysoles y sus Mapas de Distribuci\u00f3n en Europa<\/a><\/p>\n<p style=\"text-align: justify;\"><strong>Stagnosoles (WRB 2006-2007)<\/strong><\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/03\/17\/138151\">Stagnosoles<\/a><\/p>\n<p style=\"text-align: justify;\"><strong>Histosoles<\/strong><\/p>\n<p style=\"text-align: justify;\"><a title=\"Enlace permanente a Histosoles (WRB 1998): Las Turberas\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/03\/30\/138691\">Histosoles (WRB 1998): Las Turberas<\/a>; <a title=\"Enlace permanente a Histosoles (Turberas): Geograf\u00eda, Ambiente y Paisaje\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/04\/05\/138702\">Histosoles (Turberas): Geograf\u00eda, Ambiente y Paisaje<\/a>; <a title=\"Enlace permanente a Histosoles Uso y Manejo (Turberas) (WRB 1998)\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/04\/06\/138714\">Histosoles Uso y Manejo (Turberas) (WRB 1998)<\/a>; <a title=\"Enlace permanente a Histosoles en Latinoam\u00e9rica Tropical\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/04\/08\/138760\">Histosoles en Latinoam\u00e9rica Tropical<\/a>; <a title=\"Enlace permanente a Histosoles en Europa (Turberas)\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/04\/11\/138742\">Histosoles en Europa (Turberas)<\/a>; <a title=\"Enlace permanente a Tipos de Histosoles y sus Mapas de Distribuci\u00f3n en Europa (WRB 1998)\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/04\/20\/138751\">Tipos de Histosoles y sus Mapas de Distribuci\u00f3n en Europa (WRB 1998)<\/a><\/p>\n<p style=\"text-align: justify;\"><strong>Cambisoles<\/strong><\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/06\/09\/139388\">Cambisoles<\/a>; <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/06\/15\/139402\">Cambisoles: Geograf\u00eda Ambiente y Paisaje<\/a>; <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/06\/22\/139434\">Cambisoles: Uso y Manejo<\/a>; <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/06\/23\/139458\">Cambisoles en Latinoam\u00e9rica<\/a>;\u00a0 <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/06\/30\/139418\">Cambisoles en Europa<\/a>; <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/07\/07\/139426\">Tipos de Cambisoles y Sus Mapas de Distribuci\u00f3n en Europa<\/a><\/p>\n<p style=\"text-align: justify;\"><strong>Arenosoles<\/strong><\/p>\n<p style=\"text-align: justify;\"><a title=\"Enlace permanente a Dunas y Paisajes Arenosos (WRB 1998)\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/07\/12\/139706\">Dunas y Paisajes Arenosos (WRB 1998)<\/a>; <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/07\/13\/139746\">Arenosoles<\/a>; <a title=\"Enlace permanente a Arenosoles: Geograf\u00eda Ambiente y Paisaje\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/07\/18\/139756\">Arenosoles: Geograf\u00eda; Ambiente y Paisaje<\/a>; <a title=\"Enlace permanente a Arenosoles: Uso y Manejo\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/07\/21\/139772\">Arenosoles: Uso y Manejo<\/a>; <a title=\"Enlace permanente a Arenosoles en Latinoam\u00e9rica\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/07\/28\/139786\">Arenosoles en Latinoam\u00e9rica<\/a>; <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/08\/04\/139794\">Arenosoles en Europa<\/a>; <a title=\"Enlace permanente a Tipos de Arenosoles y sus Mapas de Distribuci\u00f3n en Europa\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/08\/11\/139800\">Tipos de Arenosoles y sus Mapas de Distribuci\u00f3n en Europa<\/a><\/p>\n<p style=\"text-align: justify;\"><strong>Vertisoles<\/strong><\/p>\n<p style=\"text-align: justify;\"><a title=\"Enlace permanente a Paisajes Arcillosos (WRB, 1998)\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/09\/29\/139981\">Paisajes Arcillosos (WRB, 1998)<\/a>, <a title=\"Enlace permanente a Microrelieve Gilgai  (Vertisoles, WRB, 1998)\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/10\/04\/140078\">Microrelieve Gilgai (Vertisoles, WRB, 1998)<\/a>, <a title=\"Enlace permanente a Vertisoles (WRB, 1998)\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/10\/06\/140062\">Vertisoles (WRB, 1998)<\/a>, <a title=\"Enlace permanente a Vertisoles: Geograf\u00eda, Ambiente y Paisaje\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/10\/13\/140087\">Vertisoles: Geograf\u00eda, Ambiente y Paisaje<\/a>, <a title=\"Enlace permanente a Vertisoles: Uso y Manejo\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/10\/21\/140108\">Vertisoles: Uso y Manejo<\/a>, <a title=\"Enlace permanente a Vertisoles en Latinoam\u00e9rica\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/10\/28\/140114\">Vertisoles en Latinoam\u00e9rica<\/a>, <a title=\"Enlace permanente a Vertisoles en La UE y el Continente Europeo\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/11\/01\/140049\">Vertisoles en La UE y el Continente Europeo<\/a>, <a title=\"Enlace permanente a Tipos de Vertisoles y sus Mapas de Distribuci\u00f3n en Europa\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/11\/11\/140053\">Tipos de Vertisoles y sus Mapas de Distribuci\u00f3n en Europa<\/a><\/p>\n<p style=\"text-align: justify;\"><strong>Andosoles<\/strong><\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/11\/16\/140617\">Paisajes Volc\u00e1nicos<\/a>, <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/11\/23\/140258\">Andosoles<\/a>, <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/12\/02\/140627\">Andosoles: geograf\u00eda ambiente y paisaje<\/a>, <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/12\/20\/140649\">Andosoles Uso y Manejo<\/a>, <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/01\/17\/140659\">Andosoles en Latinoam\u00e9rica<\/a>, <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/01\/25\/140135\">Andosoles en Europa<\/a>, <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/01\/25\/140135\">Andosoles en Europa\u00a0 y los Suelos de Islandia<\/a>, <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/02\/02\/140142\">Tipos de Andosoles y sus mapas de distribuci\u00f3n en Europa<\/a><strong><\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Luvisoles<\/strong><\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/02\/28\/141085\">Luvisoles<\/a>, <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/03\/15\/141095\">Luvisoles: geograf\u00eda ambiente y paisaje<\/a>, <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/03\/23\/141101\">Luvisoles Uso y Manejo<\/a>; <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/03\/27\/141109\">Luvisoles en Latinoam\u00e9rica<\/a>, <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/04\/03\/141236\">Luvisoles en Europa<\/a>, <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/04\/07\/141248\">Tipos de Luvisoles y sus mapas de distribuci\u00f3n en Europa<\/a>.<\/p>\n<p style=\"text-align: justify;\"><strong>Alisoles<\/strong><\/p>\n<p style=\"text-align: justify;\"><a title=\"Enlace permanente a Alisoles (WRB, 1998)\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/04\/19\/141598\">Alisoles (WRB, 1998)<\/a>; <a title=\"Enlace permanente a Alisoles: Geograf\u00eda Ambiente y Paisaje\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/04\/25\/141607\">Alisoles: Geograf\u00eda Ambiente y Paisaje<\/a>, <a title=\"Enlace permanente: Alisoles: Uso y Manejo\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/05\/03\/141613\">Alisoles: Uso y Manejo<\/a><\/p>\n<p style=\"text-align: justify;\"><strong>Lixisoles<\/strong><\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/05\/09\/141636\">Lixisoles<\/a>; <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/05\/22\/141646\">Lixisoles: Geograf\u00eda ambiente y paisaje<\/a>; <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/05\/31\/141657\">Lixisoles: Uso y manejo<\/a><\/p>\n<p style=\"text-align: justify;\"><strong>Acrisoles<\/strong><\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/06\/07\/142059\">Acrisoles<\/a>, <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/06\/13\/142068\">Acrisoles: geograf\u00eda ambiente y paisaje<\/a>, <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/06\/20\/142080\">Acrisoles Uso y Manejo<\/a>, <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/07\/11\/142092\">Acrisoles en Latinoam\u00e9rica<\/a>, <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/06\/28\/142112\">Acrisoles en Europa<\/a>, <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/07\/05\/142118\">Tipos de Acrisoles y sus mapas de distribuci\u00f3n en Europa<\/a>.<\/p>\n<p style=\"text-align: justify;\"><strong>Albeluvisoles<\/strong><\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/07\/20\/142243\">Albeluvisoles<\/a>: <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/07\/27\/142257\">Albeluvisoles: Geograf\u00eda, Ambiente y Paisaje<\/a>; <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/08\/03\/142273\">Albeluvisoles: uso y manejo<\/a>; <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/08\/10\/142287\">Albeluvisoles en Europa<\/a>, <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/08\/10\/142287\">Albeluvisoles y sus mapas de distribuci\u00f3n en Europa<\/a>,<\/p>\n<p style=\"text-align: justify;\"><strong>Podozoles<\/strong><\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/08\/24\/142310\">Podzoles<\/a>, <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/09\/01\/142321\">Podzoles: Geograf\u00eda, Ambiente y Paisaje<\/a>, <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/09\/07\/142329\">Podzoles Uso y Manejo<\/a>, <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/09\/14\/142338\">Podzoles en Europa,<\/a> <a title=\"Enlace permanente a Tipos de Podzoles y sus Mapas de Distribuci\u00f3n en Europa\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/09\/21\/142344\">Tipos de Podzoles y sus Mapas de Distribuci\u00f3n en Europa<\/a>.<\/p>\n<p style=\"text-align: justify;\"><strong>Planosoles<\/strong><strong><\/strong><\/p>\n<p style=\"text-align: justify;\"><a title=\"Enlace permanente a Planosoles WRB\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/09\/28\/142528\">Planosoles WRB<\/a>, <a title=\"Enlace permanente a Planosoles: Geograf\u00eda Ambiente y Paisaje\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/10\/04\/142544\">Planosoles: Geograf\u00eda Ambiente y Paisaje<\/a>, <a title=\"Enlace permanente a Planosoles: Uso y Manejo\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/10\/12\/142554\">Planosoles: Uso y Manejo<\/a>, <a title=\"Enlace permanente a Planosoles en Europa\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/10\/18\/142564\">Planosoles en Europa<\/a>, <a title=\"Enlace permanente a Planosoles en Latinoam\u00e9rica\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/10\/25\/142569\">Planosoles en Latinoam\u00e9rica<\/a>, <a title=\"Enlace permanente a Tipos de Planosoles y sus Mapas de Distribuci\u00f3n en Europa\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/11\/02\/142577\">Tipos de Planosoles y sus Mapas de Distribuci\u00f3n en Europa<\/a>.<\/p>\n<p style=\"text-align: justify;\"><strong>Criosoles<\/strong><\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/11\/08\/142393\">Criosoles WRB<\/a>, <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/11\/20\/142421\">Criosoles: Geograf\u00eda, Ambiente y Paisaje<\/a>, <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/11\/27\/142435\">Criosoles: Uso y Manejo<\/a>, <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/12\/05\/142451\">Criosoles en Europa y la Ant\u00e1rtida<\/a>, <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/12\/21\/142457\">Criosoles: Mapas de Distribuci\u00f3n en Europa<\/a>.<\/p>\n<p style=\"text-align: justify;\"><strong>Umbrisoles<\/strong><\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/01\/09\/142763\">Umbrisoles WRB,<\/a> <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/01\/16\/142805\">Umbrisoles: Geograf\u00eda Ambiente y Paisaje<\/a>, <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/01\/25\/143713\">Umbrisoles: Uso y Manejo<\/a>, <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/01\/31\/142896\">Umbrisoles en Europa<\/a><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/02\/06\/142903\">, Tipo de Umbrisoles en Europa y sus Mapas de Distribuci\u00f3n<\/a>.<\/p>\n<p style=\"text-align: justify;\"><strong>Calcisoles<\/strong><\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/02\/13\/143541\">Calcisoles WRB<\/a>, <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/02\/20\/143555\">Calcisoles: Geograf\u00eda Ambiente y Paisaje<\/a>; <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/02\/27\/143561\">Calcisoles: Uso y manejo<\/a>; <a title=\"Enlace permanente: Calcisoles en Latinoam\u00e9rica (WRB)\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/03\/06\/143596\">Calcisoles en Latinoam\u00e9rica (WRB)<\/a>; <a title=\"Enlace permanente a Calcisoles en Europa (WRB)\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/03\/13\/143575\">Calcisoles en Europa<\/a>; <a title=\"Enlace permanente a Calcisoles (WRB): Mapas de Distribuci\u00f3n en Europa\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/03\/20\/143587\">Calcisoles: Mapas de Distribuci\u00f3n en Europa<\/a>;<\/p>\n<p style=\"text-align: justify;\"><strong>Nitisoles (Nitosoles)<\/strong><\/p>\n<p style=\"text-align: justify;\"><a title=\"Enlace permanente a Nitisoles (WRB)\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/03\/30\/143790\">Nitisoles (WRB)<\/a>; <a title=\"Enlace permanente a Nitisoles o Nitosoles: Geograf\u00eda Ambiente y Paisaje (Suelos Ferral\u00edticos)\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/04\/06\/143803\">Nitisoles o Nitosoles: Geograf\u00eda Ambiente y Paisaje (Suelos Ferral\u00edticos)<\/a>; <a title=\"Enlace permanente a Nitisoles (Nitosoles): Uso y Manejo (Suelos Ferral\u00edticos)\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/04\/10\/143811\">Nitisoles (Nitosoles): Uso y Manejo (Suelos Ferral\u00edticos)<\/a>; <a title=\"Enlace permanente a Nitisoles (Nitosoles) en Latinoam\u00e9rica (Suelos Ferral\u00edticos)\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/04\/18\/143817\">Nitisoles (Nitosoles) en Latinoam\u00e9rica (Suelos Ferral\u00edticos)<\/a>;<\/p>\n<p style=\"text-align: justify;\">\u00a0<strong>Ferralsoles<\/strong><\/p>\n<p style=\"text-align: justify;\">\u00a0<a title=\"Enlace permanente a Ferralsoles (WRB)\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/04\/25\/143832\">Ferralsoles (WRB)<\/a>; <a title=\"Enlace permanente a Ferralsoles: Geograf\u00eda, Ambiente y Paisaje (Suelos Tropicales)\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/05\/02\/143842\">Ferralsoles: Geograf\u00eda, Ambiente y Paisaje (Suelos Tropicales)<\/a>; <a title=\"Enlace permanente a Ferralsoles: Uso y Manejo (WRB)\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/05\/09\/143848\">Ferralsoles: Uso y Manejo (WRB)<\/a><\/p>\n<p style=\"text-align: justify;\">\u00a0<strong>Plintosoles<\/strong><\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/06\/17\/143891\">Plintosoles (WRB) Suelos con Plintita<\/a>, <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/06\/26\/143907\">Plintosoles: Geograf\u00eda, Ambiente y paisaje<\/a>, <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/07\/06\/143914\">Plintosoles Uso y Manejo<\/a>, <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/07\/11\/143929\">Plintosoles (Plintosoles) en Latinoam\u00e9rica<\/a>,<\/p>\n<p style=\"text-align: justify;\"><strong>Durisoles<\/strong><\/p>\n<p style=\"text-align: justify;\"><a title=\"Enlace permanente a Durisoles (WRB) Suelos Con Horizontes Endurecidos\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/09\/18\/144494\">Durisoles (WRB) Suelos Con Horizontes Endurecidos<\/a>; <a title=\"Enlace permanente a Durisoles: Geograf\u00eda, ambiente y paisaje\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/09\/28\/144500\">Durisoles: Geograf\u00eda, ambiente y paisaje<\/a>; <a title=\"Enlace permanente a Durisoles: Uso y Manejo\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/10\/24\/144508\">Durisoles: Uso y Manejo<\/a>; <a title=\"Enlace permanente a Durisoles en Latinoam\u00e9rica y Europa\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/10\/31\/144519\">Durisoles en Latinoam\u00e9rica y Europa<\/a><\/p>\n<h3>Im\u00e1genes Relacionadas:<\/h3>","protected":false},"excerpt":{"rendered":"<p>Karst de Yesos Sorbas Almer\u00eda, que necesariamente no implica la presencia de Gypsisoles. Fuente: Almer\u00eda Natura Los Gypsisoles (Gipsisoles)\u00a0y Calcisoles se encuentran en un amplio rango de formaciones fisiogr\u00e1ficas, incluyendo pedimentos, fondos de lagos, terrazas y abanicos aluviales. Los Durisoles, con un horizonte D\u00farico o Petrod\u00farico que est\u00e1 endurecido por s\u00edlice (SiO2), no es exclusivo de las regiones \u00e1ridas, si bien la mayor\u00eda de los Durisoles se ubican en tierras secas, por ejemplo, al lado de Calcisoles o Gipsisoles. Los Gipsisoles son exclusivos de regiones \u00e1ridas y semi\u00e1ridas; su extensi\u00f3n en el mundo\u00a0ha sido calculada en unos de 100 millones\u2026<\/p>\n","protected":false},"author":160,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0},"categories":[1],"tags":[],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":4}},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Karst de Yesos Sorbas Almer\u00eda, que necesariamente no implica la presencia de Gypsisoles. Fuente: Almer\u00eda Natura Los Gypsisoles (Gipsisoles) y Calcisoles se encuentran en un amplio rango de formaciones fisiogr\u00e1ficas, incluyendo pedimentos, fondos de lagos, terrazas y abanicos aluviales. Los Durisoles, con un horizonte D\u00farico o Petrod\u00farico que est\u00e1 endurecido por s\u00edlice (SiO2), no es exclusivo\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Juan Jose Ib\u00e1\u00f1ez  y Francisco Javier Manr\u00edquez Cosio\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/11\/14\/144679\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Un Universo invisible bajo nuestros pies - Los suelos y la vida\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Gypsisoles (Gipsisoles) Geograf\u00eda Ambiente y Paisaje - Un Universo invisible bajo nuestros pies\" \/>\n\t\t<meta property=\"og:description\" content=\"Karst de Yesos Sorbas Almer\u00eda, que necesariamente no implica la presencia de Gypsisoles. Fuente: Almer\u00eda Natura Los Gypsisoles (Gipsisoles) y Calcisoles se encuentran en un amplio rango de formaciones fisiogr\u00e1ficas, incluyendo pedimentos, fondos de lagos, terrazas y abanicos aluviales. Los Durisoles, con un horizonte D\u00farico o Petrod\u00farico que est\u00e1 endurecido por s\u00edlice (SiO2), no es exclusivo\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/11\/14\/144679\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2013-11-14T13:15:42+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2013-11-29T13:10:58+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/juan.j.marti.14\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Gypsisoles (Gipsisoles) Geograf\u00eda Ambiente y Paisaje - Un Universo invisible bajo nuestros pies\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Karst de Yesos Sorbas Almer\u00eda, que necesariamente no implica la presencia de Gypsisoles. Fuente: Almer\u00eda Natura Los Gypsisoles (Gipsisoles) y Calcisoles se encuentran en un amplio rango de formaciones fisiogr\u00e1ficas, incluyendo pedimentos, fondos de lagos, terrazas y abanicos aluviales. Los Durisoles, con un horizonte D\u00farico o Petrod\u00farico que est\u00e1 endurecido por s\u00edlice (SiO2), no es exclusivo\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2013\\\/11\\\/14\\\/144679#blogposting\",\"name\":\"Gypsisoles (Gipsisoles) Geograf\\u00eda Ambiente y Paisaje - Un Universo invisible bajo nuestros pies\",\"headline\":\"Gypsisoles (Gipsisoles) Geograf\\u00eda Ambiente y Paisaje\",\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/juanjosibezyfranciscojaviermanriquezcosio#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"http:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/wp-content\\\/blogs.dir\\\/42\\\/files\\\/164\\\/karst-de-yesos-sorbas-almeria-fuente-almeria-natura.jpg\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2013\\\/11\\\/14\\\/144679\\\/#articleImage\"},\"datePublished\":\"2013-11-14T14:15:42+01:00\",\"dateModified\":\"2013-11-29T14:10:58+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2013\\\/11\\\/14\\\/144679#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2013\\\/11\\\/14\\\/144679#webpage\"},\"articleSection\":\"General\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2013\\\/11\\\/14\\\/144679#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/general#listItem\",\"name\":\"General\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/general#listItem\",\"position\":2,\"name\":\"General\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/general\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2013\\\/11\\\/14\\\/144679#listItem\",\"name\":\"Gypsisoles (Gipsisoles) Geograf\\u00eda Ambiente y Paisaje\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2013\\\/11\\\/14\\\/144679#listItem\",\"position\":3,\"name\":\"Gypsisoles (Gipsisoles) Geograf\\u00eda Ambiente y Paisaje\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/general#listItem\",\"name\":\"General\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#organization\",\"name\":\"Un Universo invisible bajo nuestros pies\",\"description\":\"Los suelos y la vida\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/files\\\/2022\\\/02\\\/logo.png\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2013\\\/11\\\/14\\\/144679\\\/#organizationLogo\",\"width\":217,\"height\":72},\"image\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2013\\\/11\\\/14\\\/144679\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/juan.j.marti.14\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/juanjosibezyfranciscojaviermanriquezcosio#author\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/juanjosibezyfranciscojaviermanriquezcosio\",\"name\":\"Juan Jose Ib\\u00e1\\u00f1ez  y Francisco Javier Manr\\u00edquez Cosio\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2013\\\/11\\\/14\\\/144679#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fb970ba39345138010f6a98cf960b8eb?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Juan Jose Ib\\u00e1\\u00f1ez  y Francisco Javier Manr\\u00edquez Cosio\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2013\\\/11\\\/14\\\/144679#webpage\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2013\\\/11\\\/14\\\/144679\",\"name\":\"Gypsisoles (Gipsisoles) Geograf\\u00eda Ambiente y Paisaje - Un Universo invisible bajo nuestros pies\",\"description\":\"Karst de Yesos Sorbas Almer\\u00eda, que necesariamente no implica la presencia de Gypsisoles. Fuente: Almer\\u00eda Natura Los Gypsisoles (Gipsisoles) y Calcisoles se encuentran en un amplio rango de formaciones fisiogr\\u00e1ficas, incluyendo pedimentos, fondos de lagos, terrazas y abanicos aluviales. Los Durisoles, con un horizonte D\\u00farico o Petrod\\u00farico que est\\u00e1 endurecido por s\\u00edlice (SiO2), no es exclusivo\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2013\\\/11\\\/14\\\/144679#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/juanjosibezyfranciscojaviermanriquezcosio#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/juanjosibezyfranciscojaviermanriquezcosio#author\"},\"datePublished\":\"2013-11-14T14:15:42+01:00\",\"dateModified\":\"2013-11-29T14:10:58+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#website\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/\",\"name\":\"Un Universo invisible bajo nuestros pies\",\"description\":\"Los suelos y la vida\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Gypsisoles (Gipsisoles) Geograf\u00eda Ambiente y Paisaje - Un Universo invisible bajo nuestros pies","description":"Karst de Yesos Sorbas Almer\u00eda, que necesariamente no implica la presencia de Gypsisoles. Fuente: Almer\u00eda Natura Los Gypsisoles (Gipsisoles) y Calcisoles se encuentran en un amplio rango de formaciones fisiogr\u00e1ficas, incluyendo pedimentos, fondos de lagos, terrazas y abanicos aluviales. Los Durisoles, con un horizonte D\u00farico o Petrod\u00farico que est\u00e1 endurecido por s\u00edlice (SiO2), no es exclusivo","canonical_url":"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/11\/14\/144679","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/11\/14\/144679#blogposting","name":"Gypsisoles (Gipsisoles) Geograf\u00eda Ambiente y Paisaje - Un Universo invisible bajo nuestros pies","headline":"Gypsisoles (Gipsisoles) Geograf\u00eda Ambiente y Paisaje","author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/juanjosibezyfranciscojaviermanriquezcosio#author"},"publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#organization"},"image":{"@type":"ImageObject","url":"http:\/\/www.madrimasd.org\/blogs\/universo\/wp-content\/blogs.dir\/42\/files\/164\/karst-de-yesos-sorbas-almeria-fuente-almeria-natura.jpg","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/11\/14\/144679\/#articleImage"},"datePublished":"2013-11-14T14:15:42+01:00","dateModified":"2013-11-29T14:10:58+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/11\/14\/144679#webpage"},"isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/11\/14\/144679#webpage"},"articleSection":"General"},{"@type":"BreadcrumbList","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/11\/14\/144679#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo#listItem","position":1,"name":"Home","item":"https:\/\/www.madrimasd.org\/blogs\/universo","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/general#listItem","name":"General"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/general#listItem","position":2,"name":"General","item":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/general","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/11\/14\/144679#listItem","name":"Gypsisoles (Gipsisoles) Geograf\u00eda Ambiente y Paisaje"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/11\/14\/144679#listItem","position":3,"name":"Gypsisoles (Gipsisoles) Geograf\u00eda Ambiente y Paisaje","previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/general#listItem","name":"General"}}]},{"@type":"Organization","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#organization","name":"Un Universo invisible bajo nuestros pies","description":"Los suelos y la vida","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/","logo":{"@type":"ImageObject","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/11\/14\/144679\/#organizationLogo","width":217,"height":72},"image":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/11\/14\/144679\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/juan.j.marti.14"]},{"@type":"Person","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/juanjosibezyfranciscojaviermanriquezcosio#author","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/juanjosibezyfranciscojaviermanriquezcosio","name":"Juan Jose Ib\u00e1\u00f1ez  y Francisco Javier Manr\u00edquez Cosio","image":{"@type":"ImageObject","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/11\/14\/144679#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/fb970ba39345138010f6a98cf960b8eb?s=96&d=mm&r=g","width":96,"height":96,"caption":"Juan Jose Ib\u00e1\u00f1ez  y Francisco Javier Manr\u00edquez Cosio"}},{"@type":"WebPage","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/11\/14\/144679#webpage","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/11\/14\/144679","name":"Gypsisoles (Gipsisoles) Geograf\u00eda Ambiente y Paisaje - Un Universo invisible bajo nuestros pies","description":"Karst de Yesos Sorbas Almer\u00eda, que necesariamente no implica la presencia de Gypsisoles. Fuente: Almer\u00eda Natura Los Gypsisoles (Gipsisoles) y Calcisoles se encuentran en un amplio rango de formaciones fisiogr\u00e1ficas, incluyendo pedimentos, fondos de lagos, terrazas y abanicos aluviales. Los Durisoles, con un horizonte D\u00farico o Petrod\u00farico que est\u00e1 endurecido por s\u00edlice (SiO2), no es exclusivo","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#website"},"breadcrumb":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/11\/14\/144679#breadcrumblist"},"author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/juanjosibezyfranciscojaviermanriquezcosio#author"},"creator":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/juanjosibezyfranciscojaviermanriquezcosio#author"},"datePublished":"2013-11-14T14:15:42+01:00","dateModified":"2013-11-29T14:10:58+01:00"},{"@type":"WebSite","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#website","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/","name":"Un Universo invisible bajo nuestros pies","description":"Los suelos y la vida","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Un Universo invisible bajo nuestros pies - Los suelos y la vida","og:type":"article","og:title":"Gypsisoles (Gipsisoles) Geograf\u00eda Ambiente y Paisaje - Un Universo invisible bajo nuestros pies","og:description":"Karst de Yesos Sorbas Almer\u00eda, que necesariamente no implica la presencia de Gypsisoles. Fuente: Almer\u00eda Natura Los Gypsisoles (Gipsisoles) y Calcisoles se encuentran en un amplio rango de formaciones fisiogr\u00e1ficas, incluyendo pedimentos, fondos de lagos, terrazas y abanicos aluviales. Los Durisoles, con un horizonte D\u00farico o Petrod\u00farico que est\u00e1 endurecido por s\u00edlice (SiO2), no es exclusivo","og:url":"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/11\/14\/144679","og:image":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png","og:image:secure_url":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png","article:published_time":"2013-11-14T13:15:42+00:00","article:modified_time":"2013-11-29T13:10:58+00:00","article:publisher":"https:\/\/www.facebook.com\/juan.j.marti.14","twitter:card":"summary","twitter:title":"Gypsisoles (Gipsisoles) Geograf\u00eda Ambiente y Paisaje - Un Universo invisible bajo nuestros pies","twitter:description":"Karst de Yesos Sorbas Almer\u00eda, que necesariamente no implica la presencia de Gypsisoles. Fuente: Almer\u00eda Natura Los Gypsisoles (Gipsisoles) y Calcisoles se encuentran en un amplio rango de formaciones fisiogr\u00e1ficas, incluyendo pedimentos, fondos de lagos, terrazas y abanicos aluviales. Los Durisoles, con un horizonte D\u00farico o Petrod\u00farico que est\u00e1 endurecido por s\u00edlice (SiO2), no es exclusivo","twitter:image":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png"},"aioseo_meta_data":{"post_id":"144679","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":null,"isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","tabs":null,"priority":null,"frequency":null,"local_seo":null,"created":"2022-06-03 16:45:37","updated":"2026-05-26 17:49:01","limit_modified_date":false,"ai":null,"breadcrumb_settings":null,"seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/general\" title=\"General\">General<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tGypsisoles (Gipsisoles) Geograf\u00eda Ambiente y Paisaje\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.madrimasd.org\/blogs\/universo"},{"label":"General","link":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/general"},{"label":"Gypsisoles (Gipsisoles) Geograf\u00eda Ambiente y Paisaje","link":"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/11\/14\/144679"}],"_links":{"self":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts\/144679"}],"collection":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/users\/160"}],"replies":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/comments?post=144679"}],"version-history":[{"count":7,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts\/144679\/revisions"}],"predecessor-version":[{"id":144857,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts\/144679\/revisions\/144857"}],"wp:attachment":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/media?parent=144679"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/categories?post=144679"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/tags?post=144679"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}