{"id":145101,"date":"2014-06-15T14:58:07","date_gmt":"2014-06-15T13:58:07","guid":{"rendered":"http:\/\/www.madrimasd.org\/blogs\/universo\/?p=145101"},"modified":"2014-06-15T14:58:07","modified_gmt":"2014-06-15T13:58:07","slug":"tipos-de-chernozems-suelos-de-estepa-fria-y-sus-mapas-de-distribucion-en-europa","status":"publish","type":"post","link":"https:\/\/www.madrimasd.org\/blogs\/universo\/2014\/06\/15\/145101","title":{"rendered":"Tipos de Chernozems (Suelos de Estepa Fr\u00eda) y sus Mapas de Distribuci\u00f3n en Europa"},"content":{"rendered":"<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Con este post terminamos la serie dedicada a los\u00a0<\/span><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2014\/04\/26\/145061\"><span style=\"color: #0000ff; font-family: Calibri; font-size: medium;\">Chenozems<\/span><\/a><span style=\"color: #000000;\">. Ya os hablamos en un post precedente \u00a0(<\/span><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/07\/20\/136498\">Cartograf\u00eda de los Suelos de Europa en Im\u00e1genes<\/a><span style=\"color: #000000;\">) a cerca de la racionalidad de esta serie de post, por lo que entraremos a abundar en m\u00e1s detalles. Seguidamente, <\/span><strong><span style=\"color: #3366ff;\">os mostramos los mapas\u00a0de los seis edafotaxa que hasta ahora aparece en la base de datos de Europa (unidades al segundo nivel,<\/span> <span style=\"color: #3366ff;\">incluidas en el Grupo de Referencia de los Suelos de la WRB, 1998, FAO, <\/span><\/strong><span style=\"color: #000000;\">denominado<\/span><span style=\"color: #3366ff;\"><strong> Chernozems<\/strong><span style=\"color: #333333;\">)<\/span><\/span><span style=\"color: #000000;\">. Se trata de edafotaxa caracterizado por atesorar un horizonte \u00f3rgano-mineral profundo, rico en nutrientes y materia org\u00e1nica, por lo que es\u00a0 considerado uno de los Grupos de Suelos de Referencia de la WRB m\u00e1s f\u00e9rtiles del mundo. <\/span><\/p>\n<p style=\"text-align: justify;\">Las <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2009\/04\/10\/116218\"><span style=\"color: #0000ff; font-family: Calibri; font-size: medium;\">estepas de Eurasia<\/span><\/a>\u00a0<span style=\"color: #000000;\">resultan ser la regi\u00f3n biogeogr\u00e1fica en <strong><span style=\"color: #3366ff;\">donde los <\/span><\/strong><\/span><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2014\/05\/08\/145069\"><span style=\"color: #0000ff; font-family: Calibri; font-size: medium;\">Chernozems cubren la mayor extensi\u00f3n a nivel mundial<\/span><\/a><span style=\"color: #000000;\">. <\/span>En el continente Europeo<span style=\"color: #000000;\"> cabe mentar que los Chernozems son especialmente abundantes en el centro y especialmente el oeste, es decir en pa\u00edses como Ucrania, Rusia, Hungr\u00eda, y en menor medida en Rumania, Bulgaria, Austria, Rep\u00fablica Checa, Eslovaquia y Alemania. Cuatro de las subunidades de este Grupo de Suelos de Referencia aparecen en los pa\u00edses que constituyen la Uni\u00f3n Europea, mientras que otros dos tan solo la hacen en los estados orientales que lindan con la mentada mancomunidad de pa\u00edses y Asia. <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Los mapas que presentamos han sido llevados a cabo por <\/span><strong><span style=\"color: #3366ff;\">Eduardo Nieto y Elsa Mar\u00eda Benayas<\/span><\/strong><span style=\"color: #000000;\">, bajo la direcci\u00f3n de <\/span><span style=\"color: #3366ff;\"><strong>Rufino P\u00e9rez G\u00f3mez <\/strong><\/span><span style=\"color: #000000;\">(<\/span><a href=\"http:\/\/www.geo.upm.es\/\" target=\"_blank\">Departamento de Ingeniar\u00eda Topograf\u00eda y Cartograf\u00eda de la Universidad Polit\u00e9cnica de Madrid<\/a><span style=\"color: #000000;\">), a partir de la base de datos del<\/span> <span style=\"color: #3366ff;\"><strong>ESB<\/strong><\/span><span style=\"color: #000000;\">, por lo que no los encontrar\u00e9is en el <\/span><a href=\"http:\/\/eusoils.jrc.ec.europa.eu\/\" target=\"_blank\">European Soil <\/a><a href=\"http:\/\/eusoils.jrc.ec.europa.eu\/\" target=\"_blank\">Portal<\/a><span style=\"color: #000000;\">, al menos hasta que ellos lleven a cabo una iniciativa similar. Deb\u00e9is agradecer a Elsa, Eduardo y Rufino el enorme trabajo realizado para su elaboraci\u00f3n. Yo me limito a redactar y editar esta serie de post. Digamos finalmente, que los <span style=\"color: #3366ff;\"><strong>seis<\/strong> <strong>\u00a0tipos de Chenozems<\/strong> <\/span>(segundo nivel de la WEB 2006\/2007), son los que personalmente hemos detectado para el conjunto del continente al explotar mediante herramientas SIG la mencionada base de datos. Ya os aportamos m\u00e1s informaci\u00f3n al respecto <span style=\"color: #800000;\"><span style=\"color: #333333;\">en un post previo que llevaba el t\u00edtulo de <\/span><\/span><\/span><span style=\"color: #000000; font-family: Calibri; font-size: medium;\">\u201c<\/span><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2014\/06\/02\/145093\"><span style=\"color: #0000ff; font-family: Calibri; font-size: medium;\">Chernozems en Europa y Latinoam\u00e9rica<\/span><\/a><span style=\"color: #000000; font-family: Calibri; font-size: medium;\">\u201d<\/span><span style=\"color: #000000;\"> el cual os animamos a consultar con vistas a que obteng\u00e1is una informaci\u00f3n m\u00e1s detallada para el continente de este Grupo de Suelos de Referencia de la WRB. <\/span><\/p>\n<p align=\"center\"><img decoding=\"async\" class=\"ngg-singlepic ngg-center\" style=\"width: 397px; height: 384px;\" src=\"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-content\/blogs.dir\/42\/files\/mapas-de-los-suelos-de-europa-wrb\/chcc.jpg\" alt=\"chcc\" width=\"705\" height=\"705\" \/><\/p>\n<p align=\"center\"><span style=\"color: #0000ff;\">Chernozems c\u00e1lcicos (CHcc)<\/span><\/p>\n<p align=\"center\"><span style=\"color: #0000ff;\"><!--more--><\/span><\/p>\n<p align=\"center\"><img decoding=\"async\" class=\"ngg-singlepic ngg-center\" style=\"width: 391px; height: 354px;\" src=\"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-content\/blogs.dir\/42\/files\/mapas-de-los-suelos-de-europa-wrb\/chha.jpg\" alt=\"chha\" width=\"645\" height=\"645\" \/><\/p>\n<p align=\"center\"><span style=\"color: #0000ff;\">Chernozems h\u00e1plicos (CHha)<\/span><\/p>\n<p align=\"center\"><img decoding=\"async\" class=\"ngg-singlepic ngg-center\" style=\"width: 403px; height: 402px;\" src=\"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-content\/blogs.dir\/42\/files\/mapas-de-los-suelos-de-europa-wrb\/chlv.jpg\" alt=\"chlv\" width=\"599\" height=\"719\" \/><\/p>\n<p align=\"center\"><span style=\"color: #0000ff;\">Chernozems l\u00favicos (CHlv)<\/span><\/p>\n<p align=\"center\"><img decoding=\"async\" class=\"ngg-singlepic ngg-center\" style=\"width: 401px; height: 379px;\" src=\"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-content\/blogs.dir\/42\/files\/mapas-de-los-suelos-de-europa-wrb\/chgl.jpg\" alt=\"chgl\" width=\"681\" height=\"680\" \/><\/p>\n<p align=\"center\"><span style=\"color: #0000ff;\">Chernozems Gleicos (CHgl)<\/span><\/p>\n<p align=\"center\"><img decoding=\"async\" class=\"ngg-singlepic ngg-center\" style=\"width: 403px; height: 376px;\" src=\"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-content\/blogs.dir\/42\/files\/mapas-de-los-suelos-de-europa-wrb\/chgs.jpg\" alt=\"chgs\" width=\"735\" height=\"739\" \/><\/p>\n<p align=\"center\"><span style=\"color: #0000ff;\">Chernozems gl\u00f3sicos (CHgs)<\/span><\/p>\n<p align=\"center\"><img decoding=\"async\" class=\"ngg-singlepic ngg-center\" style=\"width: 417px; height: 367px;\" src=\"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-content\/blogs.dir\/42\/files\/mapas-de-los-suelos-de-europa-wrb\/chch.jpg\" alt=\"chch\" width=\"755\" height=\"751\" \/><\/p>\n<p align=\"center\"><span style=\"color: #0000ff;\">Chernozems ch\u00e9rnicos (CChc)<\/span><\/p>\n<p><span style=\"color: #008000;\"><strong>Juan Jos\u00e9 Ib\u00e1\u00f1ez<\/strong><\/span><\/p>\n<p><span style=\"color: #800000;\"><strong>Material\u00a0 Bibliogr\u00e1fico<\/strong><\/span><\/p>\n<p><a href=\"http:\/\/www.fao.org\/nr\/land\/soils\/soil\/en\">P\u00e1gina Web de la WRB<\/a><\/p>\n<p><a href=\"ftp:\/\/ftp.fao.org\/docrep\/fao\/011\/a0510s\/a0510s00.pdf\">Clasificaci\u00f3n WRB 2006-2007<\/a><\/p>\n<p><a href=\"http:\/\/www.fao.org\/DOCREP\/003\/Y1899E\/Y1899E00.HTM\">Lecture notes on the major soils of the world<\/a> (versi\u00f3n personal traducida al espa\u00f1ol por Javier Manr\u00edquez Cos\u00edo)<\/p>\n<p><a href=\"http:\/\/www.inegi.org.mx\/prod_serv\/contenidos\/espanol\/bvinegi\/productos\/integracion\/especiales\/BoletinSNEIG\/2010\/Bsnieg14_b.pdf\">Los suelos de Latinoam\u00e9rica: retos y oportunidades de uso y estudio<\/a> (ir al titulo correspondiente) Autores: Francisco Bautista, Alfred J. Zinck y Silke Cram. Bolet\u00edn del Sistema Nacional de Informaci\u00f3n Estad\u00edstica y Geogr\u00e1fica: VII(3) Septiembre-Diciembre 2009, p\u00e1ginas 94-142<\/p>\n<p><a href=\"http:\/\/eusoils.jrc.ec.europa.eu\/esdb_archive\/eusoils_docs\/other\/EUR23439.pdf\">Soils of the European Union<\/a> (en Ingles)<\/p>\n<p><span style=\"color: #800000;\"><strong>Post Previos de Nuestro\u00a0Breve de Nuestro Curso B\u00e1sico Tipos de Suelos del Mundo<\/strong><\/span><\/p>\n<p><span style=\"color: #000000;\">\u00a0<\/span><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/06\/23\/136471\">Los Suelos del Mundo y Su clasificaci\u00f3n (WRB). Curso B\u00e1sico sobre Clasificaci\u00f3n de Suelos<\/a><\/p>\n<p><span style=\"color: #000000;\">\u00a0<\/span><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/06\/28\/136476\">Suelos Minerales Condicionados por la Topograf\u00eda o Fisiograf\u00eda: Leptosoles, Regosoles, Fluvisoles y Gleysoles<\/a><\/p>\n<p><span style=\"color: #800000;\"><strong>Post Previos\u00a0 de Nuestro\u00a0Breve de Nuestro Curso B\u00e1sico Tipos de Suelos del Mundo hasta febrero\u00a0de 2014<\/strong><\/span><\/p>\n<p><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/06\/23\/136471\">Los Suelos del Mundo y Su clasificaci\u00f3n (WRB). Curso B\u00e1sico sobre Clasificaci\u00f3n de Suelos<\/a><\/p>\n<p><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/06\/28\/136476\">Suelos Minerales Condicionados por la Topograf\u00eda o Fisiograf\u00eda: Leptosoles, Regosoles, Fluvisoles y Gleysoles<\/a><\/p>\n<p><strong><span style=\"color: #000000;\">Leptosoles<\/span><\/strong><\/p>\n<p><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/07\/06\/136490\">Leptosoles<\/a><span style=\"color: #000000;\">;\u00a0<\/span><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/07\/13\/136682\">Leptosoles: Geograf\u00eda Ambiente y Paisaje<\/a><span style=\"color: #000000;\">;\u00a0<\/span><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/07\/28\/136691\">Leptosoles Uso y Manejo<\/a><span style=\"color: #000000;\">;<\/span><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/08\/04\/136695\">Leptosoles en Latinoam\u00e9rica<\/a><span style=\"color: #000000;\">;\u00a0<\/span><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/08\/11\/136703\">Leptosoles en Europa<\/a><span style=\"color: #000000;\">;\u00a0<\/span><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/08\/22\/136503\">Tipos de Leptosoles y sus Mapas de Distribuci\u00f3n en Europa<\/a><\/p>\n<p><strong><span style=\"color: #000000;\">Regosoles<\/span><\/strong><\/p>\n<p><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/09\/02\/136720\">Regosoles<\/a><span style=\"color: #000000;\">; \u00a0<\/span><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/09\/09\/136869\">Regosoles: Geograf\u00eda, Ambiente y Paisaje<\/a><span style=\"color: #000000;\">;\u00a0<\/span><a title=\"Enlace permanente a Regosoles: Uso y Manejo\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/09\/16\/136876\">Regosoles: Uso y Manejo<\/a><span style=\"color: #000000;\">:\u00a0<\/span><a title=\"Enlace permanente a Regosoles en Latinoam\u00e9rica\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/09\/24\/136882\">Regosoles en Latinoam\u00e9rica<\/a><span style=\"color: #000000;\">;\u00a0<\/span><a title=\"Enlace permanente a Regosoles en Europa\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/10\/28\/136908\">Regosoles en Europa<\/a><span style=\"color: #000000;\">;\u00a0<\/span><a title=\"Enlace permanente a Tipos de Regosoles y sus Mapas de Distribuci\u00f3n en Europa(WRB 1998)\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/11\/04\/136894\">Tipos de Regosoles y sus Mapas de Distribuci\u00f3n en Europa(WRB 1998)<\/a><\/p>\n<p><strong><span style=\"color: #000000;\">Fluvisoles<\/span><\/strong><\/p>\n<p><a title=\"Enlace permanente a Paisajes Aluviales No Costeros de las Redes Fluviales (WRB 1998)\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/01\/06\/137193\">Paisajes Aluviales No Costeros de las Redes Fluviales (WRB 1998)<\/a><span style=\"color: #000000;\">;\u00a0<\/span><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/01\/13\/137830\">Deltas, Estuarios y Marismas<\/a><span style=\"color: #000000;\">;\u00a0<\/span><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/01\/19\/137847\">Geoformas de las L\u00edneas de Costa Generadas por la Din\u00e1mica Marina (WRB-FAO 2000)<\/a><span style=\"color: #000000;\">,\u00a0<\/span><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/01\/26\/137868\">Fluvisoles<\/a><span style=\"color: #000000;\">,\u00a0<\/span><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/02\/02\/138188\">Fluvisoles ti\u00f3nicos<\/a><span style=\"color: #000000;\">,\u00a0<\/span><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/02\/01\/137894\">Distribuci\u00f3n geogr\u00e1fica de los Fluvisoles<\/a><span style=\"color: #000000;\">,\u00a0<\/span><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/02\/03\/137903\">Fluvisoles uso y manejo<\/a><span style=\"color: #000000;\">,\u00a0<\/span><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/02\/04\/137912\">Fluvisoles en Latinoam\u00e9rica<\/a><span style=\"color: #000000;\">,\u00a0<\/span><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/02\/07\/137923\">Fluvisoles en Europa<\/a><span style=\"color: #000000;\">,\u00a0<\/span><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/02\/08\/137936\">Mapas de los tipos de suelos de Europa (WRB 1998)<\/a><\/p>\n<p><span style=\"color: #000000;\">\u00a0<strong>Gleysoles<\/strong><\/span><\/p>\n<p><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/02\/16\/138132\">Gleysoles<\/a><span style=\"color: #000000;\">;\u00a0<\/span><a title=\"Enlace permanente a Gleysoles: Geograf\u00eda Ambiente y Paisaje\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/02\/24\/138158\">Gleysoles: Geograf\u00eda Ambiente y Paisaje<\/a><span style=\"color: #000000;\">\u00a0<\/span><a title=\"Enlace permanente a Gleysoles: Uso y Manejo\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/02\/25\/138174\">Gleysoles: Uso y Manejo<\/a><span style=\"color: #000000;\">,\u00a0<\/span><a title=\"Enlace permanente a Gleysoles en Latinoam\u00e9rica\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/02\/28\/138196\">Gleysoles en Latinoam\u00e9rica<\/a><span style=\"color: #000000;\">,\u00a0<\/span><a title=\"Enlace permanente a Gleysoles en Europa\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/03\/01\/138204\">Gleysoles en Europa<\/a><span style=\"color: #000000;\">,\u00a0<\/span><a title=\"Enlace permanente a Tipos de Gleysoles y sus Mapas de Distribuci\u00f3n en Europa\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/03\/03\/138117\">Tipos de Gleysoles y sus Mapas de Distribuci\u00f3n en Europa<\/a><\/p>\n<p><strong><span style=\"color: #000000;\">Stagnosoles (WRB 2006-2007)<\/span><\/strong><\/p>\n<p><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/03\/17\/138151\">Stagnosoles<\/a><\/p>\n<p><strong><span style=\"color: #000000;\">Histosoles<\/span><\/strong><\/p>\n<p><a title=\"Enlace permanente a Histosoles (WRB 1998): Las Turberas\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/03\/30\/138691\">Histosoles (WRB 1998): Las Turberas<\/a>; <a title=\"Enlace permanente a Histosoles (Turberas): Geograf\u00eda, Ambiente y Paisaje\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/04\/05\/138702\">Histosoles (Turberas): Geograf\u00eda, Ambiente y Paisaje<\/a>; <a title=\"Enlace permanente a Histosoles Uso y Manejo (Turberas) (WRB 1998)\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/04\/06\/138714\">Histosoles Uso y Manejo (Turberas) (WRB 1998)<\/a>; <a title=\"Enlace permanente a Histosoles en Latinoam\u00e9rica Tropical\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/04\/08\/138760\">Histosoles en Latinoam\u00e9rica Tropical<\/a>; <a title=\"Enlace permanente a Histosoles en Europa (Turberas)\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/04\/11\/138742\">Histosoles en Europa (Turberas)<\/a>; <a title=\"Enlace permanente a Tipos de Histosoles y sus Mapas de Distribuci\u00f3n en Europa (WRB 1998)\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/04\/20\/138751\">Tipos de Histosoles y sus Mapas de Distribuci\u00f3n en Europa (WRB 1998)<\/a><\/p>\n<p><strong><span style=\"color: #000000;\">Cambisoles<\/span><\/strong><\/p>\n<p><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/06\/09\/139388\">Cambisoles<\/a>; <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/06\/15\/139402\">Cambisoles: Geograf\u00eda Ambiente y Paisaje<\/a>; <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/06\/22\/139434\">Cambisoles: Uso y Manejo<\/a>; <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/06\/23\/139458\">Cambisoles en Latinoam\u00e9rica<\/a>;\u00a0 <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/06\/30\/139418\">Cambisoles en Europa<\/a>; <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/07\/07\/139426\">Tipos de Cambisoles y Sus Mapas de Distribuci\u00f3n en Europa<\/a><\/p>\n<p><strong><span style=\"color: #000000;\">Arenosoles<\/span><\/strong><\/p>\n<p><a title=\"Enlace permanente a Dunas y Paisajes Arenosos (WRB 1998)\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/07\/12\/139706\">Dunas y Paisajes Arenosos (WRB 1998)<\/a>; <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/07\/13\/139746\">Arenosoles<\/a>; <a title=\"Enlace permanente a Arenosoles: Geograf\u00eda Ambiente y Paisaje\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/07\/18\/139756\">Arenosoles: Geograf\u00eda; Ambiente y Paisaje<\/a>; <a title=\"Enlace permanente a Arenosoles: Uso y Manejo\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/07\/21\/139772\">Arenosoles: Uso y Manejo<\/a>; <a title=\"Enlace permanente a Arenosoles en Latinoam\u00e9rica\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/07\/28\/139786\">Arenosoles en Latinoam\u00e9rica<\/a>; <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/08\/04\/139794\">Arenosoles en Europa<\/a>; <a title=\"Enlace permanente a Tipos de Arenosoles y sus Mapas de Distribuci\u00f3n en Europa\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/08\/11\/139800\">Tipos de Arenosoles y sus Mapas de Distribuci\u00f3n en Europa<\/a><\/p>\n<p><strong><span style=\"color: #000000;\">Vertisoles<\/span><\/strong><\/p>\n<p><a title=\"Enlace permanente a Paisajes Arcillosos (WRB, 1998)\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/09\/29\/139981\">Paisajes Arcillosos (WRB, 1998)<\/a>, <a title=\"Enlace permanente a Microrelieve Gilgai  (Vertisoles, WRB, 1998)\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/10\/04\/140078\">Microrelieve Gilgai (Vertisoles, WRB, 1998)<\/a>, <a title=\"Enlace permanente a Vertisoles (WRB, 1998)\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/10\/06\/140062\">Vertisoles (WRB, 1998)<\/a>, <a title=\"Enlace permanente a Vertisoles: Geograf\u00eda, Ambiente y Paisaje\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/10\/13\/140087\">Vertisoles: Geograf\u00eda, Ambiente y Paisaje<\/a>, <a title=\"Enlace permanente a Vertisoles: Uso y Manejo\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/10\/21\/140108\">Vertisoles: Uso y Manejo<\/a>, <a title=\"Enlace permanente a Vertisoles en Latinoam\u00e9rica\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/10\/28\/140114\">Vertisoles en Latinoam\u00e9rica<\/a>, <a title=\"Enlace permanente a Vertisoles en La UE y el Continente Europeo\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/11\/01\/140049\">Vertisoles en La UE y el Continente Europeo<\/a>, <a title=\"Enlace permanente a Tipos de Vertisoles y sus Mapas de Distribuci\u00f3n en Europa\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/11\/11\/140053\">Tipos de Vertisoles y sus Mapas de Distribuci\u00f3n en Europa<\/a><\/p>\n<p><strong><span style=\"color: #000000;\">Andosoles<\/span><\/strong><\/p>\n<p><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/11\/16\/140617\">Paisajes Volc\u00e1nicos<\/a>, <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/11\/23\/140258\">Andosoles<\/a>, <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/12\/02\/140627\">Andosoles: geograf\u00eda ambiente y paisaje<\/a>, <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/12\/20\/140649\">Andosoles Uso y Manejo<\/a>, <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/01\/17\/140659\">Andosoles en Latinoam\u00e9rica<\/a>, <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/01\/25\/140135\">Andosoles en Europa<\/a>, <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/01\/25\/140135\">Andosoles en Europa\u00a0 y los Suelos de Islandia<\/a>, <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/02\/02\/140142\">Tipos de Andosoles y sus mapas de distribuci\u00f3n en Europa<\/a><\/p>\n<p><strong><span style=\"color: #000000;\">Luvisoles<\/span><\/strong><\/p>\n<p><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/02\/28\/141085\">Luvisoles<\/a>, <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/03\/15\/141095\">Luvisoles: geograf\u00eda ambiente y paisaje<\/a>, <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/03\/23\/141101\">Luvisoles Uso y Manejo<\/a>; <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/03\/27\/141109\">Luvisoles en Latinoam\u00e9rica<\/a>, <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/04\/03\/141236\">Luvisoles en Europa<\/a>, <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/04\/07\/141248\">Tipos de Luvisoles y sus mapas de distribuci\u00f3n en Europa<\/a>.<\/p>\n<p><strong><span style=\"color: #000000;\">Alisoles<\/span><\/strong><\/p>\n<p><a title=\"Enlace permanente a Alisoles (WRB, 1998)\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/04\/19\/141598\"><span style=\"font-family: Calibri;\">Alisoles (WRB, 1998)<\/span><\/a><span style=\"font-family: Calibri;\">; <\/span><a title=\"Enlace permanente a Alisoles: Geograf\u00eda Ambiente y Paisaje\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/04\/25\/141607\"><span style=\"font-family: Calibri;\">Alisoles: Geograf\u00eda Ambiente y Paisaje<\/span><\/a><span style=\"font-family: Calibri;\">, <\/span><a title=\"Enlace permanente: Alisoles: Uso y Manejo\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/05\/03\/141613\"><span style=\"font-family: Calibri;\">Alisoles: Uso y Manejo<\/span><\/a><\/p>\n<p><strong><span style=\"color: #000000;\">Lixisoles<\/span><\/strong><\/p>\n<p><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/05\/09\/141636\"><span style=\"font-family: Calibri;\">Lixisoles<\/span><\/a><span style=\"font-family: Calibri;\">; <\/span><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/05\/22\/141646\"><span style=\"font-family: Calibri;\">Lixisoles: Geograf\u00eda ambiente y paisaje<\/span><\/a><span style=\"font-family: Calibri;\">; <\/span><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/05\/31\/141657\"><span style=\"font-family: Calibri;\">Lixisoles: Uso y manejo<\/span><\/a><\/p>\n<p><strong><span style=\"color: #000000;\">Acrisoles<\/span><\/strong><\/p>\n<p><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/06\/07\/142059\">Acrisoles<\/a>, <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/06\/13\/142068\">Acrisoles: geograf\u00eda ambiente y paisaje<\/a>, <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/06\/20\/142080\">Acrisoles Uso y Manejo<\/a>, <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/07\/11\/142092\">Acrisoles en Latinoam\u00e9rica<\/a>, <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/06\/28\/142112\">Acrisoles en Europa<\/a>, <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/07\/05\/142118\">Tipos de Acrisoles y sus mapas de distribuci\u00f3n en Europa<\/a>.<\/p>\n<p><strong><span style=\"color: #000000;\">Albeluvisoles<\/span><\/strong><\/p>\n<p><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/07\/20\/142243\">Albeluvisoles<\/a>: <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/07\/27\/142257\">Albeluvisoles: Geograf\u00eda, Ambiente y Paisaje<\/a>; <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/08\/03\/142273\">Albeluvisoles: uso y manejo<\/a>; <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/08\/10\/142287\">Albeluvisoles en Europa<\/a>, <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/08\/10\/142287\">Albeluvisoles y sus mapas de distribuci\u00f3n en Europa<\/a>,<\/p>\n<p><strong><span style=\"color: #000000; font-family: Calibri;\">Podozoles<\/span><\/strong><\/p>\n<p><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/08\/24\/142310\"><span style=\"font-family: Calibri;\">Podzoles<\/span><\/a><span style=\"font-family: Calibri;\">, <\/span><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/09\/01\/142321\"><span style=\"font-family: Calibri;\">Podzoles: Geograf\u00eda, Ambiente y Paisaje<\/span><\/a><span style=\"font-family: Calibri;\">, <\/span><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/09\/07\/142329\"><span style=\"font-family: Calibri;\">Podzoles Uso y Manejo<\/span><\/a><span style=\"font-family: Calibri;\">, <\/span><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/09\/14\/142338\"><span style=\"font-family: Calibri;\">Podzoles en Europa,<\/span><\/a><a title=\"Enlace permanente a Tipos de Podzoles y sus Mapas de Distribuci\u00f3n en Europa\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/09\/21\/142344\">Tipos de Podzoles y sus Mapas de Distribuci\u00f3n en Europa<\/a>.<\/p>\n<p><strong><span style=\"color: #000000;\">Planosoles<\/span><\/strong><\/p>\n<p><a title=\"Enlace permanente a Planosoles WRB\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/09\/28\/142528\">Planosoles WRB<\/a>, <a title=\"Enlace permanente a Planosoles: Geograf\u00eda Ambiente y Paisaje\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/10\/04\/142544\">Planosoles: Geograf\u00eda Ambiente y Paisaje<\/a>, <a title=\"Enlace permanente a Planosoles: Uso y Manejo\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/10\/12\/142554\">Planosoles: Uso y Manejo<\/a>, <a title=\"Enlace permanente a Planosoles en Europa\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/10\/18\/142564\">Planosoles en Europa<\/a>, <a title=\"Enlace permanente a Planosoles en Latinoam\u00e9rica\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/10\/25\/142569\">Planosoles en Latinoam\u00e9rica<\/a>, <a title=\"Enlace permanente a Tipos de Planosoles y sus Mapas de Distribuci\u00f3n en Europa\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/11\/02\/142577\">Tipos de Planosoles y sus Mapas de Distribuci\u00f3n en Europa<\/a>.<\/p>\n<p><strong><span style=\"color: #000000;\">Criosoles<\/span><\/strong><\/p>\n<p><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/11\/08\/142393\">Criosoles WRB<\/a>, <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/11\/20\/142421\">Criosoles: Geograf\u00eda, Ambiente y Paisaje<\/a>, <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/11\/27\/142435\">Criosoles: Uso y Manejo<\/a>, <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/12\/05\/142451\">Criosoles en Europa y la Ant\u00e1rtida<\/a>, <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/12\/21\/142457\">Criosoles: Mapas de Distribuci\u00f3n en Europa<\/a>.<\/p>\n<p><strong><span style=\"color: #000000; font-family: Calibri;\">Umbrisoles<\/span><\/strong><\/p>\n<p><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/01\/09\/142763\"><span style=\"font-family: Calibri;\">Umbrisoles WRB,<\/span><\/a><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/01\/16\/142805\"><span style=\"font-family: Calibri;\">Umbrisoles: Geograf\u00eda Ambiente y Paisaje<\/span><\/a><span style=\"font-family: Calibri;\">, <\/span><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/01\/25\/143713\"><span style=\"font-family: Calibri;\">Umbrisoles: Uso y Manejo<\/span><\/a><span style=\"font-family: Calibri;\">, <\/span><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/01\/31\/142896\"><span style=\"font-family: Calibri;\">Umbrisoles en Europa<\/span><\/a><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/02\/06\/142903\"><span style=\"font-family: Calibri;\">, Tipo de Umbrisoles en Europa y sus Mapas de Distribuci\u00f3n<\/span><\/a><span style=\"font-family: Calibri;\">. <\/span><\/p>\n<p><strong><span style=\"color: #000000;\">Calcisoles<\/span><\/strong><\/p>\n<p><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/02\/13\/143541\"><span style=\"font-family: Calibri;\">Calcisoles WRB<\/span><\/a><span style=\"font-family: Calibri;\">, <\/span><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/02\/20\/143555\"><span style=\"font-family: Calibri;\">Calcisoles: Geograf\u00eda Ambiente y Paisaje<\/span><\/a><span style=\"font-family: Calibri;\">; <\/span><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/02\/27\/143561\"><span style=\"font-family: Calibri;\">Calcisoles: Uso y manejo<\/span><\/a><span style=\"font-family: Calibri;\">; <\/span><a title=\"Enlace permanente: Calcisoles en Latinoam\u00e9rica (WRB)\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/03\/06\/143596\">Calcisoles en Latinoam\u00e9rica (WRB)<\/a>; <a title=\"Enlace permanente a Calcisoles en Europa (WRB)\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/03\/13\/143575\">Calcisoles en Europa<\/a>; <a title=\"Enlace permanente a Calcisoles (WRB): Mapas de Distribuci\u00f3n en Europa\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/03\/20\/143587\">Calcisoles: Mapas de Distribuci\u00f3n en Europa<\/a>;<\/p>\n<p><strong><span style=\"color: #000000;\">Nitisoles (Nitosoles)<\/span><\/strong><\/p>\n<p><a title=\"Enlace permanente a Nitisoles (WRB)\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/03\/30\/143790\"><span style=\"font-family: Calibri;\">Nitisoles (WRB)<\/span><\/a><span style=\"font-family: Calibri;\">; <\/span><a title=\"Enlace permanente a Nitisoles o Nitosoles: Geograf\u00eda Ambiente y Paisaje (Suelos Ferral\u00edticos)\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/04\/06\/143803\"><span style=\"font-family: Calibri;\">Nitisoles o Nitosoles: Geograf\u00eda Ambiente y Paisaje (Suelos Ferral\u00edticos)<\/span><\/a><span style=\"font-family: Calibri;\">; <\/span><a title=\"Enlace permanente a Nitisoles (Nitosoles): Uso y Manejo (Suelos Ferral\u00edticos)\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/04\/10\/143811\"><span style=\"font-family: Calibri;\">Nitisoles (Nitosoles): Uso y Manejo (Suelos Ferral\u00edticos)<\/span><\/a><span style=\"font-family: Calibri;\">; <\/span><a title=\"Enlace permanente a Nitisoles (Nitosoles) en Latinoam\u00e9rica (Suelos Ferral\u00edticos)\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/04\/18\/143817\"><span style=\"font-family: Calibri;\">Nitisoles (Nitosoles) en Latinoam\u00e9rica (Suelos Ferral\u00edticos)<\/span><\/a><span style=\"font-family: Calibri;\">;<\/span><\/p>\n<p><strong><span style=\"color: #000000;\">Ferralsoles<\/span><\/strong><\/p>\n<p><a title=\"Enlace permanente a Ferralsoles (WRB)\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/04\/25\/143832\">Ferralsoles (WRB)<\/a>; <a title=\"Enlace permanente a Ferralsoles: Geograf\u00eda, Ambiente y Paisaje (Suelos Tropicales)\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/05\/02\/143842\">Ferralsoles: Geograf\u00eda, Ambiente y Paisaje (Suelos Tropicales)<\/a>; <a title=\"Enlace permanente a Ferralsoles: Uso y Manejo (WRB)\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/05\/09\/143848\">Ferralsoles: Uso y Manejo (WRB)<\/a>, <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/05\/17\/143874\">Ferralsoles en Latinoam\u00e9rica<\/a>, <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/07\/15\/143863\">Paisajes Geomorfol\u00f3gicos de los Tr\u00f3picos H\u00famedos y Subh\u00famedos (Geoformas)<\/a>,<\/p>\n<p><strong><span style=\"color: #000000;\">Plintosoles<\/span><\/strong><\/p>\n<p><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/06\/17\/143891\">Plintosoles (WRB) Suelos con Plintita<\/a>, <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/06\/26\/143907\">Plintosoles: Geograf\u00eda, Ambiente y paisaje<\/a>, <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/07\/06\/143914\">Plintosoles Uso y Manejo<\/a>, <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/07\/11\/143929\">Plintosoles (Plintosoles) en Latinoam\u00e9rica<\/a>,<\/p>\n<p><strong><span style=\"color: #000000;\">Durisoles<\/span><\/strong><\/p>\n<p><a title=\"Enlace permanente a Durisoles (WRB) Suelos Con Horizontes Endurecidos\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/09\/18\/144494\">Durisoles (WRB) Suelos Con Horizontes Endurecidos<\/a>; <a title=\"Enlace permanente a Durisoles: Geograf\u00eda, ambiente y paisaje\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/09\/28\/144500\">Durisoles: Geograf\u00eda, ambiente y paisaje<\/a>; <a title=\"Enlace permanente a Durisoles: Uso y Manejo\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/10\/24\/144508\">Durisoles: Uso y Manejo<\/a>; <a title=\"Enlace permanente a Durisoles en Latinoam\u00e9rica y Europa\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/10\/31\/144519\">Durisoles en Latinoam\u00e9rica y Europa<\/a><\/p>\n<p><strong><span style=\"color: #000000;\">Gypsisoles (Gipsisoles)<\/span><\/strong><\/p>\n<p><a title=\"Enlace permanente a Gypsisoles o Gipsisoles (WRB): Suelos con yeso Edafogen\u00e9tico\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/11\/07\/144670\">Gypsisoles o Gipsisoles (WRB): Suelos con yeso Edafogen\u00e9tico<\/a>, <a title=\"Enlace permanente: Durisoles: Geograf\u00eda, ambiente y paisaje\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/09\/28\/144500\">Durisoles: Geograf\u00eda, ambiente y paisaje<\/a>, <a title=\"Enlace permanente: Durisoles: Uso y Manejo\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/10\/24\/144508\">Durisoles: Uso y Manejo<\/a>, <a title=\"Enlace permanente: Durisoles en Latinoam\u00e9rica y Europa\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/10\/31\/144519\">Durisoles en Latinoam\u00e9rica y Europa<\/a><\/p>\n<p><strong><span style=\"color: #000000;\">Solonchaks (Suelos Salinos)<\/span><\/strong><\/p>\n<p><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/12\/17\/144776\"><span style=\"color: #0000ff;\">Solonchaks o Suelos Salinos (WRB)<\/span><\/a><span style=\"color: #000000;\">, Solonetz: Geograf\u00eda Ambiente y Paisaje, Solonetz en Latinoam\u00e9rica. <\/span><\/p>\n<h3>Im\u00e1genes Relacionadas:<\/h3>","protected":false},"excerpt":{"rendered":"<p>Con este post terminamos la serie dedicada a los\u00a0Chenozems. Ya os hablamos en un post precedente \u00a0(Cartograf\u00eda de los Suelos de Europa en Im\u00e1genes) a cerca de la racionalidad de esta serie de post, por lo que entraremos a abundar en m\u00e1s detalles. Seguidamente, os mostramos los mapas\u00a0de los seis edafotaxa que hasta ahora aparece en la base de datos de Europa (unidades al segundo nivel, incluidas en el Grupo de Referencia de los Suelos de la WRB, 1998, FAO, denominado Chernozems). Se trata de edafotaxa caracterizado por atesorar un horizonte \u00f3rgano-mineral profundo, rico en nutrientes y materia org\u00e1nica, por\u2026<\/p>\n","protected":false},"author":26,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0},"categories":[1929,604],"tags":[47535,46744,1950,2051],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":4}},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Con este post terminamos la serie dedicada a los Chenozems. Ya os hablamos en un post precedente (Cartograf\u00eda de los Suelos de Europa en Im\u00e1genes) a cerca de la racionalidad de esta serie de post, por lo que entraremos a abundar en m\u00e1s detalles. Seguidamente, os mostramos los mapas de los seis edafotaxa que hasta ahora aparece\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Juan Jos\u00e9 Ib\u00e1\u00f1ez\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2014\/06\/15\/145101\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Un Universo invisible bajo nuestros pies - Los suelos y la vida\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Tipos de Chernozems (Suelos de Estepa Fr\u00eda) y sus Mapas de Distribuci\u00f3n en Europa - Un Universo invisible bajo nuestros pies\" \/>\n\t\t<meta property=\"og:description\" content=\"Con este post terminamos la serie dedicada a los Chenozems. Ya os hablamos en un post precedente (Cartograf\u00eda de los Suelos de Europa en Im\u00e1genes) a cerca de la racionalidad de esta serie de post, por lo que entraremos a abundar en m\u00e1s detalles. Seguidamente, os mostramos los mapas de los seis edafotaxa que hasta ahora aparece\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2014\/06\/15\/145101\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2014-06-15T13:58:07+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2014-06-15T13:58:07+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/juan.j.marti.14\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Tipos de Chernozems (Suelos de Estepa Fr\u00eda) y sus Mapas de Distribuci\u00f3n en Europa - Un Universo invisible bajo nuestros pies\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Con este post terminamos la serie dedicada a los Chenozems. Ya os hablamos en un post precedente (Cartograf\u00eda de los Suelos de Europa en Im\u00e1genes) a cerca de la racionalidad de esta serie de post, por lo que entraremos a abundar en m\u00e1s detalles. Seguidamente, os mostramos los mapas de los seis edafotaxa que hasta ahora aparece\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2014\\\/06\\\/15\\\/145101#blogposting\",\"name\":\"Tipos de Chernozems (Suelos de Estepa Fr\\u00eda) y sus Mapas de Distribuci\\u00f3n en Europa - Un Universo invisible bajo nuestros pies\",\"headline\":\"Tipos de Chernozems (Suelos de Estepa Fr\\u00eda) y sus Mapas de Distribuci\\u00f3n en Europa\",\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"http:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/wp-content\\\/blogs.dir\\\/42\\\/files\\\/mapas-de-los-suelos-de-europa-wrb\\\/chcc.jpg\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2014\\\/06\\\/15\\\/145101\\\/#articleImage\"},\"datePublished\":\"2014-06-15T14:58:07+01:00\",\"dateModified\":\"2014-06-15T14:58:07+01:00\",\"inLanguage\":\"es-ES\",\"commentCount\":1,\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2014\\\/06\\\/15\\\/145101#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2014\\\/06\\\/15\\\/145101#webpage\"},\"articleSection\":\"Curso B\\u00e1sico: Tipos de Suelos del Mundo, Geograf\\u00eda de Suelos y Megaedafolog\\u00eda, Chernozems, geograf\\u00eda de suelos, Mapas de Suelos de Europa, suelos de estepa\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2014\\\/06\\\/15\\\/145101#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/geografia-de-suelos-y-megaedafologia#listItem\",\"name\":\"Geograf\\u00eda de Suelos y Megaedafolog\\u00eda\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/geografia-de-suelos-y-megaedafologia#listItem\",\"position\":2,\"name\":\"Geograf\\u00eda de Suelos y Megaedafolog\\u00eda\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/geografia-de-suelos-y-megaedafologia\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2014\\\/06\\\/15\\\/145101#listItem\",\"name\":\"Tipos de Chernozems (Suelos de Estepa Fr\\u00eda) y sus Mapas de Distribuci\\u00f3n en Europa\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2014\\\/06\\\/15\\\/145101#listItem\",\"position\":3,\"name\":\"Tipos de Chernozems (Suelos de Estepa Fr\\u00eda) y sus Mapas de Distribuci\\u00f3n en Europa\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/geografia-de-suelos-y-megaedafologia#listItem\",\"name\":\"Geograf\\u00eda de Suelos y Megaedafolog\\u00eda\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#organization\",\"name\":\"Un Universo invisible bajo nuestros pies\",\"description\":\"Los suelos y la vida\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/files\\\/2022\\\/02\\\/logo.png\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2014\\\/06\\\/15\\\/145101\\\/#organizationLogo\",\"width\":217,\"height\":72},\"image\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2014\\\/06\\\/15\\\/145101\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/juan.j.marti.14\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo\",\"name\":\"Juan Jos\\u00e9 Ib\\u00e1\\u00f1ez\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2014\\\/06\\\/15\\\/145101#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/387f3a100385573d8f42ce2a3211fd1c?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Juan Jos\\u00e9 Ib\\u00e1\\u00f1ez\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2014\\\/06\\\/15\\\/145101#webpage\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2014\\\/06\\\/15\\\/145101\",\"name\":\"Tipos de Chernozems (Suelos de Estepa Fr\\u00eda) y sus Mapas de Distribuci\\u00f3n en Europa - Un Universo invisible bajo nuestros pies\",\"description\":\"Con este post terminamos la serie dedicada a los Chenozems. Ya os hablamos en un post precedente (Cartograf\\u00eda de los Suelos de Europa en Im\\u00e1genes) a cerca de la racionalidad de esta serie de post, por lo que entraremos a abundar en m\\u00e1s detalles. Seguidamente, os mostramos los mapas de los seis edafotaxa que hasta ahora aparece\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2014\\\/06\\\/15\\\/145101#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\"},\"datePublished\":\"2014-06-15T14:58:07+01:00\",\"dateModified\":\"2014-06-15T14:58:07+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#website\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/\",\"name\":\"Un Universo invisible bajo nuestros pies\",\"description\":\"Los suelos y la vida\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Tipos de Chernozems (Suelos de Estepa Fr\u00eda) y sus Mapas de Distribuci\u00f3n en Europa - Un Universo invisible bajo nuestros pies","description":"Con este post terminamos la serie dedicada a los Chenozems. Ya os hablamos en un post precedente (Cartograf\u00eda de los Suelos de Europa en Im\u00e1genes) a cerca de la racionalidad de esta serie de post, por lo que entraremos a abundar en m\u00e1s detalles. Seguidamente, os mostramos los mapas de los seis edafotaxa que hasta ahora aparece","canonical_url":"https:\/\/www.madrimasd.org\/blogs\/universo\/2014\/06\/15\/145101","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2014\/06\/15\/145101#blogposting","name":"Tipos de Chernozems (Suelos de Estepa Fr\u00eda) y sus Mapas de Distribuci\u00f3n en Europa - Un Universo invisible bajo nuestros pies","headline":"Tipos de Chernozems (Suelos de Estepa Fr\u00eda) y sus Mapas de Distribuci\u00f3n en Europa","author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author"},"publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#organization"},"image":{"@type":"ImageObject","url":"http:\/\/www.madrimasd.org\/blogs\/universo\/wp-content\/blogs.dir\/42\/files\/mapas-de-los-suelos-de-europa-wrb\/chcc.jpg","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2014\/06\/15\/145101\/#articleImage"},"datePublished":"2014-06-15T14:58:07+01:00","dateModified":"2014-06-15T14:58:07+01:00","inLanguage":"es-ES","commentCount":1,"mainEntityOfPage":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2014\/06\/15\/145101#webpage"},"isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2014\/06\/15\/145101#webpage"},"articleSection":"Curso B\u00e1sico: Tipos de Suelos del Mundo, Geograf\u00eda de Suelos y Megaedafolog\u00eda, Chernozems, geograf\u00eda de suelos, Mapas de Suelos de Europa, suelos de estepa"},{"@type":"BreadcrumbList","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2014\/06\/15\/145101#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo#listItem","position":1,"name":"Home","item":"https:\/\/www.madrimasd.org\/blogs\/universo","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/geografia-de-suelos-y-megaedafologia#listItem","name":"Geograf\u00eda de Suelos y Megaedafolog\u00eda"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/geografia-de-suelos-y-megaedafologia#listItem","position":2,"name":"Geograf\u00eda de Suelos y Megaedafolog\u00eda","item":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/geografia-de-suelos-y-megaedafologia","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2014\/06\/15\/145101#listItem","name":"Tipos de Chernozems (Suelos de Estepa Fr\u00eda) y sus Mapas de Distribuci\u00f3n en Europa"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2014\/06\/15\/145101#listItem","position":3,"name":"Tipos de Chernozems (Suelos de Estepa Fr\u00eda) y sus Mapas de Distribuci\u00f3n en Europa","previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/geografia-de-suelos-y-megaedafologia#listItem","name":"Geograf\u00eda de Suelos y Megaedafolog\u00eda"}}]},{"@type":"Organization","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#organization","name":"Un Universo invisible bajo nuestros pies","description":"Los suelos y la vida","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/","logo":{"@type":"ImageObject","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2014\/06\/15\/145101\/#organizationLogo","width":217,"height":72},"image":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2014\/06\/15\/145101\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/juan.j.marti.14"]},{"@type":"Person","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo","name":"Juan Jos\u00e9 Ib\u00e1\u00f1ez","image":{"@type":"ImageObject","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2014\/06\/15\/145101#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/387f3a100385573d8f42ce2a3211fd1c?s=96&d=mm&r=g","width":96,"height":96,"caption":"Juan Jos\u00e9 Ib\u00e1\u00f1ez"}},{"@type":"WebPage","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2014\/06\/15\/145101#webpage","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/2014\/06\/15\/145101","name":"Tipos de Chernozems (Suelos de Estepa Fr\u00eda) y sus Mapas de Distribuci\u00f3n en Europa - Un Universo invisible bajo nuestros pies","description":"Con este post terminamos la serie dedicada a los Chenozems. Ya os hablamos en un post precedente (Cartograf\u00eda de los Suelos de Europa en Im\u00e1genes) a cerca de la racionalidad de esta serie de post, por lo que entraremos a abundar en m\u00e1s detalles. Seguidamente, os mostramos los mapas de los seis edafotaxa que hasta ahora aparece","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#website"},"breadcrumb":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2014\/06\/15\/145101#breadcrumblist"},"author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author"},"creator":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author"},"datePublished":"2014-06-15T14:58:07+01:00","dateModified":"2014-06-15T14:58:07+01:00"},{"@type":"WebSite","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#website","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/","name":"Un Universo invisible bajo nuestros pies","description":"Los suelos y la vida","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Un Universo invisible bajo nuestros pies - Los suelos y la vida","og:type":"article","og:title":"Tipos de Chernozems (Suelos de Estepa Fr\u00eda) y sus Mapas de Distribuci\u00f3n en Europa - Un Universo invisible bajo nuestros pies","og:description":"Con este post terminamos la serie dedicada a los Chenozems. Ya os hablamos en un post precedente (Cartograf\u00eda de los Suelos de Europa en Im\u00e1genes) a cerca de la racionalidad de esta serie de post, por lo que entraremos a abundar en m\u00e1s detalles. Seguidamente, os mostramos los mapas de los seis edafotaxa que hasta ahora aparece","og:url":"https:\/\/www.madrimasd.org\/blogs\/universo\/2014\/06\/15\/145101","og:image":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png","og:image:secure_url":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png","article:published_time":"2014-06-15T13:58:07+00:00","article:modified_time":"2014-06-15T13:58:07+00:00","article:publisher":"https:\/\/www.facebook.com\/juan.j.marti.14","twitter:card":"summary","twitter:title":"Tipos de Chernozems (Suelos de Estepa Fr\u00eda) y sus Mapas de Distribuci\u00f3n en Europa - Un Universo invisible bajo nuestros pies","twitter:description":"Con este post terminamos la serie dedicada a los Chenozems. Ya os hablamos en un post precedente (Cartograf\u00eda de los Suelos de Europa en Im\u00e1genes) a cerca de la racionalidad de esta serie de post, por lo que entraremos a abundar en m\u00e1s detalles. Seguidamente, os mostramos los mapas de los seis edafotaxa que hasta ahora aparece","twitter:image":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png"},"aioseo_meta_data":{"post_id":"145101","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":null,"isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","tabs":null,"priority":null,"frequency":null,"local_seo":null,"created":"2022-06-03 16:54:45","updated":"2026-05-26 18:02:48","limit_modified_date":false,"ai":null,"breadcrumb_settings":null,"seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/geografia-de-suelos-y-megaedafologia\" title=\"Geograf\u00eda de Suelos y Megaedafolog\u00eda\">Geograf\u00eda de Suelos y Megaedafolog\u00eda<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tTipos de Chernozems (Suelos de Estepa Fr\u00eda) y sus Mapas de Distribuci\u00f3n en Europa\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.madrimasd.org\/blogs\/universo"},{"label":"Geograf\u00eda de Suelos y Megaedafolog\u00eda","link":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/geografia-de-suelos-y-megaedafologia"},{"label":"Tipos de Chernozems (Suelos de Estepa Fr\u00eda) y sus Mapas de Distribuci\u00f3n en Europa","link":"https:\/\/www.madrimasd.org\/blogs\/universo\/2014\/06\/15\/145101"}],"_links":{"self":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts\/145101"}],"collection":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/comments?post=145101"}],"version-history":[{"count":10,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts\/145101\/revisions"}],"predecessor-version":[{"id":145741,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts\/145101\/revisions\/145741"}],"wp:attachment":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/media?parent=145101"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/categories?post=145101"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/tags?post=145101"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}