{"id":145109,"date":"2014-08-09T18:43:15","date_gmt":"2014-08-09T17:43:15","guid":{"rendered":"http:\/\/www.madrimasd.org\/blogs\/universo\/?p=145109"},"modified":"2014-08-09T18:46:43","modified_gmt":"2014-08-09T17:46:43","slug":"ingenieros-y-selvicultores-del-suelo","status":"publish","type":"post","link":"https:\/\/www.madrimasd.org\/blogs\/universo\/2014\/08\/09\/145109","title":{"rendered":"\u00bfIngenieros y Selvicultores del Suelo?"},"content":{"rendered":"<p style=\"text-align: center;\"><img decoding=\"async\" class=\"ngg-singlepic ngg-center alignleft\" src=\"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-content\/blogs.dir\/42\/files\/163\/ecologia-del-suelo-fuente-blog-ecologia.jpg\" alt=\"ecologia-del-suelo-fuente-blog-ecologia\" \/><\/p>\n<p style=\"text-align: center;\"><a href=\"http:\/\/aldiaenecologia.blogspot.com.es\/2008_10_01_archive.html\">Ecolog\u00eda del Suelo Micorrizas; Fuente: Blog Ecolog\u00eda<\/a><\/p>\n<p style=\"text-align: justify;\">Hoy no voy a comentar, sino mostrar una noticia que apareci\u00f3 en el bolet\u00edn \u00a0mi+d reproducida de <a href=\"http:\/\/www.upm.es\/institucional\/UPM\/CanalUPM\/Noticias\/b5d1d18323973410VgnVCM10000009c7648aRCRD\"><span style=\"color: #0000ff;\">una p\u00e1gina Web de la UPM<\/span><\/a>. Francamente no s\u00e9 qu\u00e9 pensar, es decir dudo si se trata de un tema interesante o simplemente de una mera conjetura. El tema estriba en que no logro entender una buena parte del texto de la noticia. Francamente su redacci\u00f3n se me antoja farragosa, confusa y confundente. No obstante, atesora algunos p\u00e1rrafos que pudieran ser muy interesantes en lo concerniente a la estructura y din\u00e1mica ecol\u00f3gica de los suelos. Posiblemente, los m\u00e1s versados en el tema extraig\u00e1is m\u00e1s sustancia que la que yo os puedo ofrecer. Si rogar\u00eda a los autores del estudio que, en materia de divulgaci\u00f3n cient\u00edfica, sean m\u00e1s directos, eludan en lo posible tecnicismos y especialmente mejoren la redacci\u00f3n de sus textos. La cuesti\u00f3n estriba en que si analizo p\u00e1rrafo por p\u00e1rrafo detecto tanto \u201caparentes\u201d o \u201creales\u201d contradicciones, como generalizaciones posiblemente infundadas, etc. sin saber, a \u201cciencia cierta\u201d, que tiene realmente el estudio de novedoso y que de ret\u00f3rica. Del mismo modo a\u00f1adir otro nuevo palabro a la pl\u00e9tora de los ya existentes abunda en la ceremonia de la confusi\u00f3n<strong>. <span style=\"color: #3366ff;\">El concepto de <\/span><\/strong><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2007\/06\/04\/67011\"><span style=\"color: #0000ff; font-family: Calibri; font-size: medium;\">Ingenieros del suelo<\/span><\/a>\u00a0<strong><span style=\"color: #3366ff;\">ya se encuentra plenamente enraizado en la bibliograf\u00eda. \u00a0\u00bfAporta algo a\u00f1adir el de selvicultores del suelo?. \u00a1No! \u00a1pura ret\u00f3rica!<\/span><\/strong> Por todo ello he a\u00f1adido enlaces a los trabajos que mentan, y\/o sus res\u00famenes, con vistas a que los interesados en el tema profundicen un poco m\u00e1s. En el sitio <a href=\"https:\/\/www.researchgate.net\/profile\/Luis_Garcia-Montero\/\"><span style=\"color: #0000ff;\">Researchgate de Luis G Garc\u00eda Montero<\/span><\/a>, obtendr\u00e9is m\u00e1s informaci\u00f3n.<\/p>\n<p><strong><!--more--><\/strong><\/p>\n<h3 style=\"text-align: justify;\"><a href=\"http:\/\/www.madrimasd.org\/informacionidi\/noticias\/noticia.asp?id=59032&amp;origen=notiweb_suplemento&amp;dia_suplemento=lunes&amp;seccion=noticiaslunes\"><strong><span style=\"color: #0000ff;\">Hongos y lombrices act\u00faan como selvicultores<\/span><\/strong><\/a><\/h3>\n<p style=\"text-align: justify;\"><strong>Investigadores de la <\/strong><a title=\"Universidad Polit\u00e9cnica de Madrid\" href=\"http:\/\/www.upm.es\/\" target=\"_blank\"><strong>Universidad Polit\u00e9cnica de Madrid<\/strong><\/a><strong> proponen un modelo de fijaci\u00f3n del carbono asociado al calcio, a diversos hongos y a las lombrices que, adem\u00e1s, potencia el desarrollo de los bosques. <\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>FUENTE | UPM &#8211; mi+d 13\/01\/2014<\/strong><\/p>\n<p style=\"text-align: justify;\">\u00a0El modelo, que ha sido desarrollado por un grupo de investigaci\u00f3n de la <a title=\"Escuela T\u00e9cnica Superior de Ingenieros de Montes\" href=\"http:\/\/www.montes.upm.es\/ETSIMontes\" target=\"_blank\">Escuela T\u00e9cnica Superior de Ingenieros de Montes<\/a> de la <strong>UPM<\/strong>, muestra c\u00f3mo <strong>ciertas especies de hongos (como trufas, boletos o n\u00edscalos), asociados a las lombrices de tierra, desarrollan un mecanismo de &#8216;ingenier\u00eda ambiental&#8217; con el que incrementan los niveles de calcio y sus sales entre las ra\u00edces de los \u00e1rboles, lo que produce un aumento en la micorrizaci\u00f3n de los \u00e1rboles y en el desarrollo del bosque<\/strong>. Este fen\u00f3meno parece que sucede a gran escala en los <strong>bosques templados del planeta<\/strong>, lo que puede tener una fuerte repercusi\u00f3n en la fijaci\u00f3n del carbono y en la gesti\u00f3n forestal.<\/p>\n<p style=\"text-align: justify;\"><strong>Uno de los enigmas que encierra la rizosfera de muchos bosques es la acumulaci\u00f3n de calcio y sus sales (carbonatos y oxalatos) entre las ra\u00edces de los \u00e1rboles<\/strong>. Este fen\u00f3meno sorprende debido a su magnitud a escala global, por las caracter\u00edsticas de muchos suelos donde se produce, y porque <strong>podr\u00eda tener un impacto en la fijaci\u00f3n del carbono. Sin embargo, los mecanismos que explican este proceso no hab\u00edan sido clarificados hasta ahora<\/strong>.<\/p>\n<p>Recientemente un grupo de investigadores de la Universidad de Lausanne han propuesto un interesante modelo <strong>de &#8216;transformaci\u00f3n de la luz del sol en rocas&#8217;<\/strong> <strong>a trav\u00e9s de un proceso de biomineralizaci\u00f3n<\/strong>. Se trata de un fen\u00f3meno raro <strong>provocado por una interacci\u00f3n entre el oxalato y el carbonato de calcio de la rizosfera<\/strong>, que estar\u00eda promovido por la fotos\u00edntesis y actividad de las ra\u00edces <a href=\"http:\/\/es.wikipedia.org\/wiki\/Iroko\"><span style=\"color: #0000ff;\">de un \u00e1rbol africano (el iroko)<\/span><\/a> y la disponibilidad de calcio en el suelo, junto a la acci\u00f3n c\u00f3mplice de las <strong>termitas y los hongos saprof\u00edticos<\/strong> que se asocian a este \u00e1rbol. As\u00ed, el <strong><em>&#8216;modelo del iroko&#8217;<\/em><\/strong> representar\u00eda <strong>un &#8216;ecosistema-trampa del carbono &#8216;que fijar\u00eda este elemento a largo plazo en forma de carbonato en su rizosfera<\/strong>.<\/p>\n<p>En paralelo, <strong>el grupo de investigaci\u00f3n de la UPM <\/strong>\u00a0<a title=\"Defensa y aprovechamiento del medio natural\" href=\"http:\/\/www.upm.es\/observatorio\/vi\/index.jsp?pageac=grupo.jsp&amp;idGrupo=240\" target=\"_blank\">Defensa y aprovechamiento del medio natural<\/a>, <strong>ha propuesto otro modelo de fijaci\u00f3n del carbono asociado al calcio (Ca) y a diversos hongos ectomicorr\u00edcicos (ECMs)<\/strong>, que son un tipo de micorrizas que <strong>dominan en los bosques templados y que incluyen<\/strong> a las trufas, boletos, n\u00edscalos y otros hongos populares. El &#8216;<em>modelo del Ca-ECMs&#8217; <\/em><strong>tambi\u00e9n estar\u00eda asociado con otros organismos presentes en la rizosfera -como las lombrices- en bosques europeos y norteamericanos<\/strong>. Este modelo <strong>ser\u00eda comparable al <em>&#8216;modelo del iroko&#8217;<\/em> porque ambos relacionan el calcio y sus sales presentes en el suelo, junto a la luz del sol<\/strong> (a trav\u00e9s de la fotos\u00edntesis) <strong>y junto a una interacci\u00f3n entre plantas-hongos-animales del suelo, con el objeto de explicar una parte de la fijaci\u00f3n del carbono en los bosques<\/strong>.<\/p>\n<p>Las micorrizas son simbiosis mutual\u00edsticas entre hongos y plantas que implican un intercambio entre los nutrientes que obtienen los hongos del suelo, y los nutrientes que producen las plantas con la fotos\u00edntesis. Sin embargo, <strong>en determinadas condiciones ambientales<\/strong> (nichos favorables para las plantas) o evolutivas (ecosistemas desfavorables para los hongos), <strong>las plantas minimizan o evitan la micorrizaci\u00f3n<\/strong>. <strong>El <em>&#8216;modelo del Ca-ECMs&#8217;<\/em> propone que los hongos establecen una &#8216;simbiosis tramposa&#8217; en la que<\/strong> las ECMs manipulan las propiedades del suelo entre las ra\u00edces para forzar la micorrizaci\u00f3n y la &#8216;explotaci\u00f3n&#8217; de los \u00e1rboles.<\/p>\n<p style=\"text-align: justify;\"><strong>Diversos estudios del grupo mencionado han mostrado c\u00f3mo ciertas ECMs desarrollan un mecanismo de <em>&#8216;ingenier\u00eda ambiental&#8217;<\/em> con el que incrementan los niveles del calcio<\/strong> (y sus sales) <strong>y\/o del pH en el suelo entre las ra\u00edces de los \u00e1rboles<\/strong>, todo lo cual <strong>potencia el desarrollo de las ra\u00edces finas e induce un estr\u00e9s nutricional en estos \u00e1rboles (cuyo efecto se conoce como clorosis).<\/strong> Este mecanismo est\u00e1 relacionado con el reciente descubrimiento de que <strong>las ECMs buscan, localizan, penetran y &#8216;disuelven&#8217; ciertas rocas de manera selectiva, para extraer su calcio y otros nutrientes como el f\u00f3sforo, en una actividad conocida como <\/strong><a href=\"http:\/\/www.nature.com\/nature\/journal\/v389\/n6652\/abs\/389682a0.html\"><span style=\"color: #0000ff;\"><strong><em>&#8216;rock-eating&#8217;<\/em><\/strong>.<\/span><\/a> Adem\u00e1s, <strong>existe una sinergia entre estos hongos ECMs y las lombrices de tierra, lo que provoca un incremento todav\u00eda mayor en los niveles de carbonato de calcio y pH entre la ra\u00edces de los \u00e1rboles. El efecto final<\/strong> de todo este mecanismo de <em>&#8216;ingenier\u00eda ambiental&#8217;<\/em> <strong>es un incremento en la micorrizaci\u00f3n de los \u00e1rboles y en el desarrollo del bosque<\/strong>.<\/p>\n<p><strong>Los suelos y bosques esconden claves que incrementar\u00e1n la comprensi\u00f3n del ciclo del carbono y su fijaci\u00f3n a escala global<\/strong>. Desde hace a\u00f1os, diversos investigadores de los departamentos de <a title=\"Ingenier\u00eda Forestal\" href=\"http:\/\/www2.montes.upm.es\/Dptos\/DptoIngForestal\/index.htm\" target=\"_blank\">Ingenier\u00eda Forestal<\/a> y <a title=\"Silvopascicultura\" href=\"http:\/\/www2.montes.upm.es\/Dptos\/DptoSilvopascicultura\/index.html\" target=\"_blank\">Silvopascicultura<\/a> de la ETSI de Montes estudian estas claves y, adem\u00e1s, j\u00f3venes ingenieros de la UPM han iniciado actividades profesionales relacionadas dirigidas al balance y fijaci\u00f3n del carbono.<\/p>\n<p style=\"text-align: justify;\">GARC\u00cdA-MONTERO, L.G.; VALVERDE-ASENJO, I.; GRANDE-ORT\u00cdZ, M.A.; MENTA, C.; HERNANDO, I<a href=\"https:\/\/www.researchgate.net\/publication\/257510731_Impact_of_earthworm_casts_on_soil_pH_and_calcium_carbonate_in_black_truffle_burns\"><span style=\"color: #0000ff;\">. <strong>Impact of earthworm casts on soil pH and calcium carbonate in black truffle burns<\/strong><\/span><\/a>. <em>Agroforestry Systems 87<\/em>: 815\u2013826. 2013.<\/p>\n<p>GARC\u00cdA-MONTERO, L.G.; VALVERDE-ASENJO, I.; MORENO, D.; D\u00cdAZ, P.; HERNANDO, I.; MENTA, C.; TARASCONI, K<a href=\"http:\/\/link.springer.com\/chapter\/10.1007%2F978-3-642-33823-6_6\"><span style=\"color: #0000ff;\">. <strong>Influence of edaphic factors on edible ectomycorrhizal mushrooms: new hypotheses on soil nutrition and C sinks associated to ectomycorrhizae and soil fauna using the Tuber br\u00fbl\u00e9 model<\/strong><\/span><\/a>. Edible Ectomycorrhizal Mushrooms. A. Zambonelli, G. Bonito (Eds.). <em>Soil Biology 34<\/em>. Springer-Verlag, Berlin. pp 83-104. 2012.<\/p>\n<p>GARC\u00cdA-MONTERO, L.G.; QUINTANA, A.; VALVERDE-ASENJO, I.; D\u00cdAZ, P. <a href=\"https:\/\/www.researchgate.net\/publication\/229358499_Calcareous_amendments_in_truffle_culture_A_soil_nutrition_hypothesis\"><strong><span style=\"color: #0000ff;\">Calcareous amendments in truffle culture: a soil nutrition hypothesis<\/span><\/strong><\/a>. <em>Soil Biology and Biochemistry 41<\/em>: 1227\u20131232. 2009.<\/p>\n<h3>Im\u00e1genes Relacionadas:<\/h3>","protected":false},"excerpt":{"rendered":"<p>Ecolog\u00eda del Suelo Micorrizas; Fuente: Blog Ecolog\u00eda Hoy no voy a comentar, sino mostrar una noticia que apareci\u00f3 en el bolet\u00edn \u00a0mi+d reproducida de una p\u00e1gina Web de la UPM. Francamente no s\u00e9 qu\u00e9 pensar, es decir dudo si se trata de un tema interesante o simplemente de una mera conjetura. El tema estriba en que no logro entender una buena parte del texto de la noticia. Francamente su redacci\u00f3n se me antoja farragosa, confusa y confundente. No obstante, atesora algunos p\u00e1rrafos que pudieran ser muy interesantes en lo concerniente a la estructura y din\u00e1mica ecol\u00f3gica de los suelos. Posiblemente,\u2026<\/p>\n","protected":false},"author":26,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0},"categories":[596],"tags":[46833,47033],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":4}},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Ecolog\u00eda del Suelo Micorrizas; Fuente: Blog Ecolog\u00eda Hoy no voy a comentar, sino mostrar una noticia que apareci\u00f3 en el bolet\u00edn mi+d reproducida de una p\u00e1gina Web de la UPM. Francamente no s\u00e9 qu\u00e9 pensar, es decir dudo si se trata de un tema interesante o simplemente de una mera conjetura. El tema estriba en\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Juan Jos\u00e9 Ib\u00e1\u00f1ez\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2014\/08\/09\/145109\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Un Universo invisible bajo nuestros pies - Los suelos y la vida\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"\u00bfIngenieros y Selvicultores del Suelo? - Un Universo invisible bajo nuestros pies\" \/>\n\t\t<meta property=\"og:description\" content=\"Ecolog\u00eda del Suelo Micorrizas; Fuente: Blog Ecolog\u00eda Hoy no voy a comentar, sino mostrar una noticia que apareci\u00f3 en el bolet\u00edn mi+d reproducida de una p\u00e1gina Web de la UPM. Francamente no s\u00e9 qu\u00e9 pensar, es decir dudo si se trata de un tema interesante o simplemente de una mera conjetura. El tema estriba en\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2014\/08\/09\/145109\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2014-08-09T17:43:15+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2014-08-09T17:46:43+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/juan.j.marti.14\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"\u00bfIngenieros y Selvicultores del Suelo? - Un Universo invisible bajo nuestros pies\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Ecolog\u00eda del Suelo Micorrizas; Fuente: Blog Ecolog\u00eda Hoy no voy a comentar, sino mostrar una noticia que apareci\u00f3 en el bolet\u00edn mi+d reproducida de una p\u00e1gina Web de la UPM. Francamente no s\u00e9 qu\u00e9 pensar, es decir dudo si se trata de un tema interesante o simplemente de una mera conjetura. El tema estriba en\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2014\\\/08\\\/09\\\/145109#blogposting\",\"name\":\"\\u00bfIngenieros y Selvicultores del Suelo? - Un Universo invisible bajo nuestros pies\",\"headline\":\"\\u00bfIngenieros y Selvicultores del Suelo?\",\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"http:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/wp-content\\\/blogs.dir\\\/42\\\/files\\\/163\\\/ecologia-del-suelo-fuente-blog-ecologia.jpg\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2014\\\/08\\\/09\\\/145109\\\/#articleImage\"},\"datePublished\":\"2014-08-09T18:43:15+01:00\",\"dateModified\":\"2014-08-09T18:46:43+01:00\",\"inLanguage\":\"es-ES\",\"commentCount\":2,\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2014\\\/08\\\/09\\\/145109#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2014\\\/08\\\/09\\\/145109#webpage\"},\"articleSection\":\"Biolog\\u00eda y Ecolog\\u00eda del Suelo, ecolog\\u00eda del suelo, ingenieros del suelo\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2014\\\/08\\\/09\\\/145109#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/biologia-y-ecologia-del-suelo#listItem\",\"name\":\"Biolog\\u00eda y Ecolog\\u00eda del Suelo\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/biologia-y-ecologia-del-suelo#listItem\",\"position\":2,\"name\":\"Biolog\\u00eda y Ecolog\\u00eda del Suelo\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/biologia-y-ecologia-del-suelo\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2014\\\/08\\\/09\\\/145109#listItem\",\"name\":\"\\u00bfIngenieros y Selvicultores del Suelo?\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2014\\\/08\\\/09\\\/145109#listItem\",\"position\":3,\"name\":\"\\u00bfIngenieros y Selvicultores del Suelo?\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/biologia-y-ecologia-del-suelo#listItem\",\"name\":\"Biolog\\u00eda y Ecolog\\u00eda del Suelo\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#organization\",\"name\":\"Un Universo invisible bajo nuestros pies\",\"description\":\"Los suelos y la vida\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/files\\\/2022\\\/02\\\/logo.png\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2014\\\/08\\\/09\\\/145109\\\/#organizationLogo\",\"width\":217,\"height\":72},\"image\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2014\\\/08\\\/09\\\/145109\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/juan.j.marti.14\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo\",\"name\":\"Juan Jos\\u00e9 Ib\\u00e1\\u00f1ez\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2014\\\/08\\\/09\\\/145109#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/387f3a100385573d8f42ce2a3211fd1c?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Juan Jos\\u00e9 Ib\\u00e1\\u00f1ez\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2014\\\/08\\\/09\\\/145109#webpage\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2014\\\/08\\\/09\\\/145109\",\"name\":\"\\u00bfIngenieros y Selvicultores del Suelo? - Un Universo invisible bajo nuestros pies\",\"description\":\"Ecolog\\u00eda del Suelo Micorrizas; Fuente: Blog Ecolog\\u00eda Hoy no voy a comentar, sino mostrar una noticia que apareci\\u00f3 en el bolet\\u00edn mi+d reproducida de una p\\u00e1gina Web de la UPM. Francamente no s\\u00e9 qu\\u00e9 pensar, es decir dudo si se trata de un tema interesante o simplemente de una mera conjetura. El tema estriba en\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2014\\\/08\\\/09\\\/145109#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\"},\"datePublished\":\"2014-08-09T18:43:15+01:00\",\"dateModified\":\"2014-08-09T18:46:43+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#website\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/\",\"name\":\"Un Universo invisible bajo nuestros pies\",\"description\":\"Los suelos y la vida\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"\u00bfIngenieros y Selvicultores del Suelo? - Un Universo invisible bajo nuestros pies","description":"Ecolog\u00eda del Suelo Micorrizas; Fuente: Blog Ecolog\u00eda Hoy no voy a comentar, sino mostrar una noticia que apareci\u00f3 en el bolet\u00edn mi+d reproducida de una p\u00e1gina Web de la UPM. Francamente no s\u00e9 qu\u00e9 pensar, es decir dudo si se trata de un tema interesante o simplemente de una mera conjetura. El tema estriba en","canonical_url":"https:\/\/www.madrimasd.org\/blogs\/universo\/2014\/08\/09\/145109","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2014\/08\/09\/145109#blogposting","name":"\u00bfIngenieros y Selvicultores del Suelo? - Un Universo invisible bajo nuestros pies","headline":"\u00bfIngenieros y Selvicultores del Suelo?","author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author"},"publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#organization"},"image":{"@type":"ImageObject","url":"http:\/\/www.madrimasd.org\/blogs\/universo\/wp-content\/blogs.dir\/42\/files\/163\/ecologia-del-suelo-fuente-blog-ecologia.jpg","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2014\/08\/09\/145109\/#articleImage"},"datePublished":"2014-08-09T18:43:15+01:00","dateModified":"2014-08-09T18:46:43+01:00","inLanguage":"es-ES","commentCount":2,"mainEntityOfPage":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2014\/08\/09\/145109#webpage"},"isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2014\/08\/09\/145109#webpage"},"articleSection":"Biolog\u00eda y Ecolog\u00eda del Suelo, ecolog\u00eda del suelo, ingenieros del suelo"},{"@type":"BreadcrumbList","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2014\/08\/09\/145109#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo#listItem","position":1,"name":"Home","item":"https:\/\/www.madrimasd.org\/blogs\/universo","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/biologia-y-ecologia-del-suelo#listItem","name":"Biolog\u00eda y Ecolog\u00eda del Suelo"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/biologia-y-ecologia-del-suelo#listItem","position":2,"name":"Biolog\u00eda y Ecolog\u00eda del Suelo","item":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/biologia-y-ecologia-del-suelo","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2014\/08\/09\/145109#listItem","name":"\u00bfIngenieros y Selvicultores del Suelo?"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2014\/08\/09\/145109#listItem","position":3,"name":"\u00bfIngenieros y Selvicultores del Suelo?","previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/biologia-y-ecologia-del-suelo#listItem","name":"Biolog\u00eda y Ecolog\u00eda del Suelo"}}]},{"@type":"Organization","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#organization","name":"Un Universo invisible bajo nuestros pies","description":"Los suelos y la vida","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/","logo":{"@type":"ImageObject","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2014\/08\/09\/145109\/#organizationLogo","width":217,"height":72},"image":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2014\/08\/09\/145109\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/juan.j.marti.14"]},{"@type":"Person","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo","name":"Juan Jos\u00e9 Ib\u00e1\u00f1ez","image":{"@type":"ImageObject","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2014\/08\/09\/145109#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/387f3a100385573d8f42ce2a3211fd1c?s=96&d=mm&r=g","width":96,"height":96,"caption":"Juan Jos\u00e9 Ib\u00e1\u00f1ez"}},{"@type":"WebPage","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2014\/08\/09\/145109#webpage","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/2014\/08\/09\/145109","name":"\u00bfIngenieros y Selvicultores del Suelo? - Un Universo invisible bajo nuestros pies","description":"Ecolog\u00eda del Suelo Micorrizas; Fuente: Blog Ecolog\u00eda Hoy no voy a comentar, sino mostrar una noticia que apareci\u00f3 en el bolet\u00edn mi+d reproducida de una p\u00e1gina Web de la UPM. Francamente no s\u00e9 qu\u00e9 pensar, es decir dudo si se trata de un tema interesante o simplemente de una mera conjetura. El tema estriba en","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#website"},"breadcrumb":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2014\/08\/09\/145109#breadcrumblist"},"author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author"},"creator":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author"},"datePublished":"2014-08-09T18:43:15+01:00","dateModified":"2014-08-09T18:46:43+01:00"},{"@type":"WebSite","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#website","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/","name":"Un Universo invisible bajo nuestros pies","description":"Los suelos y la vida","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Un Universo invisible bajo nuestros pies - Los suelos y la vida","og:type":"article","og:title":"\u00bfIngenieros y Selvicultores del Suelo? - Un Universo invisible bajo nuestros pies","og:description":"Ecolog\u00eda del Suelo Micorrizas; Fuente: Blog Ecolog\u00eda Hoy no voy a comentar, sino mostrar una noticia que apareci\u00f3 en el bolet\u00edn mi+d reproducida de una p\u00e1gina Web de la UPM. Francamente no s\u00e9 qu\u00e9 pensar, es decir dudo si se trata de un tema interesante o simplemente de una mera conjetura. El tema estriba en","og:url":"https:\/\/www.madrimasd.org\/blogs\/universo\/2014\/08\/09\/145109","og:image":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png","og:image:secure_url":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png","article:published_time":"2014-08-09T17:43:15+00:00","article:modified_time":"2014-08-09T17:46:43+00:00","article:publisher":"https:\/\/www.facebook.com\/juan.j.marti.14","twitter:card":"summary","twitter:title":"\u00bfIngenieros y Selvicultores del Suelo? - Un Universo invisible bajo nuestros pies","twitter:description":"Ecolog\u00eda del Suelo Micorrizas; Fuente: Blog Ecolog\u00eda Hoy no voy a comentar, sino mostrar una noticia que apareci\u00f3 en el bolet\u00edn mi+d reproducida de una p\u00e1gina Web de la UPM. Francamente no s\u00e9 qu\u00e9 pensar, es decir dudo si se trata de un tema interesante o simplemente de una mera conjetura. El tema estriba en","twitter:image":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png"},"aioseo_meta_data":{"post_id":"145109","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":null,"isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","tabs":null,"priority":null,"frequency":null,"local_seo":null,"created":"2022-06-03 16:55:38","updated":"2026-05-26 18:03:58","limit_modified_date":false,"ai":null,"breadcrumb_settings":null,"seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/biologia-y-ecologia-del-suelo\" title=\"Biolog\u00eda y Ecolog\u00eda del Suelo\">Biolog\u00eda y Ecolog\u00eda del Suelo<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t\u00bfIngenieros y Selvicultores del Suelo?\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.madrimasd.org\/blogs\/universo"},{"label":"Biolog\u00eda y Ecolog\u00eda del Suelo","link":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/biologia-y-ecologia-del-suelo"},{"label":"\u00bfIngenieros y Selvicultores del Suelo?","link":"https:\/\/www.madrimasd.org\/blogs\/universo\/2014\/08\/09\/145109"}],"_links":{"self":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts\/145109"}],"collection":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/comments?post=145109"}],"version-history":[{"count":9,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts\/145109\/revisions"}],"predecessor-version":[{"id":145904,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts\/145109\/revisions\/145904"}],"wp:attachment":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/media?parent=145109"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/categories?post=145109"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/tags?post=145109"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}