{"id":145493,"date":"2015-05-15T14:03:24","date_gmt":"2015-05-15T13:03:24","guid":{"rendered":"http:\/\/www.madrimasd.org\/blogs\/universo\/?p=145493"},"modified":"2015-05-15T14:03:24","modified_gmt":"2015-05-15T13:03:24","slug":"phaeozems-feozems-en-europa","status":"publish","type":"post","link":"https:\/\/www.madrimasd.org\/blogs\/universo\/2015\/05\/15\/145493","title":{"rendered":"Phaeozems (Feozems) En Europa"},"content":{"rendered":"<p align=\"center\"><img decoding=\"async\" class=\"ngg-singlepic ngg-center\" style=\"width: 494px; height: 302px;\" src=\"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-content\/blogs.dir\/42\/files\/mapas-de-los-suelos-de-europa-wrb\/phaeozem-europa-esb.jpg\" alt=\"phaeozem-europa-esb\" width=\"1062\" height=\"642\" \/><\/p>\n<p align=\"center\"><span style=\"color: #0000ff;\">Phaeozems. Mapa de Europa. Fuente: Bur\u00f3 Europeo de Suelos<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Los <\/span><a title=\"Enlace permanente: Phaeozems o Feozems (WRB, 1998)\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2015\/02\/12\/145465\"><span style=\"color: #0000ff;\">Phaeozems o Feozems\u00a0<\/span><\/a><span style=\"color: #000000;\">se extienden aproximadamente por unos <\/span><span style=\"color: #3366ff;\"><strong>70.000 km<sup>2<\/sup><\/strong><\/span><span style=\"color: #000000;\"> de la Uni\u00f3n Europea (UE), lo que equivale aproximadamente al <\/span><span style=\"color: #3366ff;\"><strong>1.7% de la cobertura de suelos en esta mancomunidad de pa\u00edses<\/strong><\/span><span style=\"color: #000000;\">. Este Grupo de Suelos de Referencia de la WRB se ubica principalmente en el <\/span><strong><span style=\"color: #000000;\"><span style=\"color: #3366ff;\">centro y este de Europa<\/span><\/span><\/strong><span style=\"color: #000000;\">, as\u00ed como en <\/span><span style=\"color: #3366ff;\"><strong>Espa\u00f1a<\/strong><\/span><span style=\"color: #000000;\">. En la UE se presentan <\/span><span style=\"color: #3366ff;\"><strong>cinco tipos de Phaeozems<\/strong><\/span><span style=\"color: #000000;\"> (segundo nivel de la WRB, 1998) que en orden de mayor a menos abundancia ser\u00edan los siguientes: <\/span><span style=\"color: #3366ff;\"><strong><em>Phaeozem calc\u00e1ricos<\/em><\/strong><\/span><span style=\"color: #000000;\"> (PHca 15383 km<\/span><sup><span style=\"color: #000000;\">2<\/span><\/sup><span style=\"color: #000000;\">; 31.11%), <\/span><span style=\"color: #3366ff;\"><strong><em>Phaeozem gleycos<\/em><\/strong><\/span><span style=\"color: #000000;\"> (PHgl 14374 km<\/span><sup><span style=\"color: #000000;\">2<\/span><\/sup><span style=\"color: #000000;\">; 21.84%), <\/span><span style=\"color: #3366ff;\"><strong><em>Phaeozem h\u00e1plicos<\/em><\/strong><\/span><span style=\"color: #000000;\"> (PHha 15938 km<\/span><sup><span style=\"color: #000000;\">2<\/span><\/sup><span style=\"color: #000000;\">; 22. <\/span><span style=\"color: #000000;\">63%); <\/span><span style=\"color: #3366ff;\"><strong><em>Phaeozem l\u00favicos<\/em><\/strong><\/span><span style=\"color: #000000;\"> (PHlv 24734 km<\/span><sup><span style=\"color: #000000;\">2<\/span><\/sup><span style=\"color: #000000;\"> 20.41%) y exiguas extensiones de <\/span><span style=\"color: #3366ff;\"><strong><em>Phaeozem s\u00f3dicos<\/em><\/strong><\/span><span style=\"color: #000000;\"> (PHso 9 km<\/span><sup><span style=\"color: #000000;\">2<\/span><\/sup><span style=\"color: #000000;\">: 0.01%). <\/span><span style=\"color: #000000;\">Sin embargo, conforme a nuestra base de datos, <strong><span style=\"color: #3366ff;\">en el sureste del continente Europeo<\/span> <\/strong>tambi\u00e9n se forma otro tipo de Phaeozem ausente en la UE. Se trata de los ampliamente representados <\/span><strong><em><span style=\"color: #000000;\"><span style=\"color: #3366ff;\">Phaeozem \u00e1lbicos<\/span><\/span><\/em><\/strong><span style=\"color: #000000;\">. Los m\u00e1s abundantes resultan ser pues los Phaeozem calc\u00e1ricos, preferentemente localizados en la <\/span><span style=\"color: #3366ff;\"><strong>Cuenca de los C\u00e1rpatos<\/strong><\/span><span style=\"color: #000000;\"> y el tercio noreste de Espa\u00f1a. Los Phaeozem gleycos se presentan en nueve pa\u00edses aunque son mayoritarios en <\/span><span style=\"color: #3366ff;\"><strong>Hungr\u00eda y Rumania<\/strong><\/span><span style=\"color: #000000;\">, es decir en la <\/span><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2009\/03\/28\/115420\"><span style=\"color: #0000ff;\">Regi\u00f3n Biogeogr\u00e1fica Pan\u00f3nica<\/span><\/a><span style=\"color: #000000;\"> y en menor extensi\u00f3n en la <\/span><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2009\/03\/25\/115186\"><span style=\"color: #0000ff;\">Continental<\/span><\/a><span style=\"color: #000000;\">. <\/span><span style=\"color: #000000;\">\u00a0<\/span><span style=\"color: #000000;\">Por su parte, los Phaeozem h\u00e1plicos se encuentran tambi\u00e9n ampliamente representados en Hungr\u00eda y Ruman\u00eda, aunque en menor proporci\u00f3n aparecen en <\/span><span style=\"color: #3366ff;\"><strong>Francia, Alemania, Polonia, Eslovaquia y Rep\u00fablica Checa<\/strong><\/span><span style=\"color: #000000;\">. Del mismo modo en <\/span><span style=\"color: #3366ff;\"><strong>Bulgaria<\/strong><\/span><span style=\"color: #000000;\">, Ruman\u00eda Alemania y tan solo a modo de inclusiones en <\/span><span style=\"color: #3366ff;\"><strong>Italia<\/strong>,<strong> Polonia<\/strong><\/span><span style=\"color: #000000;\"> y Rep\u00fablica Checa, pueden detectarse los Phaeozem l\u00favicos. Finalmente, existe un peque\u00f1o espacio geogr\u00e1fico en el este de Ruman\u00eda en donde pueden encontrarse Phaeozem s\u00f3dicos.<span style=\"color: #3366ff;\"><strong> Si nos ce\u00f1imos a las regiones biogeogr\u00e1ficas<\/strong><\/span>, <span style=\"color: #3366ff;\"><strong>el porcentaje por orden decreciente que cubren<\/strong> <\/span>en cada una de las mismas, ser\u00eda el siguiente: <\/span><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2009\/03\/28\/115420\"><span style=\"color: #0000ff;\">Pan\u00f3nica<\/span><\/a><span style=\"color: #000000;\"> (24.09), <\/span><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2009\/03\/25\/115186\"><span style=\"color: #0000ff;\">Continental<\/span><\/a><span style=\"color: #000000;\"> (15.93%), <\/span><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2009\/05\/12\/118054\"><span style=\"color: #0000ff;\">Alpina<\/span><\/a><span style=\"color: #000000;\"> (8.39%), <\/span><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2009\/04\/10\/116218\"><span style=\"color: #0000ff;\">Est\u00e9pica<\/span><\/a><span style=\"color: #000000;\"> (4.35),\u00a0<\/span><span style=\"color: #000000;\">\u00a0<\/span><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2009\/04\/17\/116584\"><span style=\"color: #0000ff;\">Mar negro<\/span><\/a><span style=\"color: #000000;\"> (2.18%), <\/span><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2009\/03\/16\/114585\"><span style=\"color: #0000ff;\">Boreal<\/span><\/a><span style=\"color: #000000;\"> (0.41%), <\/span><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2009\/05\/05\/117641\"><span style=\"color: #0000ff;\">Mediterr\u00e1nea<\/span><\/a><span style=\"color: #000000;\"> (0.97%), <\/span><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2009\/03\/17\/114665\"><span style=\"color: #0000ff;\">Atl\u00e1ntica<\/span><\/a><span style=\"color: #000000;\"> (0.10%), <\/span><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2009\/05\/17\/118390\"><span style=\"color: #0000ff;\">Macarron\u00e9sica<\/span><\/a><span style=\"color: #000000;\"> (0.35%) y <\/span><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2009\/02\/05\/112366\"><span style=\"color: #0000ff;\">\u00c1rtica<\/span><\/a><span style=\"color: #000000;\"> (0.0%). <\/span><\/p>\n<p align=\"center\"><span style=\"color: #000000;\">\u00a0<\/span><img decoding=\"async\" class=\"ngg-singlepic ngg-center\" src=\"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-content\/blogs.dir\/42\/files\/mapas-de-los-suelos-de-europa-wrb\/phaeozem-mapa-de-europa-esb.jpg\" alt=\"phaeozem-mapa-de-europa-esb\" \/><\/p>\n<p align=\"center\"><span style=\"color: #0000ff;\">Phaeozems. Mapa de la Uni\u00f3n Europea. Fuente: Bur\u00f3 Europeo de suelos<\/span><\/p>\n<p style=\"text-align: justify;\" align=\"center\"><!--more--><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Como ya comentamos, de acuerdo a la monograf\u00eda <\/span><a href=\"http:\/\/eusoils.jrc.ec.europa.eu\/esdb_archive\/eusoils_docs\/other\/EUR23439.pdf\">Soils of the European Union<\/a><span style=\"color: #000000;\">y otros documentos de la FAO, Los Phaeozem son edafotaxa <\/span><strong><span style=\"color: #000000;\">representativos de las praderas de las estepas h\u00famedas del mundo, cubriendo aproximadamente 1.9 millones de Km<\/span><sup><span style=\"color: #000000;\">2<\/span><\/sup><\/strong><span style=\"color: #000000;\">. <\/span><span style=\"color: #000000;\">\u00a0<\/span><span style=\"color: #000000;\">Su formaci\u00f3n se realizar\u00eda preferentemente sobre sedimentos de tipo loes, derrubios glaciares y otros materiales l\u00edticos no consolidados, form\u00e1ndose especialmente en superficies topogr\u00e1ficas llanas u onduladas. Estos suelos <\/span><strong><span style=\"color: #000000;\">se encuentran emparentados <\/span><\/strong><strong><span style=\"color: #000000;\">con<\/span><\/strong><span style=\"color: #000000;\"> otros t\u00edpicos de los ambientes esteparios, como lo son los <\/span><strong>Chernozems<\/strong><span style=\"color: #000000;\"> bajo climas m\u00e1s fr\u00edos, y los <\/span><strong>Chernozems<\/strong><span style=\"color: #000000;\"> de sus fronteras secas. <\/span><strong><span style=\"color: #000000;\">Comparten con estos grupos de Suelos de Referencia de la WRB un horizonte superficial oscuro y rico en materia org\u00e1nica<\/span><\/strong><span style=\"color: #000000;\">, aunque no muestran rasgos que denuncien la presencia de carbonato c\u00e1lcico en el primer metro del perfil ed\u00e1fico. Son suelos de <\/span><strong><span style=\"color: #000000;\">excelentes propiedades f\u00edsicas<\/span><\/strong><span style=\"color: #000000;\">, tales como una elevada porosidad y buen aireamiento, estructura estable (grumosa o en bloques), <\/span><strong><span style=\"color: #000000;\">magnificas aptitud para almacenar agua<\/span><\/strong><span style=\"color: #000000;\"> (aunque a veces no suficiente con vistas a satisfacer la demanda de las plantas durante la estaci\u00f3n seca). Su contenido medio de materia org\u00e1nica ronda el 5%. Se trata de edafotaxa <\/span><strong><span style=\"color: #000000;\">muy f\u00e9rtiles, excelentes para las producciones agropecuarias<\/span><\/strong><span style=\"color: #000000;\">. <\/span><span style=\"color: #000000;\">\u00a0<\/span><span style=\"color: #000000;\">En otras calificaciones edafol\u00f3gicas reciben denominaciones tales como: Brunizems (Argentina, Francia), Parabraunerde-Tsjernozems (Alemania) y Aquolls Suborden de los Molisoles en la USDA-Soil Taxonomy).<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">No obstante, estos suelos pueden formarse localmente tambi\u00e9n en otros ambientes, y bajo otras fisiograf\u00edas, vegetaci\u00f3n y rocas, tal como ocurre en el bioma <\/span><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2009\/05\/05\/117641\"><span style=\"color: #0000ff;\">mediterr\u00e1neo<\/span><\/a><span style=\"color: #000000;\"> y <\/span><strong>subtropical seco<\/strong><span style=\"color: #000000;\">. <\/span><span style=\"color: #000000;\">\u00a0<\/span><span style=\"color: #000000;\">Recordemos finalmente, que <\/span><strong><span style=\"color: #000000;\">gran parte de su biomasa y necromasa procede de los sistemas radicales que suelen superar la que atesoran las partes a\u00e9reas de las plantas<\/span><\/strong><span style=\"color: #000000;\">. <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #008000;\"><strong>Juan Jos\u00e9 Ib\u00e1\u00f1ez<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #800000;\"><strong>Material\u00a0 Bibliogr\u00e1fico<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.fao.org\/nr\/land\/soils\/soil\/en\">P\u00e1gina Web de la WRB<\/a><\/p>\n<p style=\"text-align: justify;\"><a href=\"ftp:\/\/ftp.fao.org\/docrep\/fao\/011\/a0510s\/a0510s00.pdf\">Clasificaci\u00f3n WRB 2006-2007<\/a><\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.fao.org\/DOCREP\/003\/Y1899E\/Y1899E00.HTM\">Lecture notes on the major soils of the world<\/a><span style=\"color: #000000;\"> (versi\u00f3n personal traducida al espa\u00f1ol por Javier Manr\u00edquez Cos\u00edo)<\/span><\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.inegi.org.mx\/prod_serv\/contenidos\/espanol\/bvinegi\/productos\/integracion\/especiales\/BoletinSNEIG\/2010\/Bsnieg14_b.pdf\">Los suelos de Latinoam\u00e9rica: retos y oportunidades de uso y estudio<\/a><span style=\"color: #000000;\"> (ir al titulo correspondiente) Autores: Francisco Bautista, Alfred J. Zinck y Silke Cram. Bolet\u00edn del Sistema Nacional de Informaci\u00f3n Estad\u00edstica y Geogr\u00e1fica: VII(3) Septiembre-Diciembre 2009, p\u00e1ginas 94-142<\/span><\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/eusoils.jrc.ec.europa.eu\/esdb_archive\/eusoils_docs\/other\/EUR23439.pdf\">Soils of the European Union<\/a><span style=\"color: #000000;\"> (en Ingles)<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #800000;\"><strong>Post Previos <\/strong><strong>de Nuestro Breve de Nuestro Curso B\u00e1sico Tipos de Suelos del Mundo<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\">\u00a0<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/06\/23\/136471\">Los Suelos del Mundo y Su clasificaci\u00f3n (WRB). Curso B\u00e1sico sobre Clasificaci\u00f3n de Suelos<\/a><\/p>\n<p style=\"text-align: justify;\">\u00a0<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/06\/28\/136476\">Suelos Minerales Condicionados por la Topograf\u00eda o Fisiograf\u00eda: Leptosoles, Regosoles, Fluvisoles y Gleysoles<\/a><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #800000;\"><strong>Post Previos\u00a0 de Nuestro Breve\u00a0Curso B\u00e1sico Tipos de Suelos del Mundo hasta Junio de 2014<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/06\/23\/136471\">Los Suelos del Mundo y Su clasificaci\u00f3n (WRB). Curso B\u00e1sico sobre Clasificaci\u00f3n de Suelos<\/a><\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/06\/28\/136476\">Suelos Minerales Condicionados por la Topograf\u00eda o Fisiograf\u00eda: Leptosoles, Regosoles, Fluvisoles y Gleysoles<\/a><\/p>\n<p style=\"text-align: justify;\"><strong>Leptosoles<\/strong><\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/07\/06\/136490\">Leptosoles<\/a>;\u00a0<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/07\/13\/136682\">Leptosoles: Geograf\u00eda Ambiente y Paisaje<\/a>;\u00a0<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/07\/28\/136691\">Leptosoles Uso y Manejo<\/a>;<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/08\/04\/136695\">Leptosoles en Latinoam\u00e9rica<\/a>;\u00a0<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/08\/11\/136703\">Leptosoles en Europa<\/a>;\u00a0<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/08\/22\/136503\">Tipos de Leptosoles y sus Mapas de Distribuci\u00f3n en Europa<\/a><\/p>\n<p style=\"text-align: justify;\"><strong>Regosoles<\/strong><\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/09\/02\/136720\">Regosoles<\/a>; \u00a0<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/09\/09\/136869\">Regosoles: Geograf\u00eda, Ambiente y Paisaje<\/a>;\u00a0<a title=\"Enlace permanente a Regosoles: Uso y Manejo\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/09\/16\/136876\">Regosoles: Uso y Manejo<\/a>:\u00a0<a title=\"Enlace permanente a Regosoles en Latinoam\u00e9rica\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/09\/24\/136882\">Regosoles en Latinoam\u00e9rica<\/a>;\u00a0<a title=\"Enlace permanente a Regosoles en Europa\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/10\/28\/136908\">Regosoles en Europa<\/a>;\u00a0<a title=\"Enlace permanente a Tipos de Regosoles y sus Mapas de Distribuci\u00f3n en Europa(WRB 1998)\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/11\/04\/136894\">Tipos de Regosoles y sus Mapas de Distribuci\u00f3n en Europa(WRB 1998)<\/a><\/p>\n<p style=\"text-align: justify;\"><strong>Fluvisoles<\/strong><\/p>\n<p style=\"text-align: justify;\"><a title=\"Enlace permanente a Paisajes Aluviales No Costeros de las Redes Fluviales (WRB 1998)\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/01\/06\/137193\">Paisajes Aluviales No Costeros de las Redes Fluviales (WRB 1998)<\/a>;\u00a0<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/01\/13\/137830\">Deltas, Estuarios y Marismas<\/a>;\u00a0<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/01\/19\/137847\">Geoformas de las L\u00edneas de Costa Generadas por la Din\u00e1mica Marina (WRB-FAO 2000)<\/a>,\u00a0<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/01\/26\/137868\">Fluvisoles<\/a>,\u00a0<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/02\/02\/138188\">Fluvisoles ti\u00f3nicos<\/a>,\u00a0<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/02\/01\/137894\">Distribuci\u00f3n geogr\u00e1fica de los Fluvisoles<\/a>,\u00a0<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/02\/03\/137903\">Fluvisoles uso y manejo<\/a>,\u00a0<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/02\/04\/137912\">Fluvisoles en Latinoam\u00e9rica<\/a>,\u00a0<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/02\/07\/137923\">Fluvisoles en Europa<\/a>,\u00a0<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/02\/08\/137936\">Mapas de los tipos de suelos de Europa (WRB 1998)<\/a><\/p>\n<p style=\"text-align: justify;\">\u00a0<strong>Gleysoles<\/strong><\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/02\/16\/138132\">Gleysoles<\/a>;\u00a0<a title=\"Enlace permanente a Gleysoles: Geograf\u00eda Ambiente y Paisaje\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/02\/24\/138158\">Gleysoles: Geograf\u00eda Ambiente y Paisaje<\/a>\u00a0<a title=\"Enlace permanente a Gleysoles: Uso y Manejo\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/02\/25\/138174\">Gleysoles: Uso y Manejo<\/a>,\u00a0<a title=\"Enlace permanente a Gleysoles en Latinoam\u00e9rica\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/02\/28\/138196\">Gleysoles en Latinoam\u00e9rica<\/a>,\u00a0<a title=\"Enlace permanente a Gleysoles en Europa\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/03\/01\/138204\">Gleysoles en Europa<\/a>,\u00a0<a title=\"Enlace permanente a Tipos de Gleysoles y sus Mapas de Distribuci\u00f3n en Europa\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/03\/03\/138117\">Tipos de Gleysoles y sus Mapas de Distribuci\u00f3n en Europa<\/a><\/p>\n<p style=\"text-align: justify;\"><strong>Stagnosoles (WRB 2006-2007)<\/strong><\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/03\/17\/138151\">Stagnosoles<\/a><\/p>\n<p style=\"text-align: justify;\"><strong>Histosoles<\/strong><\/p>\n<p style=\"text-align: justify;\"><a title=\"Enlace permanente a Histosoles (WRB 1998): Las Turberas\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/03\/30\/138691\">Histosoles (WRB 1998): Las Turberas<\/a><span style=\"color: #000000;\">; <\/span><a title=\"Enlace permanente a Histosoles (Turberas): Geograf\u00eda, Ambiente y Paisaje\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/04\/05\/138702\">Histosoles (Turberas): Geograf\u00eda, Ambiente y Paisaje<\/a><span style=\"color: #000000;\">; <\/span><a title=\"Enlace permanente a Histosoles Uso y Manejo (Turberas) (WRB 1998)\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/04\/06\/138714\">Histosoles Uso y Manejo (Turberas) (WRB 1998)<\/a><span style=\"color: #000000;\">; <\/span><a title=\"Enlace permanente a Histosoles en Latinoam\u00e9rica Tropical\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/04\/08\/138760\">Histosoles en Latinoam\u00e9rica Tropical<\/a><span style=\"color: #000000;\">; <\/span><a title=\"Enlace permanente a Histosoles en Europa (Turberas)\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/04\/11\/138742\">Histosoles en Europa (Turberas)<\/a><span style=\"color: #000000;\">; <\/span><a title=\"Enlace permanente a Tipos de Histosoles y sus Mapas de Distribuci\u00f3n en Europa (WRB 1998)\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/04\/20\/138751\">Tipos de Histosoles y sus Mapas de Distribuci\u00f3n en Europa (WRB 1998)<\/a><\/p>\n<p style=\"text-align: justify;\"><strong>Cambisoles<\/strong><\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/06\/09\/139388\">Cambisoles<\/a><span style=\"color: #000000;\">; <\/span><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/06\/15\/139402\">Cambisoles: Geograf\u00eda Ambiente y Paisaje<\/a><span style=\"color: #000000;\">; <\/span><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/06\/22\/139434\">Cambisoles: Uso y Manejo<\/a><span style=\"color: #000000;\">; <\/span><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/06\/23\/139458\">Cambisoles en Latinoam\u00e9rica<\/a><span style=\"color: #000000;\">;\u00a0 <\/span><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/06\/30\/139418\">Cambisoles en Europa<\/a><span style=\"color: #000000;\">; <\/span><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/07\/07\/139426\">Tipos de Cambisoles y Sus Mapas de Distribuci\u00f3n en Europa<\/a><\/p>\n<p style=\"text-align: justify;\"><strong>Arenosoles<\/strong><\/p>\n<p style=\"text-align: justify;\"><a title=\"Enlace permanente a Dunas y Paisajes Arenosos (WRB 1998)\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/07\/12\/139706\">Dunas y Paisajes Arenosos (WRB 1998)<\/a><span style=\"color: #000000;\">; <\/span><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/07\/13\/139746\">Arenosoles<\/a><span style=\"color: #000000;\">; <\/span><a title=\"Enlace permanente a Arenosoles: Geograf\u00eda Ambiente y Paisaje\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/07\/18\/139756\">Arenosoles: Geograf\u00eda; Ambiente y Paisaje<\/a><span style=\"color: #000000;\">; <\/span><a title=\"Enlace permanente a Arenosoles: Uso y Manejo\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/07\/21\/139772\">Arenosoles: Uso y Manejo<\/a><span style=\"color: #000000;\">; <\/span><a title=\"Enlace permanente a Arenosoles en Latinoam\u00e9rica\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/07\/28\/139786\">Arenosoles en Latinoam\u00e9rica<\/a><span style=\"color: #000000;\">; <\/span><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/08\/04\/139794\">Arenosoles en Europa<\/a><span style=\"color: #000000;\">; <\/span><a title=\"Enlace permanente a Tipos de Arenosoles y sus Mapas de Distribuci\u00f3n en Europa\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/08\/11\/139800\">Tipos de Arenosoles y sus Mapas de Distribuci\u00f3n en Europa<\/a><\/p>\n<p style=\"text-align: justify;\"><strong>Vertisoles<\/strong><\/p>\n<p style=\"text-align: justify;\"><a title=\"Enlace permanente a Paisajes Arcillosos (WRB, 1998)\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/09\/29\/139981\">Paisajes Arcillosos (WRB, 1998)<\/a><span style=\"color: #000000;\">, <\/span><a title=\"Enlace permanente a Microrelieve Gilgai  (Vertisoles, WRB, 1998)\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/10\/04\/140078\">Microrelieve Gilgai (Vertisoles, WRB, 1998)<\/a><span style=\"color: #000000;\">, <\/span><a title=\"Enlace permanente a Vertisoles (WRB, 1998)\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/10\/06\/140062\">Vertisoles (WRB, 1998)<\/a><span style=\"color: #000000;\">, <\/span><a title=\"Enlace permanente a Vertisoles: Geograf\u00eda, Ambiente y Paisaje\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/10\/13\/140087\">Vertisoles: Geograf\u00eda, Ambiente y Paisaje<\/a><span style=\"color: #000000;\">, <\/span><a title=\"Enlace permanente a Vertisoles: Uso y Manejo\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/10\/21\/140108\">Vertisoles: Uso y Manejo<\/a><span style=\"color: #000000;\">, <\/span><a title=\"Enlace permanente a Vertisoles en Latinoam\u00e9rica\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/10\/28\/140114\">Vertisoles en Latinoam\u00e9rica<\/a><span style=\"color: #000000;\">, <\/span><a title=\"Enlace permanente a Vertisoles en La UE y el Continente Europeo\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/11\/01\/140049\">Vertisoles en La UE y el Continente Europeo<\/a><span style=\"color: #000000;\">, <\/span><a title=\"Enlace permanente a Tipos de Vertisoles y sus Mapas de Distribuci\u00f3n en Europa\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/11\/11\/140053\">Tipos de Vertisoles y sus Mapas de Distribuci\u00f3n en Europa<\/a><\/p>\n<p style=\"text-align: justify;\"><strong>Andosoles<\/strong><\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/11\/16\/140617\">Paisajes Volc\u00e1nicos<\/a><span style=\"color: #000000;\">, <\/span><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/11\/23\/140258\">Andosoles<\/a><span style=\"color: #000000;\">, <\/span><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/12\/02\/140627\">Andosoles: geograf\u00eda ambiente y paisaje<\/a><span style=\"color: #000000;\">, <\/span><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/12\/20\/140649\">Andosoles Uso y Manejo<\/a><span style=\"color: #000000;\">, <\/span><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/01\/17\/140659\">Andosoles en Latinoam\u00e9rica<\/a><span style=\"color: #000000;\">, <\/span><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/01\/25\/140135\">Andosoles en Europa<\/a><span style=\"color: #000000;\">, <\/span><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/01\/25\/140135\">Andosoles en Europa\u00a0 y los Suelos de Islandia<\/a><span style=\"color: #000000;\">, <\/span><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/02\/02\/140142\">Tipos de Andosoles y sus mapas de distribuci\u00f3n en Europa<\/a><\/p>\n<p style=\"text-align: justify;\"><strong>Luvisoles<\/strong><\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/02\/28\/141085\">Luvisoles<\/a><span style=\"color: #000000;\">, <\/span><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/03\/15\/141095\">Luvisoles: geograf\u00eda ambiente y paisaje<\/a><span style=\"color: #000000;\">, <\/span><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/03\/23\/141101\">Luvisoles Uso y Manejo<\/a><span style=\"color: #000000;\">; <\/span><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/03\/27\/141109\">Luvisoles en Latinoam\u00e9rica<\/a><span style=\"color: #000000;\">, <\/span><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/04\/03\/141236\">Luvisoles en Europa<\/a><span style=\"color: #000000;\">, <\/span><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/04\/07\/141248\">Tipos de Luvisoles y sus mapas de distribuci\u00f3n en Europa<\/a><span style=\"color: #000000;\">.<\/span><\/p>\n<p style=\"text-align: justify;\"><strong>Alisoles<\/strong><\/p>\n<p style=\"text-align: justify;\"><a title=\"Enlace permanente a Alisoles (WRB, 1998)\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/04\/19\/141598\"><span style=\"font-family: Calibri;\">Alisoles (WRB, 1998)<\/span><\/a><span style=\"color: #000000; font-family: Calibri;\">; <\/span><a title=\"Enlace permanente a Alisoles: Geograf\u00eda Ambiente y Paisaje\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/04\/25\/141607\"><span style=\"font-family: Calibri;\">Alisoles: Geograf\u00eda Ambiente y Paisaje<\/span><\/a><span style=\"color: #000000; font-family: Calibri;\">, <\/span><a title=\"Enlace permanente: Alisoles: Uso y Manejo\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/05\/03\/141613\"><span style=\"font-family: Calibri;\">Alisoles: Uso y Manejo<\/span><\/a><\/p>\n<p style=\"text-align: justify;\"><strong>Lixisoles<\/strong><\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/05\/09\/141636\"><span style=\"font-family: Calibri;\">Lixisoles<\/span><\/a><span style=\"color: #000000; font-family: Calibri;\">; <\/span><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/05\/22\/141646\"><span style=\"font-family: Calibri;\">Lixisoles: Geograf\u00eda ambiente y paisaje<\/span><\/a><span style=\"color: #000000; font-family: Calibri;\">; <\/span><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/05\/31\/141657\"><span style=\"font-family: Calibri;\">Lixisoles: Uso y manejo<\/span><\/a><\/p>\n<p style=\"text-align: justify;\"><strong>Acrisoles<\/strong><\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/06\/07\/142059\">Acrisoles<\/a><span style=\"color: #000000;\">, <\/span><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/06\/13\/142068\">Acrisoles: geograf\u00eda ambiente y paisaje<\/a><span style=\"color: #000000;\">, <\/span><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/06\/20\/142080\">Acrisoles Uso y Manejo<\/a><span style=\"color: #000000;\">, <\/span><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/07\/11\/142092\">Acrisoles en Latinoam\u00e9rica<\/a><span style=\"color: #000000;\">, <\/span><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/06\/28\/142112\">Acrisoles en Europa<\/a><span style=\"color: #000000;\">, <\/span><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/07\/05\/142118\">Tipos de Acrisoles y sus mapas de distribuci\u00f3n en Europa<\/a><span style=\"color: #000000;\">.<\/span><\/p>\n<p style=\"text-align: justify;\"><strong>Albeluvisoles<\/strong><\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/07\/20\/142243\">Albeluvisoles<\/a><span style=\"color: #000000;\">: <\/span><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/07\/27\/142257\">Albeluvisoles: Geograf\u00eda, Ambiente y Paisaje<\/a><span style=\"color: #000000;\">; <\/span><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/08\/03\/142273\">Albeluvisoles: uso y manejo<\/a><span style=\"color: #000000;\">; <\/span><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/08\/10\/142287\">Albeluvisoles en Europa<\/a><span style=\"color: #000000;\">, <\/span><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/08\/10\/142287\">Albeluvisoles y sus mapas de distribuci\u00f3n en Europa<\/a><span style=\"color: #000000;\">,<\/span><\/p>\n<p style=\"text-align: justify;\"><strong><span style=\"font-family: Calibri;\">Podozoles<\/span><\/strong><\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/08\/24\/142310\"><span style=\"font-family: Calibri;\">Podzoles<\/span><\/a><span style=\"color: #000000; font-family: Calibri;\">, <\/span><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/09\/01\/142321\"><span style=\"font-family: Calibri;\">Podzoles: Geograf\u00eda, Ambiente y Paisaje<\/span><\/a><span style=\"color: #000000; font-family: Calibri;\">, <\/span><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/09\/07\/142329\"><span style=\"font-family: Calibri;\">Podzoles Uso y Manejo<\/span><\/a><span style=\"color: #000000; font-family: Calibri;\">, <\/span><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/09\/14\/142338\"><span style=\"font-family: Calibri;\">Podzoles en Europa,<\/span><\/a><a title=\"Enlace permanente a Tipos de Podzoles y sus Mapas de Distribuci\u00f3n en Europa\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/09\/21\/142344\">Tipos de Podzoles y sus Mapas de Distribuci\u00f3n en Europa<\/a><span style=\"color: #000000;\">.<\/span><\/p>\n<p style=\"text-align: justify;\"><strong>Planosoles<\/strong><\/p>\n<p style=\"text-align: justify;\"><a title=\"Enlace permanente a Planosoles WRB\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/09\/28\/142528\">Planosoles WRB<\/a><span style=\"color: #000000;\">, <\/span><a title=\"Enlace permanente a Planosoles: Geograf\u00eda Ambiente y Paisaje\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/10\/04\/142544\">Planosoles: Geograf\u00eda Ambiente y Paisaje<\/a><span style=\"color: #000000;\">, <\/span><a title=\"Enlace permanente a Planosoles: Uso y Manejo\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/10\/12\/142554\">Planosoles: Uso y Manejo<\/a><span style=\"color: #000000;\">, <\/span><a title=\"Enlace permanente a Planosoles en Europa\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/10\/18\/142564\">Planosoles en Europa<\/a><span style=\"color: #000000;\">, <\/span><a title=\"Enlace permanente a Planosoles en Latinoam\u00e9rica\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/10\/25\/142569\">Planosoles en Latinoam\u00e9rica<\/a><span style=\"color: #000000;\">, <\/span><a title=\"Enlace permanente a Tipos de Planosoles y sus Mapas de Distribuci\u00f3n en Europa\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/11\/02\/142577\">Tipos de Planosoles y sus Mapas de Distribuci\u00f3n en Europa<\/a><span style=\"color: #000000;\">.<\/span><\/p>\n<p style=\"text-align: justify;\"><strong>Criosoles<\/strong><\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/11\/08\/142393\">Criosoles WRB<\/a><span style=\"color: #000000;\">, <\/span><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/11\/20\/142421\">Criosoles: Geograf\u00eda, Ambiente y Paisaje<\/a><span style=\"color: #000000;\">, <\/span><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/11\/27\/142435\">Criosoles: Uso y Manejo<\/a><span style=\"color: #000000;\">, <\/span><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/12\/05\/142451\">Criosoles en Europa y la Ant\u00e1rtida<\/a><span style=\"color: #000000;\">, <\/span><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/12\/21\/142457\">Criosoles: Mapas de Distribuci\u00f3n en Europa<\/a><span style=\"color: #000000;\">.<\/span><\/p>\n<p style=\"text-align: justify;\"><strong><span style=\"font-family: Calibri;\">Umbrisoles<\/span><\/strong><\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/01\/09\/142763\"><span style=\"font-family: Calibri;\">Umbrisoles WRB,<\/span><\/a><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/01\/16\/142805\"><span style=\"font-family: Calibri;\">Umbrisoles: Geograf\u00eda Ambiente y Paisaje<\/span><\/a><span style=\"color: #000000; font-family: Calibri;\">, <\/span><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/01\/25\/143713\"><span style=\"font-family: Calibri;\">Umbrisoles: Uso y Manejo<\/span><\/a><span style=\"color: #000000; font-family: Calibri;\">, <\/span><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/01\/31\/142896\"><span style=\"font-family: Calibri;\">Umbrisoles en Europa<\/span><\/a><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/02\/06\/142903\"><span style=\"font-family: Calibri;\">, Tipo de Umbrisoles en Europa y sus Mapas de Distribuci\u00f3n<\/span><\/a><span style=\"color: #000000; font-family: Calibri;\">. <\/span><\/p>\n<p style=\"text-align: justify;\"><strong>Calcisoles<\/strong><\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/02\/13\/143541\"><span style=\"font-family: Calibri;\">Calcisoles WRB<\/span><\/a><span style=\"color: #000000; font-family: Calibri;\">, <\/span><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/02\/20\/143555\"><span style=\"font-family: Calibri;\">Calcisoles: Geograf\u00eda Ambiente y Paisaje<\/span><\/a><span style=\"color: #000000; font-family: Calibri;\">; <\/span><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/02\/27\/143561\"><span style=\"font-family: Calibri;\">Calcisoles: Uso y manejo<\/span><\/a><span style=\"color: #000000; font-family: Calibri;\">; <\/span><a title=\"Enlace permanente: Calcisoles en Latinoam\u00e9rica (WRB)\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/03\/06\/143596\">Calcisoles en Latinoam\u00e9rica (WRB)<\/a><span style=\"color: #000000;\">; <\/span><a title=\"Enlace permanente a Calcisoles en Europa (WRB)\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/03\/13\/143575\">Calcisoles en Europa<\/a><span style=\"color: #000000;\">; <\/span><a title=\"Enlace permanente a Calcisoles (WRB): Mapas de Distribuci\u00f3n en Europa\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/03\/20\/143587\">Calcisoles: Mapas de Distribuci\u00f3n en Europa<\/a><span style=\"color: #000000;\">;<\/span><\/p>\n<p style=\"text-align: justify;\"><strong>Nitisoles (Nitosoles)<\/strong><\/p>\n<p style=\"text-align: justify;\"><a title=\"Enlace permanente a Nitisoles (WRB)\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/03\/30\/143790\"><span style=\"font-family: Calibri;\">Nitisoles (WRB)<\/span><\/a><span style=\"color: #000000; font-family: Calibri;\">; <\/span><a title=\"Enlace permanente a Nitisoles o Nitosoles: Geograf\u00eda Ambiente y Paisaje (Suelos Ferral\u00edticos)\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/04\/06\/143803\"><span style=\"font-family: Calibri;\">Nitisoles o Nitosoles: Geograf\u00eda Ambiente y Paisaje (Suelos Ferral\u00edticos)<\/span><\/a><span style=\"color: #000000; font-family: Calibri;\">; <\/span><a title=\"Enlace permanente a Nitisoles (Nitosoles): Uso y Manejo (Suelos Ferral\u00edticos)\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/04\/10\/143811\"><span style=\"font-family: Calibri;\">Nitisoles (Nitosoles): Uso y Manejo (Suelos Ferral\u00edticos)<\/span><\/a><span style=\"color: #000000; font-family: Calibri;\">; <\/span><a title=\"Enlace permanente a Nitisoles (Nitosoles) en Latinoam\u00e9rica (Suelos Ferral\u00edticos)\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/04\/18\/143817\"><span style=\"font-family: Calibri;\">Nitisoles (Nitosoles) en Latinoam\u00e9rica (Suelos Ferral\u00edticos)<\/span><\/a><span style=\"color: #000000; font-family: Calibri;\">;<\/span><\/p>\n<p style=\"text-align: justify;\"><strong>Ferralsoles<\/strong><\/p>\n<p style=\"text-align: justify;\"><a title=\"Enlace permanente a Ferralsoles (WRB)\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/04\/25\/143832\">Ferralsoles (WRB)<\/a><span style=\"color: #000000;\">; <\/span><a title=\"Enlace permanente a Ferralsoles: Geograf\u00eda, Ambiente y Paisaje (Suelos Tropicales)\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/05\/02\/143842\">Ferralsoles: Geograf\u00eda, Ambiente y Paisaje (Suelos Tropicales)<\/a><span style=\"color: #000000;\">; <\/span><a title=\"Enlace permanente a Ferralsoles: Uso y Manejo (WRB)\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/05\/09\/143848\">Ferralsoles: Uso y Manejo (WRB)<\/a><span style=\"color: #000000;\">, <\/span><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/05\/17\/143874\">Ferralsoles en Latinoam\u00e9rica<\/a><span style=\"color: #000000;\">, <\/span><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/07\/15\/143863\">Paisajes Geomorfol\u00f3gicos de los Tr\u00f3picos H\u00famedos y Subh\u00famedos (Geoformas)<\/a><span style=\"color: #000000;\">,<\/span><\/p>\n<p style=\"text-align: justify;\"><strong>Plintosoles<\/strong><\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/06\/17\/143891\">Plintosoles (WRB) Suelos con Plintita<\/a><span style=\"color: #000000;\">, <\/span><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/06\/26\/143907\">Plintosoles: Geograf\u00eda, Ambiente y paisaje<\/a><span style=\"color: #000000;\">, <\/span><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/07\/06\/143914\">Plintosoles Uso y Manejo<\/a><span style=\"color: #000000;\">, <\/span><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/07\/11\/143929\">Plintosoles (Plintosoles) en Latinoam\u00e9rica<\/a><span style=\"color: #000000;\">,<\/span><\/p>\n<p style=\"text-align: justify;\"><strong>Durisoles<\/strong><\/p>\n<p style=\"text-align: justify;\"><a title=\"Enlace permanente a Durisoles (WRB) Suelos Con Horizontes Endurecidos\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/09\/18\/144494\">Durisoles (WRB) Suelos Con Horizontes Endurecidos<\/a><span style=\"color: #000000;\">; <\/span><a title=\"Enlace permanente a Durisoles: Geograf\u00eda, ambiente y paisaje\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/09\/28\/144500\">Durisoles: Geograf\u00eda, ambiente y paisaje<\/a><span style=\"color: #000000;\">; <\/span><a title=\"Enlace permanente a Durisoles: Uso y Manejo\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/10\/24\/144508\">Durisoles: Uso y Manejo<\/a><span style=\"color: #000000;\">; <\/span><a title=\"Enlace permanente a Durisoles en Latinoam\u00e9rica y Europa\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/10\/31\/144519\">Durisoles en Latinoam\u00e9rica y Europa<\/a><\/p>\n<p style=\"text-align: justify;\"><strong>Gypsisoles (Gipsisoles)<\/strong><\/p>\n<p style=\"text-align: justify;\"><a title=\"Enlace permanente a Gypsisoles o Gipsisoles (WRB): Suelos con yeso Edafogen\u00e9tico\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/11\/07\/144670\">Gypsisoles o Gipsisoles (WRB): Suelos con yeso Edafogen\u00e9tico<\/a><span style=\"color: #000000;\">; <\/span><a title=\"Enlace permanente: Durisoles: Geograf\u00eda, ambiente y paisaje\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/09\/28\/144500\">Durisoles: Geograf\u00eda, ambiente y paisaje<\/a><span style=\"color: #000000;\">; <\/span><a title=\"Enlace permanente: Durisoles: Uso y Manejo\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/10\/24\/144508\">Durisoles: Uso y Manejo<\/a><span style=\"color: #000000;\">; <\/span><a title=\"Enlace permanente: Durisoles en Latinoam\u00e9rica y Europa\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/10\/31\/144519\">Durisoles en Latinoam\u00e9rica y Europa<\/a><span style=\"color: #000000;\">;<\/span><\/p>\n<p style=\"text-align: justify;\"><strong>Solonchaks (Suelos Salinos)<\/strong><\/p>\n<p style=\"text-align: justify;\"><a title=\"Enlace permanente a Paisajes Des\u00e9rticos, \u00c1ridos y Semi\u00e1ridos (Fisiograf\u00eda y Suelos)\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2014\/01\/04\/145025\"><span style=\"font-family: Calibri; font-size: medium;\">Paisajes Des\u00e9rticos, \u00c1ridos y Semi\u00e1ridos (Fisiograf\u00eda y Suelos)<\/span><\/a><span style=\"color: #000000; font-family: Calibri; font-size: medium;\">;<\/span><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/12\/17\/144776\">Solonchaks o Suelos Salinos (WRB)<\/a><span style=\"color: #000000;\">;<\/span> <a title=\"Enlace permanente a Solonchaks (Suelos Salinos): Geograf\u00eda Ambiente y Paisaje\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/12\/30\/144797\"><span style=\"font-family: Calibri; font-size: medium;\">Solonchaks (Suelos Salinos): Geograf\u00eda Ambiente y Paisaje<\/span><\/a><span style=\"color: #000000; font-family: Calibri; font-size: medium;\">; <\/span><a title=\"Enlace permanente a Solonchaks (Suelos Salinos): Uso y Manejo\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2014\/01\/15\/144820\"><span style=\"font-family: Calibri; font-size: medium;\">Solonchaks (Suelos Salinos): Uso y Manejo<\/span><\/a><span style=\"font-family: Calibri;\"><span style=\"color: #000000; font-size: medium;\">;<\/span><span style=\"color: #000000; font-size: medium;\">\u00a0 <\/span><\/span><a title=\"Enlace permanente a Solonchaks (suelos salinos) en Latinoam\u00e9rica y Europa\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2014\/01\/30\/144831\"><span style=\"font-family: Calibri; font-size: medium;\">Solonchaks (suelos salinos) en Latinoam\u00e9rica y Europa<\/span><\/a><span style=\"color: #000000; font-family: Calibri; font-size: medium;\">; <\/span><a title=\"Enlace permanente a Tipos de Solonchaks (suelos Salinos o afectados por sales) y Sus Mapas de Distribuci\u00f3n en Europa\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2014\/02\/06\/144839\"><span style=\"font-family: Calibri; font-size: medium;\">Tipos de Solonchaks (suelos Salinos o afectados por sales) y Sus Mapas de Distribuci\u00f3n en Europa<\/span><\/a><span style=\"color: #000000; font-family: Calibri; font-size: medium;\">; <\/span><\/p>\n<p><strong>Solonetz (suelos S\u00f3dicos) <\/strong><\/p>\n<p><a title=\"Enlace permanente a Solonetz (WRB): Suelos S\u00f3dicos\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2014\/02\/12\/144949\">Solonetz (WRB): Suelos S\u00f3dicos<\/a>; <a title=\"Enlace permanente a Solonetz: Geograf\u00eda Ambiente y Paisaje\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2014\/02\/27\/144958\">Solonetz: Geograf\u00eda Ambiente y Paisaje<\/a>; <a title=\"Enlace permanente a Solonetz: Uso y Manejo\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2014\/03\/06\/144975\">Solonetz: Uso y Manejo<\/a>; <a title=\"Enlace permanente a Solonetz en Latinoam\u00e9rica (Suelos S\u00f3dicos)\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2014\/03\/25\/144996\">Solonetz en Latinoam\u00e9rica (Suelos S\u00f3dicos)<\/a>; <a title=\"Enlace permanente a Solonetz en Europa (suelos S\u00f3dicos)\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2014\/04\/05\/145004\">Solonetz en Europa (suelos S\u00f3dicos)<\/a>;\u00a0Tipos de Solonchaks (suelos Salinos o afectados por sales) y Sus Mapas de Distribuci\u00f3n en Europa.<\/p>\n<p><strong>Chernozems (Suelos de Estepas h\u00famedas)<\/strong><\/p>\n<p><a title=\"Enlace permanente a Estepas, Praderas y Pampas\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2014\/04\/23\/145037\">Estepas, Praderas y Pampas<\/a>; <a title=\"Enlace permanente a Chernozems (Suelos de Praderas, Estepas y Pampas)\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2014\/04\/26\/145061\">Chernozems (Suelos de Praderas, Estepas y Pampas)<\/a>;<a title=\"Enlace permanente a Chernozems: Geograf\u00eda Ambiente y Paisaje\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2014\/05\/08\/145069\">Chernozems: Geograf\u00eda Ambiente y Paisaje<\/a>; <a title=\"Enlace permanente a Chernozems: Uso y Manejo\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2014\/05\/15\/145080\">Chernozems: Uso y Manejo<\/a>; <a title=\"Enlace permanente a Chernozems en Europa y Latinoam\u00e9rica\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2014\/06\/02\/145093\">Chernozems en Europa y Latinoam\u00e9rica<\/a>; <a title=\"Enlace permanente a Tipos de Chernozems (Suelos de Estepa Fr\u00eda) y sus Mapas de Distribuci\u00f3n en Europa\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2014\/06\/15\/145101\">Tipos de Chernozems (Suelos de Estepa Fr\u00eda) y sus Mapas de Distribuci\u00f3n en Europa<\/a><\/p>\n<p><strong>Kastanozems (suelos de estepas secas)<\/strong><\/p>\n<p><a title=\"Enlace permanente a Kastanozems (KS) (Suelos Pardos de Estepas Secas)\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2014\/09\/10\/145408\">Kastanozems (KS) (Suelos Pardos de Estepas Secas)<\/a>; <a title=\"Enlace permanente a Kastanozems: Geograf\u00eda, Ambiente y Paisaje (Suelos Pardos de Estepa seca)\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2014\/09\/25\/145415\">Kastanozems: Geograf\u00eda, Ambiente y Paisaje (Suelos Pardos de Estepa seca)<\/a>; <a title=\"Enlace permanente a Kastanozems: Uso y Manejo (Suelos de Estepas Secas)\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2014\/10\/07\/145423\">Kastanozems: Uso y Manejo (Suelos de Estepas Secas)<\/a>; <a title=\"Enlace permanente a Kastanozems en Latinoam\u00e9rica (Suelos de Estepa Seca)\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2014\/10\/15\/145437\">Kastanozems en Latinoam\u00e9rica (Suelos de Estepa Seca)<\/a>; <a title=\"Enlace permanente a Kastanozems en Europa (Suelos de Estepas Secas)\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2014\/11\/03\/145443\">Kastanozems en Europa (Suelos de Estepas Secas)<\/a><\/p>\n<p><strong>Pheozems (suelos de estepas subh\u00famedas)<\/strong><\/p>\n<p><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2015\/02\/12\/145465\">Phaeozems<\/a>, <a title=\"Enlace permanente a Phaeozem (Feozem): Geograf\u00eda, Ambiente y Paisaje\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2015\/02\/18\/145471\">Phaeozem (Feozem): Geograf\u00eda, Ambiente y Paisaje<\/a>, <a title=\"Enlace permanente: Phaeozems o Feozems en Latinoam\u00e9rica\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2015\/04\/30\/145483\"><span style=\"color: #0000ff; font-family: Calibri; font-size: medium;\">Phaeozems o Feozems en Latino Am\u00e9rica<\/span><\/a>.<\/p>\n<h3>Im\u00e1genes Relacionadas:<\/h3>","protected":false},"excerpt":{"rendered":"<p>Phaeozems. Mapa de Europa. Fuente: Bur\u00f3 Europeo de Suelos Los Phaeozems o Feozems\u00a0se extienden aproximadamente por unos 70.000 km2 de la Uni\u00f3n Europea (UE), lo que equivale aproximadamente al 1.7% de la cobertura de suelos en esta mancomunidad de pa\u00edses. Este Grupo de Suelos de Referencia de la WRB se ubica principalmente en el centro y este de Europa, as\u00ed como en Espa\u00f1a. En la UE se presentan cinco tipos de Phaeozems (segundo nivel de la WRB, 1998) que en orden de mayor a menos abundancia ser\u00edan los siguientes: Phaeozem calc\u00e1ricos (PHca 15383 km2; 31.11%), Phaeozem gleycos (PHgl 14374 km2;\u2026<\/p>\n","protected":false},"author":26,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0},"categories":[1929,604],"tags":[46796,47581,46744,46740,47222],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":4}},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Phaeozems. Mapa de Europa. Fuente: Bur\u00f3 Europeo de Suelos Los Phaeozems o Feozems se extienden aproximadamente por unos 70.000 km2 de la Uni\u00f3n Europea (UE), lo que equivale aproximadamente al 1.7% de la cobertura de suelos en esta mancomunidad de pa\u00edses. Este Grupo de Suelos de Referencia de la WRB se ubica principalmente en el centro\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Juan Jos\u00e9 Ib\u00e1\u00f1ez\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2015\/05\/15\/145493\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Un Universo invisible bajo nuestros pies - Los suelos y la vida\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Phaeozems (Feozems) En Europa - Un Universo invisible bajo nuestros pies\" \/>\n\t\t<meta property=\"og:description\" content=\"Phaeozems. Mapa de Europa. Fuente: Bur\u00f3 Europeo de Suelos Los Phaeozems o Feozems se extienden aproximadamente por unos 70.000 km2 de la Uni\u00f3n Europea (UE), lo que equivale aproximadamente al 1.7% de la cobertura de suelos en esta mancomunidad de pa\u00edses. Este Grupo de Suelos de Referencia de la WRB se ubica principalmente en el centro\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2015\/05\/15\/145493\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2015-05-15T13:03:24+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2015-05-15T13:03:24+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/juan.j.marti.14\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Phaeozems (Feozems) En Europa - Un Universo invisible bajo nuestros pies\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Phaeozems. Mapa de Europa. Fuente: Bur\u00f3 Europeo de Suelos Los Phaeozems o Feozems se extienden aproximadamente por unos 70.000 km2 de la Uni\u00f3n Europea (UE), lo que equivale aproximadamente al 1.7% de la cobertura de suelos en esta mancomunidad de pa\u00edses. Este Grupo de Suelos de Referencia de la WRB se ubica principalmente en el centro\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2015\\\/05\\\/15\\\/145493#blogposting\",\"name\":\"Phaeozems (Feozems) En Europa - Un Universo invisible bajo nuestros pies\",\"headline\":\"Phaeozems (Feozems) En Europa\",\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"http:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/wp-content\\\/blogs.dir\\\/42\\\/files\\\/mapas-de-los-suelos-de-europa-wrb\\\/phaeozem-europa-esb.jpg\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2015\\\/05\\\/15\\\/145493\\\/#articleImage\"},\"datePublished\":\"2015-05-15T14:03:24+01:00\",\"dateModified\":\"2015-05-15T14:03:24+01:00\",\"inLanguage\":\"es-ES\",\"commentCount\":1,\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2015\\\/05\\\/15\\\/145493#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2015\\\/05\\\/15\\\/145493#webpage\"},\"articleSection\":\"Curso B\\u00e1sico: Tipos de Suelos del Mundo, Geograf\\u00eda de Suelos y Megaedafolog\\u00eda, Europa, Feozems, geograf\\u00eda de suelos, Mapa de Suelos, Phaeozems\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2015\\\/05\\\/15\\\/145493#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/geografia-de-suelos-y-megaedafologia#listItem\",\"name\":\"Geograf\\u00eda de Suelos y Megaedafolog\\u00eda\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/geografia-de-suelos-y-megaedafologia#listItem\",\"position\":2,\"name\":\"Geograf\\u00eda de Suelos y Megaedafolog\\u00eda\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/geografia-de-suelos-y-megaedafologia\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2015\\\/05\\\/15\\\/145493#listItem\",\"name\":\"Phaeozems (Feozems) En Europa\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2015\\\/05\\\/15\\\/145493#listItem\",\"position\":3,\"name\":\"Phaeozems (Feozems) En Europa\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/geografia-de-suelos-y-megaedafologia#listItem\",\"name\":\"Geograf\\u00eda de Suelos y Megaedafolog\\u00eda\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#organization\",\"name\":\"Un Universo invisible bajo nuestros pies\",\"description\":\"Los suelos y la vida\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/files\\\/2022\\\/02\\\/logo.png\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2015\\\/05\\\/15\\\/145493\\\/#organizationLogo\",\"width\":217,\"height\":72},\"image\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2015\\\/05\\\/15\\\/145493\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/juan.j.marti.14\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo\",\"name\":\"Juan Jos\\u00e9 Ib\\u00e1\\u00f1ez\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2015\\\/05\\\/15\\\/145493#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/387f3a100385573d8f42ce2a3211fd1c?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Juan Jos\\u00e9 Ib\\u00e1\\u00f1ez\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2015\\\/05\\\/15\\\/145493#webpage\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2015\\\/05\\\/15\\\/145493\",\"name\":\"Phaeozems (Feozems) En Europa - Un Universo invisible bajo nuestros pies\",\"description\":\"Phaeozems. Mapa de Europa. Fuente: Bur\\u00f3 Europeo de Suelos Los Phaeozems o Feozems se extienden aproximadamente por unos 70.000 km2 de la Uni\\u00f3n Europea (UE), lo que equivale aproximadamente al 1.7% de la cobertura de suelos en esta mancomunidad de pa\\u00edses. Este Grupo de Suelos de Referencia de la WRB se ubica principalmente en el centro\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2015\\\/05\\\/15\\\/145493#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\"},\"datePublished\":\"2015-05-15T14:03:24+01:00\",\"dateModified\":\"2015-05-15T14:03:24+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#website\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/\",\"name\":\"Un Universo invisible bajo nuestros pies\",\"description\":\"Los suelos y la vida\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Phaeozems (Feozems) En Europa - Un Universo invisible bajo nuestros pies","description":"Phaeozems. Mapa de Europa. Fuente: Bur\u00f3 Europeo de Suelos Los Phaeozems o Feozems se extienden aproximadamente por unos 70.000 km2 de la Uni\u00f3n Europea (UE), lo que equivale aproximadamente al 1.7% de la cobertura de suelos en esta mancomunidad de pa\u00edses. Este Grupo de Suelos de Referencia de la WRB se ubica principalmente en el centro","canonical_url":"https:\/\/www.madrimasd.org\/blogs\/universo\/2015\/05\/15\/145493","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2015\/05\/15\/145493#blogposting","name":"Phaeozems (Feozems) En Europa - Un Universo invisible bajo nuestros pies","headline":"Phaeozems (Feozems) En Europa","author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author"},"publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#organization"},"image":{"@type":"ImageObject","url":"http:\/\/www.madrimasd.org\/blogs\/universo\/wp-content\/blogs.dir\/42\/files\/mapas-de-los-suelos-de-europa-wrb\/phaeozem-europa-esb.jpg","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2015\/05\/15\/145493\/#articleImage"},"datePublished":"2015-05-15T14:03:24+01:00","dateModified":"2015-05-15T14:03:24+01:00","inLanguage":"es-ES","commentCount":1,"mainEntityOfPage":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2015\/05\/15\/145493#webpage"},"isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2015\/05\/15\/145493#webpage"},"articleSection":"Curso B\u00e1sico: Tipos de Suelos del Mundo, Geograf\u00eda de Suelos y Megaedafolog\u00eda, Europa, Feozems, geograf\u00eda de suelos, Mapa de Suelos, Phaeozems"},{"@type":"BreadcrumbList","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2015\/05\/15\/145493#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo#listItem","position":1,"name":"Home","item":"https:\/\/www.madrimasd.org\/blogs\/universo","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/geografia-de-suelos-y-megaedafologia#listItem","name":"Geograf\u00eda de Suelos y Megaedafolog\u00eda"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/geografia-de-suelos-y-megaedafologia#listItem","position":2,"name":"Geograf\u00eda de Suelos y Megaedafolog\u00eda","item":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/geografia-de-suelos-y-megaedafologia","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2015\/05\/15\/145493#listItem","name":"Phaeozems (Feozems) En Europa"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2015\/05\/15\/145493#listItem","position":3,"name":"Phaeozems (Feozems) En Europa","previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/geografia-de-suelos-y-megaedafologia#listItem","name":"Geograf\u00eda de Suelos y Megaedafolog\u00eda"}}]},{"@type":"Organization","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#organization","name":"Un Universo invisible bajo nuestros pies","description":"Los suelos y la vida","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/","logo":{"@type":"ImageObject","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2015\/05\/15\/145493\/#organizationLogo","width":217,"height":72},"image":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2015\/05\/15\/145493\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/juan.j.marti.14"]},{"@type":"Person","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo","name":"Juan Jos\u00e9 Ib\u00e1\u00f1ez","image":{"@type":"ImageObject","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2015\/05\/15\/145493#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/387f3a100385573d8f42ce2a3211fd1c?s=96&d=mm&r=g","width":96,"height":96,"caption":"Juan Jos\u00e9 Ib\u00e1\u00f1ez"}},{"@type":"WebPage","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2015\/05\/15\/145493#webpage","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/2015\/05\/15\/145493","name":"Phaeozems (Feozems) En Europa - Un Universo invisible bajo nuestros pies","description":"Phaeozems. Mapa de Europa. Fuente: Bur\u00f3 Europeo de Suelos Los Phaeozems o Feozems se extienden aproximadamente por unos 70.000 km2 de la Uni\u00f3n Europea (UE), lo que equivale aproximadamente al 1.7% de la cobertura de suelos en esta mancomunidad de pa\u00edses. Este Grupo de Suelos de Referencia de la WRB se ubica principalmente en el centro","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#website"},"breadcrumb":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2015\/05\/15\/145493#breadcrumblist"},"author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author"},"creator":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author"},"datePublished":"2015-05-15T14:03:24+01:00","dateModified":"2015-05-15T14:03:24+01:00"},{"@type":"WebSite","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#website","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/","name":"Un Universo invisible bajo nuestros pies","description":"Los suelos y la vida","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Un Universo invisible bajo nuestros pies - Los suelos y la vida","og:type":"article","og:title":"Phaeozems (Feozems) En Europa - Un Universo invisible bajo nuestros pies","og:description":"Phaeozems. Mapa de Europa. Fuente: Bur\u00f3 Europeo de Suelos Los Phaeozems o Feozems se extienden aproximadamente por unos 70.000 km2 de la Uni\u00f3n Europea (UE), lo que equivale aproximadamente al 1.7% de la cobertura de suelos en esta mancomunidad de pa\u00edses. Este Grupo de Suelos de Referencia de la WRB se ubica principalmente en el centro","og:url":"https:\/\/www.madrimasd.org\/blogs\/universo\/2015\/05\/15\/145493","og:image":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png","og:image:secure_url":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png","article:published_time":"2015-05-15T13:03:24+00:00","article:modified_time":"2015-05-15T13:03:24+00:00","article:publisher":"https:\/\/www.facebook.com\/juan.j.marti.14","twitter:card":"summary","twitter:title":"Phaeozems (Feozems) En Europa - Un Universo invisible bajo nuestros pies","twitter:description":"Phaeozems. Mapa de Europa. Fuente: Bur\u00f3 Europeo de Suelos Los Phaeozems o Feozems se extienden aproximadamente por unos 70.000 km2 de la Uni\u00f3n Europea (UE), lo que equivale aproximadamente al 1.7% de la cobertura de suelos en esta mancomunidad de pa\u00edses. Este Grupo de Suelos de Referencia de la WRB se ubica principalmente en el centro","twitter:image":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png"},"aioseo_meta_data":{"post_id":"145493","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":null,"isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","tabs":null,"priority":null,"frequency":null,"local_seo":null,"created":"2022-06-03 17:05:37","updated":"2026-05-26 18:19:48","limit_modified_date":false,"ai":null,"breadcrumb_settings":null,"seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/geografia-de-suelos-y-megaedafologia\" title=\"Geograf\u00eda de Suelos y Megaedafolog\u00eda\">Geograf\u00eda de Suelos y Megaedafolog\u00eda<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tPhaeozems (Feozems) En Europa\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.madrimasd.org\/blogs\/universo"},{"label":"Geograf\u00eda de Suelos y Megaedafolog\u00eda","link":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/geografia-de-suelos-y-megaedafologia"},{"label":"Phaeozems (Feozems) En Europa","link":"https:\/\/www.madrimasd.org\/blogs\/universo\/2015\/05\/15\/145493"}],"_links":{"self":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts\/145493"}],"collection":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/comments?post=145493"}],"version-history":[{"count":10,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts\/145493\/revisions"}],"predecessor-version":[{"id":147017,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts\/145493\/revisions\/147017"}],"wp:attachment":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/media?parent=145493"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/categories?post=145493"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/tags?post=145493"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}