{"id":145642,"date":"2015-01-27T15:30:13","date_gmt":"2015-01-27T14:30:13","guid":{"rendered":"http:\/\/www.madrimasd.org\/blogs\/universo\/?p=145642"},"modified":"2015-01-27T15:30:13","modified_gmt":"2015-01-27T14:30:13","slug":"los-jardines-preuropeos-maories-de-nueva-zelanda-sus-antrosoles-manejo-y-biocarbones-biochar","status":"publish","type":"post","link":"https:\/\/www.madrimasd.org\/blogs\/universo\/2015\/01\/27\/145642","title":{"rendered":"Los Jardines Preuropeos Maor\u00edes de Nueva Zelanda, sus Antrosoles, manejo y biocarbones (Biochar)"},"content":{"rendered":"<p align=\"center\"><span style=\"color: #000000; font-family: Calibri; font-size: medium;\"><img decoding=\"async\" class=\"ngg-singlepic ngg-center\" src=\"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-content\/blogs.dir\/42\/files\/255\/paisaje-agrario-maori-fuente-ministry-for-culture-and-heritage.jpg\" alt=\"paisaje-agrario-maori-fuente-ministry-for-culture-and-heritage\" \/>\u00a0<\/span><\/p>\n<p align=\"center\"><a href=\"http:\/\/whenuaviz.landcareresearch.co.nz\/Search\/DigitalNZSearch?placeName=Kainga\"><span style=\"color: #0000ff;\">Paisaje Agrario Maor\u00ed. Fuente:<\/span><span style=\"color: #0000ff;\">Ministry for Culture and Heritage<\/span><\/a><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Ya os comentamos en un post anterior como la llegada de los Maor\u00edes a Nueva Zelanda transform\u00f3 sus paisajes pr\u00edstinos, si bien, poco a\u00f1adimos acerca de su agricultura (\u201c<\/span><a title=\"Enlace permanente: Culturas Abor\u00edgenes, Paisajes, Incendios y Suelos. El Pueblo Maor\u00ed en Nueva Zelanda\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/04\/26\/138064\">Culturas Abor\u00edgenes, Paisajes, Incendios y Suelos. El Pueblo Maor\u00ed en Nueva Zelanda<\/a><span style=\"text-decoration: underline;\">\u00ab)<\/span><span style=\"color: #000000;\">. Recientemente El <\/span><a href=\"http:\/\/onlinelibrary.wiley.com\/journal\/10.1111\/(ISSN)1365-2389\"><span style=\"color: #0000ff;\">European Journal of Soil Science<\/span><\/a><span style=\"color: #000000;\"> ha publicado un monogr\u00e1fico sobre el <\/span><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/11\/03\/144639\"><span style=\"color: #0000ff;\">biochar o biocarb\u00f3n<\/span><\/a><span style=\"color: #000000;\">, que como muchos de vosotros sab\u00e9is, comenz\u00f3 a investigarse fan\u00e1ticamente a partir de su descubrimiento en las <\/span><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2008\/05\/11\/91490\"><span style=\"color: #0000ff;\">Terras Pretas do Indio amaz\u00f3nicas<\/span><\/a><span style=\"color: #000000;\">, de las que tanto os hemos hablado. Los contenidos de este n\u00famero especial son sorprendentes reveladores, por lo que merecen abordarse\u00a0en un post aparte, con tintes que no se si calificar como sociol\u00f3gicos o psicol\u00f3gicos. A pesar de todo,\u00a0existen algunos art\u00edculos que como el que da lugar a este entrega, atesoraban un contenido interesante. Se trata del <\/span><span style=\"color: #3366ff;\"><strong>manejo de suelos en los denominados Jardines Maor\u00edes Preuropeos<\/strong><\/span><span style=\"color: #000000;\">. <\/span><strong><span style=\"color: #000000;\"><span style=\"color: #3366ff;\">Hablamos de la\u00a0gesti\u00f3n que la cultura maor\u00ed hac\u00eda de sus suelos agrarios<\/span><\/span><\/strong><span style=\"color: #000000;\"> con vistas a la producci\u00f3n de cultivos. Abajo os muestro un material relativamente abundante escrito a toda velocidad, por lo que contendr\u00e1 algunos errores, especialmente dada la premura en su traducci\u00f3n\/redacci\u00f3n. Pido disculpas por ello. Tan solo exponeros antes unas breves l\u00edneas centradas principalmente en los aspectos etnoedafol\u00f3gicos que considero m\u00e1s relevantes, entre el material le\u00eddo. <\/span><span style=\"color: #000000;\">\u00a0<\/span><\/p>\n<p align=\"center\"><span style=\"color: #000000;\">\u00a0<\/span><img decoding=\"async\" class=\"ngg-singlepic ngg-center\" style=\"width: 476px; height: 297px;\" src=\"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-content\/blogs.dir\/42\/files\/255\/recreacion-de-los-jardines-maories-fuente-chris-gregory-alphathreads.jpg\" alt=\"recreacion-de-los-jardines-maories-fuente-chris-gregory-alphathreads\" width=\"952\" height=\"567\" \/><\/p>\n<p align=\"center\"><a href=\"https:\/\/alphathread.wordpress.com\/category\/new-zealand\/\"><span style=\"color: #0000ff;\">Recreaci\u00f3n de los Jardines Maor\u00edes: Fuente: Chris Gregory&#8217;s Alphathreads<\/span><\/a><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Al parecer, El <\/span><a href=\"http:\/\/es.wikipedia.org\/wiki\/Maor\u00ed\"><span style=\"color: #0000ff;\">Pueblo Maor\u00ed<\/span><\/a><span style=\"color: #000000;\"> atesoraba <\/span><span style=\"color: #3366ff;\"><strong>sorprendentes conocimientos de los suelos <\/strong><span style=\"color: #333333;\">que a\u00fan perviven en su lengua. Del mismo modo,<\/span> <strong>discern\u00edan entre diferentes tipos de suelos<\/strong>. <strong>La gesti\u00f3n de sus cultivos inclu\u00eda principalmente el trasporte de arena y gravas a sus parcelas, pero tambi\u00e9n las enmendaban con<\/strong><\/span><span style=\"color: #000000;\"> limo, arcillas, conchas (carbonatos) materia org\u00e1nica carbonizada (es decir <\/span><a href=\"http:\/\/digital.csic.es\/bitstream\/10261\/94182\/1\/Detailed%20carbon%20chemistry_Sevilla.pdf\"><span style=\"color: #0000ff;\">utilizaban biocarbones<\/span><\/a><span style=\"color: #000000;\">), etc. Por lo que se sabe. su sistema de manejo inclu\u00eda sutilezas como la de <\/span><strong><span style=\"color: #000000;\"><span style=\"color: #3366ff;\">cubrir el suelo con una especie de mulching, con vistas a que la cobertura superficial no fuera presa de la erosi\u00f3n e\u00f3lica<\/span><\/span><\/strong><span style=\"color: #000000;\">. De este modo <\/span><strong><span style=\"color: #000000;\"><span style=\"color: #3366ff;\">modificaban<\/span> <span style=\"color: #3366ff;\">sus suelos antropogen\u00e9ticamante<\/span><\/span><\/strong><span style=\"color: #000000;\"> hasta el punto de que <\/span><span style=\"color: #3366ff;\"><strong>algunos autores los han clasificado en dos tipos diferentes de Antrosoles \u00a0Pl\u00e1gicos<\/strong><\/span><span style=\"color: #000000;\"> (<\/span><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2008\/11\/01\/105554\"><span style=\"color: #0000ff;\">plagen, pl\u00e1cico<\/span><\/a><span style=\"text-decoration: underline;\"><span style=\"color: #0000ff; text-decoration: underline;\">)<\/span><\/span><span style=\"color: #000000;\">. Tambi\u00e9n <\/span><strong><span style=\"color: #000000;\"><span style=\"color: #3366ff;\">constru\u00edan mont\u00edculos en donde depositaban las semillas de las especies a cultivar<\/span><\/span><\/strong><span style=\"color: #000000;\">, principalmente batata. En una de las fuentes consultadas se menta que, <\/span><strong><span style=\"color: #000000;\"><span><span style=\"color: #3366ff;\">por sus tradiciones y tab\u00faes<\/span>, <strong><span style=\"color: #3366ff;\">no pod\u00eda\u00a0a\u00f1adirse<\/span><\/strong>\u00a0<span style=\"color: #3366ff;\">abono org\u00e1nico sin tratar<\/span>\u00a0<\/span><\/span><\/strong><span style=\"color: #000000;\">. As\u00ed pues, la gesti\u00f3n de los <\/span><a href=\"http:\/\/envirohistorynz.com\/2010\/06\/07\/maori-gardening-in-pre-european-nz\/\"><span style=\"color: #0000ff;\">jardines Maor\u00edes<\/span><\/a><span style=\"color: #000000;\">, al parecer contemplaban\u00a0procedimientos que hoy se consideran modernos ya que las gravas, el mulching y las enmiendas precocinadas (como los biocarbones), (\u2026) <\/span><a href=\"http:\/\/www.archaeopedia.com\/wiki\/index.php?title=Maori_Gardening\"><span style=\"color: #0000ff;\">Jardines Maor\u00edes<\/span><\/a><span style=\"color: #000000;\"> resultan ser <\/span><strong><span style=\"color: #000000;\"><span style=\"color: #3366ff;\">otro ejemplo, del ingenio de los primeros agricultores o cazadores\/recolectores\/agricultores que muestran como la agricultura naci\u00f3 ya con su vista puesta en el suelo<\/span><\/span><\/strong><span style=\"color: #000000;\">.<\/span><\/p>\n<p style=\"text-align: center;\" align=\"center\"><img decoding=\"async\" class=\"ngg-singlepic ngg-center aligncenter\" src=\"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-content\/blogs.dir\/42\/files\/255\/mahor.jpg\" alt=\"mahor\" width=\"499\" height=\"310\" \/><\/p>\n<p align=\"center\"><a href=\"http:\/\/repository.openpolytechnic.ac.nz\/bitstream\/handle\/11072\/1208\/Use%20of%20Charcoal.ppt?sequence=1\"><span style=\"color: #0000ff;\">Recreaci\u00f3n de algunas pr\u00e1cticas Maor\u00edes del Manejo del Suelo. <\/span><span style=\"color: #0000ff;\">Fuente:<\/span><span style=\"color: #0000ff;\">\u00a0 <\/span><span style=\"color: #0000ff;\">Mike Burtenshaw The Open Polytechnic of New Zealand<\/span><\/a><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Tan solo se\u00f1alar adicionalmente que <strong><span style=\"color: #3366ff;\">(i)<\/span><\/strong> los an\u00e1lisis realizados sobre <\/span><span style=\"color: #3366ff;\"><strong>aquellos biochar constatan su recalcitrante composici\u00f3n y dificultad para\u00a0 biodegradarse<\/strong><\/span><span style=\"color: #000000;\"> (algo bastante natural cuando la materia org\u00e1nica es carbonizada, como ocurre tras un fuego natural); y <strong><span style=\"color: #3366ff;\">(ii)<\/span><\/strong> que ya <\/span><span style=\"color: #3366ff;\"><strong>se han detectado la adici\u00f3n de biochar ind\u00edgena en tres continentes<\/strong><\/span><span style=\"color: #000000;\">, como lo son: <\/span><span style=\"color: #3366ff;\"><strong>Am\u00e9rica del Sur<\/strong><\/span><span style=\"color: #000000;\"> (la Amazon\u00eda), <\/span><span style=\"color: #3366ff;\"><strong>As\u00eda<\/strong><\/span><span style=\"color: #000000;\"> (<\/span><strong><span style=\"color: #3366ff;\">Nepal<\/span><\/strong><span style=\"color: #000000;\">), y ahora vemos que tambi\u00e9n en <\/span><span style=\"color: #3366ff;\"><strong>Ocean\u00eda<\/strong><\/span><span style=\"color: #333333;\">. Seguro que con el tiempo ir\u00e1n saliendo a la luz otros muchos ejemplos. Os dejo con el material recopilado y traducido apresuradamente (so pena de eternizarme), pidiendo de antemano disculpas.<\/span><\/p>\n<p><strong><span style=\"color: #000000;\"><span style=\"color: #008000;\">Juan Jos\u00e9 Ib\u00e1\u00f1ez<\/span> <\/span><\/strong><\/p>\n<p align=\"center\"><img decoding=\"async\" class=\"ngg-singlepic ngg-center\" src=\"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-content\/blogs.dir\/42\/files\/255\/antrosoles-de-los-jardines-mahories.jpg\" alt=\"antrosoles-de-los-jardines-mahories\" \/><\/p>\n<p align=\"center\"><a href=\"http:\/\/www.stuff.co.nz\/nelson-mail\/features\/lifestyle\/going-green\/9162181\/Coal-solution-a-burning-issue\"><span style=\"color: #0000ff;\">Antrosoles de los jardines Maor\u00edes. Fuente Nelson Mail<\/span><\/a><\/p>\n<p><span style=\"color: #000000;\"><!--more--><\/span><\/p>\n<p style=\"text-align: justify;\"><a title=\"Enlace permanente: Culturas Abor\u00edgenes, Paisajes, Incendios y Suelos. El Pueblo Maor\u00ed en Nueva Zelanda\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/04\/26\/138064\">Culturas Abor\u00edgenes, Paisajes, Incendios y Suelos. El Pueblo Maor\u00ed en Nueva Zelanda<\/a><span style=\"color: #000000;\"> (como los Maor\u00edes transformaran sus paisajes pr\u00edstinos)<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">The stability of biochar, a form of charcoal intentionally made to be added to soil to sequester carbon (C) and improve its function, remains unclear. As it is not feasible to perform long-term (decades, centuries) laboratory experiments to assess biochar evolution after soil amendment, the study of ancient archaeological charcoals can help to identify characteristics (and possibly molecular markers) associated with the decomposition and preservation dynamics of biochar in specific pedoclimatic environments.<\/span><\/p>\n<p style=\"text-align: justify;\"><strong><em>La estabilidad de biocarb\u00f3n, una forma de carb\u00f3n vegetal intencionalmente elaborado con vistas a ser a\u00f1adido al suelo para secuestrar el carbono (C) y mejorar su funci\u00f3n, sigue estando poco clara desde un punto de vista cient\u00edfico<\/em><\/strong><em>. Ya que no es factible realizar a largo plazo (d\u00e9cadas, siglos), experimentos de laboratorio para evaluar la evoluci\u00f3n del biochar tras su incorporaci\u00f3n al suelo, el estudio de los antiguos carboncillos arqueol\u00f3gicos puede ayudarnos a identificar las caracter\u00edsticas (y posiblemente marcadores moleculares) asociados a la din\u00e1mica de la descomposici\u00f3n y de la preservaci\u00f3n del biochar en entornos edafoclim\u00e1ticos concretos.<\/em><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">\u00a0<\/span><span style=\"color: #000000;\">In this study, the chemical composition of the organic carbon fractions of three charcoals from pre-European Maori gardens of New Zealand (buried &gt;25 cm depth) was thoroughly assessed. Complementary short-term incubations of charcoals in sand were used to (i) evaluate the stability of C in the short-medium term, (ii) model its mineralization processes and (iii) estimate the C turnover. <\/span><\/p>\n<p style=\"text-align: justify;\"><em>En este estudio, la composici\u00f3n qu\u00edmica de las fracciones de carbono org\u00e1nico procedentes de tres carbones de pre-europeos de los <strong>jardines maor\u00edes de Nueva Zelanda<\/strong> (enterrados a m\u00e1s de 25 cm de profundidad) fue analizada a fondo. Incubaciones complementarias a corto plazo de los carbones de le\u00f1a en la arena fueron utilizadas llevados a cabo al objeto de (i) evaluar la estabilidad de carbono a corto-medio plazo, (ii) modelar sus procesos de mineralizaci\u00f3n y (iii) la estimaci\u00f3n de su reciclado. Omitimos aqu\u00ed los sofisticados m\u00e9todos llevados a cabo por los autores<\/em><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">The oldest buried deposit (770\u00b150 years BP) still retained un-charred or weakly charred lignocellulosic material, indicating that such material survived decomposition processes for several centuries. The amount of organic C mineralized in 109 days was &lt;0.5% of the initial charcoal-C. No differences in MRT among samples were detected in spite of inferred differences in thermal impact. Longer-term incubations are needed to obtain better estimates of C turnover rates in charred material.<\/span><\/p>\n<p style=\"text-align: justify;\"><strong><em>El dep\u00f3sito m\u00e1s antiguo enterrado (770 \u00b1 50 a\u00f1os) a\u00fan conservaba material lignocelul\u00f3sico d\u00e9bilmente carbonizado, lo que indica que este tipo de material ha resistido los procesos de descomposici\u00f3n durante varios siglos<\/em><\/strong><em>. La cantidad de C org\u00e1nico mineralizado en 109 d\u00edas era inferior al 0,5% del carb\u00f3n de le\u00f1a inicial. Se necesitan las incubaciones a largo plazo con vistas a obtener mejores estimaciones de las tasas de retorno de C en el material carbonizado.<\/em><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Fire, either natural or anthropogenic, has contributed to the development of the landscape of New Zealand (McGlone &amp; Wilmshurst, 1999). Polynesians settled in New Zealand <\/span><em><span style=\"color: #000000;\">c<\/span><\/em><span style=\"color: #000000;\">. 1200\u20131400AD (McGlone &amp; Wilmshurst, 1999) and made widespread.<\/span><\/p>\n<p style=\"text-align: justify;\"><strong><em><span style=\"color: #000000;\">Fuego, ya sea natural o antropog\u00e9nico, ha contribuido al desarrollo del paisaje de Nueva Zelanda<\/span><\/em><\/strong><em><span style=\"color: #000000;\">. Los Polinesios se establecieron en Nueva Zelanda alrededor de 1200-1400AD.<\/span><\/em><\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/repository.openpolytechnic.ac.nz\/bitstream\/handle\/11072\/1208\/Use%20of%20Charcoal.ppt?sequence=1\"><span style=\"color: #0000ff;\">Ver este ppt<\/span><\/a><span style=\"text-decoration: underline;\"><span style=\"color: #0000ff;\"> (posee imagines del manejo del suelo muy interesantes)<\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">M\u0101ori commonly amended soils by adding sand and gravel but did they deliberately use charcoal as a addition? Deeply held beliefs concerning and sacred and profane meant the use of animal dung as manure was totally abhorrent Various tapus (taboos) played and important part in the agricultural life of M\u0101ori Food must not be contaminated by unsanctioned contact with manure including human waste<\/span><span style=\"color: #000000;\">Colenso (1880) described the transportation and addition of sand to garden soils as an annual task.<\/span><\/p>\n<p style=\"text-align: justify;\"><strong><em>Los suelos destinados a la producci\u00f3n por el pueblo Maor\u00ed com\u00fanmente recib\u00edan arena y grava y carb\u00f3n. Creencias profundamente arraigadas entre lo sagrado y lo profano implicaba que el uso de esti\u00e9rcol como abono eras aborrecido. Varios tab\u00faes jugaron una parte importante en la vida agr\u00edcola de los maor\u00edes alimentaci\u00f3n no debe ser contaminado por el contacto no autorizado con esti\u00e9rcol incluyendo desechos humanos, habi\u00e9ndose sido descrito el transporte y la adici\u00f3n de arena anualmente a los suelos de sus jardines<\/em><\/strong><em>.<\/em><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">McFadgen classified M\u0101ori plaggen soils as varying between two types. One where sediments are thickly spread 20cm-30cm deep but poorly mixed with base soil and one where transported sediments are well mixed with the base soil. Gumbley believes sand was added at the position of individual puke (mounds) and the excavated soil dispatched by sand was used to form the planting mound<\/span><\/p>\n<p style=\"text-align: justify;\"><strong><em><span style=\"color: #000000;\">McFadgen clasifica los antrosoles maor\u00edes como suelos plaggen discerniendo entre dos tipos<\/span><\/em><\/strong><em>. Uno donde los sedimentos a\u00f1adidos alcanzaban espesores de unos 20-30cm de profundidad, aunque escasamente mezclados con los materiales ed\u00e1ficos y otro en donde los mentados materiales transportados resultaban adecuadamente mezclados con los del suelo base. Gumbley cree arena se a\u00f1ad\u00eda a los mont\u00edculos la posici\u00f3n del individuo Puke (mont\u00edculos) removi\u00e9ndose en el suelo para formar el mont\u00edculo de siembra<\/em><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><span style=\"color: #800000;\"><strong>Results<\/strong><\/span>:<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">One site had 67% added sand and gravel (range 49-86%) equivalent to 2 litres of added sand per litre of soil. The<\/span><span style=\"color: #000000;\">\u00a0 <\/span><span style=\"color: #000000;\">second site had 47%( range 31-87%) 70% added sand is roughly equivalent to adding 2 litres of sand per litre of soil. Coarse sand additions common practice but not on all M\u0101ori garden areas.<\/span><span style=\"color: #000000;\">What about charcoal? Did we have the equivalent of terra preta soils M\u0101ori garden areas? What is the evidence?<\/span><span style=\"color: #000000;\">Elsdon Best describes a<\/span><span style=\"color: #000000;\">\u00a0 <\/span><span style=\"color: #000000;\">treatment for some soils.<\/span><\/p>\n<p style=\"text-align: justify;\"><strong><em>Uno de los lugares inspeccionados conten\u00eda un 67% de arena y grava agregada (49-86%) equivalente a 2 litros de arena a\u00f1adida por litro de suelo<\/em><\/strong><em>. El segundo sitio atesoraba aproximadamente un 47% (rango 31-87%) 70% de arena a\u00f1adida, m\u00e1s o menos equivalente a la adici\u00f3n de 2 litros de arena por litro de suelo. <strong>Adiciones arena gruesa pr\u00e1ctica com\u00fan, pero no en todas las zonas ajardinadas de los maor\u00edes<\/strong>. \u00bfQu\u00e9 pasaba con el carb\u00f3n? \u00bfEra similar al de las terra preta amaz\u00f3nicas? <\/em><em>\u00bfSe han detectado<\/em> evidencias?<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Manuka brush or second growth is cut and spread over the field and left lying there until planting time is near. Then set fire to so a layer of charcoal and ash covers the earth. Residue of burned brush called \u201ckota\u201d. Cover again with m\u0101nuka to prevent wind blowing away the kota before mound forming and planting. No deliberate effort to create a slow burning environment that would result in more charcoal.<\/span><span style=\"color: #000000;\">Reporting on Waimea West these authors describe M\u0101ori gravel soil is so dark when wet to appear black in contrast to natural brown of parent soils. They conclude dark appearance results from the presence of charcoal introduced during preparation of the land. No recent analysis of these soils found but it requires further investigation.<\/span><\/p>\n<p style=\"text-align: justify;\"><em>El material de Manuka de segundo crecimiento se corta y extend\u00eda sobre el campo dej\u00e1ndose tendido all\u00ed hasta poco antes de la siembra. A continuaci\u00f3n, prend\u00edan dando lugar a una capa de carb\u00f3n y ceniza que terminaba cubriendo la superficie del suelo. El residuo de la quema era denominado \u00abkota\u00bb. De nuevo la tierra era cubierta con Manuka para evitar la acci\u00f3n erosiva del viento que exportara el material antropog\u00e9nicamente generado, antes de formar mont\u00edculos y realizar la \u00a0siembra. No se llevaban a cabo esfuerzos deliberados con vistas a crear un ambiente de combusti\u00f3n lenta que se traducir\u00eda en m\u00e1s carb\u00f3n. Al informar sobre el Ostete de Waimea estos autores describen los maor\u00edes grava del suelo es tan oscuro cuando est\u00e1 mojado aparezca negro en contraste con marr\u00f3n natural de los suelos de los padres Concluyen resultados de apariencia oscura de la presencia de carb\u00f3n introducido durante la preparaci\u00f3n de la tierra. Ning\u00fan an\u00e1lisis reciente de estos suelos se encontr\u00f3 pero requiere de mayor investigaci\u00f3n.<\/em><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Reporting on M\u0101ori<\/span><span style=\"color: #000000;\">\u00a0 <\/span><span style=\"color: #000000;\">soils<\/span><span style=\"color: #000000;\">\u00a0 <\/span><span style=\"color: #000000;\">in mid-Waikato Basin. Charcoal present was from original podocarp\/broadleaf forest rather than pioneer seral species and was deposited from original burn off. However they do comment that m\u0101nuka charcoal was present in other sites.<\/span><\/p>\n<p style=\"text-align: justify;\"><em>Al informar sobre los suelos maor\u00edes a mediados de Waikato Cuenca. <\/em><\/p>\n<p style=\"text-align: justify;\"><em>El Biocarb\u00f3n (charcoal) presente proced\u00eda era de los bosques de podocarpos de hoja ancha originales, en lugar de las especies pioneras de su sucesi\u00f3n ecol\u00f3gica y se deposita tras su quema.\u00a0 Sin embargo ellos comentan algunos autores sostienen que carb\u00f3n Manuka tambi\u00e9n se encontraba presente en otros sitios<strong>.<\/strong><\/em><\/p>\n<p style=\"text-align: justify;\"><strong>Conclusion<\/strong><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Reporting on Maori soils in mid-Waikato Basin. Charcoal present was from original podocarp\/broadleaf forest rather than pioneer seral species and was deposited from original burn off. However they do comment that m\u0101nuka charcoal was present in other sites.<\/span><span style=\"color: #000000;\">M\u0101ori have an extensive knowledge of different soil types with many linguistic terms for soil types.<\/span><span style=\"color: #000000;\">\u00a0 <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">The use of sand and gravel to modify soil in k\u016bmara gardens was common and well embedded in traditional agricultural knowledge. Further experimental work is need to investigate the effects. Reports of burning wood to create ashes for soil modification relate to specific sites or types of soil. <\/span><span style=\"color: #000000;\">\u00a0<\/span><span style=\"color: #000000;\">There is no evidence pointing to the deliberate production of charcoal as a soil additive in pre-contact M\u0101ori k\u016bmara gardening with the exception of Waimea West. The occurrence of elevated levels of charcoal in some soils result from the original forest burning where a reduced oxygen or slow burning event occurred.<\/span><\/p>\n<p style=\"text-align: justify;\"><strong><em>Conclusi\u00f3n<\/em><\/strong><\/p>\n<p style=\"text-align: justify;\"><em><span style=\"color: #000000;\">Al informar sobre los suelos maor\u00edes de la Cuenca de Waikato: El biocarb\u00f3n o biochar presente se generaba de biomasa extra\u00edda de bosques originales de podocarpos de hoja ancha, m\u00e1s que de las especies pioneras de la sucesi\u00f3n ecol\u00f3gica tras su transformaci\u00f3n por el fuego. <\/span>Sin embargo ellos comentan que el carb\u00f3n Manuka se encontraba presente en otros lugares<span style=\"color: #000000;\">. <\/span><strong><span style=\"color: #000000;\">Los Maor\u00ed atesoraban un amplio conocimiento de los diferentes tipos de suelo, usando numerosos t\u00e9rminos ling\u00fc\u00edsticos que daban cuenta de los tipos de suelo<\/span><\/strong><span style=\"color: #000000;\">. <\/span><\/em><\/p>\n<p style=\"text-align: justify;\"><strong><em><span style=\"color: #000000;\">El uso de arena y grava a la hora de modificar el suelo de aquellos ancestrales jardines era com\u00fan y bien integrado en los conocimientos agr\u00edcolas tradicionales<\/span><\/em><\/strong><em><span style=\"color: #000000;\">. Son necesarios muchos m\u00e1s estudios experimentales con vistas a investigar los efectos que producci\u00f3n en el suelo y su productividad. <\/span><\/em><\/p>\n<p style=\"text-align: justify;\"><em><span style=\"color: #000000;\">Los informes de la quema de madera para producir las cenizas que a la postre modificaban las condiciones del suelo se refieren a sitios o tipos de suelo espec\u00edficos<\/span><strong><span style=\"color: #000000;\">. No hay pruebas s\u00f3lidas que apunten a la producci\u00f3n deliberada de carb\u00f3n como un aditivo para el suelo<\/span><\/strong><span style=\"color: #000000;\"> en pre-contacto maor\u00edes kum\u0101ra jardiner\u00eda con la excepci\u00f3n del Oeste de Waimea<\/span><strong><span style=\"color: #000000;\">. La presencia de niveles elevados de carb\u00f3n en algunos suelos,podr\u00eda deberse a la quema forestal original donde se produjeron, con una reducci\u00f3n de ox\u00edgeno o un evento de combusti\u00f3n lenta<\/span><\/strong><span style=\"color: #000000;\">.<\/span><\/em><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #800000;\"><strong>Del art\u00edculo: en su Introducci\u00f3n<\/strong><\/span><span style=\"color: #000000;\">: <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">These <\/span><strong><span style=\"color: #000000;\">pre-European gardeners<\/span><\/strong><span style=\"color: #000000;\"> cultivated mainly kumara, also known as sweet potato (Ipomea batatas L.), in a system involving planting mounds (pukes) directly formed by adding sand or gravel to the topsoil; other additives included ash, silt and clay materials, burnt scrub, shell and fireplace charcoal (Gumbley et al., 2004; A. Hoffmann, unpublished information). Through these processes, Polynesians created anthropogenic soils currently known as \u2018historical Maori gardens\u2019 (McFadgen, 1980) and also referred to as \u2018plaggen soils\u2019 or Anthrosols in<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">the literature (IUSS, 2006). Archaeological remains of historical M\u00afaori gardens found in numerous locations of New Zealand have helped understand the functioning of these pre-European settlements (Gumbley et al., 2004; W. Gumbley, unpublished information; A. Hoffmann, unpublished information). <\/span><\/p>\n<p style=\"text-align: justify;\"><strong><em><span style=\"color: #000000;\">Estos jardineros pre-europeos cultivan principalmente<\/span><\/em><\/strong><em><span style=\"color: #000000;\"> Kumara, tambi\u00e9n conocida como batata (Ipomea batatas L.), <\/span><strong><span style=\"color: #000000;\">en un sistema que implica la plantaci\u00f3n sobre de mont\u00edculos <\/span><\/strong><span style=\"color: #000000;\">(Pukes) <\/span><strong><span style=\"color: #000000;\">directamente formados por la adici\u00f3n de arena o grava a la capa superior del suelo<\/span><\/strong><span style=\"color: #000000;\">. <\/span><strong><span style=\"color: #000000;\">Otras enmiendas<\/span><\/strong><span style=\"color: #000000;\"> inclu\u00edan incluyen cenizas, limo y arcillas, matorral quemado, conchas y<\/span><span style=\"color: #000000;\">\u00a0 <\/span><span style=\"color: #000000;\">carb\u00f3n de <\/span><strong><span style=\"color: #000000;\">chimenea A trav\u00e9s de estos procesos, los polinesios crearon sus propios suelos antropog\u00e9nicos<\/span><\/strong><span style=\"color: #000000;\"> actualmente conocidos como <\/span><strong><span style=\"color: #000000;\">Jardines Hist\u00f3ricos Maor\u00edes<\/span><\/strong><span style=\"color: #000000;\">, clasificados coniforme a la WRB como <\/span><strong><span style=\"color: #000000;\">\u00absuelos plaggen o Antrosoles<\/span><\/strong><span style=\"color: #000000;\"> (IUSS, 2006). Los restos arqueol\u00f3gicos de los jardines hist\u00f3ricos maor\u00edes se esparcen por numerosos lugares de Nueva<\/span><\/em><em><span style=\"color: #000000;\">Zelanda, ayudando a entender el funcionamiento y edad de aquellos <\/span><span style=\"color: #000000;\">\u00a0<\/span><span style=\"color: #000000;\">asentamientos pre-europeos.<\/span><\/em><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">This is of special interest in New Zealand as these gardens represent environments similar to those to which biochar may be added in the future. The use of biochar, biomass thermochemically converted in an oxygen-limited environment, as a soil conditioner has gained interest as a means to sequester carbon (C) sustainably and simultaneously improve soil functions without having a negative impact on the environment and human health in the short or long term (Verheijen et al., 2009; IBI, 2012). Understanding the stability of biochar in specific soils is paramount for assessing its C sequestration capacity and potential. Once quantified, biochar may obtain monetary value, apart from its agricultural value, through the C credit market. It is assumed that charred material (such as charcoal) is more recalcitrant than other types of organic compounds common in soil and this is attributed to the intrinsic chemical and biochemical stability of condensed aromatic groups<\/span><\/p>\n<p style=\"text-align: justify;\"><em><span style=\"color: #000000;\">Tales pr\u00e1cticas son de especial inter\u00e9s con vistas a rescatar el patrimonio que representen las <\/span><strong><span style=\"color: #000000;\">culturas abor\u00edgenes de Nueva Zelanda<\/span><\/strong><span style=\"color: #000000;\">, que algunos consideran equivalentes a los que las <\/span><strong><span style=\"color: #000000;\">culturas amaz\u00f3nicas<\/span><\/strong><span style=\"color: #000000;\"> de Brasil y su enigm\u00e1tico <\/span><strong><span style=\"color: #000000;\">Biochar<\/span><\/strong><span style=\"color: #000000;\"> que tanto intriga a los expertos contempor\u00e1neos. El uso de biochar, la conversi\u00f3n termoqu\u00edmica de la biomasa en un entorno de ox\u00edgeno limitado, como acondicionador del suelo ha despertado el inter\u00e9s como medio para secuestrar el carbono atmosf\u00e9rico (C) de manera sostenible, al mismo tiempo que pudieran mejorar las funciones del suelo sin tener un impacto negativo sobre el medio ambiente y la salud humana en el corto o largo plazo. La comprensi\u00f3n de la estabilidad de biochar en suelos espec\u00edficos es de suma importancia para evaluar la capacidad del secuestro de C. Una vez cuantificado, el biochar puede obtener valor monetario, adem\u00e1s de su valor agr\u00edcola, a trav\u00e9s del mercado de los de cr\u00e9dito carbono. Se supone que el material carbonizado (tal como carb\u00f3n vegetal) es m\u00e1s recalcitrante que otros tipos de compuestos org\u00e1nicos comunes en el suelo y esto se atribuye a sus intr\u00ednsecas propiedades qu\u00edmicas al parecer condicionada por la estabilidad de grupos arom\u00e1ticos condensados que su combusti\u00f3n genera.<\/span><\/em><\/p>\n<h3>Im\u00e1genes Relacionadas:<\/h3>","protected":false},"excerpt":{"rendered":"<p>\u00a0 Paisaje Agrario Maor\u00ed. Fuente:Ministry for Culture and Heritage Ya os comentamos en un post anterior como la llegada de los Maor\u00edes a Nueva Zelanda transform\u00f3 sus paisajes pr\u00edstinos, si bien, poco a\u00f1adimos acerca de su agricultura (\u201cCulturas Abor\u00edgenes, Paisajes, Incendios y Suelos. El Pueblo Maor\u00ed en Nueva Zelanda\u00ab). Recientemente El European Journal of Soil Science ha publicado un monogr\u00e1fico sobre el biochar o biocarb\u00f3n, que como muchos de vosotros sab\u00e9is, comenz\u00f3 a investigarse fan\u00e1ticamente a partir de su descubrimiento en las Terras Pretas do Indio amaz\u00f3nicas, de las que tanto os hemos hablado. Los contenidos de este n\u00famero especial\u2026<\/p>\n","protected":false},"author":26,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0},"categories":[608,603,599,613,597,604,607],"tags":[27914,47526,47175,46775,47013,27955,27956,46969],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":4}},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Paisaje Agrario Maor\u00ed. Fuente:Ministry for Culture and Heritage Ya os comentamos en un post anterior como la llegada de los Maor\u00edes a Nueva Zelanda transform\u00f3 sus paisajes pr\u00edstinos, si bien, poco a\u00f1adimos acerca de su agricultura (\u201cCulturas Abor\u00edgenes, Paisajes, Incendios y Suelos. El Pueblo Maor\u00ed en Nueva Zelanda&quot;). Recientemente El European Journal of Soil\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Juan Jos\u00e9 Ib\u00e1\u00f1ez\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2015\/01\/27\/145642\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Un Universo invisible bajo nuestros pies - Los suelos y la vida\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Los Jardines Preuropeos Maor\u00edes de Nueva Zelanda, sus Antrosoles, manejo y biocarbones (Biochar) - Un Universo invisible bajo nuestros pies\" \/>\n\t\t<meta property=\"og:description\" content=\"Paisaje Agrario Maor\u00ed. Fuente:Ministry for Culture and Heritage Ya os comentamos en un post anterior como la llegada de los Maor\u00edes a Nueva Zelanda transform\u00f3 sus paisajes pr\u00edstinos, si bien, poco a\u00f1adimos acerca de su agricultura (\u201cCulturas Abor\u00edgenes, Paisajes, Incendios y Suelos. El Pueblo Maor\u00ed en Nueva Zelanda&quot;). Recientemente El European Journal of Soil\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2015\/01\/27\/145642\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2015-01-27T14:30:13+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2015-01-27T14:30:13+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/juan.j.marti.14\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Los Jardines Preuropeos Maor\u00edes de Nueva Zelanda, sus Antrosoles, manejo y biocarbones (Biochar) - Un Universo invisible bajo nuestros pies\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Paisaje Agrario Maor\u00ed. Fuente:Ministry for Culture and Heritage Ya os comentamos en un post anterior como la llegada de los Maor\u00edes a Nueva Zelanda transform\u00f3 sus paisajes pr\u00edstinos, si bien, poco a\u00f1adimos acerca de su agricultura (\u201cCulturas Abor\u00edgenes, Paisajes, Incendios y Suelos. El Pueblo Maor\u00ed en Nueva Zelanda&quot;). Recientemente El European Journal of Soil\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2015\\\/01\\\/27\\\/145642#blogposting\",\"name\":\"Los Jardines Preuropeos Maor\\u00edes de Nueva Zelanda, sus Antrosoles, manejo y biocarbones (Biochar) - Un Universo invisible bajo nuestros pies\",\"headline\":\"Los Jardines Preuropeos Maor\\u00edes de Nueva Zelanda, sus Antrosoles, manejo y biocarbones (Biochar)\",\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"http:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/wp-content\\\/blogs.dir\\\/42\\\/files\\\/255\\\/paisaje-agrario-maori-fuente-ministry-for-culture-and-heritage.jpg\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2015\\\/01\\\/27\\\/145642\\\/#articleImage\"},\"datePublished\":\"2015-01-27T15:30:13+01:00\",\"dateModified\":\"2015-01-27T15:30:13+01:00\",\"inLanguage\":\"es-ES\",\"commentCount\":2,\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2015\\\/01\\\/27\\\/145642#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2015\\\/01\\\/27\\\/145642#webpage\"},\"articleSection\":\"Biomasa y Necromasa en los Suelos: Ra\\u00edces y Materia Org\\u00e1nica, Carpeta sobre Paisajes de Suelos y los Suelos en el Paisaje, Etnoedafolog\\u00eda y Conocimiento Campesino, Fertilidad de Suelos y Nutrici\\u00f3n Vegetal, Filosof\\u00eda, Historia y Sociolog\\u00eda de la Edafolog\\u00eda, Geograf\\u00eda de Suelos y Megaedafolog\\u00eda, Historia de la Tierra y de los Suelos., Antrosoles, biocarbones, Biochar, etnoedafolog\\u00eda, etnopedolog\\u00eda, Jardines Preuropeos Maor\\u00edes, manejo del suelo, Nueva Zelanda\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2015\\\/01\\\/27\\\/145642#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/filosofia-historia-y-sociologia-de-la-edafologia#listItem\",\"name\":\"Filosof\\u00eda, Historia y Sociolog\\u00eda de la Edafolog\\u00eda\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/filosofia-historia-y-sociologia-de-la-edafologia#listItem\",\"position\":2,\"name\":\"Filosof\\u00eda, Historia y Sociolog\\u00eda de la Edafolog\\u00eda\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/filosofia-historia-y-sociologia-de-la-edafologia\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2015\\\/01\\\/27\\\/145642#listItem\",\"name\":\"Los Jardines Preuropeos Maor\\u00edes de Nueva Zelanda, sus Antrosoles, manejo y biocarbones (Biochar)\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2015\\\/01\\\/27\\\/145642#listItem\",\"position\":3,\"name\":\"Los Jardines Preuropeos Maor\\u00edes de Nueva Zelanda, sus Antrosoles, manejo y biocarbones (Biochar)\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/filosofia-historia-y-sociologia-de-la-edafologia#listItem\",\"name\":\"Filosof\\u00eda, Historia y Sociolog\\u00eda de la Edafolog\\u00eda\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#organization\",\"name\":\"Un Universo invisible bajo nuestros pies\",\"description\":\"Los suelos y la vida\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/files\\\/2022\\\/02\\\/logo.png\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2015\\\/01\\\/27\\\/145642\\\/#organizationLogo\",\"width\":217,\"height\":72},\"image\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2015\\\/01\\\/27\\\/145642\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/juan.j.marti.14\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo\",\"name\":\"Juan Jos\\u00e9 Ib\\u00e1\\u00f1ez\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2015\\\/01\\\/27\\\/145642#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/387f3a100385573d8f42ce2a3211fd1c?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Juan Jos\\u00e9 Ib\\u00e1\\u00f1ez\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2015\\\/01\\\/27\\\/145642#webpage\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2015\\\/01\\\/27\\\/145642\",\"name\":\"Los Jardines Preuropeos Maor\\u00edes de Nueva Zelanda, sus Antrosoles, manejo y biocarbones (Biochar) - Un Universo invisible bajo nuestros pies\",\"description\":\"Paisaje Agrario Maor\\u00ed. Fuente:Ministry for Culture and Heritage Ya os comentamos en un post anterior como la llegada de los Maor\\u00edes a Nueva Zelanda transform\\u00f3 sus paisajes pr\\u00edstinos, si bien, poco a\\u00f1adimos acerca de su agricultura (\\u201cCulturas Abor\\u00edgenes, Paisajes, Incendios y Suelos. El Pueblo Maor\\u00ed en Nueva Zelanda\\\"). Recientemente El European Journal of Soil\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2015\\\/01\\\/27\\\/145642#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\"},\"datePublished\":\"2015-01-27T15:30:13+01:00\",\"dateModified\":\"2015-01-27T15:30:13+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#website\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/\",\"name\":\"Un Universo invisible bajo nuestros pies\",\"description\":\"Los suelos y la vida\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Los Jardines Preuropeos Maor\u00edes de Nueva Zelanda, sus Antrosoles, manejo y biocarbones (Biochar) - Un Universo invisible bajo nuestros pies","description":"Paisaje Agrario Maor\u00ed. Fuente:Ministry for Culture and Heritage Ya os comentamos en un post anterior como la llegada de los Maor\u00edes a Nueva Zelanda transform\u00f3 sus paisajes pr\u00edstinos, si bien, poco a\u00f1adimos acerca de su agricultura (\u201cCulturas Abor\u00edgenes, Paisajes, Incendios y Suelos. El Pueblo Maor\u00ed en Nueva Zelanda\"). Recientemente El European Journal of Soil","canonical_url":"https:\/\/www.madrimasd.org\/blogs\/universo\/2015\/01\/27\/145642","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2015\/01\/27\/145642#blogposting","name":"Los Jardines Preuropeos Maor\u00edes de Nueva Zelanda, sus Antrosoles, manejo y biocarbones (Biochar) - Un Universo invisible bajo nuestros pies","headline":"Los Jardines Preuropeos Maor\u00edes de Nueva Zelanda, sus Antrosoles, manejo y biocarbones (Biochar)","author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author"},"publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#organization"},"image":{"@type":"ImageObject","url":"http:\/\/www.madrimasd.org\/blogs\/universo\/wp-content\/blogs.dir\/42\/files\/255\/paisaje-agrario-maori-fuente-ministry-for-culture-and-heritage.jpg","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2015\/01\/27\/145642\/#articleImage"},"datePublished":"2015-01-27T15:30:13+01:00","dateModified":"2015-01-27T15:30:13+01:00","inLanguage":"es-ES","commentCount":2,"mainEntityOfPage":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2015\/01\/27\/145642#webpage"},"isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2015\/01\/27\/145642#webpage"},"articleSection":"Biomasa y Necromasa en los Suelos: Ra\u00edces y Materia Org\u00e1nica, Carpeta sobre Paisajes de Suelos y los Suelos en el Paisaje, Etnoedafolog\u00eda y Conocimiento Campesino, Fertilidad de Suelos y Nutrici\u00f3n Vegetal, Filosof\u00eda, Historia y Sociolog\u00eda de la Edafolog\u00eda, Geograf\u00eda de Suelos y Megaedafolog\u00eda, Historia de la Tierra y de los Suelos., Antrosoles, biocarbones, Biochar, etnoedafolog\u00eda, etnopedolog\u00eda, Jardines Preuropeos Maor\u00edes, manejo del suelo, Nueva Zelanda"},{"@type":"BreadcrumbList","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2015\/01\/27\/145642#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo#listItem","position":1,"name":"Home","item":"https:\/\/www.madrimasd.org\/blogs\/universo","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/filosofia-historia-y-sociologia-de-la-edafologia#listItem","name":"Filosof\u00eda, Historia y Sociolog\u00eda de la Edafolog\u00eda"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/filosofia-historia-y-sociologia-de-la-edafologia#listItem","position":2,"name":"Filosof\u00eda, Historia y Sociolog\u00eda de la Edafolog\u00eda","item":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/filosofia-historia-y-sociologia-de-la-edafologia","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2015\/01\/27\/145642#listItem","name":"Los Jardines Preuropeos Maor\u00edes de Nueva Zelanda, sus Antrosoles, manejo y biocarbones (Biochar)"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2015\/01\/27\/145642#listItem","position":3,"name":"Los Jardines Preuropeos Maor\u00edes de Nueva Zelanda, sus Antrosoles, manejo y biocarbones (Biochar)","previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/filosofia-historia-y-sociologia-de-la-edafologia#listItem","name":"Filosof\u00eda, Historia y Sociolog\u00eda de la Edafolog\u00eda"}}]},{"@type":"Organization","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#organization","name":"Un Universo invisible bajo nuestros pies","description":"Los suelos y la vida","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/","logo":{"@type":"ImageObject","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2015\/01\/27\/145642\/#organizationLogo","width":217,"height":72},"image":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2015\/01\/27\/145642\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/juan.j.marti.14"]},{"@type":"Person","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo","name":"Juan Jos\u00e9 Ib\u00e1\u00f1ez","image":{"@type":"ImageObject","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2015\/01\/27\/145642#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/387f3a100385573d8f42ce2a3211fd1c?s=96&d=mm&r=g","width":96,"height":96,"caption":"Juan Jos\u00e9 Ib\u00e1\u00f1ez"}},{"@type":"WebPage","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2015\/01\/27\/145642#webpage","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/2015\/01\/27\/145642","name":"Los Jardines Preuropeos Maor\u00edes de Nueva Zelanda, sus Antrosoles, manejo y biocarbones (Biochar) - Un Universo invisible bajo nuestros pies","description":"Paisaje Agrario Maor\u00ed. Fuente:Ministry for Culture and Heritage Ya os comentamos en un post anterior como la llegada de los Maor\u00edes a Nueva Zelanda transform\u00f3 sus paisajes pr\u00edstinos, si bien, poco a\u00f1adimos acerca de su agricultura (\u201cCulturas Abor\u00edgenes, Paisajes, Incendios y Suelos. El Pueblo Maor\u00ed en Nueva Zelanda\"). Recientemente El European Journal of Soil","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#website"},"breadcrumb":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2015\/01\/27\/145642#breadcrumblist"},"author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author"},"creator":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author"},"datePublished":"2015-01-27T15:30:13+01:00","dateModified":"2015-01-27T15:30:13+01:00"},{"@type":"WebSite","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#website","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/","name":"Un Universo invisible bajo nuestros pies","description":"Los suelos y la vida","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Un Universo invisible bajo nuestros pies - Los suelos y la vida","og:type":"article","og:title":"Los Jardines Preuropeos Maor\u00edes de Nueva Zelanda, sus Antrosoles, manejo y biocarbones (Biochar) - Un Universo invisible bajo nuestros pies","og:description":"Paisaje Agrario Maor\u00ed. Fuente:Ministry for Culture and Heritage Ya os comentamos en un post anterior como la llegada de los Maor\u00edes a Nueva Zelanda transform\u00f3 sus paisajes pr\u00edstinos, si bien, poco a\u00f1adimos acerca de su agricultura (\u201cCulturas Abor\u00edgenes, Paisajes, Incendios y Suelos. El Pueblo Maor\u00ed en Nueva Zelanda&quot;). Recientemente El European Journal of Soil","og:url":"https:\/\/www.madrimasd.org\/blogs\/universo\/2015\/01\/27\/145642","og:image":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png","og:image:secure_url":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png","article:published_time":"2015-01-27T14:30:13+00:00","article:modified_time":"2015-01-27T14:30:13+00:00","article:publisher":"https:\/\/www.facebook.com\/juan.j.marti.14","twitter:card":"summary","twitter:title":"Los Jardines Preuropeos Maor\u00edes de Nueva Zelanda, sus Antrosoles, manejo y biocarbones (Biochar) - Un Universo invisible bajo nuestros pies","twitter:description":"Paisaje Agrario Maor\u00ed. Fuente:Ministry for Culture and Heritage Ya os comentamos en un post anterior como la llegada de los Maor\u00edes a Nueva Zelanda transform\u00f3 sus paisajes pr\u00edstinos, si bien, poco a\u00f1adimos acerca de su agricultura (\u201cCulturas Abor\u00edgenes, Paisajes, Incendios y Suelos. El Pueblo Maor\u00ed en Nueva Zelanda&quot;). Recientemente El European Journal of Soil","twitter:image":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png"},"aioseo_meta_data":{"post_id":"145642","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":null,"isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","tabs":null,"priority":null,"frequency":null,"local_seo":null,"created":"2022-06-03 16:39:08","updated":"2026-05-26 18:13:59","limit_modified_date":false,"ai":null,"breadcrumb_settings":null,"seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/filosofia-historia-y-sociologia-de-la-edafologia\" title=\"Filosof\u00eda, Historia y Sociolog\u00eda de la Edafolog\u00eda\">Filosof\u00eda, Historia y Sociolog\u00eda de la Edafolog\u00eda<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tLos Jardines Preuropeos Maor\u00edes de Nueva Zelanda, sus Antrosoles, manejo y biocarbones (Biochar)\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.madrimasd.org\/blogs\/universo"},{"label":"Filosof\u00eda, Historia y Sociolog\u00eda de la Edafolog\u00eda","link":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/filosofia-historia-y-sociologia-de-la-edafologia"},{"label":"Los Jardines Preuropeos Maor\u00edes de Nueva Zelanda, sus Antrosoles, manejo y biocarbones (Biochar)","link":"https:\/\/www.madrimasd.org\/blogs\/universo\/2015\/01\/27\/145642"}],"_links":{"self":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts\/145642"}],"collection":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/comments?post=145642"}],"version-history":[{"count":29,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts\/145642\/revisions"}],"predecessor-version":[{"id":146637,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts\/145642\/revisions\/146637"}],"wp:attachment":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/media?parent=145642"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/categories?post=145642"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/tags?post=145642"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}