{"id":146157,"date":"2014-10-01T20:17:47","date_gmt":"2014-10-01T19:17:47","guid":{"rendered":"http:\/\/www.madrimasd.org\/blogs\/universo\/?p=146157"},"modified":"2014-10-02T09:37:47","modified_gmt":"2014-10-02T08:37:47","slug":"ebola-degradacion-ambiental-y-cambio-global","status":"publish","type":"post","link":"https:\/\/www.madrimasd.org\/blogs\/universo\/2014\/10\/01\/146157","title":{"rendered":"\u00c9bola, Degradaci\u00f3n Ambiental y Cambio Global"},"content":{"rendered":"<p align=\"center\"><img decoding=\"async\" class=\"ngg-singlepic ngg-center\" style=\"width: 451px; height: 287px;\" src=\"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-content\/blogs.dir\/42\/files\/1357\/ebola.jpg\" alt=\"ebola\" width=\"659\" height=\"369\" \/><\/p>\n<p align=\"center\"><a href=\"http:\/\/www.despiertavenezuela.org\/2014\/08\/08\/oms-declara-emergencia-de-salud-publica-mundial-por-brote-de-ebola-en-africa\/\"><span style=\"color: #0000ff;\">Los estragos del virus del \u00c9bola. Fuente: Despierta Venezuela<\/span><\/a><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Personalmente el <\/span><a href=\"http:\/\/www.madrimasd.org\/blogs\/virusemergentes\/\"><span style=\"color: #0000ff;\">Blog Virus Emergentes y Cambio Global<\/span><\/a><span style=\"color: #000000;\">, cuyo administrador resulta ser <\/span><a title=\"Entradas de Miguel \u00c1ngel Jim\u00e9nez Clavero\" href=\"http:\/\/www.madrimasd.org\/blogs\/virusemergentes\/author\/virusemergentes\/\">Miguel \u00c1ngel Jim\u00e9nez Clavero<\/a><span style=\"color: #000000;\">, me parece uno de los mejores de nuestro sistema de bit\u00e1coras, aunque por desgracia su actualizaci\u00f3n no resulta ser muy frecuente. Eso s\u00ed, pr\u00e1cticamente todas sus entradas se me antojan excelentes. Por desgracia ahora debe tratar la dram\u00e1tica epidemia del <\/span><a href=\"http:\/\/es.wikipedia.org\/wiki\/\u00c9bola_(virus)\"><span style=\"color: #0000ff;\">Virus del \u00c9bola<\/span><\/a><span style=\"color: #000000;\">, y su dram\u00e1tica extensi\u00f3n en esa <\/span><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2008\/06\/13\/94576\"><span style=\"color: #0000ff;\">\u00c1frica Olvidada<\/span><\/a><span style=\"color: #000000;\"> y maltratada. Tambi\u00e9n a t\u00edtulo personal me siento indignado al observar que los medios de comunicaci\u00f3n y nuestros pol\u00edticos siguen centr\u00e1ndose estos d\u00edas (oto\u00f1o de 2014) en temas geopol\u00edticos como la tensi\u00f3n surgida entre Rusia y los pa\u00edses occidentales acerca de Ucrania o la locura desatada por el movimiento terrorista denominado <\/span><a href=\"http:\/\/es.wikipedia.org\/wiki\/Estado_Isl\u00e1mico_(organizaci\u00f3n_terrorista)\"><span style=\"color: #0000ff;\">Estado Isl\u00e1mico<\/span><\/a><span style=\"color: #000000;\"> en Oriente Medio. Ciertamente son asuntos de gravedad, especialmente el segundo, empero que no alcanzan la dimensi\u00f3n y significado del drama desatado por el famoso virus, ya conocido desde hace tiempo, pero que al afectar a zonas densamente pobladas puede inducir (por sus tasas de mortalidad) estragos descomunales. Ante este problema de salud p\u00fablica <\/span><span style=\"color: #000000;\">\u00a0<\/span><span style=\"color: #000000;\">las alarmas generadas no hace tiempo por <\/span><a href=\"http:\/\/es.wikipedia.org\/wiki\/Influenzavirus_A_subtipo_H5N1\"><span style=\"color: #0000ff;\">el virus de la gripe aviar<\/span><\/a><span style=\"color: #000000;\">, de la que ya hablamos en varios post, <\/span><span style=\"color: #000000;\">\u00a0<\/span><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/04\/08\/142688\"><span style=\"color: #0000ff;\">como en este<\/span><\/a><span style=\"color: #000000;\"> parecen menores. Miguel \u00c1ngel abord\u00f3 por primera vez el tema en el siguiente post: <\/span><span style=\"color: #000000;\">\u00a0<\/span><a title=\"Enlace permanente a Alerta internacional por virus Ebola, 2014\" href=\"http:\/\/www.madrimasd.org\/blogs\/virusemergentes\/2014\/08\/alerta-internacional-por-virus-ebola-2014\/\">Alerta internacional por virus Ebola, 2014<\/a><span style=\"color: #000000;\">y hoy mismo (el d\u00eda que redacto este post) ha editado el segundo cuya lectura os recomiendo v\u00edvidamente a todos vosotros: \u201c<\/span><a href=\"http:\/\/www.madrimasd.org\/blogs\/virusemergentes\/2014\/09\/ebola-africa-occidental-6-meses-despues-es-un-virus-emergente\/\"><span style=\"color: #0000ff; font-family: Calibri; font-size: medium;\">\u00c9bola, \u00c1frica Occidental, 6 meses despu\u00e9s: \u00bfes un virus emergente?<\/span><\/a><span style=\"color: #000000;\">\u201d. \u00a0<\/span><span style=\"color: #000000;\">El autor nos informa de que efectivamente se trata de un virus emergente conforme a la definici\u00f3n vigente<\/span><strong><span style=\"color: #000000;\">. <span style=\"color: #3366ff;\">Del mismo modo nos recuerda que su r\u00e1pida expansi\u00f3n se debe en gran parte a las la \u201cd\u00e9bil infraestructura sanitaria de los pa\u00edses m\u00e1s afectados\u201d <\/span><\/span><\/strong><span style=\"color: #000000;\">dejado de la mano de Dios y de los hombres<\/span><strong><span style=\"color: #000000;\">. <span style=\"color: #3366ff;\">No obstante hace hincapi\u00e9 en un aspecto clave que suele soslayarse. Muchos problemas de salud p\u00fablica acaecidos son el resultado de graves desastres medioambientales que siguen surgiendo incesantemente ya que el incontrolado desarrollo econ\u00f3mico <\/span><\/span><\/strong><span style=\"color: #000000;\">del capitalismo neoliberal\/global <\/span><strong><span style=\"color: #000000;\"><span style=\"color: #3366ff;\">parece re\u00f1ido con la protecci\u00f3n del medio ambiente y la propia salud p\u00fablica<\/span><\/span><\/strong><span style=\"color: #000000;\">. Ya que se trata de un texto muy reciente, no reproducir\u00e9 el mismo, rog\u00e1ndoos que le\u00e1is ambas entregas. Si me detendr\u00e9 a extraer del \u00faltimo post algunas de las conclusiones personales de M.A. o avaladas por diversas instituciones que no tienen desperdicio. Me centrar\u00e9 pues en los temas que conciernen a una bit\u00e1cora como la nuestra, que no a otras relacionadas directamente con la sanidad y el salubr\u00edsimo. Tan solo mentar que algo parecido alegaron hace unos a\u00f1os expertos latinoamericanos al abordar <\/span><span style=\"color: #000000;\">\u00a0<\/span><span style=\"color: #000000;\">el asunto de la <\/span><a href=\"http:\/\/www.who.int\/features\/qa\/79\/es\/\"><span style=\"color: #0000ff;\">Tuberculosis Multiresistente<\/span><\/a><span style=\"color: #000000;\">, aunque ya no recuerdo la fuente del texto, por lo que os ofrezco mis m\u00e1s sinceras escusas. <\/span><span style=\"color: #000000;\">\u00a0<\/span><span style=\"color: #000000;\">Me ce\u00f1ir\u00e9 en primer lugar a recoger las frases que me parecen m\u00e1s reveladoras para a\u00f1adir<\/span><span style=\"color: #000000;\">\u00a0 <\/span><span style=\"color: #000000;\">un peque\u00f1o comentario al final del post. <\/span><span style=\"color: #3366ff;\"><strong>Estamos pues hablando de un grave problema de degradaci\u00f3n global que a la postre genera una pl\u00e9tora de efectos colaterales, como en esta caso la susodicha <\/strong><\/span><span style=\"color: #000000;\"><span style=\"color: #3366ff;\"><strong>epidemia<\/strong> <\/span>del <\/span><a href=\"http:\/\/es.wikipedia.org\/wiki\/\u00c9bola_(virus)\"><span style=\"color: #0000ff;\">Virus del \u00c9bola<\/span><\/a><span style=\"color: #000000;\">. <\/span><span style=\"color: #3366ff;\"><strong>Comenta o recoge Miguel \u00c1ngel de otras fuentes\u2026.<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><!--more--><\/p>\n<p style=\"text-align: justify;\"><em><span style=\"color: #000000;\">Entre los factores que han conducido a la presente situaci\u00f3n, in\u00e9dita por lo que respecta al virus \u00e9bola, destacan (\u2026) actividades humanas como la <strong>deforestaci\u00f3n y la construcci\u00f3n de carreteras y v\u00edas de comunicaci\u00f3n hacia zonas remotas<\/strong><\/span><span style=\"color: #000000;\"> que <\/span><strong><span style=\"color: #000000;\">facilitan los contactos con la fauna selv\u00e1tica<\/span><\/strong><span style=\"color: #000000;\"> que constituye el reservorio del virus.<\/span><\/em><\/p>\n<p style=\"text-align: justify;\"><em><span style=\"color: #000000;\">Cabe pues preguntarse cuales son los factores que han provocado esta emergencia por virus \u00e9bola. En un editorial recientemente publicado en <\/span><\/em><em><a title=\"Ebola in west Africa\" href=\"http:\/\/www.thelancet.com\/journals\/laninf\/article\/PIIS1473-3099(14)70785-6\/fulltext\" target=\"_blank\">The Lancet Infectious Diseases<\/a><\/em><span style=\"color: #000000;\"><em>\u00a0el 15 de agosto pasado, se se\u00f1alan dos importantes factores a tener en cuenta:<\/em><em>la fragilidad de los sistemas sanitarios de los pa\u00edses afectados\u201c, lo que (\u2026.)<\/em><\/span><span style=\"color: #000000;\">. <\/span><em><span style=\"color: #000000;\">El segundo motivo que apunta el editorial es la \u201c<strong>mejora de las carreteras<\/strong><\/span><span style=\"color: #000000;\">\u201c, que habr\u00eda permitido a la enfermedad expandirse m\u00e1s r\u00e1pido. <\/span><strong><span style=\"color: #000000;\">Este segundo factor, apuntado tan lac\u00f3nicamente por The Lancet<\/span><span style=\"color: #000000;\">, merece un examen m\u00e1s detenido<\/span><\/strong><span style=\"color: #000000;\">. <\/span><\/em><\/p>\n<p style=\"text-align: justify;\"><em><span style=\"color: #000000;\">En un <\/span><\/em><em><a title=\"Ebola epidemic being driven by deforestation and climate change\" href=\"http:\/\/www.climateactionprogramme.org\/news\/ebola_epidemic_being_driven_by_deforetation_and_climate_change\" target=\"_blank\">reciente art\u00edculo en la web de \u201cClimate Action\u201c<\/a><\/em><em><span style=\"color: #000000;\">, una organizaci\u00f3n auspiciada por el <strong>Programa de Naciones Unidas para el Medio Ambiente (UNEP)<\/strong><strong>,<\/strong><\/span><span style=\"color: #000000;\"> van un poco m\u00e1s all\u00e1, se\u00f1alando al \u201c<\/span><span style=\"color: #000000;\"><strong>cambio clim\u00e1tico y la deforestaci\u00f3n<\/strong><strong>\u201d como factores subyacentes que en parte han determinado el curso m\u00e1s grave de este brote \u00a0de enfermedad por virus \u00e9bola<\/strong><\/span><span style=\"color: #000000;\">. En el mencionado art\u00edculo se recogen declaraciones de expertos como <\/span><strong><span style=\"color: #000000;\">Jonathan Epstein<\/span><\/strong><span style=\"color: #000000;\">, de la prestigiosa organizaci\u00f3n <\/span><strong><span style=\"color: #000000;\">EcoHealth Alliance<\/span><\/strong><span style=\"color: #000000;\">, quien dice que:<\/span><\/em><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><strong><em>La expansi\u00f3n del impacto humano realmente puede desencadenar brotes: la deforestaci\u00f3n, la construcci\u00f3n de carreteras, la localizaci\u00f3n de explotaciones agr\u00edcolas y ganaderas en \u00e1reas que fueron antes densas masas forestales, todo ello incrementa las oportunidades para que los animales salvajes entren en contacto con el ganado y con los humanos<\/em><\/strong><strong>.<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><em><span style=\"color: #000000;\">Como en brotes precedentes, la chispa que inici\u00f3 la <strong>transmisi\u00f3n<\/strong><\/span><span style=\"color: #000000;\"> a humanos pudo ser <\/span><strong><span style=\"color: #000000;\">zoon\u00f3tica<\/span><\/strong><span style=\"color: #000000;\"> (desde un hospedador animal), y m\u00e1s concretamente <\/span><strong><span style=\"color: #000000;\">a trav\u00e9s del consumo de \u201ccarne silvestre\u201d <\/span><\/strong><span style=\"color: #000000;\">(\u2026 procedente de animales salvajes), <\/span><strong><span style=\"color: #000000;\">alimento bastante com\u00fan en la selva tropical y subtropical<\/span><\/strong><span style=\"color: #000000;\">. Entre los animales que pueden ser infectados por el virus \u00e9bola se cuentan (\u2026) <\/span><span style=\"color: #000000;\">\u00a0<\/span><span style=\"color: #000000;\">que son considerados su reservorio natural. Estos animales son consumidos regularmente por las poblaciones cercanas a la selva que constituye su h\u00e1bitat natura (\u2026). Desde esta \u00e1rea remota el virus se ha expandido por los tres pa\u00edses con inusitada celeridad. <\/span><strong><span style=\"color: #000000;\">La expansi\u00f3n de la actividad humana hacia zonas remotas de la selva ha sido m\u00e1s intensa en tiempos recientes<\/span><\/strong><span style=\"color: #000000;\">. <\/span><strong><span style=\"color: #000000;\">El acceso a estas zonas por carretera conlleva un efecto no deseado como es facilitar la expansi\u00f3n de organismos pat\u00f3genos<\/span><\/strong><span style=\"color: #000000;\"> como el \u00e9bola, cuyo reservorio selv\u00e1tico no convive con el hombre de forma natural, sino que se encuentra en h\u00e1bitats restringidos y poco accesibles al ser humano.<\/span><\/em><\/p>\n<p style=\"text-align: justify;\"><strong><em><span style=\"text-decoration: underline;\"><span style=\"color: #000000;\">La deforestaci\u00f3n<\/span><\/span><\/em><\/strong><em><span style=\"color: #000000;\"> es algo corriente en el \u00c1frica occidental. El art\u00edculo de \u201cClimate Action\u201d se\u00f1ala que desde la d\u00e9cada de 1920 la deforestaci\u00f3n ha dejado intacta tan s\u00f3lo el 4% de la cubierta forestal original de Sierra Leona, seg\u00fan el Programa de las Naciones Unidas (UNEP).\u00a0En Liberia, el <strong>desarrollo agr\u00edcola<\/strong><\/span><span style=\"color: #000000;\"> ha absorbido alrededor del 20 por ciento de los bosques densos del pa\u00eds desde 1979, seg\u00fan un informe del Gobierno.\u00a0<\/span><strong><span style=\"color: #000000;\">En Guinea alrededor de 20 por ciento de las zonas boscosas se han perdido desde 1990,<\/span><\/strong><span style=\"color: #000000;\"> seg\u00fan datos de las Naciones Unidas. La <\/span><strong><span style=\"color: #000000;\">p\u00e9rdida de h\u00e1bitat<\/span><\/strong><strong><span style=\"color: #000000;\">se ha traducido en un aumento significativo de las concentraciones de las poblaciones de animales salvajes en el bosque restante, poniendo a los reservorios de Ebola<\/span><span style=\"color: #000000;\">, antes lejanos, en mayor proximidad con los seres humanos<\/span><\/strong><span style=\"color: #000000;\">. <\/span><strong><span style=\"color: #000000;\">Las grandes inversiones para explotar la riqueza natural en \u00c1frica Occidental, incluyendo sus ricos yacimientos minerales,<\/span><\/strong><span style=\"color: #000000;\"> han generado una <\/span><strong><span style=\"color: #000000;\">infraestructura de transporte<\/span><\/strong><span style=\"color: #000000;\"> hacia aldeas que antes eran remotas, lo que <\/span><strong><span style=\"color: #000000;\">facilita<\/span><\/strong><span style=\"color: #000000;\"> tanto el<\/span><strong><span style=\"color: #000000;\"> contacto<\/span><\/strong><span style=\"color: #000000;\"> con el virus como su <\/span><strong><span style=\"color: #000000;\">diseminaci\u00f3n<\/span><\/strong><span style=\"color: #000000;\">.<\/span><\/em><\/p>\n<p style=\"text-align: justify;\"><em><span style=\"color: #000000;\">Este art\u00edculo tambi\u00e9n menciona el <strong>cambio clim\u00e1tico<\/strong><\/span><span style=\"color: #000000;\"> como otro factor que puede determinar la frecuencia con que ocurren las epidemias por virus \u00c9bola (han relacionado las epidemias de \u00c9bola) con <\/span><strong><span style=\"color: #000000;\">periodos de fuertes lluvias tras per\u00edodos de extrema sequ\u00eda.\u00a0<\/span><\/strong><span style=\"color: #000000;\">No obstante, aunque fen\u00f3menos de cambio clim\u00e1tico puedan tener indirectamente\u00a0alguna influencia, los otros factores mencionados, como la deforestaci\u00f3n y la \u00a0construcci\u00f3n de carreteras a zonas remotas de la selva (\u2026), guardan una relaci\u00f3n mucho m\u00e1s directa con la situaci\u00f3n actual de agravamiento de la crisis sanitaria (..).<\/span><\/em><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><strong><em>Como reflexi\u00f3n final<\/em><\/strong><em>, no deja de ser parad\u00f3jico que la inversi\u00f3n en infraestructuras, promovida por el inter\u00e9s econ\u00f3mico para obtener beneficios de la explotaci\u00f3n de riquezas naturales presentes en la zona, no tenga otra contrapartida para la poblaci\u00f3n local que traer consigo una lacra sanitaria del calibre del virus \u00e9bola, y que encima multiplique sus efectos por la facilidad del transporte. <strong>Poner el beneficio econ\u00f3mico por encima de cualquier otra consideraci\u00f3n tiene efectos perversos como este, efectos que, a la vista est\u00e1, no soluciona la simple acci\u00f3n de los mercados. Una explotaci\u00f3n m\u00e1s racional, que retorne la parte que corresponda del beneficio obtenido con los recursos naturales de estos pa\u00edses y los dedique a infraestructuras sanitarias y de otro tipo, ser\u00eda no solo m\u00e1s deseable, sino tambi\u00e9n m\u00e1s justo. Paliar los efectos de plagas como el \u00e9bola no es una cuesti\u00f3n simplemente econ\u00f3mica, es una cuesti\u00f3n \u00e9tica y de humanidad y nos concierne a todos<\/strong><\/em>.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><span style=\"color: #3366ff;\"><strong>Debemos pues agradecer y aplaudir<\/strong> <\/span>a <\/span><a title=\"Entradas de Miguel \u00c1ngel Jim\u00e9nez Clavero\" href=\"http:\/\/www.madrimasd.org\/blogs\/virusemergentes\/author\/virusemergentes\/\">Miguel \u00c1ngel Jim\u00e9nez Clavero<\/a><span style=\"color: #000000;\">, por atesorar y exponernos una perspectiva tan integradora de los diversos factores que han influido en esta nueva tragedia, y que podr\u00eda agravarse a\u00fan m\u00e1s. Tan solo se trata pues de otra de las innumerables consecuencias que el sistema geopol\u00edtico-econ\u00f3mico-global que padecemos puede terminar acabando con la biosfera y el propio ser humano que lo fomenta. Ya hemos narrado en innumerables post, las repercusiones del cambio clim\u00e1tico, los dramas engendrados por los pesticidas y otro agroqu\u00edmicos, los estragos de la poluci\u00f3n por exceso de fertilizaci\u00f3n de la agricultura industrial, los efectos de la contaminaci\u00f3n del aire, tierras y aguas, el impacto de la naturaleza del trasiego de especies o especies invasoras, la galopante extinci\u00f3n de diversas culturas abor\u00edgenes, el nacimiento de las especies multiresistentes por un mal uso de los suelos, y un sinf\u00edn m\u00e1s de tropel\u00edas que nos venden como garantes del progreso tecnol\u00f3gico, el estado del bienestar, etc. etc. \u00a0\u00a0<\/span><span style=\"color: #000000;\"><span style=\"color: #3366ff;\">Debemos sentirnos orgullosos, \u00bfverdad? \u00bf<\/span><\/span><strong><span style=\"color: #000000;\"><span style=\"color: #3366ff;\">Cu\u00e1ntas pruebas necesitamos con vistas a demostrar que el sistema que padecemos no es sustentable? Cu\u00e1ntas evidencias adicionales har\u00e1n falta para que nuestros poderes f\u00e1cticos reconozcan que si deseamos vivir en este planeta azul necesitamos r\u00e1pida e imperiosamente un dr\u00e1stico giro de tim\u00f3n de la gas gobernanzas nacionales y globales?<\/span><\/span><\/strong><span style=\"color: #000000;\"><em>.<\/em><\/span><span style=\"color: #000000;\"> Vivimos rodeados de idiotez, por lo que con toda sinceridad soy muy, pero que muy pesimista. <\/span><\/p>\n<p style=\"text-align: justify;\"><strong><span style=\"color: #000000;\">Juan Jos\u00e9 Ib\u00e1\u00f1ez<\/span><\/strong><\/p>\n<h3>Im\u00e1genes Relacionadas:<\/h3>","protected":false},"excerpt":{"rendered":"<p>Los estragos del virus del \u00c9bola. Fuente: Despierta Venezuela Personalmente el Blog Virus Emergentes y Cambio Global, cuyo administrador resulta ser Miguel \u00c1ngel Jim\u00e9nez Clavero, me parece uno de los mejores de nuestro sistema de bit\u00e1coras, aunque por desgracia su actualizaci\u00f3n no resulta ser muy frecuente. Eso s\u00ed, pr\u00e1cticamente todas sus entradas se me antojan excelentes. Por desgracia ahora debe tratar la dram\u00e1tica epidemia del Virus del \u00c9bola, y su dram\u00e1tica extensi\u00f3n en esa \u00c1frica Olvidada y maltratada. Tambi\u00e9n a t\u00edtulo personal me siento indignado al observar que los medios de comunicaci\u00f3n y nuestros pol\u00edticos siguen centr\u00e1ndose estos d\u00edas (oto\u00f1o\u2026<\/p>\n","protected":false},"author":26,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0},"categories":[618,1,592,615],"tags":[46814,47653,47654,28139],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":4}},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Los estragos del virus del \u00c9bola. Fuente: Despierta Venezuela Personalmente el Blog Virus Emergentes y Cambio Global, cuyo administrador resulta ser Miguel \u00c1ngel Jim\u00e9nez Clavero, me parece uno de los mejores de nuestro sistema de bit\u00e1coras, aunque por desgracia su actualizaci\u00f3n no resulta ser muy frecuente. Eso s\u00ed, pr\u00e1cticamente todas sus entradas se me antojan\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Juan Jos\u00e9 Ib\u00e1\u00f1ez\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2014\/10\/01\/146157\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Un Universo invisible bajo nuestros pies - Los suelos y la vida\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"\u00c9bola, Degradaci\u00f3n Ambiental y Cambio Global - Un Universo invisible bajo nuestros pies\" \/>\n\t\t<meta property=\"og:description\" content=\"Los estragos del virus del \u00c9bola. Fuente: Despierta Venezuela Personalmente el Blog Virus Emergentes y Cambio Global, cuyo administrador resulta ser Miguel \u00c1ngel Jim\u00e9nez Clavero, me parece uno de los mejores de nuestro sistema de bit\u00e1coras, aunque por desgracia su actualizaci\u00f3n no resulta ser muy frecuente. Eso s\u00ed, pr\u00e1cticamente todas sus entradas se me antojan\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2014\/10\/01\/146157\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2014-10-01T19:17:47+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2014-10-02T08:37:47+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/juan.j.marti.14\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"\u00c9bola, Degradaci\u00f3n Ambiental y Cambio Global - Un Universo invisible bajo nuestros pies\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Los estragos del virus del \u00c9bola. Fuente: Despierta Venezuela Personalmente el Blog Virus Emergentes y Cambio Global, cuyo administrador resulta ser Miguel \u00c1ngel Jim\u00e9nez Clavero, me parece uno de los mejores de nuestro sistema de bit\u00e1coras, aunque por desgracia su actualizaci\u00f3n no resulta ser muy frecuente. Eso s\u00ed, pr\u00e1cticamente todas sus entradas se me antojan\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2014\\\/10\\\/01\\\/146157#blogposting\",\"name\":\"\\u00c9bola, Degradaci\\u00f3n Ambiental y Cambio Global - Un Universo invisible bajo nuestros pies\",\"headline\":\"\\u00c9bola, Degradaci\\u00f3n Ambiental y Cambio Global\",\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"http:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/wp-content\\\/blogs.dir\\\/42\\\/files\\\/1357\\\/ebola.jpg\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2014\\\/10\\\/01\\\/146157\\\/#articleImage\"},\"datePublished\":\"2014-10-01T20:17:47+01:00\",\"dateModified\":\"2014-10-02T09:37:47+01:00\",\"inLanguage\":\"es-ES\",\"commentCount\":1,\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2014\\\/10\\\/01\\\/146157#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2014\\\/10\\\/01\\\/146157#webpage\"},\"articleSection\":\"Ecolog\\u00eda y Biogeograf\\u00eda post posteriores a agosto de 2009, General, Los Suelos y la Salud, Notas Breves de Prensa, degradaci\\u00f3n ambiental, del \\u00c9bola, desarrollo insostenible, Virus\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2014\\\/10\\\/01\\\/146157#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/general#listItem\",\"name\":\"General\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/general#listItem\",\"position\":2,\"name\":\"General\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/general\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2014\\\/10\\\/01\\\/146157#listItem\",\"name\":\"\\u00c9bola, Degradaci\\u00f3n Ambiental y Cambio Global\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2014\\\/10\\\/01\\\/146157#listItem\",\"position\":3,\"name\":\"\\u00c9bola, Degradaci\\u00f3n Ambiental y Cambio Global\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/general#listItem\",\"name\":\"General\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#organization\",\"name\":\"Un Universo invisible bajo nuestros pies\",\"description\":\"Los suelos y la vida\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/files\\\/2022\\\/02\\\/logo.png\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2014\\\/10\\\/01\\\/146157\\\/#organizationLogo\",\"width\":217,\"height\":72},\"image\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2014\\\/10\\\/01\\\/146157\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/juan.j.marti.14\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo\",\"name\":\"Juan Jos\\u00e9 Ib\\u00e1\\u00f1ez\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2014\\\/10\\\/01\\\/146157#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/387f3a100385573d8f42ce2a3211fd1c?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Juan Jos\\u00e9 Ib\\u00e1\\u00f1ez\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2014\\\/10\\\/01\\\/146157#webpage\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2014\\\/10\\\/01\\\/146157\",\"name\":\"\\u00c9bola, Degradaci\\u00f3n Ambiental y Cambio Global - Un Universo invisible bajo nuestros pies\",\"description\":\"Los estragos del virus del \\u00c9bola. Fuente: Despierta Venezuela Personalmente el Blog Virus Emergentes y Cambio Global, cuyo administrador resulta ser Miguel \\u00c1ngel Jim\\u00e9nez Clavero, me parece uno de los mejores de nuestro sistema de bit\\u00e1coras, aunque por desgracia su actualizaci\\u00f3n no resulta ser muy frecuente. Eso s\\u00ed, pr\\u00e1cticamente todas sus entradas se me antojan\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2014\\\/10\\\/01\\\/146157#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\"},\"datePublished\":\"2014-10-01T20:17:47+01:00\",\"dateModified\":\"2014-10-02T09:37:47+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#website\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/\",\"name\":\"Un Universo invisible bajo nuestros pies\",\"description\":\"Los suelos y la vida\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"\u00c9bola, Degradaci\u00f3n Ambiental y Cambio Global - Un Universo invisible bajo nuestros pies","description":"Los estragos del virus del \u00c9bola. Fuente: Despierta Venezuela Personalmente el Blog Virus Emergentes y Cambio Global, cuyo administrador resulta ser Miguel \u00c1ngel Jim\u00e9nez Clavero, me parece uno de los mejores de nuestro sistema de bit\u00e1coras, aunque por desgracia su actualizaci\u00f3n no resulta ser muy frecuente. Eso s\u00ed, pr\u00e1cticamente todas sus entradas se me antojan","canonical_url":"https:\/\/www.madrimasd.org\/blogs\/universo\/2014\/10\/01\/146157","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2014\/10\/01\/146157#blogposting","name":"\u00c9bola, Degradaci\u00f3n Ambiental y Cambio Global - Un Universo invisible bajo nuestros pies","headline":"\u00c9bola, Degradaci\u00f3n Ambiental y Cambio Global","author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author"},"publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#organization"},"image":{"@type":"ImageObject","url":"http:\/\/www.madrimasd.org\/blogs\/universo\/wp-content\/blogs.dir\/42\/files\/1357\/ebola.jpg","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2014\/10\/01\/146157\/#articleImage"},"datePublished":"2014-10-01T20:17:47+01:00","dateModified":"2014-10-02T09:37:47+01:00","inLanguage":"es-ES","commentCount":1,"mainEntityOfPage":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2014\/10\/01\/146157#webpage"},"isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2014\/10\/01\/146157#webpage"},"articleSection":"Ecolog\u00eda y Biogeograf\u00eda post posteriores a agosto de 2009, General, Los Suelos y la Salud, Notas Breves de Prensa, degradaci\u00f3n ambiental, del \u00c9bola, desarrollo insostenible, Virus"},{"@type":"BreadcrumbList","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2014\/10\/01\/146157#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo#listItem","position":1,"name":"Home","item":"https:\/\/www.madrimasd.org\/blogs\/universo","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/general#listItem","name":"General"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/general#listItem","position":2,"name":"General","item":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/general","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2014\/10\/01\/146157#listItem","name":"\u00c9bola, Degradaci\u00f3n Ambiental y Cambio Global"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2014\/10\/01\/146157#listItem","position":3,"name":"\u00c9bola, Degradaci\u00f3n Ambiental y Cambio Global","previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/general#listItem","name":"General"}}]},{"@type":"Organization","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#organization","name":"Un Universo invisible bajo nuestros pies","description":"Los suelos y la vida","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/","logo":{"@type":"ImageObject","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2014\/10\/01\/146157\/#organizationLogo","width":217,"height":72},"image":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2014\/10\/01\/146157\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/juan.j.marti.14"]},{"@type":"Person","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo","name":"Juan Jos\u00e9 Ib\u00e1\u00f1ez","image":{"@type":"ImageObject","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2014\/10\/01\/146157#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/387f3a100385573d8f42ce2a3211fd1c?s=96&d=mm&r=g","width":96,"height":96,"caption":"Juan Jos\u00e9 Ib\u00e1\u00f1ez"}},{"@type":"WebPage","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2014\/10\/01\/146157#webpage","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/2014\/10\/01\/146157","name":"\u00c9bola, Degradaci\u00f3n Ambiental y Cambio Global - Un Universo invisible bajo nuestros pies","description":"Los estragos del virus del \u00c9bola. Fuente: Despierta Venezuela Personalmente el Blog Virus Emergentes y Cambio Global, cuyo administrador resulta ser Miguel \u00c1ngel Jim\u00e9nez Clavero, me parece uno de los mejores de nuestro sistema de bit\u00e1coras, aunque por desgracia su actualizaci\u00f3n no resulta ser muy frecuente. Eso s\u00ed, pr\u00e1cticamente todas sus entradas se me antojan","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#website"},"breadcrumb":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2014\/10\/01\/146157#breadcrumblist"},"author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author"},"creator":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author"},"datePublished":"2014-10-01T20:17:47+01:00","dateModified":"2014-10-02T09:37:47+01:00"},{"@type":"WebSite","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#website","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/","name":"Un Universo invisible bajo nuestros pies","description":"Los suelos y la vida","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Un Universo invisible bajo nuestros pies - Los suelos y la vida","og:type":"article","og:title":"\u00c9bola, Degradaci\u00f3n Ambiental y Cambio Global - Un Universo invisible bajo nuestros pies","og:description":"Los estragos del virus del \u00c9bola. Fuente: Despierta Venezuela Personalmente el Blog Virus Emergentes y Cambio Global, cuyo administrador resulta ser Miguel \u00c1ngel Jim\u00e9nez Clavero, me parece uno de los mejores de nuestro sistema de bit\u00e1coras, aunque por desgracia su actualizaci\u00f3n no resulta ser muy frecuente. Eso s\u00ed, pr\u00e1cticamente todas sus entradas se me antojan","og:url":"https:\/\/www.madrimasd.org\/blogs\/universo\/2014\/10\/01\/146157","og:image":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png","og:image:secure_url":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png","article:published_time":"2014-10-01T19:17:47+00:00","article:modified_time":"2014-10-02T08:37:47+00:00","article:publisher":"https:\/\/www.facebook.com\/juan.j.marti.14","twitter:card":"summary","twitter:title":"\u00c9bola, Degradaci\u00f3n Ambiental y Cambio Global - Un Universo invisible bajo nuestros pies","twitter:description":"Los estragos del virus del \u00c9bola. Fuente: Despierta Venezuela Personalmente el Blog Virus Emergentes y Cambio Global, cuyo administrador resulta ser Miguel \u00c1ngel Jim\u00e9nez Clavero, me parece uno de los mejores de nuestro sistema de bit\u00e1coras, aunque por desgracia su actualizaci\u00f3n no resulta ser muy frecuente. Eso s\u00ed, pr\u00e1cticamente todas sus entradas se me antojan","twitter:image":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png"},"aioseo_meta_data":{"post_id":"146157","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":null,"isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","tabs":null,"priority":null,"frequency":null,"local_seo":null,"created":"2022-06-03 16:57:43","updated":"2026-05-26 18:08:10","limit_modified_date":false,"ai":null,"breadcrumb_settings":null,"seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/general\" title=\"General\">General<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t\u00c9bola, Degradaci\u00f3n Ambiental y Cambio Global\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.madrimasd.org\/blogs\/universo"},{"label":"General","link":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/general"},{"label":"\u00c9bola, Degradaci\u00f3n Ambiental y Cambio Global","link":"https:\/\/www.madrimasd.org\/blogs\/universo\/2014\/10\/01\/146157"}],"_links":{"self":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts\/146157"}],"collection":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/comments?post=146157"}],"version-history":[{"count":6,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts\/146157\/revisions"}],"predecessor-version":[{"id":146163,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts\/146157\/revisions\/146163"}],"wp:attachment":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/media?parent=146157"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/categories?post=146157"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/tags?post=146157"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}