{"id":146304,"date":"2015-11-09T15:39:58","date_gmt":"2015-11-09T14:39:58","guid":{"rendered":"http:\/\/www.madrimasd.org\/blogs\/universo\/?p=146304"},"modified":"2015-11-09T15:39:58","modified_gmt":"2015-11-09T14:39:58","slug":"el-secuestro-de-carbono-por-los-suelos-del-mundo-ultimas-estimaciones-en-2014","status":"publish","type":"post","link":"https:\/\/www.madrimasd.org\/blogs\/universo\/2015\/11\/09\/146304","title":{"rendered":"El Secuestro de carbono por los suelos del mundo. \u00daltimas estimaciones en 2014"},"content":{"rendered":"<p align=\"center\"><span style=\"color: #000000;\"><img decoding=\"async\" class=\"ngg-singlepic ngg-center\" style=\"width: 480px; height: 329px;\" src=\"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-content\/blogs.dir\/42\/files\/397\/wise-nuevo.jpg\" alt=\"wise-nuevo\" width=\"750\" height=\"448\" \/>\u00a0<\/span><\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/library.wur.nl\/isric\/fulltext\/isricu_t47d6414d_001.pdf\"><span style=\"color: #0000ff;\">Carbono de los suelos en forma org\u00e1nica e inorg\u00e1nicaN.H. Batjes EJSS, ISRIC<\/span><\/a><\/p>\n<p align=\"center\"><span style=\"color: #000000;\"><span style=\"color: #000000;\"><img decoding=\"async\" class=\"ngg-singlepic ngg-center\" style=\"width: 415px; height: 598px;\" src=\"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-content\/blogs.dir\/42\/files\/397\/carbono-mundo-wise.jpg\" alt=\"carbono-mundo-wise\" width=\"651\" height=\"730\" \/><\/span>\u00a0<\/span><\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/library.wur.nl\/isric\/fulltext\/isricu_t47d6414d_001.pdf\"><span style=\"color: #0000ff;\">Carbono de los suelos en forma org\u00e1nica e inorg\u00e1nica N.H. Batjes EJSS, ISRIC<\/span><\/a><\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.researchgate.net\/profile\/Niels_Batjes\"><span style=\"color: #0000ff;\">N.H. Batjes<\/span><\/a><span style=\"color: #000000;\"> ha publicado recientemente en <em>el European Journal of Soil Science<\/em><\/span><span style=\"color: #000000;\"> el <\/span><span style=\"color: #3366ff;\"><strong>\u00faltimo inventario sobre el secuestro de carbono de los suelos del mundo<\/strong>, <span style=\"color: #000000;\">en el cual<\/span> <span style=\"color: #800000;\"><strong>se incluye por primera vez no s\u00f3lo su contenido en materia org\u00e1nica, sino tambi\u00e9n el que se almacena en forma de carbonatos<\/strong><\/span><\/span><span style=\"color: #000000;\">. Como ver\u00e9is, este estudio tambi\u00e9n <\/span><span style=\"color: #3366ff;\"><strong>se encuentra en acceso abierto en la p\u00e1gina Web del ISRIC<\/strong><\/span><span style=\"color: #000000;\">, por lo que pod\u00e9is obtenerlo gratuitamente en formato digital. En este post incidiremos principalmente, en <\/span><strong><span style=\"color: #000000;\"><span style=\"color: #3366ff;\">que la inclusi\u00f3n \u201cparcial\u201d de esta \u00faltima forma de almacenamiento, es decir\u00a0sales, <span style=\"color: #800000;\">aumentando considerablemente las valoraciones previas<\/span><\/span>. <span style=\"color: #3366ff;\">Y digo parcial, ya que<\/span><\/span><\/strong><span style=\"color: #000000;\"> si bien se contempla las cantidades del primer metro a partir de la superficie, aun no se disponen cifras del que alberga el medio ed\u00e1fico a mayores profundidades. <\/span><strong><span style=\"color: #000000;\"><span style=\"color: #3366ff;\">Abajo os he traducido al espa\u00f1ol-castellano el resumen de este interesante art\u00edculo<\/span><\/span><\/strong><span style=\"color: #000000;\">. <\/span><span style=\"color: #000000;\">\u00a0<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Cabr\u00eda recordar que <span style=\"color: #3366ff;\"><strong>en los biomas mediterr\u00e1neos, semi\u00e1ridos y \u00e1ridos (incluyendo desiertos), la extensi\u00f3n de la edafotaxa<\/strong><\/span><\/span><span style=\"color: #000000;\"> (tipos de suelos) con la <\/span><span style=\"color: #3366ff;\"><strong>presencia de horizontes profundos ricos en carbonatos es enorme<\/strong><\/span><span style=\"color: #000000;\">. Del mismo modo tambi\u00e9n es necesario apreciar\u00a0que <\/span><strong><span style=\"color: #000000;\"><span style=\"color: #3366ff;\">2\/3 de la superficie terrestre del mundo resulta ser semi\u00e1rida y \u00e1rida<\/span><\/span><\/strong><span style=\"color: #000000;\">. <\/span><span style=\"color: #3366ff;\"><strong>En consecuencia, las cifras ofrecidas deben adolecer necesariamente de considerables subestimaciones<\/strong><\/span><span style=\"color: #000000;\"><span style=\"color: #3366ff;\">.<\/span> Con toda seguridad, <\/span><span style=\"color: #3366ff;\"><strong><span style=\"color: #800000;\">cuando se dispongan\u00a0 de datos m\u00e1s all\u00e1 del metro superficial, las cifras ofrecidas alcancen o superen las del almacenamiento de carbono org\u00e1nico<\/span>, como ya os anticipamos <\/strong><\/span><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2007\/06\/15\/67800\"><span style=\"color: #0000ff;\">en este post<\/span><\/a><span style=\"color: #000000;\">, \u00a1hace ya m\u00e1s de siete a\u00f1os!. Volvemos a dar en la diana, no por ser m\u00e1s listos que nadie, sino por el mero sentido com\u00fan. Eso s\u00ed, <span style=\"color: #3366ff;\"><strong>a\u00fan deben estudiarse la tasas anuales de secuestro de estas formas de carbono, ya que de ser altas, podr\u00edan cambiar el panorama ofrecido hasta la fecha, lo cual tambi\u00e9n tendr\u00eda efecto en el mercado mundial de emisiones<\/strong><\/span><\/span><span style=\"color: #000000;\">, que actualmente favorece a aquellos pa\u00edses en los que las reservas de carbono son principalmente org\u00e1nicas (ambientes m\u00e1s h\u00famedos). Os recordamos que en esta bit\u00e1cora hemos aportado abundante informaci\u00f3n sobre el tema en varios post previos incluidos en nuestra categor\u00eda <\/span><span style=\"color: #000000;\">\u00a0<\/span><span style=\"color: #000000;\">\u201c<\/span><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/biomasa-y-necromasa-en-los-suelos-raices-y-materia-organica\"><span style=\"color: #0000ff;\">Biomasa y Necromasa en los Suelos: Ra\u00edces y Materia Org\u00e1nica<\/span><\/a><span style=\"color: #000000;\">\u201d. <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Como ya me imagino que sab\u00e9is,<span style=\"color: #3366ff;\"> <strong>la mayor<\/strong><strong> parte de las estimaciones actuales se basan tan solo en calcular el secuestro de carbono en los veinte cent\u00edmetros superficiales, o en el mejor de los casos en los cuarenta<\/strong><\/span><\/span><span style=\"color: #000000;\">, como propone la Uni\u00f3n Europea.\u00a0 <\/span><span style=\"color: #000000;\">Si os fij\u00e1is en el gr\u00e1fico y tabla adjuntas (la figura la he elaborado personalmente partiendo de otra previa\u00a0del citado art\u00edculo; no es muy buena, por lo que os pido disculpas) <\/span><span style=\"color: #800000;\"><strong>tales cifras ofrecen una idea muy pobre, y porque no decirlo err\u00f3nea, del potencial del suelo para secuestrar carbono de la atm\u00f3sfera<\/strong><\/span><span style=\"color: #000000;\">. Debemos pues agradecer a <\/span><a href=\"https:\/\/www.researchgate.net\/profile\/Niels_Batjes\"><span style=\"color: #0000ff;\">N.H. Batjes<\/span><\/a><span style=\"color: #000000;\">, una vez m\u00e1s, que se interese por la realidad y no por captar fondos econ\u00f3micos aun a sabiendas de que las cifras que proporcionen no sirvan a la hora de valorar este proceso. En el art\u00edculo <\/span><a href=\"http:\/\/www.researchgate.net\/profile\/Niels_Batjes\"><span style=\"color: #0000ff;\">recientemente publicado por Batjes<\/span><\/a><span style=\"color: #000000;\"> se os muestra much\u00edsima m\u00e1s informaci\u00f3n, que no os podemos ofrecer, por tratarse de un art\u00edculo al que hay que acceder previo pago. Eso s\u00ed, por encontrarse simult\u00e1neamente en acceso abierto, os recomiendo la lectura de esta publicaci\u00f3n, con vistas a que <span style=\"color: #800000;\"><strong>desmitifiqu\u00e9is los datos oficiales que suelen publicarse en art\u00edculos y sitios WEB de la mayor\u00eda de las instituciones<\/strong><\/span><\/span><span style=\"color: #000000;\">.<\/span><span style=\"color: #000000;\">\u00a0 <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Por \u00faltimo, tan solo comentar que <span style=\"color: #3366ff;\"><strong>el carbono que se encuentra almacenado en los horizontes superficiales resulta ser generalmente mucho m\u00e1s l\u00e1bil que el que se encuentra a mayor profundidad, por lo que<\/strong><\/span><\/span><span style=\"color: #000000;\"> retorna (es emitido) antes a la atm\u00f3sfera (a no ser que se trata de formas carbonosas), hecho de gran trascendencia para una valoraci\u00f3n m\u00e1s rigurosa del significado de los datos.<\/span><span style=\"color: #000000;\">\u00a0 <\/span><span style=\"color: #000000;\">A mayor estabilidad (menor labilidad) almacenamiento m\u00e1s prolongado. <\/span><\/p>\n<p><span style=\"color: #008000;\"><strong>Juan Jos\u00e9 Ib\u00e1\u00f1ez <\/strong><\/span><\/p>\n<p><!--more--><\/p>\n<p style=\"text-align: justify;\"><em><span style=\"color: #000000;\">En el resumen del estudio <\/span><\/em><a href=\"http:\/\/www.researchgate.net\/profile\/Niels_Batjes\"><em><span style=\"color: #0000ff;\">llevado a cabo por Batjes<\/span><\/em><\/a><em><span style=\"color: #000000;\"> puede leerse\u2026\u2026<\/span><\/em><\/p>\n<p style=\"text-align: justify;\"><strong>Total carbon and nitrogen in the soils of the world (EJSS Land Mark Paper No. 3)<\/strong><\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/library.wur.nl\/isric\/fulltext\/isricu_t47d6414d_001.pdf\"><span style=\"color: #0000ff;\">Total carbon and nitrogen in the soils of the world (Acceso Abierto en la p\u00e1gina Web del ISRIC)<\/span><\/a><\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.researchgate.net\/profile\/Niels_Batjes\">N.H. Batjes<\/a>\u00a02014:\u00a0European Journal of Soil Science (Eur J Soil Sci).\u00a0DOI:\u00a010.1111\/ejss.12114_2<\/p>\n<p style=\"text-align: justify;\"><strong><span style=\"color: #800000;\">ABSTRACT<\/span>:<\/strong> The <strong>soil is important in sequestering atmospheric CO2 and<\/strong> in emitting trace gases (e.g. CO2, CH4 and N2O) that are radiatively active and enhance the \u2018greenhouse\u2019 effect. <strong>Land use changes and predicted global warming, through their effects on<\/strong> net primary productivity, the plant community and soil conditions, <strong>may have important effects on the size of the organic matter pool in the soil and directly affect the atmospheric concentration of these trace gases<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong><\/strong><em><span style=\"color: #800000;\">El suelo es importante en el secuestro de CO2 en la atm\u00f3sfera, as\u00ed como en la emisi\u00f3n de gases traza (por ejemplo CO2, CH4 y N2O) que son radiativamente activos y aumentan el efecto &#8216;invernadero&#8217;. Cambios de uso del suelo y el previsible\u00a0 calentamiento global, mediante sus efectos sobre la productividad primaria neta, la comunidad de plantas y las condiciones del suelo, pueden tener efectos importantes sobre las reservas (dep\u00f3sito) de materia org\u00e1nica en el suelo y afectar directamente la concentraci\u00f3n atmosf\u00e9rica de estos gases traza<\/span>.<br \/>\n<\/em><br \/>\n<strong>A discrepancy of approximately 350 \u00d7 1015 g (or Pg) of C in two recent estimates of soil carbon reserves worldwide is evaluated using<\/strong> the geo-referenced database developed for the World Inventory of Soil Emission Potentials (<strong>WISE<\/strong>) project. <strong>This database holds 4353 soil profiles distributed globally which are considered to represent the soil units<\/strong> shown on a 1\/2\u00b0 latitude by 1\/2\u00b0 longitude <strong>version of the corrected and digitized 1:5 M FAO\u2013UNESCO Soil Map of the World<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong><\/strong><span style=\"color: #800000;\"><em>Una discrepancia de aproximadamente 350 \u00d7 1015 g (o PG) de Carbono en dos recientes estimaciones sobre las reservas de carbono de los suelos del mundo ha sido evaluada utilizando la base de datos geo-referenciada desarrollada para el Proyecto denominado Inventario Mundial de Emisiones Potenciales (<\/em><a href=\"http:\/\/www.isric.org\/data\/isric-wise-global-soil-profile-data-ver-31\"><span style=\"color: #800000;\"><em>WISE<\/em><\/span><\/a><\/span><em><span style=\"color: #800000;\">) del medio ed\u00e1fico. Tal base de datos contiene 4353 perfiles de suelos distribuidos a por todo el mundo que son considerados representativos de las unidades o tipos de suelos que se muestran sobre cuadr\u00edculas de 1\/2 \u00b0 de latitud por 2.1 \u00b0 de longitud de la versi\u00f3n 1 corregida y digitalizada del Mapa 1:5.000.000 del Mundo llevado a cabo hace ya algunos decenios por la FAO-UNESCO<\/span><\/em><em><br \/>\n<\/em><strong><\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Total soil carbon pools for the entire land area of the world, excluding carbon held in the litter layer and charcoal, amounts to 2157\u20132293 Pg of C in the upper 100 cm<\/strong>. <strong>Soil organic carbon is estimated to be 684\u2013724 Pg of C in the upper 30 cm, 1462\u20131548 Pg of C in the upper 100 cm, and 2376\u20132456 Pg of C in the upper 200 cm<\/strong>.<\/p>\n<p style=\"text-align: justify;\"><em><span style=\"color: #800000;\">El reservorio total de carbono de los suelos de la superficie terrestre mundial, excluyendo el retenido en la capa de hojarasca y el carb\u00f3n vegetal, asciende a 2157-2293 Pg de C en los 100 cm superiores de los perfiles ed\u00e1ficos. El carbono org\u00e1nico del suelo se estima entre 684 y 724 Pg si tan solo para los 30 cm m\u00e1s superficiales del medio ed\u00e1fico, 1462-1548 Pg si se contemplan los 100 cm superiores, y de entre 2376 y 2456 Pg al contemplar los 200 superiores, punto a partir del cual los edafotaxa o tipos de suelos no contemplan sus propiedades con vistas a ser clasificados<\/span> <\/em><strong><\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Although deforestation, changes in land use and predicted climate change can alter the amount of organic carbon held in the superficial soil layers rapidly, this is less so for the soil carbonate carbon. An estimated 695\u2013748 Pg of carbonate-C is held in the upper 100 cm<\/strong> of the world&#8217;s soils. <strong>Mean C: N ratios of soil organic matter range from 9.9 for arid Yermosols to 25.8 for Histosols<\/strong>. <strong>Global amounts of soil nitrogen are estimated to be 133\u2013140 Pg of N for the upper 100 cm<\/strong>. Possible changes in soil organic carbon and nitrogen dynamics caused by increased concentrations of atmospheric CO2 and the predicted associated rise in temperature are discussed.<\/p>\n<p style=\"text-align: justify;\"><em><span style=\"color: #800000;\">Si bien la deforestaci\u00f3n, los cambios en el uso del suelo y las predicciones sobre el cambio clim\u00e1tico\u00a0 pueden alterar r\u00e1pidamente la cantidad de carbono org\u00e1nico retenido en las capas superficiales del suelo, no ocurre lo mismo para el carbono acumulado en los suelos en forma de carbonatos (secuestro mineral). Se estima que 695 a 748 Pg de carbono en forma de tales carbonatos se ubica en los 100 cm superiores de los suelos del mundo. La media de la raz\u00f3n C: N (carbono\/nitr\u00f3geno) de la materia org\u00e1nica de los suelos fluctuar\u00eda entre 9,9 para los Yermosoles de los biomas \u00e1ridos y el 25,8 en el caso de los Histosoles Turberas)que abundan en las tundras y otros biomas. Las cantidades globales de nitr\u00f3geno del suelo se estiman entre los \u00a0133 y 140 Pg \u00a0para los 100 cm superiores del perfil ed\u00e1fico. En este trabajo se discuten los posibles cambios en la din\u00e1mica del carbono y del nitr\u00f3geno org\u00e1nico del suelo que podr\u00eda ocasionar el aumento de las concentraciones de CO2 en la atm\u00f3sfera y el consiguiente aumento previsto de la temperatura a escala mundial<\/span>. <\/em><\/p>\n<p style=\"text-align: justify;\"><em><\/em>Large amounts of organic carbon, which are not yet considered in most global C-budgets (see IPCC, 1992), are also stored between depths of 100 and 200 cm. Much of this deeper carbon occurs in fairly stable forms, and therefore will not contribute much to current gaseous emissions<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #800000;\"><em>Grandes cantidades de carbono org\u00e1nico, que a\u00fan no han sido consideradas en la mayor\u00eda de las estimaciones \u00a0globales de hoy en d\u00eda (ver IPCC, 1992), son Tambi\u00e9n almacenado entre profundidades de 100 y 200 cm. Gran parte de este carbono almacenado a mayor profundidad se encuentra constituido por formas bastante estable, y que por lo tanto \u00a0no contribuyen mucho a los actuales emisiones de la atm\u00f3sfera<\/em><\/span><\/p>\n<p style=\"text-align: justify;\"><strong>El petagramo (Pg) de carbono: un Pg = 1,0<sup>15<\/sup> gramos = mil millones de toneladas m\u00e9tricas<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong><\/strong><a href=\"http:\/\/www.isric.org\/data\/isric-wise-international-soil-profile-dataset\"><strong><span style=\"color: #0000ff;\">ISRIC-WISE international soil profile dataset<\/span><\/strong><\/a><\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.isric.org\/data\/isric-wise-global-soil-profile-data-ver-31\"><strong><span style=\"color: #0000ff;\">ISRIC-WISE international soil profile dataset<\/span><\/strong><\/a><\/p>\n<p style=\"text-align: justify;\">Version 3.1 of the <strong>ISRIC-WISE database (WISE3)<\/strong> was compiled from a wide range of soil profile data collected by many soil professionals worldwide. All profiles have been harmonized with respect to the original Legend (1974) and Revised Legend (1988) of FAO-Unesco. Thereby, the primary soil data \u2500 and any secondary data derived from them \u2500 can be linked using GIS to the spatial units of the 1:5M digitized Soil Map of the World as well as more recent digital Soil and Terrain (SOTER) databases through the soil legend code.<\/p>\n<p style=\"text-align: justify;\">WISE3 holds selected attribute data for some 10,250 soil profiles, with some 47,800 horizons, from 149 countries. Individual profiles have been sampled, described, and analyzed according to methods and standards in use in the originating countries. There is no uniform set of properties for which all profiles have analytical data, generally because only selected measurements were planned during the original surveys. Methods used for laboratory determinations of specific soil properties vary between laboratories and over time; sometimes, results for the same property cannot be compared directly. WISE3 will inevitably include gaps, being a compilation of legacy soil data derived from traditional soil survey, which can be of a taxonomic, geographic, and soil analytical nature. As a result, the amount of data available for modelling is sometimes much less than expected. Adroit use of the data, however, will permit a wide range of agricultural and environmental applications at a global and continental scale (1:500 000 and broader).<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #800000;\"><strong>Additional information<\/strong><\/span>:<\/p>\n<p style=\"text-align: justify;\">Batjes NH 2009<a href=\"http:\/\/onlinelibrary.wiley.com\/doi\/10.1111\/j.1475-2743.2009.00202.x\/abstract;jsessionid=35A7E9114179E953E7552678E94903DF.f02t02\"><span style=\"color: #0000ff;\">. Harmonized soil profile data for applications at global and continental scales: updates to the WISE datase<\/span><\/a>. Soil Use and Management 25, 124-127\u00a0\u00a0\u00a0 more &#8230;<\/p>\n<h3>Im\u00e1genes Relacionadas:<\/h3>","protected":false},"excerpt":{"rendered":"<p>\u00a0 Carbono de los suelos en forma org\u00e1nica e inorg\u00e1nicaN.H. Batjes EJSS, ISRIC \u00a0 Carbono de los suelos en forma org\u00e1nica e inorg\u00e1nica N.H. Batjes EJSS, ISRIC N.H. Batjes ha publicado recientemente en el European Journal of Soil Science el \u00faltimo inventario sobre el secuestro de carbono de los suelos del mundo, en el cual se incluye por primera vez no s\u00f3lo su contenido en materia org\u00e1nica, sino tambi\u00e9n el que se almacena en forma de carbonatos. Como ver\u00e9is, este estudio tambi\u00e9n se encuentra en acceso abierto en la p\u00e1gina Web del ISRIC, por lo que pod\u00e9is obtenerlo gratuitamente en\u2026<\/p>\n","protected":false},"author":26,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0},"categories":[596,608,590,591,597,604,598,595],"tags":[28188,28187,7766,28186,20378,46676],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":4}},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Carbono de los suelos en forma org\u00e1nica e inorg\u00e1nicaN.H. Batjes EJSS, ISRIC Carbono de los suelos en forma org\u00e1nica e inorg\u00e1nica N.H. Batjes EJSS, ISRIC N.H. Batjes ha publicado recientemente en el European Journal of Soil Science el \u00faltimo inventario sobre el secuestro de carbono de los suelos del mundo, en el cual\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Juan Jos\u00e9 Ib\u00e1\u00f1ez\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2015\/11\/09\/146304\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Un Universo invisible bajo nuestros pies - Los suelos y la vida\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"El Secuestro de carbono por los suelos del mundo. \u00daltimas estimaciones en 2014 - Un Universo invisible bajo nuestros pies\" \/>\n\t\t<meta property=\"og:description\" content=\"Carbono de los suelos en forma org\u00e1nica e inorg\u00e1nicaN.H. Batjes EJSS, ISRIC Carbono de los suelos en forma org\u00e1nica e inorg\u00e1nica N.H. Batjes EJSS, ISRIC N.H. Batjes ha publicado recientemente en el European Journal of Soil Science el \u00faltimo inventario sobre el secuestro de carbono de los suelos del mundo, en el cual\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2015\/11\/09\/146304\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2015-11-09T14:39:58+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2015-11-09T14:39:58+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/juan.j.marti.14\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"El Secuestro de carbono por los suelos del mundo. \u00daltimas estimaciones en 2014 - Un Universo invisible bajo nuestros pies\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Carbono de los suelos en forma org\u00e1nica e inorg\u00e1nicaN.H. Batjes EJSS, ISRIC Carbono de los suelos en forma org\u00e1nica e inorg\u00e1nica N.H. Batjes EJSS, ISRIC N.H. Batjes ha publicado recientemente en el European Journal of Soil Science el \u00faltimo inventario sobre el secuestro de carbono de los suelos del mundo, en el cual\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2015\\\/11\\\/09\\\/146304#blogposting\",\"name\":\"El Secuestro de carbono por los suelos del mundo. \\u00daltimas estimaciones en 2014 - Un Universo invisible bajo nuestros pies\",\"headline\":\"El Secuestro de carbono por los suelos del mundo. \\u00daltimas estimaciones en 2014\",\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"http:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/wp-content\\\/blogs.dir\\\/42\\\/files\\\/397\\\/wise-nuevo.jpg\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2015\\\/11\\\/09\\\/146304\\\/#articleImage\"},\"datePublished\":\"2015-11-09T15:39:58+01:00\",\"dateModified\":\"2015-11-09T15:39:58+01:00\",\"inLanguage\":\"es-ES\",\"commentCount\":1,\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2015\\\/11\\\/09\\\/146304#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2015\\\/11\\\/09\\\/146304#webpage\"},\"articleSection\":\"Biolog\\u00eda y Ecolog\\u00eda del Suelo, Biomasa y Necromasa en los Suelos: Ra\\u00edces y Materia Org\\u00e1nica, Componentes, Estructuras y Procesos en los Suelos, Edafolog\\u00eda y Pol\\u00edtica, Filosof\\u00eda, Historia y Sociolog\\u00eda de la Edafolog\\u00eda, Geograf\\u00eda de Suelos y Megaedafolog\\u00eda, Suelos de Zonas \\u00c1ridas, Semi\\u00e1ridas y desertificaci\\u00f3n, Suelos y Cambio Clim\\u00e1tico, estimaciones globales, inorg\\u00e1nico, inventarios de suelo, org\\u00e1nico, Secustro de carbono, suelos\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2015\\\/11\\\/09\\\/146304#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/componentes-estructuras-y-procesos-en-los-suelos#listItem\",\"name\":\"Componentes, Estructuras y Procesos en los Suelos\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/componentes-estructuras-y-procesos-en-los-suelos#listItem\",\"position\":2,\"name\":\"Componentes, Estructuras y Procesos en los Suelos\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/componentes-estructuras-y-procesos-en-los-suelos\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2015\\\/11\\\/09\\\/146304#listItem\",\"name\":\"El Secuestro de carbono por los suelos del mundo. \\u00daltimas estimaciones en 2014\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2015\\\/11\\\/09\\\/146304#listItem\",\"position\":3,\"name\":\"El Secuestro de carbono por los suelos del mundo. \\u00daltimas estimaciones en 2014\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/componentes-estructuras-y-procesos-en-los-suelos#listItem\",\"name\":\"Componentes, Estructuras y Procesos en los Suelos\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#organization\",\"name\":\"Un Universo invisible bajo nuestros pies\",\"description\":\"Los suelos y la vida\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/files\\\/2022\\\/02\\\/logo.png\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2015\\\/11\\\/09\\\/146304\\\/#organizationLogo\",\"width\":217,\"height\":72},\"image\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2015\\\/11\\\/09\\\/146304\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/juan.j.marti.14\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo\",\"name\":\"Juan Jos\\u00e9 Ib\\u00e1\\u00f1ez\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2015\\\/11\\\/09\\\/146304#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/387f3a100385573d8f42ce2a3211fd1c?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Juan Jos\\u00e9 Ib\\u00e1\\u00f1ez\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2015\\\/11\\\/09\\\/146304#webpage\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2015\\\/11\\\/09\\\/146304\",\"name\":\"El Secuestro de carbono por los suelos del mundo. \\u00daltimas estimaciones en 2014 - Un Universo invisible bajo nuestros pies\",\"description\":\"Carbono de los suelos en forma org\\u00e1nica e inorg\\u00e1nicaN.H. Batjes EJSS, ISRIC Carbono de los suelos en forma org\\u00e1nica e inorg\\u00e1nica N.H. Batjes EJSS, ISRIC N.H. Batjes ha publicado recientemente en el European Journal of Soil Science el \\u00faltimo inventario sobre el secuestro de carbono de los suelos del mundo, en el cual\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2015\\\/11\\\/09\\\/146304#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\"},\"datePublished\":\"2015-11-09T15:39:58+01:00\",\"dateModified\":\"2015-11-09T15:39:58+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#website\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/\",\"name\":\"Un Universo invisible bajo nuestros pies\",\"description\":\"Los suelos y la vida\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"El Secuestro de carbono por los suelos del mundo. \u00daltimas estimaciones en 2014 - Un Universo invisible bajo nuestros pies","description":"Carbono de los suelos en forma org\u00e1nica e inorg\u00e1nicaN.H. Batjes EJSS, ISRIC Carbono de los suelos en forma org\u00e1nica e inorg\u00e1nica N.H. Batjes EJSS, ISRIC N.H. Batjes ha publicado recientemente en el European Journal of Soil Science el \u00faltimo inventario sobre el secuestro de carbono de los suelos del mundo, en el cual","canonical_url":"https:\/\/www.madrimasd.org\/blogs\/universo\/2015\/11\/09\/146304","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2015\/11\/09\/146304#blogposting","name":"El Secuestro de carbono por los suelos del mundo. \u00daltimas estimaciones en 2014 - Un Universo invisible bajo nuestros pies","headline":"El Secuestro de carbono por los suelos del mundo. \u00daltimas estimaciones en 2014","author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author"},"publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#organization"},"image":{"@type":"ImageObject","url":"http:\/\/www.madrimasd.org\/blogs\/universo\/wp-content\/blogs.dir\/42\/files\/397\/wise-nuevo.jpg","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2015\/11\/09\/146304\/#articleImage"},"datePublished":"2015-11-09T15:39:58+01:00","dateModified":"2015-11-09T15:39:58+01:00","inLanguage":"es-ES","commentCount":1,"mainEntityOfPage":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2015\/11\/09\/146304#webpage"},"isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2015\/11\/09\/146304#webpage"},"articleSection":"Biolog\u00eda y Ecolog\u00eda del Suelo, Biomasa y Necromasa en los Suelos: Ra\u00edces y Materia Org\u00e1nica, Componentes, Estructuras y Procesos en los Suelos, Edafolog\u00eda y Pol\u00edtica, Filosof\u00eda, Historia y Sociolog\u00eda de la Edafolog\u00eda, Geograf\u00eda de Suelos y Megaedafolog\u00eda, Suelos de Zonas \u00c1ridas, Semi\u00e1ridas y desertificaci\u00f3n, Suelos y Cambio Clim\u00e1tico, estimaciones globales, inorg\u00e1nico, inventarios de suelo, org\u00e1nico, Secustro de carbono, suelos"},{"@type":"BreadcrumbList","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2015\/11\/09\/146304#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo#listItem","position":1,"name":"Home","item":"https:\/\/www.madrimasd.org\/blogs\/universo","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/componentes-estructuras-y-procesos-en-los-suelos#listItem","name":"Componentes, Estructuras y Procesos en los Suelos"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/componentes-estructuras-y-procesos-en-los-suelos#listItem","position":2,"name":"Componentes, Estructuras y Procesos en los Suelos","item":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/componentes-estructuras-y-procesos-en-los-suelos","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2015\/11\/09\/146304#listItem","name":"El Secuestro de carbono por los suelos del mundo. \u00daltimas estimaciones en 2014"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2015\/11\/09\/146304#listItem","position":3,"name":"El Secuestro de carbono por los suelos del mundo. \u00daltimas estimaciones en 2014","previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/componentes-estructuras-y-procesos-en-los-suelos#listItem","name":"Componentes, Estructuras y Procesos en los Suelos"}}]},{"@type":"Organization","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#organization","name":"Un Universo invisible bajo nuestros pies","description":"Los suelos y la vida","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/","logo":{"@type":"ImageObject","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2015\/11\/09\/146304\/#organizationLogo","width":217,"height":72},"image":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2015\/11\/09\/146304\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/juan.j.marti.14"]},{"@type":"Person","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo","name":"Juan Jos\u00e9 Ib\u00e1\u00f1ez","image":{"@type":"ImageObject","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2015\/11\/09\/146304#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/387f3a100385573d8f42ce2a3211fd1c?s=96&d=mm&r=g","width":96,"height":96,"caption":"Juan Jos\u00e9 Ib\u00e1\u00f1ez"}},{"@type":"WebPage","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2015\/11\/09\/146304#webpage","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/2015\/11\/09\/146304","name":"El Secuestro de carbono por los suelos del mundo. \u00daltimas estimaciones en 2014 - Un Universo invisible bajo nuestros pies","description":"Carbono de los suelos en forma org\u00e1nica e inorg\u00e1nicaN.H. Batjes EJSS, ISRIC Carbono de los suelos en forma org\u00e1nica e inorg\u00e1nica N.H. Batjes EJSS, ISRIC N.H. Batjes ha publicado recientemente en el European Journal of Soil Science el \u00faltimo inventario sobre el secuestro de carbono de los suelos del mundo, en el cual","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#website"},"breadcrumb":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2015\/11\/09\/146304#breadcrumblist"},"author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author"},"creator":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author"},"datePublished":"2015-11-09T15:39:58+01:00","dateModified":"2015-11-09T15:39:58+01:00"},{"@type":"WebSite","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#website","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/","name":"Un Universo invisible bajo nuestros pies","description":"Los suelos y la vida","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Un Universo invisible bajo nuestros pies - Los suelos y la vida","og:type":"article","og:title":"El Secuestro de carbono por los suelos del mundo. \u00daltimas estimaciones en 2014 - Un Universo invisible bajo nuestros pies","og:description":"Carbono de los suelos en forma org\u00e1nica e inorg\u00e1nicaN.H. Batjes EJSS, ISRIC Carbono de los suelos en forma org\u00e1nica e inorg\u00e1nica N.H. Batjes EJSS, ISRIC N.H. Batjes ha publicado recientemente en el European Journal of Soil Science el \u00faltimo inventario sobre el secuestro de carbono de los suelos del mundo, en el cual","og:url":"https:\/\/www.madrimasd.org\/blogs\/universo\/2015\/11\/09\/146304","og:image":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png","og:image:secure_url":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png","article:published_time":"2015-11-09T14:39:58+00:00","article:modified_time":"2015-11-09T14:39:58+00:00","article:publisher":"https:\/\/www.facebook.com\/juan.j.marti.14","twitter:card":"summary","twitter:title":"El Secuestro de carbono por los suelos del mundo. \u00daltimas estimaciones en 2014 - Un Universo invisible bajo nuestros pies","twitter:description":"Carbono de los suelos en forma org\u00e1nica e inorg\u00e1nicaN.H. Batjes EJSS, ISRIC Carbono de los suelos en forma org\u00e1nica e inorg\u00e1nica N.H. Batjes EJSS, ISRIC N.H. Batjes ha publicado recientemente en el European Journal of Soil Science el \u00faltimo inventario sobre el secuestro de carbono de los suelos del mundo, en el cual","twitter:image":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png"},"aioseo_meta_data":{"post_id":"146304","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":null,"isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","tabs":null,"priority":null,"frequency":null,"local_seo":null,"created":"2022-06-03 17:10:42","updated":"2026-05-26 18:25:54","limit_modified_date":false,"ai":null,"breadcrumb_settings":null,"seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/componentes-estructuras-y-procesos-en-los-suelos\" title=\"Componentes, Estructuras y Procesos en los Suelos\">Componentes, Estructuras y Procesos en los Suelos<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tEl Secuestro de carbono por los suelos del mundo. \u00daltimas estimaciones en 2014\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.madrimasd.org\/blogs\/universo"},{"label":"Componentes, Estructuras y Procesos en los Suelos","link":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/componentes-estructuras-y-procesos-en-los-suelos"},{"label":"El Secuestro de carbono por los suelos del mundo. \u00daltimas estimaciones en 2014","link":"https:\/\/www.madrimasd.org\/blogs\/universo\/2015\/11\/09\/146304"}],"_links":{"self":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts\/146304"}],"collection":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/comments?post=146304"}],"version-history":[{"count":7,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts\/146304\/revisions"}],"predecessor-version":[{"id":147409,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts\/146304\/revisions\/147409"}],"wp:attachment":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/media?parent=146304"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/categories?post=146304"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/tags?post=146304"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}