{"id":146755,"date":"2016-02-29T14:30:03","date_gmt":"2016-02-29T13:30:03","guid":{"rendered":"http:\/\/www.madrimasd.org\/blogs\/universo\/?p=146755"},"modified":"2016-02-29T14:30:46","modified_gmt":"2016-02-29T13:30:46","slug":"eficiencia-energetica-y-la-propaganda-consumista","status":"publish","type":"post","link":"https:\/\/www.madrimasd.org\/blogs\/universo\/2016\/02\/29\/146755","title":{"rendered":"Eficiencia Energ\u00e9tica y Propaganda Consumista"},"content":{"rendered":"<p align=\"center\"><img decoding=\"async\" class=\"ngg-singlepic ngg-center\" style=\"width: 417px; height: 299px;\" src=\"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-content\/blogs.dir\/42\/files\/804\/e-waste.jpg\" alt=\"e-waste\" width=\"896\" height=\"537\" \/><\/p>\n<p align=\"center\"><span style=\"color: #0000ff;\">Residuos electr\u00f3nicos y eficiencia energ\u00e9tica. Fuente Colaje google im\u00e1genes<\/span><\/p>\n<p style=\"text-align: justify;\" align=\"center\"><span style=\"color: #3366ff;\"><strong>Hay noticias que deben analizarse con sumo cuidado, ya que esconden mensajes y marketing ocultos dignos de ser desenmascarados<\/strong><\/span><span style=\"color: #000000;\">. Este es el caso de unos estudios realizados recientemente y reproducidos en la prensa general con t\u00edtulos como el siguiente: \u201c<\/span><a href=\"http:\/\/www.madrimasd.org\/informacionidi\/noticias\/noticia.asp?id=63042&amp;origen=notiweb&amp;dia_suplemento=martes\"><span style=\"color: #0000ff;\">El efecto de los dispositivos tecnol\u00f3gicos obsoletos en el medio ambiente<\/span><\/a><span style=\"color: #000000;\">\u201d y que os reproduzco al final de esta entrega. El encabezado que da pie a este nos informa de que: \u201c(\u2026) <\/span><span style=\"color: #800000;\"><strong><em>en los \u00faltimos tiempos se adquieren m\u00e1s dispositivos pero no se desechan los anteriores, una situaci\u00f3n que aumenta del consumo energ\u00e9tico y, en consecuencia el impacto medioambiental <\/em><\/strong><\/span><span style=\"color: #000000;\"><span style=\"color: #800000;\">\u201d. <span style=\"color: #333333;\">Visto desde este punto de vista, el lector puede pensar que l\u00f3gicamente que se trata de un serio problema ambiental, as\u00ed como que el an\u00e1lisis es acertado. Ahora bien tambi\u00e9n podr\u00eda haberse parafraseado de la siguiente forma:<\/span> <span style=\"color: #333333;\">\u201c<\/span><\/span><\/span><strong><em><span style=\"color: #000000;\"><span style=\"color: #800000;\">Las multinacionales, en su af\u00e1n de vender nuevos electrodom\u00e9sticos y dispositivos electr\u00f3nicos\u201d, bombardean al ciudadano con propaganda que les impela a comprar m\u00e1s y m\u00e1s productos electr\u00f3nicos de \u00faltima generaci\u00f3n, excus\u00e1ndose en la menor eficiencia energ\u00e9tica de los antiguos<\/span><\/span><\/em><\/strong><span style=\"color: #333333;\"><em><\/em>\u201d<\/span><span style=\"color: #000000;\">. <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">En mi casa tengo un congelador \u201c<\/span><em><span style=\"color: #000000;\">made in Spain<\/span><\/em><span style=\"color: #000000;\">\u201d que me regalaron hace unos 25 a\u00f1os, y que por lo \u00a1que me comentaron los amigos que lo ofrecieron! debe alcanzar la vetusta edad de \u00a135!. Puedo asegurar que, a lo largo de tres decenios, es uno de los pocos artefactos que habitan en mi casa que no ha sufrido ninguna aver\u00eda. Y yo me pregunto, y os pregunto: \u00bfCu\u00e1ntos aparatos de esta guisa que se comercializan en la actualidad poseen tal ciclo de vida?. Ya os hemos hablado de la \u201c<\/span><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/01\/17\/138034\"><span style=\"color: #0000ff;\">obsolescencia programada<\/span><\/a><span style=\"color: #000000;\">\u201d, <\/span><span style=\"color: #3366ff;\"><strong>onerosa para el consumidor pero muy lucrativa para las empresas<\/strong>. \u00a0<span style=\"color: #000000;\">Pero<\/span> <strong>tal obsolescencia genera una gran cantidad de residuos con componentes t\u00f3xicos<\/strong><\/span><span style=\"color: #000000;\">, como ya explicamos en nuestro post <\/span><a title=\"Enlace permanente: e-Basura, Internet, Esclavitud Infantil, Salud P\u00fablica y Cambio Clim\u00e1tico\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/06\/14\/140714\">e-Basura, Internet, Esclavitud Infantil, Salud P\u00fablica y Cambio Clim\u00e1tico<\/a><span style=\"color: #000000;\">. Dicho de otro modo, si seguimos las directrices que nos recomiendan, aumentaremos enormemente la inmensa cantidad de basura electr\u00f3nica que termina durmiendo en los vertederos de los pa\u00edses menos favorecidos, lugares en los que los ni\u00f1os desnutridos se contaminan intentando salvar alg\u00fan componente reciclable que posiblemente sea t\u00f3xico, afectando seriamente a su salud, tras interminables y diarias b\u00fasquedas. <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #3366ff;\"><strong>Obviamente los pa\u00edses que exportan estos desechos ilegalmente, mejorar\u00e1n sus estad\u00edsticas en materia de eficiencia energ\u00e9tica, pero a costa de criaturas inocentes<\/strong><\/span><span style=\"color: #000000;\">.<\/span><span style=\"color: #000000;\">\u00a0 <\/span><span style=\"color: #000000;\">\u00bfEs eso lo que nos venden? \u00a1Pues va a ser que s\u00ed!, como veremos a continuaci\u00f3n.\u00a0<\/span><span style=\"color: #000000;\">\u00a0<\/span><span style=\"color: #000000;\">\u00a0<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">M\u00e1s adelante, y haci\u00e9ndose eco de otro estudio, la mentada noticia recalca que \u201c<\/span><em><span style=\"color: #000000;\">en los quince a\u00f1os transcurridos de 1992 a 2007 el uso de receptores de televisi\u00f3n y ordenadores de sobremesa aument\u00f3 en un 20% y un 100%, respectivamente, por lo que <\/span><span style=\"color: #800000;\"><strong>adem\u00e1s de la acumulaci\u00f3n de dispositivos, hay que tener en cuenta la mayor asiduidad con la que estos se emplean<\/strong><\/span><\/em><span style=\"color: #000000;\">\u201d. Es decir a mayor oferta, mayor demanda, lo cual nos viene a recordar que los ciudadanos viven en una sociedad en la que se intenta que cada individuo, desde su m\u00e1s tierna infancia, no pueda vivir si no est\u00e1 rodeado de aparatitos. <\/span><strong><span style=\"color: #000000;\"><span style=\"color: #3366ff;\">Son muchos los estudios m\u00e9dicos que nos alertan que tal modo de proceder se encuentra da\u00f1ando la salud f\u00edsica y ps\u00edquica infantil<\/span><\/span><\/strong><span style=\"color: #000000;\">. Hacemos necesidad de una instrumentaci\u00f3n que debiera utilizarse racionalmente, no de forma masiva e ininterrumpida. <strong><span style=\"color: #800000;\">\u00bfImporta tal tema a las empresas?. \u00a1Obviamente no!: gozan, disfrutan y se frotan las manos<\/span><\/strong>.\u00a0<\/span><span style=\"color: #000000;\">\u00a0<\/span><span style=\"color: #000000;\">\u00a0<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #3366ff;\"><strong>Pero vayamos al meollo de la mentira<\/strong><\/span><span style=\"color: #000000;\"><span style=\"color: #800000;\">, <span style=\"color: #333333;\"><span style=\"color: #000000;\">para finalizar la nota de prensa lanza estas sabrosas frases<\/span>:<\/span> \u201c<\/span><\/span><strong><em><span style=\"color: #000000;\"><span style=\"color: #800000;\">No obstante, hay margen para la esperanza a trav\u00e9s de una serie de estrategias de intervenci\u00f3n prospectivas (\u2026) que asegura que el impacto medioambiental puede reducirse mediante estrategias como (\u2026.) pero s\u00f3lo si (\u2026) las tendencias de consumo se desplazan hacia un n\u00famero menor de productos con un grado elevado de polivalencia (\u2026.) Los nuevos dispositivos multifunci\u00f3n, como las tabletas y los port\u00e1tiles (\u2026.) pueden ser las \u00abespecies invasivas\u00bb que destruyan los ecosistemas de dispositivos actuales, una circunstancia que puede ser positiva en la situaci\u00f3n actual<\/span><\/span><\/em><\/strong><span style=\"color: #000000;\">\u00ab. Mucho cuidado con este <span style=\"color: #3366ff;\">\u00bf<\/span><\/span><span style=\"color: #3366ff;\"><strong>inocente argumento<\/strong><\/span><span style=\"color: #000000;\"><span style=\"color: #3366ff;\">\u201d?.<\/span> <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Como cada a\u00f1o las multinacionales lanzan nuevas generaciones de dispositivos de esta guisa, que dicen ser mejores, m\u00e1s veloces y\u00a0eficientes energ\u00e9ticamente, en aras de la moda, muchos ciudadanos los adquieren tirando los antiguos, es decir generando m\u00e1s y m\u00e1s basura electr\u00f3nica y las nefastas consecuencias que tal proceso acarrea. Empero al margen los materiales destinados a fabricar los nuevos \u201caparatitos\u201d <\/span><span style=\"color: #3366ff;\"><strong>su producci\u00f3n conllevan un fuerte gasto de energ\u00eda <\/strong><strong>y recursos no renovables<\/strong><\/span><strong><span style=\"color: #000000;\"><span style=\"color: #3366ff;\">.<\/span> <\/span><\/strong><span style=\"color: #000000;\">\u00a0<\/span><span style=\"color: #000000;\">Ser\u00eda algo as\u00ed como comprarme un nuevo congelador cada a\u00f1o, tirar el viejo, y decir que de este modo se ahorra energ\u00eda. \u00a1Falso! \u00a1Mentira, se mire por donde se mire!. <\/span><strong><span style=\"color: #000000;\"><span style=\"color: #3366ff;\">Si hace decenios todos los electrodom\u00e9sticos duraban muchos a\u00f1os, \u00bfpor qu\u00e9 cada a\u00f1o su fecha de caducidad\u00a0 real resulta ser much\u00edsimo menor?.<\/span> <span style=\"color: #3366ff;\">Simplemente porque a m\u00e1s ventas m\u00e1s ganancias<\/span><\/span><\/strong><span style=\"color: #000000;\">.\u00a0<\/span><span style=\"color: #000000;\">\u00a0<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #3366ff;\"><strong>Esta es la propaganda empresarial que defienden algunos de nuestros expertos en aras de preservar el medio ambiente y el ahorro de energ\u00eda<\/strong><\/span><span style=\"color: #000000;\">. \u00bfCu\u00e1ntos artilugios actuales tienen la duraci\u00f3n de los que se hac\u00edan hace 30 o 40 o 50 a\u00f1os?. Antes de dormir, ya en la cama, me pongo los auriculares de una peque\u00f1a radio en la que escucho m\u00fasica para relajarme y conciliar mejor el sue\u00f1o. <\/span><span style=\"color: #000000;\">\u00a0<\/span><span style=\"color: #000000;\">\u00bfSaben cu\u00e1ntos a\u00f1os tiene? Aproximadamente \u00a120!. \u00bfQu\u00e9 ciclo de vida tienen los aparatitos actuales antes de que se estropeen o nos inciten a cambiarlos?.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #800000;\"><strong><em>Como corolario, la nota de prensa nos viene a proponer que para mejorar el medio ambiente y la eficiencia energ\u00e9tica, destruyamos el medio ambiente y despilfarremos energ\u00eda y especialmente dinero \u00a1en tiempos de crisis!.<\/em><\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Las grandes mentiras del capitalismo neoliberal, que nos intentan estafar una vez s\u00ed y otra tambi\u00e9n.\u00a0<\/span><span style=\"color: #000000;\">All\u00e1 cada cual con su conciencia. <\/span><\/p>\n<p style=\"text-align: justify;\"><em><span style=\"color: #800000;\">Os dejo pues con esta nota de\u00a0 prensa que esconde sibilinamente propaganda falsa y verdemente consumista&#8230;&#8230;&#8230;<\/span><\/em><\/p>\n<p><span style=\"color: #008000;\"><strong>Juan Jos\u00e9 Ib\u00e1\u00f1ez<\/strong><\/span><span style=\"color: #000000;\">\u00a0<\/span><\/p>\n<p><span style=\"color: #000000;\"><!--more--><\/span><\/p>\n<p><strong><a href=\"http:\/\/www.madrimasd.org\/informacionidi\/noticias\/noticia.asp?id=63042&amp;origen=notiweb&amp;dia_suplemento=martes\"><span style=\"color: #0000ff;\">El efecto de los dispositivos tecnol\u00f3gicos obsoletos en el medio ambiente<\/span><\/a><\/strong><\/p>\n<p><strong>En un estudio nuevo se informa de que en los \u00faltimos tiempos se adquieren m\u00e1s dispositivos pero no se desechan los anteriores, una situaci\u00f3n que aumenta del consumo energ\u00e9tico y, en consecuencia el impacto medioambiental. <\/strong><\/p>\n<p>FUENTE | <a href=\"http:\/\/cordis.europa.eu\/home_es.html\" target=\"_blank\">CORDIS: Servicio de Informaci\u00f3n en I+D Comunitario<\/a> 03\/03\/2015<\/p>\n<p style=\"text-align: justify;\">\u00a0<strong>Cabr\u00eda pensar que para aumentar la eficiencia en el uso de los recursos se deber\u00edan utilizar los electrodom\u00e9sticos hasta que dejen de funcionar<\/strong>, <strong>pero<\/strong> lo cierto es que, seg\u00fan un estudio nuevo, <strong>el uso de tecnolog\u00eda anticuada podr\u00eda resultar perjudicial para el medio ambiente, pues los modelos antiguos consumen a menudo m\u00e1s energ\u00eda que los nuevos para ejecutar las mismas funciones<\/strong>.<\/p>\n<p>En <a title=\"Science\" href=\"http:\/\/news.sciencemag.org\/environment\/2015\/02\/why-you-should-throw-out-your-old-tv\" target=\"_blank\">Science<\/a> informan mediante un art\u00edculo que en <strong>el estudio se registraron los costes medioambientales de distintos dispositivos a lo largo de su vida, desde la extracci\u00f3n de materias primas hasta que se dejan de utilizar<\/strong>. La investigaci\u00f3n, realizada por un equipo del <a title=\"Instituto Tecnol\u00f3gico de Rochester\" href=\"http:\/\/www.rit.edu\/\" target=\"_blank\">Instituto Tecnol\u00f3gico de Rochester<\/a> (Nueva York), <strong>ofrece informaci\u00f3n sobre la evoluci\u00f3n del consumo energ\u00e9tico dom\u00e9stico desde principios de los a\u00f1os noventa<\/strong>.<\/p>\n<p><strong>El equipo cient\u00edfico cre\u00f3 un m\u00e9todo con el que medir el impacto medioambiental neto de una &#8216;comunidad&#8217; de productos interrelacionados compuesta por electrodom\u00e9sticos fabricados, adquiridos y utilizados entre 1992 y 2007<\/strong>. Se calcul\u00f3 as\u00ed las primeras fases de la vida de productos antiguos -como ordenadores de sobremesa- y nuevos -como tabletas o televisores de plasma- mediante la base de datos Economic Input-Output Life Cycle Assessment. A continuaci\u00f3n se investigaron informes de consumo y encuestas hist\u00f3ricas donde se describen la propiedad y el empleo.<\/p>\n<p><strong>Se descubri\u00f3 que, a pesar de las mejoras en cuanto a eficiencia logradas desde 1992 hasta 2007 en dispositivos aislados, el impacto neto de la comunidad de productos al completo aument\u00f3 debido en mayor medida a que se poseen m\u00e1s dispositivos y a que se utilizan con m\u00e1s profusi\u00f3n<\/strong>. En el <span style=\"color: #000000;\">resumen del art\u00edculo se lee lo siguiente: \u00abEl impacto energ\u00e9tico neto de la comunidad de productos es notable, cerca del 30% del consumo medio de gasolina en un veh\u00edculo de pasajeros estadounidense en 2007. En el an\u00e1lisis se se\u00f1ala que una buena proporci\u00f3n de este consumo se puede atribuir a productos anticuados (televisores de tubo de rayos cat\u00f3dicos y ordenadores de sobremesa) debido a su tradicional consumo elevado, si bien su impacto se est\u00e1 desplazando hacia dispositivos m\u00f3viles de menor tama\u00f1o\u00bb.<br \/>\n<\/span><br \/>\n<strong>Uno de los problemas que se\u00f1alan en <em>Science<\/em> consiste en que se adquieren nuevos dispositivos pero no se desechan los antiguos<\/strong>. Por ejemplo, la media de dispositivos electr\u00f3nicos aument\u00f3 de cuatro por hogar en 1992 a trece en 2007, en gran medida por la presencia de dispositivos electr\u00f3nicos obsoletos. En el estudio tambi\u00e9n se afirma que la gente pasa m\u00e1s tiempo frente a estos dispositivos, un cambio de conducta que ampl\u00eda las menos de setecientas horas de uso al a\u00f1o que se produc\u00edan en 1992 hasta las m\u00e1s de mil cuatrocientas horas de 2007.<\/p>\n<p>En Grist tambi\u00e9n <strong>se hacen eco del estudio, publicado en<\/strong> <a title=\"Environmental Science and Technology\" href=\"http:\/\/pubs.acs.org\/doi\/abs\/10.1021\/es505121p\" target=\"_blank\">Environmental Science and Technology<\/a>, y se\u00f1alan que <strong>en los quince a\u00f1os transcurridos de 1992 a 2007 el uso de receptores de televisi\u00f3n y ordenadores de sobremesa aument\u00f3 en un 20% y un 100%, respectivamente, por lo que adem\u00e1s de la acumulaci\u00f3n de dispositivos, hay que tener en cuenta la mayor asiduidad con la que estos se emplean<\/strong>.<\/p>\n<p>No obstante, hay margen para la esperanza a trav\u00e9s de una serie de estrategias de intervenci\u00f3n prospectivas evaluadas por el equipo investigador, que asegura que <strong>el impacto medioambiental puede reducirse mediante estrategias como la extensi\u00f3n de la vida o la eficiencia energ\u00e9tica, pero s\u00f3lo si se aplican a todos los productos pose\u00eddos o bien si las tendencias de consumo se desplazan hacia un n\u00famero menor de productos con un grado elevado de polivalencia<\/strong>. Seg\u00fan se informa en Grist: \u00abLos <strong>nuevos dispositivos multifunci\u00f3n<\/strong>, <strong>como las tabletas y los port\u00e1tiles que tambi\u00e9n ejercen como televisiones y reproductores de m\u00fasica, pueden ser las \u00abespecies invasivas\u00bb que destruyan los ecosistemas de dispositivos actuales, una circunstancia que puede ser positiva en la situaci\u00f3n actual<\/strong>\u00ab.<\/p>\n<h3>Im\u00e1genes Relacionadas:<\/h3>","protected":false},"excerpt":{"rendered":"<p>Residuos electr\u00f3nicos y eficiencia energ\u00e9tica. Fuente Colaje google im\u00e1genes Hay noticias que deben analizarse con sumo cuidado, ya que esconden mensajes y marketing ocultos dignos de ser desenmascarados. Este es el caso de unos estudios realizados recientemente y reproducidos en la prensa general con t\u00edtulos como el siguiente: \u201cEl efecto de los dispositivos tecnol\u00f3gicos obsoletos en el medio ambiente\u201d y que os reproduzco al final de esta entrega. El encabezado que da pie a este nos informa de que: \u201c(\u2026) en los \u00faltimos tiempos se adquieren m\u00e1s dispositivos pero no se desechan los anteriores, una situaci\u00f3n que aumenta del consumo\u2026<\/p>\n","protected":false},"author":26,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0},"categories":[594,605,592,606],"tags":[47709,47163,47058,46603],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":4}},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Residuos electr\u00f3nicos y eficiencia energ\u00e9tica. Fuente Colaje google im\u00e1genes Hay noticias que deben analizarse con sumo cuidado, ya que esconden mensajes y marketing ocultos dignos de ser desenmascarados. Este es el caso de unos estudios realizados recientemente y reproducidos en la prensa general con t\u00edtulos como el siguiente: \u201cEl efecto de los dispositivos tecnol\u00f3gicos obsoletos\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Juan Jos\u00e9 Ib\u00e1\u00f1ez\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2016\/02\/29\/146755\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Un Universo invisible bajo nuestros pies - Los suelos y la vida\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Eficiencia Energ\u00e9tica y Propaganda Consumista - Un Universo invisible bajo nuestros pies\" \/>\n\t\t<meta property=\"og:description\" content=\"Residuos electr\u00f3nicos y eficiencia energ\u00e9tica. Fuente Colaje google im\u00e1genes Hay noticias que deben analizarse con sumo cuidado, ya que esconden mensajes y marketing ocultos dignos de ser desenmascarados. Este es el caso de unos estudios realizados recientemente y reproducidos en la prensa general con t\u00edtulos como el siguiente: \u201cEl efecto de los dispositivos tecnol\u00f3gicos obsoletos\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2016\/02\/29\/146755\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2016-02-29T13:30:03+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2016-02-29T13:30:46+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/juan.j.marti.14\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Eficiencia Energ\u00e9tica y Propaganda Consumista - Un Universo invisible bajo nuestros pies\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Residuos electr\u00f3nicos y eficiencia energ\u00e9tica. Fuente Colaje google im\u00e1genes Hay noticias que deben analizarse con sumo cuidado, ya que esconden mensajes y marketing ocultos dignos de ser desenmascarados. Este es el caso de unos estudios realizados recientemente y reproducidos en la prensa general con t\u00edtulos como el siguiente: \u201cEl efecto de los dispositivos tecnol\u00f3gicos obsoletos\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2016\\\/02\\\/29\\\/146755#blogposting\",\"name\":\"Eficiencia Energ\\u00e9tica y Propaganda Consumista - Un Universo invisible bajo nuestros pies\",\"headline\":\"Eficiencia Energ\\u00e9tica y Propaganda Consumista\",\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"http:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/wp-content\\\/blogs.dir\\\/42\\\/files\\\/804\\\/e-waste.jpg\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2016\\\/02\\\/29\\\/146755\\\/#articleImage\"},\"datePublished\":\"2016-02-29T14:30:03+01:00\",\"dateModified\":\"2016-02-29T14:30:46+01:00\",\"inLanguage\":\"es-ES\",\"commentCount\":29,\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2016\\\/02\\\/29\\\/146755#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2016\\\/02\\\/29\\\/146755#webpage\"},\"articleSection\":\"Degradaci\\u00f3n de Suelos: Contaminaci\\u00f3n, Fraude y Mala Praxis Cient\\u00edfica, Los Suelos y la Salud, Prensa y Pol\\u00edtica Cient\\u00edfica, basura electr\\u00f3nica, e-basura, eficiencia energ\\u00e9tica, fraude\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2016\\\/02\\\/29\\\/146755#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/los-suelos-y-la-salud#listItem\",\"name\":\"Los Suelos y la Salud\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/los-suelos-y-la-salud#listItem\",\"position\":2,\"name\":\"Los Suelos y la Salud\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/los-suelos-y-la-salud\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2016\\\/02\\\/29\\\/146755#listItem\",\"name\":\"Eficiencia Energ\\u00e9tica y Propaganda Consumista\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2016\\\/02\\\/29\\\/146755#listItem\",\"position\":3,\"name\":\"Eficiencia Energ\\u00e9tica y Propaganda Consumista\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/los-suelos-y-la-salud#listItem\",\"name\":\"Los Suelos y la Salud\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#organization\",\"name\":\"Un Universo invisible bajo nuestros pies\",\"description\":\"Los suelos y la vida\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/files\\\/2022\\\/02\\\/logo.png\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2016\\\/02\\\/29\\\/146755\\\/#organizationLogo\",\"width\":217,\"height\":72},\"image\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2016\\\/02\\\/29\\\/146755\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/juan.j.marti.14\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo\",\"name\":\"Juan Jos\\u00e9 Ib\\u00e1\\u00f1ez\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2016\\\/02\\\/29\\\/146755#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/387f3a100385573d8f42ce2a3211fd1c?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Juan Jos\\u00e9 Ib\\u00e1\\u00f1ez\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2016\\\/02\\\/29\\\/146755#webpage\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2016\\\/02\\\/29\\\/146755\",\"name\":\"Eficiencia Energ\\u00e9tica y Propaganda Consumista - Un Universo invisible bajo nuestros pies\",\"description\":\"Residuos electr\\u00f3nicos y eficiencia energ\\u00e9tica. Fuente Colaje google im\\u00e1genes Hay noticias que deben analizarse con sumo cuidado, ya que esconden mensajes y marketing ocultos dignos de ser desenmascarados. Este es el caso de unos estudios realizados recientemente y reproducidos en la prensa general con t\\u00edtulos como el siguiente: \\u201cEl efecto de los dispositivos tecnol\\u00f3gicos obsoletos\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2016\\\/02\\\/29\\\/146755#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\"},\"datePublished\":\"2016-02-29T14:30:03+01:00\",\"dateModified\":\"2016-02-29T14:30:46+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#website\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/\",\"name\":\"Un Universo invisible bajo nuestros pies\",\"description\":\"Los suelos y la vida\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Eficiencia Energ\u00e9tica y Propaganda Consumista - Un Universo invisible bajo nuestros pies","description":"Residuos electr\u00f3nicos y eficiencia energ\u00e9tica. Fuente Colaje google im\u00e1genes Hay noticias que deben analizarse con sumo cuidado, ya que esconden mensajes y marketing ocultos dignos de ser desenmascarados. Este es el caso de unos estudios realizados recientemente y reproducidos en la prensa general con t\u00edtulos como el siguiente: \u201cEl efecto de los dispositivos tecnol\u00f3gicos obsoletos","canonical_url":"https:\/\/www.madrimasd.org\/blogs\/universo\/2016\/02\/29\/146755","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2016\/02\/29\/146755#blogposting","name":"Eficiencia Energ\u00e9tica y Propaganda Consumista - Un Universo invisible bajo nuestros pies","headline":"Eficiencia Energ\u00e9tica y Propaganda Consumista","author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author"},"publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#organization"},"image":{"@type":"ImageObject","url":"http:\/\/www.madrimasd.org\/blogs\/universo\/wp-content\/blogs.dir\/42\/files\/804\/e-waste.jpg","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2016\/02\/29\/146755\/#articleImage"},"datePublished":"2016-02-29T14:30:03+01:00","dateModified":"2016-02-29T14:30:46+01:00","inLanguage":"es-ES","commentCount":29,"mainEntityOfPage":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2016\/02\/29\/146755#webpage"},"isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2016\/02\/29\/146755#webpage"},"articleSection":"Degradaci\u00f3n de Suelos: Contaminaci\u00f3n, Fraude y Mala Praxis Cient\u00edfica, Los Suelos y la Salud, Prensa y Pol\u00edtica Cient\u00edfica, basura electr\u00f3nica, e-basura, eficiencia energ\u00e9tica, fraude"},{"@type":"BreadcrumbList","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2016\/02\/29\/146755#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo#listItem","position":1,"name":"Home","item":"https:\/\/www.madrimasd.org\/blogs\/universo","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/los-suelos-y-la-salud#listItem","name":"Los Suelos y la Salud"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/los-suelos-y-la-salud#listItem","position":2,"name":"Los Suelos y la Salud","item":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/los-suelos-y-la-salud","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2016\/02\/29\/146755#listItem","name":"Eficiencia Energ\u00e9tica y Propaganda Consumista"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2016\/02\/29\/146755#listItem","position":3,"name":"Eficiencia Energ\u00e9tica y Propaganda Consumista","previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/los-suelos-y-la-salud#listItem","name":"Los Suelos y la Salud"}}]},{"@type":"Organization","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#organization","name":"Un Universo invisible bajo nuestros pies","description":"Los suelos y la vida","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/","logo":{"@type":"ImageObject","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2016\/02\/29\/146755\/#organizationLogo","width":217,"height":72},"image":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2016\/02\/29\/146755\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/juan.j.marti.14"]},{"@type":"Person","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo","name":"Juan Jos\u00e9 Ib\u00e1\u00f1ez","image":{"@type":"ImageObject","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2016\/02\/29\/146755#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/387f3a100385573d8f42ce2a3211fd1c?s=96&d=mm&r=g","width":96,"height":96,"caption":"Juan Jos\u00e9 Ib\u00e1\u00f1ez"}},{"@type":"WebPage","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2016\/02\/29\/146755#webpage","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/2016\/02\/29\/146755","name":"Eficiencia Energ\u00e9tica y Propaganda Consumista - Un Universo invisible bajo nuestros pies","description":"Residuos electr\u00f3nicos y eficiencia energ\u00e9tica. Fuente Colaje google im\u00e1genes Hay noticias que deben analizarse con sumo cuidado, ya que esconden mensajes y marketing ocultos dignos de ser desenmascarados. Este es el caso de unos estudios realizados recientemente y reproducidos en la prensa general con t\u00edtulos como el siguiente: \u201cEl efecto de los dispositivos tecnol\u00f3gicos obsoletos","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#website"},"breadcrumb":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2016\/02\/29\/146755#breadcrumblist"},"author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author"},"creator":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author"},"datePublished":"2016-02-29T14:30:03+01:00","dateModified":"2016-02-29T14:30:46+01:00"},{"@type":"WebSite","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#website","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/","name":"Un Universo invisible bajo nuestros pies","description":"Los suelos y la vida","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Un Universo invisible bajo nuestros pies - Los suelos y la vida","og:type":"article","og:title":"Eficiencia Energ\u00e9tica y Propaganda Consumista - Un Universo invisible bajo nuestros pies","og:description":"Residuos electr\u00f3nicos y eficiencia energ\u00e9tica. Fuente Colaje google im\u00e1genes Hay noticias que deben analizarse con sumo cuidado, ya que esconden mensajes y marketing ocultos dignos de ser desenmascarados. Este es el caso de unos estudios realizados recientemente y reproducidos en la prensa general con t\u00edtulos como el siguiente: \u201cEl efecto de los dispositivos tecnol\u00f3gicos obsoletos","og:url":"https:\/\/www.madrimasd.org\/blogs\/universo\/2016\/02\/29\/146755","og:image":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png","og:image:secure_url":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png","article:published_time":"2016-02-29T13:30:03+00:00","article:modified_time":"2016-02-29T13:30:46+00:00","article:publisher":"https:\/\/www.facebook.com\/juan.j.marti.14","twitter:card":"summary","twitter:title":"Eficiencia Energ\u00e9tica y Propaganda Consumista - Un Universo invisible bajo nuestros pies","twitter:description":"Residuos electr\u00f3nicos y eficiencia energ\u00e9tica. Fuente Colaje google im\u00e1genes Hay noticias que deben analizarse con sumo cuidado, ya que esconden mensajes y marketing ocultos dignos de ser desenmascarados. Este es el caso de unos estudios realizados recientemente y reproducidos en la prensa general con t\u00edtulos como el siguiente: \u201cEl efecto de los dispositivos tecnol\u00f3gicos obsoletos","twitter:image":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png"},"aioseo_meta_data":{"post_id":"146755","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":null,"isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","tabs":null,"priority":null,"frequency":null,"local_seo":null,"created":"2022-06-03 17:13:45","updated":"2026-05-26 18:29:55","limit_modified_date":false,"ai":null,"breadcrumb_settings":null,"seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/los-suelos-y-la-salud\" title=\"Los Suelos y la Salud\">Los Suelos y la Salud<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tEficiencia Energ\u00e9tica y Propaganda Consumista\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.madrimasd.org\/blogs\/universo"},{"label":"Los Suelos y la Salud","link":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/los-suelos-y-la-salud"},{"label":"Eficiencia Energ\u00e9tica y Propaganda Consumista","link":"https:\/\/www.madrimasd.org\/blogs\/universo\/2016\/02\/29\/146755"}],"_links":{"self":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts\/146755"}],"collection":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/comments?post=146755"}],"version-history":[{"count":5,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts\/146755\/revisions"}],"predecessor-version":[{"id":147890,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts\/146755\/revisions\/147890"}],"wp:attachment":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/media?parent=146755"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/categories?post=146755"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/tags?post=146755"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}