{"id":146872,"date":"2016-03-04T15:14:08","date_gmt":"2016-03-04T14:14:08","guid":{"rendered":"http:\/\/www.madrimasd.org\/blogs\/universo\/?p=146872"},"modified":"2016-03-04T15:14:08","modified_gmt":"2016-03-04T14:14:08","slug":"gaia-yo-medea-sobre-la-vida-en-las-profundidades-de-la-tierra","status":"publish","type":"post","link":"https:\/\/www.madrimasd.org\/blogs\/universo\/2016\/03\/04\/146872","title":{"rendered":"\u00bfGaia y\/o Medea? (Sobre La Vida en las Profundidades de la Tierra)"},"content":{"rendered":"<p align=\"center\"><img decoding=\"async\" class=\"ngg-singlepic ngg-center\" src=\"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-content\/blogs.dir\/42\/files\/159\/medea-o-gaia.jpg\" alt=\"medea-o-gaia\" \/><\/p>\n<p align=\"center\"><a href=\"https:\/\/isiria.wordpress.com\/2009\/06\/21\/gaia-or-medea-is-earth-driven-by-maintaining-life-or-fostering-self-destruction\/\"><span style=\"color: #0000ff;\">\u00bfGaia o Medea?: Fuente: Melange<\/span><\/a><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">\u00a0<\/span><span style=\"color: #3366ff;\"><strong>En este planeta azul, los hombres han detectado vida all\u00e1 donde la han estudiado<\/strong><\/span><span style=\"color: #000000;\">. Ya lo comentamos en algunos post anteriores, por lo que la noticia que os ofrecemos hoy, al final del post, no aporta mucho en este sentido. Sin embargo, tal hecho no deja de sorprenderme. Si realmente pudi\u00e9ramos ser entes inteligentes incorp\u00f3reos y procedentes de otros mundos, nos dar\u00edamos cuenta que <\/span><span style=\"color: #3366ff;\"><strong>en un planeta rocoso la aparici\u00f3n de la vida, podr\u00eda interpretarse como el surgimiento de unos objetos que lo trastocan todo<\/strong><\/span><span style=\"color: #000000;\">, corroyendo los materiales abi\u00f3ticos <span style=\"color: #3366ff;\">(<\/span><\/span><span style=\"color: #3366ff;\"><strong>litosfera<\/strong><\/span><span style=\"color: #000000;\"><span style=\"color: #3366ff;\">), <span style=\"color: #000000;\">cambiando la composici\u00f3n de sus fluidos<\/span> (<\/span><\/span><strong><span style=\"color: #000000;\"><span style=\"color: #3366ff;\">hidrosfera y atm\u00f3sfera<\/span><\/span><\/strong><span style=\"color: #000000;\">), y penetrando en sus entra\u00f1as o profundidades hasta poder incluso <\/span><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/07\/08\/140733\"><span style=\"color: #0000ff;\">alterar su tect\u00f3nica de placas<\/span><\/a><span style=\"color: #000000;\">, en caso de existir, como ocurre en la Tierra. <\/span><span style=\"color: #3366ff;\"><strong>Desde tal perspectiva, la vida se propaga como un c\u00e1ncer corrosivo. Sin embargo todo depende del cristal con que se mire<\/strong><\/span><span style=\"color: #000000;\">.\u00a0<\/span><span style=\"color: #000000;\">\u00a0<\/span><span style=\"color: #000000;\">\u00a0<\/span><span style=\"color: #000000;\">\u00a0<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">La <\/span><a href=\"http:\/\/es.wikipedia.org\/wiki\/Hip\u00f3tesis_de_Gaia\"><span style=\"color: #0000ff;\">Hip\u00f3tesis Gaia<\/span><\/a><span style=\"color: #000000;\">\u00a0<\/span><span style=\"color: #000000;\">o <\/span><a href=\"http:\/\/es.wikipedia.org\/wiki\/Gea\"><span style=\"color: #0000ff;\">Gea<\/span><\/a><span style=\"color: #000000;\"><strong><span style=\"color: #3366ff;\"> defiende que<\/span> <\/strong>la biosfera resulta ser un sistema \u00fanico, en el que la vida mantiene y fomenta las din\u00e1micas\u00a0biogeosf\u00e9ricas que la ayudan a sobrevivir, mediante procesos que inducen a que este planeta azul sea habitable para vida. Gaia y Gea se encuentran en varios aspectos relacionados con <\/span><a href=\"http:\/\/es.wikipedia.org\/wiki\/Pachamama\"><span style=\"color: #0000ff;\">Pachamama<\/span><\/a><span style=\"color: #000000;\">, la \u201c<strong><span style=\"color: #3366ff;\">Madre Tierra<\/span><\/strong>\u201d de las culturas precolombinas, entre otras muchas. Sin embargo, <\/span><span style=\"color: #800000;\"><strong>en contraposici\u00f3n a esta visi\u00f3n bondadosa de la biosfera se enfrenta la denominada <\/strong><\/span><a href=\"http:\/\/leomonfor.blogspot.com.es\/2014\/10\/la-hipotesis-medea-y-el-cambio-climatico.html\"><span style=\"color: #0000ff;\">Hip\u00f3tesis de Medea<\/span><\/a><span style=\"color: #000000;\">. Si la primera, como m\u00ednimo, observa la botella medio llena, la segunda apunta a percibirla como medio vac\u00eda. Describamos brevemente pues que propone la conjetura de Medea, ya que tanto esta como Gaia, no alcanzan el estatus de hip\u00f3tesis, si nos atenemos a los c\u00e1nones de la filosof\u00eda de la ciencia. <span style=\"color: #3366ff;\">Si el nombre que se asocia con la hip\u00f3tesis Gaia es el de James Lovelock, el que se vincula con la hip\u00f3tesis Medea es el de Peter Ward<\/span>, profesor en la Universidad de Washington.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">En el <\/span><a href=\"http:\/\/leomonfor.blogspot.com.es\/2014\/10\/la-hipotesis-medea-y-el-cambio-climatico.html\"><span style=\"color: #0000ff;\">blog Ciencia, Tecnolog\u00eda, poder y Cambio clim\u00e1tico<\/span><\/a><span style=\"color: #000000;\"> puede leerse: \u201c<\/span><em><span style=\"color: #000000;\">Peter Ward, profesor en la Universidad de Washington, Ward present\u00f3 en el a\u00f1o 2009 el libro <\/span><a href=\"http:\/\/en.wikipedia.org\/wiki\/Medea_hypothesis\"><span style=\"color: #0000ff;\">The Medea Hypothesis: Is Life on Earth Ultimately Self-Destructive?<\/span><\/a><span style=\"color: #000000;\"> , la conjetura que actualmente se conoce como <\/span><a href=\"http:\/\/leomonfor.blogspot.com.es\/2014\/10\/la-hipotesis-medea-y-el-cambio-climatico.html\"><span style=\"color: #0000ff;\">Hip\u00f3tesis de Medea<\/span><\/a><span style=\"color: #000000;\"> defendiendo que <\/span><span style=\"color: #000000;\">\u00a0<\/span><span style=\"color: #000000;\">la vida en la <\/span><strong><span style=\"color: #000000;\"><span style=\"color: #3366ff;\">Tierra <span style=\"color: #800000;\">se encuentra en un fr\u00e1gil balance en el que los seres vivos que la habitan tienden m\u00e1s bien a estropear las cosas que ha mantener ese equilibro<\/span><\/span><\/span><\/strong><span style=\"color: #000000;\">. El <\/span><strong><span style=\"color: #000000;\"><span style=\"color: #3366ff;\">simbolismo de <span style=\"color: #800000;\">Medea representa la otra cara de Gaia<\/span><\/span><\/span><\/strong><span style=\"color: #000000;\">. Mientras que Gaia es la buena madre Tierra, Medea en la mitolog\u00eda griega se vuelve contra sus propios hijos<\/span><\/em><span style=\"color: #000000;\">\u201d.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Resulta llamativo, que mientras que sobre Gaia existe una exagerada informaci\u00f3n en Internet de habla hispana, demos la espalda a Medea, hasta el punto de que no existe ni un capitulo al respecto en la Wikipedia hispanoparlante. <\/span><span style=\"color: #000000;\">\u00a0<\/span><span style=\"color: #000000;\">Obviamente la versi\u00f3n anglosajona de esta enciclopedia libre si la atesora. \u00a1Materia de Reflexi\u00f3n! <\/span><\/p>\n<p style=\"text-align: justify;\"><strong><span style=\"color: #000000;\"><span style=\"color: #3366ff;\">Sin embargo, Gaia parece hasta evolucionar y expandirse con vistas a defenderse de las cat\u00e1strofes<\/span> <span style=\"color: #3366ff;\">apocal\u00edpticas<\/span><\/span><\/strong><span style=\"color: #000000;\">. Se han encontrado microorganismos hasta los confines de la exploraci\u00f3n humana en nuestro Planeta. <\/span><span style=\"color: #3366ff;\"><strong>Y as\u00ed, en lugar de preg\u00fantanos que espacios ha logrado invadir la vida basada en el carbono, ser\u00eda m\u00e1s apropiado pensar y explotar hasta donde alcanza la vida en su corrosi\u00f3n y transformaci\u00f3n de la litosfera<\/strong><\/span><span style=\"color: #000000;\">. Se ha detectado vida en todos los sondeos que personalmente he le\u00eddo, ya fueran sobre la litosfera terrestre o sedimentos profundos de los fondos abisales. Sin embargo, en la mayor parte de ella detectan tan solo bacterias y arqueas. No obstante, \u00faltimamente, tambi\u00e9n se han logradoencontrar organismos pluricelulares <\/span><span style=\"color: #000000;\">como os mostramos en nuestro post <\/span><a title=\"Enlace permanente: La Vida en las Profundidades de la Tierra: Organismos llovidos del Suelo\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/06\/07\/139492\">La Vida en las Profundidades de la Tierra: Organismos llovidos del Suelo<\/a><span style=\"color: #000000;\">. Y as\u00ed, por ejemplo, si un meteorito arrasara completamente la biosfera hasta unos pocos kil\u00f3metros de profundidad, la evoluci\u00f3n biol\u00f3gica podr\u00eda continuar a una mayor velocidad de lo pensado, ya que probablemente no habr\u00eda que partir de los procariotas, sino que los eucariotas, y m\u00e1s aun de bichitos pluricelulares <\/span><span style=\"color: #000000;\">\u00a0que <\/span><span style=\"color: #000000;\">tambi\u00e9n estar\u00edan presentes. Y tan hecho podr\u00eda alegarse que avala la hip\u00f3tesis Gaia. No obstante la cuesti\u00f3n dista mucho de encontrarse resulta por la ciencia, permaneciendo en el limbo de las especulaciones. <\/span><span style=\"color: #000000;\">\u00a0<\/span><span style=\"color: #000000;\">Y all\u00ed todo vale. <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">En el <\/span><a href=\"http:\/\/leomonfor.blogspot.com.es\/2014\/10\/la-hipotesis-medea-y-el-cambio-climatico.html\"><span style=\"color: #0000ff;\">blog Ciencia, Tecnolog\u00eda, poder y Cambio clim\u00e1tico<\/span><\/a><span style=\"color: #000000;\"> se comenta al hablar de la hip\u00f3tesis Gaia: \u201c(\u2026) \u201c<\/span><em><span style=\"color: #000000;\">Pero esta forma de ver las cosas, ha sido cuestionada desde una posici\u00f3n que comparte lo fundamental, que la Tierra funciona como un sistema, pero que disiente en que este sistema tienda a un equilibrio que conserve la vida. M\u00e1s bien tiende<\/span><span style=\"color: #000000;\">\u00a0 <\/span><span style=\"color: #000000;\">a lo contrario, a expulsarla. <\/span><strong><span style=\"color: #000000;\"><span style=\"color: #3366ff;\">Esta hip\u00f3tesis ha tomado el nombre de Medea<\/span><\/span><\/strong><span style=\"color: #000000;\">, evocando la malignidad de la diosa de la mitolog\u00eda griega de este nombre (\u2026) <\/span><span style=\"color: #3366ff;\"><strong>El simbolismo de Medea representa la otra cara de Gaia. Mientras que Gaia es la buena madre Tierra, Medea<\/strong><\/span><span style=\"color: #000000;\"> en la mitolog\u00eda griega <\/span><strong><span style=\"color: #000000;\"><span style=\"color: #3366ff;\">se vuelve contra sus propios hijos<\/span><\/span><\/strong><span style=\"color: #000000;\">\u00a0<\/span><span style=\"color: #000000;\">(\u2026) <\/span><span style=\"color: #000000;\">\u00a0<\/span><span style=\"color: #000000;\">En el relato de Ward, la historia de la Tierra durante cuatro mil millones de a\u00f1os es una sucesi\u00f3n de extinciones en masa. <\/span><strong><span style=\"color: #000000;\"><span style=\"color: #3366ff;\"><span style=\"color: #800000;\">La vida tiene tendencias biocidas<\/span><\/span><\/span><\/strong><span style=\"color: #000000;\">. Algo que no s\u00f3lo vale para la Tierra, sino que es com\u00fan a todo el Universo. En estas extinciones pasadas, los microorganismos han tenido un especial protagonismo. \u00bfQu\u00e9 tiene que ver con esto el cambio clim\u00e1tico? <\/span><strong><span style=\"color: #3366ff;\">Ward, piensa que el deshielo, el aumento del nivel del mar y la ausencia de circulaci\u00f3n entre los oc\u00e9anos por el calentamiento global provocar\u00e1n, si no se act\u00faa, una grave falta de ox\u00edgeno. Esta anoxia mar\u00edtima llevar\u00eda a\u00a0un aumento de poblaci\u00f3n microbiana productora de sulfuro de hidr\u00f3geno (H<sub>2<\/sub>S). 200 mol\u00e9culas de H2<\/span><span style=\"color: #000000;\"><span style=\"color: #3366ff;\">S entre un mill\u00f3n de mol\u00e9culas de aire bastan para que un humano muera<\/span>.<\/span><\/strong><\/em><span style=\"color: #000000;\">\u201d.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Del mismo modo en el <\/span><a href=\"http:\/\/librodenotas.com\/cienciasyletras\/22013\/gaia-o-medea-el-futuro-de-la-vida-en-la-tierra\"><span style=\"color: #0000ff;\">Libro de Notas<\/span><\/a><span style=\"color: #000000;\">: se ermina un post sobre este tema con la siguiente reflexi\u00f3n: \u201c<\/span><span style=\"color: #3366ff;\"><strong><em>Curiosamente, con independencia de que la hip\u00f3tesis que tomemos como correcta sea la de Gaia o la de Medea el futuro de la vida en la Tierra est\u00e1 en manos de la Humanidad<\/em><\/strong><\/span><em><span style=\"color: #000000;\">. Si Gaia es capaz de autoregularse, tendiendo al equilibrio estable nosotros estamos rompi\u00e9ndolo, por lo que\u00a0tan s\u00f3lo en nuestras manos est\u00e1 restituirlo. Si Medea nos lleva irremediablemente al desastre tambi\u00e9n est\u00e1 en nuestras manos tratar de introducir mecanismos reguladores que lo impidan, empezando por controlar las nefastas consecuencias de nuestra actividad sobre el medio<\/span><\/em><span style=\"color: #000000;\">\u201d.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Empero<\/span><span style=\"color: #000000;\">\u00a0 <\/span><span style=\"color: #000000;\">como en el <\/span><a href=\"http:\/\/www.guiainfantil.com\/1358\/cuento-infantil-pedro-y-el-lobo.html\"><span style=\"color: #0000ff;\">cuento infantil del pastor y el lobo<\/span><\/a><span style=\"color: #000000;\">, el ser humano y la ciencia moderna braman ferozmente en contra de los desastres ambientales causados por nuestra propia especie, pero a la postre no hace nada. Y as\u00ed transcurre el tiempo, hasta que un d\u00eda, cuando tengamos delante las fauces amenazantes de la destricci\u00f3n,\u00a0ya no tengamos tiempo de reaccionar. \u00a1Demasiado tarde!.\u00a0<\/span><span style=\"color: #000000;\">\u00a0<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #3366ff;\"><strong>\u00bfGaia o Medea?<\/strong><\/span><span style=\"color: #000000;\"> Posiblemente defender una ante otra sea cuesti\u00f3n de gustos, que no de evidencias cient\u00edficas. Ahora bien, <\/span><strong><span style=\"color: #000000;\"><span style=\"color: #3366ff;\">ensalzar Gaia ante<\/span> <span style=\"color: #3366ff;\">Medea, carece de sentido, por cuanto\u00a0<\/span><\/span><\/strong><span style=\"color: #000000;\">mientras descubrimos el valor real\u00a0de los microbios, el mayor \u00e9xito de la vida org\u00e1nica, nos percatamos que\u00a0sin ellos no podr\u00edan sobrevivir los seres m\u00e1s complejos. Es licito reflexionar si en realidad\u00a0 el ser humano es\u00a0el m\u00e1s inconscientemente-consciente de todos los seres vivos, debido a que\u00a0nos afanamos\u00a0en llevar la contraria a los primeros. de los que evolutivamente procedemos, destroz\u00e1ndolo todo para nuestro\u00a0exclusivo y exacerbado beneficio. Y de nuevo otra vez, <strong><span style=\"color: #3366ff;\">como en<\/span> <\/strong><\/span><a href=\"http:\/\/www.bme.es\/peques\/elbusinfantil\/materiales\/cuentos\/verano\/cigarra.htm\"><span style=\"color: #0000ff;\">el cuento infantil de la cigarra y hormiga<\/span><\/a><span style=\"color: #000000;\">, podr\u00edamos pensar \u00a0los humanos actuamos como dicta Medea\u00a0y los microrganismos obedecen a\u00a0Gaia. Vamos que la vida es un cuenta y los cuentos, cuentos son. Eso si, en esta batalla, de seguir as\u00ed, no debe albergarse la\u00a0 menor duda de\u00a0que siempre ganar\u00e1 el universo de lo canijo, ya que el grandote, por mucho que alardee de todo lo que carece (inteligencia y sentido com\u00fan, por ejemplo), no puede sobrevivir sin esos peque\u00f1os bichitos. <\/span><\/p>\n<p><strong><span style=\"color: #008000;\">Juan Jos\u00e9 Ib\u00e1\u00f1ez \u00a0<\/span><span style=\"color: #000000;\">\u00a0<\/span><span style=\"color: #000000;\">\u00a0<\/span><span style=\"color: #000000;\">\u00a0<\/span><\/strong><\/p>\n<p><span style=\"color: #000000;\"><!--more--><\/span><\/p>\n<p><a href=\"http:\/\/www.madrimasd.org\/informacionidi\/noticias\/noticia.asp?id=62754&amp;origen=notiweb&amp;dia_suplemento=jueves\"><span style=\"color: #0000ff;\">El subsuelo profundo terrestre es m\u00e1s habitable de lo cre\u00eddo<\/span><\/a><\/p>\n<p><span style=\"color: #800000;\"><strong>Unos cient\u00edficos han cartografiado la ubicaci\u00f3n de aguas que se han encontrado atrapadas a kil\u00f3metros bajo la superficie de la Tierra, en fracturas de rocas en Canad\u00e1, Sud\u00e1frica y Escandinavia<\/strong><\/span><strong>. <\/strong><\/p>\n<p>FUENTE | <a href=\"http:\/\/noticiasdelaciencia.com\/\" target=\"_blank\">Noticias de la Ciencia<\/a> 29\/01\/2015<\/p>\n<p><strong>Estas aguas antiguas tienen una qu\u00edmica similar a la existente cerca de fumarolas hidrotermales del fondo del mar<\/strong>, a cuyo alrededor prospera la vida, lo que sugiere que <strong>esas aguas en fracturas de rocas pueden tambi\u00e9n sustentar a microbios viviendo aislados de la superficie<\/strong><strong>. <\/strong><strong>Los ecosistemas microbianos pueden ser sostenidos por ciertas interacciones entre agua y roca <\/strong><strong>que liberan gas hidr\u00f3geno y que se conocen en el <\/strong><strong>subsuelo terrestre y en el entorno de las citadas fumarolas hidrotermales<\/strong><strong>. Ese hidr\u00f3geno es una fuente de energ\u00eda para tales <\/strong><strong>comunidades microbianas<\/strong><strong>.<\/strong><\/p>\n<p>El equipo internacional de la geoqu\u00edmica Barbara Sherwood Lollar, de la <a title=\"Universidad de Toronto\" href=\"http:\/\/www.utoronto.ca\/\" target=\"_blank\">Universidad de Toronto<\/a> en Canad\u00e1<strong>, tambi\u00e9n ha determinado c\u00f3mo se combinan dos reacciones qu\u00edmicas para producir cantidades sustanciales de hidr\u00f3geno, duplicando las estimaciones de producci\u00f3n global desde estos procesos. Esto supone un salto enorme en el volumen habitable conocido de la corteza terrestre<\/strong>.<\/p>\n<p>Uno de los procesos, conocido como <strong>descomposici\u00f3n radiol\u00edtica del agua<\/strong>, hace que esta sufra una descomposici\u00f3n que libera hidr\u00f3geno cuando es expuesta a radiaci\u00f3n. El otro proceso es una reacci\u00f3n qu\u00edmica <strong>llamada serpentinizaci\u00f3n<\/strong>, una alteraci\u00f3n mineral que es habitual en rocas antiguas de un tipo muy abundante.<\/p>\n<p>Los resultados de la nueva investigaci\u00f3n publicada en <a title=\"Nature\" href=\"http:\/\/www.nature.com\/nature\/journal\/v516\/n7531\/full\/nature14017.html\" target=\"_blank\">Nature<\/a> van a tener <strong>repercusiones importantes para la b\u00fasqueda de vida microbiana en el subsuelo profundo. Cuantificar las cifras del hidr\u00f3geno global disponible para procesos biol\u00f3gicos es vital para determinar la cantidad de biomasa de la Tierra que se halla en el subsuelo, dado que muchos ecosistemas profundos contienen organismos quimiolit\u00f3trofos<\/strong>, descritos coloquialmente como microbios que comen piedra, los cuales consumen hidr\u00f3geno. <strong>En las <\/strong><strong>minas de oro profundas de Sud\u00e1frica<\/strong><strong>, as\u00ed como en <\/strong><strong>las fumarolas hidrotermales del fondo marino <\/strong><strong>donde hay fisuras <\/strong><strong>que liberan aguas calentadas geot\u00e9rmicamente, los fluidos ricos en hidr\u00f3geno sustentan comunidades microbianas complejas que se nutren de las sustancias disueltas en dichos fluidos<\/strong><strong>. El nuevo estudio ha identificado una red global de lugares profundos con aguas ricas en hidr\u00f3geno que ser\u00e1n exploradas en busca de vida durante los pr\u00f3ximos a\u00f1o<\/strong>s.<\/p>\n<p><strong>Adem\u00e1s, dado que en Marte abundan las rocas de miles de millones de a\u00f1os de antig\u00fcedad con una potencial producci\u00f3n de hidr\u00f3geno, como las citadas rocas antiguas de la Tierra, este hallazgo tiene repercusiones para la astrobiolog\u00eda<\/strong>. \u00abSi las rocas antiguas de la Tierra est\u00e1n produciendo tanto hidr\u00f3geno, podr\u00eda ser que procesos similares est\u00e9n teniendo lugar en Marte\u00bb, aventura Sherwood Lollar.<\/p>\n<h3>Im\u00e1genes Relacionadas:<\/h3>","protected":false},"excerpt":{"rendered":"<p>\u00bfGaia o Medea?: Fuente: Melange \u00a0En este planeta azul, los hombres han detectado vida all\u00e1 donde la han estudiado. Ya lo comentamos en algunos post anteriores, por lo que la noticia que os ofrecemos hoy, al final del post, no aporta mucho en este sentido. Sin embargo, tal hecho no deja de sorprenderme. Si realmente pudi\u00e9ramos ser entes inteligentes incorp\u00f3reos y procedentes de otros mundos, nos dar\u00edamos cuenta que en un planeta rocoso la aparici\u00f3n de la vida, podr\u00eda interpretarse como el surgimiento de unos objetos que lo trastocan todo, corroyendo los materiales abi\u00f3ticos (litosfera), cambiando la composici\u00f3n de sus\u2026<\/p>\n","protected":false},"author":26,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0},"categories":[596,609,618,607],"tags":[30135,30133,30134],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":4}},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"El hombre contra la biosfera\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Juan Jos\u00e9 Ib\u00e1\u00f1ez\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2016\/03\/04\/146872\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Un Universo invisible bajo nuestros pies - Los suelos y la vida\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"\u00bfGaia y\/o Medea? (Sobre La Vida en las Profundidades de la Tierra) - Un Universo invisible bajo nuestros pies\" \/>\n\t\t<meta property=\"og:description\" content=\"El hombre contra la biosfera\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2016\/03\/04\/146872\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2016-03-04T14:14:08+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2016-03-04T14:14:08+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/juan.j.marti.14\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"\u00bfGaia y\/o Medea? (Sobre La Vida en las Profundidades de la Tierra) - Un Universo invisible bajo nuestros pies\" \/>\n\t\t<meta name=\"twitter:description\" content=\"El hombre contra la biosfera\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2016\\\/03\\\/04\\\/146872#blogposting\",\"name\":\"\\u00bfGaia y\\\/o Medea? (Sobre La Vida en las Profundidades de la Tierra) - Un Universo invisible bajo nuestros pies\",\"headline\":\"\\u00bfGaia y\\\/o Medea? (Sobre La Vida en las Profundidades de la Tierra)\",\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"http:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/wp-content\\\/blogs.dir\\\/42\\\/files\\\/159\\\/medea-o-gaia.jpg\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2016\\\/03\\\/04\\\/146872\\\/#articleImage\"},\"datePublished\":\"2016-03-04T15:14:08+01:00\",\"dateModified\":\"2016-03-04T15:14:08+01:00\",\"inLanguage\":\"es-ES\",\"commentCount\":1,\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2016\\\/03\\\/04\\\/146872#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2016\\\/03\\\/04\\\/146872#webpage\"},\"articleSection\":\"Biolog\\u00eda y Ecolog\\u00eda del Suelo, Curso B\\u00e1sico Sobre Filosof\\u00eda y Sociolog\\u00eda de la Ciencia, Ecolog\\u00eda y Biogeograf\\u00eda post posteriores a agosto de 2009, Historia de la Tierra y de los Suelos., Futuro de la Tierra, Hip\\u00f3tesis Gaia, Hipotesis Medea\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2016\\\/03\\\/04\\\/146872#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/biologia-y-ecologia-del-suelo#listItem\",\"name\":\"Biolog\\u00eda y Ecolog\\u00eda del Suelo\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/biologia-y-ecologia-del-suelo#listItem\",\"position\":2,\"name\":\"Biolog\\u00eda y Ecolog\\u00eda del Suelo\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/biologia-y-ecologia-del-suelo\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2016\\\/03\\\/04\\\/146872#listItem\",\"name\":\"\\u00bfGaia y\\\/o Medea? (Sobre La Vida en las Profundidades de la Tierra)\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2016\\\/03\\\/04\\\/146872#listItem\",\"position\":3,\"name\":\"\\u00bfGaia y\\\/o Medea? (Sobre La Vida en las Profundidades de la Tierra)\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/biologia-y-ecologia-del-suelo#listItem\",\"name\":\"Biolog\\u00eda y Ecolog\\u00eda del Suelo\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#organization\",\"name\":\"Un Universo invisible bajo nuestros pies\",\"description\":\"Los suelos y la vida\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/files\\\/2022\\\/02\\\/logo.png\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2016\\\/03\\\/04\\\/146872\\\/#organizationLogo\",\"width\":217,\"height\":72},\"image\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2016\\\/03\\\/04\\\/146872\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/juan.j.marti.14\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo\",\"name\":\"Juan Jos\\u00e9 Ib\\u00e1\\u00f1ez\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2016\\\/03\\\/04\\\/146872#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/387f3a100385573d8f42ce2a3211fd1c?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Juan Jos\\u00e9 Ib\\u00e1\\u00f1ez\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2016\\\/03\\\/04\\\/146872#webpage\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2016\\\/03\\\/04\\\/146872\",\"name\":\"\\u00bfGaia y\\\/o Medea? (Sobre La Vida en las Profundidades de la Tierra) - Un Universo invisible bajo nuestros pies\",\"description\":\"El hombre contra la biosfera\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2016\\\/03\\\/04\\\/146872#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\"},\"datePublished\":\"2016-03-04T15:14:08+01:00\",\"dateModified\":\"2016-03-04T15:14:08+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#website\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/\",\"name\":\"Un Universo invisible bajo nuestros pies\",\"description\":\"Los suelos y la vida\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"\u00bfGaia y\/o Medea? (Sobre La Vida en las Profundidades de la Tierra) - Un Universo invisible bajo nuestros pies","description":"El hombre contra la biosfera","canonical_url":"https:\/\/www.madrimasd.org\/blogs\/universo\/2016\/03\/04\/146872","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2016\/03\/04\/146872#blogposting","name":"\u00bfGaia y\/o Medea? (Sobre La Vida en las Profundidades de la Tierra) - Un Universo invisible bajo nuestros pies","headline":"\u00bfGaia y\/o Medea? (Sobre La Vida en las Profundidades de la Tierra)","author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author"},"publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#organization"},"image":{"@type":"ImageObject","url":"http:\/\/www.madrimasd.org\/blogs\/universo\/wp-content\/blogs.dir\/42\/files\/159\/medea-o-gaia.jpg","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2016\/03\/04\/146872\/#articleImage"},"datePublished":"2016-03-04T15:14:08+01:00","dateModified":"2016-03-04T15:14:08+01:00","inLanguage":"es-ES","commentCount":1,"mainEntityOfPage":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2016\/03\/04\/146872#webpage"},"isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2016\/03\/04\/146872#webpage"},"articleSection":"Biolog\u00eda y Ecolog\u00eda del Suelo, Curso B\u00e1sico Sobre Filosof\u00eda y Sociolog\u00eda de la Ciencia, Ecolog\u00eda y Biogeograf\u00eda post posteriores a agosto de 2009, Historia de la Tierra y de los Suelos., Futuro de la Tierra, Hip\u00f3tesis Gaia, Hipotesis Medea"},{"@type":"BreadcrumbList","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2016\/03\/04\/146872#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo#listItem","position":1,"name":"Home","item":"https:\/\/www.madrimasd.org\/blogs\/universo","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/biologia-y-ecologia-del-suelo#listItem","name":"Biolog\u00eda y Ecolog\u00eda del Suelo"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/biologia-y-ecologia-del-suelo#listItem","position":2,"name":"Biolog\u00eda y Ecolog\u00eda del Suelo","item":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/biologia-y-ecologia-del-suelo","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2016\/03\/04\/146872#listItem","name":"\u00bfGaia y\/o Medea? (Sobre La Vida en las Profundidades de la Tierra)"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2016\/03\/04\/146872#listItem","position":3,"name":"\u00bfGaia y\/o Medea? (Sobre La Vida en las Profundidades de la Tierra)","previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/biologia-y-ecologia-del-suelo#listItem","name":"Biolog\u00eda y Ecolog\u00eda del Suelo"}}]},{"@type":"Organization","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#organization","name":"Un Universo invisible bajo nuestros pies","description":"Los suelos y la vida","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/","logo":{"@type":"ImageObject","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2016\/03\/04\/146872\/#organizationLogo","width":217,"height":72},"image":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2016\/03\/04\/146872\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/juan.j.marti.14"]},{"@type":"Person","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo","name":"Juan Jos\u00e9 Ib\u00e1\u00f1ez","image":{"@type":"ImageObject","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2016\/03\/04\/146872#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/387f3a100385573d8f42ce2a3211fd1c?s=96&d=mm&r=g","width":96,"height":96,"caption":"Juan Jos\u00e9 Ib\u00e1\u00f1ez"}},{"@type":"WebPage","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2016\/03\/04\/146872#webpage","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/2016\/03\/04\/146872","name":"\u00bfGaia y\/o Medea? (Sobre La Vida en las Profundidades de la Tierra) - Un Universo invisible bajo nuestros pies","description":"El hombre contra la biosfera","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#website"},"breadcrumb":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2016\/03\/04\/146872#breadcrumblist"},"author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author"},"creator":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author"},"datePublished":"2016-03-04T15:14:08+01:00","dateModified":"2016-03-04T15:14:08+01:00"},{"@type":"WebSite","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#website","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/","name":"Un Universo invisible bajo nuestros pies","description":"Los suelos y la vida","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Un Universo invisible bajo nuestros pies - Los suelos y la vida","og:type":"article","og:title":"\u00bfGaia y\/o Medea? (Sobre La Vida en las Profundidades de la Tierra) - Un Universo invisible bajo nuestros pies","og:description":"El hombre contra la biosfera","og:url":"https:\/\/www.madrimasd.org\/blogs\/universo\/2016\/03\/04\/146872","og:image":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png","og:image:secure_url":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png","article:published_time":"2016-03-04T14:14:08+00:00","article:modified_time":"2016-03-04T14:14:08+00:00","article:publisher":"https:\/\/www.facebook.com\/juan.j.marti.14","twitter:card":"summary","twitter:title":"\u00bfGaia y\/o Medea? (Sobre La Vida en las Profundidades de la Tierra) - Un Universo invisible bajo nuestros pies","twitter:description":"El hombre contra la biosfera","twitter:image":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png"},"aioseo_meta_data":{"post_id":"146872","title":"","description":"El hombre contra la biosfera","keywords":[{"label":"Gaia","value":"Gaia"},{"label":"Medea","value":"Medea"},{"label":"Motores de la vida","value":"Motores de la vida"},{"label":"biosfera","value":"biosfera"},{"label":"impacto humano","value":"impacto humano"},{"label":"cambio clim\u00e1tico","value":"cambio clim\u00e1tico"}],"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":null,"isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","tabs":null,"priority":null,"frequency":null,"local_seo":null,"created":"2022-06-03 17:13:45","updated":"2026-05-26 18:29:55","limit_modified_date":false,"ai":null,"breadcrumb_settings":null,"seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/biologia-y-ecologia-del-suelo\" title=\"Biolog\u00eda y Ecolog\u00eda del Suelo\">Biolog\u00eda y Ecolog\u00eda del Suelo<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t\u00bfGaia y\/o Medea? (Sobre La Vida en las Profundidades de la Tierra)\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.madrimasd.org\/blogs\/universo"},{"label":"Biolog\u00eda y Ecolog\u00eda del Suelo","link":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/biologia-y-ecologia-del-suelo"},{"label":"\u00bfGaia y\/o Medea? (Sobre La Vida en las Profundidades de la Tierra)","link":"https:\/\/www.madrimasd.org\/blogs\/universo\/2016\/03\/04\/146872"}],"_links":{"self":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts\/146872"}],"collection":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/comments?post=146872"}],"version-history":[{"count":8,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts\/146872\/revisions"}],"predecessor-version":[{"id":147896,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts\/146872\/revisions\/147896"}],"wp:attachment":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/media?parent=146872"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/categories?post=146872"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/tags?post=146872"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}