{"id":147820,"date":"2016-11-02T18:05:36","date_gmt":"2016-11-02T17:05:36","guid":{"rendered":"http:\/\/www.madrimasd.org\/blogs\/universo\/?p=147820"},"modified":"2016-11-02T18:05:36","modified_gmt":"2016-11-02T17:05:36","slug":"la-nueva-revolucion-verde-del-siglo-xxi-todo-preparado","status":"publish","type":"post","link":"https:\/\/www.madrimasd.org\/blogs\/universo\/2016\/11\/02\/147820","title":{"rendered":"La Nueva Revoluci\u00f3n Verde del Siglo XXI. Todo Preparado"},"content":{"rendered":"<p align=\"center\"><span style=\"color: #000000;\"><img decoding=\"async\" class=\"ngg-singlepic ngg-center\" style=\"width: 451px; height: 292px;\" src=\"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-content\/blogs.dir\/42\/files\/255\/nuena-revolucion-verde.jpg\" alt=\"nuena-revolucion-verde\" width=\"701\" height=\"393\" \/><\/span><\/p>\n<p align=\"center\"><a href=\"http:\/\/www.dw.com\/en\/sowing-the-seeds-of-an-organic-revolution\/a-18886533\"><span style=\"color: #0000ff;\">La Nueva Revoluci\u00f3n Verde: Fuente: made for minds<\/span><\/a><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #3366ff;\"><strong>La mayor parte de la comunidad cient\u00edfica ya se ha rendido a las evidencias<\/strong><\/span><span><span style=\"color: #000000;\">. <\/span><strong style=\"color: #000000;\"><span style=\"color: #3366ff;\">Hace diez a\u00f1os<\/span><\/strong><span style=\"color: #000000;\">, cuando comenzamos nuestra andadura en esta bit\u00e1cora, <\/span><span><strong><span style=\"color: #3366ff;\">tuvimos que sufrir abundantes\u00a0cr\u00edticas por defender que la Revoluci\u00f3n verde del siglo XX significo comida para aquella \u00e9poca, a costa de secuestrar el futuro de la soberan\u00eda alimentaria en el mundo y de<\/span><\/strong><\/span><\/span><span style=\"color: #000000;\"><span style=\"color: #3366ff;\"><strong>gradar la biosfera. Diez a\u00f1os despu\u00e9s, casi ning\u00fan experto lo discute, como tampoco la FAO y la ONU<\/strong>. <strong>Se acaba el sucio negocio de los pesticidas, insumos ingentes de fertilizantes e ir tocando los genes de las plantas<\/strong> <\/span>con las promesas m\u00e1s absurdas. Eso s\u00ed, tales <span style=\"color: #3366ff;\"><strong>multinacionales<\/strong><\/span> y los intereses que ocultan <strong><span style=\"color: #3366ff;\">se resistir\u00e1n confundiendo \u00a0los vocablos para<\/span> <span style=\"color: #3366ff;\">intentar, como han hecho siempre, vender gato por libre<\/span><\/strong>. La <\/span><a href=\"https:\/\/www.organicconsumers.org\/scientific\/organic-green-revolution\"><span style=\"color: #0000ff;\">Revoluci\u00f3n de la agricultura org\u00e1nica<\/span><\/a><span style=\"color: #000000;\"> ya parece que calienta motores, si bien tal <\/span><a href=\"http:\/\/athleteculture.com\/nutrition\/organic-farming-vs-the-green-revolution\/\"><span style=\"color: #0000ff;\">revoluci\u00f3n verde no tiene nada que ver con la propuesta de otras basadas en los principios de la agricultura ecol\u00f3gica<\/span><\/a><span style=\"color: #000000;\">, <\/span><span><strong style=\"color: #000000;\"><span style=\"color: #3366ff;\">que a su vez tampoco proponen exactamente lo mismo<\/span><\/strong><span style=\"color: #000000;\">. Siempre os <\/span><span><strong><span style=\"color: #3366ff;\">insisto que entend\u00e1is los conceptos y no os dej\u00e9is\u00a0enga\u00f1ar por los vocablos<\/span><\/strong><\/span><span style=\"color: #000000;\">, dado que se manipulan maniqueamente con harta frecuencia. Como se explica en Wikipedia, <\/span><\/span><a href=\"https:\/\/es.wikipedia.org\/wiki\/Revoluc\u00f3n_verde\"><span style=\"color: #0000ff;\">Revoluci\u00f3n verde<\/span><\/a><span style=\"color: #000000;\"><em>\u00a0es la denominaci\u00f3n usada internacionalmente para describir el importante incremento de la productividad agr\u00edcola y por tanto de alimentos <\/em><\/span><em><\/em><span style=\"color: #000000;\"><em><span style=\"color: #3366ff;\">\u00a0<\/span>en Estados Unidos, y extendida despu\u00e9s por numerosos pa\u00edses<\/em>. Empero esa es la antigua. Tener cuidado que algunos intentar\u00e1n confundir lo nuevo con lo viejo.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">La vieja <\/span><a href=\"http:\/\/athleteculture.com\/nutrition\/organic-farming-vs-the-green-revolution\/\"><span style=\"color: #0000ff;\">revoluci\u00f3n verde<\/span><\/a><span style=\"color: #000000;\"><strong>\u00a0<span style=\"color: #3366ff;\">se basaba en (i)<\/span><\/strong> la adici\u00f3n de una gran cantidad de fertilizantes qu\u00edmicos al suelo <span style=\"color: #3366ff;\"><strong>(ii)<\/strong><\/span> aplicaci\u00f3n sistem\u00e1tica de pesticidas <span style=\"color: #3366ff;\"><strong>y (iii)<\/strong> <\/span>el uso de semillas y plantas modificadas gen\u00e9ticamente. \u00a0Por su parte, <strong><span style=\"color: #3366ff;\">la nueva revoluci\u00f3n<\/span> <span style=\"color: #3366ff;\">verde<\/span><\/strong> (que en el mundo anglosaj\u00f3n se denomina org\u00e1nica): <span style=\"color: #3366ff;\"><strong>pivota sobre los siguientes tres principios: (i)<\/strong><\/span> la erradicaci\u00f3n, en la medida de lo posible de las mentadas enmiendas qu\u00edmicas; <span style=\"color: #3366ff;\"><strong>(ii)<\/strong><\/span> el menor uso posible, y tan solo cuando sea totalmente imprescindible, de nuevas y m\u00e1s amigables sustancias para el ambientalmente, en lo que concierne al control de plagas y pestes <strong><span style=\"color: #3366ff;\">y<\/span> <span style=\"color: #3366ff;\">(iii)<\/span><\/strong> uso de semillas sin ser alteradas por la biotecnolog\u00eda, es decir, los \u201ctocagenes\u201d. Sin embargo, reiteramos por en\u00e9sima vez que <span style=\"color: #3366ff;\"><strong>lo denominado org\u00e1nico en el mundo anglosaj\u00f3n no es exactamente equivalente al concepto de agricultura ecol\u00f3gica en espa\u00f1ol. Tal confusi\u00f3n est\u00e1 dando lugar a que las multinacionales del agronegocio intenten enga\u00f1arnos<\/strong> <\/span>de nuevo. Al final de esta entrada os mostramos algunos post previos relacionados con tal maniqueo abuso del lenguaje, al objeto de intentar separar el grano de la paja. En \u00a0<\/span><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/etnoedafologia-y-conocimiento-campesino\"><span style=\"color: #0000ff;\">nuestra categor\u00eda Etnoedafolog\u00eda y Conocimiento Campesino<\/span><\/a><span style=\"color: #000000;\"> podr\u00e9is leer mucho m\u00e1s sobre estos asuntos. <\/span><a href=\"https:\/\/www.researchgate.net\/publication\/286379741_Mirando_hacia_el_pasado_para_mejorar_el_futuroUn_viaje_por_las_culturas_precolombinas?ev=prf_pub\">Mirar hacia el pasado para mejorar el futuro resulta hoy m\u00e1s que nunca de suma importancia. \u00a0<\/a><span style=\"color: #000000;\">La agenda de <span style=\"color: #3366ff;\"><strong>investigaci\u00f3n que se ha marcado la FAO<\/strong><\/span>, y de la cual fui uno de los autores, es clara y rotunda (<\/span><a href=\"https:\/\/www.researchgate.net\/publication\/285588365_Plan_of_Action_for_Pillar_Three_of_the_Global_Soil_Partnership_Adopted_by_the_III_GSP_Plenary_Assembly_Promote_targeted_soil_research_and_development_focusing_on_identified_gaps_priorities_and_synergi?ev=prf_pub\">Plan of Action for Pillar Three of the Global Soil Partnership Adopted by the III GSP Plenary Assembly<\/a>) , como tambi\u00e9n el <a href=\"http:\/\/www.fao.org\/documents\/card\/en\/c\/c6814873-efc3-41db-b7d3-2081a10ede50\/\"><span style=\"color: #0000ff;\">Status of the World&#8217;s Soil Resources<\/span><\/a><span style=\"color: #000000;\"><strong>\u00a0<span style=\"color: #3366ff;\">de la ONU<\/span><\/strong>,en cuya redacci\u00f3n tambi\u00e9n modestamente intervine. No queda nada por discutir, nadie duda ya del desastre y desgracia que ha supuesto para el deterioro de la biosfera la ya denominada antigua revoluci\u00f3n verde, con el paso de los a\u00f1os. <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #3366ff;\"><strong>Hoy os hemos traducido el texto<\/strong><\/span><span style=\"color: #000000;\"> de unos investigadores del <\/span><a href=\"http:\/\/www.hutton.ac.uk\/research\/groups\/ecological%20sciences\"><span style=\"color: #0000ff;\">Ecological Sciences, James Hutton Institute<\/span><\/a><span style=\"color: #000000;\"><strong>,\u00a0<span style=\"color: #3366ff;\">en el cual se explica lo que hemos venido reiterando durante diez a\u00f1os<\/span><\/strong>. Eso s\u00ed, cuidado con el debate acerca de los <\/span><a title=\"Enlace permanente: Microorganismos Eficientes o Efectivos (EM) y Rehabilitaci\u00f3n de Suelos\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/03\/02\/137556\">Microorganismos Eficientes o Efectivos (EM) en la Rehabilitaci\u00f3n de Suelos<\/a><span style=\"color: #000000;\">, ya que una cosa es hacer uso de la ingenier\u00eda \u201cnatural de los propios organismos, y otra bien distinta que compr\u00e9is los productos que ya salen al mercado bajo esta denominaci\u00f3n y que no suelen servir para nada. Resulta <\/span><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/03\/02\/137556\/comment-page-1\"><span style=\"color: #0000ff;\">mucho m\u00e1s sencillo, viable y barato elaborarlos vosotros mismos, como se est\u00e1 haciendo en Cuba<\/span><\/a><span style=\"color: #000000;\">. Abajo os dejo tambi\u00e9n alguna relaci\u00f3n de post<\/span><span style=\"color: #000000;\">\u00a0 previos sobre estos eficient\u00edsimos organismos y el cuidado que hay que tener para no caer de nuevo en las \u00a0trampas del agronegocio. \u00bfDejar\u00e1n las poderosas internacionales que ONU y FAO lleven a cabo sus planes?. Aqu\u00ed nos enfrentamos al kit de la cuesti\u00f3n.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Del mismo modo, <span style=\"color: #3366ff;\"><strong>durante 2015<\/strong> <\/span><\/span><a href=\"https:\/\/en.wikipedia.org\/wiki\/Tom_Vilsack\"><span style=\"color: #0000ff;\">Tom Vilsack<\/span><\/a><span style=\"color: #000000;\"> el Secretario del\u00a0 <\/span><a href=\"https:\/\/es.wikipedia.org\/wiki\/Departamento_de_Agricultura_de_los_Estados_Unidos\"><span style=\"color: #0000ff;\">Departamento de Agricultura de los Estados Unidos<\/span><\/a><span style=\"color: #000000;\"> (<\/span><em><a href=\"https:\/\/en.wikipedia.org\/wiki\/United_States_Secretary_of_Agriculture\"><span style=\"color: #0000ff;\">United States Secretary of Agriculture<\/span><\/a><\/em><span style=\"color: #000000;\">), ha insistido una y otra vez ante los medios de comunicaci\u00f3n sobre la importancia de <span style=\"color: #3366ff;\"><strong>gestionar los suelos desde este nuevo paradigma para paliar la contaminaci\u00f3n tanto su contaminaci\u00f3n como la de las aguas, y as\u00ed mejorar la grave situaci\u00f3n ambiental y garantizar la<\/strong> <strong>seguridad alimentaria en USA<\/strong><\/span>. Del mismo modo <span style=\"color: #3366ff;\"><strong>los boletines de noticias del<\/strong> <\/span><\/span><a href=\"https:\/\/es.wikipedia.org\/wiki\/Departamento_de_Agricultura_de_los_Estados_Unidos\"><span style=\"color: #0000ff;\">Departamento de Agricultura de los Estados Unidos<\/span><\/a><span style=\"color: #000000;\">, <\/span><span style=\"color: #000000;\"><span style=\"color: #3366ff;\"><strong>son totalmente expl\u00edcitos en esta materia ofreciendo subvenciones y otras prebendas para todos los granjeros que se encaminen en la direcci\u00f3n de la nueva revoluci\u00f3n verde<\/strong>,<span style=\"color: #000000;\"> haciendo un especial \u00e9nfasis en los<\/span> <strong>policultivos y la diversificaci\u00f3n de las producciones agrarias<\/strong> <span style=\"color: #000000;\">de los predios,<\/span> <strong>la integraci\u00f3n en ellos y cuidado de los humedales y zonas h\u00famedas, etc<\/strong><\/span>. <\/span><\/p>\n<p><span style=\"color: #000000;\"><span style=\"color: #3366ff;\"><strong>Os dejo pues con la mentada traducci\u00f3n<\/strong> <\/span>que me mejorado un poco de lo ofrecido por los traductores autom\u00e1ticos de la red. En cualquier caso, podr\u00eda haberme esmerado m\u00e1s. Pido disculpas, si bien creo que el contenido se entender\u00e1 perfectamente.<\/span><\/p>\n<p><span style=\"color: #008000;\"><strong>Juan Jos\u00e9 Ib\u00e1\u00f1ez<\/strong><\/span><\/p>\n<p><strong><span style=\"color: #000000;\"><!--more--><\/span><\/strong><\/p>\n<p><a href=\"http:\/\/www.google.es\/url?sa=t&amp;rct=j&amp;q=&amp;esrc=s&amp;source=web&amp;cd=4&amp;cad=rja&amp;uact=8&amp;ved=0ahUKEwjF9MzdyobLAhXHuRQKHbDsDK4QFggvMAM&amp;url=http%3A%2F%2Fwww.fao.org%2F3%2Faz920e&amp;usg=AFQjCNFlMN-p4IxxazHrjyqXkyKuslB8Zw\"><span style=\"font-family: Calibri; font-size: medium;\">Plan of Action for Pillar Three of the Global Soil Partnership<\/span><\/a><\/p>\n<p><a href=\"http:\/\/www.fao.org\/documents\/card\/en\/c\/c6814873-efc3-41db-b7d3-2081a10ede50\/\"><span style=\"color: #0000ff;\">Status of the World&#8217;s Soil Resources<\/span><\/a><\/p>\n<p><span style=\"color: #000000; font-family: Calibri; font-size: medium;\">\u00a0<\/span><\/p>\n<p><strong><a href=\"http:\/\/www.hutton.ac.uk\/research\/themes\/safeguarding-natural-capital\/soilshutton\/international-year-soils-series-articles\/soils-green-revolution\"><span style=\"color: #0000ff;\">Soils will lead the next green revolution \u2013 if we allow them<\/span><\/a><\/strong><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">\u00abBy shifting crop breeding targets to promote the beneficial use of soil microbes and managing our agriculture through reduced inputs, we could take a huge step forward to such a new green revolution. <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">\u00a0<\/span><em><span style=\"color: #800000;\">Al cambiar los objetivos de mejoramiento de cultivos para promover el uso beneficioso de los microorganismos del suelo y la gesti\u00f3n de nuestra agricultura a trav\u00e9s de reducci\u00f3n de los insumos, podr\u00edamos dar un gran paso adelante a una nueva revoluci\u00f3n verde<\/span><\/em>.<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #0000ff;\"><strong>Dr Alison Bennett, Dr Tim Daniell, Dr Timothy George, Ecological Sciences, James Hutton\u00a0Institute<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">The \u201cgreen revolution\u201d led to an increase in crop yield at least three times greater than the previous century, and this increase was primarily a result of the introduction of fertilisers, pesticides, and new crop varieties.\u00a0 However, while most crop yields are no longer increasing, the world population is still growing.\u00a0 The FAO estimates the global population will reach almost 10 billion in 2050.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #800000;\"><em>La \u00abrevoluci\u00f3n verde\u00bb condujo a un aumento en el rendimiento del cultivo por lo menos tres veces mayor que el siglo anterior, y este aumento fue principalmente el resultado de la introducci\u00f3n de fertilizantes, pesticidas y nuevas variedades de cultivos. Sin embargo, mientras la mayor\u00eda de las cosechas ya no est\u00e1n aumentando, la poblaci\u00f3n mundial sigue creciendo. La FAO estima que la poblaci\u00f3n mundial llegar\u00e1 a casi 10 mil millones en 2050<\/em><\/span><em><span style=\"color: #000000;\">.<\/span><\/em><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">The sustainability of our current fertilisers and pesticides is also declining partly due to the many negative impacts of chemicals in our environment. Thus, scientists around the world, including colleagues at the James Hutton Institute in Scotland, are looking for new ways of increasing crop yield and creating a second \u201cgreen revolution.\u201d By shifting crop breeding targets to promote the beneficial use of soil microbes and managing our agriculture through reduced inputs, we could take a huge step forward to such a new green revolution.\u00a0<\/span><\/p>\n<p style=\"text-align: justify;\"><em><span style=\"color: #800000;\">La sostenibilidad de nuestros fertilizantes y pesticidas actuales tambi\u00e9n est\u00e1 declinando debido en parte a los muchos impactos negativos de los productos qu\u00edmicos en nuestro medio ambiente. Por lo tanto, los cient\u00edficos de todo el mundo, incluyendo sus colegas del Instituto James Hutton en Escocia, est\u00e1n buscando nuevas maneras de aumentar el rendimiento del cultivo y la creaci\u00f3n de una segunda \u00abrevoluci\u00f3n verde\u00bb. Al cambiar los objetivos de la mejora de los cultivos para promover el uso beneficioso de los microorganismos del suelo y la gesti\u00f3n nuestra agricultura a trav\u00e9s de reducci\u00f3n de los insumos, que podr\u00eda permitir dar un gran paso adelante hacia una nueva revoluci\u00f3n verde<\/span>.<\/em><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Soils have the ability to replace partially many conventional agricultural inputs, but only if we understand how soil microbes help crop plants grow and we also maintain soils in a healthy condition for microbes.\u00a0 If well managed, soils can improve nutrient availability, reduce disease incidence, and reduce pest pressures, and thus could, at least partially, replace fertilisers and pesticides. However, these effects strongly depend on how \u2018healthy\u2019 our soils are.<\/span><\/p>\n<p style=\"text-align: justify;\"><em><span style=\"color: #800000;\">Los suelos tienen la capacidad de reemplazar parcialmente muchos insumos agr\u00edcolas convencionales, pero s\u00f3lo si entendemos c\u00f3mo ayudan a los microbios del suelo crecen las plantas de cultivo y que tambi\u00e9n mantienen los suelos en una condici\u00f3n saludable para los microorganismos. Si son bien administrados, los suelos pueden mejorar la disponibilidad de nutrientes, reducir la incidencia de la enfermedad, y reducir las presiones de plagas, y por lo tanto podr\u00eda, al menos parcialmente, sustituir los fertilizantes y pesticidas. Sin embargo, estos efectos dependen en gran medida de la salud de los suelos<\/span>.<\/em><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">The environmental, as well as economic, costs of using chemical inputs that have led to a tightening of regulations for the use of fertilisers and pesticides have increased our need to find alternatives for these inputs. Maintaining a healthy soil community could provide an alternative for some inputs while reducing certain environmental impacts of food production such as greenhouse gas emission.\u00a0<\/span><\/p>\n<p style=\"text-align: justify;\"><em><span style=\"color: #800000;\">Los costos ambientales, as\u00ed como econ\u00f3micos, de la utilizaci\u00f3n de insumos qu\u00edmicos que han llevado a un endurecimiento de las normas para el uso de fertilizantes y pesticidas han aumentado la necesidad de encontrar alternativas que remplacen estos insumos, almenos en gran medida. El mantenimiento la slud del suelo y las\u00a0 comunidades de orgebimos que habitan en ellos podr\u00edan proporcionar una alternativa para algunos insumos, mientras que se educir\u00edan ciertos impactos ambientales relacionados con \u00a0la producci\u00f3n de alimentos, tales como las emisiones de gases de efecto invernadero<\/span>.<\/em><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">To achieve this, a number of important steps need to be taken. First, we need to improve our understanding of how soil works and our understanding of how agriculture alters soil.\u00a0 This will allow for better design of management systems, which in turn will promote greater nutrient availability and prime plants with better defense responses when challenged by pests and diseases.\u00a0<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #800000;\"><em>Para lograrlo, hay que tomar una serie de medidas importantes. En primer lugar, tenemos que mejorar nuestra comprensi\u00f3n de c\u00f3mo funciona el suelo y nuestra comprensi\u00f3n de c\u00f3mo la agricultura altera el suelo. Esto permitir\u00e1 mejores dise\u00f1os de los sistemas de gesti\u00f3n, que a su vez promover\u00edan una mayor disponibilidad de nutrientes para las plantas de cultivo, y como rolario con mejores en la respuesta de las plantas cuando sean amenazadas por plagas y enfermedades<\/em><\/span>.<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Crop breeding also needs to allow plants to take advantage of the beneficial soil microbes in a healthy soil.\u00a0 New breeding efforts could include simple measures such as an increase in the number and density of roots.\u00a0 Similar to how a farmer cultivates crops, plants use their roots and compounds to \u2018cultivate\u2019 the microbes that live around their roots.\u00a0 We can, therefore, breed crops that cultivate microbial communities, which has a beneficial effect on nutrient availability and plant defence.<\/span><\/p>\n<p style=\"text-align: justify;\"><em><span style=\"color: #800000;\">La mejora de los cultivos tambi\u00e9n tiene que permitir que las plantas se aprovechen de los microbios beneficiosos del suelo en un suelo saludable. Nuevos esfuerzos de mejora podr\u00edan incluir medidas simples tales como un aumento en el n\u00famero y la densidad de las ra\u00edces. De manera similar a c\u00f3mo un agricultor cultiva sus cosechas, las plantas usan sus ra\u00edces y los compuestos que exudan para &#8216;cultivar&#8217; los microbios que viven alrededor de sus ra\u00edces (rizosfera). Podemos, por lo tanto, criar cultivos que cultivan (permiten desarrollarse eficientemente) las comunidades microbianas, lo cual tiene un efecto beneficioso sobre la disponibilidad de nutrientes y la defensa de la planta<\/span>.<\/em><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">However, plants can only cultivate the microbes that are present in the soil, and current agricultural practices also affect soil microbes. Tillage breaks up or redistributes microbes often away from new plant roots. Similarly, adding fertilisers or pesticides or using fields planted with a single crop can also dramatically alter soil microbes. All of these practices can lead to the unnecessary loss of good types of microbes from agricultural soil, and can also result in communities of antagonistic microbes, or damage the environment.<\/span><\/p>\n<p style=\"text-align: justify;\"><em><span style=\"color: #800000;\">Sin embargo, las plantas s\u00f3lo pueden cultivar los microbios que est\u00e1n presentes en el suelo, y las pr\u00e1cticas agr\u00edcolas actuales tambi\u00e9n afectan los microbios del suelo. La labranza rompe o redistribuye los microbios a menudo fuera de las nuevas ra\u00edces de las plantas. Del mismo modo, la adici\u00f3n de fertilizantes o pesticidas o el uso de campos sembrados con un solo cultivo tambi\u00e9n puede alterar dram\u00e1ticamente los microbios del suelo. Todas estas pr\u00e1cticas pueden conducir a la p\u00e9rdida innecesaria de buenos tipos de microorganismos del suelo agr\u00edcola, y tambi\u00e9n puede resultar en comunidades de microbios antagonistas, o da\u00f1ar al el medio ambiente<\/span>.<\/em><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Changing how we grow crops will produce a healthier system and avoid the loss of important microbes.\u00a0 Currently some of these agricultural practices, such as minimum tillage and the use of alternative fertilisers such as composts, are being tested and used on farms.<\/span><\/p>\n<p style=\"text-align: justify;\"><em><span style=\"color: #800000;\">Cambiar la forma en que crecen las cosechas producir\u00e1n un sistema m\u00e1s saludable y evitar la p\u00e9rdida de microrganismos importantes. Actualmente algunas de estas pr\u00e1cticas agr\u00edcolas, como la labranza m\u00ednima y el uso de fertilizantes alternativos, como el compost, est\u00e1n siendo probados y utilizados en las granjas<\/span>.<\/em><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">In addition, most of our crops have been bred under optimal conditions, such as well-tilled soil and high inputs of fertilisers and pesticides.\u00a0 As a result, when compared to wild relatives, crop plants tend to interact poorly with soil microbes without chemicals and\u00a0tillage,\u00a0and have a less diverse microbe community around their roots. As a result, these crop species will be hindered in the future when fertilisers become rare if crop breeding practices are not changed.<\/span><\/p>\n<p style=\"text-align: justify;\"><em><span style=\"color: #800000;\">Adem\u00e1s, la mayor\u00eda de nuestros cosechas han medrado adecuadamente bajo una labranza \u00f3ptimas\u00a0 del suelo, haciendo uso de la denominada labranza cero y un elevado aporte de fertilizantes y pesticidas. Como resultado, cuando se compara con sus parientes silvestres, las plantas de cultivo tienden a interactuar mal con los microbios del suelo sin labranza ni productos qu\u00edmicos, y atesoran comunidades microbianas de menor diversidad en sus rizosferas. Como resultado, estas especies de cultivo, se desarrollar\u00e1n peor en el futuro, cuando se los imputs de fertilizantes sean raros o escasos, si las pr\u00e1cticas convencionales de cultivo no lo hacen en consonacia<\/span>.<\/em><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">We are now well placed to try and tailor our crop plants to select a beneficial community of microbes to replace some chemical inputs. Together with careful soil management and other scientific advances, crop plants bred for positive microbe associations will produce an evergreen revolution where food security is achieved in a sustainable manner<\/span><\/p>\n<p style=\"text-align: justify;\"><em><span style=\"color: #800000;\">Actualmente nos encontramos en disposici\u00f3n de tratar de adaptar nuestras plantas de cultivo para seleccionar comunidades microbianas beneficiosas que eviten tener que a\u00f1adir insumos qu\u00edmicos. Junto con un cuidadoso manejo del suelo y otros avances cient\u00edficos, las plantas de cultivo se asociaran con comunidades microbianas de forma tan eficiente como para que logremos una nueva revoluci\u00f3n siempre verde, que permite\u00a0 lograr una seguridad alimentaria sostenible<\/span>.<\/em><\/p>\n<p style=\"text-align: justify;\"><strong>Algunos post previos sobre los microrganismos del Suelo<\/strong><\/p>\n<p style=\"text-align: justify;\"><a title=\"Enlace permanente: Microorganismos Eficientes o Efectivos (EM) y Rehabilitaci\u00f3n de Suelos\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/03\/02\/137556\">Microorganismos Eficientes o Efectivos (EM) y Rehabilitaci\u00f3n de Suelos<\/a><\/p>\n<p style=\"text-align: justify;\"><a title=\"Enlace permanente: Microorganismos del Suelo y Predicciones del Calentamiento clim\u00e1tico\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2015\/05\/18\/146066\">Microorganismos del Suelo y Predicciones del Calentamiento clim\u00e1tico<\/a><\/p>\n<p style=\"text-align: justify;\"><a title=\"Enlace permanente: Microorganismos del Suelo y Microbioma Humano \u00bfCu\u00e1l es la relaci\u00f3n?\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2014\/05\/26\/144417\">Microorganismos del Suelo y Microbioma Humano \u00bfCu\u00e1l es la relaci\u00f3n?<\/a><\/p>\n<p style=\"text-align: justify;\"><a title=\"Enlace permanente: La Extraordinaria Gen\u00e9tica de los Microorganismos del Suelo\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/04\/27\/135838\">La Extraordinaria Gen\u00e9tica de los Microorganismos del Suelo<\/a><\/p>\n<p style=\"text-align: justify;\"><a title=\"Enlace permanente: Los Microorganismos del suelo y su Inmensa Diversidad: Sobre Bacterias, Hongos, Arqueas y Virus\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2008\/05\/02\/90691\">Los Microorganismos del suelo y su Inmensa Diversidad: Sobre Bacterias, Hongos, Arqueas y Virus<\/a><\/p>\n<p style=\"text-align: justify;\"><a title=\"Enlace permanente: Lluvia de Microorganismos Pat\u00f3genos: Del Suelo a la Atm\u00f3sfera y de la Atm\u00f3sfera al Suelo\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/11\/13\/139302\">Lluvia de Microorganismos Pat\u00f3genos: Del Suelo a la Atm\u00f3sfera y de la Atm\u00f3sfera al Suelo<\/a><\/p>\n<p style=\"text-align: justify;\"><a title=\"Enlace permanente: La respiraci\u00f3n de los microorganismos del suelo y el cambio clim\u00e1tico\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/06\/15\/136183\">La respiraci\u00f3n de los microorganismos del suelo y el cambio clim\u00e1tico<\/a><\/p>\n<p style=\"text-align: justify;\"><strong>Algunos post previos sobre agricultura org\u00e1nica, ecol\u00f3gica y la convencional fruto de la Revoluci\u00f3n verde<\/strong><\/p>\n<p style=\"text-align: justify;\"><a title=\"Enlace permanente: Agricultura Ecol\u00f3gica y Agricultura Tradicional: un Debate Viciado\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/12\/21\/137288\"><span style=\"font-family: Calibri; font-size: medium;\">Agricultura Ecol\u00f3gica y Agricultura Tradicional: un Debate Viciado<\/span><\/a><\/p>\n<p style=\"text-align: justify;\"><a title=\"Enlace permanente: Agricultura Ecol\u00f3gica en un Mundo Globalizado: La Percepci\u00f3n de un Docente\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2008\/02\/18\/84747\"><span style=\"font-family: Calibri; font-size: medium;\">Agricultura Ecol\u00f3gica en un Mundo Globalizado: La Percepci\u00f3n de un Docente<\/span><\/a><\/p>\n<p style=\"text-align: justify;\"><a title=\"Enlace permanente: Agricultura Ecol\u00f3gica versus Agricultura de Conservaci\u00f3n\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/03\/27\/135850\"><span style=\"font-family: Calibri; font-size: medium;\">Agricultura Ecol\u00f3gica versus Agricultura de Conservaci\u00f3n<\/span><\/a><\/p>\n<p style=\"text-align: justify;\"><a title=\"Enlace permanente: Granjas Verticales e Hidropon\u00eda Org\u00e1nica: suelos, etiquetas y certificaciones de los productos org\u00e1nicos y ecol\u00f3gicos (ocultando al consumidor la calidad de los alimentos)\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2016\/02\/10\/146995\"><span style=\"font-family: Calibri; font-size: medium;\">Granjas Verticales e Hidropon\u00eda Org\u00e1nica: suelos, etiquetas y certificaciones de los productos org\u00e1nicos y ecol\u00f3gicos (ocultando al consumidor la calidad de los alimentos)<\/span><\/a><\/p>\n<p style=\"text-align: justify;\"><a title=\"Enlace permanente: Monsanto versus Avaaz: Lobis agro-industriales contra la agricultura campesina y la seguridad alimentaria\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2014\/03\/04\/144194\"><span style=\"font-family: Calibri; font-size: medium;\">Monsanto versus Avaaz: Lobis agro-industriales contra la agricultura campesina y la seguridad alimentaria<\/span><\/a><\/p>\n<p style=\"text-align: justify;\"><a title=\"Enlace permanente: Guerra sucias entre cient\u00edficos: Ideolog\u00eda e intereses contra la objetividad cient\u00edfica (los organismos transg\u00e9nicos una vez m\u00e1s a la palestra)\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/07\/02\/142842\"><span style=\"font-family: Calibri; font-size: medium;\">Guerra sucias entre cient\u00edficos: Ideolog\u00eda e intereses contra la objetividad cient\u00edfica (los organismos transg\u00e9nicos una vez m\u00e1s a la palestra)<\/span><\/a><\/p>\n<p style=\"text-align: justify;\"><a title=\"Enlace permanente: Glifosato, Transg\u00e9nicos, Resistencia a Pesticidas  y C\u00e1ncer\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2015\/12\/02\/147183\"><span style=\"font-family: Calibri; font-size: medium;\">Glifosato, Transg\u00e9nicos, Resistencia a Pesticidas y C\u00e1ncer<\/span><\/a><\/p>\n<p style=\"text-align: justify;\"><a title=\"Enlace permanente: La Agricultura Moderna: Alimento y Veneno para el Hombre y la Biosfera\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/03\/29\/135856\"><span style=\"font-family: Calibri; font-size: medium;\">La Agricultura Moderna: Alimento y Veneno para el Hombre y la Biosfera<\/span><\/a><\/p>\n<p style=\"text-align: justify;\"><a title=\"Enlace permanente: Agricultura Ecol\u00f3gica versus Agricultura de Conservaci\u00f3n\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/03\/27\/135850\"><span style=\"font-family: Calibri; font-size: medium;\">Agricultura Ecol\u00f3gica versus Agricultura de Conservaci\u00f3n<\/span><\/a><\/p>\n<p style=\"text-align: justify;\"><a title=\"Enlace permanente: \" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2008\/10\/27\/105029\"><span style=\"font-family: Calibri; font-size: medium;\">\u201cPueblos Ind\u00edgenas\u201d Los Desheredados de Latinoam\u00e9rica<\/span><\/a><\/p>\n<p style=\"text-align: justify;\"><a title=\"Enlace permanente: Efectos de la agricultura sin labranza sobre el agua del suelo en climas fr\u00edos y \u00e1reas de monta\u00f1a\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/04\/15\/142710\"><span style=\"font-family: Calibri; font-size: medium;\">Efectos de la agricultura sin labranza sobre el agua del suelo en climas fr\u00edos y \u00e1reas de monta\u00f1a<\/span><\/a><\/p>\n<p style=\"text-align: justify;\"><a title=\"Enlace permanente: Tecnolog\u00edas para la Contaminaci\u00f3n: Biosfera Contaminada, Edafosfera Contaminada, Hidrosfera Contaminada, Atm\u00f3sfera Contaminada, Alimentos Contaminados\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/04\/24\/140402\"><span style=\"font-family: Calibri; font-size: medium;\">Tecnolog\u00edas para la Contaminaci\u00f3n: Biosfera Contaminada, Edafosfera Contaminada, Hidrosfera Contaminada, Atm\u00f3sfera Contaminada, Alimentos Contaminados<\/span><\/a><\/p>\n<p style=\"text-align: justify;\"><a title=\"Enlace permanente: Reciclaje de Residuos S\u00f3lidos Urbanos y Sus Continuos Fraudes\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2014\/08\/25\/145169\"><span style=\"font-family: Calibri; font-size: medium;\">Reciclaje de Residuos S\u00f3lidos Urbanos y Sus Continuos Fraudes<\/span><\/a><\/p>\n<p style=\"text-align: justify;\"><a title=\"Enlace permanente: Lo que los Cient\u00edficos defienden y a veces la realidad desmiente: Divulgaci\u00f3n y Cultura Cient\u00edfica\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/04\/16\/144119\"><span style=\"font-family: Calibri; font-size: medium;\">Lo que los Cient\u00edficos defienden y a veces la realidad desmiente: Divulgaci\u00f3n y Cultura Cient\u00edfica<\/span><\/a><\/p>\n<p style=\"text-align: justify;\"><a title=\"Enlace permanente: Suelos y Compost: reservorios de la Gripe Aviar H5N1\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/04\/08\/142688\"><span style=\"font-family: Calibri; font-size: medium;\">Suelos y Compost: reservorios de la Gripe Aviar H5N1<\/span><\/a><\/p>\n<p style=\"text-align: justify;\"><a title=\"Enlace permanente: Tecnolog\u00edas para la Contaminaci\u00f3n: Biosfera Contaminada, Edafosfera Contaminada, Hidrosfera Contaminada, Atm\u00f3sfera Contaminada, Alimentos Contaminados\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/04\/24\/140402\"><span style=\"font-family: Calibri; font-size: medium;\">Tecnolog\u00edas para la Contaminaci\u00f3n: Biosfera Contaminada, Edafosfera Contaminada, Hidrosfera Contaminada, Atm\u00f3sfera Contaminada, Alimentos Contaminados<\/span><\/a><\/p>\n<p style=\"text-align: justify;\"><a title=\"Enlace permanente: Tecnolog\u00edas para la Contaminaci\u00f3n: Biosfera Contaminada, Edafosfera Contaminada, Hidrosfera Contaminada, Atm\u00f3sfera Contaminada, Alimentos Contaminados\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/04\/24\/140402\"><span style=\"font-family: Calibri; font-size: medium;\">Tecnolog\u00edas para la Contaminaci\u00f3n: Biosfera Contaminada, Edafosfera Contaminada, Hidrosfera Contaminada, Atm\u00f3sfera Contaminada, Alimentos Contaminados<\/span><\/a><\/p>\n<p style=\"text-align: justify;\"><a title=\"Enlace permanente: Lo que los Cient\u00edficos defienden y a veces la realidad desmiente: Divulgaci\u00f3n y Cultura Cient\u00edfica\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/04\/16\/144119\"><span style=\"font-family: Calibri; font-size: medium;\">Lo que los Cient\u00edficos defienden y a veces la realidad desmiente: Divulgaci\u00f3n y Cultura Cient\u00edfica<\/span><\/a><\/p>\n<p style=\"text-align: justify;\"><a title=\"Enlace permanente: Suelos y Compost: reservorios de la Gripe Aviar H5N1\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/04\/08\/142688\"><span style=\"font-family: Calibri; font-size: medium;\">Suelos y Compost: reservorios de la Gripe Aviar H5N1<\/span><\/a><\/p>\n<p style=\"text-align: justify;\"><a title=\"Enlace permanente: Los Equ\u00edvocos Lenguajes de las Ciencias\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/10\/16\/137140\"><span style=\"font-family: Calibri; font-size: medium;\">Los Equ\u00edvocos Lenguajes de las Ciencias<\/span><\/a><\/p>\n<h3>Im\u00e1genes Relacionadas:<\/h3>","protected":false},"excerpt":{"rendered":"<p>La Nueva Revoluci\u00f3n Verde: Fuente: made for minds La mayor parte de la comunidad cient\u00edfica ya se ha rendido a las evidencias. Hace diez a\u00f1os, cuando comenzamos nuestra andadura en esta bit\u00e1cora, tuvimos que sufrir abundantes\u00a0cr\u00edticas por defender que la Revoluci\u00f3n verde del siglo XX significo comida para aquella \u00e9poca, a costa de secuestrar el futuro de la soberan\u00eda alimentaria en el mundo y degradar la biosfera. Diez a\u00f1os despu\u00e9s, casi ning\u00fan experto lo discute, como tampoco la FAO y la ONU. Se acaba el sucio negocio de los pesticidas, insumos ingentes de fertilizantes e ir tocando los genes de\u2026<\/p>\n","protected":false},"author":26,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0},"categories":[596,594,612,591,599,613,597,587,593,585],"tags":[46781,46887,47815,47814],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":4}},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Futura revoluci\u00f3n verde, sostenibilidad del futuro\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Juan Jos\u00e9 Ib\u00e1\u00f1ez\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2016\/11\/02\/147820\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Un Universo invisible bajo nuestros pies - Los suelos y la vida\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"La Nueva Revoluci\u00f3n Verde del Siglo XXI. Todo Preparado - Un Universo invisible bajo nuestros pies\" \/>\n\t\t<meta property=\"og:description\" content=\"Futura revoluci\u00f3n verde, sostenibilidad del futuro\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2016\/11\/02\/147820\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2016-11-02T17:05:36+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2016-11-02T17:05:36+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/juan.j.marti.14\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"La Nueva Revoluci\u00f3n Verde del Siglo XXI. Todo Preparado - Un Universo invisible bajo nuestros pies\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Futura revoluci\u00f3n verde, sostenibilidad del futuro\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2016\\\/11\\\/02\\\/147820#blogposting\",\"name\":\"La Nueva Revoluci\\u00f3n Verde del Siglo XXI. Todo Preparado - Un Universo invisible bajo nuestros pies\",\"headline\":\"La Nueva Revoluci\\u00f3n Verde del Siglo XXI. Todo Preparado\",\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"http:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/wp-content\\\/blogs.dir\\\/42\\\/files\\\/255\\\/nuena-revolucion-verde.jpg\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2016\\\/11\\\/02\\\/147820\\\/#articleImage\"},\"datePublished\":\"2016-11-02T18:05:36+01:00\",\"dateModified\":\"2016-11-02T18:05:36+01:00\",\"inLanguage\":\"es-ES\",\"commentCount\":1,\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2016\\\/11\\\/02\\\/147820#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2016\\\/11\\\/02\\\/147820#webpage\"},\"articleSection\":\"Biolog\\u00eda y Ecolog\\u00eda del Suelo, Degradaci\\u00f3n de Suelos: Contaminaci\\u00f3n, Degradaci\\u00f3n de Suelos: Salinizaci\\u00f3n y Acidificaci\\u00f3n, Edafolog\\u00eda y Pol\\u00edtica, Etnoedafolog\\u00eda y Conocimiento Campesino, Fertilidad de Suelos y Nutrici\\u00f3n Vegetal, Filosof\\u00eda, Historia y Sociolog\\u00eda de la Edafolog\\u00eda, La Crisis de la Edafolog\\u00eda, P\\u00e9rdida de los Recursos Ed\\u00e1ficos: El Sellado del Suelo, P\\u00e9rdida de los Recursos Ed\\u00e1ficos: La Erosi\\u00f3n, agricultura ecol\\u00f3gica, agricultura org\\u00e1nica, revoluci\\u00f3n verde del siglo XXI, revoluci\\u00f3n verse\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2016\\\/11\\\/02\\\/147820#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/perdida-de-los-recursos-edaficos-la-erosion#listItem\",\"name\":\"P\\u00e9rdida de los Recursos Ed\\u00e1ficos: La Erosi\\u00f3n\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/perdida-de-los-recursos-edaficos-la-erosion#listItem\",\"position\":2,\"name\":\"P\\u00e9rdida de los Recursos Ed\\u00e1ficos: La Erosi\\u00f3n\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/perdida-de-los-recursos-edaficos-la-erosion\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2016\\\/11\\\/02\\\/147820#listItem\",\"name\":\"La Nueva Revoluci\\u00f3n Verde del Siglo XXI. Todo Preparado\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2016\\\/11\\\/02\\\/147820#listItem\",\"position\":3,\"name\":\"La Nueva Revoluci\\u00f3n Verde del Siglo XXI. Todo Preparado\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/perdida-de-los-recursos-edaficos-la-erosion#listItem\",\"name\":\"P\\u00e9rdida de los Recursos Ed\\u00e1ficos: La Erosi\\u00f3n\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#organization\",\"name\":\"Un Universo invisible bajo nuestros pies\",\"description\":\"Los suelos y la vida\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/files\\\/2022\\\/02\\\/logo.png\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2016\\\/11\\\/02\\\/147820\\\/#organizationLogo\",\"width\":217,\"height\":72},\"image\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2016\\\/11\\\/02\\\/147820\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/juan.j.marti.14\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo\",\"name\":\"Juan Jos\\u00e9 Ib\\u00e1\\u00f1ez\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2016\\\/11\\\/02\\\/147820#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/387f3a100385573d8f42ce2a3211fd1c?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Juan Jos\\u00e9 Ib\\u00e1\\u00f1ez\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2016\\\/11\\\/02\\\/147820#webpage\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2016\\\/11\\\/02\\\/147820\",\"name\":\"La Nueva Revoluci\\u00f3n Verde del Siglo XXI. Todo Preparado - Un Universo invisible bajo nuestros pies\",\"description\":\"Futura revoluci\\u00f3n verde, sostenibilidad del futuro\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2016\\\/11\\\/02\\\/147820#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\"},\"datePublished\":\"2016-11-02T18:05:36+01:00\",\"dateModified\":\"2016-11-02T18:05:36+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#website\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/\",\"name\":\"Un Universo invisible bajo nuestros pies\",\"description\":\"Los suelos y la vida\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"La Nueva Revoluci\u00f3n Verde del Siglo XXI. Todo Preparado - Un Universo invisible bajo nuestros pies","description":"Futura revoluci\u00f3n verde, sostenibilidad del futuro","canonical_url":"https:\/\/www.madrimasd.org\/blogs\/universo\/2016\/11\/02\/147820","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2016\/11\/02\/147820#blogposting","name":"La Nueva Revoluci\u00f3n Verde del Siglo XXI. Todo Preparado - Un Universo invisible bajo nuestros pies","headline":"La Nueva Revoluci\u00f3n Verde del Siglo XXI. Todo Preparado","author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author"},"publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#organization"},"image":{"@type":"ImageObject","url":"http:\/\/www.madrimasd.org\/blogs\/universo\/wp-content\/blogs.dir\/42\/files\/255\/nuena-revolucion-verde.jpg","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2016\/11\/02\/147820\/#articleImage"},"datePublished":"2016-11-02T18:05:36+01:00","dateModified":"2016-11-02T18:05:36+01:00","inLanguage":"es-ES","commentCount":1,"mainEntityOfPage":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2016\/11\/02\/147820#webpage"},"isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2016\/11\/02\/147820#webpage"},"articleSection":"Biolog\u00eda y Ecolog\u00eda del Suelo, Degradaci\u00f3n de Suelos: Contaminaci\u00f3n, Degradaci\u00f3n de Suelos: Salinizaci\u00f3n y Acidificaci\u00f3n, Edafolog\u00eda y Pol\u00edtica, Etnoedafolog\u00eda y Conocimiento Campesino, Fertilidad de Suelos y Nutrici\u00f3n Vegetal, Filosof\u00eda, Historia y Sociolog\u00eda de la Edafolog\u00eda, La Crisis de la Edafolog\u00eda, P\u00e9rdida de los Recursos Ed\u00e1ficos: El Sellado del Suelo, P\u00e9rdida de los Recursos Ed\u00e1ficos: La Erosi\u00f3n, agricultura ecol\u00f3gica, agricultura org\u00e1nica, revoluci\u00f3n verde del siglo XXI, revoluci\u00f3n verse"},{"@type":"BreadcrumbList","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2016\/11\/02\/147820#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo#listItem","position":1,"name":"Home","item":"https:\/\/www.madrimasd.org\/blogs\/universo","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/perdida-de-los-recursos-edaficos-la-erosion#listItem","name":"P\u00e9rdida de los Recursos Ed\u00e1ficos: La Erosi\u00f3n"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/perdida-de-los-recursos-edaficos-la-erosion#listItem","position":2,"name":"P\u00e9rdida de los Recursos Ed\u00e1ficos: La Erosi\u00f3n","item":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/perdida-de-los-recursos-edaficos-la-erosion","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2016\/11\/02\/147820#listItem","name":"La Nueva Revoluci\u00f3n Verde del Siglo XXI. Todo Preparado"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2016\/11\/02\/147820#listItem","position":3,"name":"La Nueva Revoluci\u00f3n Verde del Siglo XXI. Todo Preparado","previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/perdida-de-los-recursos-edaficos-la-erosion#listItem","name":"P\u00e9rdida de los Recursos Ed\u00e1ficos: La Erosi\u00f3n"}}]},{"@type":"Organization","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#organization","name":"Un Universo invisible bajo nuestros pies","description":"Los suelos y la vida","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/","logo":{"@type":"ImageObject","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2016\/11\/02\/147820\/#organizationLogo","width":217,"height":72},"image":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2016\/11\/02\/147820\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/juan.j.marti.14"]},{"@type":"Person","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo","name":"Juan Jos\u00e9 Ib\u00e1\u00f1ez","image":{"@type":"ImageObject","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2016\/11\/02\/147820#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/387f3a100385573d8f42ce2a3211fd1c?s=96&d=mm&r=g","width":96,"height":96,"caption":"Juan Jos\u00e9 Ib\u00e1\u00f1ez"}},{"@type":"WebPage","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2016\/11\/02\/147820#webpage","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/2016\/11\/02\/147820","name":"La Nueva Revoluci\u00f3n Verde del Siglo XXI. Todo Preparado - Un Universo invisible bajo nuestros pies","description":"Futura revoluci\u00f3n verde, sostenibilidad del futuro","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#website"},"breadcrumb":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2016\/11\/02\/147820#breadcrumblist"},"author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author"},"creator":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author"},"datePublished":"2016-11-02T18:05:36+01:00","dateModified":"2016-11-02T18:05:36+01:00"},{"@type":"WebSite","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#website","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/","name":"Un Universo invisible bajo nuestros pies","description":"Los suelos y la vida","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Un Universo invisible bajo nuestros pies - Los suelos y la vida","og:type":"article","og:title":"La Nueva Revoluci\u00f3n Verde del Siglo XXI. Todo Preparado - Un Universo invisible bajo nuestros pies","og:description":"Futura revoluci\u00f3n verde, sostenibilidad del futuro","og:url":"https:\/\/www.madrimasd.org\/blogs\/universo\/2016\/11\/02\/147820","og:image":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png","og:image:secure_url":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png","article:published_time":"2016-11-02T17:05:36+00:00","article:modified_time":"2016-11-02T17:05:36+00:00","article:publisher":"https:\/\/www.facebook.com\/juan.j.marti.14","twitter:card":"summary","twitter:title":"La Nueva Revoluci\u00f3n Verde del Siglo XXI. Todo Preparado - Un Universo invisible bajo nuestros pies","twitter:description":"Futura revoluci\u00f3n verde, sostenibilidad del futuro","twitter:image":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png"},"aioseo_meta_data":{"post_id":"147820","title":"","description":"Futura revoluci\u00f3n verde, sostenibilidad del futuro","keywords":[{"label":"Futura revoluci\u00f3n verde","value":"Futura revoluci\u00f3n verde"},{"label":"sostenibilidad del futuro","value":"sostenibilidad del futuro"}],"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":null,"isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","tabs":null,"priority":null,"frequency":null,"local_seo":null,"created":"2022-06-03 13:32:17","updated":"2026-05-26 18:41:49","limit_modified_date":false,"ai":null,"breadcrumb_settings":null,"seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/perdida-de-los-recursos-edaficos-la-erosion\" title=\"P\u00e9rdida de los Recursos Ed\u00e1ficos: La Erosi\u00f3n\">P\u00e9rdida de los Recursos Ed\u00e1ficos: La Erosi\u00f3n<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tLa Nueva Revoluci\u00f3n Verde del Siglo XXI. Todo Preparado\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.madrimasd.org\/blogs\/universo"},{"label":"P\u00e9rdida de los Recursos Ed\u00e1ficos: La Erosi\u00f3n","link":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/perdida-de-los-recursos-edaficos-la-erosion"},{"label":"La Nueva Revoluci\u00f3n Verde del Siglo XXI. Todo Preparado","link":"https:\/\/www.madrimasd.org\/blogs\/universo\/2016\/11\/02\/147820"}],"_links":{"self":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts\/147820"}],"collection":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/comments?post=147820"}],"version-history":[{"count":7,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts\/147820\/revisions"}],"predecessor-version":[{"id":148613,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts\/147820\/revisions\/148613"}],"wp:attachment":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/media?parent=147820"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/categories?post=147820"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/tags?post=147820"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}