{"id":149066,"date":"2018-07-20T15:14:43","date_gmt":"2018-07-20T14:14:43","guid":{"rendered":"http:\/\/www.madrimasd.org\/blogs\/universo\/?p=149066"},"modified":"2018-07-20T15:14:43","modified_gmt":"2018-07-20T14:14:43","slug":"el-carbono-labilsoluble-de-los-suelos-y-sedimentos-de-las-llanuras-de-inundacion-y-otros-habitats-encharcados-como-marismas-y-manglares","status":"publish","type":"post","link":"https:\/\/www.madrimasd.org\/blogs\/universo\/2018\/07\/20\/149066","title":{"rendered":"El carbono l\u00e1bil\/soluble de los suelos y sedimentos de las llanuras de inundaci\u00f3n y otros h\u00e1bitats encharcados como marismas y manglares"},"content":{"rendered":"<p align=\"center\"><img decoding=\"async\" class=\"ngg-singlepic ngg-center\" src=\"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-content\/blogs.dir\/42\/files\/818\/llanura-inudacion-colombia.jpg\" alt=\"llanura-inudacion-colombia\" \/><\/p>\n<p align=\"center\"><a href=\"http:\/\/www.imeditores.com\/banocc\/caribe\/themes\/miniml\/galeria4caribe.html\"><span style=\"color: #0000ff;\">Llanura de Inundaci\u00f3n en la regi\u00f3n Caribe\u00f1a de Colombia. Fuente en el propio enlace<\/span><\/a><\/p>\n<p style=\"text-align: justify;\" align=\"center\">\u00a0Hoy me voy e sumergir en terrenos pantanosos desde dos puntos de vista. El primero deviene en que la nota de prensa que vamos a \u00ab\u00bfexplicar?\u00bb en este post nos informa acerca de <span style=\"color: #3366ff;\"><strong>la din\u00e1mica del carbono de suelos y sedimentos que por estar encharcados ralentizan la descomposici\u00f3n de la materia org\u00e1nica que contienen, por los que suele acumularse all\u00ed<\/strong>, <strong>en donde el azufre desempe\u00f1a una funci\u00f3n importante o vital para el metabolismo microbiano<\/strong><\/span>. Se trata de ambientes en los que a menudo abundan los denominados <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/02\/02\/138188\"><span style=\"color: #0000ff;\">Fluvisoles ti\u00f3nicos: Suelos \u00c1cido Sulfatados<\/span><\/a>. Mi segunda ci\u00e9naga, ya muy personal, estriba en que la bioqu\u00edmica del suelo que utilic\u00e9 en\u00a0mi paleol\u00edtico cient\u00edfico (inicios de la carrera profesional), ha pasado a ser patrimonio hist\u00f3rico de la ciencia. Pero si me atrevo a decir que el estudio en cuesti\u00f3n compete a lo que se denomina <a href=\"http:\/\/www.soilace.com\/pdf\/pon2008\/d26\/Cas\/04_GAlmendros.pdf\"><span style=\"color: #0000ff;\">carbono soluble, m\u00e1s o menos equivalente al l\u00e1bil<\/span><\/a>, si bien algunos expertos no estar\u00e1n de acuerdo. No obstante el <a href=\"http:\/\/www.mncn.csic.es\/Menu\/Investigacin\/Departamentosdeinvestigacin\/Biogeoquimica\/GONZALOALMENDROSMARTIN\/seccion=1382&amp;idioma=es_ES.do\"><span style=\"color: #0000ff;\">Dr. Humus<\/span><\/a> as\u00ed me lo ha hecho saber. \u00a0En consecuencia ser\u00e9 breve con vistas a no divagar y hundirme, m\u00e1s aun si cabe, en el fango de la ignominia cient\u00edfica.<\/p>\n<p style=\"text-align: justify;\">\u00a0Cient\u00edficos de la Universidad de Stanford han llevado a cabo un estudio sobre la <span style=\"color: #3366ff;\"><strong>din\u00e1mica del carbono en llanuras de inundaci\u00f3n como h\u00e1bitats representativos de los ambientes encharcados, con escasa o nula concentraciones de ox\u00edgeno<\/strong><\/span>. Es bien sabido que<span style=\"color: #3366ff;\"> <strong>en estos ambientes<\/strong> <\/span>la actividad microbiana es baja y la descomposici\u00f3n de la materia org\u00e1nica lenta, por lo que<span style=\"color: #3366ff;\"> <strong>los suelos tienden a actuar como<\/strong> <\/span>sumideros o <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2015\/11\/09\/146304\"><span style=\"color: #0000ff;\">secuestradores de carbono<\/span><\/a>. Para tales sitios, en conocido desde hace mucho tiempo que la <span style=\"color: #3366ff;\"><strong>actividad microbiana, a falta de ox\u00edgeno, echa mano del azufre<\/strong><\/span>, lo cual es advertido en el terreno por la presencia de minerales ricos en este elemento qu\u00edmico. Empero seg\u00fan estos bioqu\u00edmicos y microbi\u00f3logos: \u201ctal<em> carbono subterr\u00e1neo no permanece necesariamente bajo tierra a largo plazo. Al ser soluble en agua, el carbono puede filtrarse en las v\u00edas fluviales ricas en ox\u00edgeno, donde los microbios lo consumen f\u00e1cilmente<\/em><span style=\"color: #3366ff;\">\u201d. <\/span><span style=\"color: #000000;\"><span style=\"color: #3366ff;\"><strong>En otras<\/strong> alabras, al parecer<\/span>, <\/span><strong><span style=\"color: #3366ff;\">los materiales org\u00e1nicos solubles y no utilizados pueden migrar f\u00e1cilmente a una v\u00eda acu\u00e1tica oxigenada en donde fluyen, y se descomponen ya m\u00e1s f\u00e1cilmente, desencadenando floraciones de algas y otros problemas relacionados con la calidad de las aguas, finalizando en la atm\u00f3sfera<\/span><\/strong>. En otras palabras lo que nos \u00bfdesvelan? Los autores del estudio es que, en h\u00e1bitats encharcados de esta clase, el <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2006\/04\/19\/18983\"><span style=\"color: #0000ff;\">secuestro de carbono es menor que el que se pensaba, relacion\u00e1ndolo inmediatamente con el cambio clim\u00e1tico<\/span><\/a>, como suele ser habitual, venga o no venga a cuento. Os dejo pues con la noticia traducida (por Google, esta vez sin mi \u00a1sabia! revisi\u00f3n, por lo que pod\u00e9is taparos las narices, como cuando est\u00e1is delante de los ambientes en cuesti\u00f3n en donde os deleita ese hediondo hedor que desprenden los \u00a0denominados <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/02\/02\/138188\"><span style=\"color: #0000ff;\">Fluvisoles ti\u00f3nicos (Suelos \u00c1cido Sulfatados<\/span><\/a>). Os a\u00f1ado otros fragmentos de textos de libre acceso en Internet, que pueden ayudaros a entender los tipos de carbono involucrados y algunas cosillas que os aliviaran a la hora de interpretar el texto, si atesor\u00e1is los mismos precarios conocimientos que este impresentable bloguero (poco, o nada). La raz\u00f3n es que me acaban de operar ce cataratas en los ojos, por lo que adem\u00e1s de perder neuronas tambi\u00e9n visi\u00f3n.<\/p>\n<p><strong><span style=\"color: #008000;\">Juan Jos\u00e9 Ib\u00e1\u00f1ez<\/span><\/strong><\/p>\n<p><span style=\"color: #800000;\"><em>Continua\u2026\u2026.<\/em><\/span><\/p>\n<p><!--more--><span style=\"color: #0000ff;\"><a href=\"http:\/\/www.spacedaily.com\/reports\/Shunned_by_microbes_organic_carbon_can_resist_breakdown_in_underground_environments_999.html\"><strong>Shunned by microbes, organic carbon can resist breakdown in underground environments<\/strong><\/a><strong><br \/>\n<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\">by Staff Writers; Stanford CA (SPX) May 02, 2017<\/p>\n<p style=\"text-align: justify;\"><strong>The soils and sediments beneath our feet can contain an astonishing amount of carbon &#8211; more than in all of the world&#8217;s plants and the atmosphere combined &#8211; and represents a significant potential source of the greenhouse gas carbon dioxide<\/strong>.<\/p>\n<p style=\"text-align: justify;\">In a new study, Stanford scientists <strong>have uncovered a previously unknown mechanism that explains why microbes sometimes fail to break down all the plant and animal matter, leaving carbon underfoot<\/strong>. Understanding where, and how long, this <strong>buried organic matter <\/strong><strong>lingers is crucial for scientists and policymakers to better predict and respond to climate change<\/strong>.<\/p>\n<p style=\"text-align: justify;\">\u00ab<strong>Our picture of how organic matter is broken down in soils and sediments is incomplete<\/strong>,\u00bb said study lead author Kristin Boye, an associate staff scientist at the Stanford Synchrotron Radiation Lightsource at the SLAC National Accelerator Laboratory and former postdoctoral scholar at Stanford&#8217;s School of Earth, Energy and Environmental Sciences. \u00ab<strong>With this study, we are gaining new insights into the <span style=\"text-decoration: underline;\">mechanisms of carbon preservation in low- or no-oxygen subterranean environments<\/span><\/strong>.\u00bb<\/p>\n<p style=\"text-align: justify;\"><strong>In oxygen-starved places such as marshes and in floodplains, microorganisms do not equally break down all of the available organic matter, the study shows<\/strong>. <strong>Instead, carbon compounds that do not provide enough energy to be worthwhile for microorganisms to degrade end up accumulating. <\/strong>This passed-over carbon, however, does not necessarily stay locked away below ground in the long run. <strong>Being water soluble, the carbon can seep into nearby oxygen-rich waterways, where microbes readily consume it.<\/strong><strong><\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>To date, models of local ecosystems and broader climate change have failed <\/strong><strong>to take into account this newfound carbon preservation mechanism<\/strong>, having focused chiefly on microbial enzymes and the availability of other elements for organic matter breakdown.<\/p>\n<p style=\"text-align: justify;\">\u00ab<strong>Soils and sediments are a huge and dynamic reservoir of carbon<\/strong>,\u00bb said study senior author Scott Fendorf, a professor of soil biogeochemistry at Stanford Earth. \u00abThat&#8217;s why we worry about turnover times here with regard to how fast organic carbon is degraded and released as carbon dioxide into the atmosphere.\u00bb<\/p>\n<p style=\"text-align: justify;\"><strong>Tracking the fate of the carbon<br \/>\n<\/strong>For the new study, published in Nature Geoscience, the research team collected <strong>core samples of buried sediments from four floodplains<\/strong> in the upper Colorado River Basin in the states of Colorado and New Mexico.<\/p>\n<p style=\"text-align: justify;\"><strong>The approximately 3-foot-long, column-shaped samples went deep enough to reach oxygen-starved layers where microbes must switch from doing the microbial equivalent of breathing oxygen to breathing sulfur<\/strong>. In either case, <strong>the microbes combine oxygen or sulfur with carbon-based food to produce energy and release either carbon dioxide or sulfur dioxide into the atmosphere<\/strong>. (<strong>That sulfur dioxide is responsible for the distinctive smell of oxygen-poor wetlands.<\/strong>)<\/p>\n<p style=\"text-align: justify;\">To identify where in the sediment samples microbes had made the switch, the researchers turned to the Stanford Synchrotron Radiation Lightsource facility. The synchrotron machine generates extremely bright X-ray light that, when shone upon the samples, generates a signal revealing the chemistry of the sulfur. <strong>The presence of sulfide minerals indicates where the microbes began making use of sulfur alongside carbon to power their biochemical machinery<\/strong>.<\/p>\n<p style=\"text-align: justify;\">The question was whether the switch to sulfur influenced the carbon sources the microbes ate or left behind. To find out, the researchers relied on unique instrumentation and collaborations within the Environmental Molecular Sciences Laboratory at the Pacific Northwest National Laboratory in Richmond, Washington. With the aid of a very strong magnet, an instrument called a mass spectrometer at the lab <strong>characterized the water-soluble organic material<\/strong>.<\/p>\n<p style=\"text-align: justify;\">The tests found that, <strong>in contrast to the layers where oxygen was available, leftover carbon compounds in the sediment samples where sulfur had been used for respiration were mostly of the sort that requires more energy to degrade than would be liberated through the degradation itself. Of no use, then, to growing microbes, these carbon compounds had remained within the deeper sediment layers<\/strong>.<\/p>\n<p style=\"text-align: justify;\"><strong>Honing models of the carbon cycle<br \/>\n<\/strong><strong>Floodplains, like those sampled in the study, rank among the most common areas globally for the internment of plant and animal matter by water-borne sediments. The oxygen-poor conditions created underground there are known to sequester carbon, but as the study suggests, partly for reasons previously unrecognized and with unforeseen consequences<\/strong>.<\/p>\n<p style=\"text-align: justify;\">For such flood-prone, low-lying areas are by definition close to waterways. <strong>Soluble, unused organic material can migrate quite easily into an aerated waterway for subsequent breakdown, triggering algae blooms and other water quality issues while also leading to carbon dioxide production<\/strong>.<\/p>\n<p style=\"text-align: justify;\">Models of how living organisms, the ground, bodies of water and the atmosphere recycle carbon will increasingly need to incorporate key nuances, like the preservation mechanism described in the new Stanford study, in order to inform scientists&#8217; understanding as well as policymakers&#8217; decisions.<\/p>\n<p style=\"text-align: justify;\">\u00abGetting the constraints right on what really controls the processes of carbon breakdown is essential,\u00bb said Fendorf. \u00abThat&#8217;s what our study helps illuminate.\u00bb<\/p>\n<p style=\"text-align: justify;\">Other co-authors on the <strong>study, titled \u00abThermodynamically controlled preservation of organic carbon in floodplains,\u00bb<\/strong> include Vincent Noel, Sharon Bone and John Bargar of the SLAC National Accelerator Laboratory; Malak Tfaily of the Pacific Northwest National Laboratory; and Kenneth Williams of the Lawrence Berkeley National Laboratory. Funding was provided by the U.S. Department of Energy, the Office of Biological and Environmental Research, the SLAC National Accelerator Laboratory and the Lawrence Berkeley National Laboratory.<\/p>\n<h2 style=\"text-align: justify;\"><span style=\"color: #800000;\"><strong>La decomposic\u00f3n de la materia org\u00e1nica en los suelos y los sedimentos es incompleta<\/strong> (..).<\/span><\/h2>\n<p style=\"text-align: justify;\">\u00a0Con este estudio, estamos alcanzando nuevas perspectivas sobre los mecanismos de preservaci\u00f3n del carbono <strong>en ambientes subterr\u00e1neos bajos o sin ox\u00edgeno<\/strong>\u00ab.<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000; font-family: Times New Roman;\"><br \/>\n<\/span> <strong>En los lugares que carecen de ox\u00edgeno, como <\/strong><strong>los pantanos y en las planicies de inundaci\u00f3n<\/strong><strong>, <\/strong><strong>los microorganismos no degradan igualmente toda la materia org\u00e1nica disponible<\/strong>, seg\u00fan el estudio. <strong>En su lugar, los compuestos de carbono que no proporcionan suficiente energ\u00eda para que valga la pena que los microorganismos se degraden acaban acumul\u00e1ndose. <\/strong><strong>Sin embargo, este carbono pasado no permanece necesariamente bajo tierra a largo plazo. Al ser soluble en agua, el carbono puede filtrarse en las v\u00edas fluviales ricas en ox\u00edgeno, donde los microbios la consumen f\u00e1cilmente<\/strong>.<br \/>\n<strong>Hasta la fecha, los modelos de ecosistemas locales y el cambio clim\u00e1tico m\u00e1s amplio no han tenido en cuenta<\/strong> <strong>este nuevo mecanismo de preservaci\u00f3n del carbono, habi\u00e9ndose concentrado principalmente en las enzimas microbianas y la disponibilidad de otros elementos para la degradaci\u00f3n de la materia org\u00e1nica<\/strong>.<\/p>\n<p style=\"text-align: justify;\">\u00ab<strong>Los suelos y los sedimentos son una enorme y din\u00e1mica reserva de carbono<\/strong>\u00ab, dijo Scott Fendorf, autor del estudio, profesor de biogeoqu\u00edmica del suelo en Stanford Earth. \u00abEs por eso que nos preocupamos por los tiempos de rotaci\u00f3n aqu\u00ed con respecto <strong>a indagar la velocidad con que el carbono org\u00e1nico se degrada y libera como di\u00f3xido de carbono en la atm\u00f3sfera<\/strong>\u00ab.<\/p>\n<p style=\"text-align: justify;\"><strong>Seguimiento del destino del carbono<\/strong><\/p>\n<p style=\"text-align: justify;\">Para el nuevo estudio, publicado en Nature Geoscience, el equipo de investigaci\u00f3n recolect\u00f3 <strong>muestras b\u00e1sicas de <\/strong><strong>sedimentos enterrados de cuatro llanuras de inundaci\u00f3n en la cuenca alta del R\u00edo Colorado <\/strong><strong>en los estados de Colorado y <\/strong><strong>Nuevo M\u00e9xico<\/strong>.<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000; font-family: Times New Roman;\"><br \/>\n<\/span> <strong>Las muestras<\/strong> de aproximadamente 3 pies de largo en forma de <strong>columna fueron lo suficientemente profundas como para llegar <\/strong><strong>a las capas con hambre de ox\u00edgeno donde los microbios deben cambiar de hacer el equivalente microbiano de respirar ox\u00edgeno a respirar azufre<\/strong>. En cualquier caso, <strong>los microbios combinan ox\u00edgeno o azufre con alimentos a base de carbono para producir energ\u00eda y liberar di\u00f3xido de carbono o di\u00f3xido de azufre a la atm\u00f3sfera<\/strong>. (<strong>Que el di\u00f3xido de azufre es responsable del olor distintivo de los humedales pobres en ox\u00edgeno<\/strong>.)<\/p>\n<p style=\"text-align: justify;\">Para identificar en qu\u00e9 parte de las muestras de sedimento los microbios hab\u00edan hecho el cambio, los investigadores se dirigieron a la instalaci\u00f3n de Stanford Synchrotron Radiation Lightsource. <strong>La m\u00e1quina de sincrotr\u00f3n<\/strong> genera una luz de rayos X extremadamente brillante que, al brillar sobre las muestras<strong>, genera una se\u00f1al que revela la qu\u00edmica del azufre. <\/strong><strong>La presencia de minerales de sulfuro indica donde los microbios comenzaron a hacer uso de azufre junto al carbono para alimentar su maquinaria bioqu\u00edmica<\/strong>.<\/p>\n<p style=\"text-align: justify;\"><strong>La pregunta era si el cambio al azufre influ\u00eda en las fuentes de carbono que los microbios com\u00edan o dejaban atr\u00e1s<\/strong>. Para averiguar, los investigadores confiaron en la instrumentaci\u00f3n y las colaboraciones \u00fanicas dentro del laboratorio ambiental de las ciencias moleculares en el laboratorio nacional del noroeste pac\u00edfico en Richmond, Washington. Con la ayuda de un im\u00e1n muy fuerte, un instrumento <span style=\"color: #000000;\">llamado<\/span> <strong>espectr\u00f3metro de masas en el laboratorio caracteriz\u00f3 el material org\u00e1nico soluble en agua<\/strong>.<\/p>\n<p style=\"text-align: justify;\">Las pruebas encontraron que<strong>, en contraste con las capas donde el ox\u00edgeno estaba disponible, los restos de compuestos de carbono en las muestras de sedimento donde el azufre se hab\u00eda utilizado para la respiraci\u00f3n eran en su mayor\u00eda del tipo que requiere m\u00e1s energ\u00eda para degradarse que ser\u00eda liberado a trav\u00e9s de la degradaci\u00f3n misma. De no utilizar, entonces, a los microbios en crecimiento, estos compuestos de carbono hab\u00edan permanecido dentro de las capas de sedimentos m\u00e1s profundas<\/strong>.<\/p>\n<p style=\"text-align: justify;\"><strong>Modelos m\u00e1s precisos del ciclo del carbono<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Las planicies de inundaci\u00f3n<\/strong>, como las muestreadas en el estudio, se encuentran entre las \u00e1reas m\u00e1s comunes a nivel mundial para el internamiento de materia vegetal y animal por sedimentos acuosos. Se sabe que <strong>las condiciones pobres en ox\u00edgeno creadas en el subsuelo secuestran carbono, pero como sugiere el estudio, en parte por razones que antes no se hab\u00edan reconocido y con consecuencias imprevistas<\/strong>.<\/p>\n<p style=\"text-align: justify;\"><strong>Para esas zonas propensas a las inundaciones, las zonas bajas est\u00e1n, por definici\u00f3n, cerca de las v\u00edas navegables.<\/strong> <strong>Los materiales org\u00e1nicos solubles y no utilizados pueden migrar f\u00e1cilmente a una v\u00eda acu\u00e1tica airada para su posterior descomposici\u00f3n, desencadenando floraciones de algas y otros problemas de calidad del agua, mientras que tambi\u00e9n conducen a la producci\u00f3n de di\u00f3xido de carbono<\/strong>.<\/p>\n<p style=\"text-align: justify;\"><strong>Los modelos de c\u00f3mo los organismos vivos, el suelo, los cuerpos de agua y la atm\u00f3sfera reciclar\u00e1n carbono tendr\u00e1n cada vez m\u00e1s que incorporar matices clave<\/strong>, como el mecanismo de preservaci\u00f3n descrito en el nuevo estudio de Stanford, para informar la comprensi\u00f3n de los cient\u00edficos y las decisiones de las autoridades.<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><strong>La MOS puede ser protegida de descomposici\u00f3n acelerada mediante<\/strong>: 1) estabilizaci\u00f3n f\u00edsica por la microagregaci\u00f3n, 2) estabilizaci\u00f3n fisico-qu\u00edmica mediante asociaci\u00f3n con part\u00edculas de arcilla, y 3) estabilizaci\u00f3n bioqu\u00edmica mediante la formaci\u00f3n de compuestos altamente recalcitrantes (Six <em>et al., <\/em>2002).<\/span><\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.scielo.cl\/scielo.php?script=sci_arttext&amp;pid=S0718-27912008000100006\"><strong><span style=\"color: #0000ff;\">CARBONO ORG\u00c1NICO Y PROPIEDADES DEL SUELO<\/span><\/strong><\/a><\/p>\n<p style=\"text-align: justify;\"><strong><span style=\"color: #000000;\">Eduardo Mart\u00ednez H.<\/span><\/strong><a href=\"http:\/\/www.scielo.cl\/scielo.php?script=sci_arttext&amp;pid=S0718-27912008000100006#a1\"><strong><sup>1<\/sup><\/strong><\/a><strong><span style=\"color: #000000;\">, Juan Pablo Fuentes E. <\/span><\/strong><a href=\"http:\/\/www.scielo.cl\/scielo.php?script=sci_arttext&amp;pid=S0718-27912008000100006#a2\"><strong><sup>2<\/sup><\/strong><\/a><strong><span style=\"color: #000000;\">, Edmundo Acevedo H.<\/span><\/strong><a href=\"http:\/\/www.scielo.cl\/scielo.php?script=sci_arttext&amp;pid=S0718-27912008000100006#a1\"><strong><sup>1<\/sup><\/strong><\/a><\/p>\n<p style=\"text-align: justify;\"><strong><span style=\"color: #000000;\">FRACCIONES DE CARBONO ORG\u00c1NICO EN EL SUELO<\/span><\/strong><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Se conoce como <\/span><strong>materia org\u00e1nica del suelo (MOS)<\/strong> <span style=\"color: #000000;\">a un conjunto de residuos org\u00e1nicos de origen animal y \/ o vegetal, que est\u00e1n en diferentes etapas de descomposici\u00f3n, y que se acumulan tanto en la superficie como dentro del perfil del suelo (Rosell, 1999). Adem\u00e1s<strong>, incluye una fracci\u00f3n viva, o biota, que participa en la descomposici\u00f3n y transformaci\u00f3n de los residuos org\u00e1nicos<\/strong> (Aguilera, 2000). El COS es el principal elemento que forma parte de la MOS, por esto es com\u00fan que ambos t\u00e9rminos se confundan o se hable indistintamente de uno u otro. Al respecto cabe se\u00f1alar que los m\u00e9todos anal\u00edticos determinan COS, (calcinaci\u00f3n h\u00fameda o seca) y que la MOS se estima a partir del COS multiplicado por factores emp\u00edricos como el de van Benmelen equivalente 1,724 (Jackson, 1964). El factor de transformaci\u00f3n de COS a MOS puede variar entre 1,9 para suelos superficiales y 2,5 para muchos subsuelos (Broadbent, 1953). Como existe una considerable variaci\u00f3n entre diferentes suelos y horizontes en el factor de conversi\u00f3n <strong>COS &#8211; MOS, es preferible informar el valor de COS sin transformar <\/strong>(Allison, 1965).<\/span><\/p>\n<p style=\"text-align: justify;\"><strong>En la materia org\u00e1nica del suelo (MOS) se distingue una fracci\u00f3n l\u00e1bil, disponible como fuente energ\u00e9tica, que mantiene las caracter\u00edsticas qu\u00edmicas de su material de origen<\/strong> <span style=\"color: #000000;\">(hidratos de carbono, ligninas, prote\u00ednas, taninos, \u00e1cidos grasos), <strong>y una fracci\u00f3n h\u00famica, m\u00e1s estable, constituida por<\/strong> \u00e1cidos f\u00falvicos, \u00e1cidos h\u00famicos y huminas (Galantini, 2002, Aguilera, 2000). Cada una de estas fracciones se obtiene por solubilizaci\u00f3n en medios \u00e1cidos o alcalinos. Sin embargo, este tipo de fraccionamiento se encuentra limitado por la presencia de componentes no h\u00famicos extra\u00eddos junto con la fracci\u00f3n h\u00famica y que no pueden ser separados efectivamente mediante esta metodolog\u00eda (Hayes y Clapp, 2001). <strong>Las sustancias h\u00famicas son el principal componente de la MOS y representan, por lo menos el 50% de \u00e9sta<\/strong> (Simpson <em>et al., <\/em>2007). <strong>Las sustancias h\u00famicas son el material org\u00e1nico m\u00e1s abundante del medioambiente terrestre<\/strong> (Hayes y Clapp, 2001). Dentro de la fracci\u00f3n h\u00famica, <strong>las huminas son el componente m\u00e1s abundante. Las huminas incluyen una amplia gama de compuestos qu\u00edmicos insolubles en medio acuoso y contienen<\/strong>, adem\u00e1s, compuestos no h\u00famicos como largas cadenas de hidrocarburos, esteres, \u00e1cidos y estructuras polares, <strong>que pueden ser de origen microbiano, como polisac\u00e1ridos y glomalina, \u00edntimamente asociados a los minerales del suelo <\/strong>(Hayes y Clapp, 2001). <strong>Las huminas representan m\u00e1s del 50% del COS en suelos minerales (Kononova, 1966) y m\u00e1s del 70 % del COS en sedimentos litificados <\/strong>(Hedges <em>et al., <\/em>1995). En un estudio de un suelo de Irlanda manejado con pradera y trigo en labranza convencional Simpson <em>et al. <\/em>(2007) encontraron <strong>cinco clases de los principales compuestos de las huminas, llamadas: p\u00e9ptidos, especies alif\u00e1ticas, carbohidratos, peptidoglican y lignina<\/strong>\u2026\u2026.<\/span><\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/sjss.universia.net\/article\/view\/172\/fracciones-carbono-organico-labil-actividad-biologica-suelos-origen-volcanico-islas-canarias-\"><strong><em><span style=\"color: #0000ff;\">Spanish Journal of Soil Science<\/span><\/em><\/strong><\/a><strong><em><\/em><\/strong><\/p>\n<p style=\"text-align: justify;\"><strong><em>Fracciones de carbono org\u00e1nico l\u00e1bil y actividad biol\u00f3gica en suelos de origen volc\u00e1nico de las Islas Canarias<\/em><\/strong><em> <\/em><em><span style=\"color: #000000;\">.<\/span><\/em><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #0000ff;\"><em>Cecilia Mar\u00eda Armas Herrera, Carmen Dolores Arbelo Rodr\u00edguez, Juan Luis Mora Hern\u00e1ndez, Antonio Rodr\u00edguez Rodr\u00edguez<\/em><\/span><\/p>\n<p style=\"text-align: justify;\"><strong><span style=\"color: #000000;\">Resumen<\/span><\/strong><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">La medida de la susceptibilidad del carbono org\u00e1nico del suelo (SOC) a la mineralizaci\u00f3n es esencial para predecir la respuesta a corto plazo de los reservorios biosf\u00e9ricos de carbono a los cambios en las condiciones ambientales. En este trabajo abordamos el estudio del <\/span><strong>SOC l\u00e1bil<\/strong> <span style=\"color: #000000;\">(f\u00e1cilmente mineralizable) en suelos volc\u00e1nicos, donde la biodisponibilidad del SOC se ve caracter\u00edsticamente afectada por mecanismos de estabilizaci\u00f3n f\u00edsico-qu\u00edmica propios de estos suelos. Con este fin seleccionamos diez suelos representativos (sobre todo <strong>Andosoles<\/strong>) de los principales h\u00e1bitats naturales (matorral xerof\u00edtico, monteverde y pinar) en las <strong>Islas Canarias<\/strong>, un archipi\u00e9lago de origen volc\u00e1nico. Durante dos a\u00f1os medimos diversas fracciones <\/span><strong><span style=\"color: #000000;\">de SOC a las que se atribuye un distinto grado de biodisponibilidad: carbono soluble en agua en <\/span>muestras frescas de suelo <span style=\"color: #000000;\">(WSC) y en el extracto saturado (WSCse), carbono extra\u00edble en agua caliente (HWC), carbono extra\u00edble con sulfato pot\u00e1sico (PSC), carbono ligado a la biomasa microbiana (MBC), carbono org\u00e1nico particulado (POC), carbono de sustancias h\u00famicas (HSC), y carbono org\u00e1nico total (TOC), y realizamos ensayos de incubaci\u00f3n de las emisiones de CO2. Relacionamos estas medidas con los posibles aportes de carbono procedentes de la hojarasca y las ra\u00edces, y la actividad de enzimas hidrol\u00edticas<\/span><\/strong><span style=\"color: #000000;\"> (CM-celulasa, \u03b2-D-glucosidasa, y deshidrogenasa) implicadas en el ciclado del carbono. La medida in vitro de la mineralizaci\u00f3n en ensayos cortos (10 d\u00edas) se ajust\u00f3 a un modelo cin\u00e9tico simple de primer orden, un procedimiento sencillo que nos permiti\u00f3 obtener no s\u00f3lo una estimaci\u00f3n del SOC m\u00e1s inmediatamente mineralizable, sino tambi\u00e9n de la heterogeneidad de los sustratos consumidos durante la incubaci\u00f3n<\/span><strong><span style=\"color: #000000;\">. <\/span>Los suelos volc\u00e1nicos investigados mostraron una gran riqueza de SOC l\u00e1bil,<\/strong><span style=\"color: #000000;\"> <strong>en los que predominaron los carbohidratos simples procedentes principalmente de aportes org\u00e1nicos radiculares y de restos vegetales no-le\u00f1osos a\u00e9reos. Entre las fracciones f\u00edsico-qu\u00edmicas de SOC analizadas, el HWC<\/strong> (3.1 g kg-1 de promedio a 0-30 cm de profundidad en Andosoles) fue el que mejor se correlacion\u00f3 con el C0 (1,2 g kg-1) y por tanto el que mejor represent\u00f3 el SOC inmediatamente mineralizable. El PSC (0,77 g kg-1), que representa un reservorio de baja biodisponibilidad, se encuentra protegido de la mineralizaci\u00f3n por su adsorci\u00f3n a la al\u00f3fana en Andosoles sil\u00e1ndicos.<\/span><\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.cannabismagazine.es\/digital\/el-carbono-organico-del-suelo\"><span style=\"color: #0000ff;\">La degradaci\u00f3n de materias org\u00e1nicas produce<\/span><\/a><span style=\"color: #000000;\">, <\/span><strong>aproximadamente, entre un 50 y un 75% de todo el CO2 que est\u00e1 presente en la atm\u00f3sfera, otro 5 a 15% se incorpora a la biomasa microbiana y el resto queda parcialmente estabilizado en forma de humus en el suelo<\/strong><span style=\"color: #000000;\">. En todo este proceso las temperaturas elevadas favorecen una mayor p\u00e9rdida hacia la atm\u00f3sfera por lo que en climas mediterr\u00e1neos y tropicales sus aplicaciones deben ser mayores. En climas c\u00e1lidos el porcentaje de materia org\u00e1nica debe ser del 5% mientras que en los m\u00e1s h\u00famedos puede quedarse en un 2%.<\/span><\/p>\n<p style=\"text-align: justify;\">Se habla ya de estos temas en los cap\u00edtulo de Wikipedia \u201c<a href=\"https:\/\/es.wikipedia.org\/wiki\/Carbono_org\u00e1nico_total\"><span style=\"color: #0000ff;\">Carbono org\u00e1nico total<\/span><\/a>\u201d\u00a0 y \u201c<a href=\"https:\/\/es.wikipedia.org\/wiki\/Metabolismo_microbiano#Fermentaci.C3.B3n\"><span style=\"color: #0000ff;\">Metabolismo microbiano<\/span><\/a>\u201d.<\/p>\n<h3>Im\u00e1genes Relacionadas:<\/h3>","protected":false},"excerpt":{"rendered":"<p>Llanura de Inundaci\u00f3n en la regi\u00f3n Caribe\u00f1a de Colombia. Fuente en el propio enlace \u00a0Hoy me voy e sumergir en terrenos pantanosos desde dos puntos de vista. El primero deviene en que la nota de prensa que vamos a \u00ab\u00bfexplicar?\u00bb en este post nos informa acerca de la din\u00e1mica del carbono de suelos y sedimentos que por estar encharcados ralentizan la descomposici\u00f3n de la materia org\u00e1nica que contienen, por los que suele acumularse all\u00ed, en donde el azufre desempe\u00f1a una funci\u00f3n importante o vital para el metabolismo microbiano. Se trata de ambientes en los que a menudo abundan los denominados\u2026<\/p>\n","protected":false},"author":26,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0},"categories":[596,608,603,590,600,595],"tags":[46647,48014,38089,38088,38091,38087,46696],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":4}},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Llanura de Inundaci\u00f3n en la regi\u00f3n Caribe\u00f1a de Colombia. Fuente en el propio enlace Hoy me voy e sumergir en terrenos pantanosos desde dos puntos de vista. El primero deviene en que la nota de prensa que vamos a &quot;\u00bfexplicar?&quot; en este post nos informa acerca de la din\u00e1mica del carbono de suelos y sedimentos\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Juan Jos\u00e9 Ib\u00e1\u00f1ez\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2018\/07\/20\/149066\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Un Universo invisible bajo nuestros pies - Los suelos y la vida\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"El carbono l\u00e1bil\/soluble de los suelos y sedimentos de las llanuras de inundaci\u00f3n y otros h\u00e1bitats encharcados como marismas y manglares - Un Universo invisible bajo nuestros pies\" \/>\n\t\t<meta property=\"og:description\" content=\"Llanura de Inundaci\u00f3n en la regi\u00f3n Caribe\u00f1a de Colombia. Fuente en el propio enlace Hoy me voy e sumergir en terrenos pantanosos desde dos puntos de vista. El primero deviene en que la nota de prensa que vamos a &quot;\u00bfexplicar?&quot; en este post nos informa acerca de la din\u00e1mica del carbono de suelos y sedimentos\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2018\/07\/20\/149066\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2018-07-20T14:14:43+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2018-07-20T14:14:43+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/juan.j.marti.14\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"El carbono l\u00e1bil\/soluble de los suelos y sedimentos de las llanuras de inundaci\u00f3n y otros h\u00e1bitats encharcados como marismas y manglares - Un Universo invisible bajo nuestros pies\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Llanura de Inundaci\u00f3n en la regi\u00f3n Caribe\u00f1a de Colombia. Fuente en el propio enlace Hoy me voy e sumergir en terrenos pantanosos desde dos puntos de vista. El primero deviene en que la nota de prensa que vamos a &quot;\u00bfexplicar?&quot; en este post nos informa acerca de la din\u00e1mica del carbono de suelos y sedimentos\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2018\\\/07\\\/20\\\/149066#blogposting\",\"name\":\"El carbono l\\u00e1bil\\\/soluble de los suelos y sedimentos de las llanuras de inundaci\\u00f3n y otros h\\u00e1bitats encharcados como marismas y manglares - Un Universo invisible bajo nuestros pies\",\"headline\":\"El carbono l\\u00e1bil\\\/soluble de los suelos y sedimentos de las llanuras de inundaci\\u00f3n y otros h\\u00e1bitats encharcados como marismas y manglares\",\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"http:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/wp-content\\\/blogs.dir\\\/42\\\/files\\\/818\\\/llanura-inudacion-colombia.jpg\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2018\\\/07\\\/20\\\/149066\\\/#articleImage\"},\"datePublished\":\"2018-07-20T15:14:43+01:00\",\"dateModified\":\"2018-07-20T15:14:43+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2018\\\/07\\\/20\\\/149066#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2018\\\/07\\\/20\\\/149066#webpage\"},\"articleSection\":\"Biolog\\u00eda y Ecolog\\u00eda del Suelo, Biomasa y Necromasa en los Suelos: Ra\\u00edces y Materia Org\\u00e1nica, Carpeta sobre Paisajes de Suelos y los Suelos en el Paisaje, Componentes, Estructuras y Procesos en los Suelos, Los Suelos las Plantas y la Vegetaci\\u00f3n, Suelos y Cambio Clim\\u00e1tico, cambio clim\\u00e1tico, carbono l\\u00e1bil, carbono soluble, din\\u00e1mica del carbono, emisiones de co2, Llanuras de inundaci\\u00f3n, secuestro de carbono\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2018\\\/07\\\/20\\\/149066#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/componentes-estructuras-y-procesos-en-los-suelos#listItem\",\"name\":\"Componentes, Estructuras y Procesos en los Suelos\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/componentes-estructuras-y-procesos-en-los-suelos#listItem\",\"position\":2,\"name\":\"Componentes, Estructuras y Procesos en los Suelos\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/componentes-estructuras-y-procesos-en-los-suelos\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2018\\\/07\\\/20\\\/149066#listItem\",\"name\":\"El carbono l\\u00e1bil\\\/soluble de los suelos y sedimentos de las llanuras de inundaci\\u00f3n y otros h\\u00e1bitats encharcados como marismas y manglares\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2018\\\/07\\\/20\\\/149066#listItem\",\"position\":3,\"name\":\"El carbono l\\u00e1bil\\\/soluble de los suelos y sedimentos de las llanuras de inundaci\\u00f3n y otros h\\u00e1bitats encharcados como marismas y manglares\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/componentes-estructuras-y-procesos-en-los-suelos#listItem\",\"name\":\"Componentes, Estructuras y Procesos en los Suelos\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#organization\",\"name\":\"Un Universo invisible bajo nuestros pies\",\"description\":\"Los suelos y la vida\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/files\\\/2022\\\/02\\\/logo.png\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2018\\\/07\\\/20\\\/149066\\\/#organizationLogo\",\"width\":217,\"height\":72},\"image\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2018\\\/07\\\/20\\\/149066\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/juan.j.marti.14\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo\",\"name\":\"Juan Jos\\u00e9 Ib\\u00e1\\u00f1ez\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2018\\\/07\\\/20\\\/149066#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/387f3a100385573d8f42ce2a3211fd1c?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Juan Jos\\u00e9 Ib\\u00e1\\u00f1ez\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2018\\\/07\\\/20\\\/149066#webpage\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2018\\\/07\\\/20\\\/149066\",\"name\":\"El carbono l\\u00e1bil\\\/soluble de los suelos y sedimentos de las llanuras de inundaci\\u00f3n y otros h\\u00e1bitats encharcados como marismas y manglares - Un Universo invisible bajo nuestros pies\",\"description\":\"Llanura de Inundaci\\u00f3n en la regi\\u00f3n Caribe\\u00f1a de Colombia. Fuente en el propio enlace Hoy me voy e sumergir en terrenos pantanosos desde dos puntos de vista. El primero deviene en que la nota de prensa que vamos a \\\"\\u00bfexplicar?\\\" en este post nos informa acerca de la din\\u00e1mica del carbono de suelos y sedimentos\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2018\\\/07\\\/20\\\/149066#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\"},\"datePublished\":\"2018-07-20T15:14:43+01:00\",\"dateModified\":\"2018-07-20T15:14:43+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#website\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/\",\"name\":\"Un Universo invisible bajo nuestros pies\",\"description\":\"Los suelos y la vida\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"El carbono l\u00e1bil\/soluble de los suelos y sedimentos de las llanuras de inundaci\u00f3n y otros h\u00e1bitats encharcados como marismas y manglares - Un Universo invisible bajo nuestros pies","description":"Llanura de Inundaci\u00f3n en la regi\u00f3n Caribe\u00f1a de Colombia. Fuente en el propio enlace Hoy me voy e sumergir en terrenos pantanosos desde dos puntos de vista. El primero deviene en que la nota de prensa que vamos a \"\u00bfexplicar?\" en este post nos informa acerca de la din\u00e1mica del carbono de suelos y sedimentos","canonical_url":"https:\/\/www.madrimasd.org\/blogs\/universo\/2018\/07\/20\/149066","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2018\/07\/20\/149066#blogposting","name":"El carbono l\u00e1bil\/soluble de los suelos y sedimentos de las llanuras de inundaci\u00f3n y otros h\u00e1bitats encharcados como marismas y manglares - Un Universo invisible bajo nuestros pies","headline":"El carbono l\u00e1bil\/soluble de los suelos y sedimentos de las llanuras de inundaci\u00f3n y otros h\u00e1bitats encharcados como marismas y manglares","author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author"},"publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#organization"},"image":{"@type":"ImageObject","url":"http:\/\/www.madrimasd.org\/blogs\/universo\/wp-content\/blogs.dir\/42\/files\/818\/llanura-inudacion-colombia.jpg","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2018\/07\/20\/149066\/#articleImage"},"datePublished":"2018-07-20T15:14:43+01:00","dateModified":"2018-07-20T15:14:43+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2018\/07\/20\/149066#webpage"},"isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2018\/07\/20\/149066#webpage"},"articleSection":"Biolog\u00eda y Ecolog\u00eda del Suelo, Biomasa y Necromasa en los Suelos: Ra\u00edces y Materia Org\u00e1nica, Carpeta sobre Paisajes de Suelos y los Suelos en el Paisaje, Componentes, Estructuras y Procesos en los Suelos, Los Suelos las Plantas y la Vegetaci\u00f3n, Suelos y Cambio Clim\u00e1tico, cambio clim\u00e1tico, carbono l\u00e1bil, carbono soluble, din\u00e1mica del carbono, emisiones de co2, Llanuras de inundaci\u00f3n, secuestro de carbono"},{"@type":"BreadcrumbList","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2018\/07\/20\/149066#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo#listItem","position":1,"name":"Home","item":"https:\/\/www.madrimasd.org\/blogs\/universo","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/componentes-estructuras-y-procesos-en-los-suelos#listItem","name":"Componentes, Estructuras y Procesos en los Suelos"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/componentes-estructuras-y-procesos-en-los-suelos#listItem","position":2,"name":"Componentes, Estructuras y Procesos en los Suelos","item":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/componentes-estructuras-y-procesos-en-los-suelos","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2018\/07\/20\/149066#listItem","name":"El carbono l\u00e1bil\/soluble de los suelos y sedimentos de las llanuras de inundaci\u00f3n y otros h\u00e1bitats encharcados como marismas y manglares"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2018\/07\/20\/149066#listItem","position":3,"name":"El carbono l\u00e1bil\/soluble de los suelos y sedimentos de las llanuras de inundaci\u00f3n y otros h\u00e1bitats encharcados como marismas y manglares","previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/componentes-estructuras-y-procesos-en-los-suelos#listItem","name":"Componentes, Estructuras y Procesos en los Suelos"}}]},{"@type":"Organization","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#organization","name":"Un Universo invisible bajo nuestros pies","description":"Los suelos y la vida","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/","logo":{"@type":"ImageObject","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2018\/07\/20\/149066\/#organizationLogo","width":217,"height":72},"image":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2018\/07\/20\/149066\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/juan.j.marti.14"]},{"@type":"Person","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo","name":"Juan Jos\u00e9 Ib\u00e1\u00f1ez","image":{"@type":"ImageObject","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2018\/07\/20\/149066#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/387f3a100385573d8f42ce2a3211fd1c?s=96&d=mm&r=g","width":96,"height":96,"caption":"Juan Jos\u00e9 Ib\u00e1\u00f1ez"}},{"@type":"WebPage","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2018\/07\/20\/149066#webpage","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/2018\/07\/20\/149066","name":"El carbono l\u00e1bil\/soluble de los suelos y sedimentos de las llanuras de inundaci\u00f3n y otros h\u00e1bitats encharcados como marismas y manglares - Un Universo invisible bajo nuestros pies","description":"Llanura de Inundaci\u00f3n en la regi\u00f3n Caribe\u00f1a de Colombia. Fuente en el propio enlace Hoy me voy e sumergir en terrenos pantanosos desde dos puntos de vista. El primero deviene en que la nota de prensa que vamos a \"\u00bfexplicar?\" en este post nos informa acerca de la din\u00e1mica del carbono de suelos y sedimentos","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#website"},"breadcrumb":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2018\/07\/20\/149066#breadcrumblist"},"author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author"},"creator":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author"},"datePublished":"2018-07-20T15:14:43+01:00","dateModified":"2018-07-20T15:14:43+01:00"},{"@type":"WebSite","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#website","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/","name":"Un Universo invisible bajo nuestros pies","description":"Los suelos y la vida","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Un Universo invisible bajo nuestros pies - Los suelos y la vida","og:type":"article","og:title":"El carbono l\u00e1bil\/soluble de los suelos y sedimentos de las llanuras de inundaci\u00f3n y otros h\u00e1bitats encharcados como marismas y manglares - Un Universo invisible bajo nuestros pies","og:description":"Llanura de Inundaci\u00f3n en la regi\u00f3n Caribe\u00f1a de Colombia. Fuente en el propio enlace Hoy me voy e sumergir en terrenos pantanosos desde dos puntos de vista. El primero deviene en que la nota de prensa que vamos a &quot;\u00bfexplicar?&quot; en este post nos informa acerca de la din\u00e1mica del carbono de suelos y sedimentos","og:url":"https:\/\/www.madrimasd.org\/blogs\/universo\/2018\/07\/20\/149066","og:image":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png","og:image:secure_url":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png","article:published_time":"2018-07-20T14:14:43+00:00","article:modified_time":"2018-07-20T14:14:43+00:00","article:publisher":"https:\/\/www.facebook.com\/juan.j.marti.14","twitter:card":"summary","twitter:title":"El carbono l\u00e1bil\/soluble de los suelos y sedimentos de las llanuras de inundaci\u00f3n y otros h\u00e1bitats encharcados como marismas y manglares - Un Universo invisible bajo nuestros pies","twitter:description":"Llanura de Inundaci\u00f3n en la regi\u00f3n Caribe\u00f1a de Colombia. Fuente en el propio enlace Hoy me voy e sumergir en terrenos pantanosos desde dos puntos de vista. El primero deviene en que la nota de prensa que vamos a &quot;\u00bfexplicar?&quot; en este post nos informa acerca de la din\u00e1mica del carbono de suelos y sedimentos","twitter:image":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png"},"aioseo_meta_data":{"post_id":"149066","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":null,"isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","tabs":null,"priority":null,"frequency":null,"local_seo":null,"created":"2022-06-03 16:21:46","updated":"2026-05-26 18:58:49","limit_modified_date":false,"ai":null,"breadcrumb_settings":null,"seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/componentes-estructuras-y-procesos-en-los-suelos\" title=\"Componentes, Estructuras y Procesos en los Suelos\">Componentes, Estructuras y Procesos en los Suelos<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tEl carbono l\u00e1bil\/soluble de los suelos y sedimentos de las llanuras de inundaci\u00f3n y otros h\u00e1bitats encharcados como marismas y manglares\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.madrimasd.org\/blogs\/universo"},{"label":"Componentes, Estructuras y Procesos en los Suelos","link":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/componentes-estructuras-y-procesos-en-los-suelos"},{"label":"El carbono l\u00e1bil\/soluble de los suelos y sedimentos de las llanuras de inundaci\u00f3n y otros h\u00e1bitats encharcados como marismas y manglares","link":"https:\/\/www.madrimasd.org\/blogs\/universo\/2018\/07\/20\/149066"}],"_links":{"self":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts\/149066"}],"collection":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/comments?post=149066"}],"version-history":[{"count":6,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts\/149066\/revisions"}],"predecessor-version":[{"id":149656,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts\/149066\/revisions\/149656"}],"wp:attachment":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/media?parent=149066"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/categories?post=149066"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/tags?post=149066"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}