{"id":149160,"date":"2018-10-15T14:14:22","date_gmt":"2018-10-15T13:14:22","guid":{"rendered":"http:\/\/www.madrimasd.org\/blogs\/universo\/?p=149160"},"modified":"2018-10-15T14:16:21","modified_gmt":"2018-10-15T13:16:21","slug":"las-termitas-del-suelo-y-sus-hongos-simbiontes-el-extraordinario-tandem-para-degradar-rapidamente-los-residuos-lignocelulosicos","status":"publish","type":"post","link":"https:\/\/www.madrimasd.org\/blogs\/universo\/2018\/10\/15\/149160","title":{"rendered":"Las termitas del suelo y sus hongos simbiontes: El extraordinario t\u00e1ndem para degradar r\u00e1pidamente los residuos lignocelul\u00f3sicos"},"content":{"rendered":"<p align=\"center\"><strong>\u00a0<img decoding=\"async\" class=\"ngg-singlepic ngg-center\" src=\"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-content\/blogs.dir\/42\/files\/163\/termitas-hongos-degradacion-lignocelulosa.jpg\" alt=\"termitas-hongos-degradacion-lignocelulosa\" \/><\/strong><\/p>\n<p align=\"center\"><span style=\"color: #0000ff;\">Fuente: Colaje Google im\u00e1genes<\/span><\/p>\n<p style=\"text-align: justify;\">\u00a0Existe una abundante literatura con vistas a<span style=\"color: #3366ff;\"> <strong>obtener bioetanol y otros biocombustibles a partir de los<\/strong><\/span> <a href=\"https:\/\/www.google.es\/search?source=hp&amp;q=degradaci%C3%B3n+de+residuos+lignocelul%C3%B3sicos+biomasa+biocombustibles&amp;oq=degradaci%C3%B3n+de+residuos+lignocelul%C3%B3sicos+biomasa+biocombustibles&amp;gs_l=psy-ab.3...3509.35622.0.38621.76.75.0.0.0.0.119.5439.71j3.75.0....0...1.1.64.psy-ab..1.39.2766.6..0j35i39k1j0i131k1j0i67k1j0i22i30k1j33i160k1j0i13i30k1j0i13k1.53.UtoYlIWjLhc\"><span style=\"color: #0000ff;\">recalcitrantes residuos lignocelul\u00f3sicos<\/span><\/a><strong>. \u00a0<span style=\"color: #3366ff;\">En el suelo, estos son degradados r\u00e1pidamente<\/span><\/strong> y m\u00e1s a\u00fan en presencia de <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/01\/18\/131475\"><span style=\"color: #0000ff;\">ciertos ingenieros del suelo, como lo son las hormigas y termitas<\/span><\/a>. El estudio que os mostramos hoy \u00a0(<a href=\"http:\/\/www.seeddaily.com\/reports\/Termite_gut_holds_a_secret_to_breaking_down_plant_biomass_999.html\"><span style=\"color: #0000ff;\">El intestino de termitas tiene un secreto para descomponer la biomasa vegetal<\/span><\/a>), nos ayuda a conocer como <strong><span style=\"color: #3366ff;\">el sistema simbi\u00f3tico entre las termitas y sus simbiontes digestivos realizan tal labor sin la menor dificultad<\/span><\/strong>. Entender el proceso ayudar\u00eda a <strong><span style=\"color: #3366ff;\">obtener r\u00e1pida, econ\u00f3mica y eficientemente el mentado biocombustible<\/span><\/strong>. Se trata de un tema de candente actualidad a la hora de obtener energ\u00edas limpias y alcanzar lo antes posible un <strong><span style=\"color: #3366ff;\">desarrollo energ\u00e9tico sostenible<\/span><\/strong>. El secreto se encuentra pues en las termitas y sus simbiontes; s\u00ed esos bichitos que viven en el suelo.<\/p>\n<p style=\"text-align: justify;\">\u00a0Ya os hemos hablado en numerosas ocasiones de estas <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/07\/30\/136547\"><span style=\"color: #0000ff;\">fascinantes civilizaciones bajo el suelo<\/span><\/a> y su papel en la <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2015\/07\/08\/146341\"><span style=\"color: #0000ff;\">descomposici\u00f3n de la materia org\u00e1nica, el reciclado de\u00a0 nutrientes<\/span><\/a> y su desempe\u00f1o vital\u00a0 en la din\u00e1mica de los ecosistemas. \u00a0<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/07\/03\/136296\"><span style=\"color: #0000ff;\">Desgraciadamente, a menudo la agricultura industrial ha tachado a las termitas como enemigas de la producci\u00f3n de alimentos<\/span><\/a>, cuando de <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2014\/08\/09\/145109\"><span style=\"color: #0000ff;\">conocer sus h\u00e1bitos<\/span><\/a>, <strong><span style=\"color: #3366ff;\">ser\u00edan en realidad<\/span><\/strong> <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/07\/30\/136547\"><span style=\"color: #0000ff;\">uno de nuestros mejores aliados<\/span><\/a>. Como siempre primero disparemos a los amigos y luego resulta que\u2026.. Bien har\u00edamos en generar nuevas t\u00e9cnicas de agricultura ecol\u00f3gica con la colaboraci\u00f3n de esta <strong><span style=\"color: #3366ff;\">bioingenier\u00eda natural<\/span><\/strong>, sin necesidad de ir tocando los genes por doquier y exterminar a estos fabulosos \u201cbichitos\u201d. \u00a0Nuestro peores enemigos son, de hecho la ignorancia y arrogancia.<\/p>\n<p style=\"text-align: justify;\">\u00a0Os dejo sin m\u00e1s con la noticia original traducida del suajili al espa\u00f1ol castellano por ese torpe Mr. Google.<\/p>\n<p>\u00a0<span style=\"color: #008000;\"><strong>Juan Jos\u00e9 Ib\u00e1\u00f1ez<\/strong><\/span><\/p>\n<p><em>\u00a0<\/em><span style=\"color: #800000;\"><em>Contin\u00faa\u2026\u2026<\/em><\/span><\/p>\n<p><!--more--><strong><span style=\"color: #0000ff;\"><a href=\"http:\/\/www.seeddaily.com\/reports\/Termite_gut_holds_a_secret_to_breaking_down_plant_biomass_999.html\">Termite gut holds a secret to breaking down plant biomass<\/a><br \/>\n<\/span><\/strong><\/p>\n<p style=\"text-align: justify;\"><strong> <\/strong>by Staff Writers; Madison WI (SPX) Apr 18, 2017<\/p>\n<p style=\"text-align: justify;\">In the Microbial Sciences Building at the University of Wisconsin-Madison, the incredibly efficient eating habits of a fungus-cultivating termite are surprising even to those well acquainted with the insect&#8217;s natural gift for turning wood to dust.<\/p>\n<p style=\"text-align: justify;\">According to a study published this week in the journal Proceedings of the National Academy of Sciences, when poplar wood undergoes a short, 3.5-hour transit through the gut of the termite, the emerging feces is almost devoid of lignin, the hard and abundant polymer that gives plant cells walls their sturdiness. As lignin is <span style=\"color: #000000;\">notorious for being difficult to degrade, and remains a costly obstacle for wood processing industries such as biofuels and paper, the termite is the keeper of a <\/span><span style=\"color: #800000;\"><span style=\"color: #000000;\">highly sought after secret: a natural system for fully breaking down biomass<\/span>.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #800000;\"><em>El intestino de termitas tiene un secreto para descomponer la biomasa vegetal<\/em><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #008080;\"><em>(\u2026) los incre\u00edblemente eficientes h\u00e1bitos alimenticios de una termita cultivadora de hongos son sorprendentes incluso para aquellos que conocen bien el don natural del insecto para convertir la madera en polvo.<\/em><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #008080;\"><em>Seg\u00fan un estudio publicado esta semana en la revista Proceedings de la Academia Nacional de Ciencias, <strong>cuando la madera de \u00e1lamo se somete a un breve tr\u00e1nsito de 3,5 horas a trav\u00e9s del intestino del termitas, las heces emergentes est\u00e1n casi desprovistas de lignina<\/strong>, el pol\u00edmero duro y abundante que da a las paredes de las c\u00e9lulas vegetales su robustez. <strong>Como la lignina es notoria por ser dif\u00edcil de degradar, y sigue siendo un obst\u00e1culo costoso para las industrias de procesamiento de la madera, como los biocombustibles y el papel, el termitero es el guardi\u00e1n de un secreto altamente buscado: un sistema natural para la descomposici\u00f3n total de la biomasa<\/strong>.<\/em><\/span><\/p>\n<p style=\"text-align: justify;\">\u00abThe speed and efficiency with which the termite is breaking down the lignin polymer is totally unexpected,\u00bb says John Ralph, a UW-Madison professor of biochemistry, researcher at the Great Lakes Bioenergy Research Center (GLBRC) and lignin expert. \u00abThe tantalizing implication is that this gut system holds keys to breaking down lignin using processes that are completely unknown.\u00bb<\/p>\n<p style=\"text-align: justify;\">Hongjie Li, co-first author of the study, began studying the termite as graduate student at Zhejiang University in Hangzhou, China. Now a postdoctoral researcher in the lab of UW-Madison bacteriology professor and GLBRC researcher Cameron Currie, Li was the first to keep this genus of termite alive in a lab setting, and the first to observe close-up the symbiotic system that unites the termites with the white rot fungus Termitomyces.<\/p>\n<p style=\"text-align: justify;\">The entire process, as is often the case with social insects, is complex. Young termites, or young workers, collect and eat the wood. The termites&#8217; fungal-laden feces then become an integral part of a fungal comb, a sponge-like structure the termites create within a protected chamber. On the comb, the white rot fungi further degrade the wood until its simple sugars are ready, some 45 days later, to be consumed by old worker termites.<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #008080;\"><em>\u00abLa implicaci\u00f3n tentadora es que este sistema intestinal tiene las claves para romper la lignina usando procesos que son completamente desconocidos\u00bb.<\/em><\/span><\/p>\n<p style=\"text-align: justify;\"><em><span style=\"color: #008080;\">Hongjie Li, co-primer autor del estudio, (\u2026) fue el primero en mantener este g\u00e9nero de termitas vivo en un entorno de laboratorio y el primero en observar el sistema simbi\u00f3tico que une a las termitas con el hongo de la pudrici\u00f3n blanca Termitomyces<\/span>.<\/em><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #008080;\"><strong><em>Todo el proceso, como suele ser el caso de los insectos sociales, es complejo<\/em><\/strong><em>. <strong>Las termitas j\u00f3venes, o trabajadores j\u00f3venes, recogen y comen la madera. Las heces de las termitas cargadas de hongos se convierten en parte integrante de un peine f\u00fangico<\/strong>, <strong>una estructura parecida a una esponja que las termitas crean dentro de una c\u00e1mara protegida<\/strong>. <strong>En el peine, los hongos blancos de la putrefacci\u00f3n degradan m\u00e1s lejos la madera hasta que sus az\u00facares simples est\u00e9n listos, algunos 45 d\u00edas m\u00e1s adelante, para ser consumidos por las termitas viejas del trabajador<\/strong><\/em><\/span><\/p>\n<p style=\"text-align: justify;\">\u00abFor decades, everybody just thought that the young worker wasn&#8217;t doing anything, because of how rapidly the wood passes through its gut,\u00bb says Li. \u00abBut after observing the termites in the lab, I assumed there were some functions there, since the fungi simply cannot live on the wood on their one.\u00bb<\/p>\n<p style=\"text-align: justify;\">To explore those functions, Li enlisted the help of co-first author Daniel Yelle, a research forest products technologist with the U.S. Department of Agriculture&#8217;s Forest Products Laboratory, and an expert in wood-degrading fungal systems.<\/p>\n<p style=\"text-align: justify;\">\u00abThis system is unique because the fungus and the termite can&#8217;t live without each other,\u00bb says Yelle. \u00abThey&#8217;re symbiotic, and they work together very efficiently to do things white rot fungi can&#8217;t do in nature. Together they do everything more rapidly.\u00bb<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #008080;\"><em>Durante d\u00e9cadas, todo el mundo pensaba que el joven trabajador no estaba<\/em> <em>haciendo nada, debido a la rapidez con que la madera pasa a trav\u00e9s de su aparato digestivo (..) Pero despu\u00e9s de observar las termitas en el laboratorio, asum\u00ed que hab\u00eda algunas funciones all\u00ed que desconoc\u00eda. Los hongos simplemente no pueden vivir en la madera por s\u00ed misma \u00ab.<\/em><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #008080;\"><em>Para explorar esas funciones, Li reclut\u00f3 \u00a0(\u2026) a un experto en sistemas f\u00fangicos que degradan madera.(..) \u00ab<strong>Este sistema es \u00fanico porque el hongo y la termita no pueden vivir el uno sin \u00a0el otro\u00bb,<\/strong> dice Yelle. \u00ab<strong>Son simbi\u00f3ticas, y trabajan juntas muy eficientemente para hacer las cosas que los hongos de la pudrici\u00f3n blanca no pueden hacer en naturaleza.<\/strong> <\/em><em>Juntos hacen todo m\u00e1s r\u00e1pidamente.\u00bb<\/em><\/span><\/p>\n<p style=\"text-align: justify;\">The system may be symbiotic, but the processes involved in the gut transit &#8211; or the mechanisms by which the termite gut succeeds in cleaving even the hardest-to-cleave portions of the lignin &#8211; are still unknown. Future research will focus on determining which enzymes or bacterial systems might be at work in the gut. If that super enzyme or process can be replicated outside of the termite, it could result in a dramatic improvement in the way we process wood and make biofuels, improving economics and cutting energy use.<\/p>\n<p style=\"text-align: justify;\">\u00abThis is a great example of the value of basic science research,\u00bb says Currie. \u00abStudying how termites process plant biomass in nature not only helps us understand our natural world, but it could contribute to our own efforts to break down biomass.\u00bb<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #008080;\"><em>El sistema puede ser simbi\u00f3tico, pero los procesos implicados en el tr\u00e1nsito intestinal &#8211; o los mecanismos por los que el intestino de termitas <strong>tiene \u00e9xito en la escisi\u00f3n de incluso las porciones m\u00e1s dif\u00edciles de escindir de la lignina &#8211; son todav\u00eda desconocidos. Las investigaciones futuras se enfocar\u00e1n en determinar qu\u00e9 enzimas o sistemas bacterianos podr\u00edan estar funcionando en el intestino<\/strong>. Si esa super enzima o proceso puede ser replicado fuera de las termitas<strong>, podr\u00eda resultar en una mejora<\/strong><\/em><\/span><em><strong> dram\u00e1t<\/strong><\/em><em><strong>ica<\/strong><\/em><span style=\"color: #008080;\"><em><strong> en la forma en que procesamos la madera y fabricamos biocombustibles<\/strong>, mejorando la econom\u00eda y reduciendo el consumo de energ\u00eda.<\/em><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #008080;\"><em>\u00abEste es un gran ejemplo del valor de la investigaci\u00f3n cient\u00edfica b\u00e1sica\u00bb, dice Currie. \u00ab<strong>Estudiar c\u00f3mo las termitas procesan la biomasa vegetal en la naturaleza no solo nos ayuda a entender nuestro mundo natural, sino que podr\u00eda contribuir a nuestros propios esfuerzos para descomponer la biomasa<\/strong><\/em><em>\u00ab.<\/em><\/span><\/p>\n<p style=\"text-align: justify;\">Hongjie Lie, a UW-Madison postdoctoral researcher, was the first to observe close-up the symbiotic system that unites the termites with the white rot fungus Termitomyces. Image courtesy UW-Madison\/James<\/p>\n<h3>Im\u00e1genes Relacionadas:<\/h3>","protected":false},"excerpt":{"rendered":"<p>\u00a0 Fuente: Colaje Google im\u00e1genes \u00a0Existe una abundante literatura con vistas a obtener bioetanol y otros biocombustibles a partir de los recalcitrantes residuos lignocelul\u00f3sicos. \u00a0En el suelo, estos son degradados r\u00e1pidamente y m\u00e1s a\u00fan en presencia de ciertos ingenieros del suelo, como lo son las hormigas y termitas. El estudio que os mostramos hoy \u00a0(El intestino de termitas tiene un secreto para descomponer la biomasa vegetal), nos ayuda a conocer como el sistema simbi\u00f3tico entre las termitas y sus simbiontes digestivos realizan tal labor sin la menor dificultad. Entender el proceso ayudar\u00eda a obtener r\u00e1pida, econ\u00f3mica y eficientemente el mentado\u2026<\/p>\n","protected":false},"author":26,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0},"categories":[596,608,590,618,613,589,600],"tags":[48043,47209,773,48044,47033,48045],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":4}},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Las termitas del suelo y sus hongos simbiontes: El extraordinario t\u00e1ndem para degradar r\u00e1pidamente los residuos lignocelul\u00f3sicos\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Juan Jos\u00e9 Ib\u00e1\u00f1ez\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2018\/10\/15\/149160\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Un Universo invisible bajo nuestros pies - Los suelos y la vida\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Las termitas del suelo y sus hongos simbiontes: El extraordinario t\u00e1ndem para degradar r\u00e1pidamente los residuos lignocelul\u00f3sicos - Un Universo invisible bajo nuestros pies\" \/>\n\t\t<meta property=\"og:description\" content=\"Las termitas del suelo y sus hongos simbiontes: El extraordinario t\u00e1ndem para degradar r\u00e1pidamente los residuos lignocelul\u00f3sicos\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2018\/10\/15\/149160\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2018-10-15T13:14:22+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2018-10-15T13:16:21+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/juan.j.marti.14\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Las termitas del suelo y sus hongos simbiontes: El extraordinario t\u00e1ndem para degradar r\u00e1pidamente los residuos lignocelul\u00f3sicos - Un Universo invisible bajo nuestros pies\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Las termitas del suelo y sus hongos simbiontes: El extraordinario t\u00e1ndem para degradar r\u00e1pidamente los residuos lignocelul\u00f3sicos\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2018\\\/10\\\/15\\\/149160#blogposting\",\"name\":\"Las termitas del suelo y sus hongos simbiontes: El extraordinario t\\u00e1ndem para degradar r\\u00e1pidamente los residuos lignocelul\\u00f3sicos - Un Universo invisible bajo nuestros pies\",\"headline\":\"Las termitas del suelo y sus hongos simbiontes: El extraordinario t\\u00e1ndem para degradar r\\u00e1pidamente los residuos lignocelul\\u00f3sicos\",\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/wp-content\\\/blogs.dir\\\/42\\\/files\\\/163\\\/termitas-hongos-degradacion-lignocelulosa.jpg\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2018\\\/10\\\/15\\\/149160\\\/#articleImage\"},\"datePublished\":\"2018-10-15T14:14:22+01:00\",\"dateModified\":\"2018-10-15T14:16:21+01:00\",\"inLanguage\":\"es-ES\",\"commentCount\":2,\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2018\\\/10\\\/15\\\/149160#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2018\\\/10\\\/15\\\/149160#webpage\"},\"articleSection\":\"Biolog\\u00eda y Ecolog\\u00eda del Suelo, Biomasa y Necromasa en los Suelos: Ra\\u00edces y Materia Org\\u00e1nica, Componentes, Estructuras y Procesos en los Suelos, Ecolog\\u00eda y Biogeograf\\u00eda post posteriores a agosto de 2009, Fertilidad de Suelos y Nutrici\\u00f3n Vegetal, La Calidad y Las Funciones del Suelo, Los Suelos las Plantas y la Vegetaci\\u00f3n, degradaci\\u00f3n de residuos lignocelul\\u00f3sicos, desarrollo sostenible, energ\\u00edas renovables, hormigas y sus simbiontes, ingenieros del suelo, obtenci\\u00f3n biocombustibles\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2018\\\/10\\\/15\\\/149160#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/la-calidad-y-las-funciones-del-suelo#listItem\",\"name\":\"La Calidad y Las Funciones del Suelo\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/la-calidad-y-las-funciones-del-suelo#listItem\",\"position\":2,\"name\":\"La Calidad y Las Funciones del Suelo\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/la-calidad-y-las-funciones-del-suelo\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2018\\\/10\\\/15\\\/149160#listItem\",\"name\":\"Las termitas del suelo y sus hongos simbiontes: El extraordinario t\\u00e1ndem para degradar r\\u00e1pidamente los residuos lignocelul\\u00f3sicos\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2018\\\/10\\\/15\\\/149160#listItem\",\"position\":3,\"name\":\"Las termitas del suelo y sus hongos simbiontes: El extraordinario t\\u00e1ndem para degradar r\\u00e1pidamente los residuos lignocelul\\u00f3sicos\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/la-calidad-y-las-funciones-del-suelo#listItem\",\"name\":\"La Calidad y Las Funciones del Suelo\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#organization\",\"name\":\"Un Universo invisible bajo nuestros pies\",\"description\":\"Los suelos y la vida\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/files\\\/2022\\\/02\\\/logo.png\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2018\\\/10\\\/15\\\/149160\\\/#organizationLogo\",\"width\":217,\"height\":72},\"image\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2018\\\/10\\\/15\\\/149160\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/juan.j.marti.14\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo\",\"name\":\"Juan Jos\\u00e9 Ib\\u00e1\\u00f1ez\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2018\\\/10\\\/15\\\/149160#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/387f3a100385573d8f42ce2a3211fd1c?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Juan Jos\\u00e9 Ib\\u00e1\\u00f1ez\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2018\\\/10\\\/15\\\/149160#webpage\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2018\\\/10\\\/15\\\/149160\",\"name\":\"Las termitas del suelo y sus hongos simbiontes: El extraordinario t\\u00e1ndem para degradar r\\u00e1pidamente los residuos lignocelul\\u00f3sicos - Un Universo invisible bajo nuestros pies\",\"description\":\"Las termitas del suelo y sus hongos simbiontes: El extraordinario t\\u00e1ndem para degradar r\\u00e1pidamente los residuos lignocelul\\u00f3sicos\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2018\\\/10\\\/15\\\/149160#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\"},\"datePublished\":\"2018-10-15T14:14:22+01:00\",\"dateModified\":\"2018-10-15T14:16:21+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#website\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/\",\"name\":\"Un Universo invisible bajo nuestros pies\",\"description\":\"Los suelos y la vida\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Las termitas del suelo y sus hongos simbiontes: El extraordinario t\u00e1ndem para degradar r\u00e1pidamente los residuos lignocelul\u00f3sicos - Un Universo invisible bajo nuestros pies","description":"Las termitas del suelo y sus hongos simbiontes: El extraordinario t\u00e1ndem para degradar r\u00e1pidamente los residuos lignocelul\u00f3sicos","canonical_url":"https:\/\/www.madrimasd.org\/blogs\/universo\/2018\/10\/15\/149160","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2018\/10\/15\/149160#blogposting","name":"Las termitas del suelo y sus hongos simbiontes: El extraordinario t\u00e1ndem para degradar r\u00e1pidamente los residuos lignocelul\u00f3sicos - Un Universo invisible bajo nuestros pies","headline":"Las termitas del suelo y sus hongos simbiontes: El extraordinario t\u00e1ndem para degradar r\u00e1pidamente los residuos lignocelul\u00f3sicos","author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author"},"publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-content\/blogs.dir\/42\/files\/163\/termitas-hongos-degradacion-lignocelulosa.jpg","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2018\/10\/15\/149160\/#articleImage"},"datePublished":"2018-10-15T14:14:22+01:00","dateModified":"2018-10-15T14:16:21+01:00","inLanguage":"es-ES","commentCount":2,"mainEntityOfPage":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2018\/10\/15\/149160#webpage"},"isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2018\/10\/15\/149160#webpage"},"articleSection":"Biolog\u00eda y Ecolog\u00eda del Suelo, Biomasa y Necromasa en los Suelos: Ra\u00edces y Materia Org\u00e1nica, Componentes, Estructuras y Procesos en los Suelos, Ecolog\u00eda y Biogeograf\u00eda post posteriores a agosto de 2009, Fertilidad de Suelos y Nutrici\u00f3n Vegetal, La Calidad y Las Funciones del Suelo, Los Suelos las Plantas y la Vegetaci\u00f3n, degradaci\u00f3n de residuos lignocelul\u00f3sicos, desarrollo sostenible, energ\u00edas renovables, hormigas y sus simbiontes, ingenieros del suelo, obtenci\u00f3n biocombustibles"},{"@type":"BreadcrumbList","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2018\/10\/15\/149160#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo#listItem","position":1,"name":"Home","item":"https:\/\/www.madrimasd.org\/blogs\/universo","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/la-calidad-y-las-funciones-del-suelo#listItem","name":"La Calidad y Las Funciones del Suelo"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/la-calidad-y-las-funciones-del-suelo#listItem","position":2,"name":"La Calidad y Las Funciones del Suelo","item":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/la-calidad-y-las-funciones-del-suelo","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2018\/10\/15\/149160#listItem","name":"Las termitas del suelo y sus hongos simbiontes: El extraordinario t\u00e1ndem para degradar r\u00e1pidamente los residuos lignocelul\u00f3sicos"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2018\/10\/15\/149160#listItem","position":3,"name":"Las termitas del suelo y sus hongos simbiontes: El extraordinario t\u00e1ndem para degradar r\u00e1pidamente los residuos lignocelul\u00f3sicos","previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/la-calidad-y-las-funciones-del-suelo#listItem","name":"La Calidad y Las Funciones del Suelo"}}]},{"@type":"Organization","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#organization","name":"Un Universo invisible bajo nuestros pies","description":"Los suelos y la vida","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/","logo":{"@type":"ImageObject","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2018\/10\/15\/149160\/#organizationLogo","width":217,"height":72},"image":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2018\/10\/15\/149160\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/juan.j.marti.14"]},{"@type":"Person","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo","name":"Juan Jos\u00e9 Ib\u00e1\u00f1ez","image":{"@type":"ImageObject","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2018\/10\/15\/149160#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/387f3a100385573d8f42ce2a3211fd1c?s=96&d=mm&r=g","width":96,"height":96,"caption":"Juan Jos\u00e9 Ib\u00e1\u00f1ez"}},{"@type":"WebPage","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2018\/10\/15\/149160#webpage","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/2018\/10\/15\/149160","name":"Las termitas del suelo y sus hongos simbiontes: El extraordinario t\u00e1ndem para degradar r\u00e1pidamente los residuos lignocelul\u00f3sicos - Un Universo invisible bajo nuestros pies","description":"Las termitas del suelo y sus hongos simbiontes: El extraordinario t\u00e1ndem para degradar r\u00e1pidamente los residuos lignocelul\u00f3sicos","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#website"},"breadcrumb":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2018\/10\/15\/149160#breadcrumblist"},"author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author"},"creator":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author"},"datePublished":"2018-10-15T14:14:22+01:00","dateModified":"2018-10-15T14:16:21+01:00"},{"@type":"WebSite","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#website","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/","name":"Un Universo invisible bajo nuestros pies","description":"Los suelos y la vida","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Un Universo invisible bajo nuestros pies - Los suelos y la vida","og:type":"article","og:title":"Las termitas del suelo y sus hongos simbiontes: El extraordinario t\u00e1ndem para degradar r\u00e1pidamente los residuos lignocelul\u00f3sicos - Un Universo invisible bajo nuestros pies","og:description":"Las termitas del suelo y sus hongos simbiontes: El extraordinario t\u00e1ndem para degradar r\u00e1pidamente los residuos lignocelul\u00f3sicos","og:url":"https:\/\/www.madrimasd.org\/blogs\/universo\/2018\/10\/15\/149160","og:image":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png","og:image:secure_url":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png","article:published_time":"2018-10-15T13:14:22+00:00","article:modified_time":"2018-10-15T13:16:21+00:00","article:publisher":"https:\/\/www.facebook.com\/juan.j.marti.14","twitter:card":"summary","twitter:title":"Las termitas del suelo y sus hongos simbiontes: El extraordinario t\u00e1ndem para degradar r\u00e1pidamente los residuos lignocelul\u00f3sicos - Un Universo invisible bajo nuestros pies","twitter:description":"Las termitas del suelo y sus hongos simbiontes: El extraordinario t\u00e1ndem para degradar r\u00e1pidamente los residuos lignocelul\u00f3sicos","twitter:image":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png"},"aioseo_meta_data":{"post_id":"149160","title":"","description":"Las termitas del suelo y sus hongos simbiontes: El extraordinario t\u00e1ndem para degradar r\u00e1pidamente los residuos lignocelul\u00f3sicos","keywords":[{"label":"termitas del suelo","value":"termitas del suelo"},{"label":"hongos simbiontes","value":"hongos simbiontes"},{"label":"degradaci\u00f3n de residuos lignocelul\u00f3sicos","value":"degradaci\u00f3n de residuos lignocelul\u00f3sicos"}],"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":null,"isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","tabs":null,"priority":null,"frequency":null,"local_seo":null,"created":"2022-06-03 16:41:50","updated":"2026-05-26 18:59:51","limit_modified_date":false,"ai":null,"breadcrumb_settings":null,"seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/la-calidad-y-las-funciones-del-suelo\" title=\"La Calidad y Las Funciones del Suelo\">La Calidad y Las Funciones del Suelo<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tLas termitas del suelo y sus hongos simbiontes: El extraordinario t\u00e1ndem para degradar r\u00e1pidamente los residuos lignocelul\u00f3sicos\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.madrimasd.org\/blogs\/universo"},{"label":"La Calidad y Las Funciones del Suelo","link":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/la-calidad-y-las-funciones-del-suelo"},{"label":"Las termitas del suelo y sus hongos simbiontes: El extraordinario t\u00e1ndem para degradar r\u00e1pidamente los residuos lignocelul\u00f3sicos","link":"https:\/\/www.madrimasd.org\/blogs\/universo\/2018\/10\/15\/149160"}],"_links":{"self":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts\/149160"}],"collection":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/comments?post=149160"}],"version-history":[{"count":7,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts\/149160\/revisions"}],"predecessor-version":[{"id":149861,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts\/149160\/revisions\/149861"}],"wp:attachment":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/media?parent=149160"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/categories?post=149160"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/tags?post=149160"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}