{"id":149255,"date":"2019-01-28T13:30:12","date_gmt":"2019-01-28T12:30:12","guid":{"rendered":"http:\/\/www.madrimasd.org\/blogs\/universo\/?p=149255"},"modified":"2019-01-28T13:30:12","modified_gmt":"2019-01-28T12:30:12","slug":"hundimientos-del-terreno-y-sobreexplotacion-de-acuiferos","status":"publish","type":"post","link":"https:\/\/www.madrimasd.org\/blogs\/universo\/2019\/01\/28\/149255","title":{"rendered":"Hundimientos del Terreno y sobreexplotaci\u00f3n de acu\u00edferos"},"content":{"rendered":"<p align=\"center\"><span style=\"color: #000000;\"><img decoding=\"async\" class=\"ngg-singlepic ngg-center\" src=\"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-content\/blogs.dir\/42\/files\/1283\/subsidencia-del-terreno-y-aguas-subterraneas.jpg\" alt=\"subsidencia-del-terreno-y-aguas-subterraneas\" \/>\u00a0<\/span><\/p>\n<p align=\"center\"><span style=\"color: #800000;\">Subsidencias del terreno y sus diversas causas; Fuente. Colaje im\u00e1genes Google<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #3366ff;\"><strong>Los hundimientos de la superficie terrestre<\/strong><\/span><span style=\"color: #000000;\"> pueden ser generados por diversos procesos, naturales u antr\u00f3picos. No obstante, <span style=\"color: #3366ff;\"><strong>la sobreexplotaci\u00f3n de las aguas subterr\u00e1neas crece exponencialmente en todos los continentes y<\/strong> <strong>en especial en donde escasean las aguas superficiales<\/strong><\/span>, es decir en climas \u00e1ridos, semi\u00e1ridos y mediterr\u00e1neos. Ya comentamos en un post anterior que \u201c<\/span>No existe agricultura sustentable alguna basada en el riego, con sobreexplotaci\u00f3n de los acu\u00edferos<span style=\"color: #000000;\">\u201d. Un ejemplo palmario de tal uso insostenible de las valiosas aguas que atesoramos bajo nuestros pies, puede encontrarse en este interesante post de otro blog pertenecientes a nuestro sistema de bit\u00e1coras; \u201c <\/span><a href=\"http:\/\/www.madrimasd.org\/blogs\/remtavares\/2017\/10\/16\/133328?origen=notiweb\">La escasez de agua subterr\u00e1nea en las regiones semi-\u00e1ridas del norte de Chile: el conflicto por la demanda de agua afecta a los ecosistemas de aguas subterr\u00e1neas<\/a>\u201d. Recomiendo v\u00edvidamente que lo le\u00e1is, resume sint\u00e9ticamente casi todos los problemas relacionados con este proceso y que se concentran en el mismo espacio geogr\u00e1fico. Pr\u00e1cticamente, en pocas horas, le\u00ed otra noticia de la misma guisa, aunque menos dram\u00e1tica, pero en la que se estimaban las tasas de subsidencia del terreno, es decir m\u00e1s concretamente esta: \u201c<a href=\"http:\/\/www.madrimasd.org\/notiweb\/noticias\/terreno-vega-granada-se-hunde-hasta-un-centimetro-por-ano-consecuencia-sequia\"><span style=\"color: #0000ff;\">El terreno de la Vega de Granada se hunde hasta un cent\u00edmetro por a\u00f1o a consecuencia de la sequ\u00eda<\/span><\/a><span style=\"color: #000000;\">\u201d. En ella, se aplicaban <span style=\"color: #3366ff;\"><strong>metodolog\u00edas con vistas a su cuantificaci\u00f3n anual a nivel de cent\u00edmetros<\/strong><\/span>, por la que os la reproduzco abajo. Seguidamente realic\u00e9 una b\u00fasqueda en Internet, en ingl\u00e9s, por cuanto siempre aparecen un mayor n\u00famero de noticias cient\u00edficas. Tecleando \u201c\u201c<em>groundwater exploitation ground subsidence<\/em>\u201d, aparecieron m\u00e1s de 234,000 relacionadas con el tema \u201cY as\u00ed, por ejemplo, entre las m\u00e1s le\u00eddas, por su car\u00e1cter general, detect\u00e9 las siguientes entre otras muchas: \u201c<\/span><a href=\"https:\/\/www.google.es\/url?sa=t&amp;rct=j&amp;q=&amp;esrc=s&amp;source=web&amp;cd=2&amp;cad=rja&amp;uact=8&amp;ved=0ahUKEwjy7Y-a1PXWAhUKNxQKHdAlAwAQFggzMAE&amp;url=http%3A%2F%2Fwww.sciencedirect.com%2Fscience%2Farticle%2Fpii%2FS0013795213002147&amp;usg=AOvVaw2TMpL0PlcywB1TLxT779LD\">Land subsidence and ground failure associated to groundwater <\/a>\u201d; \u201c<a href=\"https:\/\/www.google.es\/url?sa=t&amp;rct=j&amp;q=&amp;esrc=s&amp;source=web&amp;cd=1&amp;cad=rja&amp;uact=8&amp;ved=0ahUKEwjy7Y-a1PXWAhUKNxQKHdAlAwAQFggrMAA&amp;url=https%3A%2F%2Fwww.ncbi.nlm.nih.gov%2Fpubmed%2F23604266&amp;usg=AOvVaw1nUQc9JSg8fS2L5yFvtO4e\">Groundwater exploitation management under land subsidence &#8230; &#8211; NCBI<\/a>\u201d; <span style=\"color: #000000;\">\u00a0\u201c<\/span><em><a href=\"http:\/\/www.sciencedirect.com\/science\/article\/pii\/S0013795213002147\"><span style=\"color: #0000ff;\">Land subsidence and ground failure associated to groundwater<\/span><\/a><\/em><span style=\"color: #000000;\">\u201d, \u00a0entre otras muchas. Seguidamente realic\u00e9 otra b\u00fasqueda r\u00e1pida de art\u00edculos cient\u00edficos en los que se cuantificara la tasa de subsidencia o hundimiento del terreno. Exist\u00eda tambi\u00e9n abundante documentaci\u00f3n disponible para los lectores interesados. Por ejemplo, e<\/span>n <a href=\"https:\/\/en.wikipedia.org\/wiki\/Hebei\"><span style=\"color: #0000ff;\">la llanura de Hebei<\/span><\/a>, ya hace varias d\u00e9cadas (entre 1983 a 1993) <strong><span style=\"color: #3366ff;\">se alcanz\u00f3 una subsidencia anual de \u00a142 cm\/a\u00f1o!<\/span> <\/strong><span style=\"color: #3366ff;\">(\u201cGroundwater exploitation<\/span><strong> <\/strong>and its impact on the\u2026.\u201d). <strong><span style=\"color: #000000;\"><span style=\"color: #3366ff;\">\u00a1Una barbaridad<\/span>!<\/span><\/strong><span style=\"color: #000000;\">. <\/span>Si se a\u00f1ade a la b\u00fasqueda desastres (\u201c<em>disasters<\/em>\u201d) que pueden producir, top\u00e9, por ejemplo con este caso de \u201c<a href=\"https:\/\/www.researchgate.net\/publication\/251875457_Land_subsidence_and_ground_failure_associated_to_groundwater_exploitation_in_the_Aguascalientes_Valley_Mexico\"><span style=\"color: #0000ff;\">AguasCalientes\u201d (M\u00e9xico) en donde se produjeron serios da\u00f1os econ\u00f3micos, asociados<\/span><\/a>, al parecer, a una zona de falla. Usualmente, las subsidencias no inducen <span style=\"color: #3366ff;\"><strong>desastres naturales<\/strong> <\/span>de un d\u00eda para otro. Sin embargo en condiciones concretas, y bajo el habitual desinter\u00e9s de nuestros gestores, pueden devenir en tragedias locales. En varios estudios se constaba <span style=\"color: #3366ff;\"><strong>como la disposici\u00f3n y naturaleza de rocas y regolitos entre el suelo y el acu\u00edfero son de capital importancia a la hora de generar mayores o menores problemas<\/strong><\/span>.<\/p>\n<p style=\"text-align: justify;\">Parece pues, que <strong><span style=\"color: #3366ff;\">nuestra insustentable in-cultura ecol\u00f3gica no para de crear problemas ambientales en cascada<\/span><\/strong>, incesantemente, con prisas y sin pausas. Abajo, antes de la noticia de Granada, \u00a0os muestro, \u00a0las principales causas de los hundimientos del terreno, <a href=\"https:\/\/water.usgs.gov\/ogw\/subsidence.html\"><span style=\"color: #0000ff;\">seg\u00fan la USGS<\/span><\/a>.<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #3366ff;\"><strong>El problema estriba en que, con harta frecuencia, la demanda creciente de recursos h\u00eddricos con diversos fines, en un mismo territorio, act\u00faan simult\u00e1neamente agravando el problema y vincul\u00e1ndolo de paso con otros procesos de degradaci\u00f3n ambiental como lo es la contaminaci\u00f3n ambiental, que afecta perniciosamente a la vida silvestre y las poblaciones rurales locales<\/strong><\/span>. Al paso que vamos deberemos ir cambiando con celeridad los mapas topogr\u00e1ficos de muchas regiones del mundo, ya que estamos convirtiendo su superficie en un tobog\u00e1n de finas<span style=\"color: #000000;\"> \u201c<\/span><strong><span style=\"color: #3366ff;\">ondulaciones subsistenciales<\/span><\/strong>\u201d \u00bf\u00bf??.<\/p>\n<p style=\"text-align: justify;\">Para finalizar, <strong><span style=\"color: #3366ff;\">sigo sin entender porque no se aplican est\u00e1s t\u00e9cnicas con vistas a estimar tambi\u00e9n las tases de erosi\u00f3n\/deposici\u00f3n del suelo alrededor del mundo<\/span><\/strong>.<\/p>\n<p>Os dejo ya con el material comentado.<\/p>\n<p><span style=\"color: #008000;\"><strong>Juan Jos\u00e9 Ib\u00e1\u00f1ez<\/strong><\/span><\/p>\n<p><span style=\"color: #800000;\"><em>Contin\u00faa\u2026\u2026..<\/em><\/span><\/p>\n<p><!--more--><a href=\"https:\/\/water.usgs.gov\/ogw\/subsidence.html\"><span style=\"color: #0000ff;\">Seg\u00fan la USGS<\/span><\/a>&#8230;..<\/p>\n<p><span style=\"color: #000000;\">Land subsidence is a gradual settling or sudden sinking of the Earth&#8217;s surface owing to subsurface movement of earth materials. Subsidence is a global problem and, in the United States, more than 17,000 square miles in 45 States, an area roughly the size of New Hampshire and Vermont combined, have been directly affected by subsidence.<\/span><\/p>\n<p><span style=\"color: #000000;\">The principal causes are aquifer-system compaction, drainage of organic soils, underground mining, hydrocompaction, natural compaction, sinkholes, and thawing permafrost. More than 80 percent of the identified subsidence in the Nation is a consequence of our exploitation of underground water, and the increasing development of land and water resources threatens to exacerbate existing land-subsidence problems and initiate new ones. In many areas of the arid Southwest, and in more humid areas underlain by soluble rocks such as limestone, gypsum, or salt, land subsidence is an often- overlooked environmental consequence of our land- and water-use practices.<\/span><\/p>\n<p><span style=\"color: #800000;\"><em>La subsidencia de la tierra es un asentamiento gradual o hundimiento repentino de<\/em> <\/span><em><span style=\"color: #800000;\">la superficie de la Tierra debido al movimiento subsuperficial de los materiales de la tierra. La subsidencia es un problema global y, en los Estados Unidos, m\u00e1s de 17,000 millas cuadradas en 45 estados, un \u00e1rea aproximadamente del tama\u00f1o de New Hampshire y Vermont combinadas, se han visto directamente afectadas por la subsidencia<\/span>.<\/em><\/p>\n<p><span style=\"color: #800000;\"><em>Las causas principales son la compactaci\u00f3n del sistema acu\u00edfero, drenaje de suelos org\u00e1nicos, miner\u00eda subterr\u00e1nea, hidrocompactaci\u00f3n, compactaci\u00f3n natural, sumideros y descongelamiento del permafrost. M\u00e1s del 80 por ciento de la subsidencia identificada en la Naci\u00f3n es consecuencia de nuestra explotaci\u00f3n del agua subterr\u00e1nea, y el creciente desarrollo de los recursos de tierra y agua amenaza con exacerbar los problemas existentes de subsidencia de la tierra e iniciar nuevos. En muchas \u00e1reas del suroeste \u00e1rido, y en \u00e1reas m\u00e1s h\u00famedas sustentadas por rocas solubles como la piedra caliza, el yeso o la sal, la subsidencia de la tierra es una consecuencia ambiental a menudo pasada por alto de nuestras pr\u00e1cticas de uso de tierra y agua<\/em><\/span><\/p>\n<p><a href=\"http:\/\/www.madrimasd.org\/notiweb\/noticias\/terreno-vega-granada-se-hunde-hasta-un-centimetro-por-ano-consecuencia-sequia\"><strong><span style=\"color: #0000ff;\">El terreno de la Vega de Granada se hunde hasta un cent\u00edmetro por a\u00f1o a consecuencia de la sequ\u00eda<\/span><\/strong><\/a><strong><\/strong><\/p>\n<p><strong>Tres sat\u00e9lites espaciales <\/strong><strong>han monitorizado <\/strong><strong>las variaciones del terreno de la Vega <\/strong><strong>desde el a\u00f1o 2003, <\/strong><strong>dentro de un estudio de la <\/strong><a title=\"Universidad de Granada\" href=\"https:\/\/www.ugr.es\/\" target=\"_blank\"><strong>Universidad de Granada<\/strong><\/a><strong> (UGR) y el <\/strong><a title=\"Instituto Geol\u00f3gico y Minero de Espa\u00f1a\" href=\"http:\/\/www.igme.es\/\" target=\"_blank\"><strong>Instituto Geol\u00f3gico y Minero de Espa\u00f1a<\/strong><\/a><strong> (IGME). <\/strong><strong>Tambi\u00e9n se ha analizado la explotaci\u00f3n del acu\u00edfero de la Vega durante los \u00faltimos 13 a\u00f1os, que fue explotado con mayor intensidad a lo largo de periodos secos en la zona de <\/strong><strong>Armilla, Atarfe, Chauchina y Santa Fe.<\/strong><\/p>\n<p>La Universidad de Granada y el Instituto Geol\u00f3gico y Minero de Espa\u00f1a han demostrado, gracias a <strong>un an\u00e1lisis de las variaciones del terreno (hundimientos y elevaciones), que la Vega de Granada se hunde hasta un cent\u00edmetro al a\u00f1o durante periodos secos. Para ello, han procesado las im\u00e1genes de radar obtenidas desde 2003 por tres sat\u00e9lites espaciales diferentes, logrando as\u00ed una precisi\u00f3n milim\u00e9trica en el estudio<\/strong>.<\/p>\n<p>En paralelo, se ha llevado a cabo <strong>un seguimiento de la explotaci\u00f3n del acu\u00edfero de la Vega de Granada durante los \u00faltimos 13 a\u00f1os, conociendo d\u00f3nde se han producido los mayores focos de aprovechamiento, seg\u00fan los descensos o subidas del nivel fre\u00e1tico en el acu\u00edfero<\/strong>. Adicionalmente, el estudio incluye un reconocimiento geol\u00f3gico del terreno mediante la interpretaci\u00f3n de sondeos ejecutados en la Vega de Granada desde la d\u00e9cada de los 70.<\/p>\n<p style=\"text-align: justify;\" align=\"center\"><strong>Los resultados ponen de manifiesto que durante el periodo seco 2003-2009, el acu\u00edfero fue explotado con mayor intensidad en la zona de<\/strong> Armilla, Atarfe, Chauchina y Santa Fe<strong>, lo que gener\u00f3 hundimientos del terreno de hasta un cent\u00edmetro al a\u00f1o<\/strong> en zonas localizadas al norte de Chauchina, el n\u00facleo urbano de Santa Fe, el este de Vegas del Genil, as\u00ed como en Atarfe y el sur de Maracena. <strong>Curiosamente, estas \u00e1reas coinciden con una mayor presencia de arcillas en el subsuelo, que se compactan durante las bajadas del nivel del acu\u00edfero<\/strong>.<\/p>\n<p><strong>En el periodo m\u00e1s lluvioso, entre los a\u00f1os 2011-2014, los focos de hundimiento del terreno desaparecen, aunque se detectan hundimientos importantes, de casi 13 mil\u00edmetros al a\u00f1o, en el <\/strong>entorno del aeropuerto y en el n\u00facleo urbano de Cijuela, <strong>debido a obras que conllevaron movimientos de tierra en ambas zonas<\/strong>. En los \u00faltimos a\u00f1os (2015-2016) tan solo se detectan peque\u00f1os n\u00facleos de hundimiento al noreste de Maracena, aunque su origen es desconocido.<\/p>\n<p>El director del departamento de Geodin\u00e1mica de la UGR, Jos\u00e9 Miguel Aza\u00f1\u00f3n, y Rosa Mar\u00eda Mateos, de la Unidad de Granada del Instituto Geol\u00f3gico y Minero de Espa\u00f1a, son los responsables de esta investigaci\u00f3n, de la que se ha hecho eco larevista <a title=\"Journal of Hydrology\" href=\"http:\/\/www.sciencedirect.com\/science\/article\/pii\/S0022169417305206\" target=\"_blank\">Journal of Hydrology<\/a>. Aza\u00f1\u00f3n y Mateos apuntanque <strong>los datos obtenidos \u00abno son nada alarmantes, y no implican riesgo alguno por el momento; s\u00ed son de enorme inter\u00e9s para una gesti\u00f3n adecuada del acu\u00edfero, especialmente durante los periodos de sequ\u00eda<\/strong>, como en el que nos encontramos en la actualidad\u00bb.<\/p>\n<p>\u00ab<strong>En zonas muy vulnerables, con elevado contenido en arcillas, bajadas de tan solo un par de metros del nivel fre\u00e1tico podr\u00edan generar hundimientos del terreno que, de acumularse, pueden suponer subsidencias de varios cent\u00edmetros a la d\u00e9cada y representar un peligro a largo plazo para los n\u00facleos urbanos asentados<\/strong> en la Vega de Granada\u00bb, se\u00f1alan los investigadores.<\/p>\n<p>Aza\u00f1\u00f3n y Mateos destacan c\u00f3mo <strong>se han detectado grietas en calles y aceras del municipio de <\/strong>Otura a <strong>causa de este fen\u00f3meno<\/strong>. \u00ab<strong>El verdadero riesgo lo producen las deformaciones diferenciales, es decir, el hecho de que se generen hundimientos en determinadas calles o zonas y no en otras anexas. Sin embargo, la mayor parte de las deformaciones detectadas resultan menos peligrosas al producirse de forma conjunta<\/strong>\u00ab.<\/p>\n<p><strong>Referencias bibliogr\u00e1ficas<\/strong>:<\/p>\n<p>Mateos, R.M., Ezquerro, P., Luque-Espinar, J.A., B\u00e9jar-Pizarro, M., Notti, D., Aza\u00f1\u00f3n, J.M., Montserrat, O., Herrera, G., Fern\u00e1ndez-Chac\u00f3n, F., Peinado, T., Galve, J.P., P\u00e9rez-Pe\u00f1a, V., Fern\u00e1ndez-Merodo, J.A., Jim\u00e9nez, J. 2017. <strong>Multiband PSInSAR and long-period monitoring of land subsidence in a strategic detrital aquifer (Vega de Granada, SE Spain): An approach to support management decisions<\/strong>. <em>Journal of Hydrology<\/em>, 553, pp. 71-87. DOI: 10.1016\/j.jhydrol.2017.07.056<\/p>\n<p>Notti, D., Mateos, R.M., Monserrat, O., Devanth\u00e9ry, N., Peinado, T., Rold\u00e1n, F.J., Fern\u00e1ndez-Chac\u00f3n, F., Galve, J.P., Lamas, F., Aza\u00f1\u00f3n, J.M. 2016. <a title=\"Ir al art\u00edculo en Online Library Wiley\" href=\"http:\/\/onlinelibrary.wiley.com\/doi\/10.1002\/hyp.10793\/full\" target=\"_blank\"><strong>Lithological control of land subsidence induced by groundwater withdrawal in new urban AREAS (Granada Basin, SE Spain). <\/strong><strong>Multiband DInSAR monitoring<\/strong><\/a>. <em>Hydrological Processes<\/em>, 30 (13), pp. 2317-2331. DOI: 10.1002\/hyp.10793<\/p>\n<h3>Im\u00e1genes Relacionadas:<\/h3>","protected":false},"excerpt":{"rendered":"<p>\u00a0 Subsidencias del terreno y sus diversas causas; Fuente. Colaje im\u00e1genes Google Los hundimientos de la superficie terrestre pueden ser generados por diversos procesos, naturales u antr\u00f3picos. No obstante, la sobreexplotaci\u00f3n de las aguas subterr\u00e1neas crece exponencialmente en todos los continentes y en especial en donde escasean las aguas superficiales, es decir en climas \u00e1ridos, semi\u00e1ridos y mediterr\u00e1neos. Ya comentamos en un post anterior que \u201cNo existe agricultura sustentable alguna basada en el riego, con sobreexplotaci\u00f3n de los acu\u00edferos\u201d. Un ejemplo palmario de tal uso insostenible de las valiosas aguas que atesoramos bajo nuestros pies, puede encontrarse en este interesante\u2026<\/p>\n","protected":false},"author":26,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0},"categories":[594,591,588,613,592,585,617,598],"tags":[48069,46814,47209,46704,48068,47115,48067],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":4}},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Hundimientos del Terreno y sobreexplotaci\u00f3n de acu\u00edferos\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Juan Jos\u00e9 Ib\u00e1\u00f1ez\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2019\/01\/28\/149255\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Un Universo invisible bajo nuestros pies - Los suelos y la vida\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Hundimientos del Terreno y sobreexplotaci\u00f3n de acu\u00edferos - Un Universo invisible bajo nuestros pies\" \/>\n\t\t<meta property=\"og:description\" content=\"Hundimientos del Terreno y sobreexplotaci\u00f3n de acu\u00edferos\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2019\/01\/28\/149255\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2019-01-28T12:30:12+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2019-01-28T12:30:12+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/juan.j.marti.14\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Hundimientos del Terreno y sobreexplotaci\u00f3n de acu\u00edferos - Un Universo invisible bajo nuestros pies\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Hundimientos del Terreno y sobreexplotaci\u00f3n de acu\u00edferos\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2019\\\/01\\\/28\\\/149255#blogposting\",\"name\":\"Hundimientos del Terreno y sobreexplotaci\\u00f3n de acu\\u00edferos - Un Universo invisible bajo nuestros pies\",\"headline\":\"Hundimientos del Terreno y sobreexplotaci\\u00f3n de acu\\u00edferos\",\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/wp-content\\\/blogs.dir\\\/42\\\/files\\\/1283\\\/subsidencia-del-terreno-y-aguas-subterraneas.jpg\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2019\\\/01\\\/28\\\/149255\\\/#articleImage\"},\"datePublished\":\"2019-01-28T13:30:12+01:00\",\"dateModified\":\"2019-01-28T13:30:12+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2019\\\/01\\\/28\\\/149255#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2019\\\/01\\\/28\\\/149255#webpage\"},\"articleSection\":\"Degradaci\\u00f3n de Suelos: Contaminaci\\u00f3n, Edafolog\\u00eda y Pol\\u00edtica, El Concepto de Suelo y Sus Representaciones, Fertilidad de Suelos y Nutrici\\u00f3n Vegetal, Los Suelos y la Salud, P\\u00e9rdida de los Recursos Ed\\u00e1ficos: La Erosi\\u00f3n, Procesos Superficiales terrestres: Relieve, Geomorfolog\\u00eda y Cuencas de Drenaje:, Suelos de Zonas \\u00c1ridas, Semi\\u00e1ridas y desertificaci\\u00f3n, causas antr\\u00f3picas, degradaci\\u00f3n ambiental, desarrollo sostenible, desastres naturales, hundimientos del terreno, problemas ambientales, subsidencia\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2019\\\/01\\\/28\\\/149255#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/perdida-de-los-recursos-edaficos-la-erosion#listItem\",\"name\":\"P\\u00e9rdida de los Recursos Ed\\u00e1ficos: La Erosi\\u00f3n\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/perdida-de-los-recursos-edaficos-la-erosion#listItem\",\"position\":2,\"name\":\"P\\u00e9rdida de los Recursos Ed\\u00e1ficos: La Erosi\\u00f3n\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/perdida-de-los-recursos-edaficos-la-erosion\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2019\\\/01\\\/28\\\/149255#listItem\",\"name\":\"Hundimientos del Terreno y sobreexplotaci\\u00f3n de acu\\u00edferos\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2019\\\/01\\\/28\\\/149255#listItem\",\"position\":3,\"name\":\"Hundimientos del Terreno y sobreexplotaci\\u00f3n de acu\\u00edferos\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/perdida-de-los-recursos-edaficos-la-erosion#listItem\",\"name\":\"P\\u00e9rdida de los Recursos Ed\\u00e1ficos: La Erosi\\u00f3n\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#organization\",\"name\":\"Un Universo invisible bajo nuestros pies\",\"description\":\"Los suelos y la vida\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/files\\\/2022\\\/02\\\/logo.png\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2019\\\/01\\\/28\\\/149255\\\/#organizationLogo\",\"width\":217,\"height\":72},\"image\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2019\\\/01\\\/28\\\/149255\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/juan.j.marti.14\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo\",\"name\":\"Juan Jos\\u00e9 Ib\\u00e1\\u00f1ez\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2019\\\/01\\\/28\\\/149255#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/387f3a100385573d8f42ce2a3211fd1c?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Juan Jos\\u00e9 Ib\\u00e1\\u00f1ez\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2019\\\/01\\\/28\\\/149255#webpage\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2019\\\/01\\\/28\\\/149255\",\"name\":\"Hundimientos del Terreno y sobreexplotaci\\u00f3n de acu\\u00edferos - Un Universo invisible bajo nuestros pies\",\"description\":\"Hundimientos del Terreno y sobreexplotaci\\u00f3n de acu\\u00edferos\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2019\\\/01\\\/28\\\/149255#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\"},\"datePublished\":\"2019-01-28T13:30:12+01:00\",\"dateModified\":\"2019-01-28T13:30:12+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#website\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/\",\"name\":\"Un Universo invisible bajo nuestros pies\",\"description\":\"Los suelos y la vida\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Hundimientos del Terreno y sobreexplotaci\u00f3n de acu\u00edferos - Un Universo invisible bajo nuestros pies","description":"Hundimientos del Terreno y sobreexplotaci\u00f3n de acu\u00edferos","canonical_url":"https:\/\/www.madrimasd.org\/blogs\/universo\/2019\/01\/28\/149255","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2019\/01\/28\/149255#blogposting","name":"Hundimientos del Terreno y sobreexplotaci\u00f3n de acu\u00edferos - Un Universo invisible bajo nuestros pies","headline":"Hundimientos del Terreno y sobreexplotaci\u00f3n de acu\u00edferos","author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author"},"publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-content\/blogs.dir\/42\/files\/1283\/subsidencia-del-terreno-y-aguas-subterraneas.jpg","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2019\/01\/28\/149255\/#articleImage"},"datePublished":"2019-01-28T13:30:12+01:00","dateModified":"2019-01-28T13:30:12+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2019\/01\/28\/149255#webpage"},"isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2019\/01\/28\/149255#webpage"},"articleSection":"Degradaci\u00f3n de Suelos: Contaminaci\u00f3n, Edafolog\u00eda y Pol\u00edtica, El Concepto de Suelo y Sus Representaciones, Fertilidad de Suelos y Nutrici\u00f3n Vegetal, Los Suelos y la Salud, P\u00e9rdida de los Recursos Ed\u00e1ficos: La Erosi\u00f3n, Procesos Superficiales terrestres: Relieve, Geomorfolog\u00eda y Cuencas de Drenaje:, Suelos de Zonas \u00c1ridas, Semi\u00e1ridas y desertificaci\u00f3n, causas antr\u00f3picas, degradaci\u00f3n ambiental, desarrollo sostenible, desastres naturales, hundimientos del terreno, problemas ambientales, subsidencia"},{"@type":"BreadcrumbList","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2019\/01\/28\/149255#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo#listItem","position":1,"name":"Home","item":"https:\/\/www.madrimasd.org\/blogs\/universo","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/perdida-de-los-recursos-edaficos-la-erosion#listItem","name":"P\u00e9rdida de los Recursos Ed\u00e1ficos: La Erosi\u00f3n"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/perdida-de-los-recursos-edaficos-la-erosion#listItem","position":2,"name":"P\u00e9rdida de los Recursos Ed\u00e1ficos: La Erosi\u00f3n","item":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/perdida-de-los-recursos-edaficos-la-erosion","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2019\/01\/28\/149255#listItem","name":"Hundimientos del Terreno y sobreexplotaci\u00f3n de acu\u00edferos"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2019\/01\/28\/149255#listItem","position":3,"name":"Hundimientos del Terreno y sobreexplotaci\u00f3n de acu\u00edferos","previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/perdida-de-los-recursos-edaficos-la-erosion#listItem","name":"P\u00e9rdida de los Recursos Ed\u00e1ficos: La Erosi\u00f3n"}}]},{"@type":"Organization","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#organization","name":"Un Universo invisible bajo nuestros pies","description":"Los suelos y la vida","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/","logo":{"@type":"ImageObject","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2019\/01\/28\/149255\/#organizationLogo","width":217,"height":72},"image":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2019\/01\/28\/149255\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/juan.j.marti.14"]},{"@type":"Person","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo","name":"Juan Jos\u00e9 Ib\u00e1\u00f1ez","image":{"@type":"ImageObject","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2019\/01\/28\/149255#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/387f3a100385573d8f42ce2a3211fd1c?s=96&d=mm&r=g","width":96,"height":96,"caption":"Juan Jos\u00e9 Ib\u00e1\u00f1ez"}},{"@type":"WebPage","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2019\/01\/28\/149255#webpage","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/2019\/01\/28\/149255","name":"Hundimientos del Terreno y sobreexplotaci\u00f3n de acu\u00edferos - Un Universo invisible bajo nuestros pies","description":"Hundimientos del Terreno y sobreexplotaci\u00f3n de acu\u00edferos","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#website"},"breadcrumb":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2019\/01\/28\/149255#breadcrumblist"},"author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author"},"creator":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author"},"datePublished":"2019-01-28T13:30:12+01:00","dateModified":"2019-01-28T13:30:12+01:00"},{"@type":"WebSite","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#website","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/","name":"Un Universo invisible bajo nuestros pies","description":"Los suelos y la vida","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Un Universo invisible bajo nuestros pies - Los suelos y la vida","og:type":"article","og:title":"Hundimientos del Terreno y sobreexplotaci\u00f3n de acu\u00edferos - Un Universo invisible bajo nuestros pies","og:description":"Hundimientos del Terreno y sobreexplotaci\u00f3n de acu\u00edferos","og:url":"https:\/\/www.madrimasd.org\/blogs\/universo\/2019\/01\/28\/149255","og:image":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png","og:image:secure_url":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png","article:published_time":"2019-01-28T12:30:12+00:00","article:modified_time":"2019-01-28T12:30:12+00:00","article:publisher":"https:\/\/www.facebook.com\/juan.j.marti.14","twitter:card":"summary","twitter:title":"Hundimientos del Terreno y sobreexplotaci\u00f3n de acu\u00edferos - Un Universo invisible bajo nuestros pies","twitter:description":"Hundimientos del Terreno y sobreexplotaci\u00f3n de acu\u00edferos","twitter:image":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png"},"aioseo_meta_data":{"post_id":"149255","title":"","description":"Hundimientos del Terreno y sobreexplotaci\u00f3n de acu\u00edferos","keywords":[{"label":"Hundimientos del Terreno","value":"Hundimientos del Terreno"},{"label":"subsidencia","value":"subsidencia"},{"label":"sobreexplotaci\u00f3n de acu\u00edferos","value":"sobreexplotaci\u00f3n de acu\u00edferos"}],"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":null,"isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","tabs":null,"priority":null,"frequency":null,"local_seo":null,"created":"2022-06-03 13:02:41","updated":"2026-05-26 19:02:48","limit_modified_date":false,"ai":null,"breadcrumb_settings":null,"seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/perdida-de-los-recursos-edaficos-la-erosion\" title=\"P\u00e9rdida de los Recursos Ed\u00e1ficos: La Erosi\u00f3n\">P\u00e9rdida de los Recursos Ed\u00e1ficos: La Erosi\u00f3n<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tHundimientos del Terreno y sobreexplotaci\u00f3n de acu\u00edferos\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.madrimasd.org\/blogs\/universo"},{"label":"P\u00e9rdida de los Recursos Ed\u00e1ficos: La Erosi\u00f3n","link":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/perdida-de-los-recursos-edaficos-la-erosion"},{"label":"Hundimientos del Terreno y sobreexplotaci\u00f3n de acu\u00edferos","link":"https:\/\/www.madrimasd.org\/blogs\/universo\/2019\/01\/28\/149255"}],"_links":{"self":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts\/149255"}],"collection":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/comments?post=149255"}],"version-history":[{"count":4,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts\/149255\/revisions"}],"predecessor-version":[{"id":150020,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts\/149255\/revisions\/150020"}],"wp:attachment":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/media?parent=149255"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/categories?post=149255"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/tags?post=149255"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}