{"id":150022,"date":"2019-02-14T13:58:48","date_gmt":"2019-02-14T12:58:48","guid":{"rendered":"http:\/\/www.madrimasd.org\/blogs\/universo\/?p=150022"},"modified":"2019-02-14T13:58:48","modified_gmt":"2019-02-14T12:58:48","slug":"de-la-filosofia-de-la-ciencia-a-la-filosofia-de-la-tecnociencia-nuevo-curso-basico-y-sus-razones","status":"publish","type":"post","link":"https:\/\/www.madrimasd.org\/blogs\/universo\/2019\/02\/14\/150022","title":{"rendered":"De la Filosof\u00eda de la Ciencia a la Filosof\u00eda de la Tecnociencia (Nuevo Curso B\u00e1sico y Sus Razones)"},"content":{"rendered":"<p align=\"center\"><span style=\"color: #000000;\"><img decoding=\"async\" class=\"ngg-singlepic ngg-center\" src=\"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-content\/blogs.dir\/42\/files\/405\/tecnociencia-introduccion.jpg\" alt=\"tecnociencia-introduccion\" \/>\u00a0<\/span><\/p>\n<p align=\"center\"><span style=\"color: #0000ff;\">Fuente: Colaje de im\u00e1genes Google<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Entre 2007 y 2012, aproximadamente, abrimos e implementamos los principales contenidos de nuestra categor\u00eda \u201c<\/span><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/curso-basico-sobre-filosofia-y-sociologia-de-la-ciencia\"><span style=\"color: #0000ff;\">Curso B\u00e1sico Sobre Filosof\u00eda y Sociolog\u00eda de la Ciencia<\/span><\/a><span style=\"color: #000000;\">\u201d. Jam\u00e1s pens\u00e9 que fuera a tener el \u00e9xito que ha alcanzado. Poco despu\u00e9s disfrut\u00e9 como profesor de estos temas en un master de posgrado y excelencia de la UPM (ver por ejemplo\u00a0 la siguiente entradilla \u201c<\/span><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/02\/09\/141024\"><span style=\"color: #0000ff;\">La Convergencia entre Disciplinas Cient\u00edficas e Ingenier\u00edas<\/span><\/a><span style=\"color: #000000;\">\u201d). El curso, a pesar de ir dirigido a ingenieros, es decir j\u00f3venes con una mentalidad pr\u00e1ctica, gust\u00f3 a la mayor\u00eda de los alumnos. Obviamente, <strong><span style=\"color: #3366ff;\">e<\/span><span style=\"color: #3366ff;\">ntre la filosof\u00eda y sociolog\u00eda \u201ccl\u00e1sicas\u201d de la ciencia y la praxis actual de la actividad investigadora exist\u00eda un hiato profundo<\/span><\/strong> que tan solo en parte era cubierto apelando a la filosof\u00eda, por lo que acud\u00ed, no a la cl\u00e1sica escuela \u201c<\/span><a href=\"http:\/\/www.scielo.org.co\/pdf\/res\/n37\/n37a08.pdf\"><span style=\"color: #0000ff;\">sociol\u00f3gica\u00a0 mertoniama<\/span><\/a><span style=\"color: #000000;\">\u201d de la ciencia, ins\u00edpida y poco adecuada\u00a0 a la hora de explicar el mundo de la indagaci\u00f3n en el que estamos inmersos. En consecuencia, iba inclin\u00e1ndome, sin dudarlo hacia los denominados <\/span><a href=\"https:\/\/www.oei.es\/historico\/salactsi\/ramfis.htm\"><span style=\"color: #0000ff;\">estudios de la ciencia, o estudios sociales de la ciencia<\/span><\/a><span style=\"color: #000000;\">, que pueden considerarse aqu\u00ed como sin\u00f3nimos. Estos atesoran una fuerte inspiraci\u00f3n en las propuestas que <\/span><a href=\"https:\/\/es.wikipedia.org\/wiki\/Teor\u00eda_del_Actor-Red\"><span style=\"color: #0000ff;\">Bruno Latour y Michael Callon<\/span><\/a><span style=\"color: #000000;\"> desarrollaron esencialmente a finales de la d\u00e9cada de los 80 y principios de la de los 90 del siglo pasado. A pesar de todo, present\u00eda que algo\/bastante fallaba\/faltaba, por cuanto no detectaba bibliograf\u00eda reciente (novedosa) sobre la filosof\u00eda de la ciencia. Practicante no se hab\u00edan publicado propuestas que marcaran hito alguno desde Feyerabend. Y Ara\u00f1\u00e9 la superficie sin lograr profundizar. No me equivocaba, o al menos descarriaba en demas\u00eda. Son justamente\u00a0 <strong><span style=\"color: #3366ff;\">Latour y Callon, entre otros, los que ahora han sido<\/span> <span style=\"color: #3366ff;\">\u00a0considerados pioneros destacados de la denominada<\/span><\/strong> <\/span><a href=\"http:\/\/revistas.um.es\/daimon\/article\/view\/147121\"><span style=\"color: #0000ff;\">filosof\u00eda de la tecnociencia<\/span><\/a><span style=\"color: #000000;\">, como nos explica por ejemplo el fil\u00f3sofo <\/span><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-admin\/Javier%20Echevarr\u00eda\"><span style=\"color: #0000ff;\">Javier Echevarr\u00eda<\/span><\/a><span style=\"color: #000000;\">, uno de sus principales exponentes en habla castellana. <span style=\"color: #3366ff;\"><strong>La filosof\u00eda e incluso la sociolog\u00eda de la ciencia siguen siendo v\u00e1lidas, si bien se nos quedan corta con vistas a explicar el quehacer reciente de la ciencia y su relaci\u00f3n con la tecnolog\u00eda y la sociedad<\/strong>. <strong>Actualmente, aunque se hable de ciencia, realmente la mayor\u00eda de los pol\u00edticos y medios de comunicaci\u00f3n nos informan sobre el \u201clado bueno\u201d de la denominada<\/strong> <\/span><\/span><a href=\"https:\/\/es.wikipedia.org\/wiki\/Tecnociencia\"><span style=\"color: #0000ff;\">tecnociencia<\/span><\/a><span style=\"color: #000000;\">. Empero <span style=\"color: #3366ff;\"><strong>gran parte de los males actuales que hoy nos acechan, procede de la mentada<\/strong> <\/span><\/span><a href=\"https:\/\/es.wikipedia.org\/wiki\/Tecnociencia\"><span style=\"color: #0000ff;\">tecnociencia<\/span><\/a><span style=\"color: #000000;\">. \u00a1Si! tambi\u00e9n esconde un lado oscuro, pero que muy oscuro.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><span style=\"color: #3366ff;\"><strong>Nunca existi\u00f3, en mi modesta opini\u00f3n, una filosof\u00eda de la tecnolog\u00eda digna de ser comentada<\/strong><\/span>. Sin embargo, ya sabemos que frasecitas billones de veces repetidas y aparentemente inocuas, como las de <span style=\"color: #3366ff;\"><strong>\u201cciencia, tecnolog\u00eda e innovaci\u00f3n\u201d o ciencia y desarrollo tecnol\u00f3gico, esconden un lado oscuro, pero que muy oscuro para la mayor\u00eda de los mortales<\/strong><\/span>. \u00a0No defiendo que toda tecnolog\u00eda sea perversa, y menos a\u00fan in\u00fatil, sino que <span style=\"color: #3366ff;\"><strong>se aplica a fines procelosos, estando en manos no de los cient\u00edficos, sino de esos lobbies pol\u00edticos, financieros, militares, empresariales multinacionales, etc., a los que no les importa el verdadero conocimiento, sino los pingues beneficios que, de un modo u otro, puedan acarrearles y arrebatarnos<\/strong><\/span>.\u00a0 <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Menguan r\u00e1pidamente los investigadores que nos plantemos la ciencia en t\u00e9rminos de hacer retroceder el muro de la ignorancia humana sin m\u00e1s; de entender mejor el mundo que nos rodea y a nosotros mismos, sin m\u00e1s prop\u00f3sitos. <strong><span style=\"color: #3366ff;\">El objetivo de la tecnociencia no es precisamente ese, sino el control del poder desde todas sus aristas por parte de la oligarqu\u00eda global<\/span><\/strong>. \u00a0Algunas tecnolog\u00edas, como las <span style=\"color: #3366ff;\"><strong>TICS<\/strong><\/span>, las usamos masivamente, siendo \u00fatiles para el ciudadano, muchos de los cuales son ya hiper-dependientes, por no decir adictos, a las mismas. Los propios blogs son un ejemplo, como la telefon\u00eda m\u00f3vil y esos <em>smartphones<\/em> que llevan los m\u00e1s j\u00f3venes, adheridos a sus cuerpos, abstray\u00e9ndose del resto del mundo. \u00a0Empero volvemos a reiterar que <strong><span style=\"color: #3366ff;\">dejar el control en las manos de los que enga\u00f1an y expolian a los ciudadanos, sin el menos control, nos ha conducido a esta sociedad s\u00f3rdida insolidaria y a todas luces insustentable<\/span><\/strong>. Y as\u00ed, por ejemplo, el medio\u00a0 ambiente interesa como modelo de negocio, lo mismo que la salud y el bienestar general de los ciudadanos. <span style=\"color: #3366ff;\"><strong>El control en manos privadas de casi todo, deviene en un c\u00e1ncer que ha invadido nuestro cuerpo social casi en su totalidad<\/strong><\/span>. Y entre ellas cabr\u00eda destacar tambi\u00e9n<span style=\"color: #3366ff;\"> <strong>la precarizaci\u00f3n del empleo, el paro y la salud laboral, etc., etc<\/strong><\/span>. \u00a0<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><span style=\"color: #3366ff;\"><strong>Por definici\u00f3n, el prop\u00f3sito de las industrias es vender, vender mucho, cuanto m\u00e1s mejor<\/strong><\/span> (ver como bot\u00f3n de muestra nuestro antiguo post <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/01\/17\/138034\">Las miserias del capitalismo<\/a>: <\/span><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/01\/17\/138034\"><span style=\"color: #0000ff;\">La obsolescencia programada, o por qu\u00e9 vivimos en una sociedad anti-sustentable<\/span><\/a><span style=\"color: #000000;\">\u201d). \u00a1Si!. Para vender sus productos estos deben durar poco ya que se trata de comprar, usar, tirar y comprar, usar, tirar y comprar, usar, tirar y comprar \u201c<em>ad nausean<\/em>\u201d. Luego nos lamentamos, por ejemplo, de la <span style=\"color: #3366ff;\"><strong>contaminaci\u00f3n con micropl\u00e1sticos, o del cambio clim\u00e1tico, frutos en gran parte del uso de la tecnociencia<\/strong><\/span>, como iremos demostrando<span style=\"color: #3366ff;\"><strong> \u00bfD\u00f3nde queda pues el conocimiento cient\u00edfico? Sigue siendo la piedra angular de la tecnociencia, no lo dudo, empero empleado para otros fines, generalmente, menos nobles que los de anta\u00f1o<\/strong><\/span>, con salvedades, tanto antes y despu\u00e9s. Actualmente la libertad para hacer ciencia, ha ido dando paso a que l<span style=\"color: #3366ff;\"><strong>os investigadores sean un nodo m\u00e1s en la cadena de montaje tecnocient\u00edfica<\/strong><\/span>. La ciencia, tal como exist\u00eda hasta mediados del siglo XX, sufri\u00f3 un golpe mortal bajo la denominada \u201c<\/span><em><a href=\"https:\/\/es.wikipedia.org\/wiki\/Megaciencia\"><span style=\"color: #0000ff;\">big Science<\/span><\/a><\/em><span style=\"color: #000000;\">\u201d primero, y despu\u00e9s con la ya asentada tecnociencia.\u00a0 Tan solo en las ciencias menos sexy, y aun as\u00ed por la obstinaci\u00f3n de algunos de nosotros, se la intenta hacer frente con precariedad y sufriendo todo tipo de cr\u00edticas y descalificaciones por los ciudadanos (generalmente tendenciosamente informados por los medios de comunicaci\u00f3n), pol\u00edticos y empresarios. No somos libres, sino exclavos.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Entiendo que todo esto os sonar\u00e1 a (i) Juanjo se ha quedado obsoleto y, como viejo en ciernes, defiende que\u201d todo tiempo pasado fue mejor\u201d; o (ii) Juanjo ha vuelto <\/span><a href=\"https:\/\/www.linguee.com\/spanish-english\/translation\/apretar+las+tuercas.html\"><span style=\"color: #0000ff;\">a apretar las tuercas<\/span><\/a><span style=\"color: #000000;\"> de sus neuronas radicaliz\u00e1ndose hasta l\u00edmites insospechados. \u00a1Pues va a ser que no!. <strong><span style=\"color: #3366ff;\">Lo que os voy a ir narrando no se de cosecha propia, sino de los fil\u00f3sofos y soci\u00f3logos actuales<\/span><\/strong>. Yo actuar\u00e9 como correa de transmisi\u00f3n. Eso s\u00ed, intentar\u00e9 a\u00f1adir algunos granitos de arena que intenten clarificar la situaci\u00f3n. \u00a0<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Reitero que bastante arto del rumbo de la ciencia actual, durante un par de d\u00e9cadas, soslay\u00e9 lecturas de lo que cre\u00ed que eran disquisiciones en boga, sin sustancia, puramente ret\u00f3ricas, cuando se mentaba la tecnociencia, innovaci\u00f3n, emprendimiento, etc.\u00a0 Craso error. \u00a1Enorme!, \u00a1descomunal!. Fue justamente en el verano de 2016, cuando le\u00eda un libro por placer sobre ese hilarante intento de evadir el envejecimiento y alcanzar la inmortalidad (ver el post: <\/span><a title=\"Permanent Link to Jugando a Ser Inmortales: Transhumanismo y Singularidad Tecnol\u00f3gica (El d\u00eda en que dejemos de ser humanos\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2017\/06\/09\/148137\">Jugando a Ser Inmortales: Transhumanismo y Singularidad Tecnol\u00f3gica; el d\u00eda en que dejemos de ser humanos<\/a>)<span style=\"color: #000000;\">, cuando se cay\u00f3 la venda de mis ojos y top\u00e9 abruptamente con la <strong><span style=\"color: #3366ff;\">filosof\u00eda de la Tecnociencia<\/span><\/strong>. Ahora entiendo bastante mejor muchas de mis cr\u00edticas, quejas y lamentos en entregas precedentes a cerca de la estructura, din\u00e1mica y evoluci\u00f3n de la ciencia actual. Abajo os hago una relaci\u00f3n relativamente prol\u00edfica, aunque ni mucho menos exhaustiva, de tal material ya editado. <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Repito una vez m\u00e1s, para ser lo m\u00e1s transparente posible, que resulta curioso como muchos de mis post previos almacenados durante 14 a\u00f1os en varias de las categor\u00edas de nuestra bit\u00e1cora\u00a0 (ver el margen derecho de vuestro monitor): \u201c<\/span><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/curso-basico-sobre-filosofia-y-sociologia-de-la-ciencia\"><span style=\"color: #0000ff;\">Curso B\u00e1sico Sobre Filosof\u00eda y Sociolog\u00eda de la Ciencia<\/span><\/a><span style=\"color: #000000;\">\u201d; \u201c<\/span><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/curso-breve-sobre-periodismo-cientifico\"><span style=\"color: #0000ff;\">Curso breve sobre Periodismo Cient\u00edfico<\/span><\/a><span style=\"color: #000000;\"> \u201d; \u201c<\/span><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/curso-basico-de-ciencia-para-jovenes-universitarios-y-tecnologos\"><span style=\"color: #0000ff;\">Curso B\u00e1sico de Ciencia para J\u00f3venes Universitarios y Tecn\u00f3logos<\/span><\/a><span style=\"color: #000000;\">\u201d; \u201c<\/span><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/filosofia-historia-y-sociologia-de-la-edafologia\"><span style=\"color: #0000ff;\">Filosof\u00eda, Historia y Sociolog\u00eda de la Edafolog\u00eda<\/span><\/a><span style=\"color: #000000;\">\u201d; \u201c<\/span><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/fraude-y-mala-praxis-cientifica\"><span style=\"color: #0000ff;\">Fraude y Mala Praxis Cient\u00edfica<\/span><\/a><span style=\"color: #000000;\">\u201d; \u201c<\/span><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/la-crisis-de-la-edafologia\"><span style=\"color: #0000ff;\">La Crisis de la Edafolog\u00eda<\/span><\/a><span style=\"color: #000000;\">\u201d; \u201c<\/span><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/prensa-y-politica-cientifica\"><span style=\"color: #0000ff;\">Prensa y Pol\u00edtica Cient\u00edfica<\/span><\/a><span style=\"color: #000000;\">\u201d; \u201c<\/span><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/redes-complejas-ecologicas-sociales-y-el-mundo-de-internet\"><span style=\"color: #0000ff;\">Redes Complejas, Ecol\u00f3gicas, Sociales y el Mundo de Internet<\/span><\/a><span style=\"color: #000000;\">\u201d; \u201c<\/span><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/curso-breve-sobre-periodismo-cientifico\"><span style=\"color: #0000ff;\">Curso breve sobre Periodismo Cient\u00edfico<\/span><\/a><span style=\"color: #000000;\">\u201d; \u201c<\/span><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/02\/09\/141024\"><span style=\"color: #0000ff;\">La Convergencia entre Disciplinas Cient\u00edficas e Ingenier\u00edas<\/span><\/a><span style=\"color: #000000;\">\u201d adquieren una nueva dimensi\u00f3n ante mis ojos y cortas entendederas.\u00a0<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">A diferencia del curso sobre filosof\u00eda y sociolog\u00eda de la ciencia, para el cual hab\u00eda le\u00eddo bastante y durante muchos a\u00f1os, deber\u00e9 redactar los post de este nuevo \u201ccursillo acelerado\u201d conforme vaya leyendo libros y material de Internet.\u00a0 No se trata de improvisar, sino de informaros conforme vaya asimilando lo que encuentro de inter\u00e9s en este mundillo.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">En cualquier caso, estoy completamente convencido de que <span style=\"color: #3366ff;\"><strong>con este material y sus enlaces asociados, no s\u00f3lo entender\u00e9is mejor como trabaja en gran medida la ciencia actual y con qu\u00e9 prop\u00f3sitos, sino tambi\u00e9n los sinsentidos del mundo en el que nos ha tocado vivir. \u00bfLo dud\u00e1is? \u00bfS\u00ed? Pues os aseguro que quien siga el este nuevo curso terminar\u00e1 por entender lo que no desean que entendamos o lo que no queremos ver<\/strong><\/span>. Por las razones aludidas, ir\u00e9 editando post pausadamente, no esper\u00e9is un manantial continuo o incesante. <\/span><\/p>\n<p><em><span style=\"color: #800000;\">La ciencia comparada con la tecnociencia es puro romanticismo<\/span>. <\/em><\/p>\n<p><span style=\"color: #008000;\"><strong>Juan Jos\u00e9 Ib\u00e1\u00f1ez<\/strong><\/span><\/p>\n<p><span style=\"color: #800000;\"><em>Abajo os dejo el material de partida ya publicado. Ir\u00e9 ofreciendo el nuevo en sucesivos post ya vinculados a esta nueva categor\u00eda denominada Filosof\u00eda de la Tecnociencia<\/em><\/span><\/p>\n<h2><!--more--><span style=\"color: #800000;\"><strong>M\u00e9todo Cient\u00edfico y Filosof\u00eda de la Ciencia<\/strong><\/span><\/h2>\n<p><strong>Generalidades<\/strong><\/p>\n<p><a title=\"Enlace permanente a El M\u00e9todo Cient\u00edfico, la Docencia de las Ciencias y la Divulgaci\u00f3n Cient\u00edfica (Estimulando el Pensamiento Cr\u00edtico)\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/12\/16\/137252\">El M\u00e9todo Cient\u00edfico, la Docencia de las Ciencias y la Divulgaci\u00f3n Cient\u00edfica (Estimulando el Pensamiento Cr\u00edtico)<\/a><\/p>\n<p><a title=\"Enlace permanente a Naturaleza y Ense\u00f1anza de las Ciencias. Un An\u00e1lisis Cr\u00edtico\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2007\/03\/03\/60332\">Naturaleza y Ense\u00f1anza de las Ciencias. Un An\u00e1lisis Cr\u00edtico<\/a><\/p>\n<p><a title=\"Enlace permanente a \u00bfQu\u00e9 es esa cosa llamada Ciencia?\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2006\/09\/21\/42563\">\u00bfQu\u00e9 es esa cosa llamada Ciencia?<\/a><\/p>\n<p><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2006\/04\/14\/18336\">La ciencia es\u00a0 lo que \u201cEl conjunto de cient\u00edficos que definen qu\u00e9 debe ser la ciencia\u201d (Varela)<\/a><\/p>\n<p><a title=\"Enlace permanente a Figuras Legendarias de la Ciencia por los Suelos: 3. Latour Tirando por los Suelos la Sociolog\u00eda del Conocimiento\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2006\/04\/14\/18336\">La Ciencia Como Constructo Social: Latour Tirando por los Suelos la Sociolog\u00eda del Conocimiento (EL Constructivismo)<\/a><\/p>\n<p><a title=\"Enlace permanente a El M\u00e9todo Cient\u00edfico\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2006\/10\/08\/45363\">El M\u00e9todo Cient\u00edfico<\/a><\/p>\n<p><a title=\"Enlace permanente a Leyes, Teor\u00edas, Conjeturas e Hip\u00f3tesis Cient\u00edficas: \u00bfCu\u00e1les son las Diferencias?\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2008\/05\/03\/90765\">Leyes, Teor\u00edas, Conjeturas e Hip\u00f3tesis Cient\u00edficas: \u00bfCu\u00e1les son las Diferencias?<\/a><\/p>\n<p><a title=\"Enlace permanente a Pensamiento Cualitativo y Pensamiento Cuantitativo en la Pr\u00e1ctica Cient\u00edfica\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2008\/09\/05\/100251\">Pensamiento Cualitativo y Pensamiento Cuantitativo en la Pr\u00e1ctica Cient\u00edfica<\/a><\/p>\n<p><a title=\"Enlace permanente a Ciencia B\u00e1sica versus Ciencia Aplicada\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2009\/02\/05\/112364\">Ciencia B\u00e1sica versus Ciencia Aplicada<\/a><\/p>\n<p><a title=\"Enlace permanente a El Valor Econ\u00f3mico y Social de la Ciencia B\u00e1sica (Una Mirada Retrospectiva)\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2009\/08\/29\/123925\">El Valor Econ\u00f3mico y Social de la Ciencia B\u00e1sica (Una Mirada Retrospectiva)<\/a><\/p>\n<p><a title=\"Enlace permanente a Cient\u00edficos y Filosof\u00eda de la Ciencia: Una Asignatura Pendiente (La Ciencia Como Cultura vs. La Ciencia Como Instrumento)\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/01\/01\/130608\">Cient\u00edficos y Filosof\u00eda de la Ciencia: Una Asignatura Pendiente (La Ciencia Como Cultura vs. La Ciencia Como Instrumento)<\/a><\/p>\n<p><a title=\"Enlace permanente a Clasificaci\u00f3n de las Ciencias: El Ca\u00f3tico \u00c1rbol del Conocimiento\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2009\/01\/15\/111198\">Clasificaci\u00f3n de las Ciencias: El Ca\u00f3tico \u00c1rbol del Conocimiento<\/a><\/p>\n<p><a title=\"Enlace permanente a Ciencias Duras, Ciencias Blandas, Ciencias Sociales y Humanidades\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/01\/31\/135123\">Ciencias Duras, Ciencias Blandas, Ciencias Sociales y Humanidades<\/a><\/p>\n<p><a title=\"Enlace permanente a Ciencia y Tecnolog\u00eda: La Tecnofilia\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/04\/17\/135963\">Ciencia y Tecnolog\u00eda: La Tecnofilia<\/a><\/p>\n<p><a title=\"Enlace permanente a Ciencia, Arte y Creatividad: Luchando contra tus l\u00edmites\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/05\/27\/136253\">Ciencia, Arte y Creatividad: Luchando contra tus l\u00edmites<\/a><\/p>\n<p><a title=\"Enlace permanente a Pensamiento Anal\u00f3gico y Pensamiento Digital: Acerca de lo Continuo y lo Discreto\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2007\/11\/25\/79544\">Pensamiento Anal\u00f3gico y Pensamiento Digital: Acerca de lo Continuo y lo Discreto<\/a><\/p>\n<p><a title=\"Enlace permanente a Sobre lo Continuo y lo Contiguo: (\u00bfCu\u00e1ntos Lagos hay en el Mundo?) y la Naturaleza de los Suelos\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2008\/01\/27\/83378\">Sobre lo Continuo y lo Contiguo: (\u00bfCu\u00e1ntos Lagos hay en el Mundo?) y la Naturaleza de los Suelos<\/a><\/p>\n<p><strong>Tipos de Conceptos<\/strong><\/p>\n<p><a title=\"Enlace permanente a Tipos de Conceptos Cient\u00edficos: I. De Hempel a Moster\u00edn\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2008\/04\/05\/88342\">Tipos de Conceptos Cient\u00edficos: I. De Hempel a Moster\u00edn<\/a><\/p>\n<p><a title=\"Enlace permanente a Nominalismo, Realismo y Conceptualismo: Tres maneras de entender el \" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2007\/11\/17\/78925\">Nominalismo, Realismo y Conceptualismo: Tres maneras de entender el \u201csignificado de concepto\u201d<\/a><\/p>\n<p><a title=\"Enlace permanente a Los Conceptos Cient\u00edficos y sus Limitaciones: Vivir en la Incertidumbre\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2007\/11\/10\/78477\">Los Conceptos Cient\u00edficos y sus Limitaciones: Vivir en la Incertidumbre<\/a><\/p>\n<p><a title=\"Enlace permanente a Tipos de Conceptos Cient\u00edficos: II. Conceptos Comparativos\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2008\/04\/12\/88958\">Tipos de Conceptos Cient\u00edficos: II. Conceptos Comparativos<\/a><\/p>\n<p><a title=\"Enlace permanente a Tipos de Conceptos Cient\u00edficos: III. Los Conceptos M\u00e9tricos\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2008\/04\/23\/89876\">Tipos de Conceptos Cient\u00edficos: III. Los Conceptos M\u00e9tricos<\/a><\/p>\n<p><a title=\"Enlace permanente a Especies: Sus M\u00faltiples Conceptos y definiciones\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/01\/29\/138143\">Especies: Sus M\u00faltiples Conceptos y definiciones<\/a><\/p>\n<p><a title=\"Enlace permanente a Individuos y Ecosistemas o Individuos-Ecosistemas: la Ambig\u00fcedad de la Vida y la Importancia del Suelo\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2006\/07\/04\/33569\">Individuos y Ecosistemas o Individuos-Ecosistemas: la Ambig\u00fcedad de la Vida y la Importancia del Suelo<\/a><\/p>\n<p><a title=\"Enlace permanente a El Ecosistema M\u00e1s Simple del Planeta se Encuentra Bajo Nuestros Pies: Los L\u00edmites de los Conceptos\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2009\/02\/08\/112507\">El Ecosistema M\u00e1s Simple del Planeta se Encuentra Bajo Nuestros Pies: Los L\u00edmites de los Conceptos<\/a><\/p>\n<p><strong>Curso B\u00e1sico sobre Filosof\u00eda de la Ciencia y Ejemplos<\/strong><\/p>\n<p><a title=\"Enlace permanente a Curso B\u00e1sico Sobre Filosof\u00eda y Sociolog\u00eda de la Ciencia: Introducci\u00f3n\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2006\/12\/09\/54549\">Curso B\u00e1sico Sobre Filosof\u00eda y Sociolog\u00eda de la Ciencia: Introducci\u00f3n<\/a><\/p>\n<p><strong>La Ciencia a la Luz de la Inducci\u00f3n y el Empirismo<\/strong><\/p>\n<p><a title=\"Enlace permanente a Ciencia e Inducci\u00f3n (Curso B\u00e1sico Sobre Filosof\u00eda y Sociolog\u00eda de la Ciencia)\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2006\/12\/09\/54568\">Ciencia e Inducci\u00f3n (Curso B\u00e1sico Sobre Filosof\u00eda y Sociolog\u00eda de la Ciencia)<\/a><\/p>\n<p><a title=\"Enlace permanente a El Razonamiento Inductivo y la Ciencia\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2006\/12\/13\/55116\">El Razonamiento Inductivo y la Ciencia<\/a><\/p>\n<p><a title=\"Enlace permanente a L\u00f3gica y el Razonamiento Deductivo en el Pensamiento Inductivo\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2006\/12\/17\/55441\">L\u00f3gica y el Razonamiento Deductivo en el Pensamiento Inductivo<\/a><\/p>\n<p><a title=\"Enlace permanente a Predicci\u00f3n, Explicaci\u00f3n e Inducci\u00f3n\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2006\/12\/17\/55451\">Predicci\u00f3n, Explicaci\u00f3n e Inducci\u00f3n<\/a><\/p>\n<p><a title=\"Enlace permanente a El Problema de la Inducci\u00f3n: \u00bfSe puede Justificar el Principio de Inducci\u00f3n?\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2006\/12\/23\/55843\">El Problema de la Inducci\u00f3n: \u00bfSe puede Justificar el Principio de Inducci\u00f3n?<\/a><\/p>\n<p><a title=\"Enlace permanente a Posibles Respuestas en Defensa de la Inducci\u00f3n Cient\u00edfica\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2007\/01\/03\/56466\">Posibles Respuestas en Defensa de la Inducci\u00f3n Cient\u00edfica<\/a><\/p>\n<p><a title=\"Enlace permanente a El Encanto del Inductivismo Ingenuo y Algunas Reflexiones sobre la Edafolog\u00eda\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2006\/12\/22\/55811\">El Encanto del Inductivismo Ingenuo y Algunas Reflexiones sobre la Edafolog\u00eda<\/a><\/p>\n<p><a title=\"Enlace permanente a El Positivismo L\u00f3gico y el C\u00edrculo de Viena\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2007\/08\/04\/71181\">El Positivismo L\u00f3gico y el C\u00edrculo de Viena<\/a><\/p>\n<p><a title=\"Enlace permanente a Inducci\u00f3n y Probabilidad: Un Fracaso Extraordinariamente  Fruct\u00edfero\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2006\/12\/24\/55882\">Inducci\u00f3n y Probabilidad: Un Fracaso Extraordinariamente Fruct\u00edfero<\/a><\/p>\n<p><strong>Los Problemas de la Inducci\u00f3n<\/strong><\/p>\n<p><a title=\"Enlace permanente a Las Observaciones Experimentales y su Dependencia de las Teor\u00edas Cient\u00edficas (Introducci\u00f3n)\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2007\/01\/04\/56523\">Las Observaciones Experimentales y su Dependencia de las Teor\u00edas Cient\u00edficas (Introducci\u00f3n)<\/a><\/p>\n<p><a title=\"Enlace permanente a Relaci\u00f3n Entre Datos y Teor\u00edas Cient\u00edficas: Los Enunciados Observacionales Presuponen la Teor\u00eda (a vueltas con los edafometras)\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2007\/01\/12\/57120\">Relaci\u00f3n Entre Datos y Teor\u00edas Cient\u00edficas: Los Enunciados Observacionales Presuponen la Teor\u00eda (a vueltas con los edafometras)<\/a><\/p>\n<p><a title=\"Enlace permanente a M\u00e9todo Cient\u00edfico: La Teor\u00eda Gu\u00eda la Observaci\u00f3n y la Experimentaci\u00f3n (No al Rev\u00e9s)\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2007\/01\/27\/58211\">M\u00e9todo Cient\u00edfico: La Teor\u00eda Gu\u00eda la Observaci\u00f3n y la Experimentaci\u00f3n (No al Rev\u00e9s)<\/a><\/p>\n<p><a title=\"Enlace permanente a Ciencia e Inducci\u00f3n Sofisticada: El Contexto del Descubrimiento y la L\u00f3gica de la Justificaci\u00f3n\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2007\/01\/28\/58262\">Ciencia e Inducci\u00f3n Sofisticada: El Contexto del Descubrimiento y la L\u00f3gica de la Justificaci\u00f3n<\/a><\/p>\n<p><strong>Positivismo L\u00f3gico y el Falsacionismo Popperiano<\/strong><\/p>\n<p><a title=\"Enlace permanente a El Falsacionismo y la Filosof\u00eda de la Ciencia\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2007\/02\/03\/58614\">El Falsacionismo y la Filosof\u00eda de la Ciencia<\/a><\/p>\n<p><a title=\"Enlace permanente a Las Teor\u00edas Cient\u00edficas Seg\u00fan Karl Popper: La Falsabilidad\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2007\/02\/10\/59009\">Las Teor\u00edas Cient\u00edficas Seg\u00fan Karl Popper: La Falsabilidad<\/a><\/p>\n<p><a title=\"Enlace permanente a M\u00e9todo Cient\u00edfico Seg\u00fan Popper: Conjeturas y Refutaciones\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2007\/02\/10\/59010\">M\u00e9todo Cient\u00edfico Seg\u00fan Popper: Conjeturas y Refutaciones<\/a><\/p>\n<p><a title=\"Enlace permanente a El Progreso de la Ciencia Seg\u00fan Karl Popper (Un Ejemplo Sobre el Cambio Clim\u00e1tico)\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2007\/02\/17\/59475\">El Progreso de la Ciencia Seg\u00fan Karl Popper (Un Ejemplo Sobre el Cambio Clim\u00e1tico)<\/a><\/p>\n<p><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2007\/02\/24\/59924\">Evoluci\u00f3n de la Filosof\u00eda de la Ciencia de Karl Popper: Del Falsacionismo Radical o Ingenuo al Falsacionismo Sofisticado<\/a><\/p>\n<p><strong>Los Problemas del Falsacionismo de Karl Popper<\/strong><\/p>\n<p><a title=\"Enlace permanente a Las Deficiencias Del M\u00e9todo Cient\u00edfico Propuestas por Popper: El aumento de la Falsabilidad y las Modificaciones \" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2007\/03\/03\/60326\">Las Deficiencias Del M\u00e9todo Cient\u00edfico Propuestas por Popper: El aumento de la Falsabilidad y las Modificaciones \u201cad hoc\u201d (Sobre la USLE y el Paradigma de La Calidad del Suelo)<\/a><\/p>\n<p><a title=\"Enlace permanente a Inducci\u00f3n, Falsacionismo y la Confirmaci\u00f3n de las Teor\u00edas Cient\u00edficas\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2007\/03\/10\/60880\">Inducci\u00f3n, Falsacionismo y la Confirmaci\u00f3n de las Teor\u00edas Cient\u00edficas<\/a><\/p>\n<p><a title=\"Enlace permanente a Hip\u00f3tesis Audaces e Hip\u00f3tesis Prudentes en la Filosof\u00eda de la Ciencia de Karl Popper\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2007\/03\/17\/61549\">Hip\u00f3tesis Audaces e Hip\u00f3tesis Prudentes en la Filosof\u00eda de la Ciencia de Karl Popper<\/a><\/p>\n<p><a title=\"Enlace permanente a Limitaciones del Falsacionismo: La Dependencia de la Observaci\u00f3n de la Teor\u00eda y la Falibilidad de las Falsaciones\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2007\/03\/17\/61558\">Limitaciones del Falsacionismo: La Dependencia de la Observaci\u00f3n de la Teor\u00eda y la Falibilidad de las Falsaciones<\/a><\/p>\n<p><a title=\"Enlace permanente a La Complejidad de Refutar una Teor\u00eda Cient\u00edfica (Las Limitaciones del Falsacionismo)\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2007\/03\/23\/62137\">La Complejidad de Refutar una Teor\u00eda Cient\u00edfica (Las Limitaciones del Falsacionismo)<\/a><\/p>\n<p><a title=\"Enlace permanente a Relaci\u00f3n Entre Datos y Teor\u00edas Cient\u00edficas: Los Enunciados Observacionales Presuponen la Teor\u00eda (a vueltas con los edafometras)\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2007\/01\/12\/57120\">Relaci\u00f3n Entre Datos y Teor\u00edas Cient\u00edficas: Los Enunciados Observacionales Presuponen la Teor\u00eda (a vueltas con los edafometras)<\/a><\/p>\n<p><a title=\"Enlace permanente a El Fracaso del Falsacionismo de Karl Popper\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2007\/03\/23\/62145\">El Fracaso del Falsacionismo de Karl Popper<\/a><\/p>\n<p><a title=\"Enlace permanente a Las Deficiencias Del M\u00e9todo Cient\u00edfico Propuestas por Popper: El aumento de la Falsabilidad y las Modificaciones \" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2007\/03\/03\/60326\">Las Deficiencias Del M\u00e9todo Cient\u00edfico Propuestas por Popper: El aumento de la Falsabilidad y las Modificaciones \u201cad hoc\u201d (Sobre la USLE y el Paradigma de La Calidad del Suelo)<\/a><\/p>\n<p><a title=\"Enlace permanente a Validaci\u00f3n y Rechazo de Hip\u00f3tesis Cient\u00edficas: Sobre Corroboraciones y Refutaciones\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2009\/10\/04\/125914\">Validaci\u00f3n y Rechazo de Hip\u00f3tesis Cient\u00edficas: Sobre Corroboraciones y Refutaciones<\/a><\/p>\n<p><a title=\"Enlace permanente a Refutaci\u00f3n\/Corroboraci\u00f3n de Hip\u00f3tesis y Teor\u00edas Cient\u00edficas: El Problema de las Teor\u00edas Perversas\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2009\/10\/24\/127502\">Refutaci\u00f3n\/Corroboraci\u00f3n de Hip\u00f3tesis y Teor\u00edas Cient\u00edficas: El Problema de las Teor\u00edas Perversas<\/a><\/p>\n<p><strong>A modo de Inciso<\/strong><\/p>\n<p><a title=\"Enlace permanente a Teor\u00edas Cient\u00edficas Como Estructuras Complejas\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2007\/04\/01\/62705\">Teor\u00edas Cient\u00edficas Como Estructuras Complejas<\/a><\/p>\n<p><strong>La Metodolog\u00eda de los Programas Cient\u00edficos de Investigaci\u00f3n (Irme Lakatos)<\/strong><\/p>\n<p><a title=\"Enlace permanente a Imre Lakatos y su Filosof\u00eda de la Ciencia\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2007\/04\/15\/63581\">Imre Lakatos y su Filosof\u00eda de la Ciencia<\/a><\/p>\n<p><a title=\"Enlace permanente a Metodolog\u00eda de los Programas Cient\u00edficos de Investigaci\u00f3n de Imre Lakatos\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2007\/04\/21\/64084\">Metodolog\u00eda de los Programas Cient\u00edficos de Investigaci\u00f3n de Imre Lakatos<\/a><\/p>\n<p><a title=\"Enlace permanente a Metodolog\u00eda para Evaluar Los Programas de Investigaci\u00f3n Cient\u00edfica (PIC) de Imre Lakatos\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2007\/04\/28\/64566\">Metodolog\u00eda para Evaluar Los Programas de Investigaci\u00f3n Cient\u00edfica (PIC) de Imre Lakatos<\/a><\/p>\n<p><a title=\"Enlace permanente a La Comparaci\u00f3n de los Programas de Investigaci\u00f3n Cient\u00edfica de Imre Lakatos: PIC Degenerados versus Progresistas y Teor\u00eda de Juegos\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2007\/05\/05\/64981\">La Comparaci\u00f3n de los Programas de Investigaci\u00f3n Cient\u00edfica de Imre Lakatos: PIC Degenerados versus Progresistas y Teor\u00eda de Juegos<\/a><\/p>\n<p><a title=\"Enlace permanente a Sobre la Autocensura y Las Falsas Refutaciones en Ciencia (Un Ejemplo extra\u00eddo de las Relaciones Biodiversidad-Edafodiversidad)\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2006\/02\/03\/12870\">Sobre la Autocensura y Las Falsas Refutaciones en Ciencia (Un Ejemplo extra\u00eddo de las Relaciones Biodiversidad-Edafodiversidad)<\/a><\/p>\n<p><strong>Los Paradigmas de Thomas Kuhn (Historicismo)<\/strong><\/p>\n<p><a title=\"Enlace permanente a La Filosof\u00eda de la Ciencia de Thomas Kuhn: Las Teor\u00edas como Estructuras Paradigm\u00e1ticas\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2007\/05\/19\/65903\">La Filosof\u00eda de la Ciencia de Thomas Kuhn: Las Teor\u00edas como Estructuras Paradigm\u00e1ticas<\/a><\/p>\n<p><a title=\"Enlace permanente a Thomas Kuhn: Los Paradigmas y la Ciencia Normal\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2007\/05\/26\/66445\">Thomas Kuhn: Los Paradigmas y la Ciencia Normal<\/a><\/p>\n<p><a title=\"Enlace permanente a Los Cambios de Paradigma en Ciencia: Las Crisis y Revoluciones de Thomas Kuhn\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2007\/06\/02\/66914\">Los Cambios de Paradigma en Ciencia: Las Crisis y Revoluciones de Thomas Kuhn<\/a><\/p>\n<p><a title=\"Enlace permanente a Funci\u00f3n de la Ciencia Normal y las Revoluciones Cient\u00edficas en la Filosof\u00eda de Thomas Kuhn\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2007\/06\/10\/67410\">Funci\u00f3n de la Ciencia Normal y las Revoluciones Cient\u00edficas en la Filosof\u00eda de Thomas Kuhn<\/a><\/p>\n<p><a title=\"Enlace permanente a \u00bfExiste Progreso Acumulativo en Ciencia?: Una Afirmaci\u00f3n Puesta en Entredicho por Thomas Kuhn con su Dilema de la Inconmensurabilidad\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2007\/06\/17\/67885\">\u00bfExiste Progreso Acumulativo en Ciencia?: Una Afirmaci\u00f3n Puesta en Entredicho por Thomas Kuhn con su Dilema de la Inconmensurabilidad<\/a><\/p>\n<p><a title=\"Enlace permanente a \u00bfUna Ciencia y Dos Paradigmas?: Los Problemas de Comprensi\u00f3n de la Filosof\u00eda de Thomas Kuhn y las Teor\u00edas Cosmol\u00f3gicas\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2009\/01\/10\/110934\">\u00bfUna Ciencia y Dos Paradigmas?: Los Problemas de Comprensi\u00f3n de la Filosof\u00eda de Thomas Kuhn y las Teor\u00edas Cosmol\u00f3gicas<\/a><\/p>\n<p><strong>Otro Inciso<\/strong><\/p>\n<p><a title=\"Enlace permanente a Filosof\u00eda de la Ciencia: Lakatos Frente a Kuhn y Popper: \u00bfQue Marca la Diferencia?\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2007\/05\/12\/65443\">Filosof\u00eda de la Ciencia: Lakatos Frente a Kuhn y Popper: \u00bfQue Marca la Diferencia?<\/a><\/p>\n<p><strong>La Escuela Anarquista de Paul Feyerabend y M\u00e1s<\/strong><\/p>\n<p><a title=\"Enlace permanente a Relativismo Radical en la Filosof\u00eda de la Ciencia: El Anarquismo de Paul Feyerabend\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2007\/07\/08\/69567\">Relativismo Radical en la Filosof\u00eda de la Ciencia: El Anarquismo de Paul Feyerabend<\/a><\/p>\n<p><a title=\"Enlace permanente a Filosof\u00edas Radicales de la Ciencia: Las Modas en la Ciencia Contempor\u00e1nea\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2007\/07\/14\/69915\">Filosof\u00edas Radicales de la Ciencia: Las Modas en la Ciencia Contempor\u00e1nea<\/a><\/p>\n<p><a title=\"Enlace permanente a El Concepto de Especie, Tipo de Suelo y la Filosof\u00eda de la Ciencia (El Realismo Promiscuo)\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2007\/12\/23\/81275\">El Concepto de Especie, Tipo de Suelo y la Filosof\u00eda de la Ciencia (El Realismo Promiscuo)<\/a><\/p>\n<p><strong>Otras Perspectivas sobre de la Ciencia <\/strong><\/p>\n<p><a title=\"Enlace permanente a Seredipidad o Serendipia y la L\u00f3gica de los Descubrimientos Cient\u00edficos\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2007\/10\/20\/76837\">Seredipidad o Serendipia y la L\u00f3gica de los Descubrimientos Cient\u00edficos<\/a><\/p>\n<p><a title=\"Enlace permanente a La Verdad Cient\u00edfica Como Consenso (Las Sociedades Cient\u00edficas)\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2007\/09\/01\/73087\">La Verdad Cient\u00edfica Como Consenso (Las Sociedades Cient\u00edficas)<\/a><\/p>\n<p><a title=\"Enlace permanente a El Concepto de Especie, Tipo de Suelo y la Filosof\u00eda de la Ciencia (El Realismo Promiscuo)\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2007\/12\/23\/81275\">El Concepto de Especie, Tipo de Suelo y la Filosof\u00eda de la Ciencia (El Realismo Promiscuo)<\/a><\/p>\n<p><a title=\"Enlace permanente a El M\u00e9todo Cient\u00edfico, la Docencia de las Ciencias y la Divulgaci\u00f3n Cient\u00edfica (Estimulando el Pensamiento Cr\u00edtico)\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/12\/16\/137252\">El M\u00e9todo Cient\u00edfico, la Docencia de las Ciencias y la Divulgaci\u00f3n Cient\u00edfica (Estimulando el Pensamiento Cr\u00edtico)<\/a><\/p>\n<p><a title=\"Enlace permanente a El Discurso Cient\u00edfico, los Conceptos Contrarios y la Perspectiva de Jean-Marc L\u00e9vy-Leblond\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2007\/12\/01\/80077\">El Discurso Cient\u00edfico, los Conceptos Contrarios y la Perspectiva de Jean-Marc L\u00e9vy-Leblond<\/a><\/p>\n<p><a title=\"Enlace permanente a Las Necesarias Quimeras de la Ciencia: Sobre los Reduccionismos Ontol\u00f3gicos, Epistemol\u00f3gicos, Teor\u00edas Anidadas y Jerarqu\u00edas Cient\u00edficas\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2008\/01\/19\/82675\">Las Necesarias Quimeras de la Ciencia: Sobre los Reduccionismos Ontol\u00f3gicos, Epistemol\u00f3gicos, Teor\u00edas Anidadas y Jerarqu\u00edas Cient\u00edficas<\/a><\/p>\n<p><a title=\"Permanent Link to Serendipia e Indagaci\u00f3n Cient\u00edfica\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2014\/02\/09\/145133\">Serendipia e Indagaci\u00f3n Cient\u00edfica<\/a><\/p>\n<p><strong>Filosof\u00edas con Base Cient\u00edfica (Cosmolog\u00edas)<\/strong><\/p>\n<p><a title=\"Enlace permanente a Filosof\u00eda de la Ciencia versus \" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2007\/07\/20\/70329\">Filosof\u00eda de la Ciencia versus \u201cFilosof\u00edas Cient\u00edficas\u201d<\/a><\/p>\n<p><a title=\"Enlace permanente a \u00bfFilosof\u00eda Cu\u00e1ntica?\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2007\/08\/12\/71613\">\u00bfFilosof\u00eda Cu\u00e1ntica?<\/a><\/p>\n<p><a title=\"Enlace permanente a \u00bfEs la Mente Fractal?: Dedicado a Eusebio Sempere\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2007\/08\/01\/71004\">\u00bfEs la Mente Fractal?: Dedicado a Eusebio Sempere<\/a><\/p>\n<p><a title=\"Enlace permanente a La Mente Humana, Espejo de la Naturaleza (y Viceversa)\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2008\/08\/13\/98653\">La Mente Humana, Espejo de la Naturaleza (y Viceversa)<\/a><\/p>\n<p><a title=\"Enlace permanente a \u00bfVida Inorg\u00e1nica en el Cosmos?: La Fuerza de la Autoorganizaci\u00f3n de la Materia\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2007\/08\/20\/72138\">\u00bfVida Inorg\u00e1nica en el Cosmos?: La Fuerza de la Autoorganizaci\u00f3n de la Materia<\/a><\/p>\n<p><a title=\"Enlace permanente a Filosof\u00eda de la Ciencia y Ficci\u00f3n: \u00bfVida Inorg\u00e1nica?\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2007\/08\/25\/72534\">Filosof\u00eda de la Ciencia y Ficci\u00f3n: \u00bfVida Inorg\u00e1nica?<\/a><\/p>\n<p><a title=\"Enlace permanente a Evoluci\u00f3n Social: Redes, Jerarqu\u00edas y Sistemas Complejos\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2008\/04\/10\/88762\">Evoluci\u00f3n Social: Redes, Jerarqu\u00edas y Sistemas Complejos<\/a><\/p>\n<p><a title=\"Enlace permanente a La Magia de los N\u00fameros, Diversidad de la Naturaleza y Una Teor\u00eda del Todo\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/06\/12\/136399\">La Magia de los N\u00fameros, Diversidad de la Naturaleza y Una Teor\u00eda del Todo<\/a><\/p>\n<p><strong>\u00bfExiste la Filosof\u00eda de la Tecnolog\u00eda?<\/strong><\/p>\n<p><a title=\"Enlace permanente a Filosof\u00eda de la Tecnolog\u00eda y Ortega y Gasset: Reflexiones Sobre Chauvinismos, Antichauvinismos e Imperialismos\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2007\/11\/03\/78003\">Filosof\u00eda de la Tecnolog\u00eda y Ortega y Gasset: Reflexiones Sobre Chauvinismos, Antichauvinismos e Imperialismos<\/a><\/p>\n<p><strong>Estudios Sociales de la Ciencia <\/strong><\/p>\n<p><a title=\"Enlace permanente a Filosof\u00eda de la Ciencia versus Filosof\u00eda de la Investigaci\u00f3n: \u00bfQui\u00e9n es Bruno Latour?\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2008\/01\/05\/81875\">Filosof\u00eda de la Ciencia versus Filosof\u00eda de la Investigaci\u00f3n: \u00bfQui\u00e9n es Bruno Latour?<\/a><\/p>\n<p><a title=\"Enlace permanente a El Realismo De Bruno Latour y la Actitud Sectaria de los Cient\u00edficos\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2008\/01\/12\/82262\">El Realismo De Bruno Latour y la Actitud Sectaria de los Cient\u00edficos<\/a><\/p>\n<p><a title=\"Enlace permanente a \u00bfUna Sociedad Libre o Esclavos del Poder?: El Affair de Wikipedia\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2007\/08\/17\/71972\">\u00bfUna Sociedad Libre o Esclavos del Poder?: El Affair de Wikipedia<\/a><\/p>\n<p><a title=\"Enlace permanente a Wikipedia versus Citizendium: En defensa de la Participaci\u00f3n Ciudadana o el Temor al Imperio de las Masas\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2007\/05\/07\/65094\">Wikipedia versus Citizendium: En defensa de la Participaci\u00f3n Ciudadana o el Temor al Imperio de las Masas<\/a><\/p>\n<p><a title=\"Enlace permanente a Mente y Realidad: Descartes y Kant desde la \u00d3ptica de Bruno Latour\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2008\/02\/02\/83717\">Mente y Realidad: Descartes y Kant desde la \u00d3ptica de Bruno Latour<\/a><\/p>\n<p><a title=\"Enlace permanente a Percepci\u00f3n Individual, Social y Cultural de la Realidad, Seg\u00fan Bruno Latour\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2008\/02\/16\/84625\">Percepci\u00f3n Individual, Social y Cultural de la Realidad, Seg\u00fan Bruno Latour<\/a><\/p>\n<p><a title=\"Enlace permanente a Los Poderes y su Terror al Imperio de las Masas: Bruno Latour y las Ense\u00f1anzas de las Ciencias de la Complejidad\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2008\/02\/23\/85199\">Los Poderes y su Terror al Imperio de las Masas: Bruno Latour y las Ense\u00f1anzas de las Ciencias de la Complejidad<\/a><\/p>\n<p><a title=\"Enlace permanente a Concepto y Tipos de Modelos Cient\u00edficos\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2008\/05\/10\/91441\">Concepto y Tipos de Modelos Cient\u00edficos<\/a><\/p>\n<p><strong>Aspectos Sobre Sociolog\u00eda de La Ciencia<\/strong><\/p>\n<p><a title=\"Permanent Link to \u00c9tica para la Ciencia y la Sociedad\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2014\/05\/17\/145609\">\u00c9tica para la Ciencia y la Sociedad<\/a><\/p>\n<p><a title=\"Enlace permanente a Escuelas Invisibles y Criterios de Autoridad en Ciencia\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2007\/04\/03\/62825\">Escuelas Invisibles y Criterios de Autoridad en Ciencia<\/a><\/p>\n<p><a title=\"Enlace permanente a Los Fracasos Experimentales y su Valor en la Ciencia (Reflexiones filos\u00f3ficas 1)\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2008\/08\/09\/98394\">Los Fracasos Experimentales y su Valor en la Ciencia (Reflexiones filos\u00f3ficas 1)<\/a><\/p>\n<p><a title=\"Enlace permanente a Relaciones Causa-Efecto en la Pr\u00e1ctica Cient\u00edfica (Reflexiones filos\u00f3ficas 2)\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2008\/08\/11\/98511\">Relaciones Causa-Efecto en la Pr\u00e1ctica Cient\u00edfica (Reflexiones filos\u00f3ficas 2)<\/a><\/p>\n<p><a title=\"Enlace permanente a Metaciencia y Ciencia (Una Nueva Perspectiva)\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2009\/05\/23\/118756\">Metaciencia y Ciencia (Una Nueva Perspectiva)<\/a><\/p>\n<p><a title=\"Enlace permanente a An\u00e1lisis Metacient\u00edficos y Metaciencia\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2009\/06\/14\/120173\">An\u00e1lisis Metacient\u00edficos y Metaciencia<\/a><\/p>\n<p><a title=\"Enlace permanente a Sociolog\u00eda de la Ciencia: Verdades y Falsas Verdades en Ciencia: Los T\u00f3picos Impregnantes\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2008\/10\/03\/102504\">Sociolog\u00eda de la Ciencia: Verdades y Falsas Verdades en Ciencia: Los T\u00f3picos Impregnantes<\/a><\/p>\n<p><a title=\"Enlace permanente a El papel de la Heterodoxia y la Trasgresi\u00f3n en el Progreso Cient\u00edfico\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/08\/15\/136914\">El papel de la Heterodoxia y la Trasgresi\u00f3n en el Progreso Cient\u00edfico<\/a><\/p>\n<p><a title=\"Enlace permanente a Metaciencia y Ciencia (Una Nueva Perspectiva)\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2009\/05\/23\/118756\">Metaciencia y Ciencia (Una Nueva Perspectiva)<\/a><\/p>\n<p><a title=\"Enlace permanente a La Creatividad de los Cient\u00edficos y el Origen de Sus Teor\u00edas\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2009\/06\/20\/120522\">La Creatividad de los Cient\u00edficos y el Origen de Sus Teor\u00edas<\/a><\/p>\n<p><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2014\/10\/11\/145574\"><span style=\"color: #0000ff;\">La Creatividad Cient\u00edfica y El Futuro de la Ciencia<\/span><\/a><\/p>\n<p><a title=\"Enlace permanente a Ciencia, Religi\u00f3n y Filosof\u00eda: Evoluci\u00f3n, Creacionismo, Teor\u00eda del Dise\u00f1o Inteligente y las Elucubraciones de Cient\u00edficos y Fil\u00f3sofos\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2007\/12\/08\/80527\">Ciencia, Religi\u00f3n y Filosof\u00eda: Evoluci\u00f3n, Creacionismo, Teor\u00eda del Dise\u00f1o Inteligente y las Elucubraciones de Cient\u00edficos y Fil\u00f3sofos<\/a><\/p>\n<p><a title=\"Enlace permanente a Los Cient\u00edficos, la Religi\u00f3n, la Prensa y el Marketing\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/09\/04\/136982\">Los Cient\u00edficos, la Religi\u00f3n, la Prensa y el Marketing<\/a><\/p>\n<p><a title=\"Enlace permanente a Las Grandes Instalaciones Cient\u00edficas en Tiempos de Crisis\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/09\/10\/140316\">Las Grandes Instalaciones Cient\u00edficas en Tiempos de Crisis<\/a><\/p>\n<p><a title=\"Enlace permanente a El Progreso de la Ciencia y La Computaci\u00f3n: \u00a1No es Oro todo lo que Reluce!\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2008\/10\/20\/104123\">El Progreso de la Ciencia y La Computaci\u00f3n: \u00a1No es Oro todo lo que Reluce!<\/a><\/p>\n<p><a title=\"Enlace permanente a Las Incertidumbres de la Ciencia: Ajustes a los Modelos de Regresi\u00f3n Estad\u00edstica\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2008\/06\/05\/93876\">Las Incertidumbres de la Ciencia: Ajustes a los Modelos de Regresi\u00f3n Estad\u00edstica<\/a><\/p>\n<p><a title=\"Enlace permanente a El Dudoso Estatus de los Modelos de Simulaci\u00f3n Predictivos en la Filosof\u00eda de la Ciencia\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2007\/10\/27\/77520\">El Dudoso Estatus de los Modelos de Simulaci\u00f3n Predictivos en la Filosof\u00eda de la Ciencia<\/a><\/p>\n<p><a title=\"Enlace permanente a Desvirtualizaci\u00f3n de la Ciencia por el Marketing Cient\u00edfico-Tecnol\u00f3gico: Sobre el Talento, Innovaci\u00f3n, Sociedad del Conocimiento y Sociedad de la Informaci\u00f3n\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2009\/01\/22\/111605\">Desvirtualizaci\u00f3n de la Ciencia por el Marketing Cient\u00edfico-Tecnol\u00f3gico: Sobre el Talento, Innovaci\u00f3n, Sociedad del Conocimiento y Sociedad de la Informaci\u00f3n<\/a><\/p>\n<p><a title=\"Enlace permanente a Ciencia Confusa: El Papel de las Controversias Cient\u00edficas (sobre hombres modernos y neandertales)\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/05\/01\/136050\">Ciencia Confusa: El Papel de las Controversias Cient\u00edficas (sobre hombres modernos y neandertales)<\/a><\/p>\n<p><a title=\"Enlace permanente a La Caja Negra: Ciencia, Tecnolog\u00eda y Globalizaci\u00f3n\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2009\/05\/09\/117935\">La Caja Negra: Ciencia, Tecnolog\u00eda y Globalizaci\u00f3n<\/a><\/p>\n<p><a title=\"Enlace permanente a Los L\u00edmites de la Ciencia y Sus Posibles Futuros\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2009\/09\/13\/124745\">Los L\u00edmites de la Ciencia y Sus Posibles Futuros<\/a><\/p>\n<p><a title=\"Enlace permanente a Profec\u00edas de la Ciencia\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2009\/09\/27\/125505\">Profec\u00edas de la Ciencia<\/a><\/p>\n<p><a title=\"Enlace permanente a Ciencia y Civilizaciones: El ejemplo de la Medicina China\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2009\/10\/10\/126328\">Ciencia y Civilizaciones: El ejemplo de la Medicina China<\/a><\/p>\n<p><a title=\"Enlace permanente a Historia de la Ciencia,  Racismo, Coeficiente Intelectual y el Tama\u00f1o del Cr\u00e1neo Humano\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2009\/10\/17\/126951\">Historia de la Ciencia, Racismo, Coeficiente Intelectual y el Tama\u00f1o del Cr\u00e1neo Humano<\/a><\/p>\n<p><a title=\"Enlace permanente: Los Escr\u00fapulos de la Ciencia: En los Brazos de Morfeo\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/07\/23\/139899\">Los Escr\u00fapulos de la Ciencia: En los Brazos de Morfeo (EL valor de Una Buena siesta<\/a><\/p>\n<p><a title=\"Enlace permanente a La Cuantificaci\u00f3n de las Ciencias: Ciencias y Matem\u00e1ticas\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2009\/12\/13\/130060\">La Cuantificaci\u00f3n de las Ciencias: Ciencias y Matem\u00e1ticas<\/a><\/p>\n<p><a title=\"Enlace permanente a Ciencia para Qui\u00e9n y para Qu\u00e9, en un Mundo Econ\u00f3micamente Globalizado\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/07\/23\/136741\">Ciencia para Qui\u00e9n y para Qu\u00e9, en un Mundo Econ\u00f3micamente Globalizado<\/a><\/p>\n<p><a title=\"Enlace permanente a Investigaci\u00f3n Participativa o Ciencia Ciudadana (Los Paracient\u00edficos)\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/08\/07\/136821\">Investigaci\u00f3n Participativa o Ciencia Ciudadana (Los Paracient\u00edficos)<\/a><\/p>\n<p><a title=\"Enlace permanente a Ciencia Inversa: El colapso de la Civilizaci\u00f3n\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/04\/23\/139043\">Ciencia Inversa: El colapso de la Civilizaci\u00f3n<\/a><\/p>\n<p><a title=\"Enlace permanente a Ciencia Olvidada: \" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/11\/27\/137519\">Ciencia Olvidada: \u201cEl Efecto Internet\u201d<\/a><\/p>\n<p><a title=\"Enlace permanente a Sobre los Posibles Or\u00edgenes de la Vida (Entre Jaimito y Mafalda)\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/03\/05\/138530\">Sobre los Posibles Or\u00edgenes de la Vida (Entre Jaimito y Mafalda)<\/a><\/p>\n<p><a title=\"Enlace permanente a La NASA y Sus Noticias (\u00bfHisteria y\/o Necesidad?): Guerras Medi\u00e1ticas\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/02\/19\/138336\">La NASA y Sus Noticias (\u00bfHisteria y\/o Necesidad?): Guerras Medi\u00e1ticas<\/a><\/p>\n<p><a title=\"Enlace permanente a La Decadencia de Occidente y el Colapso del Estado del Bienestar (Y la Ciencia de por Medio)\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/08\/13\/140119\">La Decadencia de Occidente y el Colapso del Estado del Bienestar (Y la Ciencia de por Medio)<\/a><\/p>\n<p><a title=\"Enlace permanente a La Inteligencia Tecnol\u00f3gica (Un debate Muy Poco Inteligente)\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/08\/06\/140034\">La Inteligencia Tecnol\u00f3gica: \u00bfla Tecnolog\u00eda nos hace m\u00e1s Inteligentes?\u00a0 (Un debate Muy Poco Inteligente)<\/a><\/p>\n<p><a title=\"Enlace permanente a El Estado del Bienestar No es I+D+i\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/07\/30\/139966\">El Estado del Bienestar No es I+D+i<\/a><\/p>\n<p><a title=\"Enlace permanente a La Percepci\u00f3n Social y Cient\u00edfica de las Drogas\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/10\/23\/140482\">La Percepci\u00f3n Social y Cient\u00edfica de las Drogas<\/a><\/p>\n<p><a title=\"Enlace permanente a Tecnolog\u00eda: Creando \u00eddolos con Pies de Barro\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/10\/07\/140472\">Tecnolog\u00eda: Creando \u00eddolos con Pies de Barro<\/a><\/p>\n<p><a title=\"Permanent Link to La Neutralidad de la Ciencia: Intereses Institucionales, Guerras Nacionalistas y Noticias Cient\u00edficas\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/03\/27\/144055\">La Neutralidad de la Ciencia: Intereses Institucionales, Guerras Nacionalistas y Noticias Cient\u00edficas<\/a><\/p>\n<p><strong>\u00bfC\u00f3mo se escoge una disciplina Cient\u00edfica de profesi\u00f3n?<\/strong><\/p>\n<p><a title=\"Enlace permanente a La Memoria Soterrada de la Mente de un Cient\u00edfico\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2007\/04\/22\/64126\">La Memoria Soterrada de la Mente de un Cient\u00edfico<\/a><\/p>\n<p><strong>Ciencia, pol\u00edtica y medios de comunicaci\u00f3n de masas<\/strong><\/p>\n<p><a title=\"Enlace permanente a La Politizaci\u00f3n de la Ciencia Comienza a ser Reconocida\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/03\/26\/138667\">La Politizaci\u00f3n de la Ciencia Comienza a ser Reconocida<\/a><\/p>\n<p><a title=\"Enlace permanente a La Objetividad de los Cient\u00edficos: \" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2007\/07\/02\/69174\">La Objetividad de los Cient\u00edficos: \u201cLos apologetas\u201d<\/a><\/p>\n<p><a title=\"Enlace permanente a Cient\u00edficos Productivos versus Cient\u00edficos Internacionalmente Reconocidos\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2006\/06\/30\/33237\">Cient\u00edficos Productivos versus Cient\u00edficos Internacionalmente Reconocidos<\/a><\/p>\n<p><a title=\"Enlace permanente a La Edafodiversidad: Una historia Repleta de Grandes Cient\u00edficos Olvidados 4. Parece que todo vale para defender la teor\u00eda vigente cuando se acumulan en evidencias en su contra\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2006\/02\/01\/12815\">La Edafodiversidad: Una historia Repleta de Grandes Cient\u00edficos <\/a><\/p>\n<p><a title=\"Enlace permanente a El Nacionalismo y la Ciencia (La Ciencia de los Nacionalismos): Bibliograf\u00eda Sobre la Historia de la Edafolog\u00eda\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2006\/12\/07\/54317\">El Nacionalismo y la Ciencia (La Ciencia de los Nacionalismos): Bibliograf\u00eda Sobre la Historia de la Edafolog\u00eda<\/a><\/p>\n<p><a title=\"Enlace permanente a Los Equ\u00edvocos Lenguajes de las Ciencias\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/10\/16\/137140\">Los Equ\u00edvocos Lenguajes de las Ciencias<\/a><\/p>\n<p><a title=\"Enlace permanente a Los Errores de la Naturaleza y el Vocabulario Cient\u00edfico\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2007\/11\/07\/78269\">Los Errores de la Naturaleza y el Vocabulario Cient\u00edfico<\/a><\/p>\n<p><a title=\"Enlace permanente a Las Perversiones de los \u00cdndices de Impacto de Revistas Indexadas (1)\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2006\/07\/26\/35511\">Las Perversiones de los \u00cdndices de Impacto de Revistas Indexadas (1)<\/a><\/p>\n<p><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2006\/08\/01\/35935\">La Inaceptable Inercia de las Revistas Indexadas frente a la Informaci\u00f3n de Internet a la Hora de Cubrir las Demandas Sociales de I + D + i<\/a><\/p>\n<p><a title=\"Enlace permanente a \u00bfHacer Buena Ciencia o Publicar?: Entre la Espada y la Pared\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2007\/05\/18\/65838\">\u00bfHacer Buena Ciencia o Publicar?: Entre la Espada y la Pared<\/a><\/p>\n<p><a title=\"Enlace permanente a Como Hacerse Famoso en Ciencia: La Regla Metodolog\u00eda (Methodological Rule)\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2006\/12\/06\/54156\">Como Hacerse Famoso en Ciencia: La Regla Metodolog\u00eda (Methodological Rule)<\/a><\/p>\n<p><a title=\"Enlace permanente a Como Hacerse Famoso en Ciencia sin Despeinarse: Las Revisiones Cient\u00edficas\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2007\/04\/02\/62751\">Como Hacerse Famoso en Ciencia sin Despeinarse: Las Revisiones Cient\u00edficas<\/a><\/p>\n<p><a title=\"Enlace permanente a La Acr\u00f3nimofilia o Como Hacerse Famoso en Ciencia sin Despeinarse: Pedotranfer Functions, Biodiversity and Pedodiversity\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2006\/11\/05\/49597\">La Acr\u00f3nimofilia o Como Hacerse Famoso en Ciencia sin Despeinarse: Pedotranfer Functions, Biodiversity and Pedodiversity<\/a><\/p>\n<p><a title=\"Enlace permanente a De la Edafolog\u00eda a la Zona Cr\u00edtica Terrestre: \u00bfIniciativa Institucional o Cambio de Paradigma Cient\u00edfico?\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2008\/07\/22\/97306\">De la Edafolog\u00eda a la Zona Cr\u00edtica Terrestre: \u00bfIniciativa Institucional o Cambio de Paradigma Cient\u00edfico?<\/a><\/p>\n<p><a title=\"Enlace permanente a Producci\u00f3n de Biocombustibles a partir de Residuos Lignocelul\u00f3sicos: Riesgo sobre la Productividad de los Suelos\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2009\/06\/08\/119798\">Producci\u00f3n de Biocombustibles a partir de Residuos Lignocelul\u00f3sicos: Riesgo sobre la Productividad de los Suelos<\/a><\/p>\n<p><a title=\"Enlace permanente a Secuestro de Carbono, Nitr\u00f3geno del Suelo y Justus von Liebig (los Desprop\u00f3sitos de la Ciencia Contempor\u00e1nea)\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2007\/09\/12\/73827\">Secuestro de Carbono, Nitr\u00f3geno del Suelo y Justus von Liebig (los Desprop\u00f3sitos de la Ciencia Contempor\u00e1nea)<\/a><\/p>\n<p><a title=\"Enlace permanente a Conceptos Pol\u00edticamente Correctos y Cient\u00edficamente Incorrectos: El Caso de la Desertificaci\u00f3n\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2006\/03\/05\/14823\">Conceptos Pol\u00edticamente Correctos y Cient\u00edficamente Incorrectos: El Caso de la Desertificaci\u00f3n<\/a><\/p>\n<p><a title=\"Enlace permanente a Pol\u00edtica Internacional y Desertificaci\u00f3n\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2006\/03\/01\/14613\">Pol\u00edtica Internacional y Desertificaci\u00f3n<\/a><\/p>\n<p><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2006\/02\/27\/14455\">Desertificaci\u00f3n: \u00bfMito o Realidad?: Los Problemas Inherentes al Concepto de Desertificaci\u00f3n<\/a><\/p>\n<p><strong>Ciencia y Cuantificaci\u00f3n<\/strong><\/p>\n<p><a title=\"Enlace permanente a La Cuantificaci\u00f3n de las Ciencias: Ciencias y Matem\u00e1ticas\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2009\/12\/13\/130060\">La Cuantificaci\u00f3n de las Ciencias: Ciencias y Matem\u00e1ticas<\/a><\/p>\n<p><a title=\"Enlace permanente a El Reto de la Edafolog\u00eda como Ciencia B\u00e1sica\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2009\/12\/01\/129569\">El Reto de la Edafolog\u00eda como Ciencia B\u00e1sica<\/a><\/p>\n<p><a title=\"Enlace permanente a Teor\u00eda de Sistemas: El Dilema de la Demarcaci\u00f3n de sus L\u00edmites y Elementos\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/09\/13\/137119\">Teor\u00eda de Sistemas: El Dilema de la Demarcaci\u00f3n de sus L\u00edmites y Elementos<\/a><\/p>\n<p><a title=\"Enlace permanente a \u00bfCuantos Tipos de Suelos Hay en el Mundo?; \u00bfCuantas Clases de Ecosistemas Hay en el Mundo?\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2007\/04\/09\/63097\">\u00bfCuantos Tipos de Suelos Hay en el Mundo?; \u00bfCu\u00e1ntas Clases de Ecosistemas Hay en el Mundo?<\/a><\/p>\n<p><strong>Fraude y Mala Praxis Cient\u00edfica<\/strong><\/p>\n<p><a title=\"Enlace permanente a Sobre Las Anatom\u00edas de los Fraudes Cient\u00edficos, la Praxis Profesional y El Periodismo: Introducci\u00f3n\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2006\/06\/23\/32482\">Sobre Las Anatom\u00edas de los Fraudes Cient\u00edficos, la Praxis Profesional y El Periodismo: Introducci\u00f3n<\/a><\/p>\n<p><a title=\"Enlace permanente a Fraude Cient\u00edfico: Quien Denuncia Paga las Consecuencias (1\u00aa Regularidad)\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2006\/09\/04\/39703\">Fraude Cient\u00edfico: Quien Denuncia Paga las Consecuencias (1\u00aa Regularidad)<\/a><\/p>\n<p><a title=\"Enlace permanente a El Fraude Cient\u00edfico y los denominados \" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2006\/09\/07\/40092\">El Fraude Cient\u00edfico y los denominados \u201cJ\u00f3venes Prodigiosos\u201d (2\u00ba Regularidad)<\/a><\/p>\n<p><a title=\"Enlace permanente a El Fraude Cient\u00edfico y la Respuesta de las Revistas Internacionales (Tercera Regularidad)\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2006\/09\/12\/40912\">El Fraude Cient\u00edfico y la Respuesta de las Revistas Internacionales (Tercera Regularidad)<\/a><\/p>\n<p><a title=\"Enlace permanente a Ciencia, Cient\u00edficos y Deontolog\u00eda\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2009\/11\/01\/127926\">Ciencia, Cient\u00edficos y Deontolog\u00eda<\/a><\/p>\n<p><a title=\"Enlace permanente a \u00c9tica y Bio\u00e9tica: Los Riesgos de la Actividad Cient\u00edfica (\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/01\/15\/137822\">\u00c9tica y Bio\u00e9tica: Los Riesgos de la Actividad Cient\u00edfica (\u201c<em>Allegro Ma Non troppo<\/em>\u201d)<\/a><\/p>\n<p><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2006\/02\/06\/13000\">Sobre Mala Praxis Cient\u00edfica, el Fraude y Las Conductas \u00c9ticas: Ejemplos Extra\u00eddos del \u00c1mbito de la Diversidad<\/a><\/p>\n<p><a title=\"Enlace permanente a Premios N\u00f3beles. Jurados y Corrupci\u00f3n\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2008\/12\/19\/109793\">Premios N\u00f3beles. Jurados y Corrupci\u00f3n<\/a><\/p>\n<p><a title=\"Enlace permanente a Cuando la Ciencia Finalmente Hace Justicia\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/10\/08\/140467\">Cuando la Ciencia Finalmente Hace Justicia (los cuasi-cristales)<\/a><\/p>\n<p><a title=\"Permanent Link to Corrupci\u00f3n de la Indagaci\u00f3n Cient\u00edfica: Publicar  a toda costa, en detrimento de la calidad\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2014\/07\/19\/144710\">Corrupci\u00f3n de la Indagaci\u00f3n Cient\u00edfica: Publicar a toda costa, en detrimento de la calidad<\/a><\/p>\n<p><a title=\"Permanent Link to \" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2014\/08\/29\/144886\">\u201cAsesinando la ciencia\u201d, \u201cla ciencia ha perdido su coraz\u00f3n\u201d. Premios Nobel contra el sistema actual de promoci\u00f3n cient\u00edfica<\/a><\/p>\n<p><a title=\"Permanent Link to Los C\u00e1rteles de la Ciencia, Malas Conductas Cient\u00edficas y la Revisi\u00f3n por Iguales (Un caso Reciente en las Ciencias del Suelo)\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2017\/06\/16\/148925\">Los C\u00e1rteles de la Ciencia, Malas Conductas Cient\u00edficas y la Revisi\u00f3n por Iguales (Un caso Reciente en las Ciencias del Suelo)<\/a><\/p>\n<p><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/01\/29\/141275\"><span style=\"color: #0000ff;\">Metodolog\u00eda de la Ciencia. Contenidos Para un Curso de Postgrado (Material B\u00e1sico) 29 de enero de 2012<\/span><\/a><\/p>\n<p><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/02\/04\/141280\"><span style=\"color: #0000ff;\">Metodolog\u00eda de la Ciencia. Contenidos Para un Curso de Postgrado (II. Sociolog\u00eda de la Ciencia y algo M\u00e1s)<\/span><\/a><\/p>\n<p><strong>Curso breve sobre Periodismo Cient\u00edfico <\/strong><\/p>\n<p><a title=\"Enlace permanente a La NASA y Sus Noticias (\u00bfHisteria y\/o Necesidad?): Guerras Medi\u00e1ticas\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/02\/19\/138336\">La NASA y Sus Noticias (\u00bfHisteria y\/o Necesidad?): Guerras Medi\u00e1ticas<\/a><\/p>\n<p><a title=\"Enlace permanente a La Semana que unos Cient\u00edficos Dijeron que Pod\u00edan Cambiar el Mundo \u00bfDe la Fusi\u00f3n Fr\u00eda a la Teletransportaci\u00f3n del DNA?\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/01\/30\/138165\">La Semana que unos Cient\u00edficos Dijeron que Pod\u00edan Cambiar el Mundo \u00bfDe la Fusi\u00f3n Fr\u00eda a la Teletransportaci\u00f3n del DNA?<\/a><\/p>\n<p><a title=\"Enlace permanente a Resistencia a los Antibi\u00f3ticos y Guerra Armament\u00edstica: \u00bfAmnesia o Cara Dura?\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2008\/04\/04\/88277\">Resistencia a los Antibi\u00f3ticos y Guerra Armament\u00edstica: \u00bfAmnesia o Cara Dura?<\/a><\/p>\n<p><a title=\"Enlace permanente a Caf\u00e9, Caf\u00e9: Caf\u00e9 para todo y para todos\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/12\/17\/140915\">Caf\u00e9, Caf\u00e9: Caf\u00e9 para todo y para todos<\/a><\/p>\n<p><a title=\"Enlace permanente a El Ecosistema como un Organismo (Viejo Vino en Nuevas Botellas)\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/07\/10\/139359\">El Ecosistema como un Organismo (Viejo Vino en Nuevas Botellas)<\/a><\/p>\n<p><a title=\"Enlace permanente a Periodismo Cient\u00edfico y Desertificaci\u00f3n: Mareando la Misma Perdiz Durante D\u00e9cadas\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2006\/06\/22\/32280\">Periodismo Cient\u00edfico y Desertificaci\u00f3n: Mareando la Misma Perdiz Durante D\u00e9cadas<\/a><\/p>\n<p><a title=\"Enlace permanente a Con la Cabeza en las Estrellas y los Pies en el Suelo\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/06\/11\/139482\">Con la Cabeza en las Estrellas y los Pies en el Suelo<\/a><\/p>\n<p><a title=\"Enlace permanente a Curso Breve para un Nuevo Periodismo Cient\u00edfico\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/04\/27\/139017\">Curso Breve para un Nuevo Periodismo Cient\u00edfico<\/a><\/p>\n<p><a title=\"Enlace permanente a La Crisis Actual del Periodismo Cient\u00edfico (Curso de Periodismo Cient\u00edfico y 2)\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/04\/30\/139027\">La Crisis Actual del Periodismo Cient\u00edfico (Curso de Periodismo Cient\u00edfico y 2)<\/a><\/p>\n<p><a title=\"Enlace permanente a Los Errores del Periodismo Cient\u00edfico a la luz de los Estudios Sociales de la Ciencia (Curso de Periodismo Cient\u00edfico y 3)\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/05\/08\/139036\">Los Errores del Periodismo Cient\u00edfico a la luz de los Estudios Sociales de la Ciencia (Curso de Periodismo Cient\u00edfico y 3)<\/a><\/p>\n<p><a title=\"Enlace permanente a La Actividad Cient\u00edfica como una Red de Relaciones (Curso de Periodismo Cient\u00edfico y 4)\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/05\/14\/139056\">La Actividad Cient\u00edfica como una Red de Relaciones (Curso de Periodismo Cient\u00edfico y 4)<\/a><\/p>\n<p><a title=\"Enlace permanente a La Ciencia como Red de Interrelaciones Humanas-No Humanas (Curso de Periodismo Cient\u00edfico y 5)\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/05\/22\/139155\">La Ciencia como Red de Interrelaciones Humanas-No Humanas (Curso de Periodismo Cient\u00edfico y 5)<\/a><\/p>\n<p><a title=\"Enlace permanente a Interacci\u00f3n entre Periodistas y Cient\u00edficos (Curso de Periodismo Cient\u00edfico y 6)\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/05\/29\/139271\">Interacci\u00f3n entre Periodistas y Cient\u00edficos (Curso de Periodismo Cient\u00edfico y 6)<\/a><\/p>\n<p><a title=\"Enlace permanente a Voceros de la Ciencia versus Periodismo Cient\u00edfico Independiente (Curso de Periodismo Cient\u00edfico y 7)\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/06\/04\/139469\">Voceros de la Ciencia versus Periodismo Cient\u00edfico Independiente (Curso de Periodismo Cient\u00edfico y 7)<\/a><\/p>\n<p><a title=\"Enlace permanente a El Periodista Cient\u00edfico como Paracient\u00edfico y Soci\u00f3logo del Entramado Inherente a la Indagaci\u00f3n Investigadora (Curso Breve de Periodismo Cient\u00edfico y 8)\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/06\/27\/139653\">El Periodista Cient\u00edfico como Paracient\u00edfico y Soci\u00f3logo del Entramado Inherente a la Indagaci\u00f3n Investigadora (Curso Breve de Periodismo Cient\u00edfico y 8)<\/a><\/p>\n<p><strong>Ejemplos Pr\u00e1cticos: <\/strong><\/p>\n<p><strong>Ejemplo 1. Como los Cient\u00edficos No Comprenden la Ciencia<\/strong><\/p>\n<p><strong>Categorizaci\u00f3n, Clasificaciones, Taxonom\u00edas, Cartograf\u00edas y Redes<\/strong><\/p>\n<p><a title=\"Enlace permanente a La Crisis de las Ciencias Taxonomicas\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2008\/07\/24\/97485\">La Crisis de las Ciencias Taxon\u00f3micas<\/a><\/p>\n<p><a title=\"Enlace permanente a Taxonom\u00edas Num\u00e9ricas versus Taxonom\u00edas Tradicionales\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2007\/07\/11\/69745\">Taxonom\u00edas Num\u00e9ricas versus Taxonom\u00edas Tradicionales<\/a><\/p>\n<p><a title=\"Enlace permanente a El Nacimiento de una Ciencia: Generalidades y An\u00e1lisis de un Caso Concreto (Planetodiversidad)\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2009\/03\/07\/114024\">El Nacimiento de una Ciencia: Generalidades y An\u00e1lisis de un Caso Concreto (Planetodiversidad)<\/a><\/p>\n<p><a title=\"Enlace permanente a Clasificaciones, Percepci\u00f3n del Mundo y Progreso Acumulativo de la Ciencia\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2007\/12\/15\/80973\">Clasificaciones, Percepci\u00f3n del Mundo y Progreso Acumulativo de la Ciencia<\/a><\/p>\n<p><a title=\"Enlace permanente a Ciencia, Cognici\u00f3n, Aprendizaje y Percepci\u00f3n del Mundo\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/07\/11\/136661\">Ciencia, Cognici\u00f3n, Aprendizaje y Percepci\u00f3n del Mundo<\/a><\/p>\n<p><a title=\"Enlace permanente a Clasificando los Suelos Desde la Edafosfera a los Edafotaxa: La Categorizaci\u00f3n\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2006\/04\/20\/19148\">Clasificando los Suelos Desde la Edafosfera a los Edafotaxa: La Categorizaci\u00f3n<\/a><\/p>\n<p><a title=\"Enlace permanente a Categorizaci\u00f3n, Clasificaci\u00f3n y Partici\u00f3n: El Caso de las Taxonom\u00edas de Suelos\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2006\/04\/24\/19864\">Categorizaci\u00f3n, Clasificaci\u00f3n y Partici\u00f3n: El Caso de las Taxonom\u00edas de Suelos<\/a><\/p>\n<p><a title=\"Enlace permanente a \u00bfPorqu\u00e9 las Clasificaciones de Suelos Suelen Ser Jer\u00e1rquicas?\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2006\/06\/03\/27769\">\u00bfPorqu\u00e9 las Clasificaciones de Suelos Suelen Ser Jer\u00e1rquicas?<\/a><\/p>\n<p><a title=\"Enlace permanente a Los Rasgos Matem\u00e1ticos Elementales de las Clasificaciones de Suelos (y Biol\u00f3gicas): Las Curvas de Willis\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2006\/05\/14\/22409\">Los Rasgos Matem\u00e1ticos Elementales de las Clasificaciones de Suelos (y Biol\u00f3gicas): Las Curvas de Willis<\/a><\/p>\n<p><a title=\"Enlace permanente a Taxonom\u00edas Edafol\u00f3gicas y Biol\u00f3gicas: Estructuras Fractales y Multifractales\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2006\/10\/25\/47839\">Taxonom\u00edas Edafol\u00f3gicas y Biol\u00f3gicas: Estructuras Fractales y Multifractales<\/a><\/p>\n<p><a title=\"Enlace permanente a Taxonom\u00edas Folk y taxonom\u00edas Cient\u00edficas: las Ense\u00f1anzas de la Antropolog\u00eda Sobre la Estructura de las Clasificaciones\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2006\/05\/19\/23860\">Taxonom\u00edas Folk y taxonom\u00edas Cient\u00edficas: las Ense\u00f1anzas de la Antropolog\u00eda Sobre la Esuctura de las Clasificaciones<\/a><\/p>\n<p><a title=\"Enlace permanente a Taxonom\u00eda de Suelos y Sesgos Cognitivos: El Efecto Protot\u00edpico de Rosch\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2006\/06\/21\/32036\">Taxonom\u00eda de Suelos y Sesgos Cognitivos: El Efecto Protot\u00edpico de Rosch<\/a><\/p>\n<p><a title=\"Enlace permanente a Los Sesgos Geogr\u00e1ficos de las Taxonom\u00edas de Suelos (y las Biol\u00f3gicas)\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2006\/08\/02\/36074\">Los Sesgos Geogr\u00e1ficos de las Taxonom\u00edas de Suelos (y las Biol\u00f3gicas)<\/a><\/p>\n<p><a title=\"Enlace permanente a Taxonom\u00edas Edafol\u00f3gicas y Biol\u00f3gicas: El \" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2006\/11\/18\/51456\">Taxonom\u00edas Edafol\u00f3gicas y Biol\u00f3gicas: El \u201cSesgo de Muestreo\u201d y Sus Repercusiones sobre las Estructuras Clasificatorias<\/a><\/p>\n<p><a title=\"Enlace permanente a Psicolog\u00eda Cognitiva, N\u00fameros M\u00e1gicos, Regla de Miller y Taxonom\u00eda de Suelos\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2007\/12\/28\/81441\">Psicolog\u00eda Cognitiva, N\u00fameros M\u00e1gicos, Regla de Miller y Taxonom\u00eda de Suelos<\/a><\/p>\n<p><a title=\"Enlace permanente a La Estructura de los Diccionarios: Jerarqu\u00edas, Leyes de Escala y Regla de Miller\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2008\/05\/21\/92492\">La Estructura de los Diccionarios: Jerarqu\u00edas, Leyes de Escala y Regla de Miller<\/a><\/p>\n<p><a title=\"Enlace permanente a Observaciones Cient\u00edficas: Concepci\u00f3n Popular y Aportaciones de las Neurociencias (Los Colores del Suelo)\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2007\/01\/06\/56646\">Observaciones Cient\u00edficas: Concepci\u00f3n Popular y Aportaciones de las Neurociencias (Los Colores del Suelo)<\/a><\/p>\n<p><a title=\"Enlace permanente a Redes en Malla versus Jerarqu\u00edas. Similitudes y Diferencias\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2008\/03\/27\/87566\">Redes en Malla versus Jerarqu\u00edas. Similitudes y Diferencias<\/a><\/p>\n<p><a title=\"Enlace permanente a Concepto de Red y Sistema Jer\u00e1rquico: Aspectos Estructurales\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2008\/03\/25\/87333\">Concepto de Red y Sistema Jer\u00e1rquico: Aspectos Estructurales<\/a><\/p>\n<p><a title=\"Enlace permanente a Redes y Sistemas Jer\u00e1rquicos: Aspectos Funcionales\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2008\/03\/26\/87469\">Redes y Sistemas Jer\u00e1rquicos: Aspectos Funcionales<\/a><\/p>\n<p><a title=\"Enlace permanente a Los Mundos Peque\u00f1os y los Seis Grados de Separaci\u00f3n: Una Conjetura Corroborada \u00bfY la Regla de Miller?\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2008\/08\/12\/98585\">Los Mundos Peque\u00f1os y los Seis Grados de Separaci\u00f3n: Una Conjetura Corroborada \u00bfY la Regla de Miller?<\/a><\/p>\n<p><a title=\"Enlace permanente a Biodiversidad y Ciencias Taxon\u00f3micas. Cuantificando las Especies del Planeta\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/12\/02\/137230\">Biodiversidad y Ciencias Taxon\u00f3micas. Cuantificando las Especies del Planeta (taxonom\u00edas como inventarios)<\/a><\/p>\n<p><a title=\"Enlace permanente a La Mente Fractal de los Edaf\u00f3logos y Cart\u00f3grafos de Suelos: La USDA Research Information\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/03\/05\/135571\">La Mente Fractal de los Edaf\u00f3logos y Cart\u00f3grafos de Suelos: La USDA Research Information<\/a><\/p>\n<p><strong>Ejemplo 2. Teor\u00edas Cient\u00edficas por Decreto Ley<\/strong><\/p>\n<p><a title=\"Enlace permanente a Hombre y Naturaleza: Dos visiones, dos futuros\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/02\/21\/135460\">Hombre y Naturaleza: Dos visiones, dos futuros<\/a><\/p>\n<p><a title=\"Enlace permanente a Darvinistas, No Darvinistas y Antidarvinistas: \u00bfY si Darwin No Hubiera Nacido?\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2009\/12\/27\/130483\">Darvinistas, No Darvinistas y Antidarvinistas: \u00bfY si Darwin No Hubiera Nacido?<\/a><\/p>\n<p><a title=\"Enlace permanente a Figuras Legendarias de la Ciencia por los Suelos: 1. Darwin y sus Lombrices Pisoteando a Arist\u00f3teles\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2006\/04\/12\/18252\">Figuras Legendarias de la Ciencia por los Suelos: 1. Darwin y sus Lombrices Pisoteando a Arist\u00f3teles<\/a><\/p>\n<p><a title=\"Enlace permanente a La Evoluci\u00f3n Simbi\u00f3tica: Innovaci\u00f3n a trav\u00e9s de Simbiosis (Sobre bacterias, Insectos Sociales y Ciclos Biogeoqu\u00edmicos)\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/01\/09\/130844\">La Evoluci\u00f3n Simbi\u00f3tica: Innovaci\u00f3n a trav\u00e9s de Simbiosis (Sobre bacterias, Insectos Sociales y Ciclos Biogeoqu\u00edmicos)<\/a><\/p>\n<p><a title=\"Enlace permanente a El Origen de Gaia: Selecci\u00f3n Natural y Gaia no son Compatibles\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2008\/10\/17\/103843\">El Origen de Gaia: Selecci\u00f3n Natural y Gaia no son Compatibles<\/a><\/p>\n<p><a title=\"Enlace permanente a Teor\u00eda de la Evoluci\u00f3n y Sociedad: Neodarvinismo vs Teor\u00eda Simbiog\u00e9nica de la Evoluci\u00f3n;  Microsoft vs \" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2007\/02\/14\/59275\">Teor\u00eda de la Evoluci\u00f3n y Sociedad: Neodarvinismo vs. Teor\u00eda Simbiog\u00e9nica de la Evoluci\u00f3n; Microsoft vs \u201cCreative Commons\u201d<\/a><\/p>\n<p><a title=\"Enlace permanente a Guerra Por un Nuevo Modelo de Sociedad: Neodarwinistas en la Superficie, Simbiog\u00e9nicos en el \" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2007\/02\/14\/59285\">Guerra Por un Nuevo Modelo de Sociedad: Neodarwinistas en la Superficie, Simbiog\u00e9nicos en el \u201cMundo de Matrix\u201d<\/a><\/p>\n<p><a title=\"Enlace permanente a De la Madre Tierra a Gaia y\/o Gea Pasando por la Biofilia\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/05\/17\/136092\">De la Madre Tierra a Gaia y\/o Gea Pasando por la Biofilia<\/a><\/p>\n<p><a title=\"Enlace permanente a Teor\u00eda de Juegos, Evoluci\u00f3n y Complejidad y Crisis Econ\u00f3mica\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2009\/04\/18\/116623\">Teor\u00eda de Juegos, Evoluci\u00f3n y Complejidad y Crisis Econ\u00f3mica<\/a><\/p>\n<p><strong>Ejemplo 3. Ciencia y Chauvinismo Humano<\/strong><\/p>\n<p><a title=\"Enlace permanente a Los Nuevos L\u00edmites del Cuaternario\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2009\/09\/25\/125425\">Los Nuevos L\u00edmites del Cuaternario<\/a><\/p>\n<p><a title=\"Enlace permanente a Ciencia o Teleolog\u00eda. Los Conceptos de Calidad, Funciones y Salud del suelo.\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2006\/03\/13\/15712\">Ciencia o Teleolog\u00eda. Los Conceptos de Calidad, Funciones y Salud del suelo.<\/a><\/p>\n<p><a title=\"Enlace permanente a Funciones del Suelo, Calidad del Suelo y Representaciones del Sistema Ed\u00e1fico: Las Funciones del Suelo\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2006\/05\/09\/21576\">Funciones del Suelo, Calidad del Suelo y Representaciones del Sistema Ed\u00e1fico: Las Funciones del Suelo<\/a><\/p>\n<p><strong>Transhumanismo y Poshumanismo<\/strong><\/p>\n<p><a title=\"Permanent Link to Jugando a Ser Inmortales: Transhumanismo y Singularidad Tecnol\u00f3gica (El d\u00eda en que dejemos de ser humanos\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2017\/06\/09\/148137\">Jugando a Ser Inmortales: Transhumanismo y Singularidad Tecnol\u00f3gica (El d\u00eda en que dejemos de ser humanos<\/a><span style=\"color: #000000;\">.<\/span><\/p>\n<p><strong><span style=\"text-decoration: underline;\">Post m\u00e1s Recientes especialmente a partir de 2012<\/span><\/strong><strong>.<\/strong><\/p>\n<p><a title=\"Permanent Link to Ciencia y Neoliberalismo Econ\u00f3mico\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/05\/05\/141902\">Ciencia y Neoliberalismo Econ\u00f3mico<\/a><\/p>\n<p><a title=\"Permanent Link to Tecnolog\u00edas de Primera y Segunda Generaci\u00f3n (Un Riesgo Social en Ciernes)\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/03\/11\/141424\">Tecnolog\u00edas de Primera y Segunda Generaci\u00f3n (Un Riesgo Social en Ciernes)<\/a><\/p>\n<p><a title=\"Permanent Link to Internet del Futuro y Tecnolog\u00eda: M\u00e1s All\u00e1 de la Tonter\u00eda\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/05\/12\/141525\">Internet del Futuro y Tecnolog\u00eda: M\u00e1s All\u00e1 de la Tonter\u00eda<\/a><\/p>\n<p><a title=\"Permanent Link to Comercializaci\u00f3n de la Ciencia: Riesgos y Contradicciones\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/06\/03\/142137\">Comercializaci\u00f3n de la Ciencia: Riesgos y Contradicciones<\/a><\/p>\n<p><a title=\"Permanent Link to Los Cient\u00edficos sus Vanidades y los Premios: \u00a1Son como Ni\u00f1os!\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/06\/16\/142262\">Los Cient\u00edficos sus Vanidades y los Premios: \u00a1Son como Ni\u00f1os!<\/a><\/p>\n<p><a title=\"Permanent Link to El Olvido de la Ciencia: El Efecto Internet\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/06\/23\/141403\">El Olvido de la Ciencia: El Efecto Internet<\/a><\/p>\n<p><a title=\"Permanent Link to Cient\u00edficos a la Guillotina. El Riesgo de Dedicarse a los Modelos Predictivos\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/10\/27\/143073\">Cient\u00edficos a la Guillotina. El Riesgo de Dedicarse a los Modelos Predictivos<\/a><\/p>\n<p><a title=\"Permanent Link to Ciencia, Xenofobia, Sociedad y Epidemias\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/11\/03\/141794\">Ciencia, Xenofobia, Sociedad y Epidemias<\/a><\/p>\n<p><a title=\"Permanent Link to Creatividad Cient\u00edfica. Entre la Vigilia y el Sue\u00f1o\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/02\/15\/142599\">Creatividad Cient\u00edfica. Entre la Vigilia y el Sue\u00f1o<\/a><\/p>\n<p><a title=\"Permanent Link to La Neutralidad de la Ciencia: Intereses Institucionales, Guerras Nacionalistas y Noticias Cient\u00edficas\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/03\/27\/144055\">La Neutralidad de la Ciencia: Intereses Institucionales, Guerras Nacionalistas y Noticias Cient\u00edficas<\/a><\/p>\n<p><a title=\"Permanent Link to El Origen y Evoluci\u00f3n de la Complejidad\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/04\/12\/144043\">El Origen y Evoluci\u00f3n de la Complejidad<\/a><\/p>\n<p><a title=\"Permanent Link to La Filosof\u00eda de la Ciencia en la Docencia Universitaria\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/09\/13\/144426\">La Filosof\u00eda de la Ciencia en la Docencia Universitaria<\/a><\/p>\n<p><a title=\"Permanent Link to La Filosof\u00eda y Sociolog\u00eda de La Ciencia en la Docencia Universitaria: la Reacci\u00f3n de los Alumnos\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/09\/21\/144433\">La Filosof\u00eda y Sociolog\u00eda de La Ciencia en la Docencia Universitaria: la Reacci\u00f3n de los Alumnos<\/a><\/p>\n<p><a title=\"Permanent Link to Las Funciones del Suelo y el Dise\u00f1o Inteligente (Un C\u00e1ncer que Desgarra las Ciencias de Suelo)\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/09\/26\/144528\">Las Funciones del Suelo y el Dise\u00f1o Inteligente (Un C\u00e1ncer que Desgarra las Ciencias de Suelo)<\/a><\/p>\n<p><a title=\"Permanent Link to La Divulgaci\u00f3n Cient\u00edfica y su Futuro \u00a1Que divulguen otros!\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/10\/17\/143302\">La Divulgaci\u00f3n Cient\u00edfica y su Futuro \u00a1Que divulguen otros!<\/a><\/p>\n<p><a title=\"Permanent Link to El Biochar, Inteligencia Militar y Espionaje Masivo entre las Fuerzas del  Bien y del Mal en el Seno del Suelo\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/11\/09\/144655\">El Biochar, Inteligencia Militar y Espionaje Masivo entre las Fuerzas del Bien y del Mal en el Seno del Suelo<\/a><\/p>\n<p><a title=\"Permanent Link to Medicinas personalizadas, y a la carta, bajo la econom\u00eda neoliberal\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/11\/23\/143748\">Medicinas personalizadas, y a la carta, bajo la econom\u00eda neoliberal<\/a><\/p>\n<p><a title=\"Permanent Link to La Decadencia de las Civilizaciones y su Complejidad\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2014\/11\/01\/145559\">La Decadencia de las Civilizaciones y su Complejidad<\/a><\/p>\n<p><a title=\"Permanent Link to La Regla Metodol\u00f3gica, Citaciones Cient\u00edficas e \" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2015\/05\/29\/146296\">La Regla Metodol\u00f3gica, Citaciones Cient\u00edficas e \u201cHistoria de la Ciencia\u201d (The Top 100 Papers of Nature)<\/a><\/p>\n<p><a title=\"Permanent Link to Superorganismos y Sociobiolog\u00eda: Una Perspectiva Tenebrosamente Inquietante\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2015\/11\/06\/145975\">Superorganismos y Sociobiolog\u00eda: Una Perspectiva Tenebrosamente Inquietante<\/a><\/p>\n<p><a title=\"Permanent Link to Como Publicar en una Revista de Impacto Investigaciones Intrascendentes, por decir algo\u2026 (Comunidades del Suelo, Cambio Clim\u00e1tico y Pesticidas)\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2015\/11\/23\/146521\">Como Publicar en una Revista de Impacto Investigaciones Intrascendentes, por decir algo\u2026 (Comunidades del Suelo, Cambio Clim\u00e1tico y Pesticidas)<\/a><\/p>\n<p><a title=\"Permanent Link to El Circo de la Ciencia Contempor\u00e1nea\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2015\/12\/29\/146594\">El Circo de la Ciencia Contempor\u00e1nea<\/a><\/p>\n<p><a title=\"Permanent Link to Calidad de los Art\u00edculos Cient\u00edficos: Fomentando la Mediocridad y Las Bellas Durmientes\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2016\/01\/24\/147103\">Calidad de los Art\u00edculos Cient\u00edficos: Fomentando la Mediocridad y Las Bellas Durmientes<\/a><\/p>\n<p><a title=\"Permanent Link to \u00bfQu\u00e9 es la Ciencia?: \u00bfLo Sabemos los Cient\u00edficos?\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2016\/04\/22\/147410\">\u00bfQu\u00e9 es la Ciencia?: \u00bfLo Sabemos los Cient\u00edficos?<\/a><\/p>\n<p><a title=\"Permanent Link to Cient\u00edficos Creativos e Innovadores: El extra\u00f1o caso de Vladimir Markovich Fridland\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2016\/04\/27\/147112\">Cient\u00edficos Creativos e Innovadores: El extra\u00f1o caso de Vladimir Markovich Fridland<\/a><\/p>\n<p><a title=\"Permanent Link to Disciplinas Maduras e Inmaduras: \u00bfHay disciplinas maduras?\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2016\/05\/13\/147687\">Disciplinas Maduras e Inmaduras: \u00bfHay disciplinas madurEl Mito de los biocombustibles y el cambio clim\u00e1tico. Fraude Social, degradaci\u00f3n de tierras, contaminaci\u00f3n y pol\u00edtica insensataas?<\/a><\/p>\n<p><a title=\"Permanent Link to Prostituyendo la Historia de la Ciencia (Ciencia Amn\u00e9sica e Imperio Anglosaj\u00f3n)\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2016\/12\/08\/147937\">Prostituyendo la Historia de la Ciencia (Ciencia Amn\u00e9sica e Imperio Anglosaj\u00f3n)<\/a><\/p>\n<p><a title=\"Permanent Link to \u00bfQu\u00e9 es la Geodiversidad?: El Concepto, Definici\u00f3n\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2017\/03\/28\/148175\">\u00bfQu\u00e9 es la Geodiversidad?: El Concepto, Definici\u00f3n<\/a><\/p>\n<p><a title=\"Permanent Link to Envejecimiento, Futuro de la Humanidad y Obsolescencia Programada en un Mundo Superpoblado\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2017\/04\/10\/148104\">Envejecimiento, Futuro de la Humanidad y Obsolescencia Programada en un Mundo Superpoblado<\/a><\/p>\n<p><a title=\"Permanent Link to Compartir libremente el conocimiento: \u00bfEl fin del Publica o Perece?\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2017\/06\/20\/148221\">Compartir libremente el conocimiento: \u00bfEl fin del Publica o Perece?<\/a><\/p>\n<p><a title=\"Permanent Link to Los J\u00f3venes Edaf\u00f3logos y su Indignaci\u00f3n (\u00bfleg\u00edtimas reclamaciones o xenofobia bajo el suelo?)\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2017\/06\/22\/149018\">Los J\u00f3venes Edaf\u00f3logos y su Indignaci\u00f3n (\u00bfleg\u00edtimas reclamaciones o xenofobia bajo el suelo?)<\/a><\/p>\n<p><a title=\"Permanent Link to El Reciclado del Conocimiento Cient\u00edfico y el Origen de los Seres Humanos\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2017\/06\/27\/148243\">El Reciclado del Conocimiento Cient\u00edfico y el Origen de los Seres Humanos<\/a><\/p>\n<p><a title=\"Permanent Link to Las Mentes creativas ante el desprecio del Establishment Conservador (frases celebres recopiladas por Jos\u00e9 Luis Rubio)\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2017\/11\/02\/148517\">Las Mentes creativas ante el desprecio del Establishment Conservador (frases celebres recopiladas por Jos\u00e9 Luis Rubio)<\/a><\/p>\n<p><a title=\"Permanent Link to Soberan\u00eda Alimentaria: los pa\u00edses ricos se alimentan a costa de los que se encuentran en v\u00edas de desarrollo (devorando suelos)\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2018\/04\/03\/148813\">Soberan\u00eda Alimentaria: los pa\u00edses ricos se alimentan a costa de los que se encuentran en v\u00edas de desarrollo (devorando suelos)<\/a><\/p>\n<p><a title=\"Permanent Link to El Poblamiento precolombino del Amazonas: Agricultura, gesti\u00f3n h\u00eddrica y forestal (Un duro golpe a la ecolog\u00eda te\u00f3rica).\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2018\/04\/09\/148850\">El Poblamiento precolombino del Amazonas: Agricultura, gesti\u00f3n h\u00eddrica y forestal (Un duro golpe a la ecolog\u00eda te\u00f3rica).<\/a><\/p>\n<p><a title=\"Permanent Link to La excelencia Cient\u00edfica y la Publicaci\u00f3n de Art\u00edculos de Investigaci\u00f3n: Entre la meritocracia, el rigor, el politiqueo y la serendipia.\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2018\/08\/01\/149080\">La excelencia Cient\u00edfica y la Publicaci\u00f3n de Art\u00edculos de Investigaci\u00f3n: Entre la meritocracia, el rigor, el politiqueo y la serendipia.<\/a><\/p>\n<p><a title=\"Permanent Link to Cambio Clim\u00e1tico, Degradaci\u00f3n Ambiental, Demograf\u00eda y Envejecimiento\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2018\/09\/24\/149107\">Cambio Clim\u00e1tico, Degradaci\u00f3n Ambiental, Demograf\u00eda y Envejecimiento<\/a><\/p>\n<p><a title=\"Permanent Link to Sobre la raz\u00f3n y la racionalidad cient\u00edfica: \u00bfPor qu\u00e9 ha generado sensaci\u00f3n y preocupaci\u00f3n que los micro y nanopl\u00e1sticos se encuentren ya en nuestros intestinos?\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2018\/10\/26\/149926\">Sobre la raz\u00f3n y la racionalidad cient\u00edfica: \u00bfPor qu\u00e9 ha generado sensaci\u00f3n y preocupaci\u00f3n que los micro y nanopl\u00e1sticos se encuentren ya en nuestros intestinos?<\/a>.<\/p>\n<p><strong>Categor\u00edas que contienen materiales interesantes para entender la tecnociencia<\/strong><strong><\/strong><\/p>\n<p><span style=\"color: #000000;\">\u201c<\/span><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/curso-basico-sobre-filosofia-y-sociologia-de-la-ciencia\"><span style=\"color: #0000ff;\">Curso B\u00e1sico Sobre Filosof\u00eda y Sociolog\u00eda de la Ciencia<\/span><\/a><span style=\"color: #000000;\">\u201d<\/span><\/p>\n<p><span style=\"color: #000000;\">\u201c<\/span><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/curso-breve-sobre-periodismo-cientifico\"><span style=\"color: #0000ff;\">Curso breve sobre Periodismo Cient\u00edfico<\/span><\/a><span style=\"color: #000000;\"> \u201d<\/span><\/p>\n<p><span style=\"color: #000000;\">\u201c<\/span><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/curso-basico-de-ciencia-para-jovenes-universitarios-y-tecnologos\"><span style=\"color: #0000ff;\">Curso b\u00e1sico de ciencia para j\u00f3venes universitarios y tecn\u00f3logos<\/span><\/a><span style=\"color: #000000;\">\u201d<\/span><\/p>\n<p><span style=\"color: #000000;\">\u201c<\/span><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/filosofia-historia-y-sociologia-de-la-edafologia\"><span style=\"color: #0000ff;\">Filosof\u00eda, Historia y Sociolog\u00eda de la Edafolog\u00eda<\/span><\/a><span style=\"color: #000000;\">\u201d<\/span><\/p>\n<p><span style=\"color: #000000;\">\u201c<\/span><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/fraude-y-mala-praxis-cientifica\"><span style=\"color: #0000ff;\">Fraude y Mala Praxis Cient\u00edfica<\/span><\/a><span style=\"color: #000000;\">\u201d<\/span><\/p>\n<p><span style=\"color: #000000;\">\u201c<\/span><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/la-crisis-de-la-edafologia\"><span style=\"color: #0000ff;\">La Crisis de la Edafolog\u00eda<\/span><\/a><span style=\"color: #000000;\">\u201d<\/span><\/p>\n<p><span style=\"color: #000000;\">\u201c<\/span><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/prensa-y-politica-cientifica\"><span style=\"color: #0000ff;\">Prensa y Pol\u00edtica Cient\u00edfica<\/span><\/a><span style=\"color: #000000;\">\u201d<\/span><\/p>\n<p><span style=\"color: #000000;\">\u201c<\/span><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/redes-complejas-ecologicas-sociales-y-el-mundo-de-internet\"><span style=\"color: #0000ff;\">Redes Complejas, Ecol\u00f3gicas, Sociales y el Mundo de Internet<\/span><\/a><span style=\"color: #000000;\">\u201d<\/span><\/p>\n<p><span style=\"color: #000000;\">\u201c<\/span><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/curso-breve-sobre-periodismo-cientifico\"><span style=\"color: #0000ff;\">Curso breve sobre Periodismo Cient\u00edfico<\/span><\/a><span style=\"color: #000000;\">\u201d<\/span><\/p>\n<h3>Im\u00e1genes Relacionadas:<\/h3>","protected":false},"excerpt":{"rendered":"<p>\u00a0 Fuente: Colaje de im\u00e1genes Google Entre 2007 y 2012, aproximadamente, abrimos e implementamos los principales contenidos de nuestra categor\u00eda \u201cCurso B\u00e1sico Sobre Filosof\u00eda y Sociolog\u00eda de la Ciencia\u201d. Jam\u00e1s pens\u00e9 que fuera a tener el \u00e9xito que ha alcanzado. Poco despu\u00e9s disfrut\u00e9 como profesor de estos temas en un master de posgrado y excelencia de la UPM (ver por ejemplo\u00a0 la siguiente entradilla \u201cLa Convergencia entre Disciplinas Cient\u00edficas e Ingenier\u00edas\u201d). El curso, a pesar de ir dirigido a ingenieros, es decir j\u00f3venes con una mentalidad pr\u00e1ctica, gust\u00f3 a la mayor\u00eda de los alumnos. Obviamente, entre la filosof\u00eda y sociolog\u00eda\u2026<\/p>\n","protected":false},"author":26,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0},"categories":[13638,39962,609,7651,597,605],"tags":[46820,2355,39963,46880],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":4}},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Cr\u00edtica a la tecnociencia, Qu\u00e9 es la tecnociencia, Curso b\u00e1sico, razones,\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Juan Jos\u00e9 Ib\u00e1\u00f1ez\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2019\/02\/14\/150022\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Un Universo invisible bajo nuestros pies - Los suelos y la vida\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"De la Filosof\u00eda de la Ciencia a la Filosof\u00eda de la Tecnociencia (Nuevo Curso B\u00e1sico y Sus Razones) - Un Universo invisible bajo nuestros pies\" \/>\n\t\t<meta property=\"og:description\" content=\"Cr\u00edtica a la tecnociencia, Qu\u00e9 es la tecnociencia, Curso b\u00e1sico, razones,\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2019\/02\/14\/150022\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2019-02-14T12:58:48+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2019-02-14T12:58:48+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/juan.j.marti.14\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"De la Filosof\u00eda de la Ciencia a la Filosof\u00eda de la Tecnociencia (Nuevo Curso B\u00e1sico y Sus Razones) - Un Universo invisible bajo nuestros pies\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Cr\u00edtica a la tecnociencia, Qu\u00e9 es la tecnociencia, Curso b\u00e1sico, razones,\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2019\\\/02\\\/14\\\/150022#blogposting\",\"name\":\"De la Filosof\\u00eda de la Ciencia a la Filosof\\u00eda de la Tecnociencia (Nuevo Curso B\\u00e1sico y Sus Razones) - Un Universo invisible bajo nuestros pies\",\"headline\":\"De la Filosof\\u00eda de la Ciencia a la Filosof\\u00eda de la Tecnociencia (Nuevo Curso B\\u00e1sico y Sus Razones)\",\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/wp-content\\\/blogs.dir\\\/42\\\/files\\\/405\\\/tecnociencia-introduccion.jpg\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2019\\\/02\\\/14\\\/150022\\\/#articleImage\"},\"datePublished\":\"2019-02-14T13:58:48+01:00\",\"dateModified\":\"2019-02-14T13:58:48+01:00\",\"inLanguage\":\"es-ES\",\"commentCount\":7,\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2019\\\/02\\\/14\\\/150022#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2019\\\/02\\\/14\\\/150022#webpage\"},\"articleSection\":\"Curso b\\u00e1sico de ciencia para jovenes universitarios y tecn\\u00f3logos, Curso B\\u00e1sico sobre Filosof\\u00eda de la Tecnociencia, Curso B\\u00e1sico Sobre Filosof\\u00eda y Sociolog\\u00eda de la Ciencia, Curso breve sobre Periodismo Cient\\u00edfico, Filosof\\u00eda, Historia y Sociolog\\u00eda de la Edafolog\\u00eda, Fraude y Mala Praxis Cient\\u00edfica, curso b\\u00e1sico, filosof\\u00eda de la ciencia, Filosof\\u00eda de le tecnociencia, sociolog\\u00eda de la ciencia\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2019\\\/02\\\/14\\\/150022#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/filosofia-historia-y-sociologia-de-la-edafologia#listItem\",\"name\":\"Filosof\\u00eda, Historia y Sociolog\\u00eda de la Edafolog\\u00eda\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/filosofia-historia-y-sociologia-de-la-edafologia#listItem\",\"position\":2,\"name\":\"Filosof\\u00eda, Historia y Sociolog\\u00eda de la Edafolog\\u00eda\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/filosofia-historia-y-sociologia-de-la-edafologia\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2019\\\/02\\\/14\\\/150022#listItem\",\"name\":\"De la Filosof\\u00eda de la Ciencia a la Filosof\\u00eda de la Tecnociencia (Nuevo Curso B\\u00e1sico y Sus Razones)\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2019\\\/02\\\/14\\\/150022#listItem\",\"position\":3,\"name\":\"De la Filosof\\u00eda de la Ciencia a la Filosof\\u00eda de la Tecnociencia (Nuevo Curso B\\u00e1sico y Sus Razones)\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/filosofia-historia-y-sociologia-de-la-edafologia#listItem\",\"name\":\"Filosof\\u00eda, Historia y Sociolog\\u00eda de la Edafolog\\u00eda\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#organization\",\"name\":\"Un Universo invisible bajo nuestros pies\",\"description\":\"Los suelos y la vida\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/files\\\/2022\\\/02\\\/logo.png\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2019\\\/02\\\/14\\\/150022\\\/#organizationLogo\",\"width\":217,\"height\":72},\"image\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2019\\\/02\\\/14\\\/150022\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/juan.j.marti.14\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo\",\"name\":\"Juan Jos\\u00e9 Ib\\u00e1\\u00f1ez\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2019\\\/02\\\/14\\\/150022#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/387f3a100385573d8f42ce2a3211fd1c?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Juan Jos\\u00e9 Ib\\u00e1\\u00f1ez\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2019\\\/02\\\/14\\\/150022#webpage\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2019\\\/02\\\/14\\\/150022\",\"name\":\"De la Filosof\\u00eda de la Ciencia a la Filosof\\u00eda de la Tecnociencia (Nuevo Curso B\\u00e1sico y Sus Razones) - Un Universo invisible bajo nuestros pies\",\"description\":\"Cr\\u00edtica a la tecnociencia, Qu\\u00e9 es la tecnociencia, Curso b\\u00e1sico, razones,\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2019\\\/02\\\/14\\\/150022#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\"},\"datePublished\":\"2019-02-14T13:58:48+01:00\",\"dateModified\":\"2019-02-14T13:58:48+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#website\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/\",\"name\":\"Un Universo invisible bajo nuestros pies\",\"description\":\"Los suelos y la vida\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"De la Filosof\u00eda de la Ciencia a la Filosof\u00eda de la Tecnociencia (Nuevo Curso B\u00e1sico y Sus Razones) - Un Universo invisible bajo nuestros pies","description":"Cr\u00edtica a la tecnociencia, Qu\u00e9 es la tecnociencia, Curso b\u00e1sico, razones,","canonical_url":"https:\/\/www.madrimasd.org\/blogs\/universo\/2019\/02\/14\/150022","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2019\/02\/14\/150022#blogposting","name":"De la Filosof\u00eda de la Ciencia a la Filosof\u00eda de la Tecnociencia (Nuevo Curso B\u00e1sico y Sus Razones) - Un Universo invisible bajo nuestros pies","headline":"De la Filosof\u00eda de la Ciencia a la Filosof\u00eda de la Tecnociencia (Nuevo Curso B\u00e1sico y Sus Razones)","author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author"},"publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-content\/blogs.dir\/42\/files\/405\/tecnociencia-introduccion.jpg","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2019\/02\/14\/150022\/#articleImage"},"datePublished":"2019-02-14T13:58:48+01:00","dateModified":"2019-02-14T13:58:48+01:00","inLanguage":"es-ES","commentCount":7,"mainEntityOfPage":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2019\/02\/14\/150022#webpage"},"isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2019\/02\/14\/150022#webpage"},"articleSection":"Curso b\u00e1sico de ciencia para jovenes universitarios y tecn\u00f3logos, Curso B\u00e1sico sobre Filosof\u00eda de la Tecnociencia, Curso B\u00e1sico Sobre Filosof\u00eda y Sociolog\u00eda de la Ciencia, Curso breve sobre Periodismo Cient\u00edfico, Filosof\u00eda, Historia y Sociolog\u00eda de la Edafolog\u00eda, Fraude y Mala Praxis Cient\u00edfica, curso b\u00e1sico, filosof\u00eda de la ciencia, Filosof\u00eda de le tecnociencia, sociolog\u00eda de la ciencia"},{"@type":"BreadcrumbList","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2019\/02\/14\/150022#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo#listItem","position":1,"name":"Home","item":"https:\/\/www.madrimasd.org\/blogs\/universo","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/filosofia-historia-y-sociologia-de-la-edafologia#listItem","name":"Filosof\u00eda, Historia y Sociolog\u00eda de la Edafolog\u00eda"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/filosofia-historia-y-sociologia-de-la-edafologia#listItem","position":2,"name":"Filosof\u00eda, Historia y Sociolog\u00eda de la Edafolog\u00eda","item":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/filosofia-historia-y-sociologia-de-la-edafologia","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2019\/02\/14\/150022#listItem","name":"De la Filosof\u00eda de la Ciencia a la Filosof\u00eda de la Tecnociencia (Nuevo Curso B\u00e1sico y Sus Razones)"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2019\/02\/14\/150022#listItem","position":3,"name":"De la Filosof\u00eda de la Ciencia a la Filosof\u00eda de la Tecnociencia (Nuevo Curso B\u00e1sico y Sus Razones)","previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/filosofia-historia-y-sociologia-de-la-edafologia#listItem","name":"Filosof\u00eda, Historia y Sociolog\u00eda de la Edafolog\u00eda"}}]},{"@type":"Organization","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#organization","name":"Un Universo invisible bajo nuestros pies","description":"Los suelos y la vida","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/","logo":{"@type":"ImageObject","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2019\/02\/14\/150022\/#organizationLogo","width":217,"height":72},"image":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2019\/02\/14\/150022\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/juan.j.marti.14"]},{"@type":"Person","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo","name":"Juan Jos\u00e9 Ib\u00e1\u00f1ez","image":{"@type":"ImageObject","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2019\/02\/14\/150022#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/387f3a100385573d8f42ce2a3211fd1c?s=96&d=mm&r=g","width":96,"height":96,"caption":"Juan Jos\u00e9 Ib\u00e1\u00f1ez"}},{"@type":"WebPage","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2019\/02\/14\/150022#webpage","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/2019\/02\/14\/150022","name":"De la Filosof\u00eda de la Ciencia a la Filosof\u00eda de la Tecnociencia (Nuevo Curso B\u00e1sico y Sus Razones) - Un Universo invisible bajo nuestros pies","description":"Cr\u00edtica a la tecnociencia, Qu\u00e9 es la tecnociencia, Curso b\u00e1sico, razones,","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#website"},"breadcrumb":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2019\/02\/14\/150022#breadcrumblist"},"author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author"},"creator":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author"},"datePublished":"2019-02-14T13:58:48+01:00","dateModified":"2019-02-14T13:58:48+01:00"},{"@type":"WebSite","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#website","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/","name":"Un Universo invisible bajo nuestros pies","description":"Los suelos y la vida","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Un Universo invisible bajo nuestros pies - Los suelos y la vida","og:type":"article","og:title":"De la Filosof\u00eda de la Ciencia a la Filosof\u00eda de la Tecnociencia (Nuevo Curso B\u00e1sico y Sus Razones) - Un Universo invisible bajo nuestros pies","og:description":"Cr\u00edtica a la tecnociencia, Qu\u00e9 es la tecnociencia, Curso b\u00e1sico, razones,","og:url":"https:\/\/www.madrimasd.org\/blogs\/universo\/2019\/02\/14\/150022","og:image":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png","og:image:secure_url":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png","article:published_time":"2019-02-14T12:58:48+00:00","article:modified_time":"2019-02-14T12:58:48+00:00","article:publisher":"https:\/\/www.facebook.com\/juan.j.marti.14","twitter:card":"summary","twitter:title":"De la Filosof\u00eda de la Ciencia a la Filosof\u00eda de la Tecnociencia (Nuevo Curso B\u00e1sico y Sus Razones) - Un Universo invisible bajo nuestros pies","twitter:description":"Cr\u00edtica a la tecnociencia, Qu\u00e9 es la tecnociencia, Curso b\u00e1sico, razones,","twitter:image":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png"},"aioseo_meta_data":{"post_id":"150022","title":"","description":"Cr\u00edtica a la tecnociencia, Qu\u00e9 es la  tecnociencia, Curso b\u00e1sico, razones,","keywords":[{"label":"Cr\u00edtica a la tecnociencia","value":"Cr\u00edtica a la tecnociencia"},{"label":"Qu\u00e9 es la  tecnociencia","value":"Qu\u00e9 es la  tecnociencia"},{"label":"Curso b\u00e1sico","value":"Curso b\u00e1sico"},{"label":"razones","value":"razones"},{"label":"critica a la tecnociencia","value":"critica a la tecnociencia"},{"label":"","value":""}],"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":null,"isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","tabs":null,"priority":null,"frequency":null,"local_seo":null,"created":"2022-06-03 10:21:57","updated":"2026-05-26 19:02:48","limit_modified_date":false,"ai":null,"breadcrumb_settings":null,"seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/filosofia-historia-y-sociologia-de-la-edafologia\" title=\"Filosof\u00eda, Historia y Sociolog\u00eda de la Edafolog\u00eda\">Filosof\u00eda, Historia y Sociolog\u00eda de la Edafolog\u00eda<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tDe la Filosof\u00eda de la Ciencia a la Filosof\u00eda de la Tecnociencia (Nuevo Curso B\u00e1sico y Sus Razones)\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.madrimasd.org\/blogs\/universo"},{"label":"Filosof\u00eda, Historia y Sociolog\u00eda de la Edafolog\u00eda","link":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/filosofia-historia-y-sociologia-de-la-edafologia"},{"label":"De la Filosof\u00eda de la Ciencia a la Filosof\u00eda de la Tecnociencia (Nuevo Curso B\u00e1sico y Sus Razones)","link":"https:\/\/www.madrimasd.org\/blogs\/universo\/2019\/02\/14\/150022"}],"_links":{"self":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts\/150022"}],"collection":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/comments?post=150022"}],"version-history":[{"count":10,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts\/150022\/revisions"}],"predecessor-version":[{"id":150072,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts\/150022\/revisions\/150072"}],"wp:attachment":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/media?parent=150022"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/categories?post=150022"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/tags?post=150022"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}