{"id":150099,"date":"2019-10-14T12:47:11","date_gmt":"2019-10-14T11:47:11","guid":{"rendered":"http:\/\/www.madrimasd.org\/blogs\/universo\/?p=150099"},"modified":"2019-10-14T12:47:11","modified_gmt":"2019-10-14T11:47:11","slug":"sobre-la-tecnociencia-la-filosofia-del-conocimiento-el-constructivismo-y-la-teoria-actor-red","status":"publish","type":"post","link":"https:\/\/www.madrimasd.org\/blogs\/universo\/2019\/10\/14\/150099","title":{"rendered":"Sobre la Tecnociencia, la Filosof\u00eda del Conocimiento, el Constructivismo y La Teor\u00eda Actor-red"},"content":{"rendered":"<p align=\"center\"><span style=\"color: #000000;\"><img decoding=\"async\" class=\"ngg-singlepic ngg-center\" src=\"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-content\/blogs.dir\/42\/files\/857\/0-filosofia-del-conocimiento-y-tecnociencia.jpg\" alt=\"0-filosofia-del-conocimiento-y-tecnociencia\" \/>\u00a0<\/span><\/p>\n<p align=\"center\"><span style=\"color: #0000ff;\">Fuente: Colaje Google Im\u00e1genes<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><span style=\"color: #3366ff;\"><strong>\u00bfQu\u00e9 es la verdad Cient\u00edfica?<\/strong> <\/span>Ya os he expuesto en varias ocasiones nuestra postura, que a la postre fue previamente avalada anta\u00f1o por las \u00faltimas escuelas de la filosof\u00eda de la ciencia (como vimos en nuestro <\/span><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/curso-basico-sobre-filosofia-y-sociologia-de-la-ciencia\"><span style=\"color: #0000ff;\">Curso B\u00e1sico sobre Filosof\u00eda y Sociolog\u00eda de la Ciencia<\/span><\/a><span style=\"color: #000000;\">, y m\u00e1s concretamente en varios post como este: <\/span><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2007\/09\/01\/73087\"><span style=\"color: #0000ff;\">La Verdad Cient\u00edfica Como Consenso<\/span><\/a><span style=\"color: #000000;\">) Si hay una verdad absoluta ah\u00ed fuera, se encuentra m\u00e1s all\u00e1 de nuestro alcance. Eso s\u00ed, la ciencia intenta hacer retroceder, paso a paso, el muro de nuestra incalculable ignorancia. Empero muchos cient\u00edficos profesan un amor incondicional a su objeto de estudio y no terminan de reconocerlo. \u00a1El amor es ciego! e \u00a1ignorante!, dicho sea de paso. A menudo, casi textualmente, he sido criticado en varias ocasiones por \u201censa\u00f1arme mucho con la ciencia, demasiado! \u00a1Se trata de una percepci\u00f3n rotundamente falsa! A t\u00edtulo personal \u00a0tengo pasi\u00f3n por ella, lo que ocurre es que una cuesti\u00f3n es el inter\u00e9s\/ pasi\u00f3n, y otra muy distinta pensar que \u201cella es perfecta\u201d, como defienden muchos profesionales dedicados a la <\/span><a href=\"https:\/\/es.wikipedia.org\/wiki\/Filosof\u00eda_de_la_ciencia\"><span style=\"color: #0000ff;\">Filosof\u00eda del Conocimiento<\/span><\/a><span style=\"color: #000000;\">. Se trata de una escuela a la que denominamos <\/span><a href=\"https:\/\/es.wikipedia.org\/wiki\/Constructivismo_(filosof\u00eda)\"><span style=\"color: #0000ff;\">constructivismo<\/span><\/a><span style=\"color: #000000;\">, muy importante desde hace tiempo y que sigue ganando adeptos, m\u00e1s aun desde que las ciencias cognitivas comenzar\u00e1n a dinamitar desde el propio seno de la indagaci\u00f3n cient\u00edfica cualquier atisbo de objetividad pura, tanto en nuestras mentes como en los productos que se derivan de ella. Nos estamos refiriendo pues a<span style=\"color: #3366ff;\"><strong> un constructo social<\/strong><\/span>. Abajo os dejo unos p\u00e1rrafos preliminares, extra\u00eddos de Wikipedia, acerca de estas ramas del saber. Fijaros que cuando os reproduzco unos escasos fragmentos del texto que expone la enciclopedia libre sobre filosof\u00eda del conociendo, lo hago desde su cap\u00edtulo dedicado a la de la ciencia, para que no albergu\u00e9is la menor duda.\u00a0<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Ruego al lector que se fije en el siguiente hecho<strong>: <span style=\"color: #3366ff;\">La tecnociencia incorpora parte de las humanidades y en especial las ciencias sociales al n\u00facleo duro de su<\/span><\/strong> <\/span><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2007\/04\/15\/63581\"><span style=\"color: #0000ff;\">programa cient\u00edfico de Investigaci\u00f3n<\/span><\/a><span style=\"color: #000000;\">, desde la <\/span><a href=\"https:\/\/es.wikipedia.org\/wiki\/Imre_Lakatos\"><span style=\"color: #0000ff;\">perspectiva lakatosiana<\/span><\/a><span style=\"color: #000000;\">, sobre la que ya abundamos con varios post en nuestro \u201cCurso B\u00e1sico de Filosof\u00eda de la ciencia\u201d. Se me antoja parad\u00f3jico que un hecho deseable, lograra por fin entrar en el seno de las discusiones acerca de\u00a0 la ciencia, usando un veh\u00edculo que considero intelectualmente muy obsceno como lo es la propia <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2019\/02\/27\/150045\">tecnociencia<\/a>. M\u00e1s aun, dado <strong><span style=\"color: #3366ff;\">que esta \u00faltima y los estudios sociales de la ciencia, al contrario que en la filosof\u00eda cl\u00e1sica sobre el tema, cambian de direcci\u00f3n al analizar c\u00f3mo trabaja la ciencia, dejando en un segundo lugar su esencia de la indagaci\u00f3n cient\u00edfica<\/span><\/strong> (como lo es por antonomasia el m\u00e9todo cient\u00edfico en su mismo),<strong><span style=\"color: #3366ff;\"> la propia filosof\u00eda se \u201csocializa\u201d y \u201cdesacraliza\u201d bajando tambi\u00e9n de su pedestal<\/span><\/strong>.\u00a0<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><span style=\"color: #008000;\"><strong>Ser\u00e1 a partir de ahora la praxis y los intereses que la condicionan los que aglutinar\u00e1n los estudios acerca de que es la ciencia.\u00a0 Y as\u00ed el progreso de la ciencia no se cargar\u00e1 a \u201chombros de gigantes intelectuales\u201d, sino que debatiremos acerca del poder, la avaricia, la codicia, la vanidad y otras cualidades lamentablemente muy humanas<\/strong><\/span>.\u00a0<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Y estas l\u00edneas vienen a colaci\u00f3n <span style=\"color: #3366ff;\"><strong>debido a la propia definici\u00f3n de <\/strong><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2019\/02\/27\/150045\"><span style=\"color: #000000;\">Tecnociencia<\/span><\/a><strong>, ya que esta diluye lo natural de lo social, lo objetivo de lo subjetivo, etc<\/strong>.<\/span> Extraje el siguiente fragmento de texto, que ya os coment\u00e9 y sobre el que sigo abundando abajo, de un art\u00edculo, firmado por tres expertos, y entre ellos Xavier Echeverr\u00eda: <strong>\u201c<span style=\"color: #3366ff;\"><em>Todas las dicotom\u00edas (naturaleza\/sociedad, sujeto\/objeto, humano\/no humano) son puestas en tela de juicio en un intento de superaci\u00f3n de la ideolog\u00eda de la modernidad<\/em>\u201d<\/span><\/strong><span style=\"color: #3366ff;\"> (\u2026). <span style=\"color: #000000;\">Soslayando toda esa desiderata de modernidad, posmodernidad, etc., lo cierto es que las aludidas dicotom\u00edas son a menudo las peores de todas ellas, por lo menos cuando abordamos temas cient\u00edficos:<\/span> \u201c<\/span><\/span><a href=\"https:\/\/es.wikipedia.org\/wiki\/Antinomia\"><span style=\"color: #0000ff;\"><span style=\"color: #3366ff;\">las antonimias<\/span><\/span><\/a><span style=\"color: #000000;\">\u201d. En este sentido os recomiendo que le\u00e1is una interesante obra del pensador franc\u00e9s\u00a0 de <\/span><a href=\"https:\/\/es.wikipedia.org\/wiki\/Jean-Marc_L\u00e9vy-Leblond\"><span style=\"color: #0000ff;\">Jean-Marc L\u00e9vy-Leblond<\/span><\/a><span style=\"color: #000000;\"> de la que hablamos en nuestro post: \u201c<\/span><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2007\/12\/01\/80077\"><span style=\"color: #0000ff;\">El Discurso Cient\u00edfico, los Conceptos Contrarios<\/span><\/a><span style=\"color: #000000;\">\u201d. Y reitero por en\u00e9sima vez, <strong><span style=\"color: #3366ff;\">no podemos seguir pensando<\/span> <span style=\"color: #3366ff;\">que es posible asirse a alguna verdad absoluta<\/span><\/strong>. \u00a0Debemos aprender a vivir con la incertidumbre de nuestros progresos, cient\u00edficos o culturales en general, siempre mejorables (<\/span><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2007\/11\/10\/78477\"><span style=\"color: #0000ff;\">Los Conceptos Cient\u00edficos y sus Limitaciones: Vivir en la Incertidumbre<\/span><\/a><span style=\"color: #000000;\">).\u00a0 <span style=\"color: #3366ff;\"><strong>Y si la ciencia es un constructo social, la anta\u00f1o considerada n\u00edtida frontera entre la\u00a0 filosof\u00eda y la sociolog\u00eda, se diluye paulatinamente<\/strong><\/span>. De aqu\u00ed que<span style=\"color: #3366ff;\"> <strong>la Tecnociencia, incluso para aquellos que tienen fe ciega en la misma<\/strong> <\/span>(que son los poderes f\u00e1cticos que la sustentan) <strong><span style=\"color: #3366ff;\">s<\/span><span style=\"color: #3366ff;\">uelen aceptar tal constructivismo sin m\u00e1s miramientos y reparos<\/span><\/strong>, y menos a\u00fan ascos en sus discursos.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Y <span style=\"color: #3366ff;\"><strong>quiz\u00e1s sea este uno de los aspectos de la Tecnociencia que menos da\u00f1ino se me antoja. Me refiero al reconocimiento \u00a0del inter\u00e9s de romper esa invisible pero pertinaz frontera que separa las humanidades de las ciencias<\/strong><\/span>. Ya en 1959 <\/span><a href=\"https:\/\/es.wikipedia.org\/wiki\/Charles_Percy_Snow\"><span style=\"color: #0000ff;\">C. P. Snow<\/span><\/a><span style=\"color: #000000;\"> habl\u00f3 del da\u00f1o generado por tal l\u00ednea roja, tanto a los estudios transdisciplinares como al conocimiento humano en general. <\/span><a href=\"https:\/\/es.wikipedia.org\/wiki\/Las_dos_culturas\"><span style=\"color: #0000ff;\">Necesitamos la convergencia de las dos culturas<\/span><\/a><span style=\"color: #000000;\">, pero no en la direcci\u00f3n que apuntan los ayatolas de la tecnociencia.\u00a0<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Por otro lado, y como ver\u00e9is en los fragmentos de texto que os expongo abajo,<\/span><span style=\"color: #3366ff;\"> <strong>las Tesis sobre las que Echeverr\u00eda se bas\u00f3 para el desarrollo de su propuesta de tecnociencia,\u00a0 en primera instancia, no parecer\u00edan encajar adecuadamente con las que usaron Latour y call\u00f3n a la hora de exponer la denominada<\/strong> <\/span><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/05\/22\/139155\"><span style=\"color: #0000ff;\">Teor\u00eda Actor-Red<\/span><\/a><span style=\"color: #000000;\">.<span style=\"color: #3366ff;\"> <strong>Sin embargo<\/strong><\/span> a la postre este notable fil\u00f3sofo, junto a Gonz\u00e1lez y Casanova (2004),<span style=\"color: #3366ff;\"> <strong>intentaron, m\u00e1s que conciliarlas, demostrar que juntas estimulan mutuamente su potencialidad heur\u00edstica<\/strong><\/span>. Y es por esta raz\u00f3n por lo que hemos preferido escoger este art\u00edculo a otros de igual calidad.\u00a0<\/span><\/p>\n<p><span style=\"color: #000000;\">As\u00ed pues, <span style=\"color: #800000;\"><strong>en este post intentamos relacionar la Tecnociencia<\/strong>, <strong>con<\/strong><\/span> la <\/span><a href=\"https:\/\/es.wikipedia.org\/wiki\/Filosof\u00eda_de_la_ciencia\"><span style=\"color: #0000ff;\">Filosof\u00eda del Conocimiento<\/span><\/a><span style=\"color: #000000;\"> y la denominada <\/span><span style=\"color: #0000ff;\"><a href=\"https:\/\/es.wikipedia.org\/wiki\/Etnometodolog\u00eda\">Etnometodolog\u00eda<\/a><span style=\"text-decoration: underline;\">.<\/span><\/span><\/p>\n<p><span style=\"color: #008000;\"><strong>Juan Jos\u00e9 Ib\u00e1\u00f1ez<\/strong><\/span><\/p>\n<p><span style=\"color: #800000;\"><em>Contin\u00faa\u2026\u2026.<\/em><\/span><\/p>\n<p><span style=\"color: #000000; font-family: Calibri; font-size: medium;\"><!--more--><\/span><\/p>\n<p><a href=\"https:\/\/es.wikipedia.org\/wiki\/Filosof\u00eda_de_la_ciencia\"><span style=\"color: #0000ff;\">Filosof\u00eda del Conocimiento<\/span><\/a><\/p>\n<p style=\"text-align: justify;\">La <strong>filosof\u00eda de la ciencia<\/strong> <strong>investiga el<\/strong> <a title=\"Conocimiento cient\u00edfico\" href=\"https:\/\/es.wikipedia.org\/wiki\/Conocimiento_cient%C3%ADfico\">conocimiento cient\u00edfico<\/a> <strong>y la pr\u00e1ctica cient\u00edfica<\/strong>. Se ocupa de saber, entre otras cosas, c\u00f3mo se desarrollan, eval\u00faan y cambian las <a title=\"Teor\u00eda\" href=\"https:\/\/es.wikipedia.org\/wiki\/Teor%C3%ADa\">teor\u00edas<\/a> cient\u00edficas, y de <strong>saber si la<\/strong> <a title=\"Ciencia\" href=\"https:\/\/es.wikipedia.org\/wiki\/Ciencia\">ciencia<\/a> <strong>es capaz de revelar la verdad de las \u00abentidades ocultas\u00bb (o sea, no observables) y los procesos de la naturaleza<\/strong>. Son <a title=\"Filosof\u00eda\" href=\"https:\/\/es.wikipedia.org\/wiki\/Filosof%C3%ADa\">filos\u00f3ficas<\/a> <strong>las diversas proposiciones b\u00e1sicas que permiten construir la ciencia. Por ejemplo<\/strong>:<\/p>\n<ul>\n<li>Existe de manera independiente de la mente humana (tesis ontol\u00f3gica de <a title=\"Realismo filos\u00f3fico\" href=\"https:\/\/es.wikipedia.org\/wiki\/Realismo_filos%C3%B3fico\">realismo<\/a>).<\/li>\n<li>La <a title=\"Naturaleza\" href=\"https:\/\/es.wikipedia.org\/wiki\/Naturaleza\">naturaleza<\/a> es regular, al menos en alguna medida (tesis ontol\u00f3gica de legalidad).<\/li>\n<li>El <a title=\"Ser humano\" href=\"https:\/\/es.wikipedia.org\/wiki\/Ser_humano\">ser humano<\/a> es capaz de comprender la naturaleza (tesis <a title=\"Gnoseolog\u00eda\" href=\"https:\/\/es.wikipedia.org\/wiki\/Gnoseolog%C3%ADa\">gnoseol\u00f3gica<\/a> de inteligibilidad).<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Si bien <strong>estos supuestos<\/strong> <a title=\"Metaf\u00edsica\" href=\"https:\/\/es.wikipedia.org\/wiki\/Metaf%C3%ADsica\"><strong>metaf\u00edsicos<\/strong><\/a><strong> no son cuestionados por e<\/strong>l <a title=\"Realismo cient\u00edfico\" href=\"https:\/\/es.wikipedia.org\/wiki\/Realismo_cient%C3%ADfico\">realismo cient\u00edfico<\/a>, <strong>muchos han planteado serias sospechas respecto del segundo de ell<\/strong>os<a href=\"https:\/\/es.wikipedia.org\/wiki\/Filosof%C3%ADa_de_la_ciencia#cite_note-1\"><sup>1<\/sup><\/a> <strong>y numerosos fil\u00f3sofos han puesto en tela de juicio alguno de ellos o los tres<\/strong>.<a href=\"https:\/\/es.wikipedia.org\/wiki\/Filosof%C3%ADa_de_la_ciencia#cite_note-2\"><sup>2<\/sup><\/a> De hecho, <strong>las principales sospechas con respecto a la validez de estos supuestos metaf\u00edsicos son parte de la base para distinguir las diferentes corrientes epistemol\u00f3gicas hist\u00f3ricas y actuales<\/strong>. De tal modo, aunque en t\u00e9rminos generales el <a title=\"Empirismo l\u00f3gico\" href=\"https:\/\/es.wikipedia.org\/wiki\/Empirismo_l%C3%B3gico\">empirismo l\u00f3gico<\/a> defiende el segundo principio, opone reparos al tercero y asume una posici\u00f3n <a title=\"Fen\u00f3meno\" href=\"https:\/\/es.wikipedia.org\/wiki\/Fen%C3%B3meno\">fenomenista<\/a>, es decir, admite que el hombre puede comprender la naturaleza siempre que por naturaleza se entienda \u00ablos fen\u00f3menos\u00bb (el producto de la experiencia humana) y no la propia realidad.<\/p>\n<p>En pocas palabras, lo que intenta la filosof\u00eda de la ciencia es explicar problemas tales como:<\/p>\n<ul>\n<li>la naturaleza y la obtenci\u00f3n de las ideas cient\u00edficas (<a title=\"Concepto\" href=\"https:\/\/es.wikipedia.org\/wiki\/Concepto\">conceptos<\/a>, <a title=\"Hip\u00f3tesis (m\u00e9todo cient\u00edfico)\" href=\"https:\/\/es.wikipedia.org\/wiki\/Hip%C3%B3tesis_(m%C3%A9todo_cient%C3%ADfico)\">hip\u00f3tesis<\/a>, <a title=\"Modelo cient\u00edfico\" href=\"https:\/\/es.wikipedia.org\/wiki\/Modelo_cient%C3%ADfico\">modelos<\/a>, <a title=\"Teor\u00eda\" href=\"https:\/\/es.wikipedia.org\/wiki\/Teor%C3%ADa\">teor\u00edas<\/a>, <a title=\"Paradigma\" href=\"https:\/\/es.wikipedia.org\/wiki\/Paradigma\">paradigma<\/a>, etc.);<\/li>\n<li>la relaci\u00f3n de cada una de ellas con la <a title=\"Realidad\" href=\"https:\/\/es.wikipedia.org\/wiki\/Realidad\">realidad<\/a>;<\/li>\n<li>c\u00f3mo la ciencia describe, explica, predice y contribuye al control de la naturaleza (esto \u00faltimo en conjunto con la <a title=\"Filosof\u00eda de la tecnolog\u00eda\" href=\"https:\/\/es.wikipedia.org\/wiki\/Filosof%C3%ADa_de_la_tecnolog%C3%ADa\">filosof\u00eda de la tecnolog\u00eda<\/a>);<\/li>\n<li>la formulaci\u00f3n y uso del <a title=\"M\u00e9todo cient\u00edfico\" href=\"https:\/\/es.wikipedia.org\/wiki\/M%C3%A9todo_cient%C3%ADfico\">m\u00e9todo cient\u00edfico<\/a>;<\/li>\n<li>los tipos de <a title=\"Raz\u00f3n\" href=\"https:\/\/es.wikipedia.org\/wiki\/Raz%C3%B3n\">razonamiento<\/a> utilizados para llegar a conclusiones;<\/li>\n<li>las implicaciones de los diferentes m\u00e9todos y modelos de ciencia.<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">La filosof\u00eda de la ciencia comparte algunos problemas con la <a title=\"Gnoseolog\u00eda\" href=\"https:\/\/es.wikipedia.org\/wiki\/Gnoseolog%C3%ADa\">gnoseolog\u00eda<\/a> \u2014<strong>la teor\u00eda del conocimiento\u2014 que se ocupa de los l\u00edmites y condiciones de posibilidad de <em>todo<\/em> conocimiento<\/strong>. Pero, a diferencia de \u00e9sta, la filosof\u00eda de la ciencia <strong>restringe su campo de investigaci\u00f3n a los problemas que plantea el conocimiento cient\u00edfico<\/strong>; el cual, tradicionalmente, se distingue de otros tipos de conocimiento, como el \u00e9tico o est\u00e9tico, o las <a title=\"Tradici\u00f3n\" href=\"https:\/\/es.wikipedia.org\/wiki\/Tradici%C3%B3n\">tradiciones<\/a> <a title=\"Cultura\" href=\"https:\/\/es.wikipedia.org\/wiki\/Cultura\">culturales<\/a>.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/es.wikipedia.org\/wiki\/Constructivismo_(filosof\u00eda)\"><span style=\"color: #0000ff;\">Constructivismo seg\u00fan Wikipedia<\/span><\/a><span style=\"color: #000000;\">:\u00a0<\/span><\/p>\n<p style=\"text-align: justify;\">En <a title=\"Filosof\u00eda de la ciencia\" href=\"https:\/\/es.wikipedia.org\/wiki\/Filosof%C3%ADa_de_la_ciencia\">filosof\u00eda de la ciencia<\/a> y <a title=\"Epistemolog\u00eda\" href=\"https:\/\/es.wikipedia.org\/wiki\/Epistemolog%C3%ADa\">epistemolog\u00eda<\/a> se denomina <strong>constructivismo<\/strong> o <strong>constructivismo epistemol\u00f3gico<\/strong> a una <a title=\"Corriente de pensamiento\" href=\"https:\/\/es.wikipedia.org\/wiki\/Corriente_de_pensamiento\">corriente de pensamiento<\/a> surgida hacia mediados del <a title=\"Siglo XX\" href=\"https:\/\/es.wikipedia.org\/wiki\/Siglo_XX\">siglo XX<\/a>, de la mano de investigadores de disciplinas muy diversas (\u2026.). <strong>Para el pensamiento constructivista, la realidad es una construcci\u00f3n en cierto grado \u00abinventada\u00bb por quien la observa. Nunca se podr\u00e1 llegar a conocer la realidad tal como es pues siempre, al conocer algo, ordenamos los datos obtenidos de la realidad (aunque sean percepciones b\u00e1sicas) en un marco te\u00f3rico o mental<\/strong>. De tal modo<strong>, ese objeto o re<\/strong>alidad que entendemos \u00abliteral\u00bb no es tal, no tenemos un \u00abreflejo especular\u00bb de lo que est\u00e1 \u00abah\u00ed fuera de nosotros\u00bb, sino <strong>algo que hemos construido con base en nuestras percepciones y datos emp\u00edricos. As\u00ed, la ciencia y el conocimiento en general ofrecen solamente una aproximaci\u00f3n a la verdad<\/strong>, que queda fuera de nuestro alcance.<a href=\"https:\/\/es.wikipedia.org\/wiki\/Constructivismo_(filosof%C3%ADa)#cite_note-1\"><sup>1<\/sup><\/a><\/p>\n<p style=\"text-align: justify;\"><a title=\"Gerald M. Edelman\" href=\"https:\/\/es.wikipedia.org\/wiki\/Gerald_M._Edelman\">Gerald M. Edelman<\/a> ilustra esta idea diciendo que \u00abCada acto de percepci\u00f3n es en cierto grado un acto de creaci\u00f3n y cada acto de memoria es a cierto modo un acto de imaginaci\u00f3n\u00bb.<a href=\"https:\/\/es.wikipedia.org\/wiki\/Constructivismo_(filosof%C3%ADa)#cite_note-2\"><sup>2<\/sup><\/a><\/p>\n<p><span style=\"color: #800000;\"><strong>Post ya editados hasta febrero de 2019 del Curso B\u00e1sico <\/strong><\/span><strong><\/strong><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/curso-basico-sobre-filosofia-de-la-tecnociencia\"><strong><span style=\"color: #0000ff;\">Sobre la Filosof\u00eda de la tecnociencia<\/span><\/strong><\/a><strong><\/strong><\/p>\n<p><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2019\/02\/14\/150022\"><span style=\"color: #0000ff;\">De la Filosof\u00eda de la Ciencia a la Filosof\u00eda de la Tecnociencia (Nuevo Curso B\u00e1sico y Sus Razones)<\/span><\/a><\/p>\n<p><span style=\"color: #000000;\">\u00a0<\/span><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2019\/02\/20\/150034\"><span style=\"color: #0000ff;\">Bibliograf\u00eda de libre Acceso en la Red Para el Curso B\u00e1sico de Tecnociencias<\/span><\/a><\/p>\n<p><a title=\"Permanent Link to Las Dos Caras de la Ciencia\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2019\/04\/10\/149444\">Las Dos Caras de la Ciencia<\/a><\/p>\n<p><a title=\"Permanent Link to De la Bigscience a la Tecnociencia (La Macrociencia Tard\u00eda)\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2019\/03\/27\/150060\">De la Bigscience a la Tecnociencia (La Macrociencia Tard\u00eda)<\/a><\/p>\n<p><a title=\"Permanent Link to Historia de la Tecnociencia: De la Ciencia a La Macrociencia Temprana\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2019\/03\/07\/150054\">Historia de la Tecnociencia: De la Ciencia a La Macrociencia Temprana<\/a><\/p>\n<p><a title=\"Permanent Link to Tecnociencia Definiciones y Objetivos\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2019\/02\/27\/150045\">Tecnociencia Definiciones y Objetivos<\/a><\/p>\n<p><a title=\"Permanent Link to Tecnociencia y Ciencia Disruptiva: La paradoja de los Grandes Equipos de Investigaci\u00f3n\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2019\/05\/24\/150077\">Tecnociencia y Ciencia Disruptiva: La paradoja de los Grandes Equipos de Investigaci\u00f3n<\/a><\/p>\n<p><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2019\/05\/10\/150379\">Bruno Latour se interesa por los suelos y la zona cr\u00edtica terrestre<\/a><\/p>\n<p><span style=\"color: #000000;\">Abajo fragmentos del art\u00edculo: Gonz\u00e1lez, M. I. Casanova, P., Echeverr\u00eda, J. 2004. Las nuevas ciencias y las humanidades: de la academia a la pol\u00edtica. Anthropos Editorial, Barcelona. <\/span><a href=\"https:\/\/www.researchgate.net\/publication\/26627200_La_teoria_del_actor-red_y_la_tesis_de_la_tecnociencia\"><span style=\"color: #0000ff;\">La teor\u00eda del actor-red y la tesis de la tecnociencia<\/span><\/a><span style=\"color: #000000;\">. Fundaci\u00f3n Ikerbasque-Universidad del Pa\u00eds Vasco. ARBOR Ciencia, Pensamiento y Cultura CLXXXV 738 julio-agosto (2009) 705-720 ISSN: 0210-1963; doi: 10.3989\/arbor.2009.738n1047.<\/span><\/p>\n<p><span style=\"color: #000000;\">En su art\u00edculo estos autores comentan que (<span style=\"color: #0000ff;\"><em>los hiperv\u00ednculos para explicar algunos conceptos son de este bloguero<\/em><\/span>):<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><strong>La revoluci\u00f3n en los estudios sobre la ciencia y la tecnolog\u00eda hab\u00eda aparecido ligada al imperativo de buscar la explicaci\u00f3n del contenido de la ciencia en su \u201ccontexto social<\/strong>\u201d. Una ideolog\u00eda pol\u00edtica determinada, cierto inter\u00e9s econ\u00f3mico o alg\u00fan arraigado prejuicio eran el tipo de factores que se rastreaban para explicar la g\u00e9nesis y legitimaci\u00f3n de las teor\u00edas cient\u00edficas. Para dar cuenta de la construcci\u00f3n de la naturaleza, defend\u00eda <strong>la revoluci\u00f3n constructivista<\/strong>, <strong>es necesario apelar a la sociedad<\/strong>. Sin embargo, algunos autores se mostraron insatisfechos con esta \u201csociolog\u00eda de lo social\u201d (\u2026) lo social se \u201ccoproducen\u201d mutuamente.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><strong>Este cambio de rumbo tuvo como influencias, entre otras, el estudio de los sistemas sociot\u00e9cnicos<\/strong> desarrollado por Thomas Hughes (1983), <strong>en el que elementos organizativos, pol\u00edticos, cient\u00edficos, tecnol\u00f3gicos&#8230; se combinan para conformar la arquitectura de un sistema tecnol\u00f3gico estabilizado<\/strong>; y la <\/span><a href=\"https:\/\/es.wikipedia.org\/wiki\/Etnometodolog\u00eda\"><span style=\"color: #0000ff;\">etnometodolog\u00eda<\/span><\/a><span style=\"color: #000000;\"> de Alfred Shutz. El <\/span><a href=\"http:\/\/www.scielo.org.co\/scielo.php?script=sci_arttext&amp;pid=S1900-54072016000300001\"><span style=\"color: #0000ff;\">an\u00e1lisis etnogr\u00e1fico de la ciencia<\/span><\/a><span style=\"color: #000000;\">, tal y como lo ensayaron <strong>Bruno Latour y Steve Woolgar (1979\/1986<\/strong>) <strong>no tiene ya ninguna pretensi\u00f3n explicativa, sino tan s\u00f3lo la de describir la actividad que cient\u00edficos y tecn\u00f3logos desarrollan en sus laboratorios y de la que surge nuestra concepci\u00f3n del \u201cmundo real\u201d, natural y social<\/strong>. <\/span><strong>Los etnometod\u00f3logos de la ciencia sostienen<\/strong> <span style=\"color: #000000;\">que no puede apelarse a intereses, fines y factores sociales en general para dar cuenta de nuestras teor\u00edas, porque ellos mismos son tambi\u00e9n producto, y no causa, de las mismas fuerzas que dan forma a las afirmaciones de conocimiento cient\u00edfico y, por tanto, a la \u201crealidad\u201d.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><strong>Los estudios de laboratorio, sobre la base de los puntos m\u00e1s provocadores del programa fuerte en sociolog\u00eda del conocimiento cient\u00edfico de David Bloor (1976\/1991),<\/strong> simetr\u00eda y reflexividad, <strong>se desarrollaron en varias direcciones. <\/strong><\/span><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/05\/14\/139056\"><span style=\"color: #0000ff;\">La teor\u00eda del actor-red<\/span><\/a><span style=\"color: #000000;\"><strong> fue una<\/strong> de ellas. <strong>El punto de partida es la denuncia de que las pr\u00e1cticas de los soci\u00f3logos del conocimiento cient\u00edfico, lejos de adecuarse al principio de la simetr\u00eda, son profundamente asim\u00e9tricas<\/strong>. No s\u00f3lo los soci\u00f3logos \u201c<\/span><a href=\"https:\/\/www.revistadelibros.com\/articulos\/david-bloor-y-el-programa-fuerte\"><span style=\"color: #0000ff;\">tipo Edimburgo<\/span><\/a><span style=\"color: #000000;\">\u201d tratan de forma asim\u00e9trica la naturaleza y la sociedad, suponiendo a la \u00faltima como factor causal de la primera, sino que tambi\u00e9n tratan asim\u00e9tricamente a los \u201cactores\u201d humanos y no humanos del escenario cient\u00edfico-tecnol\u00f3gico<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><strong>Las propuestas de Echeverr\u00eda y la teor\u00eda del actor-red confluyen en su especial atenci\u00f3n a la pr\u00e1ctica cient\u00edfica<\/strong>. El <strong>programa fuerte y los primeros enfoques en sociolog\u00eda del conocimiento cient\u00edfico se centraron en el estudio de los factores sociales que influyen en la construcci\u00f3n del conocimiento<\/strong>, y en cierta manera lo determinan, pero <strong>se interesaron menos por el estudio de la pr\u00e1ctica cient\u00edfica<\/strong>, al menos en su primera \u00e9poca. En los a\u00f1os noventa, algunos historiadores, fil\u00f3sofos y soci\u00f3logos de la ciencia, como Hacking, Franklin, Galison o Pickering, comenzaron a ocuparse de la actividad cient\u00edfica sin reducirla a la construcci\u00f3n de conocimiento.\u00a0<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><strong>Pese a sus puntos comunes, tratar de articular el trabajo sobre la tecnociencia contempor\u00e1nea con la teor\u00eda del actor-red es una empresa arriesgada, aunque la recompensa puede ser importante<\/strong>. Mientras que la idea de <strong>tecnociencia<\/strong>, tal y como ha sido desarrollada <strong>por Echeverr\u00eda (2003)<\/strong>, responde al <strong>intento filos\u00f3fico de clasificar y caracterizar las modalidades de pr\u00e1ctica cient\u00edfico-tecnol\u00f3gica contempor\u00e1nea<\/strong>, el conjunto de herramientas metodol\u00f3gicas de <strong>la teor\u00eda del actor-red trae al primer plano el desorden oculto tras la ordenada apariencia de la tecnociencia<\/strong>, la contempor\u00e1nea y la de \u00e9pocas pasadas. Sin embargo, al analizar la tecnociencia contempor\u00e1nea, en el sentido de Echeverr\u00eda, <strong>la teor\u00eda del actor-red ha de mostrarse necesariamente \u00fatil para describir las complejas redes tejidas por<\/strong> <strong>centros de investigaci\u00f3n, instituciones, universidades y empresas, y los productos resultantes de las mismas en t\u00e9rminos de orden natural y social<\/strong>.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><strong>ANT <\/strong>ha sido duramente criticada desde el propio campo de los estudios de la ciencia. Una de las acusaciones fundamentales es la de la esterilidad, e incluso el peligro de conservadurismo, en este tipo de enfoques. Desestimar la apelaci\u00f3n a la sociedad en explicaciones causales del cambio cient\u00edfico podr\u00eda convertir esta clase de estudios sociales en un ejercicio acad\u00e9mico de sal\u00f3n tan insatisfactorio como las concepciones filos\u00f3ficas y sociol\u00f3gicas cl\u00e1sicas que pretenden sustituir. Si bien <strong>estos autores sostienen que la tecnociencia y la pol\u00edtica son indistinguibles<\/strong>, <strong>tal revelaci\u00f3n podr\u00eda no tener ninguna consecuencia pr\u00e1ctica, porque quien posee la verdad es aqu\u00e9l que consigue reunir el suficiente poder para convencer al contrario de que tiene raz\u00f3n<\/strong>. Al abrir la caja negra de la tecnociencia quiz\u00e1 nos llevemos la sorpresa, augurada por Langdon Winner (1993), de encontrarla vac\u00eda y, como a\u00f1adir\u00edan Collins y Yearley (1992), encontrarnos a nosotros mismos impotentes. Sin embargo, <strong>la teor\u00eda del actor-red ha mostrado fruct\u00edferas potencialidades en el \u00e1mbito pol\u00edtico<\/strong>, bien por parte de autores de la \u201cdi\u00e1spora\u201d, bien en los desarrollos m\u00e1s recientes de sus propios fundadores, como Bruno Latour y Michel Callon.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">LA TEOR\u00cdA DEL ACTOR-RED Y LA TESIS DE LA TECNOCIENCIA<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Javier Echeverr\u00eda (Fundaci\u00f3n Ikerbasque-Universidad del Pa\u00eds Vasco, Instituto de Filosof\u00eda y Red CTI\/CSIC) y Marta I. Gonz\u00e1lez (Instituto de Filosof\u00eda y Red CTI\/CSIC); doi: 10.3989\/arbor.2009.738n1047<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Gonz\u00e1lez, M. I. Casanova, P., Echeverr\u00eda, J. 2004. Las nuevas ciencias y las humanidades: de la academia a la pol\u00edtica. Anthropos Editorial, Barcelona. <\/span><a href=\"https:\/\/www.researchgate.net\/publication\/26627200_La_teoria_del_actor-red_y_la_tesis_de_la_tecnociencia\"><span style=\"color: #0000ff;\">La teor\u00eda del actor-red y la tesis de la tecnociencia<\/span><\/a><span style=\"color: #000000;\">. Fundaci\u00f3n Ikerbasque-Universidad del Pa\u00eds Vasco. ARBOR Ciencia, Pensamiento y Cultura CLXXXV 738 julio-agosto (2009) 705-720 ISSN: 0210-1963; doi: 10.3989\/arbor.2009.738n1047.<\/span><\/p>\n<h3>Im\u00e1genes Relacionadas:<\/h3>","protected":false},"excerpt":{"rendered":"<p>\u00a0 Fuente: Colaje Google Im\u00e1genes \u00bfQu\u00e9 es la verdad Cient\u00edfica? Ya os he expuesto en varias ocasiones nuestra postura, que a la postre fue previamente avalada anta\u00f1o por las \u00faltimas escuelas de la filosof\u00eda de la ciencia (como vimos en nuestro Curso B\u00e1sico sobre Filosof\u00eda y Sociolog\u00eda de la Ciencia, y m\u00e1s concretamente en varios post como este: La Verdad Cient\u00edfica Como Consenso) Si hay una verdad absoluta ah\u00ed fuera, se encuentra m\u00e1s all\u00e1 de nuestro alcance. Eso s\u00ed, la ciencia intenta hacer retroceder, paso a paso, el muro de nuestra incalculable ignorancia. Empero muchos cient\u00edficos profesan un amor incondicional\u2026<\/p>\n","protected":false},"author":26,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0},"categories":[13638,39962,609],"tags":[48208,2355,39966,48207,47039],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":4}},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Sobre la Tecnociencia, la Filosof\u00eda del Conocimiento, el Constructivismo y La Teor\u00eda Actor-red\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Juan Jos\u00e9 Ib\u00e1\u00f1ez\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2019\/10\/14\/150099\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Un Universo invisible bajo nuestros pies - Los suelos y la vida\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Sobre la Tecnociencia, la Filosof\u00eda del Conocimiento, el Constructivismo y La Teor\u00eda Actor-red - Un Universo invisible bajo nuestros pies\" \/>\n\t\t<meta property=\"og:description\" content=\"Sobre la Tecnociencia, la Filosof\u00eda del Conocimiento, el Constructivismo y La Teor\u00eda Actor-red\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2019\/10\/14\/150099\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2019-10-14T11:47:11+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2019-10-14T11:47:11+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/juan.j.marti.14\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Sobre la Tecnociencia, la Filosof\u00eda del Conocimiento, el Constructivismo y La Teor\u00eda Actor-red - Un Universo invisible bajo nuestros pies\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Sobre la Tecnociencia, la Filosof\u00eda del Conocimiento, el Constructivismo y La Teor\u00eda Actor-red\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2019\\\/10\\\/14\\\/150099#blogposting\",\"name\":\"Sobre la Tecnociencia, la Filosof\\u00eda del Conocimiento, el Constructivismo y La Teor\\u00eda Actor-red - Un Universo invisible bajo nuestros pies\",\"headline\":\"Sobre la Tecnociencia, la Filosof\\u00eda del Conocimiento, el Constructivismo y La Teor\\u00eda Actor-red\",\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/wp-content\\\/blogs.dir\\\/42\\\/files\\\/857\\\/0-filosofia-del-conocimiento-y-tecnociencia.jpg\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2019\\\/10\\\/14\\\/150099\\\/#articleImage\"},\"datePublished\":\"2019-10-14T12:47:11+01:00\",\"dateModified\":\"2019-10-14T12:47:11+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2019\\\/10\\\/14\\\/150099#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2019\\\/10\\\/14\\\/150099#webpage\"},\"articleSection\":\"Curso b\\u00e1sico de ciencia para jovenes universitarios y tecn\\u00f3logos, Curso B\\u00e1sico sobre Filosof\\u00eda de la Tecnociencia, Curso B\\u00e1sico Sobre Filosof\\u00eda y Sociolog\\u00eda de la Ciencia, Etnometodolog\\u00eda, filosof\\u00eda de la ciencia, Filosof\\u00eda de la Tecnociencia, filosof\\u00eda del conocimiento, Teor\\u00eda-Actor Red\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2019\\\/10\\\/14\\\/150099#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/curso-basico-sobre-filosofia-y-sociologia-de-la-ciencia#listItem\",\"name\":\"Curso B\\u00e1sico Sobre Filosof\\u00eda y Sociolog\\u00eda de la Ciencia\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/curso-basico-sobre-filosofia-y-sociologia-de-la-ciencia#listItem\",\"position\":2,\"name\":\"Curso B\\u00e1sico Sobre Filosof\\u00eda y Sociolog\\u00eda de la Ciencia\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/curso-basico-sobre-filosofia-y-sociologia-de-la-ciencia\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2019\\\/10\\\/14\\\/150099#listItem\",\"name\":\"Sobre la Tecnociencia, la Filosof\\u00eda del Conocimiento, el Constructivismo y La Teor\\u00eda Actor-red\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2019\\\/10\\\/14\\\/150099#listItem\",\"position\":3,\"name\":\"Sobre la Tecnociencia, la Filosof\\u00eda del Conocimiento, el Constructivismo y La Teor\\u00eda Actor-red\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/curso-basico-sobre-filosofia-y-sociologia-de-la-ciencia#listItem\",\"name\":\"Curso B\\u00e1sico Sobre Filosof\\u00eda y Sociolog\\u00eda de la Ciencia\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#organization\",\"name\":\"Un Universo invisible bajo nuestros pies\",\"description\":\"Los suelos y la vida\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/files\\\/2022\\\/02\\\/logo.png\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2019\\\/10\\\/14\\\/150099\\\/#organizationLogo\",\"width\":217,\"height\":72},\"image\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2019\\\/10\\\/14\\\/150099\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/juan.j.marti.14\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo\",\"name\":\"Juan Jos\\u00e9 Ib\\u00e1\\u00f1ez\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2019\\\/10\\\/14\\\/150099#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/387f3a100385573d8f42ce2a3211fd1c?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Juan Jos\\u00e9 Ib\\u00e1\\u00f1ez\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2019\\\/10\\\/14\\\/150099#webpage\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2019\\\/10\\\/14\\\/150099\",\"name\":\"Sobre la Tecnociencia, la Filosof\\u00eda del Conocimiento, el Constructivismo y La Teor\\u00eda Actor-red - Un Universo invisible bajo nuestros pies\",\"description\":\"Sobre la Tecnociencia, la Filosof\\u00eda del Conocimiento, el Constructivismo y La Teor\\u00eda Actor-red\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2019\\\/10\\\/14\\\/150099#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\"},\"datePublished\":\"2019-10-14T12:47:11+01:00\",\"dateModified\":\"2019-10-14T12:47:11+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#website\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/\",\"name\":\"Un Universo invisible bajo nuestros pies\",\"description\":\"Los suelos y la vida\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Sobre la Tecnociencia, la Filosof\u00eda del Conocimiento, el Constructivismo y La Teor\u00eda Actor-red - Un Universo invisible bajo nuestros pies","description":"Sobre la Tecnociencia, la Filosof\u00eda del Conocimiento, el Constructivismo y La Teor\u00eda Actor-red","canonical_url":"https:\/\/www.madrimasd.org\/blogs\/universo\/2019\/10\/14\/150099","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2019\/10\/14\/150099#blogposting","name":"Sobre la Tecnociencia, la Filosof\u00eda del Conocimiento, el Constructivismo y La Teor\u00eda Actor-red - Un Universo invisible bajo nuestros pies","headline":"Sobre la Tecnociencia, la Filosof\u00eda del Conocimiento, el Constructivismo y La Teor\u00eda Actor-red","author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author"},"publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-content\/blogs.dir\/42\/files\/857\/0-filosofia-del-conocimiento-y-tecnociencia.jpg","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2019\/10\/14\/150099\/#articleImage"},"datePublished":"2019-10-14T12:47:11+01:00","dateModified":"2019-10-14T12:47:11+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2019\/10\/14\/150099#webpage"},"isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2019\/10\/14\/150099#webpage"},"articleSection":"Curso b\u00e1sico de ciencia para jovenes universitarios y tecn\u00f3logos, Curso B\u00e1sico sobre Filosof\u00eda de la Tecnociencia, Curso B\u00e1sico Sobre Filosof\u00eda y Sociolog\u00eda de la Ciencia, Etnometodolog\u00eda, filosof\u00eda de la ciencia, Filosof\u00eda de la Tecnociencia, filosof\u00eda del conocimiento, Teor\u00eda-Actor Red"},{"@type":"BreadcrumbList","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2019\/10\/14\/150099#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo#listItem","position":1,"name":"Home","item":"https:\/\/www.madrimasd.org\/blogs\/universo","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/curso-basico-sobre-filosofia-y-sociologia-de-la-ciencia#listItem","name":"Curso B\u00e1sico Sobre Filosof\u00eda y Sociolog\u00eda de la Ciencia"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/curso-basico-sobre-filosofia-y-sociologia-de-la-ciencia#listItem","position":2,"name":"Curso B\u00e1sico Sobre Filosof\u00eda y Sociolog\u00eda de la Ciencia","item":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/curso-basico-sobre-filosofia-y-sociologia-de-la-ciencia","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2019\/10\/14\/150099#listItem","name":"Sobre la Tecnociencia, la Filosof\u00eda del Conocimiento, el Constructivismo y La Teor\u00eda Actor-red"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2019\/10\/14\/150099#listItem","position":3,"name":"Sobre la Tecnociencia, la Filosof\u00eda del Conocimiento, el Constructivismo y La Teor\u00eda Actor-red","previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/curso-basico-sobre-filosofia-y-sociologia-de-la-ciencia#listItem","name":"Curso B\u00e1sico Sobre Filosof\u00eda y Sociolog\u00eda de la Ciencia"}}]},{"@type":"Organization","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#organization","name":"Un Universo invisible bajo nuestros pies","description":"Los suelos y la vida","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/","logo":{"@type":"ImageObject","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2019\/10\/14\/150099\/#organizationLogo","width":217,"height":72},"image":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2019\/10\/14\/150099\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/juan.j.marti.14"]},{"@type":"Person","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo","name":"Juan Jos\u00e9 Ib\u00e1\u00f1ez","image":{"@type":"ImageObject","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2019\/10\/14\/150099#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/387f3a100385573d8f42ce2a3211fd1c?s=96&d=mm&r=g","width":96,"height":96,"caption":"Juan Jos\u00e9 Ib\u00e1\u00f1ez"}},{"@type":"WebPage","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2019\/10\/14\/150099#webpage","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/2019\/10\/14\/150099","name":"Sobre la Tecnociencia, la Filosof\u00eda del Conocimiento, el Constructivismo y La Teor\u00eda Actor-red - Un Universo invisible bajo nuestros pies","description":"Sobre la Tecnociencia, la Filosof\u00eda del Conocimiento, el Constructivismo y La Teor\u00eda Actor-red","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#website"},"breadcrumb":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2019\/10\/14\/150099#breadcrumblist"},"author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author"},"creator":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author"},"datePublished":"2019-10-14T12:47:11+01:00","dateModified":"2019-10-14T12:47:11+01:00"},{"@type":"WebSite","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#website","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/","name":"Un Universo invisible bajo nuestros pies","description":"Los suelos y la vida","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Un Universo invisible bajo nuestros pies - Los suelos y la vida","og:type":"article","og:title":"Sobre la Tecnociencia, la Filosof\u00eda del Conocimiento, el Constructivismo y La Teor\u00eda Actor-red - Un Universo invisible bajo nuestros pies","og:description":"Sobre la Tecnociencia, la Filosof\u00eda del Conocimiento, el Constructivismo y La Teor\u00eda Actor-red","og:url":"https:\/\/www.madrimasd.org\/blogs\/universo\/2019\/10\/14\/150099","og:image":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png","og:image:secure_url":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png","article:published_time":"2019-10-14T11:47:11+00:00","article:modified_time":"2019-10-14T11:47:11+00:00","article:publisher":"https:\/\/www.facebook.com\/juan.j.marti.14","twitter:card":"summary","twitter:title":"Sobre la Tecnociencia, la Filosof\u00eda del Conocimiento, el Constructivismo y La Teor\u00eda Actor-red - Un Universo invisible bajo nuestros pies","twitter:description":"Sobre la Tecnociencia, la Filosof\u00eda del Conocimiento, el Constructivismo y La Teor\u00eda Actor-red","twitter:image":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png"},"aioseo_meta_data":{"post_id":"150099","title":"","description":"Sobre la Tecnociencia, la Filosof\u00eda del Conocimiento, el Constructivismo y La Teor\u00eda Actor-red","keywords":[{"label":"filosof\u00eda de la Tecnociencia","value":"filosof\u00eda de la Tecnociencia"},{"label":"teor\u00eda Actor-Red","value":"teor\u00eda Actor-Red"},{"label":"Bruno Latour.","value":"Bruno Latour."}],"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":null,"isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","tabs":null,"priority":null,"frequency":null,"local_seo":null,"created":"2022-06-03 17:44:46","updated":"2026-05-26 19:11:57","limit_modified_date":false,"ai":null,"breadcrumb_settings":null,"seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/curso-basico-sobre-filosofia-y-sociologia-de-la-ciencia\" title=\"Curso B\u00e1sico Sobre Filosof\u00eda y Sociolog\u00eda de la Ciencia\">Curso B\u00e1sico Sobre Filosof\u00eda y Sociolog\u00eda de la Ciencia<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tSobre la Tecnociencia, la Filosof\u00eda del Conocimiento, el Constructivismo y La Teor\u00eda Actor-red\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.madrimasd.org\/blogs\/universo"},{"label":"Curso B\u00e1sico Sobre Filosof\u00eda y Sociolog\u00eda de la Ciencia","link":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/curso-basico-sobre-filosofia-y-sociologia-de-la-ciencia"},{"label":"Sobre la Tecnociencia, la Filosof\u00eda del Conocimiento, el Constructivismo y La Teor\u00eda Actor-red","link":"https:\/\/www.madrimasd.org\/blogs\/universo\/2019\/10\/14\/150099"}],"_links":{"self":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts\/150099"}],"collection":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/comments?post=150099"}],"version-history":[{"count":5,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts\/150099\/revisions"}],"predecessor-version":[{"id":150650,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts\/150099\/revisions\/150650"}],"wp:attachment":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/media?parent=150099"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/categories?post=150099"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/tags?post=150099"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}