{"id":151641,"date":"2021-03-08T12:51:03","date_gmt":"2021-03-08T11:51:03","guid":{"rendered":"http:\/\/www.madrimasd.org\/blogs\/universo\/?p=151641"},"modified":"2021-03-08T13:14:40","modified_gmt":"2021-03-08T12:14:40","slug":"el-gran-reseteo-hacia-una-sociedad-sustentable-foro-davos-foro-economico-mundial-y-el-cuento-de-caperucita-roja","status":"publish","type":"post","link":"https:\/\/www.madrimasd.org\/blogs\/universo\/2021\/03\/08\/151641","title":{"rendered":"El Gran Reseteo: \u00bfHacia una Sociedad Sustentable?: Foro Davos, Foro Econ\u00f3mico Mundial y el Cuento de Caperucita Roja"},"content":{"rendered":"<p align=\"center\">\u00a0<img decoding=\"async\" class=\"ngg-singlepic ngg-center\" src=\"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-content\/blogs.dir\/42\/files\/405\/foro-davos-sustentabilidad.jpg\" alt=\"foro-davos-sustentabilidad\" \/><\/p>\n<p align=\"center\"><span style=\"color: #0000ff;\">Colaje Im\u00e1genes Google<\/span><\/p>\n<p style=\"text-align: justify;\">La primera noticia que os ofrecemos hoy lleva por t\u00edtulo, traducido del ingl\u00e9s<em>:\u201d <\/em><a href=\"https:\/\/nuevoperiodico.com\/el-crecimiento-tiene-un-costo-devastador-para-la-naturaleza-dice-un-informe\/\"><strong><em>El crecimiento econ\u00f3mico tiene un costo devastador para la naturaleza<\/em><\/strong>\u201d<\/a>. Aunque tambi\u00e9n debiera a\u00f1adirse sobre las desigualdades sociales y otras muchas. \u00bfYa nadie parece dudarlo?. La segunda noticia que os ofrecemos, y cuyo encabezamiento resulta ser <strong><em><a title=\"Protegido por Outlook: https:\/\/www.libremercado.com\/2021-02-02\/gran-reseteo-foro-davos-foro-economico-mundial-trenes-cama-viajes-fin-capitalismo-6704819\/. Haga clic o pulse para seguir el v\u00ednculo.\" href=\"https:\/\/emea01.safelinks.protection.outlook.com\/?url=https%3A%2F%2Fwww.libremercado.com%2F2021-02-02%2Fgran-reseteo-foro-davos-foro-economico-mundial-trenes-cama-viajes-fin-capitalismo-6704819%2F&amp;data=04%7C01%7C%7Cefbec59a0af44da9d19f08d8c9ff13f7%7C84df9e7fe9f640afb435aaaaaaaaaaaa%7C1%7C0%7C637481444670529500%7CUnknown%7CTWFpbGZsb3d8eyJWIjoiMC4wLjAwMDAiLCJQIjoiV2luMzIiLCJBTiI6Ik1haWwiLCJXVCI6Mn0%3D%7C1000&amp;sdata=rjGzIyBUDneHkbSboUilI81RK90u%2Bb2wi5tVyBsQLhs%3D&amp;reserved=0\" target=\"_blank\">&#8216;El Gran Reseteo&#8217; de Davos concluye con la implantaci\u00f3n de los viajes en trenes-cama y el fin del capitalismo seg\u00fan el rotativo de internet &#8211; Libre Mercado<\/a><\/em><\/strong>, abunda en el tema desde un perspectiva de la derecha que a\u00fan es negacionista del cambio clim\u00e1tico, siendo muy cr\u00edtica copn este pronunciamiento\/amago\/propaganda del Gran Reseteo, como se denomina a este giro ya sea real, imaginario o propagand\u00edstico. <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-admin\/El%20Gran%20Reinicio\"><strong>\u00bfEs el gran reseteo una conspiraci\u00f3n?, se preguntan algunos en Wikipedi<\/strong>a<\/a>. \u00bf<a href=\"https:\/\/es.weforum.org\/agenda\/archive\/the-great-reset\/\">El Gran reinicio<\/a>?. \u00bf<a href=\"https:\/\/gaceta.es\/espana\/el-gran-reseteo-los-globalistas-quieren-resetear-la-economia-post-covid-20201007-1327\/\">Y que se p\u00ecensa en Latinoam\u00e9rica<\/a>?. \u00bfNo ser\u00e1 una nueva y perversa versi\u00f3n de \u201c<a href=\"https:\/\/es.wikipedia.org\/wiki\/La_doctrina_del_shock\">La doctrina del shock<\/a>\u201d nacida en la crisis de la primera d\u00e9cada del SXXI?. M\u00e1s que dudas albergo muchos temores, a pesar de que yo firmar\u00eda gran parte de los objetivos mostrados. Los malvados disfrazados de superh\u00e9roes?.<\/p>\n<p style=\"text-align: justify;\">Sin embargo, cambiar un modelo de desarrollo elaborado por los todopoderosos por otra propuesta dise\u00f1ada por ellos mismos, y que no da\u00f1e sus\u00a0 principales intereses y en especial, su capacidad para manejar el mundo a su antojo, es otro asunto. <strong><span style=\"color: #3366ff;\">Ellos son los l\u00edderes econ\u00f3micos y pol\u00edticos, es decir los adalides de la actual gobernanza mundial<\/span><\/strong> que nos vienen arrastrando por el fango a los pobres mortales. Realmente, <strong><span style=\"color: #3366ff;\">\u00bfSe creen realmente lo que dicen<\/span>?<\/strong>. Se me antoja algo casi imposible. Ahora bien uno de sus principales exponentes resulta ser el Foro Davos.<\/p>\n<p style=\"text-align: justify;\">Y es que el <a href=\"https:\/\/www.bbva.com\/es\/foro-economico-davos\/\">Foro de Davos 2021<\/a>, en <a href=\"https:\/\/economipedia.com\/actual\/lo-mas-destacado-del-foro-de-davos-2021.html\">sus conclusiones<\/a>, \u201cparece\u201d que comienzan a repensar el futuro, visto lo visto.<span style=\"color: #3366ff;\"> <strong>Esta lobby es un ejemplo palmario del neoliberalismo y su dictadura financiera<\/strong><\/span>, por cuanto all\u00ed se re\u00fanen personajes e instituciones que \u201cdicen\u201d representar a los agentes m\u00e1s poderosos del mundo. En \u00e9l se: \u201c<em>re\u00fanen <span style=\"color: #3366ff;\"><strong>los principales l\u00edderes empresariales, los l\u00edderes<\/strong><\/span><strong><span style=\"color: #3366ff;\"> pol\u00edticos internacionales<\/span><\/strong>, as\u00ed como periodistas e intelectuales selectos, a efectos de analizar <span style=\"color: #3366ff;\"><strong>los problemas m\u00e1s apremiantes que afronta el mundo, y entre ellos, la salud y el medio ambiente desde 1971<\/strong><\/span><\/em>\u201d. Sin embargo, muchos dudamos de sus verdaderas intenciones y como bot\u00f3n de muestra leer estas noticias: <a href=\"https:\/\/www.elsaltodiario.com\/capitalismo\/nick-buxton-proposito-davos-golpe-transnacional\">El prop\u00f3sito de Davos: \u00a1\u00bfun golpe transnacional?<\/a>; <a href=\"https:\/\/www.eldiario.es\/opinion\/zona-critica\/desgobierna-mundo_129_4789809.html\">Pero \u00bfqui\u00e9n (des)gobierna este mundo?<\/a>.<\/p>\n<p><span style=\"color: #3366ff;\"><strong>Vivimos en la era de la<\/strong><\/span> <a href=\"https:\/\/es.wikipedia.org\/wiki\/Posverdad\">posverdad<\/a>: y esta resulta ser <span style=\"color: #3366ff;\"><strong>mucho m\u00e1s nefasta que la mentira<\/strong><\/span>, por cuanto confunde, distorsiona y oculta las genuinas verdades. Empero hasta los l\u00edderes chinos, entre otros muchos, tambi\u00e9n\u00a0 defienden ahora que el modelo econ\u00f3mico neoliberal ya no funciona. Nos dirigimos todos hacia un modelo chino: <a href=\"https:\/\/es.wikipedia.org\/wiki\/Un_pa\u00eds,_dos_sistemas\">\u00bfUn pa\u00eds mil sistemas?<\/a>.<\/p>\n<p style=\"text-align: justify;\">Realmente tanta \u201clumbrera\u201d y sabidur\u00eda de estos agentes casi infinitamente ricos y poderosos me desconcierta. <strong><span style=\"color: #3366ff;\">En esta bit\u00e1cora llevamos ya quince a\u00f1os bramando lo mismo. Vamos camino de arrasar el planeta y a sus habitantes de todo tipo (biosfera)<\/span><\/strong>. Llevamos tres lustros advirtiendo de <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2019\/06\/17\/149684\">que el cambio clim\u00e1tico, p\u00e9rdida de biodiversidad, etc. son s\u00edntomas de una degradaci\u00f3n ambiental insostenible<strong> <\/strong>que se encuentra ya a punto de explotar irremediablemente<\/a>. Podr\u00eda personalmente pensar si la <a href=\"https:\/\/es.wikipedia.org\/wiki\/Pandemia_de_COVID-19\">pandemia COVID-19<\/a> les ha metido el miedo en el cuerpo y hoy se sienten m\u00e1s inseguros y mortales. \u00bf\u00bf??. \u00a1Lo dudo!. Ser\u00eda un gran reseteo de sus cerebros, ya que <strong><span style=\"color: #3366ff;\">de facto supone<\/span> r<span style=\"color: #3366ff;\">econocer que sus pol\u00edticas son las que han conducido a la situaci\u00f3n en la que nos encontramos<\/span><\/strong>. Ellos han sido los culpables y ahora, \u00bfhablan todos en nombre de la inmensa mayor\u00eda de v\u00edctimas?.<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #3366ff;\"><strong>Miren ustedes, los poderosos, en una econom\u00eda de libre mercado sin aduanas al tr\u00e1nsito\u00a0 de bienes, personas y mercanc\u00edas, resulta casi imposible frenar la libre circulaci\u00f3n de pat\u00f3genos y sus enfermedades infecciosas. Y cuando se ha tomado alguna medida, como actualmente ocurre con la pandemia, la econom\u00eda neoliberal se desploma<\/strong><\/span>. Del mismo modo, para los pitonisos que intentan predecir crecimientos econ\u00f3micos bas\u00e1ndose en modelos matem\u00e1ticos lineales, cuando el sistema econ\u00f3mico (como casi todo) es complejo, no lineal, y como corolario impredecible, cabr\u00eda recordarles que <strong><span style=\"color: #3366ff;\">un min\u00fasculo virus, cuyo surgimiento y expansi\u00f3n era imposible de pronosticar,\u00a0 ha dado un enorme revolc\u00f3n a loa econom\u00eda y posiblemente a muchas empresas multinacionales<\/span><\/strong>. Empero todo <strong><span style=\"color: #3366ff;\">ello a costa de la pobreza, morbilidad y muerte de parte de la<\/span> <span style=\"color: #3366ff;\">ciudadan\u00eda y el terror del resto de los mortales<\/span><\/strong>.<\/p>\n<p style=\"text-align: justify;\">Por otro lado aprovecho la ocasi\u00f3n para criticar las noticias de todos los sabios y expertos, incluyendo por supuesto a los propios cient\u00edficos que, intentan acaparar notoriedad pronosticando el devenir de la pandemia, o de la era \u201c<em>poscovid<\/em>\u201d, \u201cla nueva (sub)normalidad\u201d, etc. Como adivinos los cient\u00edficos no suelen dar en el clavo ni por casualidad. Y es que a falta de datos, los pron\u00f3sticos de los investigadores son tan respetables, como los del Foro Davos o las videntes de la TV y radio. Ya he constatado en ocasiones precedentes que los integrantes de la clase cient\u00edfica\u00a0 espetan vaticinios que casi nunca se cumplen. Zapatero a tus zapatos.<\/p>\n<p style=\"text-align: justify;\">Ojal\u00e1 pudiera creerme el gran reseteo que claman, o con el que amenazan, llevara la cordura a nuestra sociedad. \u00a0Empero que lo propongan aquellos que se han lucrado a nuestra costa, dando la imagen ahora de \u201c<em>hermanitas de la caridad<\/em>\u201d o ecologistas\u2026\u2026. <strong><span style=\"color: #3366ff;\">Si realmente creen lo que dicen, debieran primero<\/span><\/strong> pedir disculpas, luego ser juzgados y, finalmente, ceder el poder a los que no nos han hecho <a href=\"https:\/\/es.wiktionary.org\/wiki\/comulgar_con_ruedas_de_molino\">comulgar hasta el momento con ruedas de molino<\/a>\u201d. En la segunda noticia habla el \u201clibre mercado\u201d y \u2026\u2026, no desperdici\u00e9is ni una palabra.<\/p>\n<p style=\"text-align: justify;\">Todo queda pues en suspense, pero con <a href=\"https:\/\/dle.rae.es\/mosquear#PuDeGbk\">un mosqueo de tres pares de narices<\/a>\u2026\u2026<\/p>\n<p><span style=\"color: #008000;\"><strong>Juan Jos\u00e9 Ib\u00e1\u00f1ez<\/strong><\/span><\/p>\n<p><span style=\"color: #800000;\"><em>Contin\u00faa\u2026\u2026\u2026..<\/em><\/span><\/p>\n<p><!--more--><\/p>\n<h2><a href=\"https:\/\/www.terradaily.com\/reports\/Economic_growth_has_devastating_cost_to_nature_review_finds_999.html\"><strong>Economic growth has &#8216;devastating cost to nature&#8217;, review finds<\/strong><\/a><strong><br \/>\n<\/strong>By Patrick GALEY; Paris (AFP) Feb 2, 2021<\/h2>\n<p style=\"text-align: justify;\">Humanity&#8217;s unbridled growth in recent decades has come at a \u00abdevastating cost to nature\u00bb according a wide-ranging international review on the vital economic role played by our living planet.<\/p>\n<p style=\"text-align: justify;\">The 600-page rundown of scientific material commissioned by the British government highlighted the precarious state of global biodiversity and warned that nothing short of a sea change in how countries power economic growth could prevent catastrophic impacts for nature, and humanity.<\/p>\n<p style=\"text-align: justify;\">The Dasgupta Review &#8212; a two-year collaboration of hundreds of academics from around the world overseen by Partha Dasgupta, professor emeritus of economics at the University of Cambridge &#8212; said that all livelihoods depended on the health of the planet.<\/p>\n<p style=\"text-align: justify;\">It showed that while global capital produced per person had doubled in the three decades since 1992, the stock of natural capital &#8212; that is, the quantifiable benefit an individual derives from services bestowed by nature &#8212; had plunged 40 percent.<\/p>\n<p style=\"text-align: justify;\">\u00abWhile humanity has prospered immensely in recent decades, the ways in which we have achieved such prosperity means that it has come at a devastating cost to nature,\u00bb the review said. It called for a fundamental redressing of humanity&#8217;s demands and nature&#8217;s supply, warning that biodiversity is intricately linked with human wellbeing and health. Some species are going extinct up to 1,000 times faster than the historical average, \u00abundermining nature&#8217;s productivity, resilience and adaptability\u00bb, the review said.<\/p>\n<p style=\"text-align: justify;\"><strong>&#8211; &#8216;Totally dependent&#8217; &#8211;<\/strong><\/p>\n<p style=\"text-align: justify;\">It warned that catastrophes related to nature loss &#8212; including the Covid-19 pandemic which was driven by land-use changes and species exploitation &#8212; could prove to be \u00abthe tip of the iceberg\u00bb if development continued at its current rate.<\/p>\n<p>\u00abWe are totally dependent upon the natural world,\u00bb renowned naturalist David Attenborough wrote in a foreword to the review.<\/p>\n<p>\u00abIt supplies us with every oxygen-laden breath we take and every mouthful of food we eat.<\/p>\n<p>\u00abBut we are currently damaging it so profoundly that many of its natural systems are now on the verge of breakdown.\u00bb<\/p>\n<p>The economic benefits of biodiversity had historically been missed from growth models, distorting the value of capital accumulation and leaving crucial conservation programmes chronically underfunded, said the review.<\/p>\n<p>With an estimated $4-6 trillion in funding each year going to unsustainable economic activities such as fossil fuel use and damaging farming techniques, governments \u00abexacerbate the problem by paying people more to exploit nature than to protect it\u00bb, it added.<\/p>\n<p>It called for a new way of defining economic wellbeing, one that takes nature&#8217;s services into account, to replace the traditional GDP model.<\/p>\n<p>But it warned that choosing a more sustainable growth trajectory would require \u00abtransformative change, underpinned by levels of ambition, coordination and political will akin to, or even grater than, those of the Marshall Plan\u00bb.<\/p>\n<p>&#8211; Rethinking economics &#8211;<\/p>\n<p>Such a sustainable future would include a total decarbonisation of the global energy system, the review concluded.<\/p>\n<p>More than that, properly managing Earth&#8217;s precious resources would involve people in richer nations changing consumption and wasteful habits, and better access to finance and education for women.<\/p>\n<p>\u00abNever before has it been so important to consider the economics of nature and the role biodiversity plays in supporting a healthy economy,\u00bb said Guy Poppy, professor of Ecology at the University of Southampton, who was not involved in the review.<\/p>\n<p>\u00abTwo of the major challenges currently facing humankind &#8212; climate change and Covid &#8212; both illustrate the need to link economics with the environment and to rethink how we will become more prosperous and healthy in the future.\u00bb<\/p>\n<p>The review pointed to two key summits in 2021 &#8212; the <strong>COP15<\/strong> talks on biodiversity and the <strong>COP26<\/strong> meeting on climate change &#8212; as opportunities to start to undo the damage humanity has inflicted on its only home.<\/p>\n<p>\u00abWe and our descendents deserve nothing less,\u00bb it said.<\/p>\n<h2><span style=\"color: #800000;\"><strong>El crecimiento econ\u00f3mico tiene un &#8216;costo devastador para la naturaleza&#8217;, seg\u00fan una revisi\u00f3n<\/strong><\/span><\/h2>\n<p><em>P<span style=\"color: #008080;\">or Patrick GALEY, Par\u00eds (AFP) 2 de febrero de 2021<\/span><\/em><\/p>\n<p><span style=\"color: #008080;\"><em><strong><span style=\"text-decoration: underline;\">El desenfrenado crecimiento de la humanidad en las \u00faltimas d\u00e9cadas ha tenido un \u00abcosto devastador para la naturaleza<\/span><\/strong>\u00ab, seg\u00fan una amplia revisi\u00f3n internacional sobre el papel econ\u00f3mico vital que desempe\u00f1a nuestro planeta vivo.<\/em><\/span><\/p>\n<p><span style=\"color: #008080;\"><em>El resumen de 600 p\u00e1ginas de material cient\u00edfico encargado por el gobierno brit\u00e1nico destac\u00f3 <strong>el estado precario de la biodiversidad global y advirti\u00f3 que nada menos que un cambio radical en la forma en que los pa\u00edses impulsan el crecimiento econ\u00f3mico podr\u00eda prevenir impactos catastr\u00f3ficos para la naturaleza y la humanidad<\/strong>.<\/em><\/span><\/p>\n<p><span style=\"color: #008080;\"><em>Dasgupta Review, una colaboraci\u00f3n de dos a\u00f1os de cientos de acad\u00e9micos de todo el mundo supervisada por Partha Dasgupta, profesor em\u00e9rito de econom\u00eda en la Universidad de Cambridge, dijo que todos los medios de vida depend\u00edan de la salud del planeta.<\/em><\/span><\/p>\n<p><span style=\"color: #008080;\"><em><strong>Mostr\u00f3 que, si bien el capital mundial producido por persona se hab\u00eda duplicado en las tres d\u00e9cadas desde 1992, el stock de capital natural, es decir, el beneficio cuantificable que un individuo obtiene de los servicios que brinda la naturaleza, se hab\u00eda desplomado un 40 por ciento<\/strong>.<\/em><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #008080;\"><em>\u00ab<strong>Si bien la humanidad ha prosperado enormemente en las \u00faltimas d\u00e9cadas, las formas en que hemos logrado tal prosperidad significan que ha tenido un costo devastador para la naturaleza<\/strong>\u00ab, dijo la revisi\u00f3n.<\/em><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #008080;\"><em>Pidi\u00f3 una reparaci\u00f3n fundamental de las demandas de la humanidad y el suministro de la naturaleza, advirtiendo <strong>que la biodiversidad est\u00e1 \u00edntimamente relacionada con el bienestar y la salud humanos<\/strong>.<\/em><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #008080;\"><em>Algunas especies se est\u00e1n extinguiendo hasta 1.000 veces m\u00e1s r\u00e1pido que el promedio hist\u00f3rico, \u00ab<strong>socavando la productividad, la resiliencia y la adaptabilidad de la naturaleza<\/strong>\u00ab, seg\u00fan la revisi\u00f3n.<\/em><\/span><\/p>\n<p><span style=\"color: #008080;\"><em><strong>&#8211; &#8216;Totalmente dependiente&#8217; &#8211;<\/strong><\/em><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #008080;\"><em><strong>Advirti\u00f3 que las cat\u00e1strofes relacionadas con la p\u00e9rdida de la naturaleza, incluida la pandemia Covid-19, impulsada por cambios en el uso de la tierra y la explotaci\u00f3n de especies, podr\u00edan llegar a ser \u00abla punta del iceberg\u00bb si el desarrollo contin\u00faa al ritmo actual<\/strong>.<\/em><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #008080;\"><em>\u00ab<strong>Dependemos totalmente del mundo natural<\/strong>\u00ab, escribi\u00f3 el renombrado naturalista David Attenborough en un pr\u00f3logo de la rese\u00f1a. \u00abNos proporciona cada respiraci\u00f3n cargada de ox\u00edgeno que tomamos y cada bocado de comida que comemos.<\/em><\/span><\/p>\n<p><span style=\"color: #008080;\"><em><strong>Su \u00fanico hogar<\/strong>.<\/em><\/span><\/p>\n<p><span style=\"color: #008080;\"><em>\u00abNosotros y nuestros descendientes no merecemos menos\u00bb, dec\u00eda.<\/em><\/span><\/p>\n<p><span style=\"color: #008080;\"><em>Pero advirti\u00f3 que elegir <strong>una trayectoria de crecimiento m\u00e1s sostenible requerir\u00eda \u00abun cambio transformador, respaldado por niveles de ambici\u00f3n, coordinaci\u00f3n y voluntad pol\u00edtica similares, o incluso mayores, a los del Plan Marshall<\/strong>\u00ab.<\/em><\/span><\/p>\n<p><span style=\"color: #008080;\"><em><strong><span style=\"text-decoration: underline;\">&#8211; Repensar la econom\u00eda &#8211;<\/span><\/strong><\/em><\/span><\/p>\n<p><span style=\"color: #008080;\"><em><strong>Un futuro tan sostenible incluir\u00eda una descarbonizaci\u00f3n total del sistema energ\u00e9tico global<\/strong>, concluy\u00f3 la revisi\u00f3n.<\/em><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #008080;\"><em><strong>M\u00e1s que eso, la gesti\u00f3n adecuada de los preciosos recursos de la Tierra implicar\u00eda que las personas de las naciones m\u00e1s ricas cambiaran el consumo y los h\u00e1bitos derrochadores, y<\/strong> un mejor acceso a las finanzas y la educaci\u00f3n para las mujeres.<\/em><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #008080;\"><em>\u00ab<strong>Nunca antes hab\u00eda sido tan importante considerar la econom\u00eda de la naturaleza y el papel que juega la biodiversidad en el apoyo a una econom\u00eda saludable<\/strong>\u00ab, dijo Guy Poppy, profesor de Ecolog\u00eda en la Universidad de Southampton, que no particip\u00f3 en la revisi\u00f3n.<\/em><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #008080;\"><em>\u00ab<strong>Dos de los principales desaf\u00edos que enfrenta actualmente la humanidad, el cambio clim\u00e1tico y Covid, ilustran la necesidad de vincular la econom\u00eda con el medio ambiente y repensar c\u00f3mo seremos m\u00e1s pr\u00f3speros y saludables en el futuro<\/strong>\u00ab.<\/em><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #008080;\"><em>La revisi\u00f3n se\u00f1al\u00f3 dos cumbres clave en 2021, las conversaciones de la C<strong>OP15 <\/strong>sobre biodiversidad y la reuni\u00f3n de la COP26 sobre el cambio clim\u00e1tico, como oportunidades para comenzar a deshacer el da\u00f1o que la humanidad ha infligido en su \u00fanico hogar.<\/em><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #008080;\"><em>\u00ab<strong>Nosotros y nuestros descendientes no merecemos menos<\/strong>\u00ab, dec\u00eda.<\/em><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #008080;\"><em>El Gran Reseteo de Davos concluye con la implantaci\u00f3n de los viajes en trenes cama y el fin del capitalismo<\/em><\/span><\/p>\n<h2><a title=\"Protegido por Outlook: https:\/\/www.libremercado.com\/2021-02-02\/gran-reseteo-foro-davos-foro-economico-mundial-trenes-cama-viajes-fin-capitalismo-6704819\/. Haga clic o pulse para seguir el v\u00ednculo.\" href=\"https:\/\/emea01.safelinks.protection.outlook.com\/?url=https%3A%2F%2Fwww.libremercado.com%2F2021-02-02%2Fgran-reseteo-foro-davos-foro-economico-mundial-trenes-cama-viajes-fin-capitalismo-6704819%2F&amp;data=04%7C01%7C%7Cefbec59a0af44da9d19f08d8c9ff13f7%7C84df9e7fe9f640afb435aaaaaaaaaaaa%7C1%7C0%7C637481444670529500%7CUnknown%7CTWFpbGZsb3d8eyJWIjoiMC4wLjAwMDAiLCJQIjoiV2luMzIiLCJBTiI6Ik1haWwiLCJXVCI6Mn0%3D%7C1000&amp;sdata=rjGzIyBUDneHkbSboUilI81RK90u%2Bb2wi5tVyBsQLhs%3D&amp;reserved=0\" target=\"_blank\">&#8216;El Gran Reseteo&#8217; de Davos concluye con la implantaci\u00f3n de los viajes en trenes-cama y el fin del capitalismo &#8211; Libre Mercado<\/a><\/h2>\n<p style=\"text-align: left;\" align=\"center\">Los l\u00edderes del Foro Econ\u00f3mico Mundial anuncian el adelanto de la Agenda 2030, porque los ciudadanos \u00abya est\u00e1n preparados\u00bb. <a title=\"Protegido por Outlook: https:\/\/www.libertaddigital.com\/opinion\/elena-berberana\/. Haga clic o pulse para seguir el v\u00ednculo.\" href=\"https:\/\/emea01.safelinks.protection.outlook.com\/?url=https%3A%2F%2Fwww.libertaddigital.com%2Fopinion%2Felena-berberana%2F&amp;data=04%7C01%7C%7Cefbec59a0af44da9d19f08d8c9ff13f7%7C84df9e7fe9f640afb435aaaaaaaaaaaa%7C1%7C0%7C637481444670539491%7CUnknown%7CTWFpbGZsb3d8eyJWIjoiMC4wLjAwMDAiLCJQIjoiV2luMzIiLCJBTiI6Ik1haWwiLCJXVCI6Mn0%3D%7C1000&amp;sdata=0zmGcMJ6PJxlhQQldplc54mySl6hhSzbYDNFOEUVJHg%3D&amp;reserved=0\" target=\"_blank\">Elena Berberana<\/a>\u00a0<a title=\"Protegido por Outlook: https:\/\/www.twitter.com\/elenaberberana. Haga clic o pulse para seguir el v\u00ednculo.\" href=\"https:\/\/emea01.safelinks.protection.outlook.com\/?url=https%3A%2F%2Fwww.twitter.com%2Felenaberberana&amp;data=04%7C01%7C%7Cefbec59a0af44da9d19f08d8c9ff13f7%7C84df9e7fe9f640afb435aaaaaaaaaaaa%7C1%7C0%7C637481444670539491%7CUnknown%7CTWFpbGZsb3d8eyJWIjoiMC4wLjAwMDAiLCJQIjoiV2luMzIiLCJBTiI6Ik1haWwiLCJXVCI6Mn0%3D%7C1000&amp;sdata=MWYWhEJgLRc%2BMX3cKxV9MlDZPY3B8yBIUvIv7cU4qoI%3D&amp;reserved=0\" target=\"_blank\">Seguir a elenaberberana<\/a>; 2021-02-02<\/p>\n<p style=\"text-align: justify;\"><strong>Jefes de Estado, gobiernos, CEO de empresas, medios de comunicaci\u00f3n globales y l\u00edderes izquierdistas de la sociedad civil han coincidido en que la<\/strong>\u00a0<strong>Agenda 2030<\/strong>\u00a0<strong>debe adelantarse<\/strong>. Es la conclusi\u00f3n final sustra\u00edda del\u00a0<a title=\"Protegido por Outlook: https:\/\/es.weforum.org\/. Haga clic o pulse para seguir el v\u00ednculo.\" href=\"https:\/\/emea01.safelinks.protection.outlook.com\/?url=https%3A%2F%2Fes.weforum.org%2F&amp;data=04%7C01%7C%7Cefbec59a0af44da9d19f08d8c9ff13f7%7C84df9e7fe9f640afb435aaaaaaaaaaaa%7C1%7C0%7C637481444670579469%7CUnknown%7CTWFpbGZsb3d8eyJWIjoiMC4wLjAwMDAiLCJQIjoiV2luMzIiLCJBTiI6Ik1haWwiLCJXVCI6Mn0%3D%7C1000&amp;sdata=uspgqHO6OEuSB3alE30zKhPgUOJpMQE6ECT2xTEMXVI%3D&amp;reserved=0\" target=\"_blank\">Foro Econ\u00f3mico Mundial<\/a>\u00a0(\u2026.). <strong>La excusa<\/strong> para adelantar este proyecto colectivista, que persigue la\u00a0<strong>instauraci\u00f3n de un modelo socialista mundial y sin fronteras<\/strong>, bajo el lema \u00ab<strong>The Great Reset<\/strong>\u00ab, se debe, seg\u00fan su fundador Klaus Schwab, a la crisis provocada por el coronavirus a nivel global y la alta contaminaci\u00f3n en el planeta.<\/p>\n<p style=\"text-align: justify;\">\u00a0\u00ab<strong>Ahora es el momento del Gran Reinicio<\/strong>\u00ab,\u00a0<a title=\"Protegido por Outlook: https:\/\/es.weforum.org\/agenda\/2020\/06\/ahora-es-el-momento-de-un-gran-reinicio\/. Haga clic o pulse para seguir el v\u00ednculo.\" href=\"https:\/\/emea01.safelinks.protection.outlook.com\/?url=https%3A%2F%2Fes.weforum.org%2Fagenda%2F2020%2F06%2Fahora-es-el-momento-de-un-gran-reinicio%2F&amp;data=04%7C01%7C%7Cefbec59a0af44da9d19f08d8c9ff13f7%7C84df9e7fe9f640afb435aaaaaaaaaaaa%7C1%7C0%7C637481444670589467%7CUnknown%7CTWFpbGZsb3d8eyJWIjoiMC4wLjAwMDAiLCJQIjoiV2luMzIiLCJBTiI6Ik1haWwiLCJXVCI6Mn0%3D%7C1000&amp;sdata=YVtWsWPN26AEVWrk5WrzkarC36nCAzQRbGtng85l0rk%3D&amp;reserved=0\" target=\"_blank\">han anunciado en su web<\/a>, despu\u00e9s de que finalizaran las reuniones de la cumbre celebrada entre el 25 y 29 de enero en Suiza. Parece ser que\u00a0<strong>la poblaci\u00f3n se encuentra lo suficientemente sometida<\/strong>, <strong>debido al miedo provocado por la tragedia sanitaria, <span style=\"text-decoration: underline;\">para acatar las \u00f3rdenes del c\u00f3nclave de mandatarios<\/span><\/strong>. As\u00ed lo indican en el\u00a0<a title=\"Protegido por Outlook: https:\/\/es.weforum.org\/agenda\/2020\/06\/ahora-es-el-momento-de-un-gran-reinicio\/. Haga clic o pulse para seguir el v\u00ednculo.\" href=\"https:\/\/emea01.safelinks.protection.outlook.com\/?url=https%3A%2F%2Fes.weforum.org%2Fagenda%2F2020%2F06%2Fahora-es-el-momento-de-un-gran-reinicio%2F&amp;data=04%7C01%7C%7Cefbec59a0af44da9d19f08d8c9ff13f7%7C84df9e7fe9f640afb435aaaaaaaaaaaa%7C1%7C0%7C637481444670599465%7CUnknown%7CTWFpbGZsb3d8eyJWIjoiMC4wLjAwMDAiLCJQIjoiV2luMzIiLCJBTiI6Ik1haWwiLCJXVCI6Mn0%3D%7C1000&amp;sdata=%2BrrHwjjIwlzzJL7aqrmVlxwwCrCvNFihmVF%2FWsbZ4FU%3D&amp;reserved=0\" target=\"_blank\">informe acordado en Davos 2021<\/a>, en el que se refleja que los nuevos cambios del \u00ab<strong>Gran Reseteo<\/strong>\u00bb <strong>ser\u00e1n <\/strong><strong><span style=\"text-decoration: underline;\">aceptados sin rechistar por los ciudadanos<\/span><\/strong>.<\/p>\n<p style=\"text-align: justify;\">\u00abUn aspecto positivo de la pandemia es que nos ha ense\u00f1ado que podemos introducir cambios radicales en nuestro estilo de vida con gran rapidez. Los ciudadanos han demostrado con creces que<strong>\u00a0est\u00e1n dispuestos a hacer sacrificios<\/strong>\u00a0<strong>por el bien de la atenci\u00f3n sanitaria y otros trabajadores esenciales y grupos de poblaci\u00f3n vulnerables, como los ancianos<\/strong>. Es evidente que existe <strong>una voluntad de construir una sociedad mejor<\/strong> y debemos aprovecharla para\u00a0<strong>garantizar el Gran Reinicio que necesitamos con tanta urgencia<\/strong>\u00ab, se\u00f1ala uno de los p\u00e1rrafos de la Agenda de Davos 2021. El mismo Klaus Schwab ha aseverado que \u00ab<strong>los ciudadanos ya est\u00e1n preparados para afrontarlo<\/strong>\u00ab.<\/p>\n<p style=\"text-align: justify;\"><strong>Adem\u00e1s de la excusa inicial de la p<\/strong>andemia, como apunt\u00f3 el fundador alem\u00e1n del Foro, Klaus Schwab, el segundo <strong>pretexto para acelerar la imposici\u00f3n de la Agenda 2030<\/strong> (que en Espa\u00f1a est\u00e1 a cargo de Pablo Iglesias)<strong>\u00a0es el supuesto cambio clim\u00e1tico<\/strong>. Pese a que centenares de cient\u00edficos elaboraron una carta com\u00fan explicando que no existen evidencias que culpen a la mano del hombre, y que, sobre todo, se debe a un proceso meteorol\u00f3gico propio del planeta Tierra, los <strong>l\u00edderes de Davos insisten en la culpabilidad del ser humano en la contaminaci\u00f3n y el giro del clima<\/strong>.<\/p>\n<p style=\"text-align: justify;\">Como resultado, \u00ab<strong>a partir de 2021<\/strong>,\u00a0<strong>la forma de viajar de las clases medias debe cambiar rotundamente<\/strong>\u00ab, expone la Agenda de Davos 2021. Tal y como ya avisara el multimillonario\u00a0<a title=\"Protegido por Outlook: https:\/\/www.libertaddigital.com\/personajes\/bill-gates\/. Haga clic o pulse para seguir el v\u00ednculo.\" href=\"https:\/\/emea01.safelinks.protection.outlook.com\/?url=https%3A%2F%2Fwww.libertaddigital.com%2Fpersonajes%2Fbill-gates%2F&amp;data=04%7C01%7C%7Cefbec59a0af44da9d19f08d8c9ff13f7%7C84df9e7fe9f640afb435aaaaaaaaaaaa%7C1%7C0%7C637481444670599465%7CUnknown%7CTWFpbGZsb3d8eyJWIjoiMC4wLjAwMDAiLCJQIjoiV2luMzIiLCJBTiI6Ik1haWwiLCJXVCI6Mn0%3D%7C1000&amp;sdata=8%2F6l76tVFYMKf9z8II6qxzp8eg%2BnMrZJDA2jfixrwpA%3D&amp;reserved=0\" target=\"_blank\"><strong>Bill Gates<\/strong><\/a>, tambi\u00e9n\u00a0<a title=\"Protegido por Outlook: https:\/\/www.youtube.com\/watch?v=cf-Pxxl_j0I. Haga clic o pulse para seguir el v\u00ednculo.\" href=\"https:\/\/emea01.safelinks.protection.outlook.com\/?url=https%3A%2F%2Fwww.youtube.com%2Fwatch%3Fv%3Dcf-Pxxl_j0I&amp;data=04%7C01%7C%7Cefbec59a0af44da9d19f08d8c9ff13f7%7C84df9e7fe9f640afb435aaaaaaaaaaaa%7C1%7C0%7C637481444670609462%7CUnknown%7CTWFpbGZsb3d8eyJWIjoiMC4wLjAwMDAiLCJQIjoiV2luMzIiLCJBTiI6Ik1haWwiLCJXVCI6Mn0%3D%7C1000&amp;sdata=gvLuVGDcBYPtrZzWUUXTeAvF1NOcYQnsDgI0kV0EBpg%3D&amp;reserved=0\" target=\"_blank\">miembro del Foro Econ\u00f3mico Mundial<\/a>, \u00ablos viajes en avi\u00f3n se van a reducir a m\u00e1s de la mitad en estos pr\u00f3ximos a\u00f1os. Los aviones contaminan mucho\u00bb.<\/p>\n<p style=\"text-align: justify;\">Por esta raz\u00f3n, el Foro de Davos ha anunciado al t\u00e9rmino de la cumbre que\u00a0<strong>las clases medias volver\u00e1n a viajar en tren-cama<\/strong>. Se acab\u00f3 aquello de salir de Madrid y estar en Londres en dos horas. Para inocular esta idea en la ciudadan\u00eda, en su nuevo spot propagand\u00edstico, el Foro Econ\u00f3mico Mundial intenta vender al p\u00fablico \u00ablo maravilloso que es hacer viajes en trenes nocturnos\u00bb como suced\u00eda antes de la d\u00e9cada de los 80 (\u2026.).\u00a0<strong>El gobierno de Gran Breta\u00f1a ha invertido 150 millones en trenes-cama\u00a0<\/strong>entre Londres y Escocia.<\/p>\n<p style=\"text-align: justify;\">En base a este prop\u00f3sito,\u00a0<strong>el avi\u00f3n ser\u00e1 un privilegio de ricos<\/strong>. El precio de los vuelos se elevar\u00e1, con la excusa de la contaminaci\u00f3n, viajar en avi\u00f3n se har\u00e1 inaccesible para la clase trabajadora. Por tanto, Bill Gates y sus colegas del Foro de Davos s\u00ed podr\u00e1n viajar en avi\u00f3n, pero el resto tendr\u00e1 que aguantar horas y horas en las camas de los ferrocarriles para trasladarse de pa\u00eds. Todo un adelanto. (\u2026.). La Uni\u00f3n Europea acord\u00f3 llamar al a\u00f1o 2021 \u00ab<strong>el a\u00f1o del ferrocarril europeo<\/strong>\u00ab. Impulsar los viajes en tren podr\u00eda ayudar al bloque a alcanzar la neutralidad de carbono para 2050. El comportamiento del consumidor ya ha comenzado a cambiar. (\u2026.) Este nuevo pron\u00f3stico se une a otros incluidos en el plan del <strong>Gran Reseteo<\/strong>, <strong>como la de no comer carne en 2030 y ser un individuo sin derecho a tener una propiedad, seg\u00fan los planificadores centrales de este\u00a0<em>Mundo Feliz<\/em>, al estilo de Huxley<\/strong>.<\/p>\n<p style=\"text-align: justify;\"><strong>\u00abCapitalismo inclusivo\u00bb<\/strong><\/p>\n<p style=\"text-align: justify;\">Otro de los aspectos destacados en los informes finales de la <strong>Agenda de Davos 2021 es<\/strong> <strong>el cuestionamiento del capitalismo actual<\/strong>. De forma m\u00e1s sofisticada, el Foro Econ\u00f3mico Mundial <strong>esconde sus intenciones socialcomunistas<\/strong> bajo un nuevo concepto desarrollado este a\u00f1o: \u00ab<strong>el capitalismo entre partes<\/strong>\u00ab<strong>\u00a0o\u00a0<\/strong>\u00ab<strong>capitalismo inclusivo<\/strong>\u00ab. Para los l\u00edderes del Foro, los presuntos da\u00f1os ocasionados por el <strong>supuesto cambio clim\u00e1tico a nivel mundial \u00abest\u00e1n abocando a grandes desigualdades econ\u00f3micas\u00bb, y esto se debe \u00abal capitalismo actual<\/strong>\u00ab.<\/p>\n<p style=\"text-align: justify;\">Marck Benioff, CEO de la compa\u00f1\u00eda Salforces, ha llegado a decir en una de las intervenciones en Davos que \u00ab<strong>el capitalismo, tal y como lo hemos conocido, ha muerto<\/strong>\u00ab. El Foro Econ\u00f3mico Mundial lo aclara en el resumen de esta \u00faltima cumbre: \u00ab<strong>El capitalismo, el que se ha practicado en las \u00faltimas d\u00e9cadas, con su obsesi\u00f3n en la maximizaci\u00f3n de beneficios para los accionistas ha dado lugar a una desigualdad horrible<\/strong>. Es hora de un\u00a0<strong>nuevo capitalismo m\u00e1s justo<\/strong>, un capitalismo <strong>equitativo y sostenible que realmente funciona para todos y donde las empresas, incluidas las tecnol\u00f3gicas, no solo toman de la sociedad, sino que realmente devuelven<\/strong> y tienen un impacto positivo\u00bb. Es decir, <strong>una empresa dejar\u00e1 de ser privada<\/strong>,<strong>\u00a0no existir\u00e1 un propietario<\/strong>.<\/p>\n<p style=\"text-align: justify;\"><strong>El Foro de Davos ya lo ven\u00eda anunciando<\/strong> : \u00ab<a title=\"Protegido por Outlook: https:\/\/www.libertaddigital.com\/opinion\/federico-jimenez-losantos\/en-2030-no-tendras-nada-y-seras-feliz-el-proyecto-comunista-mundial-que-aplauden-macron-y-merkel-en-davos-6703990\/. Haga clic o pulse para seguir el v\u00ednculo.\" href=\"https:\/\/emea01.safelinks.protection.outlook.com\/?url=https%3A%2F%2Fwww.libertaddigital.com%2Fopinion%2Ffederico-jimenez-losantos%2Fen-2030-no-tendras-nada-y-seras-feliz-el-proyecto-comunista-mundial-que-aplauden-macron-y-merkel-en-davos-6703990%2F&amp;data=04%7C01%7C%7Cefbec59a0af44da9d19f08d8c9ff13f7%7C84df9e7fe9f640afb435aaaaaaaaaaaa%7C1%7C0%7C637481444670609462%7CUnknown%7CTWFpbGZsb3d8eyJWIjoiMC4wLjAwMDAiLCJQIjoiV2luMzIiLCJBTiI6Ik1haWwiLCJXVCI6Mn0%3D%7C1000&amp;sdata=5ADIt6m9DGv7vmMBOwWpl5zsEynHW1p%2FQ3fFDhvExNY%3D&amp;reserved=0\" target=\"_blank\">En 2030, no tendr\u00e1s nada y ser\u00e1s feliz<\/a>\u00ab, rezaba una de sus predicciones hace tres a\u00f1os. Ahora, sus l\u00edderes adelantan que, en la nueva forma de \u00ab<strong>capitalismo equitativo<\/strong>\u00ab,\u00a0<strong>las empresas no tendr\u00e1n el control de su compa\u00f1\u00eda<\/strong>, <strong>porque tambi\u00e9n formar\u00e1n parte de ella el gobierno de turno y el Estado<\/strong>, entre otros agentes interesados<strong>. Una f\u00f3rmula id\u00e9ntica a la que aplica el Partido Comunista Chino<\/strong> en su r\u00e9gimen. No es de extra\u00f1ar que<a title=\"Protegido por Outlook: https:\/\/www.libremercado.com\/2021-01-28\/xi-jinping-foro-davos-foro-economico-mundial-2021-china-coronavirus-6702971\/. Haga clic o pulse para seguir el v\u00ednculo.\" href=\"https:\/\/emea01.safelinks.protection.outlook.com\/?url=https%3A%2F%2Fwww.libremercado.com%2F2021-01-28%2Fxi-jinping-foro-davos-foro-economico-mundial-2021-china-coronavirus-6702971%2F&amp;data=04%7C01%7C%7Cefbec59a0af44da9d19f08d8c9ff13f7%7C84df9e7fe9f640afb435aaaaaaaaaaaa%7C1%7C0%7C637481444670609462%7CUnknown%7CTWFpbGZsb3d8eyJWIjoiMC4wLjAwMDAiLCJQIjoiV2luMzIiLCJBTiI6Ik1haWwiLCJXVCI6Mn0%3D%7C1000&amp;sdata=ZOQxWMx08V1cJcM58%2F8kWG3GfjMSnEDC9W73Ubk6c1Y%3D&amp;reserved=0\" target=\"_blank\">\u00a0el invitado de honor del Foro Econ\u00f3mico Mundial 2021 fuera Xi Jinping<\/a>, el presidente de la Rep\u00fablica Popular de China.<\/p>\n<h3>Im\u00e1genes Relacionadas:<\/h3>","protected":false},"excerpt":{"rendered":"<p>\u00a0 Colaje Im\u00e1genes Google La primera noticia que os ofrecemos hoy lleva por t\u00edtulo, traducido del ingl\u00e9s:\u201d El crecimiento econ\u00f3mico tiene un costo devastador para la naturaleza\u201d. Aunque tambi\u00e9n debiera a\u00f1adirse sobre las desigualdades sociales y otras muchas. \u00bfYa nadie parece dudarlo?. La segunda noticia que os ofrecemos, y cuyo encabezamiento resulta ser &#8216;El Gran Reseteo&#8217; de Davos concluye con la implantaci\u00f3n de los viajes en trenes-cama y el fin del capitalismo seg\u00fan el rotativo de internet &#8211; Libre Mercado, abunda en el tema desde un perspectiva de la derecha que a\u00fan es negacionista del cambio clim\u00e1tico, siendo muy cr\u00edtica\u2026<\/p>\n","protected":false},"author":26,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0},"categories":[596],"tags":[48425,48424,45288,45285,48422,48423,48421,45286,45287,46689],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":4}},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"El Gran Reseteo: \u00bfHacia una Sociedad Sustentable?: Foro Davos, Foro Econ\u00f3mico Mundial y el Cuento de Caperucita Roja\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Juan Jos\u00e9 Ib\u00e1\u00f1ez\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2021\/03\/08\/151641\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Un Universo invisible bajo nuestros pies - Los suelos y la vida\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"El Gran Reseteo: \u00bfHacia una Sociedad Sustentable?: Foro Davos, Foro Econ\u00f3mico Mundial y el Cuento de Caperucita Roja - Un Universo invisible bajo nuestros pies\" \/>\n\t\t<meta property=\"og:description\" content=\"El Gran Reseteo: \u00bfHacia una Sociedad Sustentable?: Foro Davos, Foro Econ\u00f3mico Mundial y el Cuento de Caperucita Roja\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2021\/03\/08\/151641\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2021-03-08T11:51:03+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2021-03-08T12:14:40+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/juan.j.marti.14\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"El Gran Reseteo: \u00bfHacia una Sociedad Sustentable?: Foro Davos, Foro Econ\u00f3mico Mundial y el Cuento de Caperucita Roja - Un Universo invisible bajo nuestros pies\" \/>\n\t\t<meta name=\"twitter:description\" content=\"El Gran Reseteo: \u00bfHacia una Sociedad Sustentable?: Foro Davos, Foro Econ\u00f3mico Mundial y el Cuento de Caperucita Roja\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2021\\\/03\\\/08\\\/151641#blogposting\",\"name\":\"El Gran Reseteo: \\u00bfHacia una Sociedad Sustentable?: Foro Davos, Foro Econ\\u00f3mico Mundial y el Cuento de Caperucita Roja - Un Universo invisible bajo nuestros pies\",\"headline\":\"El Gran Reseteo: \\u00bfHacia una Sociedad Sustentable?: Foro Davos, Foro Econ\\u00f3mico Mundial y el Cuento de Caperucita Roja\",\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/wp-content\\\/blogs.dir\\\/42\\\/files\\\/405\\\/foro-davos-sustentabilidad.jpg\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2021\\\/03\\\/08\\\/151641\\\/#articleImage\"},\"datePublished\":\"2021-03-08T12:51:03+01:00\",\"dateModified\":\"2021-03-08T13:14:40+01:00\",\"inLanguage\":\"es-ES\",\"commentCount\":3,\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2021\\\/03\\\/08\\\/151641#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2021\\\/03\\\/08\\\/151641#webpage\"},\"articleSection\":\"Biolog\\u00eda y Ecolog\\u00eda del Suelo, \\u00bffraude? \\u00bfmentiras?, cambio de modelo econ\\u00f3mico, conspiraci\\u00f3n, El Gran Reseteo, Foro Davos, Foro econ\\u00f3mico mundial, Gran Reseteo, Hacia una Sociedad Sustentable?: Foro Davos, manipulaci\\u00f3n, sostenibilidad\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2021\\\/03\\\/08\\\/151641#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/biologia-y-ecologia-del-suelo#listItem\",\"name\":\"Biolog\\u00eda y Ecolog\\u00eda del Suelo\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/biologia-y-ecologia-del-suelo#listItem\",\"position\":2,\"name\":\"Biolog\\u00eda y Ecolog\\u00eda del Suelo\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/biologia-y-ecologia-del-suelo\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2021\\\/03\\\/08\\\/151641#listItem\",\"name\":\"El Gran Reseteo: \\u00bfHacia una Sociedad Sustentable?: Foro Davos, Foro Econ\\u00f3mico Mundial y el Cuento de Caperucita Roja\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2021\\\/03\\\/08\\\/151641#listItem\",\"position\":3,\"name\":\"El Gran Reseteo: \\u00bfHacia una Sociedad Sustentable?: Foro Davos, Foro Econ\\u00f3mico Mundial y el Cuento de Caperucita Roja\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/biologia-y-ecologia-del-suelo#listItem\",\"name\":\"Biolog\\u00eda y Ecolog\\u00eda del Suelo\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#organization\",\"name\":\"Un Universo invisible bajo nuestros pies\",\"description\":\"Los suelos y la vida\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/files\\\/2022\\\/02\\\/logo.png\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2021\\\/03\\\/08\\\/151641\\\/#organizationLogo\",\"width\":217,\"height\":72},\"image\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2021\\\/03\\\/08\\\/151641\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/juan.j.marti.14\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo\",\"name\":\"Juan Jos\\u00e9 Ib\\u00e1\\u00f1ez\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2021\\\/03\\\/08\\\/151641#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/387f3a100385573d8f42ce2a3211fd1c?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Juan Jos\\u00e9 Ib\\u00e1\\u00f1ez\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2021\\\/03\\\/08\\\/151641#webpage\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2021\\\/03\\\/08\\\/151641\",\"name\":\"El Gran Reseteo: \\u00bfHacia una Sociedad Sustentable?: Foro Davos, Foro Econ\\u00f3mico Mundial y el Cuento de Caperucita Roja - Un Universo invisible bajo nuestros pies\",\"description\":\"El Gran Reseteo: \\u00bfHacia una Sociedad Sustentable?: Foro Davos, Foro Econ\\u00f3mico Mundial y el Cuento de Caperucita Roja\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2021\\\/03\\\/08\\\/151641#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\"},\"datePublished\":\"2021-03-08T12:51:03+01:00\",\"dateModified\":\"2021-03-08T13:14:40+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#website\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/\",\"name\":\"Un Universo invisible bajo nuestros pies\",\"description\":\"Los suelos y la vida\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"El Gran Reseteo: \u00bfHacia una Sociedad Sustentable?: Foro Davos, Foro Econ\u00f3mico Mundial y el Cuento de Caperucita Roja - Un Universo invisible bajo nuestros pies","description":"El Gran Reseteo: \u00bfHacia una Sociedad Sustentable?: Foro Davos, Foro Econ\u00f3mico Mundial y el Cuento de Caperucita Roja","canonical_url":"https:\/\/www.madrimasd.org\/blogs\/universo\/2021\/03\/08\/151641","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2021\/03\/08\/151641#blogposting","name":"El Gran Reseteo: \u00bfHacia una Sociedad Sustentable?: Foro Davos, Foro Econ\u00f3mico Mundial y el Cuento de Caperucita Roja - Un Universo invisible bajo nuestros pies","headline":"El Gran Reseteo: \u00bfHacia una Sociedad Sustentable?: Foro Davos, Foro Econ\u00f3mico Mundial y el Cuento de Caperucita Roja","author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author"},"publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-content\/blogs.dir\/42\/files\/405\/foro-davos-sustentabilidad.jpg","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2021\/03\/08\/151641\/#articleImage"},"datePublished":"2021-03-08T12:51:03+01:00","dateModified":"2021-03-08T13:14:40+01:00","inLanguage":"es-ES","commentCount":3,"mainEntityOfPage":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2021\/03\/08\/151641#webpage"},"isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2021\/03\/08\/151641#webpage"},"articleSection":"Biolog\u00eda y Ecolog\u00eda del Suelo, \u00bffraude? \u00bfmentiras?, cambio de modelo econ\u00f3mico, conspiraci\u00f3n, El Gran Reseteo, Foro Davos, Foro econ\u00f3mico mundial, Gran Reseteo, Hacia una Sociedad Sustentable?: Foro Davos, manipulaci\u00f3n, sostenibilidad"},{"@type":"BreadcrumbList","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2021\/03\/08\/151641#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo#listItem","position":1,"name":"Home","item":"https:\/\/www.madrimasd.org\/blogs\/universo","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/biologia-y-ecologia-del-suelo#listItem","name":"Biolog\u00eda y Ecolog\u00eda del Suelo"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/biologia-y-ecologia-del-suelo#listItem","position":2,"name":"Biolog\u00eda y Ecolog\u00eda del Suelo","item":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/biologia-y-ecologia-del-suelo","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2021\/03\/08\/151641#listItem","name":"El Gran Reseteo: \u00bfHacia una Sociedad Sustentable?: Foro Davos, Foro Econ\u00f3mico Mundial y el Cuento de Caperucita Roja"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2021\/03\/08\/151641#listItem","position":3,"name":"El Gran Reseteo: \u00bfHacia una Sociedad Sustentable?: Foro Davos, Foro Econ\u00f3mico Mundial y el Cuento de Caperucita Roja","previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/biologia-y-ecologia-del-suelo#listItem","name":"Biolog\u00eda y Ecolog\u00eda del Suelo"}}]},{"@type":"Organization","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#organization","name":"Un Universo invisible bajo nuestros pies","description":"Los suelos y la vida","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/","logo":{"@type":"ImageObject","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2021\/03\/08\/151641\/#organizationLogo","width":217,"height":72},"image":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2021\/03\/08\/151641\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/juan.j.marti.14"]},{"@type":"Person","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo","name":"Juan Jos\u00e9 Ib\u00e1\u00f1ez","image":{"@type":"ImageObject","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2021\/03\/08\/151641#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/387f3a100385573d8f42ce2a3211fd1c?s=96&d=mm&r=g","width":96,"height":96,"caption":"Juan Jos\u00e9 Ib\u00e1\u00f1ez"}},{"@type":"WebPage","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2021\/03\/08\/151641#webpage","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/2021\/03\/08\/151641","name":"El Gran Reseteo: \u00bfHacia una Sociedad Sustentable?: Foro Davos, Foro Econ\u00f3mico Mundial y el Cuento de Caperucita Roja - Un Universo invisible bajo nuestros pies","description":"El Gran Reseteo: \u00bfHacia una Sociedad Sustentable?: Foro Davos, Foro Econ\u00f3mico Mundial y el Cuento de Caperucita Roja","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#website"},"breadcrumb":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2021\/03\/08\/151641#breadcrumblist"},"author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author"},"creator":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author"},"datePublished":"2021-03-08T12:51:03+01:00","dateModified":"2021-03-08T13:14:40+01:00"},{"@type":"WebSite","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#website","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/","name":"Un Universo invisible bajo nuestros pies","description":"Los suelos y la vida","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Un Universo invisible bajo nuestros pies - Los suelos y la vida","og:type":"article","og:title":"El Gran Reseteo: \u00bfHacia una Sociedad Sustentable?: Foro Davos, Foro Econ\u00f3mico Mundial y el Cuento de Caperucita Roja - Un Universo invisible bajo nuestros pies","og:description":"El Gran Reseteo: \u00bfHacia una Sociedad Sustentable?: Foro Davos, Foro Econ\u00f3mico Mundial y el Cuento de Caperucita Roja","og:url":"https:\/\/www.madrimasd.org\/blogs\/universo\/2021\/03\/08\/151641","og:image":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png","og:image:secure_url":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png","article:published_time":"2021-03-08T11:51:03+00:00","article:modified_time":"2021-03-08T12:14:40+00:00","article:publisher":"https:\/\/www.facebook.com\/juan.j.marti.14","twitter:card":"summary","twitter:title":"El Gran Reseteo: \u00bfHacia una Sociedad Sustentable?: Foro Davos, Foro Econ\u00f3mico Mundial y el Cuento de Caperucita Roja - Un Universo invisible bajo nuestros pies","twitter:description":"El Gran Reseteo: \u00bfHacia una Sociedad Sustentable?: Foro Davos, Foro Econ\u00f3mico Mundial y el Cuento de Caperucita Roja","twitter:image":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png"},"aioseo_meta_data":{"post_id":"151641","title":"","description":"El Gran Reseteo: \u00bfHacia una Sociedad Sustentable?: Foro Davos, Foro Econ\u00f3mico Mundial y el Cuento de Caperucita Roja","keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":null,"isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","tabs":null,"priority":null,"frequency":null,"local_seo":null,"created":"2022-06-03 14:06:50","updated":"2026-05-26 19:26:50","limit_modified_date":false,"ai":null,"breadcrumb_settings":null,"seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/biologia-y-ecologia-del-suelo\" title=\"Biolog\u00eda y Ecolog\u00eda del Suelo\">Biolog\u00eda y Ecolog\u00eda del Suelo<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tEl Gran Reseteo: \u00bfHacia una Sociedad Sustentable?: Foro Davos, Foro Econ\u00f3mico Mundial y el Cuento de Caperucita Roja\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.madrimasd.org\/blogs\/universo"},{"label":"Biolog\u00eda y Ecolog\u00eda del Suelo","link":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/biologia-y-ecologia-del-suelo"},{"label":"El Gran Reseteo: \u00bfHacia una Sociedad Sustentable?: Foro Davos, Foro Econ\u00f3mico Mundial y el Cuento de Caperucita Roja","link":"https:\/\/www.madrimasd.org\/blogs\/universo\/2021\/03\/08\/151641"}],"_links":{"self":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts\/151641"}],"collection":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/comments?post=151641"}],"version-history":[{"count":16,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts\/151641\/revisions"}],"predecessor-version":[{"id":151744,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts\/151641\/revisions\/151744"}],"wp:attachment":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/media?parent=151641"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/categories?post=151641"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/tags?post=151641"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}