{"id":152032,"date":"2023-01-31T17:58:07","date_gmt":"2023-01-31T16:58:07","guid":{"rendered":"http:\/\/www.madrimasd.org\/blogs\/universo\/?p=152032"},"modified":"2023-01-31T17:58:07","modified_gmt":"2023-01-31T16:58:07","slug":"la-insustentabilidad-de-la-agricultura-industrial-las-dust-bowl-que-se-avecinan","status":"publish","type":"post","link":"https:\/\/www.madrimasd.org\/blogs\/universo\/2023\/01\/31\/152032","title":{"rendered":"La insustentabilidad de la agricultura industrial: Las Dust Bowl que se avecinan"},"content":{"rendered":"<p align=\"center\">&nbsp;<img decoding=\"async\" class=\"ngg-singlepic ngg-center\" src=\"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-content\/blogs.dir\/42\/files\/147\/agicultura-industrial-dust-bowl.jpg\" alt=\"agicultura-industrial-dust-bowl\" width=\"726\" height=\"479\"><\/p>\n<p align=\"center\"><span style=\"color: #0000ff\">Fuente: Colaje Im\u00e1genes Google<\/span><\/p>\n<p style=\"text-align: justify\">Hablamos incesantemente de los retos de la agricultura industrial con vistas a alcanzar un futuro sustentable bajo escenarios de <strong><span style=\"color: #3366ff\">un clima en constante calentamiento, en el que habr\u00e1 m\u00e1s eventos catastr\u00f3ficos, como sequ\u00edas, inundaciones, huracanes, tornados etc., por no hablar de la enorme contaminaci\u00f3n de suelos, aguas y aire que ya han provocado estragos en el Planeta, afectando a la biosfera y la salud humana<\/span><\/strong>. Esta \u00faltima, de por s\u00ed, ya exige <a href=\"https:\/\/www.researchgate.net\/publication\/256525946_Blogs_Cientificos\">un cambio de paradigma en nuestras pr\u00e1cticas agron\u00f3micas<\/a>. &nbsp;Sin embargo, la noticia que os ofrecemos hoy se me antoja excelente como un ejemplo m\u00e1s que ilustrativo. \u00bfNo record\u00e1is la cat\u00e1strofe denominada <a href=\"https:\/\/es.wikipedia.org\/wiki\/Dust_Bowl\">Dust bowl<\/a>, que afect\u00f3 a EE.UU casi simult\u00e1neamente que la gran <a href=\"https:\/\/es.wikipedia.org\/wiki\/Gran_Depresi%C3%B3n\">depresi\u00f3n econ\u00f3mica &nbsp;de 1929<\/a>?. La <span style=\"color: #3366ff\"><strong>tragedia fue descomunal<\/strong><\/span>. El presidente aqu\u00e9l pa\u00eds&nbsp; Franklin D. Roosevelt (1882-1945): reconoci\u00f3 poco despues que: \u201c<a href=\"%20%E2%80%9CLa%20naci%C3%B3n%20que%20destruye%20su%20suelo%20se%20destruye%20a%20si%20misma\">La naci\u00f3n que destruye su suelo se destruye a si misma<\/a>\u201d. Seguidamente se cre\u00f3 el <span style=\"color: #3366ff\"><strong>Servicio de Conservaci\u00f3n de Suelos de EE.UU<\/strong><\/span>. (actualmente &nbsp;NRCS). Empero, como m\u00e1ximo, tras tres d\u00e9cadas se inici\u00f3 la denominada <a href=\"http:\/\/www.ub.edu\/geocrit\/sn-92.htm\">revoluci\u00f3n verde cuya consecuencias fueron<\/a> \u201cpan para hoy y el hambre y tragedias, dej\u00e9mosla para ma\u00f1ana\u201d. &nbsp;<span style=\"color: #3366ff\">\u00a1<strong>Tan solo tres d\u00e9cadas despu\u00e9s! se ciment\u00f3 la agricultura industrial actual, es decir, la que nos ha llevado inevitablemente a la lamentable situaci\u00f3n actual<\/strong><\/span>. \u00a1No aprendemos nada!. Hemos hablado en diversos post sobre estos asuntos y no volveremos a repetirnos.<\/p>\n<p style=\"text-align: justify\">El estudio que os os exponemostramos hoy, muestra que la frase y buenas intenciones del Presidente Roosevelt, quedaron r\u00e1pidamente escondidas en el ba\u00fal de los recuerdos, encontr\u00e1ndonos ante <span style=\"color: #3366ff\"><strong>un futuro mucho m\u00e1s sombr\u00edo que el de por aquel entonces. \u00a1Es cuesti\u00f3n de tiempo!<\/strong><\/span>. Si la cat\u00e1strofe de la denominada <a href=\"https:\/\/es.wikipedia.org\/wiki\/Dust_Bowl\">Dust bowl<\/a> se produjo en condiciones de <span style=\"color: #3366ff\"><strong>extrema aridez y huracanes<\/strong><\/span>, aunque bajo un clima sin las amenazas que ya son palpables, como el actual, \u00bfque ocurrir\u00eda hoy con toda nuestra portentosa tecnolog\u00eda?. &nbsp;&nbsp;La conclusi\u00f3n es demoledora, como podr\u00e9is leer a continuaci\u00f3n. <span style=\"color: #3366ff\"><strong>La agricultura industrial ha soslayado todas esas amenazas &nbsp;que se ciernen sobre ella, muy bien documentadas, y nos dirige hacia la cat\u00e1st<\/strong>r<strong>ofe<\/strong><\/span>.<\/p>\n<p style=\"text-align: justify\">Resulta incomprensible que, con todo lo acaecido (l\u00e9ase historia), las evidencias palpables de que disponemos actualmente, bien sustentadas por los conocimientos cient\u00edficos, y esos eventos catastr\u00f3ficos, que no son ya predicciones, sino hechos reales (lean lo que sucede en el sur y este de EE.UU., por ejemplo), &nbsp;sigamos siendo ciegos, necios y suicidas.<\/p>\n<p style=\"text-align: justify\">Ruego que os deteng\u00e1is a reflexionar acerca de las conclusiones del estudio que os muestro abajo. Al margen de predicciones, la l\u00f3gica se impone, Repito, \u00a1es cuesti\u00f3n de tiempo!, ya sea hoy, ma\u00f1ana o dentro de unos meses, o pocos a\u00f1os. <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2020\/07\/13\/151223\">La bobalizaci\u00f3n reina entre nosotros<\/a>.<\/p>\n<p>&nbsp;<strong style=\"font-size: 1.5em;text-align: justify\"><a href=\"http:\/\/www.seeddaily.com\/reports\/Dust_Bowl_would_obliterate_modern_crops_999.html\">Dust Bowl would obliterate modern crops<\/a><\/strong><\/p>\n<h2 style=\"text-align: justify\">by Brooks Hays; Chicago (UPI) Dec 20, 2016<\/h2>\n<p style=\"text-align: justify\">If <strong>the conditions of the Dust Bowl were replicated today, modern agriculture would be devastated<\/strong>, according to scientists at the University of Chicago.<\/p>\n<p style=\"text-align: justify\">Researchers analyzed how extreme drought and heat would affect maize, soy and wheat crops in the United States. <strong>The results show conditions similar to the 1930s would drastically reduce modern crop yields<\/strong>.<\/p>\n<p style=\"text-align: justify\">\u00ab<strong>We expected to find the system much more resilient because 30 percent of production is now irrigated in the United States, and because we&#8217;ve abandoned corn production in more severely drought-stricken<\/strong> <strong>places such as Oklahoma and west Texas<\/strong>,\u00bb Joshua Elliott, a research scientists at the Center for Robust Decision Making on Climate and Energy Policy, said in a news release. \u00ab<strong>But we found the opposite: The system was just as sensitive to drought and heat as it was in the 1930s<\/strong>.\u00bb<\/p>\n<p style=\"text-align: justify\">Though agricultural practices have evolved since the 1930s, most changes have privileged yield over resilience and sustainability. As a result, scientists suggest many staple crops remain vulnerable to extreme weather.<\/p>\n<p style=\"text-align: justify\">\u00abWe knew a Dust Bowl-type drought would be devastating even for modern agriculture, but we expected technological advancements to mitigate those damages much more than our results suggested,\u00bb said Michael Glotter, a graduate student in geophysical sciences at Chicago. \u00abTechnology has evolved to make yields as high as possible in normal years. But as extreme events become more frequent and severe, we may have to reframe how we breed crops and select for variance and resilience, not just for average yield.\u00bb<\/p>\n<p style=\"text-align: justify\">It&#8217;s likely a future Dust Bowl-like decade would be more catastrophic than the drought that devastated the 1930s. Today&#8217;s severe drought conditions are accompanied by ever-rising temperatures.<\/p>\n<p style=\"text-align: justify\">\u00abBy mid-century even a normal year in precipitation could be as bad as what we saw in 1936,\u00bb Elliott said. \u00abAnd a year with even a 10 to 20 percent loss of precipitation becomes extraordinarily damaging.\u00bb<\/p>\n<p style=\"text-align: justify\">The new research was published in the journal Nature Plants.<\/p>\n<h2><a href=\"https:\/\/www.upi.com\/Science_News\/2016\/12\/20\/Dust-Bowl-would-obliterate-modern-crops\/9371482244940\/\"><strong>Dust Bowl destruir\u00eda los cultivos modernos<\/strong><\/a><\/h2>\n<p style=\"text-align: justify\">\u00ab<strong>El sistema era tan sensible a la sequ\u00eda y al calor como lo era en la d\u00e9cada de 1930<\/strong>\u00ab, dijo el cient\u00edfico investigador Joshua Elliott.<\/p>\n<p style=\"text-align: justify\">Por Brooks Hays<\/p>\n<p style=\"text-align: justify\">&nbsp;<strong>Una nueva investigaci\u00f3n sugiere que los cultivos modernos son tan vulnerables a la sequ\u00eda y el calor como lo fueron durante el Dust Bowl de la d\u00e9cada de 1930<\/strong>. Foto por UPI\/Kevin Dietsch |&nbsp;<a href=\"https:\/\/www.upi.com\/News_Photos\/lp\/8e5408fadc727e8889966b1cf594411f\/\" target=\"_blank\" rel=\"noopener\">Foto de la licencia<\/a><\/p>\n<p style=\"text-align: justify\">CHICAGO, 20 de diciembre (UPI) &#8212;&nbsp;<strong>Si las condiciones del Dust Bowl se replicaran hoy, la agricultura moderna ser\u00eda devastada<\/strong>, seg\u00fan cient\u00edficos de la Universidad de Chicago.<\/p>\n<p style=\"text-align: justify\">Los investigadores analizaron c\u00f3mo la sequ\u00eda extrema y el calor afectar\u00edan los cultivos de ma\u00edz, soja y trigo en los Estados Unidos. Los resultados muestran que <strong>condiciones similares a la d\u00e9cada de 1930 reducir\u00edan dr\u00e1sticamente los rendimientos de los cultivos modernos<\/strong>.<\/p>\n<p style=\"text-align: justify\">\u00ab<strong>Esper\u00e1bamos encontrar el sistema mucho m\u00e1s resistente porque<\/strong> el 30 por ciento de la producci\u00f3n ahora se riega en estados Unidos, y porque hemos abandonado la producci\u00f3n de ma\u00edz en lugares m\u00e1s severamente afectados por la sequ\u00eda, como Oklahoma y el oeste de Texas\u00bb, dijo en un&nbsp;<a href=\"https:\/\/news.uchicago.edu\/article\/2016\/12\/19\/dust-bowl-would-devastate-todays-crops-study-finds\" target=\"_blank\" rel=\"noopener\">comunicado de prensa<\/a>Joshua Elliott, cient\u00edfico investigador del Centro para la Toma de Decisiones Robustas sobre Pol\u00edtica Clim\u00e1tica y Energ\u00e9tica. \u00ab<strong>Pero encontramos lo contrario: el sistema era tan sensible a la sequ\u00eda y el calor como lo era en la d\u00e9cada de 1930<\/strong>\u00ab.<\/p>\n<p style=\"text-align: justify\"><strong>Aunque las pr\u00e1cticas agr\u00edcolas han evolucionado desde la d\u00e9cada de 1930, la mayor\u00eda de los cambios han privilegiado el rendimiento sobre la resiliencia y la sostenibilidad. Como resultado, los cient\u00edficos sugieren que muchos cultivos b\u00e1sicos siguen siendo vulnerables al clima extremo<\/strong>.<\/p>\n<p style=\"text-align: justify\"><strong>RELACIONADO <\/strong><a title=\"November was second warmest on record in U.S.\" href=\"https:\/\/www.upi.com\/Science_News\/2016\/12\/08\/November-was-second-warmest-on-record-in-US\/5711481207674\/\">Noviembre fue el segundo m\u00e1s c\u00e1lido registrado en Estados Unidos.<\/a><\/p>\n<p style=\"text-align: justify\">\u00ab<strong>Sab\u00edamos que una sequ\u00eda tipo Dust Bowl ser\u00eda devastadora incluso para la agricultura moderna, pero esper\u00e1bamos que los avances tecnol\u00f3gicos mitigaran esos da\u00f1os mucho m\u00e1s<\/strong> de lo que suger\u00edan nuestros resultados\u00bb, dijo Michael Glotter, un estudiante graduado en ciencias geof\u00edsicas en Chicago. \u00ab<strong>La tecnolog\u00eda ha evolucionado para hacer que los rendimientos sean lo m\u00e1s altos posible en a\u00f1os normales<\/strong>. Pero a medida que <strong>los eventos extremos se vuelven m\u00e1s frecuentes y severos, es posible que tengamos que replantear la forma en que criamos los cultivos y seleccionar la varianza y la resiliencia, no solo el rendimiento promedio<\/strong>\u00ab.<\/p>\n<p style=\"text-align: justify\">Es probable que una futura d\u00e9cada similar al Dust Bowl sea m\u00e1s catastr\u00f3fica que la sequ\u00eda que devast\u00f3 la d\u00e9cada de 1930. Las severas condiciones de sequ\u00eda de hoy en d\u00eda est\u00e1n acompa\u00f1adas por temperaturas en constante aumento.<\/p>\n<p style=\"text-align: justify\">\u00ab<strong>A mediados de siglo, incluso un a\u00f1o normal en precipitaciones podr\u00eda ser tan malo como lo que vimos en 1936<\/strong>\u00ab, dijo Elliott. \u00abY un a\u00f1o con incluso una p\u00e9rdida de precipitaciones del 10 al 20 por ciento se vuelve extraordinariamente da\u00f1ino\u00bb.<\/p>\n<p><span style=\"color: #800000\"><strong>Material Adicional<\/strong><\/span><\/p>\n<p><a title=\"Enlace permanente a Conservaci\u00f3n de Suelos: Fundaci\u00f3n de una Ciencia y su Reliquia Bibliogr\u00e1fica\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/05\/17\/137981\">Conservaci\u00f3n de Suelos: Fundaci\u00f3n de una Ciencia y su Reliquia Bibliogr\u00e1fica<\/a><\/p>\n<p><a title=\"Enlace permanente a Cat\u00e1strofes Naturales: Degradaci\u00f3n de Suelos, Erosi\u00f3n, Fertilizaci\u00f3n, Contaminaci\u00f3n y la Degradaci\u00f3n de la Gran Barrera de Coral\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/05\/03\/138098\">Cat\u00e1strofes Naturales: Degradaci\u00f3n de Suelos, Erosi\u00f3n, Fertilizaci\u00f3n, Contaminaci\u00f3n y la Degradaci\u00f3n de la Gran Barrera de Coral<\/a><\/p>\n<p><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2008\/03\/03\/85811\">La Erosi\u00f3n E\u00f3lica y Sus efectos sobre el Clima y Los Ecosistemas<\/a><\/p>\n<p><a href=\"https:\/\/es.wikipedia.org\/wiki\/Dust_Bowl\">Dust bowl<\/a><\/p>\n<p><a href=\"https:\/\/historiageneral.com\/2013\/02\/14\/the-dust-bowl-gran-desastre-ecologico-del-siglo-xx\/\">The Dust Bowl, gran desastre ecol\u00f3gico del siglo XX<\/a><\/p>\n<p><a href=\"https:\/\/www.google.com\/url?sa=t&amp;rct=j&amp;q=&amp;esrc=s&amp;source=web&amp;cd=&amp;cad=rja&amp;uact=8&amp;ved=2ahUKEwim1deyy7b1AhUPoRQKHT5_ASYQFnoECCIQAQ&amp;url=https%3A%2F%2Fwww.greelane.com%2Fes%2Fhumanidades%2Fhistoria-y-cultura%2Fdust-bowl-ecological-disaster-1779273&amp;usg=AOvVaw3qDyi7_HLXxZ6kqTw1jL9X\">\u00bfC\u00f3mo exacerb\u00f3 el Dust Bowl la Gran Depresi\u00f3n? &#8211;<\/a><\/p>\n<p><a href=\"https:\/\/planetainteligente.elmundo.es\/2019\/eco\/quien-no-quiera-polvo-que-aprenda-del-pasado.html\">El Dust Bowl es hasta la fecha el desastre ecol\u00f3gico m\u00e1s devastador de la Historia de Estados Unidos, y se debi\u00f3 en gran parte, a la acci\u00f3n del hombre.<\/a><\/p>\n<h3>Im\u00e1genes Relacionadas:<\/h3>","protected":false},"excerpt":{"rendered":"<p>&nbsp; Fuente: Colaje Im\u00e1genes Google Hablamos incesantemente de los retos de la agricultura industrial con vistas a alcanzar un futuro sustentable bajo escenarios de un clima en constante calentamiento, en el que habr\u00e1 m\u00e1s eventos catastr\u00f3ficos, como sequ\u00edas, inundaciones, huracanes, tornados etc., por no hablar de la enorme contaminaci\u00f3n de suelos, aguas y aire que ya han provocado estragos en el Planeta, afectando a la biosfera y la salud humana. Esta \u00faltima, de por s\u00ed, ya exige un cambio de paradigma en nuestras pr\u00e1cticas agron\u00f3micas. &nbsp;Sin embargo, la noticia que os ofrecemos hoy se me antoja excelente como un ejemplo\u2026<\/p>\n","protected":false},"author":26,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0},"categories":[591,613,597,587,585,598,595],"tags":[46691,48508,48506,46975,48507,46689],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":4}},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Fuente: Colaje Im\u00e1genes Google Hablamos incesantemente de los retos de la agricultura industrial con vistas a alcanzar un futuro sustentable bajo escenarios de un clima en constante calentamiento, en el que habr\u00e1 m\u00e1s eventos catastr\u00f3ficos, como sequ\u00edas, inundaciones, huracanes, tornados etc., por no hablar de la enorme contaminaci\u00f3n de suelos, aguas y aire que\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Juan Jos\u00e9 Ib\u00e1\u00f1ez\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2023\/01\/31\/152032\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Un Universo invisible bajo nuestros pies - Los suelos y la vida\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"La insustentabilidad de la agricultura industrial: Las Dust Bowl que se avecinan - Un Universo invisible bajo nuestros pies\" \/>\n\t\t<meta property=\"og:description\" content=\"Fuente: Colaje Im\u00e1genes Google Hablamos incesantemente de los retos de la agricultura industrial con vistas a alcanzar un futuro sustentable bajo escenarios de un clima en constante calentamiento, en el que habr\u00e1 m\u00e1s eventos catastr\u00f3ficos, como sequ\u00edas, inundaciones, huracanes, tornados etc., por no hablar de la enorme contaminaci\u00f3n de suelos, aguas y aire que\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2023\/01\/31\/152032\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2023-01-31T16:58:07+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2023-01-31T16:58:07+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/juan.j.marti.14\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"La insustentabilidad de la agricultura industrial: Las Dust Bowl que se avecinan - Un Universo invisible bajo nuestros pies\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Fuente: Colaje Im\u00e1genes Google Hablamos incesantemente de los retos de la agricultura industrial con vistas a alcanzar un futuro sustentable bajo escenarios de un clima en constante calentamiento, en el que habr\u00e1 m\u00e1s eventos catastr\u00f3ficos, como sequ\u00edas, inundaciones, huracanes, tornados etc., por no hablar de la enorme contaminaci\u00f3n de suelos, aguas y aire que\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2023\\\/01\\\/31\\\/152032#blogposting\",\"name\":\"La insustentabilidad de la agricultura industrial: Las Dust Bowl que se avecinan - Un Universo invisible bajo nuestros pies\",\"headline\":\"La insustentabilidad de la agricultura industrial: Las Dust Bowl que se avecinan\",\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/wp-content\\\/blogs.dir\\\/42\\\/files\\\/147\\\/agicultura-industrial-dust-bowl.jpg\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2023\\\/01\\\/31\\\/152032\\\/#articleImage\"},\"datePublished\":\"2023-01-31T17:58:07+01:00\",\"dateModified\":\"2023-01-31T17:58:07+01:00\",\"inLanguage\":\"es-ES\",\"commentCount\":1,\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2023\\\/01\\\/31\\\/152032#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2023\\\/01\\\/31\\\/152032#webpage\"},\"articleSection\":\"Edafolog\\u00eda y Pol\\u00edtica, Fertilidad de Suelos y Nutrici\\u00f3n Vegetal, Filosof\\u00eda, Historia y Sociolog\\u00eda de la Edafolog\\u00eda, La Crisis de la Edafolog\\u00eda, P\\u00e9rdida de los Recursos Ed\\u00e1ficos: La Erosi\\u00f3n, Suelos de Zonas \\u00c1ridas, Semi\\u00e1ridas y desertificaci\\u00f3n, Suelos y Cambio Clim\\u00e1tico, agricultura industrial, bobalizaci\\u00f3n, Dust bowl, erosi\\u00f3n del suelo, eventos extremos, sostenibilidad\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2023\\\/01\\\/31\\\/152032#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/perdida-de-los-recursos-edaficos-la-erosion#listItem\",\"name\":\"P\\u00e9rdida de los Recursos Ed\\u00e1ficos: La Erosi\\u00f3n\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/perdida-de-los-recursos-edaficos-la-erosion#listItem\",\"position\":2,\"name\":\"P\\u00e9rdida de los Recursos Ed\\u00e1ficos: La Erosi\\u00f3n\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/perdida-de-los-recursos-edaficos-la-erosion\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2023\\\/01\\\/31\\\/152032#listItem\",\"name\":\"La insustentabilidad de la agricultura industrial: Las Dust Bowl que se avecinan\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2023\\\/01\\\/31\\\/152032#listItem\",\"position\":3,\"name\":\"La insustentabilidad de la agricultura industrial: Las Dust Bowl que se avecinan\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/perdida-de-los-recursos-edaficos-la-erosion#listItem\",\"name\":\"P\\u00e9rdida de los Recursos Ed\\u00e1ficos: La Erosi\\u00f3n\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#organization\",\"name\":\"Un Universo invisible bajo nuestros pies\",\"description\":\"Los suelos y la vida\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/files\\\/2022\\\/02\\\/logo.png\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2023\\\/01\\\/31\\\/152032\\\/#organizationLogo\",\"width\":217,\"height\":72},\"image\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2023\\\/01\\\/31\\\/152032\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/juan.j.marti.14\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo\",\"name\":\"Juan Jos\\u00e9 Ib\\u00e1\\u00f1ez\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2023\\\/01\\\/31\\\/152032#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/387f3a100385573d8f42ce2a3211fd1c?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Juan Jos\\u00e9 Ib\\u00e1\\u00f1ez\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2023\\\/01\\\/31\\\/152032#webpage\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2023\\\/01\\\/31\\\/152032\",\"name\":\"La insustentabilidad de la agricultura industrial: Las Dust Bowl que se avecinan - Un Universo invisible bajo nuestros pies\",\"description\":\"Fuente: Colaje Im\\u00e1genes Google Hablamos incesantemente de los retos de la agricultura industrial con vistas a alcanzar un futuro sustentable bajo escenarios de un clima en constante calentamiento, en el que habr\\u00e1 m\\u00e1s eventos catastr\\u00f3ficos, como sequ\\u00edas, inundaciones, huracanes, tornados etc., por no hablar de la enorme contaminaci\\u00f3n de suelos, aguas y aire que\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2023\\\/01\\\/31\\\/152032#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\"},\"datePublished\":\"2023-01-31T17:58:07+01:00\",\"dateModified\":\"2023-01-31T17:58:07+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#website\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/\",\"name\":\"Un Universo invisible bajo nuestros pies\",\"description\":\"Los suelos y la vida\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"La insustentabilidad de la agricultura industrial: Las Dust Bowl que se avecinan - Un Universo invisible bajo nuestros pies","description":"Fuente: Colaje Im\u00e1genes Google Hablamos incesantemente de los retos de la agricultura industrial con vistas a alcanzar un futuro sustentable bajo escenarios de un clima en constante calentamiento, en el que habr\u00e1 m\u00e1s eventos catastr\u00f3ficos, como sequ\u00edas, inundaciones, huracanes, tornados etc., por no hablar de la enorme contaminaci\u00f3n de suelos, aguas y aire que","canonical_url":"https:\/\/www.madrimasd.org\/blogs\/universo\/2023\/01\/31\/152032","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2023\/01\/31\/152032#blogposting","name":"La insustentabilidad de la agricultura industrial: Las Dust Bowl que se avecinan - Un Universo invisible bajo nuestros pies","headline":"La insustentabilidad de la agricultura industrial: Las Dust Bowl que se avecinan","author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author"},"publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-content\/blogs.dir\/42\/files\/147\/agicultura-industrial-dust-bowl.jpg","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2023\/01\/31\/152032\/#articleImage"},"datePublished":"2023-01-31T17:58:07+01:00","dateModified":"2023-01-31T17:58:07+01:00","inLanguage":"es-ES","commentCount":1,"mainEntityOfPage":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2023\/01\/31\/152032#webpage"},"isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2023\/01\/31\/152032#webpage"},"articleSection":"Edafolog\u00eda y Pol\u00edtica, Fertilidad de Suelos y Nutrici\u00f3n Vegetal, Filosof\u00eda, Historia y Sociolog\u00eda de la Edafolog\u00eda, La Crisis de la Edafolog\u00eda, P\u00e9rdida de los Recursos Ed\u00e1ficos: La Erosi\u00f3n, Suelos de Zonas \u00c1ridas, Semi\u00e1ridas y desertificaci\u00f3n, Suelos y Cambio Clim\u00e1tico, agricultura industrial, bobalizaci\u00f3n, Dust bowl, erosi\u00f3n del suelo, eventos extremos, sostenibilidad"},{"@type":"BreadcrumbList","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2023\/01\/31\/152032#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo#listItem","position":1,"name":"Home","item":"https:\/\/www.madrimasd.org\/blogs\/universo","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/perdida-de-los-recursos-edaficos-la-erosion#listItem","name":"P\u00e9rdida de los Recursos Ed\u00e1ficos: La Erosi\u00f3n"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/perdida-de-los-recursos-edaficos-la-erosion#listItem","position":2,"name":"P\u00e9rdida de los Recursos Ed\u00e1ficos: La Erosi\u00f3n","item":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/perdida-de-los-recursos-edaficos-la-erosion","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2023\/01\/31\/152032#listItem","name":"La insustentabilidad de la agricultura industrial: Las Dust Bowl que se avecinan"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2023\/01\/31\/152032#listItem","position":3,"name":"La insustentabilidad de la agricultura industrial: Las Dust Bowl que se avecinan","previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/perdida-de-los-recursos-edaficos-la-erosion#listItem","name":"P\u00e9rdida de los Recursos Ed\u00e1ficos: La Erosi\u00f3n"}}]},{"@type":"Organization","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#organization","name":"Un Universo invisible bajo nuestros pies","description":"Los suelos y la vida","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/","logo":{"@type":"ImageObject","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2023\/01\/31\/152032\/#organizationLogo","width":217,"height":72},"image":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2023\/01\/31\/152032\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/juan.j.marti.14"]},{"@type":"Person","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo","name":"Juan Jos\u00e9 Ib\u00e1\u00f1ez","image":{"@type":"ImageObject","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2023\/01\/31\/152032#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/387f3a100385573d8f42ce2a3211fd1c?s=96&d=mm&r=g","width":96,"height":96,"caption":"Juan Jos\u00e9 Ib\u00e1\u00f1ez"}},{"@type":"WebPage","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2023\/01\/31\/152032#webpage","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/2023\/01\/31\/152032","name":"La insustentabilidad de la agricultura industrial: Las Dust Bowl que se avecinan - Un Universo invisible bajo nuestros pies","description":"Fuente: Colaje Im\u00e1genes Google Hablamos incesantemente de los retos de la agricultura industrial con vistas a alcanzar un futuro sustentable bajo escenarios de un clima en constante calentamiento, en el que habr\u00e1 m\u00e1s eventos catastr\u00f3ficos, como sequ\u00edas, inundaciones, huracanes, tornados etc., por no hablar de la enorme contaminaci\u00f3n de suelos, aguas y aire que","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#website"},"breadcrumb":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2023\/01\/31\/152032#breadcrumblist"},"author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author"},"creator":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author"},"datePublished":"2023-01-31T17:58:07+01:00","dateModified":"2023-01-31T17:58:07+01:00"},{"@type":"WebSite","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#website","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/","name":"Un Universo invisible bajo nuestros pies","description":"Los suelos y la vida","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Un Universo invisible bajo nuestros pies - Los suelos y la vida","og:type":"article","og:title":"La insustentabilidad de la agricultura industrial: Las Dust Bowl que se avecinan - Un Universo invisible bajo nuestros pies","og:description":"Fuente: Colaje Im\u00e1genes Google Hablamos incesantemente de los retos de la agricultura industrial con vistas a alcanzar un futuro sustentable bajo escenarios de un clima en constante calentamiento, en el que habr\u00e1 m\u00e1s eventos catastr\u00f3ficos, como sequ\u00edas, inundaciones, huracanes, tornados etc., por no hablar de la enorme contaminaci\u00f3n de suelos, aguas y aire que","og:url":"https:\/\/www.madrimasd.org\/blogs\/universo\/2023\/01\/31\/152032","og:image":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png","og:image:secure_url":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png","article:published_time":"2023-01-31T16:58:07+00:00","article:modified_time":"2023-01-31T16:58:07+00:00","article:publisher":"https:\/\/www.facebook.com\/juan.j.marti.14","twitter:card":"summary","twitter:title":"La insustentabilidad de la agricultura industrial: Las Dust Bowl que se avecinan - Un Universo invisible bajo nuestros pies","twitter:description":"Fuente: Colaje Im\u00e1genes Google Hablamos incesantemente de los retos de la agricultura industrial con vistas a alcanzar un futuro sustentable bajo escenarios de un clima en constante calentamiento, en el que habr\u00e1 m\u00e1s eventos catastr\u00f3ficos, como sequ\u00edas, inundaciones, huracanes, tornados etc., por no hablar de la enorme contaminaci\u00f3n de suelos, aguas y aire que","twitter:image":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png"},"aioseo_meta_data":{"post_id":"152032","title":null,"description":null,"keywords":[],"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":null,"isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":"{\"article\":{\"articleType\":\"BlogPosting\"},\"course\":{\"name\":\"\",\"description\":\"\",\"provider\":\"\"},\"faq\":{\"pages\":[]},\"product\":{\"reviews\":[]},\"recipe\":{\"ingredients\":[],\"instructions\":[],\"keywords\":[]},\"software\":{\"reviews\":[],\"operatingSystems\":[]},\"webPage\":{\"webPageType\":\"WebPage\"}}","pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","tabs":null,"priority":null,"frequency":"default","local_seo":null,"created":"2022-08-10 15:24:24","updated":"2026-05-26 19:49:49","limit_modified_date":false,"ai":null,"breadcrumb_settings":null,"seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/perdida-de-los-recursos-edaficos-la-erosion\" title=\"P\u00e9rdida de los Recursos Ed\u00e1ficos: La Erosi\u00f3n\">P\u00e9rdida de los Recursos Ed\u00e1ficos: La Erosi\u00f3n<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tLa insustentabilidad de la agricultura industrial: Las Dust Bowl que se avecinan\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.madrimasd.org\/blogs\/universo"},{"label":"P\u00e9rdida de los Recursos Ed\u00e1ficos: La Erosi\u00f3n","link":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/perdida-de-los-recursos-edaficos-la-erosion"},{"label":"La insustentabilidad de la agricultura industrial: Las Dust Bowl que se avecinan","link":"https:\/\/www.madrimasd.org\/blogs\/universo\/2023\/01\/31\/152032"}],"_links":{"self":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts\/152032"}],"collection":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/comments?post=152032"}],"version-history":[{"count":4,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts\/152032\/revisions"}],"predecessor-version":[{"id":153962,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts\/152032\/revisions\/153962"}],"wp:attachment":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/media?parent=152032"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/categories?post=152032"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/tags?post=152032"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}