{"id":153106,"date":"2023-07-31T11:18:58","date_gmt":"2023-07-31T10:18:58","guid":{"rendered":"https:\/\/www.madrimasd.org\/blogs\/universo\/?p=153106"},"modified":"2023-07-31T11:18:58","modified_gmt":"2023-07-31T10:18:58","slug":"propuesta-de-una-definicion-funcional-de-estanque-basado-en-metodos-cuantitativos","status":"publish","type":"post","link":"https:\/\/www.madrimasd.org\/blogs\/universo\/2023\/07\/31\/153106","title":{"rendered":"Propuesta de una definici\u00f3n funcional de estanque basado en m\u00e9todos cuantitativos"},"content":{"rendered":"<p style=\"text-align: center\"><img decoding=\"async\" class=\"ngg-singlepic ngg-center\" src=\"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-content\/blogs.dir\/42\/files\/164\/charcas-lagos-y-pozas.jpg\" alt=\"charcas-lagos-y-pozas\"><\/p>\n<p style=\"text-align: center\"><span style=\"color: #0000ff\">Fuente: Colaje im\u00e1genes Google<\/span><\/p>\n<p><span style=\"color: #800000\"><em>\u00bfQu\u00e9 es una charca?: \u00bfY tu me lo preguntas?: \u00a1Una charca eres t\u00fa?.<\/em><\/span><\/p>\n<p>La bibliograf\u00eda del trabajo Original menta varios trabajos relacionados con el tema de las <strong><span style=\"color: #3366ff\">charcas o estanques, zonas h\u00famedas y peque\u00f1os cuerpos de agua<\/span><\/strong>. Bas\u00e1ndose en ellos mentan<span style=\"color: #3366ff\"> <strong>la problem\u00e1tica de las definiciones<\/strong><\/span> del tema de estudio, y en este caso concreto, esencialmente de las <span style=\"color: #3366ff\"><strong>charcas<\/strong><\/span>. Digamos antes de empezar que la traducci\u00f3n del vocablo en suajili \u201c<strong><span style=\"color: #3366ff\"><em>ponds<\/em><\/span><\/strong>\u201d puede dar lugar a significados distintos, que a la vez var\u00edan seg\u00fan la situaci\u00f3n geogr\u00e1fica (poza, estanque, laguna, alberca, balsa, etc.). Sin embargo en el art\u00edculo, <strong><span style=\"color: #3366ff\">no existe referencia bibliogr\u00e1fica alguna a la enorme y complej\u00edsima tarea concerniente al papel y significado, de los conceptos en ciencia y sus diferentes tipos. Mal Asunto<\/span><\/strong><span style=\"color: #3366ff\">. <strong>La literatura acerca de este tema en filosof\u00eda de la ciencia es inmensa<\/strong><\/span>. Me temo que, tal problem\u00e1tica, que de hecho precede a una definici\u00f3n cient\u00edficamente concreta del objeto de estudio, va a dar lugar a una pol\u00e9mica sin fin, y m\u00e1s a\u00fan por los escasos conocimientos que tienen los cient\u00edficos actuales a cerca de la filosof\u00eda de la ciencia y, por lo que se\u00f1alan, tambi\u00e9n del objeto en cuesti\u00f3n. &nbsp;En t\u00e9rminos muy groseros, como ya os explicamos en nuestra categor\u00eda \u201c<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/curso-basico-sobre-filosofia-y-sociologia-de-la-ciencia\">Curso b\u00e1sico sobre filosof\u00eda y sociolog\u00eda de la ciencia<\/a>\u201d, <span style=\"color: #3366ff\"><strong>existen varios tipos de conceptos (tambi\u00e9n de modelos) cient\u00edficos<\/strong><\/span>. Actualmente la mayor parte de los colegas de estos temas desconocen casi todo. Generalmente, a la hora de definir un objeto nos encontramos con <span style=\"color: #3366ff\"><strong>conceptos cualitativos, semicuantitativos, y cuantitativos<\/strong><\/span>. Empero, en realidad, <strong><span style=\"color: #3366ff\">suele seguirse una concatenaci\u00f3n que arranca del primero, pasa por el segundo y termina por el \u00faltimo<\/span><\/strong><span style=\"color: #3366ff\">. <strong>Dif\u00edcilmente puede alcanzarse un concepto cuantitativo cient\u00edficamente s\u00f3lido, si no se parte inicialmente de otro cuantitativo digno de menci\u00f3n<\/strong><\/span>.&nbsp; &nbsp;\u00bfY que hacer con las \u201ccharcas\u201d que no cumplen los criterios de la definici\u00f3n? \u00bfQu\u00e9 son? \u00bfC\u00f3mo definirlas? \u00bfCu\u00e1ntas clases habr\u00eda? \u00bfQu\u00e9 extensi\u00f3n ocupan en la Tierra emergida?<\/p>\n<p>Los investigadores implicados<strong>, <span style=\"color: #3366ff\">comienzan hablado de funciones<\/span><\/strong>, t\u00e9rmino que ser\u00eda enormemente criticado por gran parte de las escuelas de filosof\u00eda de la ciencia, <span style=\"color: #3366ff\">\u00bf<strong>Cu\u00e1l es la funci\u00f3n de un estanque?<\/strong><\/span>, \u00bfCu\u00e1l es la funci\u00f3n de una roca?, \u00bfCu\u00e1l es la definici\u00f3n de un relieve?<span style=\"color: #3366ff\"> <strong>\u00bfCu\u00e1l es la definici\u00f3n de un suelo?<\/strong><\/span>.&nbsp; Sobre estos \u00faltimos ya mostramos que existen m\u00e1s de una docena de definiciones de suelos, as\u00ed como de la falta de consenso y una pol\u00e9mica interminable. &nbsp;Veamos pues:&nbsp;&nbsp;&nbsp;<\/p>\n<p>La nota de prensa, como ver\u00e9is abajo, comienza se\u00f1alando que; \u201c<span style=\"color: #800000\"><em>Casi todo el mundo puede identificar un estanque, pero \u00bfqu\u00e9 lo distingue exactamente de un lago o un humedal? Un nuevo estudio codirigido por la Universidad de Cornell ofrece la primera definici\u00f3n funcional basada en datos de un estanque y evidencia de la funci\u00f3n ecol\u00f3gica distintiva de los estanques, lo que podr\u00eda tener amplias implicaciones para la ciencia y la pol\u00edtica<\/em>.\u201d (\u2026.) \u201cSu conclusi\u00f3n: <em>los estanques son cuerpos de agua peque\u00f1os y poco profundos, con una superficie m\u00e1xima de cinco hect\u00e1reas, una profundidad m\u00e1xima de 5 metros y menos del 30% de vegetaci\u00f3n emergente<\/em>\u201d. \u00bf?<\/span>.<\/p>\n<p><strong><span style=\"color: #3366ff\">\u00bfEso vale?, \u00bfYa est\u00e1?<\/span><\/strong> Del mismo modo <strong><span style=\"color: #3366ff\">reconocen que las relaciones entre las muchas de las variables que estudian con vistas a concretar y precisar la definici\u00f3n son de naturaleza no-lineal, lo cual significa impl\u00edcitamente que no puede definirse con precisi\u00f3n<\/span><\/strong>, al menos con las variables analizadas. &nbsp;Tampoco queda claro la definici\u00f3n de \u201cfunci\u00f3n\u201d sin un contexto. El que en un momento dado apelemos al cambio clim\u00e1tico, por razones aparentemente l\u00f3gicas, no significa que su propuesta valga desde otros puntos de vista. Empero <strong><span style=\"color: #3366ff\">tambi\u00e9n reconocen \u201cimpl\u00edcitamente\u201d que existe un continuo entre los tama\u00f1os y profundidades de los cuerpos de agua que alberga la tierra emergida de los continentes. \u00bfD\u00f3nde est\u00e1n los puntos de corte?<\/span><\/strong>, y m\u00e1s a\u00fan cuando incluso los lagos de mayor extensi\u00f3n pueden secarse o fragmentarse en masas de agua de menores y variadas dimensiones por ciertos eventos clim\u00e1ticos. No mentan nada en su definici\u00f3n sobre el tema de los ascensos y descenso del nivel de las aguas estacionales, anuales y conforme a los ciclos de humedad-sequ\u00eda. \u00bfQu\u00e9 ocurre cuando se contaminan o est\u00e1n eutrofizados? \u00bfNo se altera su estructura y las susodichas funcionalidades?<\/p>\n<p>Como reiteramos en diverso post del curso b\u00e1sico mencionado,<span style=\"color: #3366ff\"> <strong>Los conceptos cient\u00edficos, no dejan de ser m\u00e1s que abstracciones de la realidad, por lo que no abarcan toda loa complejidad natural<\/strong><\/span>. Generalmente, con el tiempo, se alcanza <span style=\"color: #3366ff\"><strong>un consenso<\/strong><\/span> que ser\u00e1 debatido mediante conjeturas y refutaciones hasta que sea sustituido por otro, al acumularse numerosas anomal\u00edas.<span style=\"color: #3366ff\"> <strong>Y en este continuum de tama\u00f1os, estructuras, etc., cabr\u00eda precisar que definir un cuerpo de agua determinado, exigir\u00eda realizar cortes con vistas a precisar y definir tambi\u00e9n el resto de ellos<\/strong><\/span>. Se trata de una tarea que los autores del estudio no parecen realizar. Y que decir de los <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2016\/04\/25\/147092\">suelos h\u00eddricos<\/a> <span style=\"color: #3366ff\"><strong>que componen parte de las charcas<\/strong><\/span>, los cuales var\u00edan conforme a la clasificaci\u00f3n edafol\u00f3gica que se utilice?<\/p>\n<p>En mi opini\u00f3n, <span style=\"color: #3366ff\"><strong>este estudio solo atesora el valor de abrir un debate acerca de los peque\u00f1os cuerpos de agua<\/strong>, <strong>llamando la atenci\u00f3n acerca de la falta de estudios sobre el tema<\/strong><\/span>, si es el caso (la literatura que ellos citan no avala exactamente que el asunto no se tratara con anterioridad, ni mucho menos). Tambi\u00e9n <span style=\"color: #3366ff\"><strong>reconocen que son necesarias m\u00e1s investigaciones<\/strong><\/span> a la hora de aclarar y precisar su definici\u00f3n. Es decir, <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2021\/11\/11\/150045\">demandan atenci\u00f3n y financiaci\u00f3n, lo cual en el mundo de la tecnociencia viene a ser lo mismo<\/a>.<\/p>\n<p>Abajo os dejo abundante material de nuestros posts previos, con vistas a que entend\u00e1is el salto al vac\u00edo intelectual que llevan a cabo los autores.&nbsp; &nbsp;\u00a1Tremendo!.<\/p>\n<p><span style=\"color: #008000\"><strong>Juan Jos\u00e9 Ib\u00e1\u00f1ez<\/strong><\/span><\/p>\n<p><span style=\"color: #800000\"><em>Contin\u00faa\u2026\u2026..<\/em><\/span><\/p>\n<p><!--more--><\/p>\n<h2><a href=\"https:\/\/www.spacedaily.com\/reports\/What_is_a_pond_Study_provides_first_data_driven_definition_999.html\"><strong>\u00bfQu\u00e9 es un estanque? El estudio proporciona la primera definici\u00f3n basada en datos<\/strong>&nbsp;<\/a><\/h2>\n<p>por Staff Writers; Ithaca NY (SPX) Jul 07, 2022<\/p>\n<p>Casi todo el mundo puede identificar un estanque, pero \u00bfqu\u00e9 lo distingue exactamente de un lago o un humedal? Un nuevo estudio codirigido por la Universidad de Cornell ofrece la primera definici\u00f3n funcional basada en datos de un estanque y evidencia de la funci\u00f3n ecol\u00f3gica distintiva de los estanques, lo que podr\u00eda tener amplias implicaciones para la ciencia y la pol\u00edtica.<\/p>\n<p>\u00ab<strong>La falta de una definici\u00f3n universal de estanque<\/strong> causa mucha confusi\u00f3n, desde personas que se preguntan sobre la diferencia entre un estanque y un lago, hasta programas de monitoreo acu\u00e1tico con diferentes definiciones en todas las agencias gubernamentales, <strong>incluso hasta modelar con precisi\u00f3n los presupuestos globales de carbono<\/strong>\u00ab, dijo Meredith Holgerson, profesora asistente de ecolog\u00eda y biolog\u00eda evolutiva y coautora de \u00ab<strong>Una definici\u00f3n funcional para distinguir los estanques de los lagos y humedales<\/strong>, \u00bb publicado el <strong>21 de junio en Scientific Reports<\/strong>.<\/p>\n<p>\u00abQuer\u00edamos evaluar c\u00f3mo los cient\u00edficos y los responsables pol\u00edticos definen los estanques y <strong>examinar si los estanques son funcionalmente distintos de los lagos y humedales<\/strong>\u00ab, dijo Holgerson.<\/p>\n<p><strong><u>Su conclusi\u00f3n<\/u><\/strong>: <strong><em>los estanques son cuerpos de agua peque\u00f1os y poco profundos, con una superficie m\u00e1xima de cinco hect\u00e1reas, una profundidad m\u00e1xima de 5 metros y menos del 30% de vegetaci\u00f3n emergente<\/em><\/strong>.<\/p>\n<p><strong>Hay cientos de millones o incluso miles de millones de estanques en todo el mundo, m\u00e1s del 95% de los cuerpos de agua quietos del mundo son peque\u00f1os (menos de 10 hect\u00e1reas), pero el humilde estanque est\u00e1 poco estudiado<\/strong> <strong>y se ha dejado en gran medida fuera de los programas federales y estatales de monitoreo y protecci\u00f3n<\/strong>.<\/p>\n<p>Esto se debe en parte a <strong>que su n\u00famero dificulta el monitoreo<\/strong>, <strong>pero tambi\u00e9n porque las agencias no los definen ni los distinguen de los lagos o humedales<\/strong>. La <strong>negligencia tiene implicaciones para la precisi\u00f3n de los modelos clim\u00e1ticos<\/strong>, <strong>ya que los estanques son altos emisores de gases de efecto invernadero<\/strong>, y su contribuci\u00f3n al presupuesto mundial de carbono es incierta.<\/p>\n<p>Holgerson y su equipo <strong>examinaron c\u00f3mo los cient\u00edficos definieron el estanque en m\u00e1s de 500 art\u00edculos cient\u00edficos<\/strong> relevantes, <strong>codific\u00e1ndolo para diferentes descriptores, como el \u00e1rea de superficie o la profundidad, y si las descripciones eran cualitativas o cuantitativas<\/strong>.<\/p>\n<p>\u00ab<strong>Encontramos que no hab\u00eda una definici\u00f3n que todos los investigadores citaran, y las definiciones a menudo eran cualitativas<\/strong><strong>, describiendo un estanque como &#8216;peque\u00f1o&#8217;, por ejemplo<\/strong>\u00ab, dijo Holgerson.<\/p>\n<p>El equipo <strong>tambi\u00e9n realiz\u00f3 una encuesta de las agencias estatales a cargo del monitoreo y la conservaci\u00f3n de los cuerpos de agua<\/strong>. La mitad de los estados ten\u00edan legislaci\u00f3n que hac\u00eda referencia a los estanques, pero <strong>solo un estado (Michigan) defin\u00eda los estanques<\/strong>. Otros estados designaron estanques como aguas estatales o los agruparon con lagos o humedales.<\/p>\n<p>Sin embargo, los investigadores encontraron que los estanques no son lo mismo que los lagos o los humedales. <strong>Un examen m\u00e1s detallado de la literatura revel\u00f3 que los estanques tienen estructuras y funciones ecol\u00f3gicas distintas que hacen que su categorizaci\u00f3n con lagos o humedales sea problem\u00e1tica<\/strong>.<\/p>\n<p>Holgerson y su equipo trazaron las relaciones entre el \u00e1rea de superficie y varias m\u00e9tricas de estructura o funci\u00f3n ecol\u00f3gica. \u00abObservamos par\u00e1metros como la producci\u00f3n primaria bruta, la respiraci\u00f3n, los niveles de clorofila, las emisiones de gases de efecto invernadero, los rangos de temperatura de diel y la tasa de intercambio de gases con la atm\u00f3sfera\u00bb, dijo Holgerson. \u00ab<strong><u>Nueve de los 10 par\u00e1metros del ecosistema se relacionan no linealmente con el \u00e1rea de superficie<\/u><\/strong>, <strong>lo que sugiere que los estanques realmente est\u00e1n actuando de manera diferente<\/strong>\u00ab.<\/p>\n<p><strong>Tambi\u00e9n examinaron c\u00f3mo estas m\u00e9tricas del ecosistema se relacionaban con la profundidad y la vegetaci\u00f3n emergente<\/strong> (plantas enraizadas en el fondo que se extienden hasta la superficie) y <strong>nuevamente encontraron relaciones no lineales<\/strong>. <strong>Utilizaron los umbrales para saber d\u00f3nde las funciones de los cuerpos de agua comenzaron a cambiar con el \u00e1rea de superficie, la profundidad y la vegetaci\u00f3n emergente para llegar a su definici\u00f3n<\/strong>.<\/p>\n<p>El perfil y las caracter\u00edsticas distintivas de los estanques significan que no <strong>deben cumplir con los mismos est\u00e1ndares de monitoreo que los lagos o humedales<\/strong>, dijo Holgerson. \u00abPor ejemplo, <strong>los estanques pueden tener concentraciones de nutrientes naturalmente m\u00e1s altas y flujos de metano m\u00e1s altos. <\/strong><strong>Es posible que necesitemos desarrollar est\u00e1ndares \u00fanicos de calidad del agua para el monitoreo de estanques<\/strong>\u00ab.<\/p>\n<p><strong>Se necesita m\u00e1s investigaci\u00f3n para perfeccionar la definici\u00f3n, particularmente <\/strong><strong>para comprender mejor los cuerpos de agua en los l\u00edmites entre los humedales y estanques<\/strong>, y los estanques y lagos, y c\u00f3mo el tama\u00f1o, la profundidad, la vegetaci\u00f3n y otras variables como qu\u00e9 tan protegido est\u00e1 un cuerpo de agua, afectan el funcionamiento del estanque y su categorizaci\u00f3n.<\/p>\n<p>\u00ab<strong>Al comienzo del estudio, no est\u00e1bamos seguros de si nuestra investigaci\u00f3n nos permitir\u00eda proponer una nueva definici\u00f3n en la que nos sinti\u00e9ramos seguros, pero creemos que los n\u00fameros que ofrecemos son s\u00f3lidos<\/strong> y un gran punto de partida para futuras investigaciones\u00bb, dijo Holgerson. \u00ab<strong>Pedimos m\u00e1s investigaci\u00f3n, especialmente para observar los l\u00edmites entre humedales, estanques y lagos\u00bb<\/strong>.<\/p>\n<p>Holgerson <strong>espera que la nueva definici\u00f3n tambi\u00e9n llame la atenci\u00f3n sobre los estanques como ecosistemas distintos y significativos que merecen estudio<\/strong>, monitoreo y protecci\u00f3n. \u00abInvestigar y monitorear estanques puede ayudarnos a descubrir c\u00f3mo funcionan estos cuerpos de agua abundantes a nivel mundial. <strong>Tambi\u00e9n hay un elemento humano esencial\u00bb<\/strong>, dijo Holgerson. \u00abMuchas personas tienen conexiones con estanques, tienen historias de la infancia de atrapar ranas o aprender a pescar en un estanque cercano\u00bb.<\/p>\n<p>Esta investigaci\u00f3n fue apoyada por numerosas agencias, incluida la Red Global de Observatorios Ecol\u00f3gicos de Lagos, la Fundaci\u00f3n Nacional de Ciencias y el Programa Colaborativo de Investigaci\u00f3n e Investigaci\u00f3n de Pregrado de St. Olaf.<\/p>\n<p><strong>Informe de investigaci\u00f3n<\/strong><a href=\"https:\/\/dx.doi.org\/10.1038\/s41598-022-14569-0\"><strong>: Una definici\u00f3n funcional para distinguir los estanques de los lagos y humedales<\/strong><\/a><\/p>\n<p><strong><a href=\"\u00bfQu\u00e9%20es%20un%20estanque?%20El%20estudio%20proporciona%20la%20primera%20definici\u00f3n%20basada%20en%20datos\">\u00bfQu\u00e9 es un estanque? El estudio proporciona la primera definici\u00f3n basada en datos<\/a><\/strong><\/p>\n<p>por&nbsp;<a href=\"https:\/\/notimundo.news\/author\/jucebo\/\"><strong>Redaccion NM<\/strong><\/a><\/p>\n<p><a href=\"https:\/\/notimundo.news\/que-es-un-estanque-el-estudio-proporciona-la-primera-definicion-basada-en-datos\/\">Share<\/a><\/p>\n<p>Casi todo el mundo puede identificar un estanque, pero \u00bfqu\u00e9 es exactamente lo que lo distingue de un lago o un humedal? Un nuevo estudio codirigido por la Universidad de Cornell ofrece la primera definici\u00f3n funcional basada en datos de un estanque y evidencia de la funci\u00f3n ecol\u00f3gica distinta de los estanques, lo que podr\u00eda tener amplias implicaciones para la ciencia y la pol\u00edtica.<\/p>\n<p>\u00ab<strong>La falta de una definici\u00f3n universal de estanque causa mucha confusi\u00f3n<\/strong>, desde personas que se preguntan sobre la diferencia entre un estanque y un lago, hasta programas de monitoreo acu\u00e1tico con diferentes definiciones en agencias gubernamentales, incluso hasta modelar con precisi\u00f3n los presupuestos globales de carbono\u00bb, dijo Meredith. Holgerson, profesor asistente de ecolog\u00eda y biolog\u00eda evolutiva y coautor de \u00ab<strong>Una definici\u00f3n funcional<\/strong> para distinguir estanques de lagos y humedales\u00bb, publicado el 21 de junio en&nbsp;<em>Informes cient\u00edficos<\/em>.<\/p>\n<p>\u00abQuer\u00edamos evaluar c\u00f3mo los cient\u00edficos y los legisladores definen los estanques y examinar si los estanques son funcionalmente distintos de los lagos y humedales\u00bb, dijo Holgerson.<\/p>\n<p><strong>Su conclusi\u00f3n: Las charcas son cuerpos de agua peque\u00f1os y poco profundos, con una superficie m\u00e1xima de cinco hect\u00e1reas, una profundidad m\u00e1xima de 5 metros y menos del 30% de vegetaci\u00f3n emergente<\/strong>.<\/p>\n<p><strong>Hay cientos de millones o incluso miles de millones de estanques en todo el mundo (m\u00e1s del 95 % de los cuerpos de agua inm\u00f3viles del mundo son peque\u00f1os (menos de 10 hect\u00e1reas)), pero el humilde estanque no se ha estudiado y se ha dejado en gran parte fuera del control y la protecci\u00f3n federal y estatal<\/strong>. programas Esto se debe en parte a que su n\u00famero dificulta el monitoreo, pero tambi\u00e9n a que las agencias no logran definirlos o distinguirlos de lagos o humedales. El descuido tiene implicaciones para la precisi\u00f3n de los modelos clim\u00e1ticos, ya que los estanques son grandes emisores de gases de efecto invernadero y su contribuci\u00f3n al balance global de carbono es incierta.<\/p>\n<p>Holgerson y su equipo examinaron c\u00f3mo los cient\u00edficos definieron el estanque en m\u00e1s de 500 art\u00edculos cient\u00edficos relevantes, codific\u00e1ndolo para diferentes descriptores, como \u00e1rea de superficie o profundidad, y si las descripciones eran cualitativas o cuantitativas.<\/p>\n<p>\u00abDescubrimos que no hab\u00eda una definici\u00f3n que todos los investigadores citaran, y las definiciones a menudo eran cualitativas, describiendo un estanque como \u2018peque\u00f1o\u2019, por ejemplo\u00bb, dijo Holgerson.<\/p>\n<p>El equipo tambi\u00e9n realiz\u00f3 una encuesta de las agencias estatales a cargo del monitoreo y la conservaci\u00f3n de los cuerpos de agua. La mitad de los estados ten\u00edan legislaci\u00f3n que hac\u00eda referencia a los estanques, pero solo un estado (Michigan) los defin\u00eda. Otros estados designaron estanques como aguas estatales o los agruparon con lagos o humedales.<\/p>\n<p>Sin embargo, los investigadores descubrieron que los estanques no son lo mismo que los lagos o los humedales. Un examen m\u00e1s detallado de la literatura revel\u00f3 que los estanques tienen estructuras y funciones ecol\u00f3gicas distintas que hacen que su categorizaci\u00f3n con lagos o humedales sea problem\u00e1tica.<\/p>\n<p><strong>Holgerson y su equipo trazaron las relaciones entre el \u00e1rea de superficie y varias m\u00e9tricas de estructura o funci\u00f3n ecol\u00f3gica<\/strong>. \u00abObservamos par\u00e1metros como la producci\u00f3n primaria bruta, la respiraci\u00f3n, los niveles de clorofila, las emisiones de gases de efecto invernadero, los rangos de temperatura diaria y la tasa de intercambio de gases con la atm\u00f3sfera\u00bb, dijo Holgerson. \u00abNueve de los 10 par\u00e1metros del ecosistema se relacionaron de forma no lineal con el \u00e1rea de la superficie, lo que sugiere que los estanques realmente est\u00e1n actuando de manera diferente\u00bb.<\/p>\n<p><strong>Tambi\u00e9n examinaron c\u00f3mo estas m\u00e9tricas del ecosistema se relacionaban con la profundidad y la vegetaci\u00f3n emergente<\/strong> (plantas enraizadas en el fondo que se extienden hacia la superficie) y nuevamente encontraron relaciones no lineales. Usaron los umbrales donde las funciones de los cuerpos de agua comenzaron a cambiar con el \u00e1rea superficial, la profundidad y la vegetaci\u00f3n emergente para llegar a su definici\u00f3n.<\/p>\n<p>El perfil y las caracter\u00edsticas distintas de los estanques significa que no deben someterse a los mismos est\u00e1ndares de monitoreo que los lagos o los humedales, dijo Holgerson. \u00abPor ejemplo, los estanques pueden tener concentraciones de nutrientes naturalmente m\u00e1s altas y flujos de metano m\u00e1s altos. Es posible que necesitemos desarrollar est\u00e1ndares \u00fanicos de calidad del agua para monitorear estanques\u00bb.<\/p>\n<p>Se necesita m\u00e1s investigaci\u00f3n para perfeccionar la definici\u00f3n, particularmente para comprender mejor los cuerpos de agua en los l\u00edmites entre humedales y estanques, y estanques y lagos, y c\u00f3mo el tama\u00f1o, la profundidad, la vegetaci\u00f3n y otras variables, como qu\u00e9 tan protegido est\u00e1 un cuerpo de agua, impactan en el estado del estanque. funcionamiento y su categorizaci\u00f3n.<\/p>\n<p>\u00abAl comienzo del estudio, no est\u00e1bamos seguros de si nuestra investigaci\u00f3n nos permitir\u00eda proponer una nueva definici\u00f3n en la que nos sinti\u00e9ramos seguros, pero creemos que los n\u00fameros que ofrecemos son s\u00f3lidos y un excelente punto de partida para futuras investigaciones\u00bb. dijo Holgerson. \u00abPedimos m\u00e1s investigaci\u00f3n, especialmente para observar los l\u00edmites entre los humedales, los estanques y los lagos\u00bb.<\/p>\n<p>Holgerson espera que la nueva definici\u00f3n tambi\u00e9n llame la atenci\u00f3n sobre los estanques como ecosistemas distintos e importantes que merecen ser estudiados, monitoreados y protegidos. \u00abLa investigaci\u00f3n y el monitoreo de los estanques pueden ayudarnos a descubrir c\u00f3mo funcionan estos cuerpos de agua abundantes en todo el mundo. Tambi\u00e9n hay un elemento humano esencial\u00bb, dijo Holgerson. \u00abMuchas personas tienen conexiones con los estanques: tienen historias de la infancia de atrapar ranas o aprender a pescar en un estanque cercano\u00bb.<\/p>\n<p>Esta investigaci\u00f3n fue apoyada por numerosas agencias, incluida la Red del Observatorio Ecol\u00f3gico Global de Lagos, la Fundaci\u00f3n Nacional de Ciencias y el Programa Colaborativo de Investigaci\u00f3n e Investigaci\u00f3n de Pregrado de St. Olaf.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Sobre conceptos cient\u00edficos Concretamente<\/strong><\/p>\n<p><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2008\/04\/05\/88342\"><strong>Tipos de Conceptos Cient\u00edficos: I. De Hempel a Moster\u00edn<\/strong><\/a><\/p>\n<p><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2008\/04\/12\/88958\"><strong>Tipos de Conceptos Cient\u00edficos: II. Conceptos Comparativos<\/strong><\/a><\/p>\n<p><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2008\/04\/23\/89876\"><strong>Tipos de Conceptos Cient\u00edficos: III. Los Conceptos M\u00e9tricos<\/strong><\/a><\/p>\n<p><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2007\/11\/10\/78477\"><strong>Los Conceptos Cient\u00edficos y sus Limitaciones: Vivir en la Incertidumbre<\/strong><\/a><\/p>\n<p><strong>Otros posts relacionados con el tema<\/strong><\/p>\n<p><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2008\/01\/27\/83378\">Sobre lo Continuo y lo Contiguo: (\u00bfCu\u00e1ntos Lagos hay en el Mundo?) y la Naturaleza de los Suelos<\/a><\/p>\n<p><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2007\/11\/10\/78477\">Los Conceptos Cient\u00edficos y sus Limitaciones: Vivir en la Incertidumbre<\/a><\/p>\n<p><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/01\/29\/138143\">Especies: Sus M\u00faltiples Conceptos y definiciones<\/a><\/p>\n<p><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2009\/08\/07\/122826\">Las Controversias Cient\u00edficas y Sus Repercusiones Sociales (Sobre Conceptos y Taxonom\u00edas)<\/a><\/p>\n<p><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2007\/12\/23\/81275\">El Concepto de Especie, Tipo de Suelo y la Filosof\u00eda de la Ciencia (El Realismo Promiscuo)<\/a><\/p>\n<p><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2007\/08\/27\/72661\">Las Leyes Fractales de las Estructuras Superficiales terrestres (Terremotos, Deslizamientos, Avalanchas, Aludes, Lluvias Torrenciales, Inundaciones, etc.)<\/a><\/p>\n<p><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2008\/05\/10\/91441\">Concepto y Tipos de Modelos Cient\u00edficos<\/a><\/p>\n<p><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2008\/04\/23\/89876\">Tipos de Conceptos Cient\u00edficos: III. Los Conceptos M\u00e9tricos<\/a><\/p>\n<p><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2008\/04\/12\/88958\">Tipos de Conceptos Cient\u00edficos: II. Conceptos Comparativos<\/a><\/p>\n<p><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2008\/04\/05\/88342\">Tipos de Conceptos Cient\u00edficos: I. De Hempel a Moster\u00edn<\/a><\/p>\n<p><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2007\/11\/17\/78925\">Nominalismo, Realismo y Conceptualismo: Tres maneras de entender el \u201csignificado de concepto\u201d<\/a><\/p>\n<p><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2007\/12\/01\/80077\">El Discurso Cient\u00edfico, los Conceptos Contrarios y la Perspectiva de Jean-Marc L\u00e9vy-Leblond<\/a><\/p>\n<p><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2007\/11\/17\/78932\">WRB 2006 y sus Problemas Conceptuales\/Estructurales: El concepto de Suelo<\/a><\/p>\n<p><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2009\/12\/13\/130060\">La Cuantificaci\u00f3n de las Ciencias: Ciencias y Matem\u00e1ticas<\/a><\/p>\n<p><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2009\/08\/07\/122826\">Las Controversias Cient\u00edficas y Sus Repercusiones Sociales (Sobre Conceptos y Taxonom\u00edas)<\/a><\/p>\n<p><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2019\/10\/14\/150099\">Sobre la Tecnociencia, la Filosof\u00eda del Conocimiento, el Constructivismo y La Teor\u00eda Actor-red<\/a><\/p>\n<p><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2019\/02\/14\/150022\">De la Filosof\u00eda de la Ciencia a la Filosof\u00eda de la Tecnociencia (Nuevo Curso B\u00e1sico y Sus Razones)<\/a><\/p>\n<p><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/09\/21\/144433\">La Filosof\u00eda y Sociolog\u00eda de La Ciencia en la Docencia Universitaria: la Reacci\u00f3n de los Alumnos<\/a><\/p>\n<p><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/09\/13\/144426\">La Filosof\u00eda de la Ciencia en la Docencia Universitaria<\/a><\/p>\n<p><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/01\/09\/139998\">El Concepto de Suelos Zonales Corroborado por un Nuevo Estudio<\/a><\/p>\n<p><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2009\/01\/10\/110934\">\u00bfUna Ciencia y Dos Paradigmas?: Los Problemas de Comprensi\u00f3n de la Filosof\u00eda de Thomas Kuhn y las Teor\u00edas Cosmol\u00f3gicas<\/a><\/p>\n<p><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2008\/01\/05\/81875\">Filosof\u00eda de la Ciencia versus Filosof\u00eda de la Investigaci\u00f3n: \u00bfQui\u00e9n es Bruno Latour?<\/a><\/p>\n<p><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2007\/12\/08\/80527\">Ciencia, Religi\u00f3n y Filosof\u00eda: Evoluci\u00f3n, Creacionismo, Teor\u00eda del Dise\u00f1o Inteligente y las Elucubraciones de Cient\u00edficos y Fil\u00f3sofos<\/a><\/p>\n<p><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2007\/10\/27\/77520\">El Dudoso Estatus de los Modelos de Simulaci\u00f3n Predictivos en la Filosof\u00eda de la Ciencia<\/a><\/p>\n<p><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2007\/07\/08\/69567\">Relativismo Radical en la Filosof\u00eda de la Ciencia: El Anarquismo de Paul Feyerabend<\/a><\/p>\n<p><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2007\/05\/12\/65443\">Filosof\u00eda de la Ciencia: Lakatos Frente a Kuhn y Popper: \u00bfQue Marca la Diferencia?<\/a><\/p>\n<p><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2019\/03\/20\/149336\">La Dualidad Onda Part\u00edcula: Observaci\u00f3n y Teor\u00eda en Ecolog\u00eda y Ciencias del Suelo<\/a><\/p>\n<p><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2009\/01\/15\/111198\">Clasificaci\u00f3n de las Ciencias: El Ca\u00f3tico \u00c1rbol del Conocimiento<\/a><\/p>\n<p><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2008\/10\/20\/104123\">El Progreso de la Ciencia y La Computaci\u00f3n: \u00a1No es Oro todo lo que Reluce!<\/a><\/p>\n<p><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2008\/09\/05\/100251\">Pensamiento Cualitativo y Pensamiento Cuantitativo en la Pr\u00e1ctica Cient\u00edfica<\/a><\/p>\n<p><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2008\/08\/09\/98394\">Los Fracasos Experimentales y su Valor en la Ciencia (Reflexiones filos\u00f3ficas 1)<\/a><\/p>\n<p><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2007\/11\/25\/79544\">Pensamiento Anal\u00f3gico y Pensamiento Digital: Acerca de lo Continuo y lo Discreto<\/a><\/p>\n<p><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2019\/09\/17\/150234\">\u00bfQue son las malas Hierbas y la Maleza?<\/a><\/p>\n<p><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2013\/09\/26\/144528\">Las Funciones del Suelo y el Dise\u00f1o Inteligente (Un C\u00e1ncer que Desgarra las Ciencias de Suelo)<\/a><\/p>\n<p><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2008\/08\/13\/98653\">La Mente Humana, Espejo de la Naturaleza (y Viceversa)<\/a><\/p>\n<p><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2008\/08\/11\/98511\">Relaciones Causa-Efecto en la Pr\u00e1ctica Cient\u00edfica (Reflexiones filos\u00f3ficas 2)<\/a><\/p>\n<p><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2008\/05\/03\/90765\">Leyes, Teor\u00edas, Conjeturas e Hip\u00f3tesis Cient\u00edficas: \u00bfCu\u00e1les son las Diferencias?<\/a><\/p>\n<p><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2008\/02\/16\/84625\">Percepci\u00f3n Individual, Social y Cultural de la Realidad, Seg\u00fan Bruno Latour<\/a><\/p>\n<p><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2008\/02\/02\/83717\">Mente y Realidad: Descartes y Kant desde la \u00d3ptica de Bruno Latour<\/a><\/p>\n<p><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2008\/01\/19\/82675\">Las Necesarias Quimeras de la Ciencia: Sobre los Reduccionismos Ontol\u00f3gicos, Epistemol\u00f3gicos, Teor\u00edas Anidadas y Jerarqu\u00edas Cient\u00edficas<\/a><\/p>\n<p><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2007\/12\/15\/80973\">Clasificaciones, Percepci\u00f3n del Mundo y Progreso Acumulativo de la Ciencia<\/a><\/p>\n<p><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2009\/06\/20\/120522\">La Creatividad de los Cient\u00edficos y el Origen de Sus Teor\u00edas<\/a><\/p>\n<p><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2009\/06\/14\/120173\">An\u00e1lisis Metacient\u00edficos y Metaciencia<\/a><\/p>\n<p><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2009\/05\/23\/118756\">Metaciencia y Ciencia (Una Nueva Perspectiva)<\/a><\/p>\n<p><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2007\/04\/18\/63838\">Megaedafolog\u00eda, Edafomas, Regiones de Suelos, Conceptos Cient\u00edficos, Escalamiento y N\u00fameros M\u00e1gicos<\/a><\/p>\n<p><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2007\/04\/15\/63581\">Imre Lakatos y su Filosof\u00eda de la Ciencia<\/a><\/p>\n<p><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2006\/09\/21\/42562\">Filosofar sobre Ciencia no es apelar a la Filosof\u00eda de la Ciencia: Contestando a Antonio Ruiz Elvira<\/a><\/p>\n<p><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2022\/06\/23\/151650\">Taxonom\u00edas Gen\u00e9ticas de Ida y Vuelta: Tendencias en las Clasificaciones de Suelos y Minerales<\/a><\/p>\n<p><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2021\/11\/11\/150045\">Tecnociencia: Definici\u00f3n y Prop\u00f3sito<\/a><\/p>\n<p><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2016\/05\/13\/147687\">Disciplinas Maduras e Inmaduras: \u00bfHay disciplinas maduras?<\/a><\/p>\n<p><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/09\/13\/137119\">Teor\u00eda de Sistemas: El Dilema de la Demarcaci\u00f3n de sus L\u00edmites y Elementos<\/a><\/p>\n<p><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2009\/12\/19\/130315\">Informaci\u00f3n como Campo F\u00edsico o Metaf\u00edsico<\/a><\/p>\n<p><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2009\/03\/07\/114024\">El Nacimiento de una Ciencia: Generalidades y An\u00e1lisis de un Caso Concreto (Planetodiversidad)<\/a><\/p>\n<p><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2008\/10\/03\/102504\">Sociolog\u00eda de la Ciencia: Verdades y Falsas Verdades en Ciencia: Los T\u00f3picos Impregnantes<\/a><\/p>\n<p><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2007\/06\/17\/67885\">\u00bfExiste Progreso Acumulativo en Ciencia?: Una Afirmaci\u00f3n Puesta en Entredicho por Thomas Kuhn con su Dilema de la Inconmensurabilidad<\/a><\/p>\n<p><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2007\/05\/26\/66445\">Thomas Kuhn: Los Paradigmas y la Ciencia Normal<\/a><\/p>\n<p><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2007\/04\/01\/62705\">Teor\u00edas Cient\u00edficas Como Estructuras Complejas<\/a><\/p>\n<p><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2007\/03\/23\/62137\">La Complejidad de Refutar una Teor\u00eda Cient\u00edfica (Las Limitaciones del Falsacionismo)<\/a><\/p>\n<p><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2007\/01\/12\/57120\">Relaci\u00f3n Entre Datos y Teor\u00edas Cient\u00edficas: Los Enunciados Observacionales Presuponen la Teor\u00eda (a vueltas con los edafometras)<\/a><\/p>\n<p><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2006\/10\/08\/45363\">El M\u00e9todo Cient\u00edfico<\/a><\/p>\n<p><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2006\/01\/09\/11785\">Modelos Conceptuales y Representaciones del Sistema Suelo 9: El Suelo Como Biomanto<\/a><\/p>\n<p><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2010\/10\/30\/136974\">Los Conceptos de Suelo y sus Representaciones: Un Compendium<\/a><\/p>\n<h3>Im\u00e1genes Relacionadas:<\/h3>","protected":false},"excerpt":{"rendered":"<p>Fuente: Colaje im\u00e1genes Google \u00bfQu\u00e9 es una charca?: \u00bfY tu me lo preguntas?: \u00a1Una charca eres t\u00fa?. La bibliograf\u00eda del trabajo Original menta varios trabajos relacionados con el tema de las charcas o estanques, zonas h\u00famedas y peque\u00f1os cuerpos de agua. Bas\u00e1ndose en ellos mentan la problem\u00e1tica de las definiciones del tema de estudio, y en este caso concreto, esencialmente de las charcas. Digamos antes de empezar que la traducci\u00f3n del vocablo en suajili \u201cponds\u201d puede dar lugar a significados distintos, que a la vez var\u00edan seg\u00fan la situaci\u00f3n geogr\u00e1fica (poza, estanque, laguna, alberca, balsa, etc.). Sin embargo en el\u2026<\/p>\n","protected":false},"author":26,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0},"categories":[603,609,618,588,597,611],"tags":[48984,48985,48983,47702],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":4}},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Fuente: Colaje im\u00e1genes Google \u00bfQu\u00e9 es una charca?: \u00bfY tu me lo preguntas?: \u00a1Una charca eres t\u00fa?. La bibliograf\u00eda del trabajo Original menta varios trabajos relacionados con el tema de las charcas o estanques, zonas h\u00famedas y peque\u00f1os cuerpos de agua. Bas\u00e1ndose en ellos mentan la problem\u00e1tica de las definiciones del tema de estudio, y\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Juan Jos\u00e9 Ib\u00e1\u00f1ez\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2023\/07\/31\/153106\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Un Universo invisible bajo nuestros pies - Los suelos y la vida\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Propuesta de una definici\u00f3n funcional de estanque basado en m\u00e9todos cuantitativos - Un Universo invisible bajo nuestros pies\" \/>\n\t\t<meta property=\"og:description\" content=\"Fuente: Colaje im\u00e1genes Google \u00bfQu\u00e9 es una charca?: \u00bfY tu me lo preguntas?: \u00a1Una charca eres t\u00fa?. La bibliograf\u00eda del trabajo Original menta varios trabajos relacionados con el tema de las charcas o estanques, zonas h\u00famedas y peque\u00f1os cuerpos de agua. Bas\u00e1ndose en ellos mentan la problem\u00e1tica de las definiciones del tema de estudio, y\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2023\/07\/31\/153106\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2023-07-31T10:18:58+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2023-07-31T10:18:58+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/juan.j.marti.14\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Propuesta de una definici\u00f3n funcional de estanque basado en m\u00e9todos cuantitativos - Un Universo invisible bajo nuestros pies\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Fuente: Colaje im\u00e1genes Google \u00bfQu\u00e9 es una charca?: \u00bfY tu me lo preguntas?: \u00a1Una charca eres t\u00fa?. La bibliograf\u00eda del trabajo Original menta varios trabajos relacionados con el tema de las charcas o estanques, zonas h\u00famedas y peque\u00f1os cuerpos de agua. Bas\u00e1ndose en ellos mentan la problem\u00e1tica de las definiciones del tema de estudio, y\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2023\\\/07\\\/31\\\/153106#blogposting\",\"name\":\"Propuesta de una definici\\u00f3n funcional de estanque basado en m\\u00e9todos cuantitativos - Un Universo invisible bajo nuestros pies\",\"headline\":\"Propuesta de una definici\\u00f3n funcional de estanque basado en m\\u00e9todos cuantitativos\",\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/wp-content\\\/blogs.dir\\\/42\\\/files\\\/164\\\/charcas-lagos-y-pozas.jpg\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2023\\\/07\\\/31\\\/153106\\\/#articleImage\"},\"datePublished\":\"2023-07-31T11:18:58+01:00\",\"dateModified\":\"2023-07-31T11:18:58+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2023\\\/07\\\/31\\\/153106#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2023\\\/07\\\/31\\\/153106#webpage\"},\"articleSection\":\"Carpeta sobre Paisajes de Suelos y los Suelos en el Paisaje, Curso B\\u00e1sico Sobre Filosof\\u00eda y Sociolog\\u00eda de la Ciencia, Ecolog\\u00eda y Biogeograf\\u00eda post posteriores a agosto de 2009, El Concepto de Suelo y Sus Representaciones, Filosof\\u00eda, Historia y Sociolog\\u00eda de la Edafolog\\u00eda, Zona Cr\\u00edtica Terrestre y El Futuro de la Edafolog\\u00eda, concepto de charcas, concepto de pozas, definici\\u00f3n de charcas, tipos de suelos\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2023\\\/07\\\/31\\\/153106#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/el-concepto-de-suelo-y-sus-representaciones#listItem\",\"name\":\"El Concepto de Suelo y Sus Representaciones\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/el-concepto-de-suelo-y-sus-representaciones#listItem\",\"position\":2,\"name\":\"El Concepto de Suelo y Sus Representaciones\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/el-concepto-de-suelo-y-sus-representaciones\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2023\\\/07\\\/31\\\/153106#listItem\",\"name\":\"Propuesta de una definici\\u00f3n funcional de estanque basado en m\\u00e9todos cuantitativos\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2023\\\/07\\\/31\\\/153106#listItem\",\"position\":3,\"name\":\"Propuesta de una definici\\u00f3n funcional de estanque basado en m\\u00e9todos cuantitativos\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/el-concepto-de-suelo-y-sus-representaciones#listItem\",\"name\":\"El Concepto de Suelo y Sus Representaciones\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#organization\",\"name\":\"Un Universo invisible bajo nuestros pies\",\"description\":\"Los suelos y la vida\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/files\\\/2022\\\/02\\\/logo.png\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2023\\\/07\\\/31\\\/153106\\\/#organizationLogo\",\"width\":217,\"height\":72},\"image\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2023\\\/07\\\/31\\\/153106\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/juan.j.marti.14\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo\",\"name\":\"Juan Jos\\u00e9 Ib\\u00e1\\u00f1ez\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2023\\\/07\\\/31\\\/153106#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/387f3a100385573d8f42ce2a3211fd1c?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Juan Jos\\u00e9 Ib\\u00e1\\u00f1ez\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2023\\\/07\\\/31\\\/153106#webpage\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2023\\\/07\\\/31\\\/153106\",\"name\":\"Propuesta de una definici\\u00f3n funcional de estanque basado en m\\u00e9todos cuantitativos - Un Universo invisible bajo nuestros pies\",\"description\":\"Fuente: Colaje im\\u00e1genes Google \\u00bfQu\\u00e9 es una charca?: \\u00bfY tu me lo preguntas?: \\u00a1Una charca eres t\\u00fa?. La bibliograf\\u00eda del trabajo Original menta varios trabajos relacionados con el tema de las charcas o estanques, zonas h\\u00famedas y peque\\u00f1os cuerpos de agua. Bas\\u00e1ndose en ellos mentan la problem\\u00e1tica de las definiciones del tema de estudio, y\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2023\\\/07\\\/31\\\/153106#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\"},\"datePublished\":\"2023-07-31T11:18:58+01:00\",\"dateModified\":\"2023-07-31T11:18:58+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#website\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/\",\"name\":\"Un Universo invisible bajo nuestros pies\",\"description\":\"Los suelos y la vida\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Propuesta de una definici\u00f3n funcional de estanque basado en m\u00e9todos cuantitativos - Un Universo invisible bajo nuestros pies","description":"Fuente: Colaje im\u00e1genes Google \u00bfQu\u00e9 es una charca?: \u00bfY tu me lo preguntas?: \u00a1Una charca eres t\u00fa?. La bibliograf\u00eda del trabajo Original menta varios trabajos relacionados con el tema de las charcas o estanques, zonas h\u00famedas y peque\u00f1os cuerpos de agua. Bas\u00e1ndose en ellos mentan la problem\u00e1tica de las definiciones del tema de estudio, y","canonical_url":"https:\/\/www.madrimasd.org\/blogs\/universo\/2023\/07\/31\/153106","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2023\/07\/31\/153106#blogposting","name":"Propuesta de una definici\u00f3n funcional de estanque basado en m\u00e9todos cuantitativos - Un Universo invisible bajo nuestros pies","headline":"Propuesta de una definici\u00f3n funcional de estanque basado en m\u00e9todos cuantitativos","author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author"},"publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-content\/blogs.dir\/42\/files\/164\/charcas-lagos-y-pozas.jpg","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2023\/07\/31\/153106\/#articleImage"},"datePublished":"2023-07-31T11:18:58+01:00","dateModified":"2023-07-31T11:18:58+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2023\/07\/31\/153106#webpage"},"isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2023\/07\/31\/153106#webpage"},"articleSection":"Carpeta sobre Paisajes de Suelos y los Suelos en el Paisaje, Curso B\u00e1sico Sobre Filosof\u00eda y Sociolog\u00eda de la Ciencia, Ecolog\u00eda y Biogeograf\u00eda post posteriores a agosto de 2009, El Concepto de Suelo y Sus Representaciones, Filosof\u00eda, Historia y Sociolog\u00eda de la Edafolog\u00eda, Zona Cr\u00edtica Terrestre y El Futuro de la Edafolog\u00eda, concepto de charcas, concepto de pozas, definici\u00f3n de charcas, tipos de suelos"},{"@type":"BreadcrumbList","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2023\/07\/31\/153106#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo#listItem","position":1,"name":"Home","item":"https:\/\/www.madrimasd.org\/blogs\/universo","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/el-concepto-de-suelo-y-sus-representaciones#listItem","name":"El Concepto de Suelo y Sus Representaciones"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/el-concepto-de-suelo-y-sus-representaciones#listItem","position":2,"name":"El Concepto de Suelo y Sus Representaciones","item":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/el-concepto-de-suelo-y-sus-representaciones","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2023\/07\/31\/153106#listItem","name":"Propuesta de una definici\u00f3n funcional de estanque basado en m\u00e9todos cuantitativos"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2023\/07\/31\/153106#listItem","position":3,"name":"Propuesta de una definici\u00f3n funcional de estanque basado en m\u00e9todos cuantitativos","previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/el-concepto-de-suelo-y-sus-representaciones#listItem","name":"El Concepto de Suelo y Sus Representaciones"}}]},{"@type":"Organization","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#organization","name":"Un Universo invisible bajo nuestros pies","description":"Los suelos y la vida","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/","logo":{"@type":"ImageObject","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2023\/07\/31\/153106\/#organizationLogo","width":217,"height":72},"image":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2023\/07\/31\/153106\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/juan.j.marti.14"]},{"@type":"Person","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo","name":"Juan Jos\u00e9 Ib\u00e1\u00f1ez","image":{"@type":"ImageObject","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2023\/07\/31\/153106#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/387f3a100385573d8f42ce2a3211fd1c?s=96&d=mm&r=g","width":96,"height":96,"caption":"Juan Jos\u00e9 Ib\u00e1\u00f1ez"}},{"@type":"WebPage","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2023\/07\/31\/153106#webpage","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/2023\/07\/31\/153106","name":"Propuesta de una definici\u00f3n funcional de estanque basado en m\u00e9todos cuantitativos - Un Universo invisible bajo nuestros pies","description":"Fuente: Colaje im\u00e1genes Google \u00bfQu\u00e9 es una charca?: \u00bfY tu me lo preguntas?: \u00a1Una charca eres t\u00fa?. La bibliograf\u00eda del trabajo Original menta varios trabajos relacionados con el tema de las charcas o estanques, zonas h\u00famedas y peque\u00f1os cuerpos de agua. Bas\u00e1ndose en ellos mentan la problem\u00e1tica de las definiciones del tema de estudio, y","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#website"},"breadcrumb":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2023\/07\/31\/153106#breadcrumblist"},"author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author"},"creator":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author"},"datePublished":"2023-07-31T11:18:58+01:00","dateModified":"2023-07-31T11:18:58+01:00"},{"@type":"WebSite","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#website","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/","name":"Un Universo invisible bajo nuestros pies","description":"Los suelos y la vida","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Un Universo invisible bajo nuestros pies - Los suelos y la vida","og:type":"article","og:title":"Propuesta de una definici\u00f3n funcional de estanque basado en m\u00e9todos cuantitativos - Un Universo invisible bajo nuestros pies","og:description":"Fuente: Colaje im\u00e1genes Google \u00bfQu\u00e9 es una charca?: \u00bfY tu me lo preguntas?: \u00a1Una charca eres t\u00fa?. La bibliograf\u00eda del trabajo Original menta varios trabajos relacionados con el tema de las charcas o estanques, zonas h\u00famedas y peque\u00f1os cuerpos de agua. Bas\u00e1ndose en ellos mentan la problem\u00e1tica de las definiciones del tema de estudio, y","og:url":"https:\/\/www.madrimasd.org\/blogs\/universo\/2023\/07\/31\/153106","og:image":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png","og:image:secure_url":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png","article:published_time":"2023-07-31T10:18:58+00:00","article:modified_time":"2023-07-31T10:18:58+00:00","article:publisher":"https:\/\/www.facebook.com\/juan.j.marti.14","twitter:card":"summary","twitter:title":"Propuesta de una definici\u00f3n funcional de estanque basado en m\u00e9todos cuantitativos - Un Universo invisible bajo nuestros pies","twitter:description":"Fuente: Colaje im\u00e1genes Google \u00bfQu\u00e9 es una charca?: \u00bfY tu me lo preguntas?: \u00a1Una charca eres t\u00fa?. La bibliograf\u00eda del trabajo Original menta varios trabajos relacionados con el tema de las charcas o estanques, zonas h\u00famedas y peque\u00f1os cuerpos de agua. Bas\u00e1ndose en ellos mentan la problem\u00e1tica de las definiciones del tema de estudio, y","twitter:image":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png"},"aioseo_meta_data":{"post_id":"153106","title":null,"description":null,"keywords":[],"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":"{\"article\":{\"articleType\":\"BlogPosting\"},\"course\":{\"name\":\"\",\"description\":\"\",\"provider\":\"\"},\"faq\":{\"pages\":[]},\"product\":{\"reviews\":[]},\"recipe\":{\"ingredients\":[],\"instructions\":[],\"keywords\":[]},\"software\":{\"reviews\":[],\"operatingSystems\":[]},\"webPage\":{\"webPageType\":\"WebPage\"}}","pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","tabs":null,"priority":0,"frequency":"default","local_seo":null,"created":"2022-07-14 12:21:03","updated":"2026-05-26 19:59:59","limit_modified_date":false,"ai":null,"breadcrumb_settings":null,"seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/el-concepto-de-suelo-y-sus-representaciones\" title=\"El Concepto de Suelo y Sus Representaciones\">El Concepto de Suelo y Sus Representaciones<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tPropuesta de una definici\u00f3n funcional de estanque basado en m\u00e9todos cuantitativos\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.madrimasd.org\/blogs\/universo"},{"label":"El Concepto de Suelo y Sus Representaciones","link":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/el-concepto-de-suelo-y-sus-representaciones"},{"label":"Propuesta de una definici\u00f3n funcional de estanque basado en m\u00e9todos cuantitativos","link":"https:\/\/www.madrimasd.org\/blogs\/universo\/2023\/07\/31\/153106"}],"_links":{"self":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts\/153106"}],"collection":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/comments?post=153106"}],"version-history":[{"count":2,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts\/153106\/revisions"}],"predecessor-version":[{"id":154777,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts\/153106\/revisions\/154777"}],"wp:attachment":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/media?parent=153106"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/categories?post=153106"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/tags?post=153106"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}