{"id":153505,"date":"2023-12-13T14:45:11","date_gmt":"2023-12-13T13:45:11","guid":{"rendered":"https:\/\/www.madrimasd.org\/blogs\/universo\/?p=153505"},"modified":"2023-12-13T14:45:18","modified_gmt":"2023-12-13T13:45:18","slug":"agricultura-y-huertos-familiares-diversidad-y-seguridad-alimentaria-una-asociacion-indisociable","status":"publish","type":"post","link":"https:\/\/www.madrimasd.org\/blogs\/universo\/2023\/12\/13\/153505","title":{"rendered":"Agricultura y Huertos Familiares, Diversidad y Seguridad Alimentaria: Una asociaci\u00f3n indisociable."},"content":{"rendered":"<p style=\"text-align: center\"><img decoding=\"async\" class=\"ngg-singlepic ngg-center\" src=\"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-content\/blogs.dir\/42\/files\/255\/agrodiversidad-granjas-pequenas.jpg\" alt=\"agrodiversidad-granjas-pequenas\"><\/p>\n<p style=\"text-align: center\"><span style=\"color: #0000ff\">Fuente: Colaje im\u00e1genes Google<\/span><\/p>\n<p><span style=\"color: #3366ff\"><strong>Debemos preguntarnos y responder sinceramente que hemos ganado y que, perdido, al ir transformando la producci\u00f3n de alimentos en una empresa global, en la cual maximizar la productividad y la b\u00fasqueda de beneficios econ\u00f3micos son el fin en s\u00ed mismos<\/strong><\/span>. Las dos notas de prensa que os proporciono hoy dan fe de ello. <span style=\"color: #3366ff\"><strong>La globalizaci\u00f3n econ\u00f3mica y como corolario tambi\u00e9n la agraria<\/strong>, <strong>ha destrozado grandes extensiones de espacios geogr\u00e1ficos sustentables, y generando inseguridad alimentaria en el mundo<\/strong>. <strong>Las agriculturas y huertos familiares proporcionaban abundantes beneficios tanto alimentarios como ecol\u00f3gicos, y sobre todo seguridad alimentaria<\/strong><\/span>. Por el contrario, la<span style=\"color: #3366ff\"> <strong>agricultura industrial<\/strong><\/span>, manipulada por los grandes lobbies agroindustriales y alimentarios, a cortocircuitado todo el proceso, siendo a veces exclusivamente beneficiosa para los <span style=\"color: #3366ff\"><strong>tenedores de grandes predios<\/strong>. <strong>La agricultura industrial, ha expuesto a los campesinos a las veleidades de una econom\u00eda de mercado, en la que<\/strong> <\/span>el valor de las producciones sube y baja sin cesar pudiendo obtener ganancia unos a\u00f1os, perder o incluso arruinarse en otros. \u00bfQu\u00e9 ocurre si un a\u00f1o ese cultivo fracasa por la acci\u00f3n de eventos extremos o plagas? Ustedes conocen la respuesta.<span style=\"color: #3366ff\"><strong>Y, como corolario, esa diversidad agraria que generaba la obtenci\u00f3n de alimentos y otras materias primas, dando lugar a que los granjeros tuvieran bastante independencia respecto a las econom\u00edas de mercado a gran escala<\/strong>. <strong>La inclusi\u00f3n de estos lobbies industriales y\/o instituciones gubernamentales que animan mediante est\u00edmulos a erradicar las variedades locales e implantar las que \u201cen ese momento\u201d son m\u00e1s rentables, da lugar a una enorme p\u00e9rdida de diversidad tanto de especies como gen\u00e9tica<\/strong>. <\/span>Del mismo modo,<span style=\"color: #3366ff\"><strong>los peque\u00f1os propietarios deben adquirir bienes que antes produc\u00edan ellos<\/strong><\/span>, a obtenerlos <span style=\"color: #3366ff\"><strong>en la inseguridad intr\u00ednseca de la econom\u00eda de mercado<\/strong>. &nbsp;<strong>Gran parte de esas peque\u00f1as granjas inclu\u00edan frutales y otros \u00e1rboles, tanto en su seno como en sus lindes, mientras que hoy<\/strong><\/span> observamos espacios mon\u00f3tonos insustanciales. Es decir, se reemplazan abundantes de especies por los productos y variedades que demanda el mercado por unas pocas y, a menudo artificiales (transg\u00e9nicos, etc.), a menudo por puras modas. &nbsp;<\/p>\n<p>Los post que hemos traducido hoy: <strong>(i)<\/strong> <strong><a href=\"https:\/\/phys.org\/news\/2022-08-agricultural-diversity-positive-impact-food.html?utm_source=nwletter&amp;utm_medium=email&amp;utm_campaign=daily-nwletter\">Un estudio concluye que la diversidad agr\u00edcola tiene un impacto positivo en la seguridad alimentaria<\/a> y (ii) <a href=\"https:\/\/phys.org\/news\/2022-08-home-gardens-gene-banks-sustain.html?utm_source=nwletter&amp;utm_medium=email&amp;utm_campaign=daily-nwletter\">Los huertos familiares son bancos de genes vivos que sostienen los medios de vida en Asia Central<\/a><\/strong>, os mostrar\u00e1n muchos m\u00e1s detalles. Todos aquellos que profetizan prosperidad y seguridad bajo las bases de abandonar todo todito todo a la econom\u00eda de mercado, por muchas novedades y promesas que publicitan, conducen a la <span style=\"color: #3366ff\"><strong>inseguridad alimentaria y p\u00e9rdida de servicios ecosist\u00e9micos<\/strong><\/span>.<\/p>\n<p>En uno de los estudios, se habla de la pl\u00e9tora de \u00edndices que se han propuesto en la literatura a tal respecto, aunque pronto os ofrecer\u00e9 uno, enormemente sencillo y que cualquiera puede aplicar con los datos de internet. Esta \u00faltima publicci\u00f3n muestra incuestionablemente que siempre ganan los mismos ante la inexorable <a href=\"https:\/\/es.wikipedia.org\/wiki\/Efecto_Mateo\">Ley de San Mateo<\/a>. Leer las dos noticias ya que resultan sumamente esclarecedoras. La <strong><a href=\"%20Una%20asociaci\u00f3n%20indisociable.\">Bobalizaci\u00f3n Econ\u00f3mica deviene en la globalizaci\u00f3n de la pobreza<\/a><\/strong>.<\/p>\n<p><span style=\"color: #008000\"><strong>Juan Jos\u00e9 Ib\u00e1\u00f1ez<\/strong><\/span><\/p>\n<p><span style=\"color: #800000\"><em>Contin\u00faa\u2026\u2026..<\/em><\/span><\/p>\n<p><!--more--><\/p>\n<h4><strong><a href=\"https:\/\/phys.org\/news\/2022-08-agricultural-diversity-positive-impact-food.html?utm_source=nwletter&amp;utm_medium=email&amp;utm_campaign=daily-nwletter\">Un estudio concluye que la diversidad agr\u00edcola tiene un impacto positivo en la seguridad alimentaria<\/a><\/strong><\/h4>\n<p>por la Alianza de Bioversity International y el Centro Internacional de Agricultura Tropical<\/p>\n<p><strong>La diversidad agr\u00edcola puede ser un importante impulsor de la seguridad alimentaria, pero la magnitud de la contribuci\u00f3n depende de las caracter\u00edsticas socioecon\u00f3micas y biof\u00edsicas m\u00e1s amplias del sistema agr\u00edcola local<\/strong>, seg\u00fan un art\u00edculo publicado recientemente por investigadores que incluyen a los de la Alianza de Bioversity International y el CIAT.<\/p>\n<p>En su art\u00edculo publicado en la revista&nbsp;<em>Global Food Security<\/em>&nbsp;en junio de 2022, los investigadores encontraron que, <strong>en casi dos tercios de todos los casos, la diversidad agr\u00edcola tuvo un efecto positivo en la seguridad alimentaria, pero en aproximadamente un tercio de las relaciones no hubo ning\u00fan efecto de la diversidad agr\u00edcola en la seguridad alimentaria, o los resultados fueron mixtos<\/strong>.<\/p>\n<p><strong>Seg\u00fan<\/strong> la Organizaci\u00f3n de las Naciones Unidas para la Agricultura y la Alimentaci\u00f3n (<strong>FAO<\/strong>), <strong>la seguridad alimentaria existe cuando todas las personas, en todo momento, tienen acceso f\u00edsico y econ\u00f3mico a alimentos suficientes<\/strong>,&nbsp;<a href=\"https:\/\/phys.org\/tags\/nutritious+food\/\">inocuos y nutritivos<\/a>&nbsp;<strong>que satisfagan sus necesidades diet\u00e9ticas y preferencias alimentarias para una vida activa y<\/strong>&nbsp;<a href=\"https:\/\/phys.org\/tags\/healthy+life\/\">saludable<\/a>, <strong>mientras que la diversidad agr\u00edcola incluye la diversidad de variedades de cultivos, razas de ganado, especies de peces y recursos no domesticados (silvestres), incluida la forma en que se procesan y consumen<\/strong>.<\/p>\n<p><strong>La revisi\u00f3n de la literatura<\/strong> realizada por los investigadores mostr\u00f3 que <strong>el trabajo que se hab\u00eda realizado en todo el Sur Global o los pa\u00edses de ingresos medios-bajos (LMIC) que analizan el v\u00ednculo entre la diversidad agr\u00edcola y la seguridad alimentaria y proporcionan una base para que otros investigadores en el campo ahora puedan usarse para<\/strong> encontrar colaboradores o pensar en otras preguntas de investigaci\u00f3n.<\/p>\n<p>Katharina Waha, cient\u00edfica investigadora principal en el grupo de Seguridad Alimentaria y Nutricional Global de CSIRO en Brisbane, Australia, y autora principal del estudio, dijo que <strong>hab\u00eda 40 \u00edndices que med\u00edan las diferentes medidas y relaciones individuales<\/strong>.<\/p>\n<p>\u00ab<strong>Analizamos todas las combinaciones que se podr\u00edan pensar y c\u00f3mo medir cuantitativamente entre los indicadores de seguridad alimentaria y diversidad<\/strong>\u00ab, dijo Waha, \u00abEn t\u00e9rminos de&nbsp;<a href=\"https:\/\/phys.org\/tags\/health+outcomes\/\">resultados<\/a>&nbsp;negativos de salud para las personas, toda la literatura sobre resultados nutricionales y de salud dir\u00eda que no tener esa diversidad o calidad es el resultado final\u00bb.<\/p>\n<p><strong>Los investigadores encontraron que, aunque la diversidad agr\u00edcola puede ser beneficiosa para la seguridad alimentaria, no es la \u00fanica estrategia disponible<\/strong> para promover la seguridad alimentaria. Donde <strong>la diversificaci\u00f3n es tambi\u00e9n la estrategia m\u00e1s barata en t\u00e9rminos de costos monetarios y laborales, puede ser una opci\u00f3n atractiva y efectiva para mejorar las pr\u00e1cticas y ganancias agr\u00edcolas<\/strong>.<\/p>\n<p>Elisabetta Gotor es cient\u00edfica principal y economista agr\u00edcola de la Alianza de Bioversity International y el CIAT. Tiene 20 a\u00f1os de experiencia en an\u00e1lisis econ\u00f3micos y evaluaci\u00f3n de soluciones del sistema alimentario que est\u00e1n en el nexo de la agricultura, el medio ambiente y la nutrici\u00f3n, con investigaciones centradas en <strong>vincular la intervenci\u00f3n basada en la biodiversidad con<\/strong>&nbsp;<strong><a href=\"https:\/\/phys.org\/tags\/poverty+reduction\/\">la reducci\u00f3n de la pobreza, la<\/a><\/strong><strong>&nbsp;seguridad alimentaria y la nutrici\u00f3n, los medios de vida rurales sostenibles y los resultados de resiliencia<\/strong>. Gotor dijo que era importante estudiar el v\u00ednculo entre los dos conceptos.<\/p>\n<p>Gotor dijo que era importante <strong>estudiar el v\u00ednculo entre los dos conceptos<\/strong>.<\/p>\n<p>\u00ab<strong>Tengo una serie de estudios en los que encuentro el v\u00ednculo entre la diversidad agr\u00edcola y la<\/strong>&nbsp;<a href=\"https:\/\/phys.org\/tags\/food+security\/\">seguridad alimentaria<\/a>\u00ab, dijo Gotor, \u00ab<strong>no solo es el impulsor, sino que es la base de todo<\/strong>\u00ab.<\/p>\n<p>Gotor dijo que <strong>la diversidad en la granja debe preservarse y la forma de conservarla es a trav\u00e9s del uso diario<\/strong>.<\/p>\n<p>\u00ab<strong>Si tienes un sistema diverso, puedes lidiar con el estr\u00e9s bi\u00f3tico y abi\u00f3tico, por ejemplo, como los impactos del cambio clim\u00e1tico<\/strong>\u00ab, dijo Gotor, y agreg\u00f3 que la&nbsp;<a href=\"https:\/\/phys.org\/tags\/genetic+diversity\/\">diversidad gen\u00e9tica<\/a>&nbsp;<strong>es necesaria para encontrar nuevas variedades de cultivos<\/strong>.<\/p>\n<p>\u00abEs importante entender c\u00f3mo medimos la diversidad y c\u00f3mo evaluamos los otros elementos de la diversidad\u00bb, dijo Gotor.<\/p>\n<p>Los investigadores dijeron <strong>que los dise\u00f1os de estudios hol\u00edsticos que consideran los aspectos naturales, sociales y<\/strong>&nbsp;<a href=\"https:\/\/phys.org\/tags\/economic+aspects\/\">econ\u00f3micos<\/a>&nbsp;<strong>de los sistemas agr\u00edcolas y alimentarios son los m\u00e1s adecuados para representar las interacciones entre ellos y comprender los complejos efectos de la diversificaci\u00f3n<\/strong>.<\/p>\n<p><strong>Explora m\u00e1s a fondo<\/strong><\/p>\n<p><a href=\"https:\/\/phys.org\/news\/2022-02-varied-agricultural-production-women-dietary.html\">Correlaci\u00f3n entre la producci\u00f3n agr\u00edcola variada y la diversidad diet\u00e9tica de las mujeres<\/a><\/p>\n<p><strong>M\u00e1s informaci\u00f3n:<\/strong>&nbsp;Katharina Waha et al, The benefits and trade-offs of agricultural diversity for food security in low- and middle-income countries: A review of existing knowledge and evidence,&nbsp;<em>Global Food Security<\/em>&nbsp;(2022).&nbsp;<a href=\"https:\/\/dx.doi.org\/10.1016\/j.gfs.2022.100645\">DOI: 10.1016\/j.gfs.2022.100645<\/a><\/p>\n<p>Proporcionado por La Alianza de Bioversity International y el Centro Internacional de Agricultura Tropical<\/p>\n<h4><a href=\"https:\/\/phys.org\/news\/2022-08-home-gardens-gene-banks-sustain.html?utm_source=nwletter&amp;utm_medium=email&amp;utm_campaign=daily-nwletter\"><strong>Los huertos familiares son bancos de genes vivos que sostienen los medios de vida en Asia Central<\/strong><\/a><\/h4>\n<p>por la Alianza de Bioversity International y el Centro Internacional de Agricultura Tropical<\/p>\n<p>La investigaci\u00f3n sobre <strong>los huertos familiares ha demostrado el papel cr\u00edtico que desempe\u00f1an en los medios de vida y el sustento de los habitantes rurales de todo el mundo, pero poca atenci\u00f3n acad\u00e9mica se ha centrado en los huertos familiares en Asia Central<\/strong>, particularmente en la literatura en ingl\u00e9s.<\/p>\n<p>En un nuevo art\u00edculo publicado en&nbsp;<em>PLOS ONE<\/em>, los investigadores abordan esta brecha y <strong>muestran la rica<\/strong>&nbsp;<a href=\"https:\/\/phys.org\/tags\/diversity\/\">diversidad<\/a>, <strong>tanto dentro como entre especies, de \u00e1rboles frutales y de nueces que mantienen los jardineros caseros de Asia Central<\/strong>. Bas\u00e1ndose en entrevistas con administradores&nbsp;<a href=\"https:\/\/phys.org\/tags\/garden\/\">de huertos<\/a>&nbsp;caseros, los autores <strong>tambi\u00e9n muestran los v\u00ednculos entre los \u00e1rboles en estos jardines y sus parientes silvestres en los bosques cercanos<\/strong>.<\/p>\n<p><strong>La diversidad vegetal fluye entre bosques y jardines<\/strong><\/p>\n<p><strong>Los investigadores encontraron que los huertos familiares se establecieron en promedio entre 40 y 50 a\u00f1os antes de la<\/strong>&nbsp;<a href=\"https:\/\/phys.org\/tags\/data+collection\/\">recopilaci\u00f3n de datos<\/a>, es decir, durante el gobierno de la Uni\u00f3n Sovi\u00e9tica, <strong>con algunos huertos dom\u00e9sticos m\u00e1s antiguos de m\u00e1s de 70 a\u00f1os encontrados en<\/strong> Uzbekist\u00e1n y Kirguist\u00e1n, y algunos muy j\u00f3venes encontrados en Kirguist\u00e1n. En Tayikist\u00e1n, \u00ab<strong>estos \u00e1rboles han sido vitales para que las personas sobrevivan en tiempos de conflicto, y estos huertos familiares con \u00e1rboles y verduras desempe\u00f1an un papel importante para apoyar a las familias<\/strong>, <strong>proporcionando una gran cantidad de alimentos para el hogar, adem\u00e1s de los ingresos<\/strong>\u00ab, explica Barbara Vinceti, ec\u00f3loga&nbsp;<a href=\"https:\/\/phys.org\/tags\/forest\/\">forestal<\/a>&nbsp;y autora principal del estudio.<\/p>\n<p>Marl\u00e8ne Elias, cient\u00edfica principal de la Alianza de Bioversity International y el CIAT, dice que <strong>el papel de los huertos familiares en el mantenimiento y la protecci\u00f3n de una rica diversidad de especies de \u00e1rboles los convierte en \u00abbancos de genes vivos<\/strong>\u00ab.<\/p>\n<p>\u00ab<strong>Observamos los huertos familiares situados cerca de los bosques y examinamos c\u00f3mo se mueve el<\/strong>&nbsp;<a href=\"https:\/\/phys.org\/tags\/genetic+material\/\">material gen\u00e9tico<\/a>&nbsp;<strong>entre los bosques y los huertos familiares<\/strong>\u00ab, dijo Elias, y agreg\u00f3 que este <strong>flujo entre los dos es fundamental para mantener la diversidad de \u00e1rboles y \u00e1rboles varietales tanto en los huertos dom\u00e9sticos como en los bosques<\/strong>.<\/p>\n<p><strong>La diversidad local est\u00e1 en riesgo<\/strong><\/p>\n<p>Sin embargo, a pesar de esta rica diversidad, Vinceti advierte <strong>que las variedades extranjeras se han vuelto m\u00e1s comunes en los huertos familiares porque son cada vez m\u00e1s lucrativas<\/strong>. Las variedades de manzana y pera, en particular, est\u00e1n <strong>cada vez m\u00e1s amenazadas por la afluencia de variedades comerciales extranjeras<\/strong>.<\/p>\n<p>\u00ab<strong>Vimos una erosi\u00f3n significativa de las variedades de \u00e1rboles locales de especies clave a medida que m\u00e1s variedades provienen del exterior<\/strong>\u00ab, dijo Vinceti, y agreg\u00f3 que los <strong>ex\u00f3ticos comerciales que llegan de los Estados Unidos, Rusia y Europa estaban comenzando a reemplazar la diversidad local en los huertos familiares<\/strong>.<\/p>\n<p>\u00ab<strong>La gente ha estado administrando estos huertos familiares durante d\u00e9cadas porque sirven para varios prop\u00f3sitos<\/strong>\u00ab, dijo Vinceti. \u00abAhora que <strong>las variedades externas est\u00e1n surgiendo con alg\u00fan<\/strong>&nbsp;<a href=\"https:\/\/phys.org\/tags\/market+value\/\">valor de mercado<\/a>, <strong>las variedades tradicionales est\u00e1n en riesgo, y una vez que se pierde esa diversidad, se pierde para siempre<\/strong>\u00ab.<\/p>\n<p>La p\u00e9rdida de biodiversidad tiene graves repercusiones. Elias <strong>se\u00f1ala que las variedades adaptadas localmente incluyen informaci\u00f3n gen\u00e9tica valiosa que podr\u00eda ayudar a enfrentar desaf\u00edos como el cambio clim\u00e1tico o las infestaciones de plagas<\/strong>.<\/p>\n<p>Los investigadores sugirieron que, dado el inter\u00e9s que encontraron para&nbsp;<a href=\"https:\/\/phys.org\/tags\/younger+generations\/\">las generaciones m\u00e1s j\u00f3venes para mantener los huertos familiares<\/a>&nbsp;<strong>e incluso expandir el cultivo de \u00e1rboles frutales y de nueces, los esfuerzos para conservar la diversidad de especies de \u00e1rboles y las variedades locales deber\u00edan estar bien integrados en los programas nacionales de investigaci\u00f3n y extensi\u00f3n<\/strong>, para permitir que estos sistemas complejos contin\u00faen prosperando a pesar de las crecientes presiones.<\/p>\n<p><strong>Explora m\u00e1s a fondo<\/strong><\/p>\n<p><a href=\"https:\/\/phys.org\/news\/2022-08-ornamental-pollinators.html\">\u00bfQu\u00e9 plantas ornamentales funcionan mejor para los polinizadores?<\/a><\/p>\n<p><strong>M\u00e1s informaci\u00f3n:<\/strong>&nbsp;Barbara Vinceti et al, Huertos familiares de Asia Central: reservorios de diversidad de especies de \u00e1rboles frutales y de nueces,&nbsp;<em>PLOS ONE<\/em>&nbsp;(2022).&nbsp;<a href=\"https:\/\/dx.doi.org\/10.1371\/journal.pone.0271398\">DOI: 10.1371\/journal.pone.0271398<\/a><\/p>\n<h3>Im\u00e1genes Relacionadas:<\/h3>","protected":false},"excerpt":{"rendered":"<p>Fuente: Colaje im\u00e1genes Google Debemos preguntarnos y responder sinceramente que hemos ganado y que, perdido, al ir transformando la producci\u00f3n de alimentos en una empresa global, en la cual maximizar la productividad y la b\u00fasqueda de beneficios econ\u00f3micos son el fin en s\u00ed mismos. Las dos notas de prensa que os proporciono hoy dan fe de ello. La globalizaci\u00f3n econ\u00f3mica y como corolario tambi\u00e9n la agraria, ha destrozado grandes extensiones de espacios geogr\u00e1ficos sustentables, y generando inseguridad alimentaria en el mundo. Las agriculturas y huertos familiares proporcionaban abundantes beneficios tanto alimentarios como ecol\u00f3gicos, y sobre todo seguridad alimentaria. Por el\u2026<\/p>\n","protected":false},"author":26,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0},"categories":[586,618,591,599,613],"tags":[53135,46736,53136,53137,47308,2352],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":4}},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Fuente: Colaje im\u00e1genes Google Debemos preguntarnos y responder sinceramente que hemos ganado y que, perdido, al ir transformando la producci\u00f3n de alimentos en una empresa global, en la cual maximizar la productividad y la b\u00fasqueda de beneficios econ\u00f3micos son el fin en s\u00ed mismos. Las dos notas de prensa que os proporciono hoy dan fe\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Juan Jos\u00e9 Ib\u00e1\u00f1ez\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2023\/12\/13\/153505\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Un Universo invisible bajo nuestros pies - Los suelos y la vida\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Agricultura y Huertos Familiares, Diversidad y Seguridad Alimentaria: Una asociaci\u00f3n indisociable. - Un Universo invisible bajo nuestros pies\" \/>\n\t\t<meta property=\"og:description\" content=\"Fuente: Colaje im\u00e1genes Google Debemos preguntarnos y responder sinceramente que hemos ganado y que, perdido, al ir transformando la producci\u00f3n de alimentos en una empresa global, en la cual maximizar la productividad y la b\u00fasqueda de beneficios econ\u00f3micos son el fin en s\u00ed mismos. Las dos notas de prensa que os proporciono hoy dan fe\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2023\/12\/13\/153505\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2023-12-13T13:45:11+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2023-12-13T13:45:18+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/juan.j.marti.14\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Agricultura y Huertos Familiares, Diversidad y Seguridad Alimentaria: Una asociaci\u00f3n indisociable. - Un Universo invisible bajo nuestros pies\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Fuente: Colaje im\u00e1genes Google Debemos preguntarnos y responder sinceramente que hemos ganado y que, perdido, al ir transformando la producci\u00f3n de alimentos en una empresa global, en la cual maximizar la productividad y la b\u00fasqueda de beneficios econ\u00f3micos son el fin en s\u00ed mismos. Las dos notas de prensa que os proporciono hoy dan fe\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2023\\\/12\\\/13\\\/153505#blogposting\",\"name\":\"Agricultura y Huertos Familiares, Diversidad y Seguridad Alimentaria: Una asociaci\\u00f3n indisociable. - Un Universo invisible bajo nuestros pies\",\"headline\":\"Agricultura y Huertos Familiares, Diversidad y Seguridad Alimentaria: Una asociaci\\u00f3n indisociable.\",\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/wp-content\\\/blogs.dir\\\/42\\\/files\\\/255\\\/agrodiversidad-granjas-pequenas.jpg\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2023\\\/12\\\/13\\\/153505\\\/#articleImage\"},\"datePublished\":\"2023-12-13T14:45:11+01:00\",\"dateModified\":\"2023-12-13T14:45:18+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2023\\\/12\\\/13\\\/153505#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2023\\\/12\\\/13\\\/153505#webpage\"},\"articleSection\":\"Diversidad, Complejidad y Fractales, Ecolog\\u00eda y Biogeograf\\u00eda post posteriores a agosto de 2009, Edafolog\\u00eda y Pol\\u00edtica, Etnoedafolog\\u00eda y Conocimiento Campesino, Fertilidad de Suelos y Nutrici\\u00f3n Vegetal, agrodiversidad, Biodiversidad, granjas, lo peque\\u00f1o es hermoso, soberan\\u00eda alimentaria, Sustentabilidad\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2023\\\/12\\\/13\\\/153505#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/diversidad-complejidad-y-fractales#listItem\",\"name\":\"Diversidad, Complejidad y Fractales\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/diversidad-complejidad-y-fractales#listItem\",\"position\":2,\"name\":\"Diversidad, Complejidad y Fractales\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/diversidad-complejidad-y-fractales\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2023\\\/12\\\/13\\\/153505#listItem\",\"name\":\"Agricultura y Huertos Familiares, Diversidad y Seguridad Alimentaria: Una asociaci\\u00f3n indisociable.\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2023\\\/12\\\/13\\\/153505#listItem\",\"position\":3,\"name\":\"Agricultura y Huertos Familiares, Diversidad y Seguridad Alimentaria: Una asociaci\\u00f3n indisociable.\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/diversidad-complejidad-y-fractales#listItem\",\"name\":\"Diversidad, Complejidad y Fractales\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#organization\",\"name\":\"Un Universo invisible bajo nuestros pies\",\"description\":\"Los suelos y la vida\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/files\\\/2022\\\/02\\\/logo.png\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2023\\\/12\\\/13\\\/153505\\\/#organizationLogo\",\"width\":217,\"height\":72},\"image\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2023\\\/12\\\/13\\\/153505\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/juan.j.marti.14\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo\",\"name\":\"Juan Jos\\u00e9 Ib\\u00e1\\u00f1ez\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2023\\\/12\\\/13\\\/153505#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/387f3a100385573d8f42ce2a3211fd1c?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Juan Jos\\u00e9 Ib\\u00e1\\u00f1ez\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2023\\\/12\\\/13\\\/153505#webpage\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2023\\\/12\\\/13\\\/153505\",\"name\":\"Agricultura y Huertos Familiares, Diversidad y Seguridad Alimentaria: Una asociaci\\u00f3n indisociable. - Un Universo invisible bajo nuestros pies\",\"description\":\"Fuente: Colaje im\\u00e1genes Google Debemos preguntarnos y responder sinceramente que hemos ganado y que, perdido, al ir transformando la producci\\u00f3n de alimentos en una empresa global, en la cual maximizar la productividad y la b\\u00fasqueda de beneficios econ\\u00f3micos son el fin en s\\u00ed mismos. Las dos notas de prensa que os proporciono hoy dan fe\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2023\\\/12\\\/13\\\/153505#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\"},\"datePublished\":\"2023-12-13T14:45:11+01:00\",\"dateModified\":\"2023-12-13T14:45:18+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#website\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/\",\"name\":\"Un Universo invisible bajo nuestros pies\",\"description\":\"Los suelos y la vida\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Agricultura y Huertos Familiares, Diversidad y Seguridad Alimentaria: Una asociaci\u00f3n indisociable. - Un Universo invisible bajo nuestros pies","description":"Fuente: Colaje im\u00e1genes Google Debemos preguntarnos y responder sinceramente que hemos ganado y que, perdido, al ir transformando la producci\u00f3n de alimentos en una empresa global, en la cual maximizar la productividad y la b\u00fasqueda de beneficios econ\u00f3micos son el fin en s\u00ed mismos. Las dos notas de prensa que os proporciono hoy dan fe","canonical_url":"https:\/\/www.madrimasd.org\/blogs\/universo\/2023\/12\/13\/153505","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2023\/12\/13\/153505#blogposting","name":"Agricultura y Huertos Familiares, Diversidad y Seguridad Alimentaria: Una asociaci\u00f3n indisociable. - Un Universo invisible bajo nuestros pies","headline":"Agricultura y Huertos Familiares, Diversidad y Seguridad Alimentaria: Una asociaci\u00f3n indisociable.","author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author"},"publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-content\/blogs.dir\/42\/files\/255\/agrodiversidad-granjas-pequenas.jpg","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2023\/12\/13\/153505\/#articleImage"},"datePublished":"2023-12-13T14:45:11+01:00","dateModified":"2023-12-13T14:45:18+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2023\/12\/13\/153505#webpage"},"isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2023\/12\/13\/153505#webpage"},"articleSection":"Diversidad, Complejidad y Fractales, Ecolog\u00eda y Biogeograf\u00eda post posteriores a agosto de 2009, Edafolog\u00eda y Pol\u00edtica, Etnoedafolog\u00eda y Conocimiento Campesino, Fertilidad de Suelos y Nutrici\u00f3n Vegetal, agrodiversidad, Biodiversidad, granjas, lo peque\u00f1o es hermoso, soberan\u00eda alimentaria, Sustentabilidad"},{"@type":"BreadcrumbList","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2023\/12\/13\/153505#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo#listItem","position":1,"name":"Home","item":"https:\/\/www.madrimasd.org\/blogs\/universo","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/diversidad-complejidad-y-fractales#listItem","name":"Diversidad, Complejidad y Fractales"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/diversidad-complejidad-y-fractales#listItem","position":2,"name":"Diversidad, Complejidad y Fractales","item":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/diversidad-complejidad-y-fractales","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2023\/12\/13\/153505#listItem","name":"Agricultura y Huertos Familiares, Diversidad y Seguridad Alimentaria: Una asociaci\u00f3n indisociable."},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2023\/12\/13\/153505#listItem","position":3,"name":"Agricultura y Huertos Familiares, Diversidad y Seguridad Alimentaria: Una asociaci\u00f3n indisociable.","previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/diversidad-complejidad-y-fractales#listItem","name":"Diversidad, Complejidad y Fractales"}}]},{"@type":"Organization","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#organization","name":"Un Universo invisible bajo nuestros pies","description":"Los suelos y la vida","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/","logo":{"@type":"ImageObject","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2023\/12\/13\/153505\/#organizationLogo","width":217,"height":72},"image":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2023\/12\/13\/153505\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/juan.j.marti.14"]},{"@type":"Person","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo","name":"Juan Jos\u00e9 Ib\u00e1\u00f1ez","image":{"@type":"ImageObject","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2023\/12\/13\/153505#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/387f3a100385573d8f42ce2a3211fd1c?s=96&d=mm&r=g","width":96,"height":96,"caption":"Juan Jos\u00e9 Ib\u00e1\u00f1ez"}},{"@type":"WebPage","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2023\/12\/13\/153505#webpage","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/2023\/12\/13\/153505","name":"Agricultura y Huertos Familiares, Diversidad y Seguridad Alimentaria: Una asociaci\u00f3n indisociable. - Un Universo invisible bajo nuestros pies","description":"Fuente: Colaje im\u00e1genes Google Debemos preguntarnos y responder sinceramente que hemos ganado y que, perdido, al ir transformando la producci\u00f3n de alimentos en una empresa global, en la cual maximizar la productividad y la b\u00fasqueda de beneficios econ\u00f3micos son el fin en s\u00ed mismos. Las dos notas de prensa que os proporciono hoy dan fe","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#website"},"breadcrumb":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2023\/12\/13\/153505#breadcrumblist"},"author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author"},"creator":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author"},"datePublished":"2023-12-13T14:45:11+01:00","dateModified":"2023-12-13T14:45:18+01:00"},{"@type":"WebSite","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#website","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/","name":"Un Universo invisible bajo nuestros pies","description":"Los suelos y la vida","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Un Universo invisible bajo nuestros pies - Los suelos y la vida","og:type":"article","og:title":"Agricultura y Huertos Familiares, Diversidad y Seguridad Alimentaria: Una asociaci\u00f3n indisociable. - Un Universo invisible bajo nuestros pies","og:description":"Fuente: Colaje im\u00e1genes Google Debemos preguntarnos y responder sinceramente que hemos ganado y que, perdido, al ir transformando la producci\u00f3n de alimentos en una empresa global, en la cual maximizar la productividad y la b\u00fasqueda de beneficios econ\u00f3micos son el fin en s\u00ed mismos. Las dos notas de prensa que os proporciono hoy dan fe","og:url":"https:\/\/www.madrimasd.org\/blogs\/universo\/2023\/12\/13\/153505","og:image":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png","og:image:secure_url":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png","article:published_time":"2023-12-13T13:45:11+00:00","article:modified_time":"2023-12-13T13:45:18+00:00","article:publisher":"https:\/\/www.facebook.com\/juan.j.marti.14","twitter:card":"summary","twitter:title":"Agricultura y Huertos Familiares, Diversidad y Seguridad Alimentaria: Una asociaci\u00f3n indisociable. - Un Universo invisible bajo nuestros pies","twitter:description":"Fuente: Colaje im\u00e1genes Google Debemos preguntarnos y responder sinceramente que hemos ganado y que, perdido, al ir transformando la producci\u00f3n de alimentos en una empresa global, en la cual maximizar la productividad y la b\u00fasqueda de beneficios econ\u00f3micos son el fin en s\u00ed mismos. Las dos notas de prensa que os proporciono hoy dan fe","twitter:image":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png"},"aioseo_meta_data":{"post_id":"153505","title":null,"description":null,"keywords":[],"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":"{\"article\":{\"articleType\":\"BlogPosting\"},\"course\":{\"name\":\"\",\"description\":\"\",\"provider\":\"\"},\"faq\":{\"pages\":[]},\"product\":{\"reviews\":[]},\"recipe\":{\"ingredients\":[],\"instructions\":[],\"keywords\":[]},\"software\":{\"reviews\":[],\"operatingSystems\":[]},\"webPage\":{\"webPageType\":\"WebPage\"}}","pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","tabs":null,"priority":0,"frequency":"default","local_seo":null,"created":"2022-08-27 14:21:52","updated":"2026-05-26 20:05:53","limit_modified_date":false,"ai":null,"breadcrumb_settings":null,"seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/diversidad-complejidad-y-fractales\" title=\"Diversidad, Complejidad y Fractales\">Diversidad, Complejidad y Fractales<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tAgricultura y Huertos Familiares, Diversidad y Seguridad Alimentaria: Una asociaci\u00f3n indisociable.\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.madrimasd.org\/blogs\/universo"},{"label":"Diversidad, Complejidad y Fractales","link":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/diversidad-complejidad-y-fractales"},{"label":"Agricultura y Huertos Familiares, Diversidad y Seguridad Alimentaria: Una asociaci\u00f3n indisociable.","link":"https:\/\/www.madrimasd.org\/blogs\/universo\/2023\/12\/13\/153505"}],"_links":{"self":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts\/153505"}],"collection":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/comments?post=153505"}],"version-history":[{"count":3,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts\/153505\/revisions"}],"predecessor-version":[{"id":155143,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts\/153505\/revisions\/155143"}],"wp:attachment":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/media?parent=153505"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/categories?post=153505"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/tags?post=153505"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}