{"id":153577,"date":"2024-02-21T18:03:09","date_gmt":"2024-02-21T17:03:09","guid":{"rendered":"https:\/\/www.madrimasd.org\/blogs\/universo\/?p=153577"},"modified":"2024-02-21T18:03:09","modified_gmt":"2024-02-21T17:03:09","slug":"las-arcillas-y-el-origen-de-la-vida-teorias-del-origen-de-la-vida-de-ida-y-vuelta","status":"publish","type":"post","link":"https:\/\/www.madrimasd.org\/blogs\/universo\/2024\/02\/21\/153577","title":{"rendered":"Las arcillas y el Origen de la Vida: Teor\u00edas del Origen de la Vida de Ida y Vuelta"},"content":{"rendered":"<p style=\"text-align: center\"><img decoding=\"async\" class=\"ngg-singlepic ngg-center\" src=\"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-content\/blogs.dir\/42\/files\/396\/Illita-origen-de-la-vida.jpg\" alt=\"Illita-origen-de-la-vida\"><\/p>\n<p style=\"text-align: center\"><span style=\"color: #0000ff\">Fuente: Colaje im\u00e1genes Google<\/span><\/p>\n<p><a href=\"Helen%20Hansma\">Helen Hansma,<\/a> en su reciente art\u00edculo \u201c<a href=\"https:\/\/www.researchgate.net\/publication\/363766455_DNA_and_the_origins_of_life_in_micaceous_clay\">DNA and the origins of life in micaceous clay<\/a>\u201d &nbsp;(pichando el enlace pod\u00e9is bajarlo gratuitamente) defiende que la <a href=\"https:\/\/es.wikipedia.org\/wiki\/Illita\">Illita<\/a>, <span style=\"color: #3366ff\"><strong>una arcilla mic\u00e1cea<\/strong>, <strong>debi\u00f3 ser el lugar donde se sintetiz\u00f3 por primera vez la vida en la Tierra<\/strong><\/span>. La Illita resulta ser abundante en <span style=\"color: #3366ff\"><strong>sedimentos<\/strong>, <strong>suelos<\/strong><\/span>, rocas arcillosas sedimentarias, y rocas metam\u00f3rficas. \u00bfNovedad? \u00a1tan solo en parte! Y yo dir\u00eda que m\u00e1s bien poca: \u00bfHabr\u00e1 le\u00eddo Helen las investigaciones muy anteriores de Alexander? \u00a1Tras revisar por encina el art\u00edculo original parece ser que no! \u00a1<a href=\"https:\/\/es.quora.com\/Cu%C3%A1l-ser%C3%ADa-el-significado-de-la-expresi%C3%B3n-en-italiano-porca-miseria\">porca miseria<\/a>!. Eso s\u00ed, su amor incondicional por <a href=\"https:\/\/en.wikipedia.org\/wiki\/Nadrian_Seeman\">Nadrian Seeman<\/a>, uno de los padres del tipo de microscopia que utilizo en su estudio, parece infinito. \u00bfY Alexander? <a href=\"https:\/\/es.wikipedia.org\/wiki\/Alexander_Graham_Cairns-Smith\">Alexander Graham Cairns-Smith<\/a> (1931-2016)&nbsp; en su libro de<span style=\"color: #3366ff\"> <strong>1986<\/strong><\/span> <a href=\"https:\/\/www.alianzaeditorial.es\/libro\/ciencias\/siete-pistas-sobre-el-origen-de-la-vida-a-g-cairns-smith-9788420674445\/\">\u201cSiete pistas sobre el origen de la vida<\/a>\u201d, <span style=\"color: #3366ff\"><strong>hab\u00eda propuesto que el origen de la vida debi\u00f3 acaecer gracias a las arcillas<\/strong><\/span>. No recuerdo muchos detalles, pero se trata de una referencia inexcusable para cualquier experto que desee hablar del origen de la vida, y m\u00e1s a\u00fan si lo sit\u00faan en las propias arcillas. M\u00e1s aun, gran parte de la bibliograf\u00eda que cita Hellen es muy reciente, demasiado, para un tema tan debatido e importante en la literatura cient\u00edfica. <span style=\"color: #3366ff\"><strong>Este desprecio por los antecedentes resulta irritante y grave, siendo reprobable por la filosof\u00eda de la ciencia y los c\u00e1nones m\u00e1s aceptados del metodo cient\u00edfico<\/strong><\/span>. Helen se\u00f1ala que debi\u00f3 ser un tipo concreto de arcilla, descartando la <a href=\"https:\/\/es.wikipedia.org\/wiki\/Montmorillonita\">montmorillonita<\/a>, otra estructuralmente muy semejante. Pues bien, en el caso de que Alexander hubiera defendido o propuesto como principal candidato a la montmorillonita (no lo recuerdo), entonces el art\u00edculo debiera debido tener un t\u00edtulo parecido a \u201cEl Origen de la Vida surgi\u00f3 de la Illita, que no de la montmorillonita\u201d. Empero si no hizo referencia a un tipo concreto, cabr\u00e1 encabezar el manuscrito con una frase de la siguiente guisa: \u201cNuevas evidencias de que el origen de la vida \u201cpudo\u201d haber surgido en el seno de una arcilla mic\u00e1cea\u201d.&nbsp; Pero tal como se redact\u00f3, parece que ella propone una teor\u00eda nueva, sin que nadie antes hubiera tenido idea alguna sobre el tema. <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2021\/11\/11\/150045\">Muy t\u00edpico todo de los tecnocient\u00edficos<\/a>, a los que las lecturas que debieran no ser olvidadas les son abducidas dela mente, por razones no cient\u00edficas que hoy prefiero soslayar.<\/p>\n<p>La cuesti\u00f3n aqu\u00ed es que <b style=\"color: #3366ff\">tanto la Illita como la montmorillonita, son minerales <\/b><span style=\"color: #3366ff\"><b>arcillosos<\/b><\/span><b style=\"color: #3366ff\"> muy frecuentes en la g\u00e9nesis de suelos, es decir en los procesos que dan lugar en el medio ed\u00e1fico a partir la meteorizaci\u00f3n o intemperizaci\u00f3n de<\/b> <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2021\/04\/26\/150808\">los materiales parentales o rocas madres<\/a>. <span style=\"color: #3366ff\"><strong>Existen razones argumentativas como para pensar que en el seno de los protosuelos primigenios pudieron acaecer los or\u00edgenes de la vida<\/strong>.&nbsp; <strong>Empero parafraseando otro refr\u00e1n \u201chechos son amores que no las buenas razones\u201d. Y de este modo se han propuesto diversas conjeturas acerca del origen de la vida que recorren, no solo los diferentes recursos naturales<\/strong><\/span>, sino tambi\u00e9n los <a href=\"https:\/\/es.wikipedia.org\/wiki\/Panspermia\">cosmol\u00f3gicos<\/a>.&nbsp; En consecuencia, nada ha cambiado desde que escrib\u00ed el post: <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/03\/05\/138530\">Sobre los Posibles Or\u00edgenes de la Vida (Entre Jaimito y Mafalda)<\/a>.<\/p>\n<p><span style=\"color: #3366ff\"><strong>Cuatro aspectos colaterales, pero importantes, debemos recordar aqu\u00ed<\/strong>. <strong>(i)<\/strong><\/span> las referencias bibliogr\u00e1ficas correctas y concretas respecto al tema abordado son inexcusables en la redacci\u00f3n de un art\u00edculo cient\u00edfico; <span style=\"color: #3366ff\"><strong>(ii)<\/strong><\/span> Se deben detallar las hip\u00f3tesis, conjeturas o teor\u00edas alternativas<span style=\"color: #3366ff\"> <strong>(iii)<\/strong><\/span> No deben atribuirse m\u00e9ritos ajenos ya que se incurre en la mala praxis cient\u00edfica. Hellen \u00a1te has lucido! Y <span style=\"color: #3366ff\"><strong>(iv)<\/strong><\/span> Existen conjeturas que son propuestas recurrentemente: pasan de moda y son reemplazadas por otras, pero vuelven a surgir de nuevo como propuestas audaces decenios despu\u00e9s (por ejemplo, la extinci\u00f3n de los dinosaurios: \u00bfmeteoritos, o gran emisi\u00f3n de magma) <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2021\/11\/11\/150045\">Empero la tecnociencia, act\u00faa a ritmo de intereses, muchos de los cuales no tienen nada que ver con la ciencia<\/a>. Abajo os dejo unos pocos posts relacionados con el tema en los que hablo, como no, <strong>Alexander Graham Cairns-Smith<\/strong>, etc. Si, Jaimito ten\u00eda raz\u00f3n.<\/p>\n<p>Os dejo pues con la nota de prensa y el resumen (algo m\u00e1s) del art\u00edculo cient\u00edfico original.<\/p>\n<p><span style=\"color: #008000\"><strong>Juan Jos\u00e9 Ib\u00e1\u00f1ez<\/strong><\/span><\/p>\n<p><span style=\"color: #800000\"><em>Contin\u00faa\u2026\u2026\u2026.<\/em><\/span><\/p>\n<p><!--more--><\/p>\n<p><strong>Algunos posts relacionados con el tema<\/strong><\/p>\n<p><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2014\/07\/24\/144726\">Suelos, Carbono, Silicio y el Origen de la Vida<\/a><\/p>\n<p><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2006\/05\/18\/23530\">Los Suelos y el Origen de la Vida<\/a><\/p>\n<p><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2016\/02\/19\/146711\">Suelos Primigenios: Nuevas conjeturas sobre los or\u00edgenes de la invasi\u00f3n de la superficie de la Tierra por la vida<\/a><\/p>\n<p><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2012\/02\/16\/140168\">Las huellas digitales de la vida en el suelo y el origen del polvo atmosf\u00e9rico<\/a><\/p>\n<p><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/03\/05\/138530\">Sobre los Posibles Or\u00edgenes de la Vida (Entre Jaimito y Mafalda)<\/a><\/p>\n<p><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2009\/06\/20\/120522\">La Creatividad de los Cient\u00edficos y el Origen de Sus Teor\u00edas<\/a><\/p>\n<p><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2016\/12\/08\/147937\">Prostituyendo la Historia de la Ciencia (Ciencia Amn\u00e9sica e Imperio Anglosaj\u00f3n)<\/a><\/p>\n<h3><a href=\"https:\/\/www.vistaalmar.es\/ciencia-tecnologia\/biologia\/11364-tuvo-vida-comienzo-arcilla-micacea.html\">\u00bfTuvo la vida su comienzo en la arcilla mic\u00e1cea?<\/a><\/h3>\n<p>&nbsp;Publicado: 21 Septiembre 2022<\/p>\n<p>Los procesos metab\u00f3licos podr\u00edan haber sido confinados entre capas de mica<\/p>\n<p><strong>En las mitolog\u00edas e historias de origen de todo el mundo, varias culturas y religiones se\u00f1alan a la arcilla como el recipiente de la vida, el material primordial que los dioses creadores imbuyeron de una existencia autosuficiente<\/strong>. Hoy en d\u00eda tenemos la biolog\u00eda para explicar c\u00f3mo surge la vida, pero \u00bfPodr\u00edan estas antiguas leyendas dar m\u00e1s en el blanco de lo que pensamos?<\/p>\n<p>En un art\u00edculo escrito para conmemorar el trabajo de Ned Seeman, inventor del campo de la nanotecnolog\u00eda del ADN, la biof\u00edsica em\u00e9rita de la Universidad de California en Santa B\u00e1rbara,&nbsp;<a href=\"https:\/\/www.news.ucsb.edu\/2022\/020714\/life-imitates-mica\">Helen Hansma, describe su idea<\/a>&nbsp;de larga data de que <strong>esa vida primitiva, en arreglos precelulares que evolucionaron en nuestras c\u00e9lulas basadas en l\u00edpidos y prote\u00ednas, puede haber tenido su comienzo en la arcilla mic\u00e1cea, tambi\u00e9n conocida como<\/strong>&nbsp;<a href=\"https:\/\/es.wikipedia.org\/wiki\/Illita\">illita<\/a>.<\/p>\n<p><strong>Originalmente propuesta hace casi 16 a\u00f1os<\/strong>, la <a href=\"https:\/\/universitam.com\/academicos\/noticias\/helen-hansma-propone-hipotesis-de-que-la-vida-se-origino-entre-laminas-de-mica\/\">hip\u00f3tesis de Hansma<\/a> <strong>se une a muchas otras especulaciones sobre<\/strong>&nbsp;<a href=\"https:\/\/www.vistaalmar.es\/ciencia-tecnologia\/biologia\/7736-oxigeno-origen-vida-tierra.html\">c\u00f3mo surgi\u00f3 la vida en la Tierra<\/a><strong>. Entre ellas se encuentran el conocido \u00ab<\/strong><a href=\"https:\/\/es.wikipedia.org\/wiki\/Hip%C3%B3tesis_del_mundo_de_ARN\"><strong>Mundo del ARN<\/strong><\/a><strong>\u00ab<\/strong>, en el que las mol\u00e9culas de ARN autorreplicantes evolucionaron hasta convertirse en ADN y prote\u00ednas<strong>, y el concepto \u00abPrimero el metabolismo\u00bb, que dice que la vida evolucion\u00f3 a partir de reacciones qu\u00edmicas espont\u00e1neas<\/strong>.<\/p>\n<p>Tambi\u00e9n hay una <strong>hip\u00f3tesis de \u00abpizza\u00bb que afirma que la vida podr\u00eda haber venido de biomol\u00e9culas org\u00e1nicas terrestres<\/strong>. <strong>Y hay otras hip\u00f3tesis de arcilla que dicen que la vida puede haberse originado en arcilla de<\/strong>&nbsp;<a href=\"https:\/\/es.wikipedia.org\/wiki\/Montmorillonita\">montmorillonita<\/a>&nbsp;o arcillas ricas en hierro.<\/p>\n<p>Hansma no se propuso averiguar&nbsp;<a href=\"https:\/\/www.vistaalmar.es\/ciencia-tecnologia\/biologia\/7517-escala-tiempo-origen-evolucion-vida-tierra.html\">c\u00f3mo evolucion\u00f3 la vida en la Tierra<\/a>&nbsp;cuando se le ocurri\u00f3 la idea por primera vez. M\u00e1s bien, como biof\u00edsica investigadora y directora de programa en la Fundaci\u00f3n Nacional de Ciencias, alrededor de 2007 se entreten\u00eda con sus juguetes favoritos: un microscopio de disecci\u00f3n y piezas de mica que estaba dividiendo en l\u00e1minas.<\/p>\n<p>\u00ab<strong>Mientras miraba los trozos de algas verdes y la suciedad marr\u00f3n en los bordes de las l\u00e1minas de mica, pens\u00e9: &#8216;este ser\u00eda un buen lugar para que se originara la vida'\u00bb, dijo en un art\u00edculo escrito para NSF sobre su trabajo<\/strong>.<\/p>\n<p>Su idea incorpora elementos de otros conceptos <strong>de abiog\u00e9nesis (c\u00f3mo surgi\u00f3 la vida a partir de material no vivo)<\/strong>, afirmando que <strong>los precursores de las biomol\u00e9culas y los procesos metab\u00f3licos podr\u00edan haber sido acorralados<\/strong> <strong>entre capas de mica<\/strong>. Es un entorno que ofrec\u00eda cierta <strong>protecci\u00f3n del mundo exterior<\/strong>, <strong>pero que permit\u00eda el libre intercambio de agua y otras sustancias que ser\u00edan esenciales para las c\u00e9lulas<\/strong>.<\/p>\n<p>\u00ab<strong>Mi imagen es que las superficies de las l\u00e1minas de mica eran un gran lugar para que crecieran las mol\u00e9culas y se desarrollaran los procesos, y eventualmente todo lo necesario para la vida estaba en la mica<\/strong>\u00ab, dijo. Esencialmente, <strong>la mica actu\u00f3 como andamiaje y \u00abc\u00e1maras de reacci\u00f3n\u00bb, donde los procesos metab\u00f3licos podr\u00edan ocurrir y evolucionar<\/strong>.<\/p>\n<p><strong>La ventaja que tienen las arcillas de mica sobre la montmorillonita, agreg\u00f3 Hansma, es que las micas, con iones de potasio que mantienen unidas las l\u00e1minas de mica, no se hinchan y, por lo tanto, proporcionan un entorno m\u00e1s estable. Las l\u00e1minas de montmorillonita, por el contrario, se mantienen unidas por iones de sodio m\u00e1s peque\u00f1os, lo que provoca que se encojan y se hinchen durante los ciclos h\u00famedo-seco y un entorno menos estable<\/strong>.<\/p>\n<p><strong>La presencia de iones de potasio en la arcilla mic\u00e1cea es otro factor a favor de la hip\u00f3tesis de la arcilla de mica<\/strong>: las c\u00e9lulas de los seres vivos tienen altas concentraciones intracelulares de potasio, lo que hace que la mica sea <strong>\u00abun h\u00e1bitat m\u00e1s probable para el origen de la vida que la montmorillonita<\/strong>\u00ab.<\/p>\n<p><strong>\u00bfY de d\u00f3nde obtendr\u00eda este ensamblaje prebi\u00f3tico la energ\u00eda para interactuar y sostenerse en ausencia de la energ\u00eda bioqu\u00edmica que ahora alimenta nuestros cuerpos? En ese momento, la luz del sol habr\u00eda sido un candidato<\/strong>, sugiere Hansma, <strong>al igual que la energ\u00eda mec\u00e1nica, a trav\u00e9s de la apertura y el cierre de las l\u00e1minas de mica a medida que el agua entraba y sal\u00eda<\/strong>.<\/p>\n<p><strong><em>Imagen derecha<\/em><\/strong><em>: Un mundo de mica: diagramas del posible origen de la vida entre l\u00e1minas de mica. Las protoc\u00e9lulas, las grandes estructuras grises, tienen un protocitoplasma que es distinto del ambiente acuoso. Recuadro: en una etapa temprana en el mundo de la mica, se ven macromol\u00e9culas y ves\u00edculas lip\u00eddicas. Las ves\u00edculas est\u00e1n llenas de agua y algunas macromol\u00e9culas. Ten en cuenta el cambio de escala entre las etapas tempranas y posteriores. Las hojas de mica son verdes. Las l\u00edneas verdes en el recuadro son l\u00e1minas de mica individuales; los espacios en blanco entre las l\u00edneas verdes contienen K+ formando puentes con l\u00e1minas de mica adyacentes. El azul es el ambiente acuoso. Adaptado de Hansma (2010)<\/em><\/p>\n<p>\u00ab<strong>Parece ser que estos movimientos de abrir y cerrar eran formas de aplastar mol\u00e9culas, antes de que existiera la energ\u00eda qu\u00edmica<\/strong>\u00ab, dijo<strong>. Esta proximidad forzada podr\u00eda haber promovido interacciones entre las mol\u00e9culas, similares a las acciones de las enzimas en la actualidad<\/strong>. Las diferentes mol\u00e9culas que interact\u00faan se combinar\u00edan para formar ARN, ADN y prote\u00ednas. Los l\u00edpidos en la mezcla eventualmente envolver\u00edan los grupos de mol\u00e9culas grandes y se convertir\u00edan en la membrana celular.<\/p>\n<p>Estos son solo algunos de los argumentos de <strong>la hip\u00f3tesis de Hansma<\/strong> que se prestan a que <strong>la vida haya comenzado en la arcilla mic\u00e1cea<\/strong>; se puede encontrar otro apoyo <strong>en la vejez de la mica y en la afinidad del mineral por las biomol\u00e9culas y otros factores que se cree que han promovido el<\/strong>&nbsp;<a href=\"https:\/\/www.vistaalmar.es\/medio-ambiente\/biodiversidad\/10634-explora-evolucion-tierra-arbol-vida-mas-completo-jamas-creado.html\">desarrollo de la vida<\/a>&nbsp;a partir de mol\u00e9culas no vivas.<\/p>\n<p>Si bien no es probable que alguna vez sepamos con certeza qu\u00e9 sucedi\u00f3 hace casi 4 mil millones de a\u00f1os, <strong>est\u00e1 claro que, como dice Hansma, \u00abla vida imita a la mica de muchas maneras<\/strong>\u00ab.<\/p>\n<p>El art\u00edculo de Helen Hansma aparece en el&nbsp;<em>Biophysical Journal<\/em>:&nbsp;<a href=\"https:\/\/www.cell.com\/biophysj\/fulltext\/S0006-3495(22)00692-0\">DNA and the origins of life in micaceous clay<\/a><\/p>\n<p>Etiquetas:&nbsp;<a href=\"https:\/\/www.vistaalmar.es\/component\/search\/?searchword=Origen%20de%20la%20vida&amp;ordering=&amp;searchphrase=all\">Origen de la vida<\/a>&nbsp;\u2022&nbsp;<a href=\"https:\/\/www.vistaalmar.es\/component\/search\/?searchword=Arcilla&amp;ordering=&amp;searchphrase=all\">Arcilla<\/a>&nbsp;\u2022&nbsp;<a href=\"https:\/\/www.vistaalmar.es\/component\/search\/?searchword=Mica&amp;ordering=&amp;searchphrase=all\">Mica<\/a><\/p>\n<p>&nbsp;<\/p>\n<p><strong>Resumen del art\u00edculo de investigaci\u00f3n original<\/strong> (traducci\u00f3n autom\u00e1tica)<\/p>\n<p>RESUMEN<\/p>\n<p>La obtenci\u00f3n de im\u00e1genes reproducibles del ADN por microscop\u00eda de fuerza at\u00f3mica fue un \u00fatil predecesor de la nanotecnolog\u00eda de ADN de Ned Seeman. Muchos de los productos de la <strong>nanotecnolog\u00eda del ADN<\/strong> se obtuvieron im\u00e1genes en el microscopio de fuerza at\u00f3mica. <strong>El sustrato de mica utilizado en esta investigaci\u00f3n de microscop\u00eda de fuerza at\u00f3mica sirvi\u00f3 de inspiraci\u00f3n para la hip\u00f3tesis de que la arcilla mic\u00e1cea era un h\u00e1bitat probable para los or\u00edgenes de la vida. La arcilla de montmorillonita ha sido un sustrato exitoso para la polimerizaci\u00f3n de amino\u00e1cidos y nucle\u00f3tidos en p\u00e9ptidos y olig\u00f3meros de ADN en la investigaci\u00f3n sobre los or\u00edgenes de la vida<\/strong>. <strong>La mica y la montmorillonita tienen la misma red ani\u00f3nica, con un espaciado hexagonal de 0,5 nm<\/strong>. Las micas son arcillas que no se hinchan, con iones de potasio (K+) que mantienen unidas las l\u00e1minas de cristal, <strong>proporcionando un entorno estable para los procesos y complejos moleculares necesarios para la aparici\u00f3n de c\u00e9lulas vivas<\/strong>. Las l\u00e1minas de cristal de montmorillonita se mantienen unidas por iones de sodio m\u00e1s peque\u00f1os (Na+), lo que provoca que se hinchen y se encojan durante los ciclos h\u00famedo-seco, lo que genera un entorno menos estable. Adem\u00e1s, las c\u00e9lulas en todos los tipos de sistemas vivos tienen altas concentraciones intracelulares de K+, lo que <strong>hace que la mica sea un h\u00e1bitat m\u00e1s probable para los or\u00edgenes de la vida que la montmorillonita<\/strong>. Finalmente, las l\u00e1minas de mica en movimiento proporcionan mec\u00e1nica energ\u00eda en los bordes divididos de <strong>las hojas en los \u00ablibros\u00bb de mica<\/strong>. Esta energ\u00eda mec\u00e1nica de las hojas de mica, que se abre y se cierra, en respuesta al flujo de fluidos, <strong>puede haber precedido a la energ\u00eda qu\u00edmica en los or\u00edgenes de la vida, impulsando procesos prebi\u00f3ticos tempranos, como la formaci\u00f3n de enlaces covalentes, las interacciones de complejos moleculares y la germinaci\u00f3n de protoc\u00e9lulas antes del mecanismo molecular de la divisi\u00f3n celular hab\u00eda desarrollado<\/strong>.<\/p>\n<p><strong>INTRODUCCI\u00d3N<\/strong><\/p>\n<p>\u00a1<strong>Ned Seeman era demasiado joven para morir <\/strong>(o, Nadrian Seeman, como se le nombra en el 99% de sus publicaciones en Google Scholar)! <strong>\u00c9l y yo nacimos con d\u00edas de diferencia<\/strong>. Recuerdo la emoci\u00f3n en el laboratorio cuando nos enteramos de <strong>su art\u00edculo de Nature de 1991 sobre la s\u00edntesis de un cubo de ADN (1), que inici\u00f3 el campo de la nanotecnolog\u00eda de ADN (2)<\/strong>.<\/p>\n<p><strong>Conoc\u00ed a Ned Seeman en SUNY Albany<\/strong> en la 21.\u00aa conversaci\u00f3n de Ramaswamy Sarma en junio de <strong>1999<\/strong>. Jeff Gelles y yo dimos charlas en la sesi\u00f3n sobre \u00abIm\u00e1genes a nivel molecular\u00bb, Gelles sobre \u00abMecanismos de transcripci\u00f3n y regulaci\u00f3n de la transcripci\u00f3n en Mol\u00e9culas individuales de ARN polimerasa\u201d, y yo sobre \u201cNuevos conocimientos de la fuerza at\u00f3mica Microscop\u00eda de ADN\u2019\u2019 (3,4). M\u00e1s tarde esa tarde, Laura Landweber, Erik Winfree y Ned Seeman dieron charlas en la sesi\u00f3n sobre \u00abComputaci\u00f3n de ADN y ARN\u00bb, Landweber sobre \u00abComputaci\u00f3n con ARN\u00bb, Winfree sobre \u00abAutoensamblaje algor\u00edtmico de ADN\u00bb, &#8216; y Seeman en &#8216;Dos dimensiones y Two States in DNA Nanotechnology\u2019\u2019 (3,5,6). de Seeman La publicaci\u00f3n sobre esta charla comienza con una cita de un poeta ingl\u00e9s: \u2018\u2018. <strong>reba\u00f1o de profetas locos, que con mirar un cristal pueden llenarlo de m\u00e1s fantas\u00edas que arenques hay en el mar<\/strong>. Alfred Noyes\u2019\u2019 (6).<\/p>\n<p>Gran parte del trabajo sobre nanotecnolog\u00eda de ADN y ARN utiliz\u00f3 im\u00e1genes de microscop\u00eda de fuerza at\u00f3mica (AFM), que se benefici\u00f3 de \u00abIm\u00e1genes reproducibles y disecci\u00f3n de ADN pl\u00e1smido bajo l\u00edquido con el microscopio de fuerza at\u00f3mica\u00bb (Fig. 1) (7). Dos proyectos que utilizaron im\u00e1genes AFM fueron \u00abDise\u00f1o y autoensamblaje de cristales de ADN bidimensionales\u00bb en 1998 (8) y \u201cConstrucci\u00f3n de rompecabezas programables con ARN\u201d en 2004 (9) (Fig. 2).<\/p>\n<p><strong>El art\u00edculo m\u00e1s memorable, para m\u00ed<\/strong>, fue el de Rothemund \u00abFolding DNA to create nanoscale patterns and patterns\u00bb.<\/p>\n<p><strong>IMPORTANCIA<\/strong> La <strong>microscop\u00eda de fuerza at\u00f3mica<\/strong> es una t\u00e9cnica valiosa para obtener im\u00e1genes de ADN y otras mol\u00e9culas biol\u00f3gicas al escanear una punta de un lado a otro de una muestra para generar un \u00abmapa\u00bb tridimensional de la superficie y las mol\u00e9culas en ella. <strong>La microscop\u00eda de fuerza at\u00f3mica ha sido \u00fatil para obtener im\u00e1genes de nuevas estructuras de ADN y ARN en la superficie de la mica<\/strong>, que es at\u00f3micamente plana. <strong>Mica es tambi\u00e9n un posible lugar donde podr\u00edan haber tenido lugar los or\u00edgenes de la vida<\/strong>. Una de las ventajas de la mica es que sus l\u00e1minas minerales se mantienen unidas por iones de potasio, y los iones de potasio tambi\u00e9n est\u00e1n presentes en grandes cantidades en las c\u00e9lulas de los organismos vivos de todo tipo. <strong>El origen de la vida es un gran rompecabezas cient\u00edfico<\/strong>\u2026\u2026<\/p>\n<h3>Im\u00e1genes Relacionadas:<\/h3>","protected":false},"excerpt":{"rendered":"<p>Fuente: Colaje im\u00e1genes Google Helen Hansma, en su reciente art\u00edculo \u201cDNA and the origins of life in micaceous clay\u201d &nbsp;(pichando el enlace pod\u00e9is bajarlo gratuitamente) defiende que la Illita, una arcilla mic\u00e1cea, debi\u00f3 ser el lugar donde se sintetiz\u00f3 por primera vez la vida en la Tierra. La Illita resulta ser abundante en sedimentos, suelos, rocas arcillosas sedimentarias, y rocas metam\u00f3rficas. \u00bfNovedad? \u00a1tan solo en parte! Y yo dir\u00eda que m\u00e1s bien poca: \u00bfHabr\u00e1 le\u00eddo Helen las investigaciones muy anteriores de Alexander? \u00a1Tras revisar por encina el art\u00edculo original parece ser que no! \u00a1porca miseria!. Eso s\u00ed, su amor incondicional\u2026<\/p>\n","protected":false},"author":26,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0},"categories":[596,618,597,607,617],"tags":[53211,53210,53209,46922],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":4}},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Fuente: Colaje im\u00e1genes Google Helen Hansma, en su reciente art\u00edculo \u201cDNA and the origins of life in micaceous clay\u201d (pichando el enlace pod\u00e9is bajarlo gratuitamente) defiende que la Illita, una arcilla mic\u00e1cea, debi\u00f3 ser el lugar donde se sintetiz\u00f3 por primera vez la vida en la Tierra. La Illita resulta ser abundante en sedimentos, suelos,\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Juan Jos\u00e9 Ib\u00e1\u00f1ez\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2024\/02\/21\/153577\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Un Universo invisible bajo nuestros pies - Los suelos y la vida\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Las arcillas y el Origen de la Vida: Teor\u00edas del Origen de la Vida de Ida y Vuelta - Un Universo invisible bajo nuestros pies\" \/>\n\t\t<meta property=\"og:description\" content=\"Fuente: Colaje im\u00e1genes Google Helen Hansma, en su reciente art\u00edculo \u201cDNA and the origins of life in micaceous clay\u201d (pichando el enlace pod\u00e9is bajarlo gratuitamente) defiende que la Illita, una arcilla mic\u00e1cea, debi\u00f3 ser el lugar donde se sintetiz\u00f3 por primera vez la vida en la Tierra. La Illita resulta ser abundante en sedimentos, suelos,\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2024\/02\/21\/153577\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2024-02-21T17:03:09+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2024-02-21T17:03:09+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/juan.j.marti.14\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Las arcillas y el Origen de la Vida: Teor\u00edas del Origen de la Vida de Ida y Vuelta - Un Universo invisible bajo nuestros pies\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Fuente: Colaje im\u00e1genes Google Helen Hansma, en su reciente art\u00edculo \u201cDNA and the origins of life in micaceous clay\u201d (pichando el enlace pod\u00e9is bajarlo gratuitamente) defiende que la Illita, una arcilla mic\u00e1cea, debi\u00f3 ser el lugar donde se sintetiz\u00f3 por primera vez la vida en la Tierra. La Illita resulta ser abundante en sedimentos, suelos,\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2024\\\/02\\\/21\\\/153577#blogposting\",\"name\":\"Las arcillas y el Origen de la Vida: Teor\\u00edas del Origen de la Vida de Ida y Vuelta - Un Universo invisible bajo nuestros pies\",\"headline\":\"Las arcillas y el Origen de la Vida: Teor\\u00edas del Origen de la Vida de Ida y Vuelta\",\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/wp-content\\\/blogs.dir\\\/42\\\/files\\\/396\\\/Illita-origen-de-la-vida.jpg\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2024\\\/02\\\/21\\\/153577\\\/#articleImage\"},\"datePublished\":\"2024-02-21T18:03:09+01:00\",\"dateModified\":\"2024-02-21T18:03:09+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2024\\\/02\\\/21\\\/153577#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2024\\\/02\\\/21\\\/153577#webpage\"},\"articleSection\":\"Biolog\\u00eda y Ecolog\\u00eda del Suelo, Ecolog\\u00eda y Biogeograf\\u00eda post posteriores a agosto de 2009, Filosof\\u00eda, Historia y Sociolog\\u00eda de la Edafolog\\u00eda, Historia de la Tierra y de los Suelos., Procesos Superficiales terrestres: Relieve, Geomorfolog\\u00eda y Cuencas de Drenaje:, arcillas mic\\u00e1ceas, candidata, Illita, origen de la vida\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2024\\\/02\\\/21\\\/153577#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/biologia-y-ecologia-del-suelo#listItem\",\"name\":\"Biolog\\u00eda y Ecolog\\u00eda del Suelo\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/biologia-y-ecologia-del-suelo#listItem\",\"position\":2,\"name\":\"Biolog\\u00eda y Ecolog\\u00eda del Suelo\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/biologia-y-ecologia-del-suelo\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2024\\\/02\\\/21\\\/153577#listItem\",\"name\":\"Las arcillas y el Origen de la Vida: Teor\\u00edas del Origen de la Vida de Ida y Vuelta\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2024\\\/02\\\/21\\\/153577#listItem\",\"position\":3,\"name\":\"Las arcillas y el Origen de la Vida: Teor\\u00edas del Origen de la Vida de Ida y Vuelta\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/biologia-y-ecologia-del-suelo#listItem\",\"name\":\"Biolog\\u00eda y Ecolog\\u00eda del Suelo\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#organization\",\"name\":\"Un Universo invisible bajo nuestros pies\",\"description\":\"Los suelos y la vida\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/files\\\/2022\\\/02\\\/logo.png\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2024\\\/02\\\/21\\\/153577\\\/#organizationLogo\",\"width\":217,\"height\":72},\"image\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2024\\\/02\\\/21\\\/153577\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/juan.j.marti.14\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo\",\"name\":\"Juan Jos\\u00e9 Ib\\u00e1\\u00f1ez\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2024\\\/02\\\/21\\\/153577#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/387f3a100385573d8f42ce2a3211fd1c?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Juan Jos\\u00e9 Ib\\u00e1\\u00f1ez\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2024\\\/02\\\/21\\\/153577#webpage\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2024\\\/02\\\/21\\\/153577\",\"name\":\"Las arcillas y el Origen de la Vida: Teor\\u00edas del Origen de la Vida de Ida y Vuelta - Un Universo invisible bajo nuestros pies\",\"description\":\"Fuente: Colaje im\\u00e1genes Google Helen Hansma, en su reciente art\\u00edculo \\u201cDNA and the origins of life in micaceous clay\\u201d (pichando el enlace pod\\u00e9is bajarlo gratuitamente) defiende que la Illita, una arcilla mic\\u00e1cea, debi\\u00f3 ser el lugar donde se sintetiz\\u00f3 por primera vez la vida en la Tierra. La Illita resulta ser abundante en sedimentos, suelos,\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2024\\\/02\\\/21\\\/153577#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\"},\"datePublished\":\"2024-02-21T18:03:09+01:00\",\"dateModified\":\"2024-02-21T18:03:09+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#website\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/\",\"name\":\"Un Universo invisible bajo nuestros pies\",\"description\":\"Los suelos y la vida\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Las arcillas y el Origen de la Vida: Teor\u00edas del Origen de la Vida de Ida y Vuelta - Un Universo invisible bajo nuestros pies","description":"Fuente: Colaje im\u00e1genes Google Helen Hansma, en su reciente art\u00edculo \u201cDNA and the origins of life in micaceous clay\u201d (pichando el enlace pod\u00e9is bajarlo gratuitamente) defiende que la Illita, una arcilla mic\u00e1cea, debi\u00f3 ser el lugar donde se sintetiz\u00f3 por primera vez la vida en la Tierra. La Illita resulta ser abundante en sedimentos, suelos,","canonical_url":"https:\/\/www.madrimasd.org\/blogs\/universo\/2024\/02\/21\/153577","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2024\/02\/21\/153577#blogposting","name":"Las arcillas y el Origen de la Vida: Teor\u00edas del Origen de la Vida de Ida y Vuelta - Un Universo invisible bajo nuestros pies","headline":"Las arcillas y el Origen de la Vida: Teor\u00edas del Origen de la Vida de Ida y Vuelta","author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author"},"publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-content\/blogs.dir\/42\/files\/396\/Illita-origen-de-la-vida.jpg","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2024\/02\/21\/153577\/#articleImage"},"datePublished":"2024-02-21T18:03:09+01:00","dateModified":"2024-02-21T18:03:09+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2024\/02\/21\/153577#webpage"},"isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2024\/02\/21\/153577#webpage"},"articleSection":"Biolog\u00eda y Ecolog\u00eda del Suelo, Ecolog\u00eda y Biogeograf\u00eda post posteriores a agosto de 2009, Filosof\u00eda, Historia y Sociolog\u00eda de la Edafolog\u00eda, Historia de la Tierra y de los Suelos., Procesos Superficiales terrestres: Relieve, Geomorfolog\u00eda y Cuencas de Drenaje:, arcillas mic\u00e1ceas, candidata, Illita, origen de la vida"},{"@type":"BreadcrumbList","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2024\/02\/21\/153577#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo#listItem","position":1,"name":"Home","item":"https:\/\/www.madrimasd.org\/blogs\/universo","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/biologia-y-ecologia-del-suelo#listItem","name":"Biolog\u00eda y Ecolog\u00eda del Suelo"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/biologia-y-ecologia-del-suelo#listItem","position":2,"name":"Biolog\u00eda y Ecolog\u00eda del Suelo","item":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/biologia-y-ecologia-del-suelo","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2024\/02\/21\/153577#listItem","name":"Las arcillas y el Origen de la Vida: Teor\u00edas del Origen de la Vida de Ida y Vuelta"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2024\/02\/21\/153577#listItem","position":3,"name":"Las arcillas y el Origen de la Vida: Teor\u00edas del Origen de la Vida de Ida y Vuelta","previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/biologia-y-ecologia-del-suelo#listItem","name":"Biolog\u00eda y Ecolog\u00eda del Suelo"}}]},{"@type":"Organization","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#organization","name":"Un Universo invisible bajo nuestros pies","description":"Los suelos y la vida","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/","logo":{"@type":"ImageObject","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2024\/02\/21\/153577\/#organizationLogo","width":217,"height":72},"image":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2024\/02\/21\/153577\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/juan.j.marti.14"]},{"@type":"Person","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo","name":"Juan Jos\u00e9 Ib\u00e1\u00f1ez","image":{"@type":"ImageObject","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2024\/02\/21\/153577#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/387f3a100385573d8f42ce2a3211fd1c?s=96&d=mm&r=g","width":96,"height":96,"caption":"Juan Jos\u00e9 Ib\u00e1\u00f1ez"}},{"@type":"WebPage","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2024\/02\/21\/153577#webpage","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/2024\/02\/21\/153577","name":"Las arcillas y el Origen de la Vida: Teor\u00edas del Origen de la Vida de Ida y Vuelta - Un Universo invisible bajo nuestros pies","description":"Fuente: Colaje im\u00e1genes Google Helen Hansma, en su reciente art\u00edculo \u201cDNA and the origins of life in micaceous clay\u201d (pichando el enlace pod\u00e9is bajarlo gratuitamente) defiende que la Illita, una arcilla mic\u00e1cea, debi\u00f3 ser el lugar donde se sintetiz\u00f3 por primera vez la vida en la Tierra. La Illita resulta ser abundante en sedimentos, suelos,","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#website"},"breadcrumb":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2024\/02\/21\/153577#breadcrumblist"},"author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author"},"creator":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author"},"datePublished":"2024-02-21T18:03:09+01:00","dateModified":"2024-02-21T18:03:09+01:00"},{"@type":"WebSite","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#website","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/","name":"Un Universo invisible bajo nuestros pies","description":"Los suelos y la vida","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Un Universo invisible bajo nuestros pies - Los suelos y la vida","og:type":"article","og:title":"Las arcillas y el Origen de la Vida: Teor\u00edas del Origen de la Vida de Ida y Vuelta - Un Universo invisible bajo nuestros pies","og:description":"Fuente: Colaje im\u00e1genes Google Helen Hansma, en su reciente art\u00edculo \u201cDNA and the origins of life in micaceous clay\u201d (pichando el enlace pod\u00e9is bajarlo gratuitamente) defiende que la Illita, una arcilla mic\u00e1cea, debi\u00f3 ser el lugar donde se sintetiz\u00f3 por primera vez la vida en la Tierra. La Illita resulta ser abundante en sedimentos, suelos,","og:url":"https:\/\/www.madrimasd.org\/blogs\/universo\/2024\/02\/21\/153577","og:image":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png","og:image:secure_url":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png","article:published_time":"2024-02-21T17:03:09+00:00","article:modified_time":"2024-02-21T17:03:09+00:00","article:publisher":"https:\/\/www.facebook.com\/juan.j.marti.14","twitter:card":"summary","twitter:title":"Las arcillas y el Origen de la Vida: Teor\u00edas del Origen de la Vida de Ida y Vuelta - Un Universo invisible bajo nuestros pies","twitter:description":"Fuente: Colaje im\u00e1genes Google Helen Hansma, en su reciente art\u00edculo \u201cDNA and the origins of life in micaceous clay\u201d (pichando el enlace pod\u00e9is bajarlo gratuitamente) defiende que la Illita, una arcilla mic\u00e1cea, debi\u00f3 ser el lugar donde se sintetiz\u00f3 por primera vez la vida en la Tierra. La Illita resulta ser abundante en sedimentos, suelos,","twitter:image":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png"},"aioseo_meta_data":{"post_id":"153577","title":null,"description":null,"keywords":[],"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":"{\"article\":{\"articleType\":\"BlogPosting\"},\"course\":{\"name\":\"\",\"description\":\"\",\"provider\":\"\"},\"faq\":{\"pages\":[]},\"product\":{\"reviews\":[]},\"recipe\":{\"ingredients\":[],\"instructions\":[],\"keywords\":[]},\"software\":{\"reviews\":[],\"operatingSystems\":[]},\"webPage\":{\"webPageType\":\"WebPage\"}}","pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","tabs":null,"priority":0,"frequency":"default","local_seo":null,"created":"2022-09-25 13:20:00","updated":"2026-05-26 20:08:48","limit_modified_date":false,"ai":null,"breadcrumb_settings":null,"seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/biologia-y-ecologia-del-suelo\" title=\"Biolog\u00eda y Ecolog\u00eda del Suelo\">Biolog\u00eda y Ecolog\u00eda del Suelo<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tLas arcillas y el Origen de la Vida: Teor\u00edas del Origen de la Vida de Ida y Vuelta\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.madrimasd.org\/blogs\/universo"},{"label":"Biolog\u00eda y Ecolog\u00eda del Suelo","link":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/biologia-y-ecologia-del-suelo"},{"label":"Las arcillas y el Origen de la Vida: Teor\u00edas del Origen de la Vida de Ida y Vuelta","link":"https:\/\/www.madrimasd.org\/blogs\/universo\/2024\/02\/21\/153577"}],"_links":{"self":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts\/153577"}],"collection":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/comments?post=153577"}],"version-history":[{"count":3,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts\/153577\/revisions"}],"predecessor-version":[{"id":155348,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts\/153577\/revisions\/155348"}],"wp:attachment":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/media?parent=153577"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/categories?post=153577"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/tags?post=153577"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}