{"id":154346,"date":"2023-05-18T13:29:59","date_gmt":"2023-05-18T12:29:59","guid":{"rendered":"https:\/\/www.madrimasd.org\/blogs\/universo\/?p=154346"},"modified":"2023-05-18T13:30:31","modified_gmt":"2023-05-18T12:30:31","slug":"la-estructura-del-universo-y-el-pensamiento-paretiano-que-aporta-la-edafologia","status":"publish","type":"post","link":"https:\/\/www.madrimasd.org\/blogs\/universo\/2023\/05\/18\/154346","title":{"rendered":"La Estructura del Universo y el pensamiento Paretiano (\u00bfQu\u00e9 aporta la edafolog\u00eda?)"},"content":{"rendered":"<p style=\"text-align: center\"><img decoding=\"async\" class=\"ngg-singlepic ngg-center\" src=\"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-content\/blogs.dir\/42\/files\/189\/Universo-distribucion-paretiana.jpg\" alt=\"Universo-distribucion-paretiana\"><\/p>\n<p style=\"text-align: center\"><span style=\"color: #0000ff\">Fuente: Colaje im\u00e1genes Google<\/span><\/p>\n<p><em>\u201c<\/em><a href=\"https:\/\/www.agenciasinc.es\/Noticias\/Asi-se-formaron-objetos-muy-masivos-en-los-primeros-instantes-de-vida-del-universo\"><em>As\u00ed se formaron objetos muy masivos en los primeros instantes de vida del universo<\/em><\/a><em>\u201d. <\/em>Este es el titulo traducido al espa\u00f1ol del original anglosaj\u00f3n del que os vamos a hablar hoy. En principio, no tiene nada que ver con las noticias que solemos incluir en nuestro blog, pero \u201csolo en principio\u201d. Poque si releemos los siguientes post:\u201d <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2014\/09\/20\/145327\">El Pensamiento Logar\u00edtmico y la Estructura de la Naturaleza<\/a> \u201d; \u201c<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2022\/05\/25\/151570\">Ley De la Geograf\u00eda y el An\u00e1lisis Geoespacial: Las Distribuciones de Cola Larga<\/a>\u201d;&nbsp; \u201c<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2022\/06\/23\/151650\">Taxonom\u00edas Gen\u00e9ticas de Ida y Vuelta: Tendencias en las Clasificaciones de Suelos y Minerales<\/a>\u201d, etc. comenzar\u00e9is a entender las razones de esta entradilla\u201d. Pero hay m\u00e1s, ya que este asunto o dilema ha sido piedra angular en los \u00faltimos a\u00f1os de mi trayectoria profesional y las publicaciones que he realizado.&nbsp; Por ejemplo, <span style=\"color: #3366ff\"><strong>planteo con toda la crudeza y abundante informaci\u00f3n procedente de las m\u00e1s diversas disciplinas que la estructura de la materia en la naturaleza y de nuestro pensamiento es esencialmente Paretiano<\/strong><\/span>, o dicho de otro modo, se ajusta \u201c<a href=\"https:\/\/es.wikipedia.org\/wiki\/Larga_cola#:~:text=La%20larga%20cola%20en%20estad%C3%ADstica,-La%20larga%20estela&amp;text=Estas%20distribuciones%20son%20semejantes%20al,la%20poblaci%C3%B3n%20que%20disminuye%20gradualmente.\">Distribuciones de colas largas<\/a>, \u201d, que no a las cl\u00e1sicas curvas de <a href=\"https:\/\/es.wikipedia.org\/wiki\/Funci%C3%B3n_gaussiana\">las distribuciones gaussianas<\/a>&nbsp; <span style=\"color: #3366ff\"><strong>o \u201cnormales\u201d<\/strong><\/span> y sus t\u00f3picas gr\u00e1ficas, como algunas del colaje de fotos que da pie a este post. Es decir, la famosa <a href=\"https:\/\/es.wikipedia.org\/wiki\/Distribuci%C3%B3n_normal\">campa\u00f1a de Gauss<\/a> parece ser abrumadoramente habitual al aplicar muchas pruebas estad\u00edsticas la denominada \u201c<a href=\"https:\/\/statologos.com\/asuncion-de-normalidad\/\">asunci\u00f3n de normalidad<\/a>\u201d.<\/p>\n<p><span style=\"color: #3366ff\"><strong>Me he preguntado durante decenios, porque en estad\u00edstica se considera a la distribuci\u00f3n normal como algo \u201cnormal\u201d o natural. Personalmente yo no he topado con ella ninguna vez<\/strong><\/span>. Sin embargo, se trata de <span style=\"color: #3366ff\"><strong>un<\/strong><\/span> \u201c<a href=\"https:\/\/es.wikipedia.org\/wiki\/Meme_(cultura)\">meme<\/a>\u201d cient\u00edfico que, al parecer <strong><span style=\"color: #3366ff\">lo llevamos gravado en nuestro sistema cognitivo a base insistir<\/span><\/strong> \u201cque la normalidad con la sangre de la insistencia entra\u201d. Har\u00e1 unos 15 o m\u00e1s a\u00f1os, en un congreso sobre matem\u00e1ticas aplicadas al an\u00e1lisis de medios porosos heterog\u00e9neos, en mi ponencia espet\u00e9: \u201csi casi todas las bases de datos que estudiamos se ajustan mejor a una ley de escala que a una distribuci\u00f3n normal, <span style=\"color: #3366ff\"><strong>\u00bfPor qu\u00e9 no escalarizamos en lugar de normalizar?<\/strong><\/span>\u201d. Todos los asistentes sab\u00edan a que me refer\u00eda, pero aguadaron el m\u00e1s absoluto silencio.&nbsp; M\u00e1s concretamente, defend\u00eda y defiendo que <span style=\"color: #3366ff\"><strong>en la naturaleza&nbsp; dominan las denominadas<\/strong><\/span> \u201c<a href=\"https:\/\/es.wikipedia.org\/wiki\/Larga_cola#:~:text=La%20larga%20cola%20en%20estad%C3%ADstica,-La%20larga%20estela&amp;text=Estas%20distribuciones%20son%20semejantes%20al,la%20poblaci%C3%B3n%20que%20disminuye%20gradualmente.\">Distribuciones de colas largas<\/a>\u201d. &nbsp;&nbsp;<\/p>\n<p>Y har\u00e1 tres a\u00f1os, en un ardiente verano, me propuse profundizar m\u00e1s aun en el tema, cuyos resultados fueron publicados en dos trabajos que llevaban por t\u00edtulo: \u201c<a href=\"https:\/\/bsssjournals.onlinelibrary.wiley.com\/doi\/abs\/10.1111\/ejss.13031\">Exploring the scaling law of geographical space: Gaussian versus Paretian thinking<\/a>\u201d (\u201c<a href=\"https:\/\/www.researchgate.net\/publication\/343225932_Exploring_the_Scaling_Law_of_Geographical_Space_Gaussian_versus_Paretian_thinking\">Explorando la Ley de Escala del Espacio Geogr\u00e1fico: Pensamiento Gaussiano versus Pareto<\/a>\u201d) y &nbsp;\u201c<a href=\"https:\/\/bsssjournals.onlinelibrary.wiley.com\/doi\/abs\/10.1111\/ejss.13035\">Land system diversity, scaling laws and polygons map analysis<\/a>\u201d. El segundo art\u00edculo no deja de ser m\u00e1s que un apoyo emp\u00edrico al primero. En cualquier caso, mis \u201ccalurosas\u201d indagaciones estivales me dejaron bastante at\u00f3nito, ya que <strong><span style=\"color: #3366ff\">constat\u00e9 que otros muchos colegas de las m\u00e1s disparatadas disciplinas como la econom\u00eda y crisis del mercado, la frecuencia con que se usan las palabras de un idioma en un libro, y desde otras ramas del conocimiento que no pod\u00e9is ni imaginar hab\u00edan topado con el mismo dilema. \u00bfQu\u00e9 ocurre?, me pregunto yo.<\/span><\/strong><\/p>\n<p>Pues bien, un d\u00eda antes de redactar este post me lleg\u00f3 una noticia que daba cuenta de como los autores publicaron <span style=\"color: #3366ff\"><strong>un estudio cosmol\u00f3gico<\/strong><\/span> (abajo os lo muestro traducido) acerca de c\u00f3mo hab\u00edan logrado <span style=\"color: #3366ff\"><strong>resolver un gran enigma cosmol\u00f3gico<\/strong><\/span>. Se trata de la l\u00ednea enlazada con que he comenzado esta entradilla: \u201c<a href=\"https:\/\/www.agenciasinc.es\/Noticias\/Asi-se-formaron-objetos-muy-masivos-en-los-primeros-instantes-de-vida-del-universo\"><em>As\u00ed se formaron los objetos muy masivos en los primeros instantes de vida del universo<\/em><\/a>\u201d. Obviamente no entrar\u00e9 a escribir detalle alguno en materia de cosmolog\u00eda, ya que soy un profano en la materia. <span style=\"color: #3366ff\"><strong>El rompecabezas estribaba en que<\/strong><\/span> las grandes estructuras del universo hab\u00edan aparecido poco despu\u00e9s del \u201c<a href=\"https:\/\/es.wikipedia.org\/wiki\/Big_Bang\">Big Ban<\/a>\u201d, cuando la cosmolog\u00eda actual consideraba que deber\u00e1n surgir mucho despu\u00e9s.&nbsp; Y s\u00ed los autores se\u00f1alan que \u201c<em>Las fluctuaciones cu\u00e1nticas durante la etapa de inflaci\u00f3n, solo unos instantes tras el nacimiento del universo, fueron clave para la formaci\u00f3n de estructuras masivas muy antiguas, como (\u2026). La clave est\u00e1 en la estad\u00edstica de estas fluctuaciones, seg\u00fan un nuevo estudio (\u2026.) explicaci\u00f3n a la existencia de grandes estructuras muy antiguas, que datan incluso de cuando el universo ten\u00eda solo entre 200 y 400 millones de a\u00f1os y que no se ajustan a las predicciones del modelo est\u00e1ndar de lla cosmolog\u00eda (\u2026) \u201cun elemento clave en este proceso: las <span style=\"color: #3366ff\"><strong>fluctuaciones cu\u00e1nticas<\/strong><\/span>&nbsp; (\u2026.) estas fluctuaciones podr\u00edan colapsar en grandes estructuras, galaxias, c\u00famulos o incluso estructuras mayores. Mientras que, con <strong><span style=\"color: #3366ff\">la hip\u00f3tesis anterior, donde ten\u00edamos una funci\u00f3n de tipo gaussiana<\/span><\/strong>, estas estructuras tardar\u00edan mucho m\u00e1s tiempo en formarse por colapso gravitaciona (&#8230;) de la llamada ecuaci\u00f3n de Fokker-Planck, que tienen en cuenta esa din\u00e1mica de fluctuaciones cu\u00e1nticas, se obtiene una funci\u00f3n de tipo el\u00edptico y <span style=\"color: #3366ff\"><strong>lognormal, no de tipo gaussiano<\/strong> <\/span>(\u2026) Sin embargo, <span style=\"color: #3366ff\"><strong>el nuevo resultado, que arroja funciones que presentan esta \u2018cola\u2019, explicar\u00eda la formaci\u00f3n de grandes estructuras muy masivas muy pronto en la edad del universo, mucho antes de lo que se requerir\u00eda por colapso gravitacional<\/strong><\/span>\u201d<\/em>.<\/p>\n<p>Loa autores se refieren a las <span style=\"color: #3366ff\"><strong>distribuciones de \u201ccolas largas\u201d<\/strong><\/span>, entre las cuales se <span style=\"color: #3366ff\"><strong>encentran la potencial, el log normal, la logar\u00edtmica y algunas m\u00e1s relacionadas con las precedentes. Se trata justamente las que encontramos en la naturaleza terrestre, tanto los estudiosos de la diversidad de diversos recursos naturales y en largo etc<\/strong><\/span>.<\/p>\n<p><strong><span style=\"color: #3366ff\">Veamos si pongo un ejemplo sencillo<\/span><\/strong>. Si asumimos que la relaci\u00f3n peso-altura de la poblaci\u00f3n humana se ajusta a una curva gaussiana, su representaci\u00f3n en coordenadas cartesianas lo hace perfectamente para los valores brutos en kilos y cent\u00edmetros. Sin embargo, si lo hace a una distribuci\u00f3n de cola larga, ambas o una de las variables debe sufrir una transformaci\u00f3n logar\u00edtmica. Cuando ocurre en ambos ejes, detectamos una ley potencial que, si persiste a lo largo de tres ordenes de magnitud dar\u00eda muestras de ser una <span style=\"color: #3366ff\"><strong>estructura fractal<\/strong><\/span>.&nbsp; De hecho, <a href=\"https:\/\/en.wikipedia.org\/wiki\/Bin_Jiang\">Bin Jiang<\/a> citado varias veces en mi trabajo del pensamiento Paretiano (entre otros) que incluyo en este post, defiende que <span style=\"color: #3366ff\"><strong>todas las familias de curvas relacionas con las colas largas, podr\u00edan considerarse como<\/strong> \u00ab<strong>fractales blandos\u00bb, <\/strong><\/span>al menos, muy a menudo. Sus argumentos me parecen muy convincentes. Las distribuciones log normal, potenciales, logar\u00edtmicas, geom\u00e9tricas, se encuentran muy relacionadas y cuando se analizan muchas bases de datos, es habitual que se ajusten a todas o casi todas ellas, aunque a una m\u00e1s que a otras, pero jam\u00e1s a las distribuciones normales y otras relacionadas con ella. Bin Jiang argumenta que las estructuras, nacen, maduran o son perturbadas hasta alcanzar una plena fractalidad en su madurez. &nbsp;En consecuencia, no debe extra\u00f1arnos que menudo no sean plenamente fractales. Este autor propone m\u00e9todos alternativos con vistas a estimar el grado de fractalidad de las bases de datos. &nbsp;<\/p>\n<p>Barrunto, ya que no llego a proponer una conjetura sino la idea personal de que, gran parte de la estad\u00edstica fue desarroll\u00e1ndose con conjuntos de datos de replicaciones, es decir replicas de un mismo ensayo en diversos individuos, parcelas de campo, placas Petri, etc. Por ejemplo, cuando deseamos analizar los efectos de un f\u00e1rmaco u otra sustancia, como los pesticidas.&nbsp; En tales circunstancias el surgimiento de estructuras normales es \u201cnormal\u201d. Empero en la naturaleza nada es replica de nada, sino objetos singulares y, en los sistemas no lineales, peque\u00f1as diferencias en sus condiciones iniciales o de contorno (perturbaciones) pueden dar lugar a grandes divergencias en sus evoluciones y configuraciones finales.<\/p>\n<p><span style=\"color: #3366ff\"><strong>\u00bfY que nos dicen las ciencias del suelo acerca de la agrupaci\u00f3n de los materiales del suelo?<\/strong><\/span>: la distribuci\u00f3n de los tama\u00f1os de las part\u00edculas del suelo, de los agregados del suelo que forman, de los poros del suelo que deja los \u00faltimos, etc. obedecen a los mismos tipos de distribuci\u00f3n. <span style=\"color: #3366ff\"><strong>Muy pocas estructuras grandes que incrementan su frecuencia conforme disminuyen el tama\u00f1o de estas. Empero tambi\u00e9n surgen en nuestras estructuras cognitivas<\/strong><\/span> como ya anunciaba hace m\u00e1s de 10 a\u00f1os en las siguientes publicciones, entre otras: (i) <a href=\"https:\/\/publications.jrc.ec.europa.eu\/repository\/handle\/JRC79481\">Magic Numbers: A Meta-Analysis for Enlarging the Scope of a Universal Soil Classification System<\/a>; (ii) <a href=\"https:\/\/www.sciencedirect.com\/science\/article\/abs\/pii\/S1476945X09000518\">The Fractal Mind of Pedologists<\/a> (iii<a href=\"https:\/\/www.sciencedirect.com\/science\/article\/abs\/pii\/S0016706106000607\">) The Mathematical Structures of Biological and Pedological Taxonomies<\/a>. Sin embargo, reitero que en \u201c<a href=\"https:\/\/bsssjournals.onlinelibrary.wiley.com\/doi\/abs\/10.1111\/ejss.13031\">Exploring the scaling law of geographical space: Gaussian versus Paretian thinking<\/a>\u201d ya muestro multitud de ejemplos.<\/p>\n<p><span style=\"color: #ff6600\"><strong>\u00bfResulta ser normal lo que en la naturaleza es anormal?<\/strong><\/span><\/p>\n<p><a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2007\/08\/01\/71004\">\u00bfEs la Mente Fractal?: Dedicado a Eusebio Sempere<\/a><\/p>\n<p><span style=\"color: #808000\"><strong>Nota sobre uno de los autores<\/strong><\/span><\/p>\n<p>Cuando le\u00ed que uno de los autores resultaba ser un colega de mi Instituci\u00f3n cuyo nombre es <a href=\"https:\/\/www.uam.es\/FisicaTeorica\/(EN)-Garc%C3%ADa-Bellido-Capdevila,-Juan\/1242650847349.htm\">Juan Garc\u00eda-Bellido<\/a>, sonre\u00ed con nostalgia, ya que conoc\u00ed relativamente bien a su padre el famoso, <a href=\"https:\/\/es.wikipedia.org\/wiki\/Antonio_Garc%C3%ADa-Bellido\">Antonio Garc\u00eda-Bellido<\/a><\/p>\n<p>Experto de fama mundial mundial en biolog\u00eda del desarrollo, y cuyo padre su vez fue un famoso arque\u00f3logo. Cuando en la d\u00e9cada de los a\u00f1os 90 del siglo pasado, el presidente del CSIC <a href=\"https:\/\/es.wikipedia.org\/wiki\/Jos%C3%A9_Mar%C3%ADa_Mato_de_la_Paz\">Jos\u00e9 Mar\u00eda Mato<\/a>, reuni\u00f3 por primera vez a su Comit\u00e9 Cient\u00edfico Asesor, me toco sentarme, por azar, al lado del respetado y temido (no s\u00e9 por qu\u00e9) Antonio Garc\u00eda Bellido. Algunos compa\u00f1eros de comit\u00e9 sonrieron, ya que&nbsp; ten\u00eda una cierta fama de aspera\/brusco. Sin embargo, congeniamos muy bien, estuvimos en varios subcomit\u00e9s, me consult\u00f3 un bien centro al que llevar a su hija quer\u00eda desarrollar una carrera sobre temas relacionados con la oceanograf\u00eda, si no recurso mal. Seg\u00fan se rumoreaba Garc\u00eda Bellido entr\u00f3 en varias ocasiones entre los posibles candidatos a ser nominado para el Premio Nobel. Me ha alegrado saber que aun se encuentra entre nosotros.&nbsp;&nbsp;&nbsp;&nbsp; &nbsp;<\/p>\n<p><span style=\"color: #008000\"><strong>Juan Jos\u00e9 Ib\u00e1\u00f1ez<\/strong><\/span><\/p>\n<p><span style=\"color: #800000\"><em>Contin\u00faa\u2026\u2026..<\/em><\/span><\/p>\n<p><!--more--><\/p>\n<p><a href=\"https:\/\/bsssjournals.onlinelibrary.wiley.com\/doi\/abs\/10.1111\/ejss.13035\">Land system diversity, scaling laws and polygons map analysis<\/a><\/p>\n<p><a href=\"https:\/\/www.researchgate.net\/publication\/343225932_Exploring_the_Scaling_Law_of_Geographical_Space_Gaussian_versus_Paretian_thinking\">Explorando la Ley de Escala del Espacio Geogr\u00e1fico: Pensamiento Gaussiano versus Pareto<\/a><\/p>\n<h3><strong><span style=\"color: #800000\"><a style=\"color: #800000\" href=\"https:\/\/bsssjournals.onlinelibrary.wiley.com\/doi\/abs\/10.1111\/ejss.13031\">Exploring the scaling law of geographical space: Gaussian versus Paretian thinking<\/a><\/span><\/strong><\/h3>\n<p>Resumen castellano (traducci\u00f3n asquerosamente electr\u00f3nica)<\/p>\n<p>Se ha producido un debate sobre las leyes de escala y la naturaleza fractal del espacio geogr\u00e1fico. Los estudios de biodiversidad y pedodiversidad muestran la aparici\u00f3n de estructuras fractales como las relaciones taxa-\u00e1rea. La biodiversidad y la pedodiversidad son recursos naturales, aunque algunos consideran que los pedotaxones son artificiales. Los estudios realizados hasta la fecha enfatizan que muchos patrones espaciales de pedodiversidad y biodiversidad convergen en las mismas regularidades. Muchos de estos estudios utilizaron mapas de recursos naturales y sus bases de datos digitales. La informaci\u00f3n se extrae de los tipos de taxones contenidos en cada pol\u00edgono y las \u00e1reas cubiertas. Sin embargo, la estructura de los mapas (n\u00famero, \u00e1rea, fragmentaci\u00f3n, etc.) rara vez ha sido objeto de estudio. Cuando se estudi\u00f3 la estructura del mapa, se observaron similitudes intrigantes en los an\u00e1lisis de pedodiversidad y biodiversidad. Para entender si estas similitudes tambi\u00e9n aparecen en otro tipo de entidades espaciales que son m\u00e1s artificiales, una revisi\u00f3n de los an\u00e1lisis geoespaciales que estudiaron temas como mapas urbanos, mapas de sistemas terrestres, etc. se llev\u00f3 a cabo. Las principales variables en estos mapas son artificiales y\/o combinaciones de capas de datos de recursos naturales. Las regularidades detectadas en la informaci\u00f3n geoespacial de estos \u00faltimos temas tambi\u00e9n parecen ajustarse a los resultados obtenidos al analizar mapas de recursos naturales como suelos, tipos de rocas, accidentes geogr\u00e1ficos, comunidades vegetales, etc. Por lo tanto, algunos ge\u00f3grafos consideran que la idea de que hay muchas m\u00e1s cosas \/ objetos peque\u00f1os que m\u00e1s grandes en varios \u00f3rdenes de magnitud en el espacio geogr\u00e1fico es una ley. Algunos ge\u00f3grafos tambi\u00e9n sostienen que <strong>el cl\u00e1sico \u00abpensamiento gaussiano\u00bb y sus herramientas estad\u00edsticas deber\u00edan ser reemplazadas por un \u00abpensamiento paretiano\u00bb y sus herramientas estad\u00edsticas relacionadas<\/strong>. Este art\u00edculo analiza los temas anteriores, as\u00ed como la falta de datos adecuados y los tipos de mapas cognitivos que utilizamos en nuestra civilizaci\u00f3n, apoyando la conjetura de que <strong>deber\u00edamos incluir el pensamiento paretiano en nuestra investigaci\u00f3n, al menos de la misma manera que usamos el pensamiento gaussiano<\/strong>.<\/p>\n<p><a href=\"https:\/\/www.agenciasinc.es\/Noticias\/Asi-se-formaron-objetos-muy-masivos-en-los-primeros-instantes-de-vida-del-universo\"><strong>As\u00ed se formaron objetos muy masivos en los primeros instantes de vida del universo<\/strong><\/a><\/p>\n<p><strong>Las fluctuaciones cu\u00e1nticas durante la etapa de inflaci\u00f3n, solo unos instantes tras el nacimiento del universo, fueron clave para la formaci\u00f3n de estructuras masivas muy antiguas, como el c\u00famulo<\/strong> El Gordo u otros captados por el telescopio James Webb. <strong>La clave est\u00e1 en la estad\u00edstica de estas fluctuaciones<\/strong>, seg\u00fan un nuevo estudio.<\/p>\n<p>&nbsp;&nbsp;&nbsp;<a href=\"https:\/\/www.agenciasinc.es\/Autor\/SINC\">SINC; <\/a><a href=\"https:\/\/www.agenciasinc.es\/articulos-del-dia\/04-05-23\">4\/5\/2023 10:18 CEST<\/a><\/p>\n<p><strong>La cuesti\u00f3n de c\u00f3mo se formaron las&nbsp;grandes estructuras del universo, como galaxias, c\u00famulos o agujeros negros, es una de las m\u00e1s antiguas en cosmolog\u00eda<\/strong>. Sin embargo, a partir de los a\u00f1os 80, los cosm\u00f3logos se dieron cuenta de <strong>un elemento clave en este proceso: las&nbsp;fluctuaciones cu\u00e1nticas<\/strong>.<\/p>\n<p>Estas son&nbsp;<strong>cambios de energ\u00eda<\/strong>&nbsp;en puntos concretos del espacio-tiempo que, de acuerdo con el&nbsp;<strong>modelo de inflaci\u00f3n<\/strong>, fueron determinantes para <strong>formar lo que se convertir\u00eda en los grumos de materia de nuestro universo<\/strong>. La inflaci\u00f3n c\u00f3smica es una propuesta muy popular para explicar la r\u00e1pida expansi\u00f3n del universo en sus instantes iniciales de vida.<\/p>\n<p>Hasta hace poco se cre\u00eda que las grandes estructuras que hoy observamos en nuestro universo, como&nbsp;<strong>c\u00famulos masivos<\/strong>, con decenas de miles de galaxias, necesariamente tendr\u00edan que haberse formado mucho m\u00e1s tarde de esa etapa.<\/p>\n<p>Sin embargo,&nbsp;<a href=\"https:\/\/journals.aps.org\/prl\/abstract\/10.1103\/PhysRevLett.130.121003\">un nuevo publicado en&nbsp;<strong>Physical Review Letters<\/strong><\/a>&nbsp;ofrece una <strong>explicaci\u00f3n a la existencia de grandes estructuras muy antiguas, que datan incluso de cuando el universo ten\u00eda solo 200 a 400 millones de a\u00f1os y que no se ajustan a las predicciones del modelo est\u00e1ndar de&nbsp;cosmolog\u00eda<\/strong>.<\/p>\n<p><em>Las fluctuaciones cu\u00e1nticas durante la etapa de inflaci\u00f3n, solo unos instantes tras el nacimiento del universo, fueron clave para la formaci\u00f3n de estructuras muy antiguas y masivas<\/em><\/p>\n<p>La clave para que se formen est\u00e1 en las&nbsp;<strong>fluctuaciones cu\u00e1nticas<\/strong>&nbsp;durante la etapa de inflaci\u00f3n, seg\u00fan los autores. Estas explicar\u00edan la existencia de observaciones con un alto corrimiento al rojo, objetos \u201cque no deber\u00edan estar ah\u00ed\u201d, formados solo unos pocos cientos de millones de a\u00f1os despu\u00e9s de la formaci\u00f3n del universo, como el c\u00famulo El Gordo o las galaxias masivas vistas por el James Webb Space Telescope.<\/p>\n<p><strong>El Gordo<\/strong>, <strong>el c\u00famulo de galaxias distantes m\u00e1s grande jam\u00e1s observado<\/strong> con los telescopios existentes, se descubri\u00f3 en 2014. \u201c<strong>Este c\u00famulo constituye un objeto muy masivo que data de 6.400 millones de a\u00f1os despu\u00e9s del Big Bang,&nbsp;algo que se habr\u00eda formado muy pronto y cuya existencia no se pod\u00eda explicar con los modelos anteriores<\/strong>\u201d, explica&nbsp;<strong>Juan Garc\u00eda-Bellido<\/strong>, coautor del estudio e investigador en el Instituto de F\u00edsica Te\u00f3rica (IFT, centro mixto de la Universidad Aut\u00f3noma de Madrid y el CSIC).<\/p>\n<p><strong>Estos c\u00famulos de varias decenas de miles de galaxias no se podr\u00edan formar, en teor\u00eda, hasta mucho despu\u00e9s. \u201cSorprendi\u00f3 encontrar objetos tan masivos tan pronto. Por tanto, era necesario encontrar una explicaci\u00f3n<\/strong>\u201d, cuenta el f\u00edsico.<\/p>\n<p>Hace a\u00f1os, los autores \u2013que tambi\u00e9n incluyen a Jos\u00e9 Mar\u00eda Ezquiaga del Instituto Niels Bohr y Vicent Vennin de la Universidad de Par\u00eds\u2013 ya se dieron cuenta de que las fluctuaciones cu\u00e1nticas durante la etapa de inflaci\u00f3n afectaban a esta din\u00e1mica de&nbsp;<strong>aceleraci\u00f3n del universo<\/strong>.<\/p>\n<p><strong>Antes del nuevo&nbsp;trabajo, se cre\u00eda que la distribuci\u00f3n estad\u00edstica de estas fluctuaciones cu\u00e1nticas durante el periodo de inflaci\u00f3n formaba una gr\u00e1fica muy concreta, conocida como campana de Gauss<\/strong>. Pero los investigadores se dieron cuenta de que, aplicando ecuaciones que permiten mirar un poco m\u00e1s all\u00e1, <strong>lo que obtenemos en realidad es una&nbsp;distribuci\u00f3n no gaussiana, que presenta una regi\u00f3n \u2018de cola\u2019, tal como se puede apreciar en la imagen inferior<\/strong>.<\/p>\n<p>\u201cEsto indica que <strong>estas fluctuaciones<\/strong>&nbsp;<strong>podr\u00edan colapsar en grandes estructuras, galaxias, c\u00famulos o incluso estructuras mayores<\/strong>. <strong>Mientras que, con la hip\u00f3tesis anterior, donde ten\u00edamos una funci\u00f3n de tipo gaussiana, estas estructuras tardar\u00edan mucho m\u00e1s tiempo en formarse por colapso gravitaciona<\/strong><strong>l<\/strong>\u201d, explica Garc\u00eda-Bellido.<\/p>\n<p><em>El nuevo resultado explicar\u00eda la formaci\u00f3n de grandes estructuras muy masivas mucho antes de lo que se requerir\u00eda por colapso gravitacional<\/em><\/p>\n<p>Es decir, con una funci\u00f3n de tipo gaussiana, estas estructuras tardar\u00edan mucho m\u00e1s tiempo en formarse, por lo que estructuras tan grandes y tempranas <strong>como El Gordo no pod\u00edan explicarse. Sin embargo, el nuevo resultado, que arroja funciones que presentan esta \u2018cola\u2019, explicar\u00eda la formaci\u00f3n de grandes estructuras muy masivas muy<\/strong>&nbsp;<strong>pronto en la edad del universo<\/strong>, mucho antes de lo que se requerir\u00eda por colapso gravitacional.<\/p>\n<p><strong>Aplicaci\u00f3n en observaciones del James Webb<\/strong><\/p>\n<p>Seg\u00fan los autores, lo interesante de la nueva propuesta es que<strong>, gracias a estas colas no gaussianas exponenciales se puede dar explicaci\u00f3n, por ejemplo<\/strong>, a las recientes observaciones del telescopio espacial<strong>&nbsp;James Webb<\/strong>.<\/p>\n<p>Desde su lanzamiento a principios de 2022, este observatorio est\u00e1 realizando detecciones muy interesantes que <strong>ahora pueden ser explicadas a trav\u00e9s de este nuevo resultado<\/strong>.<\/p>\n<p>Por ejemplo, galaxias con corrimientos al rojo muy altos. El&nbsp;<strong>corrimiento al rojo<\/strong>&nbsp;o&nbsp;<em>redshift<\/em>&nbsp;es un concepto que hace referencia a la antig\u00fcedad de los objetos astron\u00f3micos. Se define como un incremento en la longitud de onda de radiaci\u00f3n electromagn\u00e9tica recibida por un detector comparado con la longitud de onda emitida por la fuente.<\/p>\n<p><em>Los investigadores usaron m\u00e9todos computacionales para calcular la funci\u00f3n, que modifica la evoluci\u00f3n cl\u00e1sica<\/em><\/p>\n<p><strong>Adem\u00e1s, la&nbsp;formaci\u00f3n&nbsp;de objetos m\u00e1s grandes de lo esperado a principios del universo, como explica este nuevo resultado, ayuda a aliviar algunas tensiones entre las observaciones y nuestro modelo cosmol\u00f3gico est\u00e1ndar<\/strong>.&nbsp;<\/p>\n<p>Los investigadores usaron&nbsp;<strong>m\u00e9todos computacionales<\/strong>&nbsp;para calcular la funci\u00f3n, que modifica la evoluci\u00f3n cl\u00e1sica. Mediante el uso de la llamada <strong>ecuaci\u00f3n de Fokker-Planck<\/strong>, que tienen en cuenta esa din\u00e1mica de fluctuaciones cu\u00e1nticas, se <strong>obtiene una funci\u00f3n de tipo el\u00edptico y lognormal, no de tipo gaussiano<\/strong>.<\/p>\n<p>Esta nueva gr\u00e1fica es la que da mayor probabilidad de colapso para agujeros negros primordiales, galaxias tempranas y para objetos muy masivos como el c\u00famulo de&nbsp;<strong>El Gordo<\/strong>.<\/p>\n<p>\u201c<strong>Era necesario tener en cuenta la informaci\u00f3n no lineal y abrir la mente<\/strong>\u201d, reconoce Garc\u00eda-Bellido. \u201c<strong>El nuevo resultado explica las no gausianidades de las estructuras a gran escala<\/strong>, que por fin estamos comenzando a medir con los cat\u00e1logos de galaxias\u201d. <strong>En definitiva, estas fluctuaciones con cola no gaussiana nos ayudan a explicar el&nbsp;comportamiento&nbsp;a gran escala del universo<\/strong>.<\/p>\n<p>En el futuro, los investigadores esperan continuar complementando el modelo cosmol\u00f3gico est\u00e1ndar teniendo en cuenta las observaciones de los telescopios de cielo profundo, y cuya formaci\u00f3n podr\u00eda corresponder a <strong>esta din\u00e1mica de fluctuaciones cu\u00e1nticas en la<\/strong>&nbsp;<strong>etapa de inflaci\u00f3n<\/strong>, como muestra el resultado.<\/p>\n<p>El nuevo estudio, adem\u00e1s, permite a <strong>Garc\u00eda-Bellido hacer una interesante reflexi\u00f3n desde el punto de vista de la historia de la ciencia<\/strong>: \u201cHace d\u00e9cadas, pasaban muchos a\u00f1os entre la teor\u00eda y la&nbsp;<strong>aplicaci\u00f3n experimental<\/strong>. Por ejemplo, la Relatividad General no pudo aplicarse hasta los a\u00f1os 60, o el Higgs se descubri\u00f3 casi medio siglo despu\u00e9s de ser teorizado\u201d, explica. \u201cTengo la suerte de trabajar en una \u00e9poca en la que las observaciones experimentales y las predicciones te\u00f3ricas pueden ir a la par, al menos, desde hace unos 20 a\u00f1os\u201d.<\/p>\n<p><span style=\"color: #800000\"><strong>Referencia<\/strong><\/span>:&nbsp;<\/p>\n<p>Jose Mar\u00eda Ezquiaga et al. Massive Galaxy Clusters Like El Gordo Hint at Primordial Quantum Diffusion.&nbsp;<a href=\"https:\/\/journals.aps.org\/prl\/abstract\/10.1103\/PhysRevLett.130.121003\"><em>Physical Review Letters<\/em><\/a>&nbsp;(2023)<\/p>\n<h3>Im\u00e1genes Relacionadas:<\/h3>","protected":false},"excerpt":{"rendered":"<p>Fuente: Colaje im\u00e1genes Google \u201cAs\u00ed se formaron objetos muy masivos en los primeros instantes de vida del universo\u201d. Este es el titulo traducido al espa\u00f1ol del original anglosaj\u00f3n del que os vamos a hablar hoy. En principio, no tiene nada que ver con las noticias que solemos incluir en nuestro blog, pero \u201csolo en principio\u201d. Poque si releemos los siguientes post:\u201d El Pensamiento Logar\u00edtmico y la Estructura de la Naturaleza \u201d; \u201cLey De la Geograf\u00eda y el An\u00e1lisis Geoespacial: Las Distribuciones de Cola Larga\u201d;&nbsp; \u201cTaxonom\u00edas Gen\u00e9ticas de Ida y Vuelta: Tendencias en las Clasificaciones de Suelos y Minerales\u201d, etc. comenzar\u00e9is\u2026<\/p>\n","protected":false},"author":26,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0},"categories":[590,13638,586,607,616],"tags":[38681,24612,54631,48411,46712,54635,54630,54629,3016,54633],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":4}},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Fuente: Colaje im\u00e1genes Google \u201cAs\u00ed se formaron objetos muy masivos en los primeros instantes de vida del universo\u201d. Este es el titulo traducido al espa\u00f1ol del original anglosaj\u00f3n del que os vamos a hablar hoy. En principio, no tiene nada que ver con las noticias que solemos incluir en nuestro blog, pero \u201csolo en principio\u201d.\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Juan Jos\u00e9 Ib\u00e1\u00f1ez\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2023\/05\/18\/154346\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Un Universo invisible bajo nuestros pies - Los suelos y la vida\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"La Estructura del Universo y el pensamiento Paretiano (\u00bfQu\u00e9 aporta la edafolog\u00eda?) - Un Universo invisible bajo nuestros pies\" \/>\n\t\t<meta property=\"og:description\" content=\"Fuente: Colaje im\u00e1genes Google \u201cAs\u00ed se formaron objetos muy masivos en los primeros instantes de vida del universo\u201d. Este es el titulo traducido al espa\u00f1ol del original anglosaj\u00f3n del que os vamos a hablar hoy. En principio, no tiene nada que ver con las noticias que solemos incluir en nuestro blog, pero \u201csolo en principio\u201d.\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2023\/05\/18\/154346\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2023-05-18T12:29:59+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2023-05-18T12:30:31+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/juan.j.marti.14\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"La Estructura del Universo y el pensamiento Paretiano (\u00bfQu\u00e9 aporta la edafolog\u00eda?) - Un Universo invisible bajo nuestros pies\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Fuente: Colaje im\u00e1genes Google \u201cAs\u00ed se formaron objetos muy masivos en los primeros instantes de vida del universo\u201d. Este es el titulo traducido al espa\u00f1ol del original anglosaj\u00f3n del que os vamos a hablar hoy. En principio, no tiene nada que ver con las noticias que solemos incluir en nuestro blog, pero \u201csolo en principio\u201d.\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2023\\\/05\\\/18\\\/154346#blogposting\",\"name\":\"La Estructura del Universo y el pensamiento Paretiano (\\u00bfQu\\u00e9 aporta la edafolog\\u00eda?) - Un Universo invisible bajo nuestros pies\",\"headline\":\"La Estructura del Universo y el pensamiento Paretiano (\\u00bfQu\\u00e9 aporta la edafolog\\u00eda?)\",\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/wp-content\\\/blogs.dir\\\/42\\\/files\\\/189\\\/Universo-distribucion-paretiana.jpg\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2023\\\/05\\\/18\\\/154346\\\/#articleImage\"},\"datePublished\":\"2023-05-18T13:29:59+01:00\",\"dateModified\":\"2023-05-18T13:30:31+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2023\\\/05\\\/18\\\/154346#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2023\\\/05\\\/18\\\/154346#webpage\"},\"articleSection\":\"Componentes, Estructuras y Procesos en los Suelos, Curso b\\u00e1sico de ciencia para jovenes universitarios y tecn\\u00f3logos, Diversidad, Complejidad y Fractales, Historia de la Tierra y de los Suelos., Redes Complejas, Ecol\\u00f3gicas, Sociales y el Mundo de Internet, agujeros negros, ciencias del suelo, c\\u00famulos, distribuciones de colas largas, Edafolog\\u00eda, fractales blandos, galaxias, grandes estructuras del universo, revisi\\u00f3n, teor\\u00eda cosmol\\u00f3gica\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2023\\\/05\\\/18\\\/154346#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/diversidad-complejidad-y-fractales#listItem\",\"name\":\"Diversidad, Complejidad y Fractales\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/diversidad-complejidad-y-fractales#listItem\",\"position\":2,\"name\":\"Diversidad, Complejidad y Fractales\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/diversidad-complejidad-y-fractales\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2023\\\/05\\\/18\\\/154346#listItem\",\"name\":\"La Estructura del Universo y el pensamiento Paretiano (\\u00bfQu\\u00e9 aporta la edafolog\\u00eda?)\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2023\\\/05\\\/18\\\/154346#listItem\",\"position\":3,\"name\":\"La Estructura del Universo y el pensamiento Paretiano (\\u00bfQu\\u00e9 aporta la edafolog\\u00eda?)\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/diversidad-complejidad-y-fractales#listItem\",\"name\":\"Diversidad, Complejidad y Fractales\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#organization\",\"name\":\"Un Universo invisible bajo nuestros pies\",\"description\":\"Los suelos y la vida\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/files\\\/2022\\\/02\\\/logo.png\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2023\\\/05\\\/18\\\/154346\\\/#organizationLogo\",\"width\":217,\"height\":72},\"image\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2023\\\/05\\\/18\\\/154346\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/juan.j.marti.14\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo\",\"name\":\"Juan Jos\\u00e9 Ib\\u00e1\\u00f1ez\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2023\\\/05\\\/18\\\/154346#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/387f3a100385573d8f42ce2a3211fd1c?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Juan Jos\\u00e9 Ib\\u00e1\\u00f1ez\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2023\\\/05\\\/18\\\/154346#webpage\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2023\\\/05\\\/18\\\/154346\",\"name\":\"La Estructura del Universo y el pensamiento Paretiano (\\u00bfQu\\u00e9 aporta la edafolog\\u00eda?) - Un Universo invisible bajo nuestros pies\",\"description\":\"Fuente: Colaje im\\u00e1genes Google \\u201cAs\\u00ed se formaron objetos muy masivos en los primeros instantes de vida del universo\\u201d. Este es el titulo traducido al espa\\u00f1ol del original anglosaj\\u00f3n del que os vamos a hablar hoy. En principio, no tiene nada que ver con las noticias que solemos incluir en nuestro blog, pero \\u201csolo en principio\\u201d.\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2023\\\/05\\\/18\\\/154346#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\"},\"datePublished\":\"2023-05-18T13:29:59+01:00\",\"dateModified\":\"2023-05-18T13:30:31+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#website\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/\",\"name\":\"Un Universo invisible bajo nuestros pies\",\"description\":\"Los suelos y la vida\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"La Estructura del Universo y el pensamiento Paretiano (\u00bfQu\u00e9 aporta la edafolog\u00eda?) - Un Universo invisible bajo nuestros pies","description":"Fuente: Colaje im\u00e1genes Google \u201cAs\u00ed se formaron objetos muy masivos en los primeros instantes de vida del universo\u201d. Este es el titulo traducido al espa\u00f1ol del original anglosaj\u00f3n del que os vamos a hablar hoy. En principio, no tiene nada que ver con las noticias que solemos incluir en nuestro blog, pero \u201csolo en principio\u201d.","canonical_url":"https:\/\/www.madrimasd.org\/blogs\/universo\/2023\/05\/18\/154346","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2023\/05\/18\/154346#blogposting","name":"La Estructura del Universo y el pensamiento Paretiano (\u00bfQu\u00e9 aporta la edafolog\u00eda?) - Un Universo invisible bajo nuestros pies","headline":"La Estructura del Universo y el pensamiento Paretiano (\u00bfQu\u00e9 aporta la edafolog\u00eda?)","author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author"},"publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-content\/blogs.dir\/42\/files\/189\/Universo-distribucion-paretiana.jpg","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2023\/05\/18\/154346\/#articleImage"},"datePublished":"2023-05-18T13:29:59+01:00","dateModified":"2023-05-18T13:30:31+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2023\/05\/18\/154346#webpage"},"isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2023\/05\/18\/154346#webpage"},"articleSection":"Componentes, Estructuras y Procesos en los Suelos, Curso b\u00e1sico de ciencia para jovenes universitarios y tecn\u00f3logos, Diversidad, Complejidad y Fractales, Historia de la Tierra y de los Suelos., Redes Complejas, Ecol\u00f3gicas, Sociales y el Mundo de Internet, agujeros negros, ciencias del suelo, c\u00famulos, distribuciones de colas largas, Edafolog\u00eda, fractales blandos, galaxias, grandes estructuras del universo, revisi\u00f3n, teor\u00eda cosmol\u00f3gica"},{"@type":"BreadcrumbList","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2023\/05\/18\/154346#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo#listItem","position":1,"name":"Home","item":"https:\/\/www.madrimasd.org\/blogs\/universo","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/diversidad-complejidad-y-fractales#listItem","name":"Diversidad, Complejidad y Fractales"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/diversidad-complejidad-y-fractales#listItem","position":2,"name":"Diversidad, Complejidad y Fractales","item":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/diversidad-complejidad-y-fractales","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2023\/05\/18\/154346#listItem","name":"La Estructura del Universo y el pensamiento Paretiano (\u00bfQu\u00e9 aporta la edafolog\u00eda?)"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2023\/05\/18\/154346#listItem","position":3,"name":"La Estructura del Universo y el pensamiento Paretiano (\u00bfQu\u00e9 aporta la edafolog\u00eda?)","previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/diversidad-complejidad-y-fractales#listItem","name":"Diversidad, Complejidad y Fractales"}}]},{"@type":"Organization","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#organization","name":"Un Universo invisible bajo nuestros pies","description":"Los suelos y la vida","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/","logo":{"@type":"ImageObject","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2023\/05\/18\/154346\/#organizationLogo","width":217,"height":72},"image":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2023\/05\/18\/154346\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/juan.j.marti.14"]},{"@type":"Person","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo","name":"Juan Jos\u00e9 Ib\u00e1\u00f1ez","image":{"@type":"ImageObject","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2023\/05\/18\/154346#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/387f3a100385573d8f42ce2a3211fd1c?s=96&d=mm&r=g","width":96,"height":96,"caption":"Juan Jos\u00e9 Ib\u00e1\u00f1ez"}},{"@type":"WebPage","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2023\/05\/18\/154346#webpage","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/2023\/05\/18\/154346","name":"La Estructura del Universo y el pensamiento Paretiano (\u00bfQu\u00e9 aporta la edafolog\u00eda?) - Un Universo invisible bajo nuestros pies","description":"Fuente: Colaje im\u00e1genes Google \u201cAs\u00ed se formaron objetos muy masivos en los primeros instantes de vida del universo\u201d. Este es el titulo traducido al espa\u00f1ol del original anglosaj\u00f3n del que os vamos a hablar hoy. En principio, no tiene nada que ver con las noticias que solemos incluir en nuestro blog, pero \u201csolo en principio\u201d.","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#website"},"breadcrumb":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2023\/05\/18\/154346#breadcrumblist"},"author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author"},"creator":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author"},"datePublished":"2023-05-18T13:29:59+01:00","dateModified":"2023-05-18T13:30:31+01:00"},{"@type":"WebSite","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#website","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/","name":"Un Universo invisible bajo nuestros pies","description":"Los suelos y la vida","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Un Universo invisible bajo nuestros pies - Los suelos y la vida","og:type":"article","og:title":"La Estructura del Universo y el pensamiento Paretiano (\u00bfQu\u00e9 aporta la edafolog\u00eda?) - Un Universo invisible bajo nuestros pies","og:description":"Fuente: Colaje im\u00e1genes Google \u201cAs\u00ed se formaron objetos muy masivos en los primeros instantes de vida del universo\u201d. Este es el titulo traducido al espa\u00f1ol del original anglosaj\u00f3n del que os vamos a hablar hoy. En principio, no tiene nada que ver con las noticias que solemos incluir en nuestro blog, pero \u201csolo en principio\u201d.","og:url":"https:\/\/www.madrimasd.org\/blogs\/universo\/2023\/05\/18\/154346","og:image":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png","og:image:secure_url":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png","article:published_time":"2023-05-18T12:29:59+00:00","article:modified_time":"2023-05-18T12:30:31+00:00","article:publisher":"https:\/\/www.facebook.com\/juan.j.marti.14","twitter:card":"summary","twitter:title":"La Estructura del Universo y el pensamiento Paretiano (\u00bfQu\u00e9 aporta la edafolog\u00eda?) - Un Universo invisible bajo nuestros pies","twitter:description":"Fuente: Colaje im\u00e1genes Google \u201cAs\u00ed se formaron objetos muy masivos en los primeros instantes de vida del universo\u201d. Este es el titulo traducido al espa\u00f1ol del original anglosaj\u00f3n del que os vamos a hablar hoy. En principio, no tiene nada que ver con las noticias que solemos incluir en nuestro blog, pero \u201csolo en principio\u201d.","twitter:image":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png"},"aioseo_meta_data":{"post_id":"154346","title":null,"description":null,"keywords":[],"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":null,"isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":"{\"article\":{\"articleType\":\"BlogPosting\"},\"course\":{\"name\":\"\",\"description\":\"\",\"provider\":\"\"},\"faq\":{\"pages\":[]},\"product\":{\"reviews\":[]},\"recipe\":{\"ingredients\":[],\"instructions\":[],\"keywords\":[]},\"software\":{\"reviews\":[],\"operatingSystems\":[]},\"webPage\":{\"webPageType\":\"WebPage\"}}","pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","tabs":null,"priority":null,"frequency":"default","local_seo":null,"created":"2023-05-07 13:43:28","updated":"2026-05-26 19:54:50","limit_modified_date":false,"ai":null,"breadcrumb_settings":null,"seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/diversidad-complejidad-y-fractales\" title=\"Diversidad, Complejidad y Fractales\">Diversidad, Complejidad y Fractales<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tLa Estructura del Universo y el pensamiento Paretiano (\u00bfQu\u00e9 aporta la edafolog\u00eda?)\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.madrimasd.org\/blogs\/universo"},{"label":"Diversidad, Complejidad y Fractales","link":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/diversidad-complejidad-y-fractales"},{"label":"La Estructura del Universo y el pensamiento Paretiano (\u00bfQu\u00e9 aporta la edafolog\u00eda?)","link":"https:\/\/www.madrimasd.org\/blogs\/universo\/2023\/05\/18\/154346"}],"_links":{"self":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts\/154346"}],"collection":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/comments?post=154346"}],"version-history":[{"count":2,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts\/154346\/revisions"}],"predecessor-version":[{"id":154402,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts\/154346\/revisions\/154402"}],"wp:attachment":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/media?parent=154346"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/categories?post=154346"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/tags?post=154346"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}