{"id":154379,"date":"2024-11-13T13:15:40","date_gmt":"2024-11-13T12:15:40","guid":{"rendered":"https:\/\/www.madrimasd.org\/blogs\/universo\/?p=154379"},"modified":"2024-11-13T13:15:40","modified_gmt":"2024-11-13T12:15:40","slug":"islas-de-plastico-en-los-oceanos-de-un-planeta-azul","status":"publish","type":"post","link":"https:\/\/www.madrimasd.org\/blogs\/universo\/2024\/11\/13\/154379","title":{"rendered":"Islas de pl\u00e1stico en los Oc\u00e9anos de un Planeta Azul"},"content":{"rendered":"<p style=\"text-align: center\"><img decoding=\"async\" class=\"ngg-singlepic ngg-center\" src=\"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-content\/blogs.dir\/42\/files\/1283\/Islas-de-plastico.gif\" alt=\"Islas-de-plastico\"><\/p>\n<p style=\"text-align: center\"><span style=\"color: #0000ff\">Fuente: Colaje im\u00e1genes Google<\/span><\/p>\n<p>Ya hemos redactado numerosos posts sobre la denominada <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2019\/01\/21\/149192\">plasticosfera<\/a>, y no para de sorprendernos. Hace unos 15 a\u00f1os nos comenzaba a alarmar <strong><span style=\"color: #3366ff\">la acumulaci\u00f3n de residuos pl\u00e1sticos en lugares concretos y rec\u00f3nditos de los oc\u00e9anos <\/span><\/strong><span style=\"color: #3366ff\"><span style=\"color: #000000\">constatando en <\/span><\/span>poco tiempo que <strong><span style=\"color: #3366ff\">la cruda realidad superaba a nuestra imaginaci\u00f3n<\/span><\/strong>. Por aquel entonces se alegaba que, como no eran reciclables, no se descompondr\u00edan. \u201cmentira cochina\u201d. Tenemos otros posts al respecto, ya redactados y esperando su momento para ser publicados, como la <strong><span style=\"color: #3366ff\">formaci\u00f3n de rocas de pl\u00e1stico duras<\/span><\/strong>, etc. Hoy os mostramos una noticia acerca de los <span style=\"color: #3366ff\"><strong>nuevos y sorprendentes ensamblajes de seres vivos en estos enclaves que emergen de las masas oce\u00e1nicas<\/strong>. <strong>La vida se adapta a todo y tiene soluciones insuperables, nos gusten o no, sean de nuestro agrado o no<\/strong><\/span>. Estas nuevas comunidades son denominadas por los autores como \u00ab<span style=\"color: #3366ff\"><strong>comunidades neopel\u00e1gicas<\/strong><\/span>\u201d. Tambi\u00e9n es cierto que el ser humano ha creado otro tipo m\u00e1s ecol\u00f3gico (dentro de lo que cabe), como os mostramos en esta entradilla: \u201c<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2024\/09\/11\/154307\">Restauraci\u00f3n ecol\u00f3gica e Islas Artificiales<\/a>\u00bb Pero a lo que vamos. Las <strong><span style=\"color: #3366ff\">mentadas biocenosis se forman sobre las acumulaciones pl\u00e1sticas, que en algunos suelos emergidos veremos que dan lugar a rocas, a nuevos materiales parentales de \u00bfsuelos?<\/span><\/strong>. Pero hoy centr\u00e9monos sobre un aspecto relacionado con la noticia que, traducido del suajili, pero que no escriben los autores. M\u00e1s concretamente me refiero a que las <span style=\"color: #3366ff\"><strong>im\u00e1genes que he visionado acerca del enclave que mencionan y otros parecidos, dan lugar a verdaderas islas pl\u00e1sticas en medio de los oc\u00e9anos<\/strong><\/span>.<\/p>\n<p><strong><span style=\"color: #3366ff\">Por lo tanto, nuestros vertidos lugar no solo crear un nuevo tipo de \u00abrocas sint\u00e9ticas\u00bb<\/span> <\/strong><span style=\"color: #000000\">(como veremos en otro post a editar)<\/span>,<span style=\"color: #3366ff\"><strong> sino tambi\u00e9n en cierta medida crear nuevos accidentes fisiogr\u00e1ficos<\/strong><\/span>. Ciertamente el material parental ser\u00e1 pl\u00e1stico, que podr\u00e1 o no cementarse por la propia acci\u00f3n de las nuevas comunidades neopel\u00e1gicas. Ahora bien, los procesos naturales tambi\u00e9n lugar a acumulaci\u00f3n de restos org\u00e1nicos encima de las aguas que, son m\u00f3viles y han sido clasificados como un tipo de suelos que entra en la categor\u00eda de <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2011\/03\/30\/138691\">los Histosoles<\/a>, <a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2009\/01\/10\/110938\">como vimos en este post<\/a>. Obviamente no podemos alegar que sea el mismo caso, como tampoco sabemos todav\u00eda si se trata de una fisiograf\u00eda ef\u00edmera o que con el tiempo\u2026\u2026 Yo no me atrevo a especular nada ya, pero tampoco a negarlo hasta que no se monitoreen dutante a\u00f1os. <span style=\"color: #3366ff\"><strong>Nosotros introducimos estos asquerosos materiales y ahora la vida se encargar\u00e1 \u201ca su manera\u201d de medrar sobre ellos<\/strong><\/span>. Por favor buscar im\u00e1genes en Internet, ya que el colaje grafico que encabeza esta entradilla no refleja la gravedad y vistosidad de lo que realmente acaece.<\/p>\n<p><span style=\"color: #008000\"><strong>Juan Jose Iba\u00f1ez<\/strong><\/span><\/p>\n<p><span style=\"color: #800000\"><em>Contin\u00faa\u2026\u2026\u2026.<\/em><\/span><\/p>\n<p><!--more--><\/p>\n<p><strong>Fotos impresionantes en Google al buscar por \u201c<a href=\"https:\/\/www.google.es\/search?q=%E2%80%9Cgarbage+patch%E2%80%9D+%E2%80%9CPacific+Ocean&amp;source=lnms&amp;tbm=isch&amp;sa=X&amp;ved=2ahUKEwi4-MKLivD-AhXERaQEHfU5Br8Q_AUoAXoECAEQAw&amp;biw=1872&amp;bih=969&amp;dpr=1\">garbage patch\u201d \u201cPacific Ocean\u201d<\/a><\/strong><\/p>\n<h4><strong><a href=\"https:\/\/www.scientificamerican.com\/article\/surprising-creatures-lurk-in-the-great-pacific-garbage-patch\/?utm_source=Nature+Briefing&amp;utm_campaign=67313afc6d-briefing-dy-20230418&amp;utm_medium=email&amp;utm_term=0_c9dfd39373-67313afc6d-46405550\">Sorprendentes criaturas acechan en el Gran Parche de Basura del Pac\u00edfico<\/a><\/strong><\/h4>\n<p>En el Gran Parche de Basura del Pac\u00edfico, el pl\u00e1stico crea comunidades extra\u00f1as que unen a los animales costeros y de mar abierto<\/p>\n<p>Por&nbsp;<a href=\"https:\/\/www.scientificamerican.com\/author\/meghan-bartels\/\">Meghan Bartels<\/a>on&nbsp;abril 17, 2023<\/p>\n<p><strong>Los pl\u00e1sticos que flotan en un enorme \u00abparche de basura\u00bb en el Oc\u00e9ano Pac\u00edfico albergan nuevas y extra\u00f1as mezclas de especies costeras y marinas que podr\u00edan aumentar las probabilidades de que las invasiones biol\u00f3gicas causen estragos en los ecosistemas cercanos<\/strong>.<\/p>\n<p>Los cient\u00edficos saben desde hace tiempo que <strong>criaturas como gusanos, crust\u00e1ceos y moluscos podr\u00edan hacer su hogar en<\/strong>&nbsp;<a href=\"https:\/\/www.scientificamerican.com\/article\/microplastics-earth-has-a-hidden-plastic-problem-mdash-scientists-are-hunting-it-down\/\">los desechos pl\u00e1sticos<\/a>. Los animales incluso han cruzado el Oc\u00e9ano Pac\u00edfico en estas balsas improvisadas&nbsp;<a href=\"https:\/\/www.scientificamerican.com\/article\/remains-of-the-day\/\">despu\u00e9s de que un devastador tsunami azotara Jap\u00f3n en 2011<\/a>. Pero una nueva investigaci\u00f3n publicada el 17 de abril en la revista&nbsp;<em>Nature Ecology &amp; Evolution<\/em>&nbsp;agrega dos detalles que podr\u00edan ser preocupantes para los ecosistemas existentes. Primero, encuentra que el&nbsp;<a href=\"https:\/\/www.nature.com\/articles\/s41559-023-01997-y\"><strong>pl\u00e1stico est\u00e1 proporcionando un hogar para que las especies costeras prosperen en el oc\u00e9ano abierto<\/strong><\/a><strong>&nbsp;a miles de millas de la costa<\/strong>. En segundo lugar, algunas de estas especies se est\u00e1n reproduciendo a pesar del ambiente alien\u00edgena.<\/p>\n<p>\u00ab<strong>Es probablemente uno de los ambientes menos conocidos, la superficie del mar<\/strong>\u00ab, dice Martin Thiel, bi\u00f3logo marino de la Universidad Cat\u00f3lica del Norte en Chile, que no particip\u00f3 en la nueva investigaci\u00f3n. \u00abEs una comunidad muy, muy particular que estamos perturbando ahora a gran escala\u00bb.<\/p>\n<p>Para el nuevo estudio, los investigadores <strong>identificaron especies que viven en poco m\u00e1s de 100 piezas de pl\u00e1stico que se pescaron en el llamado&nbsp;<\/strong><a href=\"https:\/\/www.scientificamerican.com\/article\/sea-unworthy-a-personal-journey-into-the-pacific-garbage-patch-slide-show\/\"><strong>Gran Parche de Basura<\/strong><\/a><strong>&nbsp;del Pac\u00edfico<\/strong>, <strong>una regi\u00f3n en el norte del Oc\u00e9ano Pac\u00edfico donde las corrientes convergen para depositar aproximadamente&nbsp;<\/strong><a href=\"https:\/\/www.nature.com\/articles\/s41598-018-22939-w\"><strong>79,000 toneladas m\u00e9tricas de desechos pl\u00e1sticos<\/strong><\/a>. Los cient\u00edficos <strong>identificaron 484 invertebrados de una sorprendente variedad de especies en el pl\u00e1stico. Muchos de estos animales eran especies que se encuentran m\u00e1s com\u00fanmente cerca de las costas del Pac\u00edfico occidental. Estas especies costeras inclu\u00edan \u00abanimales de musgo\u00bb o briozoos, medusas, esponjas, gusanos y otros organismos<\/strong>.<\/p>\n<p>\u00abSolo recuerdo la primera vez que [el coautor del estudio] Jim [Carlton de Williams College y Mystic Seaport Museum] y yo sacamos un pedazo de pl\u00e1stico y vimos el nivel de especies costeras presentes, simplemente nos quedamos impresionados\u00bb, dice Linsey Haram, autora principal del estudio. Haram, quien fue investigador asociado del Centro de Investigaci\u00f3n Ambiental Smithsonian durante el estudio, se especializa en ecolog\u00eda marina.<\/p>\n<p><strong>Casi todos los escombros albergaban especies pel\u00e1gicas o de mar abierto, lo que tiene sentido<\/strong> teniendo en cuenta que la erosi\u00f3n de&nbsp;<a href=\"https:\/\/www.scientificamerican.com\/report\/how-plastic-became-a-plague\/\">gran parte del pl\u00e1stico<\/a>&nbsp;suger\u00eda que hab\u00eda pasado varios a\u00f1os en el mar. <strong>Pero en total, alrededor del 70 por ciento de los escombros que los investigadores analizaron llevaban al menos una especie que generalmente se encuentra en aguas costeras<\/strong>, un recuento mucho m\u00e1s alto de lo que Haram y sus colegas esperaban al entrar en el trabajo, dice.<\/p>\n<p>Y a medida que miraban m\u00e1s de cerca, los cient\u00edficos descubrieron que <strong>alrededor de dos tercios de las piezas de escombros albergaban especies costeras y de mar abierto que viv\u00edan una al lado de la otra. El pl\u00e1stico no solo transporta especies costeras al mar; Tambi\u00e9n est\u00e1 creando vecindarios antinaturales que los investigadores llaman \u00ab<\/strong><strong>comunidades neopel\u00e1gicas<\/strong>\u00ab.<\/p>\n<p>\u00abLo que es nuevo, la parte &#8216;neo&#8217; de eso, es que ahora, probablemente <strong>debido a los pl\u00e1sticos, estamos viendo especies costeras y estas especies pel\u00e1gicas nativas juntas, interactuando con bastante frecuencia sobre los escombros<\/strong>\u00ab, dice Haram. \u00abEsencialmente estamos creando nuevas comunidades en el oc\u00e9ano abierto\u00bb.<\/p>\n<p>ADVERTISEMENT<\/p>\n<p>Y estas comunidades antinaturales <strong>pueden tener un costo para los residentes tradicionales de mar abierto que est\u00e1n acostumbrados a vivir en desechos naturales, agrega, porque las criaturas costeras podr\u00edan estar compitiendo por el espacio y la comida o incluso podr\u00edan estar comiendo a sus vecinos<\/strong>.<\/p>\n<p>Haram y sus colegas encontraron se\u00f1ales de que estas especies costeras se estaban reproduciendo. Por ejemplo, encontraron artr\u00f3podos parecidos a insectos que tienden a garras de huevos y an\u00e9monas que brotan peque\u00f1os clones de s\u00ed mismos, <strong>indicadores que sugieren que las reubicaciones ayudadas por el pl\u00e1stico no son necesariamente temporales<\/strong>. <strong>Y el pl\u00e1stico en el Gran Parche de Basura del Pac\u00edfico no necesariamente permanece all\u00ed, sino que puede lavarse en playas extranjeras, donde las especies trasplantadas podr\u00edan echar ra\u00edces<\/strong>.<\/p>\n<p>\u00ab<strong>Si puedes reproducirte, entonces puedes propagar<\/strong>. Y si puedes propagarte, puedes invadir\u00bb, dice Linda Amaral-Zettler, microbi\u00f3loga marina del Real Instituto Holand\u00e9s de Investigaci\u00f3n del Mar, que no particip\u00f3 en el nuevo estudio. \u00abNo eres solo un callej\u00f3n sin salida; No solo est\u00e1s haciendo autostop y luego pereciendo al final\u00bb. Ella espera que la investigaci\u00f3n sirva como una advertencia de que el <strong>pl\u00e1stico puede estar facilitando las invasiones de especies<\/strong>, particularmente entre ecosistemas costeros generalizados.<\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #800000\">Suscr\u00edbase a los boletines informativos gratuitos de&nbsp;<em>Scientific American<\/em><\/span>.&nbsp;<a href=\"https:\/\/www.scientificamerican.com\/page\/newsletter-sign-up\/?origincode=2018_sciam_ArticlePromo_NewsletterSignUp\">\u00danete<\/a><\/p>\n<p><strong>Debido a que todos los escombros del estudio provienen del norte del Oc\u00e9ano Pac\u00edfico, no est\u00e1 claro si las especies costeras est\u00e1n haciendo viajes similares en otros oc\u00e9anos<\/strong>. Amaral-Zettler se pregunta particularmente qu\u00e9 podr\u00eda estar sucediendo en el Atl\u00e1ntico norte, donde las&nbsp;<a href=\"https:\/\/www.scientificamerican.com\/article\/heres-the-real-story-behind-the-massive-blob-of-seaweed-heading-toward-florida\/\"><strong>algas&nbsp;<\/strong><strong><em>Sargassum<\/em><\/strong><strong>&nbsp;flotantes<\/strong><\/a><strong>&nbsp;ofrecen un punto de apoyo natural en el oc\u00e9ano abierto, uno que podr\u00eda ser vulnerable a la invasi\u00f3n de especies que viajan sobre desechos pl\u00e1sticos<\/strong>. (Los colegas de Haram est\u00e1n trabajando para determinar si los animales encontrados en el estudio pueden reubicarse en balsas de escombros adicionales o est\u00e1n atrapados en su pieza original de pl\u00e1stico, dice ella).<\/p>\n<p>El nuevo trabajo destaca una forma diferente en que la inundaci\u00f3n de&nbsp;<a href=\"https:\/\/www.scientificamerican.com\/article\/the-deep-ocean-harbors-a-mountain-of-microplastic-pollution\/\">pl\u00e1stico est\u00e1 interfiriendo con el medio ambiente natural<\/a>, una m\u00e1s all\u00e1 del da\u00f1o bien publicitado que hace a especies como peces, tortugas y aves marinas. \u00abSabemos mucho en este momento sobre el enredo y la ingesti\u00f3n, los enormes impactos negativos que resultan de eso\u00bb, dice Haram. \u00abLa investigaci\u00f3n que estamos haciendo aqu\u00ed agrega un tipo muy diferente de efecto que tienen los pl\u00e1sticos que anteriormente no se estaba considerando\u00bb.<\/p>\n<p>Thiel est\u00e1 de acuerdo y agrega que la investigaci\u00f3n tambi\u00e9n deber\u00eda recordarnos que sabemos m\u00e1s que suficiente sobre el da\u00f1o de la contaminaci\u00f3n pl\u00e1stica para responder seriamente. \u00abPara m\u00ed, es otra llamada de advertencia para nosotros de que definitivamente necesitamos tomar medidas dr\u00e1sticas y dr\u00e1sticas para reducir la cantidad de basura pl\u00e1stica que va al oc\u00e9ano\u00bb, dice Thiel. \u00abCuando est\u00e1 en mar abierto, es demasiado tarde\u00bb.<\/p>\n<p><strong>Fotos impresionantes en Google al buscar por \u201c<\/strong><a href=\"https:\/\/www.google.es\/search?q=%E2%80%9Cgarbage+patch%E2%80%9D+%E2%80%9CPacific+Ocean&amp;source=lnms&amp;tbm=isch&amp;sa=X&amp;ved=2ahUKEwi4-MKLivD-AhXERaQEHfU5Br8Q_AUoAXoECAEQAw&amp;biw=1872&amp;bih=969&amp;dpr=1\"><strong>garbage patch\u201d \u201cPacific Ocean\u201d<\/strong><\/a><\/p>\n<h3>Im\u00e1genes Relacionadas:<\/h3>","protected":false},"excerpt":{"rendered":"<p>Fuente: Colaje im\u00e1genes Google Ya hemos redactado numerosos posts sobre la denominada plasticosfera, y no para de sorprendernos. Hace unos 15 a\u00f1os nos comenzaba a alarmar la acumulaci\u00f3n de residuos pl\u00e1sticos en lugares concretos y rec\u00f3nditos de los oc\u00e9anos constatando en poco tiempo que la cruda realidad superaba a nuestra imaginaci\u00f3n. Por aquel entonces se alegaba que, como no eran reciclables, no se descompondr\u00edan. \u201cmentira cochina\u201d. Tenemos otros posts al respecto, ya redactados y esperando su momento para ser publicados, como la formaci\u00f3n de rocas de pl\u00e1stico duras, etc. Hoy os mostramos una noticia acerca de los nuevos y sorprendentes\u2026<\/p>\n","protected":false},"author":26,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0},"categories":[603,594,618,588,607,617],"tags":[54672,9819,54670,46674,54669,46885,54671],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":4}},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Fuente: Colaje im\u00e1genes Google Ya hemos redactado numerosos posts sobre la denominada plasticosfera, y no para de sorprendernos. Hace unos 15 a\u00f1os nos comenzaba a alarmar la acumulaci\u00f3n de residuos pl\u00e1sticos en lugares concretos y rec\u00f3nditos de los oc\u00e9anos constatando en poco tiempo que la cruda realidad superaba a nuestra imaginaci\u00f3n. Por aquel entonces se\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Juan Jos\u00e9 Ib\u00e1\u00f1ez\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2024\/11\/13\/154379\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Un Universo invisible bajo nuestros pies - Los suelos y la vida\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Islas de pl\u00e1stico en los Oc\u00e9anos de un Planeta Azul - Un Universo invisible bajo nuestros pies\" \/>\n\t\t<meta property=\"og:description\" content=\"Fuente: Colaje im\u00e1genes Google Ya hemos redactado numerosos posts sobre la denominada plasticosfera, y no para de sorprendernos. Hace unos 15 a\u00f1os nos comenzaba a alarmar la acumulaci\u00f3n de residuos pl\u00e1sticos en lugares concretos y rec\u00f3nditos de los oc\u00e9anos constatando en poco tiempo que la cruda realidad superaba a nuestra imaginaci\u00f3n. Por aquel entonces se\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2024\/11\/13\/154379\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2024-11-13T12:15:40+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2024-11-13T12:15:40+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/juan.j.marti.14\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Islas de pl\u00e1stico en los Oc\u00e9anos de un Planeta Azul - Un Universo invisible bajo nuestros pies\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Fuente: Colaje im\u00e1genes Google Ya hemos redactado numerosos posts sobre la denominada plasticosfera, y no para de sorprendernos. Hace unos 15 a\u00f1os nos comenzaba a alarmar la acumulaci\u00f3n de residuos pl\u00e1sticos en lugares concretos y rec\u00f3nditos de los oc\u00e9anos constatando en poco tiempo que la cruda realidad superaba a nuestra imaginaci\u00f3n. Por aquel entonces se\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2024\\\/11\\\/13\\\/154379#blogposting\",\"name\":\"Islas de pl\\u00e1stico en los Oc\\u00e9anos de un Planeta Azul - Un Universo invisible bajo nuestros pies\",\"headline\":\"Islas de pl\\u00e1stico en los Oc\\u00e9anos de un Planeta Azul\",\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/wp-content\\\/blogs.dir\\\/42\\\/files\\\/1283\\\/Islas-de-plastico.gif\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2024\\\/11\\\/13\\\/154379\\\/#articleImage\"},\"datePublished\":\"2024-11-13T13:15:40+01:00\",\"dateModified\":\"2024-11-13T13:15:40+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2024\\\/11\\\/13\\\/154379#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2024\\\/11\\\/13\\\/154379#webpage\"},\"articleSection\":\"Carpeta sobre Paisajes de Suelos y los Suelos en el Paisaje, Degradaci\\u00f3n de Suelos: Contaminaci\\u00f3n, Ecolog\\u00eda y Biogeograf\\u00eda post posteriores a agosto de 2009, El Concepto de Suelo y Sus Representaciones, Historia de la Tierra y de los Suelos., Procesos Superficiales terrestres: Relieve, Geomorfolog\\u00eda y Cuencas de Drenaje:, biogeomorfolog\\u00eda, cartograf\\u00eda, castores, contaminaci\\u00f3n, estanques, h\\u00e1bitat, reciclado de los Nutrientes\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2024\\\/11\\\/13\\\/154379#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/el-concepto-de-suelo-y-sus-representaciones#listItem\",\"name\":\"El Concepto de Suelo y Sus Representaciones\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/el-concepto-de-suelo-y-sus-representaciones#listItem\",\"position\":2,\"name\":\"El Concepto de Suelo y Sus Representaciones\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/el-concepto-de-suelo-y-sus-representaciones\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2024\\\/11\\\/13\\\/154379#listItem\",\"name\":\"Islas de pl\\u00e1stico en los Oc\\u00e9anos de un Planeta Azul\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2024\\\/11\\\/13\\\/154379#listItem\",\"position\":3,\"name\":\"Islas de pl\\u00e1stico en los Oc\\u00e9anos de un Planeta Azul\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/el-concepto-de-suelo-y-sus-representaciones#listItem\",\"name\":\"El Concepto de Suelo y Sus Representaciones\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#organization\",\"name\":\"Un Universo invisible bajo nuestros pies\",\"description\":\"Los suelos y la vida\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/files\\\/2022\\\/02\\\/logo.png\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2024\\\/11\\\/13\\\/154379\\\/#organizationLogo\",\"width\":217,\"height\":72},\"image\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2024\\\/11\\\/13\\\/154379\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/juan.j.marti.14\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo\",\"name\":\"Juan Jos\\u00e9 Ib\\u00e1\\u00f1ez\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2024\\\/11\\\/13\\\/154379#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/387f3a100385573d8f42ce2a3211fd1c?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Juan Jos\\u00e9 Ib\\u00e1\\u00f1ez\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2024\\\/11\\\/13\\\/154379#webpage\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2024\\\/11\\\/13\\\/154379\",\"name\":\"Islas de pl\\u00e1stico en los Oc\\u00e9anos de un Planeta Azul - Un Universo invisible bajo nuestros pies\",\"description\":\"Fuente: Colaje im\\u00e1genes Google Ya hemos redactado numerosos posts sobre la denominada plasticosfera, y no para de sorprendernos. Hace unos 15 a\\u00f1os nos comenzaba a alarmar la acumulaci\\u00f3n de residuos pl\\u00e1sticos en lugares concretos y rec\\u00f3nditos de los oc\\u00e9anos constatando en poco tiempo que la cruda realidad superaba a nuestra imaginaci\\u00f3n. Por aquel entonces se\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2024\\\/11\\\/13\\\/154379#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\"},\"datePublished\":\"2024-11-13T13:15:40+01:00\",\"dateModified\":\"2024-11-13T13:15:40+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#website\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/\",\"name\":\"Un Universo invisible bajo nuestros pies\",\"description\":\"Los suelos y la vida\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Islas de pl\u00e1stico en los Oc\u00e9anos de un Planeta Azul - Un Universo invisible bajo nuestros pies","description":"Fuente: Colaje im\u00e1genes Google Ya hemos redactado numerosos posts sobre la denominada plasticosfera, y no para de sorprendernos. Hace unos 15 a\u00f1os nos comenzaba a alarmar la acumulaci\u00f3n de residuos pl\u00e1sticos en lugares concretos y rec\u00f3nditos de los oc\u00e9anos constatando en poco tiempo que la cruda realidad superaba a nuestra imaginaci\u00f3n. Por aquel entonces se","canonical_url":"https:\/\/www.madrimasd.org\/blogs\/universo\/2024\/11\/13\/154379","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2024\/11\/13\/154379#blogposting","name":"Islas de pl\u00e1stico en los Oc\u00e9anos de un Planeta Azul - Un Universo invisible bajo nuestros pies","headline":"Islas de pl\u00e1stico en los Oc\u00e9anos de un Planeta Azul","author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author"},"publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-content\/blogs.dir\/42\/files\/1283\/Islas-de-plastico.gif","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2024\/11\/13\/154379\/#articleImage"},"datePublished":"2024-11-13T13:15:40+01:00","dateModified":"2024-11-13T13:15:40+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2024\/11\/13\/154379#webpage"},"isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2024\/11\/13\/154379#webpage"},"articleSection":"Carpeta sobre Paisajes de Suelos y los Suelos en el Paisaje, Degradaci\u00f3n de Suelos: Contaminaci\u00f3n, Ecolog\u00eda y Biogeograf\u00eda post posteriores a agosto de 2009, El Concepto de Suelo y Sus Representaciones, Historia de la Tierra y de los Suelos., Procesos Superficiales terrestres: Relieve, Geomorfolog\u00eda y Cuencas de Drenaje:, biogeomorfolog\u00eda, cartograf\u00eda, castores, contaminaci\u00f3n, estanques, h\u00e1bitat, reciclado de los Nutrientes"},{"@type":"BreadcrumbList","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2024\/11\/13\/154379#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo#listItem","position":1,"name":"Home","item":"https:\/\/www.madrimasd.org\/blogs\/universo","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/el-concepto-de-suelo-y-sus-representaciones#listItem","name":"El Concepto de Suelo y Sus Representaciones"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/el-concepto-de-suelo-y-sus-representaciones#listItem","position":2,"name":"El Concepto de Suelo y Sus Representaciones","item":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/el-concepto-de-suelo-y-sus-representaciones","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2024\/11\/13\/154379#listItem","name":"Islas de pl\u00e1stico en los Oc\u00e9anos de un Planeta Azul"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2024\/11\/13\/154379#listItem","position":3,"name":"Islas de pl\u00e1stico en los Oc\u00e9anos de un Planeta Azul","previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/el-concepto-de-suelo-y-sus-representaciones#listItem","name":"El Concepto de Suelo y Sus Representaciones"}}]},{"@type":"Organization","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#organization","name":"Un Universo invisible bajo nuestros pies","description":"Los suelos y la vida","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/","logo":{"@type":"ImageObject","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2024\/11\/13\/154379\/#organizationLogo","width":217,"height":72},"image":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2024\/11\/13\/154379\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/juan.j.marti.14"]},{"@type":"Person","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo","name":"Juan Jos\u00e9 Ib\u00e1\u00f1ez","image":{"@type":"ImageObject","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2024\/11\/13\/154379#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/387f3a100385573d8f42ce2a3211fd1c?s=96&d=mm&r=g","width":96,"height":96,"caption":"Juan Jos\u00e9 Ib\u00e1\u00f1ez"}},{"@type":"WebPage","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2024\/11\/13\/154379#webpage","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/2024\/11\/13\/154379","name":"Islas de pl\u00e1stico en los Oc\u00e9anos de un Planeta Azul - Un Universo invisible bajo nuestros pies","description":"Fuente: Colaje im\u00e1genes Google Ya hemos redactado numerosos posts sobre la denominada plasticosfera, y no para de sorprendernos. Hace unos 15 a\u00f1os nos comenzaba a alarmar la acumulaci\u00f3n de residuos pl\u00e1sticos en lugares concretos y rec\u00f3nditos de los oc\u00e9anos constatando en poco tiempo que la cruda realidad superaba a nuestra imaginaci\u00f3n. Por aquel entonces se","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#website"},"breadcrumb":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2024\/11\/13\/154379#breadcrumblist"},"author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author"},"creator":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author"},"datePublished":"2024-11-13T13:15:40+01:00","dateModified":"2024-11-13T13:15:40+01:00"},{"@type":"WebSite","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#website","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/","name":"Un Universo invisible bajo nuestros pies","description":"Los suelos y la vida","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Un Universo invisible bajo nuestros pies - Los suelos y la vida","og:type":"article","og:title":"Islas de pl\u00e1stico en los Oc\u00e9anos de un Planeta Azul - Un Universo invisible bajo nuestros pies","og:description":"Fuente: Colaje im\u00e1genes Google Ya hemos redactado numerosos posts sobre la denominada plasticosfera, y no para de sorprendernos. Hace unos 15 a\u00f1os nos comenzaba a alarmar la acumulaci\u00f3n de residuos pl\u00e1sticos en lugares concretos y rec\u00f3nditos de los oc\u00e9anos constatando en poco tiempo que la cruda realidad superaba a nuestra imaginaci\u00f3n. Por aquel entonces se","og:url":"https:\/\/www.madrimasd.org\/blogs\/universo\/2024\/11\/13\/154379","og:image":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png","og:image:secure_url":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png","article:published_time":"2024-11-13T12:15:40+00:00","article:modified_time":"2024-11-13T12:15:40+00:00","article:publisher":"https:\/\/www.facebook.com\/juan.j.marti.14","twitter:card":"summary","twitter:title":"Islas de pl\u00e1stico en los Oc\u00e9anos de un Planeta Azul - Un Universo invisible bajo nuestros pies","twitter:description":"Fuente: Colaje im\u00e1genes Google Ya hemos redactado numerosos posts sobre la denominada plasticosfera, y no para de sorprendernos. Hace unos 15 a\u00f1os nos comenzaba a alarmar la acumulaci\u00f3n de residuos pl\u00e1sticos en lugares concretos y rec\u00f3nditos de los oc\u00e9anos constatando en poco tiempo que la cruda realidad superaba a nuestra imaginaci\u00f3n. Por aquel entonces se","twitter:image":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png"},"aioseo_meta_data":{"post_id":"154379","title":null,"description":null,"keywords":[],"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":"{\"article\":{\"articleType\":\"BlogPosting\"},\"course\":{\"name\":\"\",\"description\":\"\",\"provider\":\"\"},\"faq\":{\"pages\":[]},\"product\":{\"reviews\":[]},\"recipe\":{\"ingredients\":[],\"instructions\":[],\"keywords\":[]},\"software\":{\"reviews\":[],\"operatingSystems\":[]},\"webPage\":{\"webPageType\":\"WebPage\"}}","pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","tabs":null,"priority":0,"frequency":"default","local_seo":null,"created":"2023-05-12 15:27:50","updated":"2026-05-26 20:23:53","limit_modified_date":false,"ai":null,"breadcrumb_settings":null,"seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/el-concepto-de-suelo-y-sus-representaciones\" title=\"El Concepto de Suelo y Sus Representaciones\">El Concepto de Suelo y Sus Representaciones<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tIslas de pl\u00e1stico en los Oc\u00e9anos de un Planeta Azul\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.madrimasd.org\/blogs\/universo"},{"label":"El Concepto de Suelo y Sus Representaciones","link":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/el-concepto-de-suelo-y-sus-representaciones"},{"label":"Islas de pl\u00e1stico en los Oc\u00e9anos de un Planeta Azul","link":"https:\/\/www.madrimasd.org\/blogs\/universo\/2024\/11\/13\/154379"}],"_links":{"self":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts\/154379"}],"collection":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/comments?post=154379"}],"version-history":[{"count":2,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts\/154379\/revisions"}],"predecessor-version":[{"id":155996,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts\/154379\/revisions\/155996"}],"wp:attachment":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/media?parent=154379"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/categories?post=154379"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/tags?post=154379"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}