{"id":16841,"date":"2006-03-26T18:09:00","date_gmt":"2006-03-26T18:09:00","guid":{"rendered":"http:\/\/weblogs.madrimasd.org\/\/universo\/archive\/2006\/03\/26\/16841.aspx"},"modified":"2010-01-22T03:39:51","modified_gmt":"2010-01-22T02:39:51","slug":"la-erosion-historica-y-los-paisajes-vegetales-mediterraneos","status":"publish","type":"post","link":"https:\/\/www.madrimasd.org\/blogs\/universo\/2006\/03\/26\/16841","title":{"rendered":"La Erosi\u00f3n Hist\u00f3rica y los Paisajes Vegetales Mediterr\u00e1neos"},"content":{"rendered":"<p class=\"MsoNormal\" style=\"MARGIN: 0cm 0cm 0pt; TEXT-ALIGN: justify\"><span lang=\"ES\" style=\"FONT-SIZE: 10pt; FONT-FAMILY: 'Comic Sans MS'; mso-ansi-language: ES-TRAD\">En los \u00faltimos a\u00f1os se ha recopilado abundante informaci\u00f3n sobre los paleoclimas y vegetaci\u00f3n del pasado en la Cuenca Mediterr\u00e1nea. De los datos obtenidos en diversos estudios se desprende que, tras la \u00faltima glaciaci\u00f3n y especialmente despu\u00e9s de la emergencia de las <span style=\"COLOR: blue\">culturas neol\u00edticas,<\/span> hace unos 8.500 a\u00f1os en el \u00abcreciente f\u00e9rtil y\/o alrededores del Mar Negro, muchos <span style=\"COLOR: blue\">bosques <\/span>de <i style=\"mso-bidi-font-style: normal\">Quecus<\/i> <span style=\"COLOR: blue\">caducifolios fueron sustituidos por otros escler\u00f3filos e incluso por maquis y garrigas<\/span>. No existe consenso entre los especialistas sobre si fue el <span style=\"COLOR: blue\">cambio clim\u00e1tico o la acci\u00f3n antr\u00f3picas<\/span> la responsable de esta <span style=\"COLOR: blue\">aridificaci\u00f3n del paisaje<\/span>, present\u00e1ndose evidencias a favor de ambas hip\u00f3tesis.<o:p><\/o:p><\/span><\/p>\n<p><!--more--><\/p>\n<p class=\"MsoNormal\" style=\"MARGIN: 0cm 0cm 0pt; TEXT-ALIGN: justify\"><span lang=\"ES\" style=\"FONT-SIZE: 10pt; COLOR: #cc0000; FONT-FAMILY: 'Comic Sans MS'; mso-ansi-language: ES-TRAD\">J. L. Gonz\u00e1lez Rebollar<\/span><span lang=\"ES\" style=\"FONT-SIZE: 10pt; FONT-FAMILY: 'Comic Sans MS'; mso-ansi-language: ES-TRAD\"> (Estaci\u00f3n Experimental del Zaid\u00edn, CSIC, Granada) observ\u00f3, que en antiguos estudios geobot\u00e1nicos, varios autores consideraban que la<span style=\"COLOR: blue\"> erosi\u00f3n del suelo<\/span> en las <span style=\"COLOR: blue\">\u00e1reas de monta\u00f1a <\/span>generaban una reducci\u00f3n e incluso la <span style=\"COLOR: blue\">desaparici\u00f3n <\/span>del piso de<span style=\"COLOR: blue\"> vegetaci\u00f3n<\/span> <span style=\"COLOR: blue\">caducifolia<\/span> a <span style=\"COLOR: blue\">favor de los bosques<\/span> de <i style=\"mso-bidi-font-style: normal\">Quecus<\/i> <span style=\"COLOR: blue\">escler\u00f3filos<\/span> del piso inferior<span style=\"COLOR: blue\"> y<\/span> <span style=\"COLOR: blue\">de las<\/span> <span style=\"COLOR: blue\">con\u00edferas<\/span> del superior (al que denominamos <span style=\"COLOR: #cc0000\">Efecto Pinza<\/span> J. L. Gonz\u00e1lez Rebollar, J. J. Ib\u00e1\u00f1ez y A. Garc\u00eda \u00c1lvarez). De este modo, se generaba el susodicho \u00abefecto pinza\u00bb sobre los bosques <span style=\"COLOR: blue\">caducifolios<\/span>. <o:p><\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" style=\"MARGIN: 0cm 0cm 0pt; TEXT-ALIGN: justify\"><span lang=\"ES\" style=\"FONT-SIZE: 10pt; FONT-FAMILY: 'Comic Sans MS'; mso-ansi-language: ES-TRAD\"><o:p>&nbsp;<\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" style=\"MARGIN: 0cm 0cm 0pt; TEXT-ALIGN: justify\"><span lang=\"ES\" style=\"FONT-SIZE: 10pt; FONT-FAMILY: 'Comic Sans MS'; mso-ansi-language: ES-TRAD\">Mediante un programa de simulaci\u00f3n num\u00e9rica denominado \u00ab<span style=\"COLOR: blue\">Diagramas Fitoclim\u00e1ticos<\/span>\u00ab, estos investigadores constataron que<span style=\"COLOR: #cc0000\"> <\/span>tanto<span style=\"COLOR: #cc0000\"> el cambio clim\u00e1tico<\/span> como la <span style=\"COLOR: #cc0000\">erosi\u00f3n del suelo generaban una aridificaci\u00f3n similar <\/span>de los paisajes mediterr\u00e1neos (ver Figuras de la<span style=\"COLOR: blue\"> Galer\u00eda Fotos de Erosi\u00f3n y P\u00e9rdida de Suelo<\/span>). En consecuencia, todo parece apuntar a que la erosi\u00f3n en el mediterr\u00e1neo, con independencia del cambio clim\u00e1tico, puede promover la expansi\u00f3n de los bosques escler\u00f3filos, maquis y garrigas, en detrimento de los bosques caducifolios. Vistos los valores de los \u00edndices de leptosolizaci\u00f3n, es razonable pensar que la <span style=\"COLOR: #cc0000\">erosi\u00f3n del suelo generada, tras la aparici\u00f3n de las culturas neol\u00edticas, modific\u00f3 dr\u00e1sticamente el paisaje<\/span>, al menos en muchas regiones peninsulares. <o:p><\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" style=\"MARGIN: 0cm 0cm 0pt; TEXT-ALIGN: justify\"><span lang=\"ES\" style=\"FONT-SIZE: 10pt; FONT-FAMILY: 'Comic Sans MS'; mso-ansi-language: ES-TRAD\"><o:p>&nbsp;<\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" style=\"MARGIN: 0cm 0cm 0pt; TEXT-ALIGN: justify; mso-layout-grid-align: none\"><span lang=\"ES\" style=\"FONT-SIZE: 10pt; COLOR: #cc0000; FONT-FAMILY: 'Comic Sans MS'; mso-ansi-language: ES-TRAD\">Resumiendo<\/span><span lang=\"ES\" style=\"FONT-SIZE: 10pt; FONT-FAMILY: 'Comic Sans MS'; mso-ansi-language: ES-TRAD\">, gran parte de la erosi\u00f3n potencial de la Cuenca Mediterr\u00e1nea se produjo en tiempos prehist\u00f3ricos e hist\u00f3ricos, siendo generadora de los paisajes actuales. Sin embargo, las pr\u00e1cticas agr\u00edcolas actuales y el abandono de las culturas rurales sustentables est\u00e1n afectando a enclaves que con anterioridad no hab\u00edan sido presa de este proceso (incluidos los templado-h\u00famedos del oeste del continente). Muy posiblemente, lo mismo sea cierto en las <span style=\"COLOR: blue\">regiones pan\u00f3nicas y est\u00e9pico-\u00e1ridas del sur y este del continente,<\/span> que incluyen por ejemplo varios pa\u00edses que bordean el Mar Negro y el Caspio. Existen suficientes evidencias que sustentan esta hip\u00f3tesis. En este Sentido, recomendamos la lectura de la leyenda del Proyecto Glasod:<\/span><b><span lang=\"ES\" style=\"FONT-FAMILY: TimesNewRoman,Bold; mso-bidi-font-family: 'TimesNewRoman,Bold'; mso-ansi-language: ES; mso-bidi-font-size: 12.0pt\"> <\/span><\/b><b><span style=\"FONT-SIZE: 10pt; FONT-FAMILY: 'Comic Sans MS'; mso-bidi-font-family: 'TimesNewRoman,Bold'; mso-ansi-language: ES\"><a href=\"http:\/\/www.isric.org\/isric\/webdocs\/Docs\/ExplanNote.pdf\">world map of the status of<span style=\"mso-spacerun: yes\">&nbsp; <\/span>human-induced soil degradation <\/a><\/span><\/b><span style=\"FONT-SIZE: 10pt; FONT-FAMILY: 'Comic Sans MS'; mso-ansi-language: ES\"><span style=\"mso-spacerun: yes\">&nbsp;<\/span>(p. ej. <\/span><span lang=\"ES\" style=\"FONT-SIZE: 10pt; FONT-FAMILY: 'Comic Sans MS'; mso-ansi-language: ES-TRAD\">Oldeman 1990). Tambi\u00e9n son interesantes, aunque con bastantes lagunas y sesgos, ciertos informes de la Agencia Europea de Medio Ambiente sobre degradaci\u00f3n de Suelos (<\/span><span style=\"FONT-SIZE: 10pt; FONT-FAMILY: 'Comic Sans MS'; mso-bidi-font-family: Avenir-Heavy; mso-ansi-language: ES\"><a href=\"http:\/\/reports.eea.eu.int\/92-9157-202-0\/en\/3.6.pdf\">Soil degradation<\/a>). Lamentablemente no hemos podido encontrar la m\u00e1s que interesante monograf\u00eda de G. W. J. Van Lynden: \u00ab<\/span><i style=\"mso-bidi-font-style: normal\"><span style=\"FONT-SIZE: 10pt; FONT-FAMILY: 'Comic Sans MS'; mso-ansi-language: ES\">The European Soil Resource: Current Status of Soil degradation causes, impacts and need for action. Council of Europe. Strasbourg<\/span><\/i><span style=\"FONT-SIZE: 10pt; FONT-FAMILY: 'Comic Sans MS'; mso-ansi-language: ES\">\u00ab, publicada en 1994, ya que es la que nos parece el trabajo realizado en la materia aqu\u00ed comentada.<\/span><span style=\"FONT-SIZE: 10pt; FONT-FAMILY: 'Comic Sans MS'; mso-bidi-font-family: Avenir-Heavy; mso-ansi-language: ES\"><o:p><\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" style=\"MARGIN: 0cm 0cm 0pt; TEXT-ALIGN: justify\"><span style=\"FONT-SIZE: 10pt; FONT-FAMILY: 'Comic Sans MS'; mso-ansi-language: ES\"><o:p>&nbsp;<\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" style=\"MARGIN: 0cm 0cm 0pt; TEXT-ALIGN: justify\"><span lang=\"ES\" style=\"mso-ansi-language: ES-TRAD\"><o:p>&nbsp;<\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" style=\"MARGIN: 0cm 0cm 0pt; TEXT-ALIGN: justify\"><b style=\"mso-bidi-font-weight: normal\"><span style=\"FONT-SIZE: 14pt; COLOR: #cc0000; FONT-FAMILY: 'Comic Sans MS'; mso-ansi-language: ES\">Juan Jos\u00e9 Ib\u00e1\u00f1ez<o:p><\/o:p><\/span><\/b><\/p>\n<h3>Im\u00e1genes Relacionadas:<\/h3>","protected":false},"excerpt":{"rendered":"<p>En los \u00faltimos a\u00f1os se ha recopilado abundante informaci\u00f3n sobre los paleoclimas y vegetaci\u00f3n del pasado en la Cuenca Mediterr\u00e1nea. De los datos obtenidos en diversos estudios se desprende que, tras la \u00faltima glaciaci\u00f3n y especialmente despu\u00e9s de la emergencia de las culturas neol\u00edticas, hace unos 8.500 a\u00f1os en el \u00abcreciente f\u00e9rtil y\/o alrededores del Mar Negro, muchos bosques de Quecus caducifolios fueron sustituidos por otros escler\u00f3filos e incluso por maquis y garrigas. No existe consenso entre los especialistas sobre si fue el cambio clim\u00e1tico o la acci\u00f3n antr\u00f3picas la responsable de esta aridificaci\u00f3n del paisaje, present\u00e1ndose evidencias a favor\u2026<\/p>\n","protected":false},"author":26,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0},"categories":[603,600,585,598,595],"tags":[],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":4}},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"En los \u00faltimos a\u00f1os se ha recopilado abundante informaci\u00f3n sobre los paleoclimas y vegetaci\u00f3n del pasado en la Cuenca Mediterr\u00e1nea. De los datos obtenidos en diversos estudios se desprende que, tras la \u00faltima glaciaci\u00f3n y especialmente despu\u00e9s de la emergencia de las culturas neol\u00edticas, hace unos 8.500 a\u00f1os en el &quot;creciente f\u00e9rtil y\/o alrededores del\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Juan Jos\u00e9 Ib\u00e1\u00f1ez\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2006\/03\/26\/16841\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Un Universo invisible bajo nuestros pies - Los suelos y la vida\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"La Erosi\u00f3n Hist\u00f3rica y los Paisajes Vegetales Mediterr\u00e1neos - Un Universo invisible bajo nuestros pies\" \/>\n\t\t<meta property=\"og:description\" content=\"En los \u00faltimos a\u00f1os se ha recopilado abundante informaci\u00f3n sobre los paleoclimas y vegetaci\u00f3n del pasado en la Cuenca Mediterr\u00e1nea. De los datos obtenidos en diversos estudios se desprende que, tras la \u00faltima glaciaci\u00f3n y especialmente despu\u00e9s de la emergencia de las culturas neol\u00edticas, hace unos 8.500 a\u00f1os en el &quot;creciente f\u00e9rtil y\/o alrededores del\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2006\/03\/26\/16841\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2006-03-26T18:09:00+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2010-01-22T02:39:51+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/juan.j.marti.14\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"La Erosi\u00f3n Hist\u00f3rica y los Paisajes Vegetales Mediterr\u00e1neos - Un Universo invisible bajo nuestros pies\" \/>\n\t\t<meta name=\"twitter:description\" content=\"En los \u00faltimos a\u00f1os se ha recopilado abundante informaci\u00f3n sobre los paleoclimas y vegetaci\u00f3n del pasado en la Cuenca Mediterr\u00e1nea. De los datos obtenidos en diversos estudios se desprende que, tras la \u00faltima glaciaci\u00f3n y especialmente despu\u00e9s de la emergencia de las culturas neol\u00edticas, hace unos 8.500 a\u00f1os en el &quot;creciente f\u00e9rtil y\/o alrededores del\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2006\\\/03\\\/26\\\/16841#blogposting\",\"name\":\"La Erosi\\u00f3n Hist\\u00f3rica y los Paisajes Vegetales Mediterr\\u00e1neos - Un Universo invisible bajo nuestros pies\",\"headline\":\"La Erosi\\u00f3n Hist\\u00f3rica y los Paisajes Vegetales Mediterr\\u00e1neos\",\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/files\\\/2022\\\/02\\\/logo.png\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#articleImage\",\"width\":217,\"height\":72},\"datePublished\":\"2006-03-26T18:09:00+01:00\",\"dateModified\":\"2010-01-22T03:39:51+01:00\",\"inLanguage\":\"es-ES\",\"commentCount\":6,\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2006\\\/03\\\/26\\\/16841#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2006\\\/03\\\/26\\\/16841#webpage\"},\"articleSection\":\"Carpeta sobre Paisajes de Suelos y los Suelos en el Paisaje, Los Suelos las Plantas y la Vegetaci\\u00f3n, P\\u00e9rdida de los Recursos Ed\\u00e1ficos: La Erosi\\u00f3n, Suelos de Zonas \\u00c1ridas, Semi\\u00e1ridas y desertificaci\\u00f3n, Suelos y Cambio Clim\\u00e1tico\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2006\\\/03\\\/26\\\/16841#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/perdida-de-los-recursos-edaficos-la-erosion#listItem\",\"name\":\"P\\u00e9rdida de los Recursos Ed\\u00e1ficos: La Erosi\\u00f3n\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/perdida-de-los-recursos-edaficos-la-erosion#listItem\",\"position\":2,\"name\":\"P\\u00e9rdida de los Recursos Ed\\u00e1ficos: La Erosi\\u00f3n\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/perdida-de-los-recursos-edaficos-la-erosion\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2006\\\/03\\\/26\\\/16841#listItem\",\"name\":\"La Erosi\\u00f3n Hist\\u00f3rica y los Paisajes Vegetales Mediterr\\u00e1neos\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2006\\\/03\\\/26\\\/16841#listItem\",\"position\":3,\"name\":\"La Erosi\\u00f3n Hist\\u00f3rica y los Paisajes Vegetales Mediterr\\u00e1neos\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/perdida-de-los-recursos-edaficos-la-erosion#listItem\",\"name\":\"P\\u00e9rdida de los Recursos Ed\\u00e1ficos: La Erosi\\u00f3n\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#organization\",\"name\":\"Un Universo invisible bajo nuestros pies\",\"description\":\"Los suelos y la vida\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/files\\\/2022\\\/02\\\/logo.png\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2006\\\/03\\\/26\\\/16841\\\/#organizationLogo\",\"width\":217,\"height\":72},\"image\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2006\\\/03\\\/26\\\/16841\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/juan.j.marti.14\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo\",\"name\":\"Juan Jos\\u00e9 Ib\\u00e1\\u00f1ez\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2006\\\/03\\\/26\\\/16841#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/387f3a100385573d8f42ce2a3211fd1c?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Juan Jos\\u00e9 Ib\\u00e1\\u00f1ez\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2006\\\/03\\\/26\\\/16841#webpage\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2006\\\/03\\\/26\\\/16841\",\"name\":\"La Erosi\\u00f3n Hist\\u00f3rica y los Paisajes Vegetales Mediterr\\u00e1neos - Un Universo invisible bajo nuestros pies\",\"description\":\"En los \\u00faltimos a\\u00f1os se ha recopilado abundante informaci\\u00f3n sobre los paleoclimas y vegetaci\\u00f3n del pasado en la Cuenca Mediterr\\u00e1nea. De los datos obtenidos en diversos estudios se desprende que, tras la \\u00faltima glaciaci\\u00f3n y especialmente despu\\u00e9s de la emergencia de las culturas neol\\u00edticas, hace unos 8.500 a\\u00f1os en el \\\"creciente f\\u00e9rtil y\\\/o alrededores del\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2006\\\/03\\\/26\\\/16841#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\"},\"datePublished\":\"2006-03-26T18:09:00+01:00\",\"dateModified\":\"2010-01-22T03:39:51+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#website\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/\",\"name\":\"Un Universo invisible bajo nuestros pies\",\"description\":\"Los suelos y la vida\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"La Erosi\u00f3n Hist\u00f3rica y los Paisajes Vegetales Mediterr\u00e1neos - Un Universo invisible bajo nuestros pies","description":"En los \u00faltimos a\u00f1os se ha recopilado abundante informaci\u00f3n sobre los paleoclimas y vegetaci\u00f3n del pasado en la Cuenca Mediterr\u00e1nea. De los datos obtenidos en diversos estudios se desprende que, tras la \u00faltima glaciaci\u00f3n y especialmente despu\u00e9s de la emergencia de las culturas neol\u00edticas, hace unos 8.500 a\u00f1os en el \"creciente f\u00e9rtil y\/o alrededores del","canonical_url":"https:\/\/www.madrimasd.org\/blogs\/universo\/2006\/03\/26\/16841","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2006\/03\/26\/16841#blogposting","name":"La Erosi\u00f3n Hist\u00f3rica y los Paisajes Vegetales Mediterr\u00e1neos - Un Universo invisible bajo nuestros pies","headline":"La Erosi\u00f3n Hist\u00f3rica y los Paisajes Vegetales Mediterr\u00e1neos","author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author"},"publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#articleImage","width":217,"height":72},"datePublished":"2006-03-26T18:09:00+01:00","dateModified":"2010-01-22T03:39:51+01:00","inLanguage":"es-ES","commentCount":6,"mainEntityOfPage":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2006\/03\/26\/16841#webpage"},"isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2006\/03\/26\/16841#webpage"},"articleSection":"Carpeta sobre Paisajes de Suelos y los Suelos en el Paisaje, Los Suelos las Plantas y la Vegetaci\u00f3n, P\u00e9rdida de los Recursos Ed\u00e1ficos: La Erosi\u00f3n, Suelos de Zonas \u00c1ridas, Semi\u00e1ridas y desertificaci\u00f3n, Suelos y Cambio Clim\u00e1tico"},{"@type":"BreadcrumbList","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2006\/03\/26\/16841#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo#listItem","position":1,"name":"Home","item":"https:\/\/www.madrimasd.org\/blogs\/universo","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/perdida-de-los-recursos-edaficos-la-erosion#listItem","name":"P\u00e9rdida de los Recursos Ed\u00e1ficos: La Erosi\u00f3n"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/perdida-de-los-recursos-edaficos-la-erosion#listItem","position":2,"name":"P\u00e9rdida de los Recursos Ed\u00e1ficos: La Erosi\u00f3n","item":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/perdida-de-los-recursos-edaficos-la-erosion","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2006\/03\/26\/16841#listItem","name":"La Erosi\u00f3n Hist\u00f3rica y los Paisajes Vegetales Mediterr\u00e1neos"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2006\/03\/26\/16841#listItem","position":3,"name":"La Erosi\u00f3n Hist\u00f3rica y los Paisajes Vegetales Mediterr\u00e1neos","previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/perdida-de-los-recursos-edaficos-la-erosion#listItem","name":"P\u00e9rdida de los Recursos Ed\u00e1ficos: La Erosi\u00f3n"}}]},{"@type":"Organization","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#organization","name":"Un Universo invisible bajo nuestros pies","description":"Los suelos y la vida","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/","logo":{"@type":"ImageObject","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2006\/03\/26\/16841\/#organizationLogo","width":217,"height":72},"image":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2006\/03\/26\/16841\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/juan.j.marti.14"]},{"@type":"Person","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo","name":"Juan Jos\u00e9 Ib\u00e1\u00f1ez","image":{"@type":"ImageObject","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2006\/03\/26\/16841#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/387f3a100385573d8f42ce2a3211fd1c?s=96&d=mm&r=g","width":96,"height":96,"caption":"Juan Jos\u00e9 Ib\u00e1\u00f1ez"}},{"@type":"WebPage","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2006\/03\/26\/16841#webpage","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/2006\/03\/26\/16841","name":"La Erosi\u00f3n Hist\u00f3rica y los Paisajes Vegetales Mediterr\u00e1neos - Un Universo invisible bajo nuestros pies","description":"En los \u00faltimos a\u00f1os se ha recopilado abundante informaci\u00f3n sobre los paleoclimas y vegetaci\u00f3n del pasado en la Cuenca Mediterr\u00e1nea. De los datos obtenidos en diversos estudios se desprende que, tras la \u00faltima glaciaci\u00f3n y especialmente despu\u00e9s de la emergencia de las culturas neol\u00edticas, hace unos 8.500 a\u00f1os en el \"creciente f\u00e9rtil y\/o alrededores del","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#website"},"breadcrumb":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2006\/03\/26\/16841#breadcrumblist"},"author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author"},"creator":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author"},"datePublished":"2006-03-26T18:09:00+01:00","dateModified":"2010-01-22T03:39:51+01:00"},{"@type":"WebSite","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#website","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/","name":"Un Universo invisible bajo nuestros pies","description":"Los suelos y la vida","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Un Universo invisible bajo nuestros pies - Los suelos y la vida","og:type":"article","og:title":"La Erosi\u00f3n Hist\u00f3rica y los Paisajes Vegetales Mediterr\u00e1neos - Un Universo invisible bajo nuestros pies","og:description":"En los \u00faltimos a\u00f1os se ha recopilado abundante informaci\u00f3n sobre los paleoclimas y vegetaci\u00f3n del pasado en la Cuenca Mediterr\u00e1nea. De los datos obtenidos en diversos estudios se desprende que, tras la \u00faltima glaciaci\u00f3n y especialmente despu\u00e9s de la emergencia de las culturas neol\u00edticas, hace unos 8.500 a\u00f1os en el &quot;creciente f\u00e9rtil y\/o alrededores del","og:url":"https:\/\/www.madrimasd.org\/blogs\/universo\/2006\/03\/26\/16841","og:image":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png","og:image:secure_url":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png","article:published_time":"2006-03-26T18:09:00+00:00","article:modified_time":"2010-01-22T02:39:51+00:00","article:publisher":"https:\/\/www.facebook.com\/juan.j.marti.14","twitter:card":"summary","twitter:title":"La Erosi\u00f3n Hist\u00f3rica y los Paisajes Vegetales Mediterr\u00e1neos - Un Universo invisible bajo nuestros pies","twitter:description":"En los \u00faltimos a\u00f1os se ha recopilado abundante informaci\u00f3n sobre los paleoclimas y vegetaci\u00f3n del pasado en la Cuenca Mediterr\u00e1nea. De los datos obtenidos en diversos estudios se desprende que, tras la \u00faltima glaciaci\u00f3n y especialmente despu\u00e9s de la emergencia de las culturas neol\u00edticas, hace unos 8.500 a\u00f1os en el &quot;creciente f\u00e9rtil y\/o alrededores del","twitter:image":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png"},"aioseo_meta_data":{"post_id":"16841","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":null,"isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","tabs":null,"priority":null,"frequency":null,"local_seo":null,"created":"2022-06-03 13:43:18","updated":"2026-05-26 13:11:52","limit_modified_date":false,"ai":null,"breadcrumb_settings":null,"seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/perdida-de-los-recursos-edaficos-la-erosion\" title=\"P\u00e9rdida de los Recursos Ed\u00e1ficos: La Erosi\u00f3n\">P\u00e9rdida de los Recursos Ed\u00e1ficos: La Erosi\u00f3n<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tLa Erosi\u00f3n Hist\u00f3rica y los Paisajes Vegetales Mediterr\u00e1neos\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.madrimasd.org\/blogs\/universo"},{"label":"P\u00e9rdida de los Recursos Ed\u00e1ficos: La Erosi\u00f3n","link":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/perdida-de-los-recursos-edaficos-la-erosion"},{"label":"La Erosi\u00f3n Hist\u00f3rica y los Paisajes Vegetales Mediterr\u00e1neos","link":"https:\/\/www.madrimasd.org\/blogs\/universo\/2006\/03\/26\/16841"}],"_links":{"self":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts\/16841"}],"collection":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/comments?post=16841"}],"version-history":[{"count":3,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts\/16841\/revisions"}],"predecessor-version":[{"id":133985,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts\/16841\/revisions\/133985"}],"wp:attachment":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/media?parent=16841"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/categories?post=16841"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/tags?post=16841"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}