{"id":20144,"date":"2006-04-25T20:15:00","date_gmt":"2006-04-25T20:15:00","guid":{"rendered":"http:\/\/weblogs.madrimasd.org\/\/universo\/archive\/2006\/04\/25\/20144.aspx"},"modified":"2010-01-22T03:40:02","modified_gmt":"2010-01-22T02:40:02","slug":"chernobyl-contaminacion-radioactiva-medio-ambiente-y-salud-publica-por-consuelo-ibanez","status":"publish","type":"post","link":"https:\/\/www.madrimasd.org\/blogs\/universo\/2006\/04\/25\/20144","title":{"rendered":"Chern\u00f3byl, Contaminaci\u00f3n Radioactiva, Medio Ambiente y Salud P\u00fablica (por Consuelo Ib\u00e1\u00f1ez)"},"content":{"rendered":"<p align=\"justify\"><span style=\"FONT-SIZE: 10pt; FONT-FAMILY: 'Comic Sans MS'; mso-ansi-language: ES; mso-bidi-font-family: 'Times New Roman'; mso-fareast-font-family: 'Times New Roman'; mso-fareast-language: ES; mso-bidi-language: AR-SA\">Ayer el plasta de mi hermano, al que sufr\u00eds como Administrador de Esta Weblog (all\u00e1 cada uno con sus gustos;<span style=\"mso-spacerun: yes\">&nbsp; <\/span>yo no tengo m\u00e1s remedio, pero vosotros no ten\u00e9is perd\u00f3n) me pidi\u00f3 reiteradamente una peque\u00f1a colaboraci\u00f3n, desde el punto de vista de<span style=\"COLOR: #cc0000\"> salud p\u00fablica<\/span>, sobre el accidente de <span style=\"COLOR: #cc0000\">Chern\u00f3bil<\/span> y sus efectos. Sinceramente, por falta de tiempo para documentarme ampliamente, pens\u00e9 en no participar, pero la curiosidad de ponerme al d\u00eda pudo con mis \u201cmalas intenciones\u201d (en lo que al Susodicho Ib\u00e1\u00f1ez se refiere) y empec\u00e9 a revisar unos cuantos documentos. Finalmente termin\u00e9 por agarrarme un disgusto may\u00fasculo.<\/span><\/p>\n<p><!--more--><\/p>\n<p class=\"MsoNormal\" style=\"MARGIN: 0cm 0cm 0pt; TEXT-ALIGN: justify\"><span style=\"FONT-SIZE: 10pt; COLOR: #cc0000; FONT-FAMILY: 'Comic Sans MS'\">El primer informe que consult\u00e9<\/span><span style=\"FONT-SIZE: 10pt; FONT-FAMILY: 'Comic Sans MS'\"> fue el de la <span style=\"mso-spacerun: yes\">&nbsp;<\/span><span style=\"COLOR: #cc0000\"><a href=\"http:\/\/www.who.int\/ionizing_radiation\/chernobyl\/en\/index.html\"><span style=\"COLOR: #cc0000\">OMS<\/span><\/a><\/span> : \u201c<span style=\"COLOR: #cc0000\">Chern\u00f3bil: la verdadera escala del accidente.<\/span>\u201d Veinte a\u00f1os despu\u00e9s, un informe de las Naciones Unidas dice dar respuestas definitivas, a la par que formula sugerencias para reparar las vidas da\u00f1adas.<o:p><\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" style=\"MARGIN: 0cm 0cm 0pt; TEXT-ALIGN: justify\"><span style=\"FONT-SIZE: 10pt; FONT-FAMILY: 'Comic Sans MS'\"><o:p>&nbsp;<\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" style=\"MARGIN: 0cm 0cm 0pt; TEXT-ALIGN: justify\"><span style=\"FONT-SIZE: 10pt; FONT-FAMILY: 'Comic Sans MS'\">Reitero que <span style=\"COLOR: blue\">me ha podido m\u00e1s la indignaci\u00f3n<\/span> ante las opiniones, informes, etc., vertidas por esos \u201csabios\u201d que la falta de tiempo.<span style=\"mso-spacerun: yes\">&nbsp; <\/span>Yo me pregunto, \u00bfSe pueden escribir p\u00e1rrafos como este?:<o:p><\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" style=\"MARGIN: 0cm 0cm 0pt; TEXT-ALIGN: justify\"><span style=\"FONT-SIZE: 10pt; COLOR: #ff6600; FONT-FAMILY: 'Comic Sans MS'\"><o:p>&nbsp;<\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" style=\"MARGIN: 0cm 0cm 0pt; TEXT-ALIGN: justify\"><span style=\"FONT-SIZE: 9pt; COLOR: #ff6600; FONT-FAMILY: 'Comic Sans MS'\">\u201c<\/span><i style=\"mso-bidi-font-style: normal\"><span style=\"FONT-SIZE: 9pt; FONT-FAMILY: 'Comic Sans MS'\">Fue un accidente muy grave, con importantes consecuencias para la salud, especialmente para los miles de trabajadores que estuvieron expuestos en los primeros d\u00edas a dosis muy altas de radiaci\u00f3n, y los otros miles de personas que contrajeron un c\u00e1ncer de tiroides. En general, sin embargo<\/span><\/i><span style=\"FONT-SIZE: 9pt; COLOR: lime; FONT-FAMILY: 'Comic Sans MS'\">, <\/span><i style=\"mso-bidi-font-style: normal\"><span style=\"FONT-SIZE: 9pt; COLOR: #cc0000; FONT-FAMILY: 'Comic Sans MS'\">no hemos encontrado efectos negativos profundos en la salud del resto de la poblaci\u00f3n de las zonas circundantes, ni tampoco una contaminaci\u00f3n generalizada que siga suponiendo una amenaza sustancial para la vida humana, salvo en algunas zonas excepcionales y restringidas<\/span><\/i><span style=\"FONT-SIZE: 9pt; FONT-FAMILY: 'Comic Sans MS'\">\u201d, a\u00f1ade el<i style=\"mso-bidi-font-style: normal\"><span style=\"COLOR: blue\"> Dr. Bennett<\/span><\/i><span style=\"COLOR: lime\">.<o:p><\/o:p><\/span><\/span><\/p>\n<p class=\"MsoNormal\" style=\"MARGIN: 0cm 0cm 0pt\"><span style=\"FONT-SIZE: 10pt; FONT-FAMILY: 'Comic Sans MS'\"><o:p>&nbsp;<\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" style=\"MARGIN: 0cm 0cm 0pt\"><span style=\"FONT-SIZE: 10pt; FONT-FAMILY: 'Comic Sans MS'\">Y contin\u00faan con todo el morro se\u00f1alando que:<o:p><\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" style=\"MARGIN: 0cm 0cm 0pt\"><span style=\"FONT-SIZE: 10pt; FONT-FAMILY: 'Comic Sans MS'\"><o:p>&nbsp;<\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" style=\"MARGIN: 0cm 0cm 0pt; TEXT-ALIGN: justify\"><i style=\"mso-bidi-font-style: normal\"><span style=\"FONT-SIZE: 9pt; FONT-FAMILY: 'Comic Sans MS'\">\u201c<span style=\"COLOR: #cc0000\">En cuanto a los efectos en el medio ambiente, el informe tambi\u00e9n es tranquilizador: las evaluaciones cient\u00edficas indican que, salvo en la zona incluida en un radio de 30 km del reactor, que est\u00e1 muy contaminada, y en algunos lagos cerrados y bosques de acceso restringido, los niveles de radiaci\u00f3n han vuelto a situarse, en su mayor parte, en valores aceptables. \u201cEn la mayor\u00eda de las zonas los problemas son de \u00edndole econ\u00f3mica y psicol\u00f3gica, no sanitaria o ambiental<\/span>\u201d<o:p><\/o:p><\/span><\/i><\/p>\n<p class=\"MsoNormal\" style=\"MARGIN: 0cm 0cm 0pt\"><span style=\"FONT-SIZE: 10pt; COLOR: #ff6600; FONT-FAMILY: 'Comic Sans MS'\"><o:p>&nbsp;<\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" style=\"MARGIN: 0cm 0cm 0pt; TEXT-ALIGN: justify\"><span style=\"FONT-SIZE: 10pt; FONT-FAMILY: 'Comic Sans MS'\"><span style=\"mso-spacerun: yes\">&nbsp;<\/span>No quiero extenderme mucho con los \u201c<span style=\"COLOR: blue\">expertos de la OMS<\/span>, pero <span style=\"COLOR: blue\">decir que el mayor problema que existe ahora en Chernobil y las restantes zonas afectadas, es la salud mental de sus habitantes que<\/span>, \u201c<i style=\"mso-bidi-font-style: normal\">al ser tratados como v\u00edctimas en lugar de c\u00f3mo supervivientes\u201d han desarrollado una \u201c<span style=\"COLOR: blue\">neurosis de renta<\/span><\/i>\u201d y no solo no trabajan, sino que a parecer seg\u00fan los expertos de la OMS, quieren tambi\u00e9n que el estado les pague incluso las vacaciones\u2026\u2026 (mejor me callo).<o:p><\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" style=\"MARGIN: 0cm 0cm 0pt\"><span style=\"FONT-SIZE: 10pt; FONT-FAMILY: 'Comic Sans MS'\"><o:p>&nbsp;<\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" style=\"MARGIN: 0cm 0cm 0pt; TEXT-ALIGN: justify\"><span style=\"FONT-SIZE: 10pt; FONT-FAMILY: 'Comic Sans MS'\">Ya, \u00bf<span style=\"COLOR: #cc0000\">y que pasa con los c\u00e1nceres de tiroides, con las leucemias con las malformaciones gen\u00e9ticas hereditarias, <u>la contaminaci\u00f3n del<\/u> agua, del<u> suelo,<\/u> de las cosechas, de los animales que se alimentan de esas cosechas, de la flora y fauna salvaje, del aire, etc<\/span>.?\u201d<o:p><\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" style=\"MARGIN: 0cm 0cm 0pt; TEXT-ALIGN: justify\"><span style=\"FONT-SIZE: 10pt; FONT-FAMILY: 'Comic Sans MS'\"><o:p>&nbsp;<\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" style=\"MARGIN: 0cm 0cm 0pt; TEXT-ALIGN: justify\"><span style=\"FONT-SIZE: 7pt; COLOR: green; FONT-FAMILY: 'Comic Sans MS'\">PD. El subrayado es del fan\u00e1tico de mi hermano, como pod\u00e9is suponer.<o:p><\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" style=\"MARGIN: 0cm 0cm 0pt; TEXT-ALIGN: justify\"><span style=\"FONT-SIZE: 10pt; FONT-FAMILY: 'Comic Sans MS'\"><o:p>&nbsp;<\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" style=\"MARGIN: 0cm 0cm 0pt; TEXT-ALIGN: justify\"><span style=\"FONT-SIZE: 10pt; FONT-FAMILY: 'Comic Sans MS'\">Me dirijo ahora a otro documento de <span style=\"COLOR: #cc0000; mso-bidi-font-style: italic\">Jos\u00e9 Santamar\u00eda<\/span><span style=\"mso-bidi-font-style: italic\"> <a href=\"http:\/\/www.inisoc.org\/chernobil.htm\">el cierre de Chernobil no acaba con la pesadilla nuclear<\/a><o:p><\/o:p><\/span><\/span><\/p>\n<p class=\"MsoNormal\" style=\"MARGIN: 0cm 0cm 0pt; TEXT-ALIGN: justify\"><span style=\"FONT-SIZE: 10pt; FONT-FAMILY: 'Comic Sans MS'\"><o:p>&nbsp;<\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" style=\"MARGIN: 0cm 0cm 0pt; TEXT-ALIGN: justify\"><span style=\"FONT-SIZE: 10pt; FONT-FAMILY: 'Comic Sans MS'\">Bajo mi punto de vista y la experiencia de haber intentado mantenerme informada a lo largo de estos 20 a\u00f1os, me parece m\u00e1s cercano a la realidad y con su benevolencia (espero, ya que me basado b\u00e1sicamente en su estudio) <span style=\"COLOR: blue\">intentar\u00e9 resumir algunas de las conclusiones de Santamar\u00eda<\/span>, aunque lo que realmente os recomiendo es que le\u00e1is este art\u00edculo esclarecedor.<o:p><\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" style=\"MARGIN: 0cm 0cm 0pt; TEXT-ALIGN: justify\"><span style=\"FONT-SIZE: 10pt; FONT-FAMILY: 'Comic Sans MS'\"><o:p>&nbsp;<\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" style=\"MARGIN: 0cm 0cm 0pt; TEXT-ALIGN: justify\"><span style=\"FONT-SIZE: 10pt; FONT-FAMILY: 'Comic Sans MS'\">Veamos sus <span style=\"COLOR: #cc0000\">consecuencias sobre las personas<\/span>: absorci\u00f3n por el organismo de miles de personas de grandes cantidades de <span style=\"COLOR: blue\">yodo-131 y cesio-137<\/span>. <o:p><\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" style=\"MARGIN: 0cm 0cm 0pt; TEXT-ALIGN: justify\"><span style=\"FONT-SIZE: 10pt; FONT-FAMILY: 'Comic Sans MS'\"><o:p>&nbsp;<\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" style=\"MARGIN: 0cm 0cm 0pt; TEXT-ALIGN: justify\"><span style=\"FONT-SIZE: 10pt; FONT-FAMILY: 'Comic Sans MS'\">El <span style=\"COLOR: blue\">yodo-131<\/span>, aunque tiene una vida corta, se acumula en la gl\u00e1ndula tiroides, causando hipertiroidismo y c\u00e1ncer de tiroides, sobre todo en los ni\u00f1os. <o:p><\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" style=\"MARGIN: 0cm 0cm 0pt; TEXT-ALIGN: justify\"><span style=\"FONT-SIZE: 10pt; FONT-FAMILY: 'Comic Sans MS'\"><o:p>&nbsp;<\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" style=\"MARGIN: 0cm 0cm 0pt; TEXT-ALIGN: justify\"><span style=\"FONT-SIZE: 10pt; FONT-FAMILY: 'Comic Sans MS'\">El <span style=\"COLOR: blue\">cesio-137<\/span> tiene una vida media de 30 a\u00f1os, por lo que sus efectos a\u00fan se har\u00e1n notar durante muchos a\u00f1os m\u00e1s. El ADN de las c\u00e9lulas germinales que transmiten la informaci\u00f3n gen\u00e9tica fue da\u00f1ado por la radiactividad y <span style=\"mso-spacerun: yes\">&nbsp;<\/span>otro de los problemas de salud que se mantienen es el debilitamiento del sistema inmunol\u00f3gico causado por las radiaciones que hace a las personas afectadas susceptibles a m\u00faltiples enfermedades, no solo a las infecciosas.<o:p><\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" style=\"MARGIN: 0cm 0cm 0pt; TEXT-ALIGN: justify\"><span style=\"FONT-SIZE: 10pt; FONT-FAMILY: 'Comic Sans MS'\"><span style=\"mso-tab-count: 1\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; <\/span><o:p><\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" style=\"MARGIN: 0cm 0cm 0pt; TEXT-ALIGN: justify\"><span style=\"FONT-SIZE: 10pt; FONT-FAMILY: 'Comic Sans MS'\">Adem\u00e1s hay que contar con las repercusiones de: <span style=\"COLOR: blue\">cesio-134<\/span>,<span style=\"COLOR: blue\"> estroncio-90<\/span> y <span style=\"COLOR: blue\">plutonio-139<\/span>, sobre los que no abundaremos, ya que como veis el tema es interminable.<o:p><\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" style=\"MARGIN: 0cm 0cm 0pt\"><span style=\"FONT-SIZE: 10pt; FONT-FAMILY: 'Comic Sans MS'\"><o:p>&nbsp;<\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" style=\"MARGIN: 0cm 0cm 0pt\"><span style=\"FONT-SIZE: 10pt; FONT-FAMILY: 'Comic Sans MS'\"><o:p>&nbsp;<\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" style=\"MARGIN: 0cm 0cm 0pt; TEXT-ALIGN: justify\"><span style=\"FONT-SIZE: 10pt; FONT-FAMILY: 'Comic Sans MS'\">Por citar solo un ejemplo. En la <span style=\"COLOR: blue\">regi\u00f3n de Gomel<\/span>, en Bielorrusia, l<span style=\"COLOR: blue\">os c\u00e1nceres de tiroides<\/span> entre la <span style=\"COLOR: blue\">poblaci\u00f3n infantil<\/span> se han <span style=\"COLOR: blue\">multiplicado por cien<\/span>, y el n\u00famero de casos no para de aumentar. <span style=\"COLOR: blue\">Las leucemias,<\/span> cuyo periodo de latencia es m\u00e1s largo, empiezan a aparecer, sobre todo entre \u201c<i style=\"mso-bidi-font-style: normal\">los liquidadores<\/i>\u201d (trabajadores \u201cvoluntarios\u201d militares que acudieron inmediatamente a sofocar el incendio y desmantelar el reactor); l<span style=\"COLOR: blue\">a tuberculosis<\/span> es una de las enfermedades que m\u00e1s ha crecido entre las personas afectadas. Las <span style=\"COLOR: blue\">aberraciones cromos\u00f3micas<\/span>, precursoras de <span style=\"COLOR: blue\">leucemias y c\u00e1nceres<\/span>, han sido igualmente detectadas, al igual que <span style=\"COLOR: blue\">c\u00e1nceres de h\u00edgado y recto<\/span>; y <span style=\"COLOR: blue\">enfermedades del sistema endocrino, nervioso, digestivo y cardiovascular<\/span>, as\u00ed como <span style=\"COLOR: blue\">las cataratas<\/span>.<o:p><\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" style=\"MARGIN: 0cm 0cm 0pt\"><span style=\"FONT-SIZE: 10pt; FONT-FAMILY: 'Comic Sans MS'\"><o:p>&nbsp;<\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" style=\"MARGIN: 0cm 0cm 0pt; TEXT-ALIGN: justify\"><span style=\"FONT-SIZE: 10pt; FONT-FAMILY: 'Comic Sans MS'\">Pasemos a sus efectos sobre el agua: El <span style=\"COLOR: blue\">r\u00edo Pripiat <\/span>llev\u00f3 la radiactividad a su efluente, el <span style=\"COLOR: blue\">r\u00edo Dnieper<\/span> (<span style=\"COLOR: blue\">el tercer r\u00edo europeo por su caudal<\/span>) y que tras recorrer 800 kil\u00f3metros y seis grandes embalses, desemboca en el <span style=\"COLOR: blue\">Mar Negro<\/span>. El <span style=\"COLOR: #cc0000\">agua contaminada<\/span> por los residuos radiactivos <span style=\"COLOR: #cc0000\">puede llegar a haber afectado a unos 30 millones de personas<\/span>, seg\u00fan un reciente <span style=\"COLOR: blue\">informe elaborado por 59 cient\u00edficos de 8 pa\u00edses<\/span>, bajo la direcci\u00f3n del italiano Umberto Sansone: <span style=\"COLOR: blue\">m\u00e1s de 9 millones beben agua contaminada<\/span>, y <span style=\"COLOR: blue\">otros 23 millones<\/span> de personas comen <span style=\"COLOR: #cc0000\">alimentos regados con aguas radiactivas<\/span><span style=\"COLOR: blue\"> <\/span>o <span style=\"COLOR: blue\">peces<\/span> con niveles inaceptables de radiactividad. <span style=\"COLOR: blue\">Las balsas y peque\u00f1os embalses construidos para retener las aguas contaminadas a la larga agravaron el problema, pues<\/span> fueron rebasadas al caer las primeras lluvias intensas. <o:p><\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" style=\"MARGIN: 0cm 0cm 0pt; TEXT-ALIGN: justify\"><span style=\"FONT-SIZE: 10pt; FONT-FAMILY: 'Comic Sans MS'\"><o:p>&nbsp;<\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" style=\"MARGIN: 0cm 0cm 0pt; TEXT-ALIGN: justify\"><span style=\"FONT-SIZE: 10pt; FONT-FAMILY: 'Comic Sans MS'\">Los peces del l<span style=\"COLOR: blue\">ago Kojanovskoe, en Rusia<\/span>, presente<span style=\"COLOR: blue\"> niveles de radiactividad 60 veces superiores a los l\u00edmites de seguridad<\/span> de la Uni\u00f3n Europea. La \u00fanica alternativa es la completa prohibici\u00f3n del consumo de pescado en la regi\u00f3n. <o:p><\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" style=\"MARGIN: 0cm 0cm 0pt; TEXT-ALIGN: justify\"><span style=\"FONT-SIZE: 10pt; FONT-FAMILY: 'Comic Sans MS'\"><o:p>&nbsp;<\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" style=\"MARGIN: 0cm 0cm 0pt; TEXT-ALIGN: justify\"><span style=\"FONT-SIZE: 10pt; COLOR: #cc0000; FONT-FAMILY: 'Comic Sans MS'\">Los sedimentos fluviales y lacustres, as\u00ed como los suelos<\/span><span style=\"FONT-SIZE: 10pt; COLOR: blue; FONT-FAMILY: 'Comic Sans MS'\"> ba\u00f1ados por el agua contaminada son posiblemente la mayor amenaza<\/span><span style=\"FONT-SIZE: 10pt; FONT-FAMILY: 'Comic Sans MS'\"> diez a\u00f1os despu\u00e9s del accidente. <span style=\"COLOR: blue\">El accidente deposit\u00f3<\/span> 380 terabequerelios (380 x 1012 bequerelios) de <span style=\"COLOR: blue\">estroncio y plutonio<\/span> en la zona alrededor del reactor.<o:p><\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" style=\"MARGIN: 0cm 0cm 0pt\"><span style=\"FONT-SIZE: 10pt; FONT-FAMILY: 'Comic Sans MS'\"><o:p>&nbsp;<\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" style=\"MARGIN: 0cm 0cm 0pt; TEXT-ALIGN: justify\"><span style=\"FONT-SIZE: 10pt; FONT-FAMILY: 'Comic Sans MS'\">Sigamos con <span style=\"COLOR: #cc0000\">la contaminaci\u00f3n atmosf\u00e9rica. La nube t\u00f3xica<\/span> fue diseminada por el aire. Durante los primeros diez d\u00edas hubo grandes emisiones de radio nucleidos que <span style=\"COLOR: #cc0000\">contaminaron m\u00e1s de 200 000 kil\u00f3metros cuadrados ciudades suelos y lagos de Europa y occidente de Asia<\/span>. El grado de sedimentaci\u00f3n vari\u00f3 seg\u00fan que estuviera o no lloviendo cuando pasaron las masas de aire contaminado. Afectando a los <span style=\"COLOR: #cc0000\">pa\u00edses del norte de Europa<u> contaminando los suelos<\/u><\/span>, <span style=\"COLOR: #cc0000\">que a su vez contaminaron los pastos que consum\u00edan los animales y a trav\u00e9s de su consumo pas\u00f3 a los humanos<\/span>, como es natural.<o:p><\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" style=\"MARGIN: 0cm 0cm 0pt; TEXT-ALIGN: justify\"><span style=\"FONT-SIZE: 10pt; FONT-FAMILY: 'Comic Sans MS'\"><o:p>&nbsp;<\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" style=\"MARGIN: 0cm 0cm 0pt; TEXT-ALIGN: justify\"><span style=\"FONT-SIZE: 10pt; FONT-FAMILY: 'Comic Sans MS'\">Tras el accidente, <span style=\"COLOR: #cc0000\">l<u>os suelos,<\/u><\/span> <span style=\"COLOR: blue\">animales<\/span> y la<span style=\"COLOR: blue\"> vegetaci\u00f3n<\/span> de las zonas forestales y monta\u00f1osas absorbieron grandes cantidades de<span style=\"COLOR: blue\"> cesio radiactivo<\/span>, y <span style=\"COLOR: #cc0000\">los niveles siguen siendo altos en<\/span> las setas, las bayas y la caza. La<span style=\"mso-spacerun: yes\">&nbsp; <\/span>exposici\u00f3n generada por los productos forestales ha aumentado, y seg\u00fan la OMS, <span style=\"COLOR: #cc0000\">s\u00f3lo disminuir\u00e1 a medida que los materiales radiactivos migren <u>hacia zonas m\u00e1s profundas del suelo<\/u> y se desintegren lentamente<\/span>. Se ha observado una elevada transferencia de cesio radiactivo de los l\u00edquenes a la <span style=\"COLOR: blue\">carne de reno<\/span>, y de esa carne al ser humano, en el <span style=\"COLOR: blue\">\u00c1rtico <\/span>y en las <span style=\"COLOR: blue\">zonas sub\u00e1rticas<\/span>, con altos niveles de contaminaci\u00f3n de la carne de reno en <span style=\"COLOR: blue\">Finlandia, Noruega, Rusia y Suecia<\/span>.<o:p><\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" style=\"MARGIN: 0cm 0cm 0pt; TEXT-ALIGN: justify\"><span style=\"FONT-SIZE: 10pt; FONT-FAMILY: 'Comic Sans MS'\"><o:p>&nbsp;<\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" style=\"MARGIN: 0cm 0cm 0pt; TEXT-ALIGN: justify\"><span style=\"FONT-SIZE: 10pt; FONT-FAMILY: 'Comic Sans MS'\">Incluso en otros muchos pa\u00edses los efectos del desastre de Chern\u00f3bil siguen latentes. Por ejemplo, en el Reino Unido, m\u00e1s de 300 reba\u00f1os de ovejas siguen todav\u00eda en cuarentena (sin poder ser consumidas, como consecuencia de la contaminaci\u00f3n radioactiva del funesto accidente. La raz\u00f3n es lo que se denomina, \u201ctransmisi\u00f3n vertical\u201d. En otras palabras, las ovejas contaminadas por la radiaci\u00f3n procedente del accidente de Chern\u00f3bil, padecieron mutaciones gen\u00e9ticas que afectaron a su aparato reproductor, por el consumo del pasto <span style=\"mso-spacerun: yes\">&nbsp;<\/span>contaminado al absorber los elementos radioactivos fijados en el suelo. Tal contaminaci\u00f3n es transferida a sus \u201cl\u00e9chales\u201d tambi\u00e9n por el consumo de la lecha materna.<span style=\"mso-spacerun: yes\">&nbsp; <\/span><o:p><\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" style=\"MARGIN: 0cm 0cm 0pt; TEXT-ALIGN: justify\"><span style=\"FONT-SIZE: 10pt; FONT-FAMILY: 'Comic Sans MS'\"><o:p>&nbsp;<\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" style=\"MARGIN: 0cm 0cm 0pt; TEXT-ALIGN: justify\"><span style=\"FONT-SIZE: 10pt; FONT-FAMILY: 'Comic Sans MS'\">Mejor no sigo.<o:p><\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" style=\"MARGIN: 0cm 0cm 0pt; TEXT-ALIGN: justify\"><span style=\"FONT-SIZE: 10pt; FONT-FAMILY: 'Comic Sans MS'\"><o:p>&nbsp;<\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" style=\"MARGIN: 0cm 0cm 0pt; TEXT-ALIGN: justify\"><b style=\"mso-bidi-font-weight: normal\"><span style=\"FONT-SIZE: 14pt; COLOR: #cc0000; FONT-FAMILY: 'Comic Sans MS'\">Consuelo Ib\u00e1\u00f1ez<o:p><\/o:p><\/span><\/b><\/p>\n<p class=\"MsoNormal\" style=\"MARGIN: 0cm 0cm 0pt; TEXT-ALIGN: justify\"><b style=\"mso-bidi-font-weight: normal\"><span style=\"FONT-SIZE: 10pt; COLOR: blue; FONT-FAMILY: 'Comic Sans MS'\">Consejer\u00eda de Salud de la CAM<o:p><\/o:p><\/span><\/b><\/p>\n<p class=\"MsoNormal\" style=\"MARGIN: 0cm 0cm 0pt\"><span style=\"FONT-SIZE: 10pt; FONT-FAMILY: 'Comic Sans MS'\"><o:p>&nbsp;<\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" style=\"MARGIN: 0cm 0cm 0pt\"><span style=\"FONT-SIZE: 10pt; COLOR: #cc0000; FONT-FAMILY: 'Comic Sans MS'\">Nota del Administrador: <\/span><span style=\"FONT-SIZE: 10pt; FONT-FAMILY: 'Comic Sans MS'\">\u00bfCon que en las zonas profundas del suelo no contaminan y se desintegran \u201capaciblemente\u201d?. Estos \u201cvenerables ancianitos de la OMS no tienen ni idea\u201d. Abordar\u00e9 el tema en mi contribuci\u00f3n. <span style=\"COLOR: #cc0000\"><o:p><\/o:p><\/span><\/span><\/p>\n<p class=\"MsoNormal\" style=\"MARGIN: 0cm 0cm 0pt\"><span style=\"FONT-SIZE: 10pt; FONT-FAMILY: 'Comic Sans MS'\"><o:p>&nbsp;<\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" style=\"MARGIN: 0cm 0cm 0pt 45pt; TEXT-INDENT: -45pt\"><span style=\"FONT-SIZE: 10pt; COLOR: blue; FONT-FAMILY: 'Comic Sans MS'\">Consuelo<\/span><span style=\"FONT-SIZE: 10pt; FONT-FAMILY: 'Comic Sans MS'\">: Juanjo que te estoy viendo \u201cvirtualmente\u201d. Hazme favor de dejar de subrayar todo lo referente a los suelos, que este es un tema muy serio.<o:p><\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" style=\"MARGIN: 0cm 0cm 0pt 45pt; TEXT-INDENT: -45pt\"><span style=\"FONT-SIZE: 10pt; COLOR: blue; FONT-FAMILY: 'Comic Sans MS'\">Juanjo<\/span><span style=\"FONT-SIZE: 10pt; FONT-FAMILY: 'Comic Sans MS'\">:<span style=\"mso-spacerun: yes\">&nbsp;&nbsp; <\/span>Vale, vale, pero esto es una Weblog de Suelos e intento recalcar la importancia de su contaminaci\u00f3n, que todos dej\u00e1is en segundo plano. <o:p><\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" style=\"MARGIN: 0cm 0cm 0pt 45pt; TEXT-INDENT: -45pt\"><span style=\"FONT-SIZE: 10pt; COLOR: blue; FONT-FAMILY: 'Comic Sans MS'\">Carmen, Antonio y JP<\/span><span style=\"FONT-SIZE: 10pt; FONT-FAMILY: 'Comic Sans MS'\">: Est\u00e1 visto que quien cae en sus manos. Es como una maldici\u00f3n efectivamente. <o:p><\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" style=\"MARGIN: 0cm 0cm 0pt 45pt; TEXT-INDENT: -45pt\"><span style=\"FONT-SIZE: 10pt; COLOR: blue; FONT-FAMILY: 'Comic Sans MS'\">Juanjo: <\/span><span style=\"FONT-SIZE: 10pt; FONT-FAMILY: 'Comic Sans MS'\">\u00bfPor qu\u00e9 no cerr\u00e1is la boca, para una vez que no os doy la lata (\u2026)<o:p><\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" style=\"MARGIN: 0cm 0cm 0pt 45pt; TEXT-INDENT: -45pt\"><span style=\"FONT-SIZE: 10pt; COLOR: blue; FONT-FAMILY: 'Comic Sans MS'\">Carmen, Antonio y JP: <\/span><span style=\"FONT-SIZE: 10pt; FONT-FAMILY: 'Comic Sans MS'\">Vale \u201chermoso\u201d, \u00b7majete\u201d, \u201csalao\u201d (uffff casi la \u201cpifiamos)\u201d<o:p><\/o:p><\/span><\/p>\n<h3>Im\u00e1genes Relacionadas:<\/h3>","protected":false},"excerpt":{"rendered":"<p>Ayer el plasta de mi hermano, al que sufr\u00eds como Administrador de Esta Weblog (all\u00e1 cada uno con sus gustos;&nbsp; yo no tengo m\u00e1s remedio, pero vosotros no ten\u00e9is perd\u00f3n) me pidi\u00f3 reiteradamente una peque\u00f1a colaboraci\u00f3n, desde el punto de vista de salud p\u00fablica, sobre el accidente de Chern\u00f3bil y sus efectos. Sinceramente, por falta de tiempo para documentarme ampliamente, pens\u00e9 en no participar, pero la curiosidad de ponerme al d\u00eda pudo con mis \u201cmalas intenciones\u201d (en lo que al Susodicho Ib\u00e1\u00f1ez se refiere) y empec\u00e9 a revisar unos cuantos documentos. Finalmente termin\u00e9 por agarrarme un disgusto may\u00fasculo. Im\u00e1genes Relacionadas:<\/p>\n","protected":false},"author":26,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0},"categories":[594,592],"tags":[],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":4}},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Ayer el plasta de mi hermano, al que sufr\u00eds como Administrador de Esta Weblog (all\u00e1 cada uno con sus gustos; yo no tengo m\u00e1s remedio, pero vosotros no ten\u00e9is perd\u00f3n) me pidi\u00f3 reiteradamente una peque\u00f1a colaboraci\u00f3n, desde el punto de vista de salud p\u00fablica, sobre el accidente de Chern\u00f3bil y sus efectos. Sinceramente, por falta\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Juan Jos\u00e9 Ib\u00e1\u00f1ez\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2006\/04\/25\/20144\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Un Universo invisible bajo nuestros pies - Los suelos y la vida\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Chern\u00f3byl, Contaminaci\u00f3n Radioactiva, Medio Ambiente y Salud P\u00fablica (por Consuelo Ib\u00e1\u00f1ez) - Un Universo invisible bajo nuestros pies\" \/>\n\t\t<meta property=\"og:description\" content=\"Ayer el plasta de mi hermano, al que sufr\u00eds como Administrador de Esta Weblog (all\u00e1 cada uno con sus gustos; yo no tengo m\u00e1s remedio, pero vosotros no ten\u00e9is perd\u00f3n) me pidi\u00f3 reiteradamente una peque\u00f1a colaboraci\u00f3n, desde el punto de vista de salud p\u00fablica, sobre el accidente de Chern\u00f3bil y sus efectos. Sinceramente, por falta\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2006\/04\/25\/20144\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2006-04-25T20:15:00+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2010-01-22T02:40:02+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/juan.j.marti.14\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Chern\u00f3byl, Contaminaci\u00f3n Radioactiva, Medio Ambiente y Salud P\u00fablica (por Consuelo Ib\u00e1\u00f1ez) - Un Universo invisible bajo nuestros pies\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Ayer el plasta de mi hermano, al que sufr\u00eds como Administrador de Esta Weblog (all\u00e1 cada uno con sus gustos; yo no tengo m\u00e1s remedio, pero vosotros no ten\u00e9is perd\u00f3n) me pidi\u00f3 reiteradamente una peque\u00f1a colaboraci\u00f3n, desde el punto de vista de salud p\u00fablica, sobre el accidente de Chern\u00f3bil y sus efectos. Sinceramente, por falta\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2006\\\/04\\\/25\\\/20144#blogposting\",\"name\":\"Chern\\u00f3byl, Contaminaci\\u00f3n Radioactiva, Medio Ambiente y Salud P\\u00fablica (por Consuelo Ib\\u00e1\\u00f1ez) - Un Universo invisible bajo nuestros pies\",\"headline\":\"Chern\\u00f3byl, Contaminaci\\u00f3n Radioactiva, Medio Ambiente y Salud P\\u00fablica (por Consuelo Ib\\u00e1\\u00f1ez)\",\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/files\\\/2022\\\/02\\\/logo.png\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#articleImage\",\"width\":217,\"height\":72},\"datePublished\":\"2006-04-25T20:15:00+01:00\",\"dateModified\":\"2010-01-22T03:40:02+01:00\",\"inLanguage\":\"es-ES\",\"commentCount\":18,\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2006\\\/04\\\/25\\\/20144#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2006\\\/04\\\/25\\\/20144#webpage\"},\"articleSection\":\"Degradaci\\u00f3n de Suelos: Contaminaci\\u00f3n, Los Suelos y la Salud\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2006\\\/04\\\/25\\\/20144#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/los-suelos-y-la-salud#listItem\",\"name\":\"Los Suelos y la Salud\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/los-suelos-y-la-salud#listItem\",\"position\":2,\"name\":\"Los Suelos y la Salud\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/los-suelos-y-la-salud\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2006\\\/04\\\/25\\\/20144#listItem\",\"name\":\"Chern\\u00f3byl, Contaminaci\\u00f3n Radioactiva, Medio Ambiente y Salud P\\u00fablica (por Consuelo Ib\\u00e1\\u00f1ez)\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2006\\\/04\\\/25\\\/20144#listItem\",\"position\":3,\"name\":\"Chern\\u00f3byl, Contaminaci\\u00f3n Radioactiva, Medio Ambiente y Salud P\\u00fablica (por Consuelo Ib\\u00e1\\u00f1ez)\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/los-suelos-y-la-salud#listItem\",\"name\":\"Los Suelos y la Salud\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#organization\",\"name\":\"Un Universo invisible bajo nuestros pies\",\"description\":\"Los suelos y la vida\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/files\\\/2022\\\/02\\\/logo.png\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2006\\\/04\\\/25\\\/20144\\\/#organizationLogo\",\"width\":217,\"height\":72},\"image\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2006\\\/04\\\/25\\\/20144\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/juan.j.marti.14\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo\",\"name\":\"Juan Jos\\u00e9 Ib\\u00e1\\u00f1ez\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2006\\\/04\\\/25\\\/20144#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/387f3a100385573d8f42ce2a3211fd1c?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Juan Jos\\u00e9 Ib\\u00e1\\u00f1ez\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2006\\\/04\\\/25\\\/20144#webpage\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2006\\\/04\\\/25\\\/20144\",\"name\":\"Chern\\u00f3byl, Contaminaci\\u00f3n Radioactiva, Medio Ambiente y Salud P\\u00fablica (por Consuelo Ib\\u00e1\\u00f1ez) - Un Universo invisible bajo nuestros pies\",\"description\":\"Ayer el plasta de mi hermano, al que sufr\\u00eds como Administrador de Esta Weblog (all\\u00e1 cada uno con sus gustos; yo no tengo m\\u00e1s remedio, pero vosotros no ten\\u00e9is perd\\u00f3n) me pidi\\u00f3 reiteradamente una peque\\u00f1a colaboraci\\u00f3n, desde el punto de vista de salud p\\u00fablica, sobre el accidente de Chern\\u00f3bil y sus efectos. Sinceramente, por falta\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2006\\\/04\\\/25\\\/20144#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\"},\"datePublished\":\"2006-04-25T20:15:00+01:00\",\"dateModified\":\"2010-01-22T03:40:02+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#website\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/\",\"name\":\"Un Universo invisible bajo nuestros pies\",\"description\":\"Los suelos y la vida\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Chern\u00f3byl, Contaminaci\u00f3n Radioactiva, Medio Ambiente y Salud P\u00fablica (por Consuelo Ib\u00e1\u00f1ez) - Un Universo invisible bajo nuestros pies","description":"Ayer el plasta de mi hermano, al que sufr\u00eds como Administrador de Esta Weblog (all\u00e1 cada uno con sus gustos; yo no tengo m\u00e1s remedio, pero vosotros no ten\u00e9is perd\u00f3n) me pidi\u00f3 reiteradamente una peque\u00f1a colaboraci\u00f3n, desde el punto de vista de salud p\u00fablica, sobre el accidente de Chern\u00f3bil y sus efectos. Sinceramente, por falta","canonical_url":"https:\/\/www.madrimasd.org\/blogs\/universo\/2006\/04\/25\/20144","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2006\/04\/25\/20144#blogposting","name":"Chern\u00f3byl, Contaminaci\u00f3n Radioactiva, Medio Ambiente y Salud P\u00fablica (por Consuelo Ib\u00e1\u00f1ez) - Un Universo invisible bajo nuestros pies","headline":"Chern\u00f3byl, Contaminaci\u00f3n Radioactiva, Medio Ambiente y Salud P\u00fablica (por Consuelo Ib\u00e1\u00f1ez)","author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author"},"publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#articleImage","width":217,"height":72},"datePublished":"2006-04-25T20:15:00+01:00","dateModified":"2010-01-22T03:40:02+01:00","inLanguage":"es-ES","commentCount":18,"mainEntityOfPage":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2006\/04\/25\/20144#webpage"},"isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2006\/04\/25\/20144#webpage"},"articleSection":"Degradaci\u00f3n de Suelos: Contaminaci\u00f3n, Los Suelos y la Salud"},{"@type":"BreadcrumbList","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2006\/04\/25\/20144#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo#listItem","position":1,"name":"Home","item":"https:\/\/www.madrimasd.org\/blogs\/universo","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/los-suelos-y-la-salud#listItem","name":"Los Suelos y la Salud"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/los-suelos-y-la-salud#listItem","position":2,"name":"Los Suelos y la Salud","item":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/los-suelos-y-la-salud","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2006\/04\/25\/20144#listItem","name":"Chern\u00f3byl, Contaminaci\u00f3n Radioactiva, Medio Ambiente y Salud P\u00fablica (por Consuelo Ib\u00e1\u00f1ez)"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2006\/04\/25\/20144#listItem","position":3,"name":"Chern\u00f3byl, Contaminaci\u00f3n Radioactiva, Medio Ambiente y Salud P\u00fablica (por Consuelo Ib\u00e1\u00f1ez)","previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/los-suelos-y-la-salud#listItem","name":"Los Suelos y la Salud"}}]},{"@type":"Organization","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#organization","name":"Un Universo invisible bajo nuestros pies","description":"Los suelos y la vida","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/","logo":{"@type":"ImageObject","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2006\/04\/25\/20144\/#organizationLogo","width":217,"height":72},"image":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2006\/04\/25\/20144\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/juan.j.marti.14"]},{"@type":"Person","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo","name":"Juan Jos\u00e9 Ib\u00e1\u00f1ez","image":{"@type":"ImageObject","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2006\/04\/25\/20144#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/387f3a100385573d8f42ce2a3211fd1c?s=96&d=mm&r=g","width":96,"height":96,"caption":"Juan Jos\u00e9 Ib\u00e1\u00f1ez"}},{"@type":"WebPage","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2006\/04\/25\/20144#webpage","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/2006\/04\/25\/20144","name":"Chern\u00f3byl, Contaminaci\u00f3n Radioactiva, Medio Ambiente y Salud P\u00fablica (por Consuelo Ib\u00e1\u00f1ez) - Un Universo invisible bajo nuestros pies","description":"Ayer el plasta de mi hermano, al que sufr\u00eds como Administrador de Esta Weblog (all\u00e1 cada uno con sus gustos; yo no tengo m\u00e1s remedio, pero vosotros no ten\u00e9is perd\u00f3n) me pidi\u00f3 reiteradamente una peque\u00f1a colaboraci\u00f3n, desde el punto de vista de salud p\u00fablica, sobre el accidente de Chern\u00f3bil y sus efectos. Sinceramente, por falta","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#website"},"breadcrumb":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2006\/04\/25\/20144#breadcrumblist"},"author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author"},"creator":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author"},"datePublished":"2006-04-25T20:15:00+01:00","dateModified":"2010-01-22T03:40:02+01:00"},{"@type":"WebSite","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#website","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/","name":"Un Universo invisible bajo nuestros pies","description":"Los suelos y la vida","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Un Universo invisible bajo nuestros pies - Los suelos y la vida","og:type":"article","og:title":"Chern\u00f3byl, Contaminaci\u00f3n Radioactiva, Medio Ambiente y Salud P\u00fablica (por Consuelo Ib\u00e1\u00f1ez) - Un Universo invisible bajo nuestros pies","og:description":"Ayer el plasta de mi hermano, al que sufr\u00eds como Administrador de Esta Weblog (all\u00e1 cada uno con sus gustos; yo no tengo m\u00e1s remedio, pero vosotros no ten\u00e9is perd\u00f3n) me pidi\u00f3 reiteradamente una peque\u00f1a colaboraci\u00f3n, desde el punto de vista de salud p\u00fablica, sobre el accidente de Chern\u00f3bil y sus efectos. Sinceramente, por falta","og:url":"https:\/\/www.madrimasd.org\/blogs\/universo\/2006\/04\/25\/20144","og:image":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png","og:image:secure_url":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png","article:published_time":"2006-04-25T20:15:00+00:00","article:modified_time":"2010-01-22T02:40:02+00:00","article:publisher":"https:\/\/www.facebook.com\/juan.j.marti.14","twitter:card":"summary","twitter:title":"Chern\u00f3byl, Contaminaci\u00f3n Radioactiva, Medio Ambiente y Salud P\u00fablica (por Consuelo Ib\u00e1\u00f1ez) - Un Universo invisible bajo nuestros pies","twitter:description":"Ayer el plasta de mi hermano, al que sufr\u00eds como Administrador de Esta Weblog (all\u00e1 cada uno con sus gustos; yo no tengo m\u00e1s remedio, pero vosotros no ten\u00e9is perd\u00f3n) me pidi\u00f3 reiteradamente una peque\u00f1a colaboraci\u00f3n, desde el punto de vista de salud p\u00fablica, sobre el accidente de Chern\u00f3bil y sus efectos. Sinceramente, por falta","twitter:image":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png"},"aioseo_meta_data":{"post_id":"20144","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":null,"isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","tabs":null,"priority":null,"frequency":null,"local_seo":null,"created":"2022-06-03 13:45:32","updated":"2026-05-26 13:16:05","limit_modified_date":false,"ai":null,"breadcrumb_settings":null,"seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/los-suelos-y-la-salud\" title=\"Los Suelos y la Salud\">Los Suelos y la Salud<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tChern\u00f3byl, Contaminaci\u00f3n Radioactiva, Medio Ambiente y Salud P\u00fablica (por Consuelo Ib\u00e1\u00f1ez)\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.madrimasd.org\/blogs\/universo"},{"label":"Los Suelos y la Salud","link":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/los-suelos-y-la-salud"},{"label":"Chern\u00f3byl, Contaminaci\u00f3n Radioactiva, Medio Ambiente y Salud P\u00fablica (por Consuelo Ib\u00e1\u00f1ez)","link":"https:\/\/www.madrimasd.org\/blogs\/universo\/2006\/04\/25\/20144"}],"_links":{"self":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts\/20144"}],"collection":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/comments?post=20144"}],"version-history":[{"count":3,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts\/20144\/revisions"}],"predecessor-version":[{"id":134014,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts\/20144\/revisions\/134014"}],"wp:attachment":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/media?parent=20144"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/categories?post=20144"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/tags?post=20144"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}