{"id":32484,"date":"2006-06-23T13:10:00","date_gmt":"2006-06-23T13:10:00","guid":{"rendered":"http:\/\/weblogs.madrimasd.org\/\/universo\/archive\/2006\/06\/23\/32484.aspx"},"modified":"2017-09-28T17:37:51","modified_gmt":"2017-09-28T16:37:51","slug":"homo-sapiens-el-sistema-suelo-planta-diversidad-natutal-y-evolucion-cultural","status":"publish","type":"post","link":"https:\/\/www.madrimasd.org\/blogs\/universo\/2006\/06\/23\/32484","title":{"rendered":"Homo Sapiens, El Sistema Suelo-Planta, Diversidad Natural y Evoluci\u00f3n Cultural"},"content":{"rendered":"<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt; text-align: justify;\"><span style=\"font-size: 10pt; font-family: 'Comic Sans MS';\">Vaya mezcla \u00bfno? \u00bfEst\u00e1n relacionadas? \u00a1Pues va a ser que s\u00ed?. <span style=\"color: blue;\">En una contribuci\u00f3n anterior<\/span> vimos como <span style=\"color: blue;\"><a href=\"http:\/\/weblogs.madrimasd.org\/universo\/archive\/2006\/05\/22\/24490.aspx\">la etimolog\u00eda de \u201cHomo sapiens\u201d<\/a><\/span> hace menci\u00f3n al suelo a \u201dtutiplen\u201d. Parece mentira que se nos haya olvidado. Quiz\u00e1s debiera ser el santo y se\u00f1a de nuestra reivindicaci\u00f3n para que los pol\u00edticos tomen conciencia de la importancia del suelo. Las sociedades industriales lo han olvidado. <span style=\"color: blue;\"><a href=\"http:\/\/weblogs.madrimasd.org\/universo\/archive\/2006\/05\/23\/24796.aspx\">Ramiro Ram\u00edrez<\/a><\/span>, desde Colombia <span style=\"color: blue;\">nos recuerda, la importancia de los suelos en los pa\u00edses<\/span> \u201ceufem\u00edsticamente\u201d denominados <span style=\"color: blue;\">en v\u00edas de desarrollo<\/span>.<span style=\"mso-spacerun: yes;\">\u00a0 <\/span>Tambi\u00e9n, tal vez, debi\u00e9ramos comenzar los cursos de edafolog\u00eda en esta direcci\u00f3n.<span style=\"mso-spacerun: yes;\">\u00a0 <\/span>Recientemente se ha reeditado un libro que gan\u00f3 el <a href=\"http:\/\/www.elementos.buap.mx\/num57\/htm\/54.htm\">Premio Pulitzer<\/a> y cuya primera edici\u00f3n data de 1998. Se trata de <span style=\"mso-spacerun: yes;\">\u00a0<\/span>\u201c<span style=\"color: blue;\"><a href=\"http:\/\/www.agapea.com\/Armas-germenes-y-acero-n217243i.htm\">Armas, G\u00e9rmenes y Acero<\/a><\/span>\u201d, de <span style=\"color: #cc0000;\">Jared Diamond<\/span>. \u00bf<a href=\"http:\/\/www.cubaliteraria.com\/evento\/filh\/libro2006.php?Id=89\">No lo hab\u00e9is le\u00eddo<\/a>? Os lo recomiendo v\u00edvidamente, tanto por su inter\u00e9s como por su amenidad. Veamos porqu\u00e9.<\/span><\/p>\n<p><!--more--><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt; text-align: justify;\"><span style=\"font-size: 10pt; color: blue; font-family: 'Comic Sans MS';\">Jared Diamond<\/span><span style=\"font-size: 10pt; font-family: 'Comic Sans MS';\">, es un afamado experto en biodiversidad. Empero <a href=\"http:\/\/amador.cbsj.org\/?p=11\">este libro<\/a> <span style=\"color: #cc0000;\">entronca las<span style=\"mso-spacerun: yes;\">\u00a0 <\/span>relaciones entre biodiversidad-diversidad abi\u00f3tica (como la edafodiversidad)-y evoluci\u00f3n social y tecnol\u00f3gica de las culturas humanas<\/span>. Su lectura me dej\u00f3 impresionado. Yo dir\u00eda que se trata del mejor libro que relata la historia de las sociedades humanas en los \u00faltimos 13.000 a\u00f1os. Impresionante <span style=\"color: #cc0000;\">alegato tambi\u00e9n contra los racismos y los nacionalismos<\/span> por cuanto constata como todos, o casi<span style=\"color: blue;\"> todos los pueblos estamos \u201cdeslocalizados\u201d<\/span>: fuera de nuestras \u00e1reas primigenias de procedencia. Si la civilizaci\u00f3n naci\u00f3 en el creciente f\u00e9rtil fue, ni m\u00e1s ni menos, por una serie de circunstancias ambientales que determinaron la presencia de ciertos vegetales (ciertos tipos de gram\u00edneas y leguminosas) y animales (los actualmente domesticados). Nada de supremac\u00edas raciales ni culturales.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt; text-align: justify;\"><span style=\"font-size: 10pt; font-family: 'Comic Sans MS';\">\u00a0<\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt; text-align: justify;\"><span style=\"font-size: 10pt; color: #cc0000; font-family: 'Comic Sans MS';\">La neolitizaci\u00f3n, o el dominio del sistema suelo-planta, fue la clave del \u00e9xito euroasi\u00e1tico<\/span><span style=\"font-size: 10pt; font-family: 'Comic Sans MS';\">. El manejo de suelos y plantas <span style=\"color: blue;\">nos hizo algo as\u00ed como descender un eslab\u00f3n de la pir\u00e1mide tr\u00f3fica<\/span> (de depredadores a omn\u00edvoros). Los excedentes alimentarios permitieron la multiplicaci\u00f3n de individuos mucho m\u00e1s all\u00e1 de lo que pod\u00eda ocurrir en las <span style=\"color: blue;\">sociedades de cazadores-recolectores<\/span>. <span style=\"color: #cc0000;\">El manejo del sistema suelo-planta permiti\u00f3<\/span>, como corolario, la <span style=\"color: #cc0000;\">evoluci\u00f3n cultural y tecnol\u00f3gica<\/span>, la especializaci\u00f3n e incremento de complejidad de las sociedades basadas en ella. Recomiendo el libro a todos aquellos pueblos que hallan sido <a href=\"http:\/\/amador.cbsj.org\/?p=11\">maltratados por la esclavitud, el racismo<\/a>, o cualquier otro tipo de opresi\u00f3n.<span style=\"mso-spacerun: yes;\">\u00a0 <\/span>Desmitifica cualquier intento a defender la supremac\u00eda de unas razas sobre otras.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt; text-align: justify;\"><span style=\"font-size: 10pt; font-family: 'Comic Sans MS';\">\u00a0<\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt; text-align: justify;\"><span style=\"font-size: 10pt; font-family: 'Comic Sans MS';\">Diamond, <a href=\"http:\/\/marioyvr.blogspot.com\/2006\/04\/armas-grmenes-y-acero.html\">con ejemplos fascinantes<\/a> tambi\u00e9n nos <span style=\"color: #cc0000;\">demuestra la importancia de la edafodiversidad en la evoluci\u00f3n cultural y tecnol\u00f3gica<\/span> (si bien no la menciona expl\u00edcitamente). Las migraciones de sociedades avanzadas de sus tiempos a islas remotas de escasa edafodiversidad y por tanto: con escasas posibilidades de diversificar el manejo de los sistemas suelo-planta<span style=\"mso-spacerun: yes;\">\u00a0 <\/span>(las semillas las llevaban consigo) acarreaba una involuci\u00f3n cultural hacia sociedades m\u00e1s primitivas. La diversidad litol\u00f3gica y fisiogr\u00e1fica tambi\u00e9n eran de suma importancia. <span style=\"mso-spacerun: yes;\">\u00a0<\/span><\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt; text-align: justify;\"><span style=\"font-size: 10pt; font-family: 'Comic Sans MS';\">\u00a0<\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt; text-align: justify;\"><span style=\"font-size: 10pt; color: blue; font-family: 'Comic Sans MS';\">Las migraciones de las sociedades m\u00e1s avanzadas a otros continentes<\/span><span style=\"font-size: 10pt; font-family: 'Comic Sans MS';\"> (como en el caso de de la llegada de Col\u00f3n a las \u201cAm\u00e9ricas\u201d) <span style=\"color: blue;\">devast\u00f3 las culturas conquistadas, no tanto por las guerras o el esclavismo, sino por una consecuencia colateral de la neolitizaci\u00f3n<\/span>: <span style=\"color: blue;\">las enfermedades<\/span> a las que eran inmunes los agricultores-ganaderos, tras su contacto con el ganado (de las que surgieron), afectaron a los conquistados y no inmunizados, <span style=\"color: blue;\">generando pandemias y extinciones de etnias casi por completo<\/span>. Fue involuntario (aunque no siempre como lo demuestra en el caso de los indios de EE.UU.), pero sucedi\u00f3.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt; text-align: justify;\"><span style=\"font-size: 10pt; font-family: 'Comic Sans MS';\">\u00a0<\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt; text-align: justify;\"><span style=\"font-size: 10pt; font-family: 'Comic Sans MS';\">El hombre ha olvidado que sus ra\u00edces, como las de las plantas, penetran y se nutren del suelo. <\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt; text-align: justify;\"><span style=\"font-size: 10pt; font-family: 'Comic Sans MS';\">\u00a0<\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt; text-align: justify;\"><span style=\"font-size: 10pt; font-family: 'Comic Sans MS';\">Por favor leerlo. <span style=\"color: #cc0000;\"><a href=\"http:\/\/www.elementos.buap.mx\/num57\/pdf\/54.pdf\">Armas, G\u00e9rmenes y Acero es<\/a><\/span> un libro que cuando se lee jam\u00e1s se puede olvidar. <\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt; text-align: justify;\"><span style=\"font-size: 10pt; font-family: 'Comic Sans MS';\">\u00a0<\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt; text-align: justify;\"><strong style=\"mso-bidi-font-weight: normal;\"><span style=\"font-size: 14pt; color: #cc0000; font-family: 'Comic Sans MS';\">Juan Jos\u00e9 Ib\u00e1\u00f1ez<\/span><\/strong><span style=\"font-size: 10pt; font-family: 'Comic Sans MS';\"><span style=\"mso-spacerun: yes;\">\u00a0 <\/span><span style=\"mso-spacerun: yes;\">\u00a0<\/span><span style=\"mso-spacerun: yes;\">\u00a0\u00a0<\/span><\/span><\/p>\n<h3>Im\u00e1genes Relacionadas:<\/h3>","protected":false},"excerpt":{"rendered":"<p>Vaya mezcla \u00bfno? \u00bfEst\u00e1n relacionadas? \u00a1Pues va a ser que s\u00ed?. En una contribuci\u00f3n anterior vimos como la etimolog\u00eda de \u201cHomo sapiens\u201d hace menci\u00f3n al suelo a \u201dtutiplen\u201d. Parece mentira que se nos haya olvidado. Quiz\u00e1s debiera ser el santo y se\u00f1a de nuestra reivindicaci\u00f3n para que los pol\u00edticos tomen conciencia de la importancia del suelo. Las sociedades industriales lo han olvidado. Ramiro Ram\u00edrez, desde Colombia nos recuerda, la importancia de los suelos en los pa\u00edses \u201ceufem\u00edsticamente\u201d denominados en v\u00edas de desarrollo.\u00a0 Tambi\u00e9n, tal vez, debi\u00e9ramos comenzar los cursos de edafolog\u00eda en esta direcci\u00f3n.\u00a0 Recientemente se ha reeditado un libro\u2026<\/p>\n","protected":false},"author":26,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0},"categories":[586,584,599,600],"tags":[],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":4}},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Vaya mezcla \u00bfno? \u00bfEst\u00e1n relacionadas? \u00a1Pues va a ser que s\u00ed?. En una contribuci\u00f3n anterior vimos como la etimolog\u00eda de \u201cHomo sapiens\u201d hace menci\u00f3n al suelo a \u201dtutiplen\u201d. Parece mentira que se nos haya olvidado. Quiz\u00e1s debiera ser el santo y se\u00f1a de nuestra reivindicaci\u00f3n para que los pol\u00edticos tomen conciencia de la importancia del\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Juan Jos\u00e9 Ib\u00e1\u00f1ez\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2006\/06\/23\/32484\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Un Universo invisible bajo nuestros pies - Los suelos y la vida\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Homo Sapiens, El Sistema Suelo-Planta, Diversidad Natural y Evoluci\u00f3n Cultural - Un Universo invisible bajo nuestros pies\" \/>\n\t\t<meta property=\"og:description\" content=\"Vaya mezcla \u00bfno? \u00bfEst\u00e1n relacionadas? \u00a1Pues va a ser que s\u00ed?. En una contribuci\u00f3n anterior vimos como la etimolog\u00eda de \u201cHomo sapiens\u201d hace menci\u00f3n al suelo a \u201dtutiplen\u201d. Parece mentira que se nos haya olvidado. Quiz\u00e1s debiera ser el santo y se\u00f1a de nuestra reivindicaci\u00f3n para que los pol\u00edticos tomen conciencia de la importancia del\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2006\/06\/23\/32484\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2006-06-23T13:10:00+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2017-09-28T16:37:51+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/juan.j.marti.14\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Homo Sapiens, El Sistema Suelo-Planta, Diversidad Natural y Evoluci\u00f3n Cultural - Un Universo invisible bajo nuestros pies\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Vaya mezcla \u00bfno? \u00bfEst\u00e1n relacionadas? \u00a1Pues va a ser que s\u00ed?. En una contribuci\u00f3n anterior vimos como la etimolog\u00eda de \u201cHomo sapiens\u201d hace menci\u00f3n al suelo a \u201dtutiplen\u201d. Parece mentira que se nos haya olvidado. Quiz\u00e1s debiera ser el santo y se\u00f1a de nuestra reivindicaci\u00f3n para que los pol\u00edticos tomen conciencia de la importancia del\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2006\\\/06\\\/23\\\/32484#blogposting\",\"name\":\"Homo Sapiens, El Sistema Suelo-Planta, Diversidad Natural y Evoluci\\u00f3n Cultural - Un Universo invisible bajo nuestros pies\",\"headline\":\"Homo Sapiens, El Sistema Suelo-Planta, Diversidad Natural y Evoluci\\u00f3n Cultural\",\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/files\\\/2022\\\/02\\\/logo.png\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#articleImage\",\"width\":217,\"height\":72},\"datePublished\":\"2006-06-23T13:10:00+01:00\",\"dateModified\":\"2017-09-28T17:37:51+01:00\",\"inLanguage\":\"es-ES\",\"commentCount\":8,\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2006\\\/06\\\/23\\\/32484#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2006\\\/06\\\/23\\\/32484#webpage\"},\"articleSection\":\"Diversidad, Complejidad y Fractales, Documentos sobre Edafolog\\u00eda + Instituciones + Enlaces, Etnoedafolog\\u00eda y Conocimiento Campesino, Los Suelos las Plantas y la Vegetaci\\u00f3n\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2006\\\/06\\\/23\\\/32484#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/documentos-sobre-edafologia-instituciones-enlaces#listItem\",\"name\":\"Documentos sobre Edafolog\\u00eda + Instituciones + Enlaces\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/documentos-sobre-edafologia-instituciones-enlaces#listItem\",\"position\":2,\"name\":\"Documentos sobre Edafolog\\u00eda + Instituciones + Enlaces\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/documentos-sobre-edafologia-instituciones-enlaces\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2006\\\/06\\\/23\\\/32484#listItem\",\"name\":\"Homo Sapiens, El Sistema Suelo-Planta, Diversidad Natural y Evoluci\\u00f3n Cultural\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2006\\\/06\\\/23\\\/32484#listItem\",\"position\":3,\"name\":\"Homo Sapiens, El Sistema Suelo-Planta, Diversidad Natural y Evoluci\\u00f3n Cultural\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/documentos-sobre-edafologia-instituciones-enlaces#listItem\",\"name\":\"Documentos sobre Edafolog\\u00eda + Instituciones + Enlaces\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#organization\",\"name\":\"Un Universo invisible bajo nuestros pies\",\"description\":\"Los suelos y la vida\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/files\\\/2022\\\/02\\\/logo.png\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2006\\\/06\\\/23\\\/32484\\\/#organizationLogo\",\"width\":217,\"height\":72},\"image\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2006\\\/06\\\/23\\\/32484\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/juan.j.marti.14\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo\",\"name\":\"Juan Jos\\u00e9 Ib\\u00e1\\u00f1ez\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2006\\\/06\\\/23\\\/32484#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/387f3a100385573d8f42ce2a3211fd1c?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Juan Jos\\u00e9 Ib\\u00e1\\u00f1ez\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2006\\\/06\\\/23\\\/32484#webpage\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2006\\\/06\\\/23\\\/32484\",\"name\":\"Homo Sapiens, El Sistema Suelo-Planta, Diversidad Natural y Evoluci\\u00f3n Cultural - Un Universo invisible bajo nuestros pies\",\"description\":\"Vaya mezcla \\u00bfno? \\u00bfEst\\u00e1n relacionadas? \\u00a1Pues va a ser que s\\u00ed?. En una contribuci\\u00f3n anterior vimos como la etimolog\\u00eda de \\u201cHomo sapiens\\u201d hace menci\\u00f3n al suelo a \\u201dtutiplen\\u201d. Parece mentira que se nos haya olvidado. Quiz\\u00e1s debiera ser el santo y se\\u00f1a de nuestra reivindicaci\\u00f3n para que los pol\\u00edticos tomen conciencia de la importancia del\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2006\\\/06\\\/23\\\/32484#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\"},\"datePublished\":\"2006-06-23T13:10:00+01:00\",\"dateModified\":\"2017-09-28T17:37:51+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#website\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/\",\"name\":\"Un Universo invisible bajo nuestros pies\",\"description\":\"Los suelos y la vida\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Homo Sapiens, El Sistema Suelo-Planta, Diversidad Natural y Evoluci\u00f3n Cultural - Un Universo invisible bajo nuestros pies","description":"Vaya mezcla \u00bfno? \u00bfEst\u00e1n relacionadas? \u00a1Pues va a ser que s\u00ed?. En una contribuci\u00f3n anterior vimos como la etimolog\u00eda de \u201cHomo sapiens\u201d hace menci\u00f3n al suelo a \u201dtutiplen\u201d. Parece mentira que se nos haya olvidado. Quiz\u00e1s debiera ser el santo y se\u00f1a de nuestra reivindicaci\u00f3n para que los pol\u00edticos tomen conciencia de la importancia del","canonical_url":"https:\/\/www.madrimasd.org\/blogs\/universo\/2006\/06\/23\/32484","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2006\/06\/23\/32484#blogposting","name":"Homo Sapiens, El Sistema Suelo-Planta, Diversidad Natural y Evoluci\u00f3n Cultural - Un Universo invisible bajo nuestros pies","headline":"Homo Sapiens, El Sistema Suelo-Planta, Diversidad Natural y Evoluci\u00f3n Cultural","author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author"},"publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#articleImage","width":217,"height":72},"datePublished":"2006-06-23T13:10:00+01:00","dateModified":"2017-09-28T17:37:51+01:00","inLanguage":"es-ES","commentCount":8,"mainEntityOfPage":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2006\/06\/23\/32484#webpage"},"isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2006\/06\/23\/32484#webpage"},"articleSection":"Diversidad, Complejidad y Fractales, Documentos sobre Edafolog\u00eda + Instituciones + Enlaces, Etnoedafolog\u00eda y Conocimiento Campesino, Los Suelos las Plantas y la Vegetaci\u00f3n"},{"@type":"BreadcrumbList","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2006\/06\/23\/32484#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo#listItem","position":1,"name":"Home","item":"https:\/\/www.madrimasd.org\/blogs\/universo","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/documentos-sobre-edafologia-instituciones-enlaces#listItem","name":"Documentos sobre Edafolog\u00eda + Instituciones + Enlaces"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/documentos-sobre-edafologia-instituciones-enlaces#listItem","position":2,"name":"Documentos sobre Edafolog\u00eda + Instituciones + Enlaces","item":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/documentos-sobre-edafologia-instituciones-enlaces","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2006\/06\/23\/32484#listItem","name":"Homo Sapiens, El Sistema Suelo-Planta, Diversidad Natural y Evoluci\u00f3n Cultural"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2006\/06\/23\/32484#listItem","position":3,"name":"Homo Sapiens, El Sistema Suelo-Planta, Diversidad Natural y Evoluci\u00f3n Cultural","previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/documentos-sobre-edafologia-instituciones-enlaces#listItem","name":"Documentos sobre Edafolog\u00eda + Instituciones + Enlaces"}}]},{"@type":"Organization","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#organization","name":"Un Universo invisible bajo nuestros pies","description":"Los suelos y la vida","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/","logo":{"@type":"ImageObject","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2006\/06\/23\/32484\/#organizationLogo","width":217,"height":72},"image":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2006\/06\/23\/32484\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/juan.j.marti.14"]},{"@type":"Person","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo","name":"Juan Jos\u00e9 Ib\u00e1\u00f1ez","image":{"@type":"ImageObject","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2006\/06\/23\/32484#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/387f3a100385573d8f42ce2a3211fd1c?s=96&d=mm&r=g","width":96,"height":96,"caption":"Juan Jos\u00e9 Ib\u00e1\u00f1ez"}},{"@type":"WebPage","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2006\/06\/23\/32484#webpage","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/2006\/06\/23\/32484","name":"Homo Sapiens, El Sistema Suelo-Planta, Diversidad Natural y Evoluci\u00f3n Cultural - Un Universo invisible bajo nuestros pies","description":"Vaya mezcla \u00bfno? \u00bfEst\u00e1n relacionadas? \u00a1Pues va a ser que s\u00ed?. En una contribuci\u00f3n anterior vimos como la etimolog\u00eda de \u201cHomo sapiens\u201d hace menci\u00f3n al suelo a \u201dtutiplen\u201d. Parece mentira que se nos haya olvidado. Quiz\u00e1s debiera ser el santo y se\u00f1a de nuestra reivindicaci\u00f3n para que los pol\u00edticos tomen conciencia de la importancia del","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#website"},"breadcrumb":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2006\/06\/23\/32484#breadcrumblist"},"author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author"},"creator":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author"},"datePublished":"2006-06-23T13:10:00+01:00","dateModified":"2017-09-28T17:37:51+01:00"},{"@type":"WebSite","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#website","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/","name":"Un Universo invisible bajo nuestros pies","description":"Los suelos y la vida","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Un Universo invisible bajo nuestros pies - Los suelos y la vida","og:type":"article","og:title":"Homo Sapiens, El Sistema Suelo-Planta, Diversidad Natural y Evoluci\u00f3n Cultural - Un Universo invisible bajo nuestros pies","og:description":"Vaya mezcla \u00bfno? \u00bfEst\u00e1n relacionadas? \u00a1Pues va a ser que s\u00ed?. En una contribuci\u00f3n anterior vimos como la etimolog\u00eda de \u201cHomo sapiens\u201d hace menci\u00f3n al suelo a \u201dtutiplen\u201d. Parece mentira que se nos haya olvidado. Quiz\u00e1s debiera ser el santo y se\u00f1a de nuestra reivindicaci\u00f3n para que los pol\u00edticos tomen conciencia de la importancia del","og:url":"https:\/\/www.madrimasd.org\/blogs\/universo\/2006\/06\/23\/32484","og:image":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png","og:image:secure_url":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png","article:published_time":"2006-06-23T13:10:00+00:00","article:modified_time":"2017-09-28T16:37:51+00:00","article:publisher":"https:\/\/www.facebook.com\/juan.j.marti.14","twitter:card":"summary","twitter:title":"Homo Sapiens, El Sistema Suelo-Planta, Diversidad Natural y Evoluci\u00f3n Cultural - Un Universo invisible bajo nuestros pies","twitter:description":"Vaya mezcla \u00bfno? \u00bfEst\u00e1n relacionadas? \u00a1Pues va a ser que s\u00ed?. En una contribuci\u00f3n anterior vimos como la etimolog\u00eda de \u201cHomo sapiens\u201d hace menci\u00f3n al suelo a \u201dtutiplen\u201d. Parece mentira que se nos haya olvidado. Quiz\u00e1s debiera ser el santo y se\u00f1a de nuestra reivindicaci\u00f3n para que los pol\u00edticos tomen conciencia de la importancia del","twitter:image":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png"},"aioseo_meta_data":{"post_id":"32484","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":null,"isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","tabs":null,"priority":null,"frequency":null,"local_seo":null,"created":"2022-06-03 13:50:51","updated":"2026-05-26 13:22:51","limit_modified_date":false,"ai":null,"breadcrumb_settings":null,"seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/documentos-sobre-edafologia-instituciones-enlaces\" title=\"Documentos sobre Edafolog\u00eda + Instituciones + Enlaces\">Documentos sobre Edafolog\u00eda + Instituciones + Enlaces<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tHomo Sapiens, El Sistema Suelo-Planta, Diversidad Natural y Evoluci\u00f3n Cultural\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.madrimasd.org\/blogs\/universo"},{"label":"Documentos sobre Edafolog\u00eda + Instituciones + Enlaces","link":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/documentos-sobre-edafologia-instituciones-enlaces"},{"label":"Homo Sapiens, El Sistema Suelo-Planta, Diversidad Natural y Evoluci\u00f3n Cultural","link":"https:\/\/www.madrimasd.org\/blogs\/universo\/2006\/06\/23\/32484"}],"_links":{"self":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts\/32484"}],"collection":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/comments?post=32484"}],"version-history":[{"count":7,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts\/32484\/revisions"}],"predecessor-version":[{"id":149199,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts\/32484\/revisions\/149199"}],"wp:attachment":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/media?parent=32484"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/categories?post=32484"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/tags?post=32484"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}