{"id":69567,"date":"2007-07-08T10:21:00","date_gmt":"2007-07-08T10:21:00","guid":{"rendered":"http:\/\/weblogs.madrimasd.org\/\/universo\/archive\/2007\/07\/08\/69567.aspx"},"modified":"2024-06-03T15:18:31","modified_gmt":"2024-06-03T14:18:31","slug":"relativismo-radical-en-la-filosofia-de-la-ciencia-el-anarquismo-de-paul-feyerabend","status":"publish","type":"post","link":"https:\/\/www.madrimasd.org\/blogs\/universo\/2007\/07\/08\/69567","title":{"rendered":"Relativismo Radical en la Filosof\u00eda de la Ciencia: El Anarquismo de Paul Feyerabend"},"content":{"rendered":"<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt;text-align: justify\"><span lang=\"ES-TRAD\" style=\"font-size: 10pt;font-family: 'Comic Sans MS'\">Hasta este post hemos venido narrando en nuestro \u201c<a href=\"http:\/\/weblogs.madrimasd.org\/universo\/category\/496.aspx\"><span style=\"color: #800080\">Curso B\u00e1sico sobre filosof\u00eda y Sociolog\u00eda de la Ciencia<\/span><\/a>\u201d, las posiciones de las distintas escuelas m\u00e1s o menos convencionales. Como se ha podido observar l<b><span style=\"color: #3366ff\">os conceptos de ciencia, m\u00e9todo cient\u00edfico, progreso y otros \u00edtems relacionados han ido relativiz\u00e1ndose, en vista de que ninguna escuela precedente ha sido capaz de ofrecer un modelo v\u00e1lido<\/span><\/b> de c\u00f3mo funciona la ciencia y cuales son sus principios. <b><span style=\"color: #3366ff\">La sociolog\u00eda de la ciencia ofrece una perspectiva del comportamiento de la(s) comunidad(es) cient\u00edfica(s) como empresas humanas<\/span><\/b>. En consecuencia, a\u00f1aden m\u00e1s elementos, tanto para el debate como para la discusi\u00f3n. Las filosof\u00edas de la ciencia, posteriores a la propuesta de Kuhn <b><span style=\"color: #3366ff\">son a\u00fan m\u00e1s relativistas<\/span><\/b> y abundan en el componente sociol\u00f3gico. <b><span style=\"color: #3366ff\">La empresa cient\u00edfica, como los valores de la sociedad, cambian con los tiempos y, en consecuencia, tambi\u00e9n las perspectivas que tenemos de ella<\/span><\/b>. La actividad cient\u00edfica, insistimos, es una actividad humana y social. Como corolario, \u00e9sta no puede disociarse&nbsp;de los individuos que la constituyen, ni de sus valores, como tampoco del contexto hist\u00f3rico en el que surgieron las distintas teor\u00edas. <\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt;text-align: justify\">&nbsp;<\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt;text-align: justify\"><span lang=\"ES-TRAD\" style=\"font-size: 10pt;font-family: 'Comic Sans MS'\">&nbsp;<span lang=\"ES-TRAD\" style=\"font-size: 10pt;font-family: 'Comic Sans MS'\"><img decoding=\"async\" class=\"aligncenter\" src=\"\/blogs\/universo\/wp-content\/blogs.dir\/42\/files\/159\/o_Feyerabend.JPG\" width=\"903\" height=\"1213\"><\/span><\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt;text-align: justify\"><span lang=\"ES-TRAD\" style=\"font-size: 10pt;font-family: 'Comic Sans MS'\">&nbsp;<\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt;text-align: justify\">&nbsp;<\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt;text-align: justify\"><b><span lang=\"ES-TRAD\" style=\"font-size: 10pt;color: #3366ff;font-family: 'Comic Sans MS'\">Paul Feyerabend<\/span><\/b><\/p>\n<p><!--more--><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt;text-align: justify\"><span lang=\"ES-TRAD\" style=\"font-size: 10pt;font-family: 'Comic Sans MS'\">&nbsp;<\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt;text-align: justify\"><span lang=\"ES-TRAD\" style=\"font-size: 10pt;font-family: 'Comic Sans MS'\">Aunque nosotros nos sentimos relativistas moderados, tambi\u00e9n consideramos que<b><span style=\"color: #3366ff\"> todas las escuelas tienen algo que ofrecer<\/span><\/b>. De aqu\u00ed, nuestro contumaz apoyo al <b><span style=\"color: #3366ff\">pluralismo epistemol\u00f3gico<\/span><\/b>, que es tambi\u00e9n del gusto de muchos relativistas modernos. El encarecimiento de la actividad cient\u00edfica, as\u00ed como la consolidaci\u00f3n de un modelo de sociedad basado en la ciencia como motor de la innovaci\u00f3n y desarrollo tecnol\u00f3gico, est\u00e1n generando <b><span style=\"color: #3366ff\">una dependencia cada vez m\u00e1s estrecha entre la primera, los agentes sociales y la pol\u00edtica<\/span><\/b>. Bajo tales circunstancias, <b><span style=\"color: #3366ff\">resulta totalmente vano desvincular la ciencia de su entorno<\/span><\/b>. Intentar analizarla como un sistema cerrado que evoluciona, total o exclusivamente, gracias a un determinado tipo de racionalidad y m\u00e9todo es una mera quimera. Desde la promoci\u00f3n, hasta el logro de subvenciones, pasando por la posibilidad de publicar en las revistas de mayor prestigio, se encuentra condicionada, como el suelo, por aquellos factores externos (condiciones de contorno) o de control de los cuales depende.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt;text-align: justify\"><span lang=\"ES-TRAD\" style=\"font-size: 10pt;font-family: 'Comic Sans MS'\">&nbsp;<\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt;text-align: justify\"><span lang=\"ES-TRAD\" style=\"font-size: 10pt;font-family: 'Comic Sans MS'\">Por estas razones, animamos a los posibles lectores a que profundicen en el tema consultando posturas a\u00fan m\u00e1s radicales que las que ofreci\u00f3 en su momento Thomas Kuhn. Si deseamos saber que papel desempe\u00f1amos en la empresa cient\u00edfica, no podemos adoptar posturas acomodaticias, debemos pasar de ser meros obreros en nuestros puestos de trabajo a intentar conocer cuales son nuestros roles en una estructura cada vez m\u00e1s compleja y entrelazada. Los sistemas de investigaci\u00f3n y desarrollo tecnol\u00f3gico trascienden a los productos elaborados por el colectivo de cient\u00edficos y tecn\u00f3logos. Aqu\u00ed hemos puesto nuestro granito de arena. <\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt;text-align: justify\"><span lang=\"ES-TRAD\" style=\"font-size: 10pt;font-family: 'Comic Sans MS'\">&nbsp;<\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt;text-align: justify\"><span lang=\"ES-TRAD\" style=\"font-size: 10pt;font-family: 'Comic Sans MS'\">En cualquier caso debemos advertir que,<b><span style=\"color: #3366ff\"> para muchas escuelas de filosof\u00eda de la ciencia, la edafolog\u00eda ser\u00eda m\u00e1s una protociencia que una ciencia<\/span><\/b>, por cuanto no tiene articulado ning\u00fan entramado te\u00f3rico que gu\u00ede claramente nuestra actividad y articule los conocimientos alcanzados en un corpus doctrinal coherente e indiscutible. <b><span style=\"color: #3366ff\">Tan solo a la luz de algunas de las escuelas relativistas m\u00e1s radicales, podr\u00edamos hablar de la edafolog\u00eda como ciencia por derecho propio<\/span><\/b>. De nosotros depender\u00e1 que seamos capaces de articular una teor\u00eda edafol\u00f3gica digna de ser considerada como tal por la comunidad cient\u00edfica y la mayor parte de las escuelas filos\u00f3ficas. La tarea es dif\u00edcil, pero no imposible. Como hemos ido refiriendo a lo largo del presente curso, <b><span style=\"color: #3366ff\">otras disciplinas afines (geomorfolog\u00eda, ecolog\u00eda, geograf\u00eda, etc.) han iniciado una seria reflexi\u00f3n sobre sus respectivos status epistemol\u00f3gicos con vistas a solucionar sus problemas de coherencia interna<\/span><\/b>. A nosotros nos resulta sorprendente, como los especialistas de muchos de estos campos, enfocan ya las cuestiones de su competencia desde puntos de vista muy relativistas. Si no logramos dar los mismos pasos, la edafolog\u00eda no pasar\u00e1 de ser considerada como una disciplina acad\u00e9mica (que no ciencia) cuyo rumbo ir\u00e1 al vaiv\u00e9n de las modas, sociedad, los grupos f\u00e1cticos y vaivenes pol\u00edticos.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt;text-align: justify\"><span lang=\"ES-TRAD\" style=\"font-size: 10pt;font-family: 'Comic Sans MS'\">&nbsp;<\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt;text-indent: 21.3pt;text-align: justify\"><span lang=\"ES-TRAD\" style=\"font-size: 10pt;font-family: 'Comic Sans MS'\">Posiblemente, la primera reacci\u00f3n radicalmente relativista la postul\u00f3 el <b><span style=\"color: #3366ff\">fil\u00f3sofo anarquista alem\u00e1n Paul Feyerabend (1970, 1981), <\/span><\/b>en su ya cl\u00e1sica y popular obra <\/span><span style=\"font-size: 10pt;font-family: 'Comic Sans MS'\">\u00ab<i>Against method: Outline of an anarchistic theory of knowledg<\/i>\u00bb (<b><span style=\"color: #3366ff\">Contra el M\u00e9todo: Bosquejo de una Teor\u00eda Anarquista del Conocimiento<\/span><\/b>). <\/span><span lang=\"ES-TRAD\" style=\"font-size: 10pt;font-family: 'Comic Sans MS'\">De acuerdo con la tesis m\u00e1s radical que se puede leer en los escritos m\u00e1s recientes de <a href=\"http:\/\/es.wikipedia.org\/wiki\/Paul_Feyerabend\"><span style=\"color: #800080\">Feyerabend<\/span><\/a>, <b><span style=\"color: #3366ff\">la ciencia no poseer\u00eda rasgos especiales que la hagan intr\u00ednsecamente superior a otras ramas del conocimiento humano<\/span><\/b>, tales como los antiguos mitos o el vud\u00fa. El elevado respeto por la ciencia a los ojos de este autor son un mero reflejo de intentar convertirla en una <b><span style=\"color: #3366ff\">religi\u00f3n moderna<\/span><\/b>, que desempe\u00f1a un papel similar al que tuvo el cristianismo en Europa en \u00e9pocas anteriores. Para Feyerabend, la elecci\u00f3n entre distintas teor\u00edas rivales se reduce a una decisi\u00f3n colectiva basada en los valores y deseos subjetivos de los individuos involucrados. Demasiado radical. Nosotros no pretendemos dar una explicaci\u00f3n de la f\u00edsica que sea tan subjetivista o individualista, aunque <b><span style=\"color: #3366ff\">como Chalmers (1984) aceptamos buena parte de la cr\u00edtica contra el m\u00e9todo de Feyerabend<\/span><\/b>.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt;text-align: justify\"><span lang=\"ES-TRAD\" style=\"font-size: 10pt;font-family: 'Comic Sans MS'\">&nbsp;<\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt;text-align: justify\"><span lang=\"ES-TRAD\" style=\"font-size: 10pt;font-family: 'Comic Sans MS'\">A los lectores no versados en temas sobre filosof\u00eda de la ciencia, les resultar\u00e1 dif\u00edcil de entender el respecto que los colegas mostraron ante los feroces ataques de <a href=\"http:\/\/es.wikipedia.org\/wiki\/Paul_Feyerabend\"><span style=\"color: #800080\">Feyerabend<\/span><\/a> en contra de la divinizaci\u00f3n de la ciencia en el mundo moderno. <b><span style=\"color: #3366ff\">Autor de mente \u00e1gil, apasionadas propuestas y mordaz pluma, ha calado en la filosof\u00eda de la ciencia actual como un \u201cPepito Grillo<\/span><\/b>\u201d, con el que no se debe entrar a discutir, pero al que hay que tener siempre presente de reojo.&nbsp; Y no se cortaba el pelo <b><span style=\"color: #3366ff\">al comparar a la ciencia con un prost\u00edbulo<\/span><\/b>. Tambi\u00e9n ahond\u00f3 en el problema de <b><span style=\"color: #3366ff\">la inconmensurabilidad de las teor\u00edas cient\u00edficas <\/span><\/b>propuestas por Kuhn.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt;text-align: justify\"><span lang=\"ES-TRAD\" style=\"font-size: 10pt;font-family: 'Comic Sans MS'\">&nbsp;<\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt;text-align: justify\"><span lang=\"ES-TRAD\" style=\"font-size: 10pt;font-family: 'Comic Sans MS'\">Como defensor del pluralismo epistemol\u00f3gico, considero que <b><span style=\"color: #3366ff\">los ataques de Feyerabend contra la ciencia institucionalizada son de obligada lectura<\/span><\/b>. Empero existen otras proposiciones posteriores, tanto o m\u00e1s audaces y provocativas que ir\u00e1n desgran\u00e1ndose despacio en nuestra aventura \u201c<i>Bloggera<\/i>\u201d. <\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt;text-indent: 21.3pt;text-align: justify\"><span lang=\"ES-TRAD\" style=\"font-size: 10pt;font-family: 'Comic Sans MS'\">&nbsp;<\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt;text-align: justify\"><b><span lang=\"ES-TRAD\" style=\"color: #cc0000;font-family: 'Comic Sans MS'\">Juan Jos\u00e9 Ib\u00e1\u00f1ez<\/span><\/b><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt;text-align: center\" align=\"center\"><b><span lang=\"ES-TRAD\" style=\"font-size: 10pt;color: green;font-family: 'Comic Sans MS'\">&nbsp;<\/span><\/b><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt;text-align: center\" align=\"center\"><b><span lang=\"ES-TRAD\" style=\"font-size: 10pt;color: green;font-family: 'Comic Sans MS'\">Sumario de los post editados en \u201cCurso B\u00e1sico sobre Filosof\u00eda y Sociolog\u00eda de la Ciencia hasta este post (pinchar en los n\u00fameros para desplegar los post)<\/span><\/b><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt\"><b><span lang=\"ES-TRAD\" style=\"font-size: 14pt;color: #cc0000;font-family: 'Comic Sans MS'\">&nbsp;<\/span><\/b><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt\"><span lang=\"ES-TRAD\" style=\"font-size: 8pt;font-family: 'Comic Sans MS'\"><a href=\"http:\/\/weblogs.madrimasd.org\/universo\/archive\/2006\/09\/21\/42563.aspx\">\u00bfQu\u00e9 es esa cosa llamada Ciencia?<\/a><\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt\"><span lang=\"ES-TRAD\" style=\"font-size: 8pt;font-family: 'Comic Sans MS'\"><a href=\"http:\/\/weblogs.madrimasd.org\/universo\/archive\/2006\/10\/08\/45363.aspx\">El M\u00e9todo Cient\u00edfico<\/a><\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt\"><span lang=\"ES-TRAD\" style=\"font-size: 8pt;color: #222222;font-family: 'Comic Sans MS'\"><a href=\"http:\/\/weblogs.madrimasd.org\/universo\/archive\/2006\/12\/09\/54549.aspx\">Curso B\u00e1sico sobre Filosof\u00eda y Sociolog\u00eda de la Ciencia<\/a><\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt\"><span lang=\"ES-TRAD\" style=\"font-size: 8pt;color: #222222;font-family: 'Comic Sans MS'\"><a href=\"http:\/\/weblogs.madrimasd.org\/universo\/archive\/2005\/12\/20\/11008.aspx\">Reduccionismo Epistemol\u00f3gico<\/a><\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt\"><span lang=\"ES-TRAD\" style=\"font-size: 8pt;color: blue;font-family: 'Comic Sans MS'\">Ciencia e Inducci\u00f3n<\/span><span lang=\"ES-TRAD\" style=\"font-size: 8pt;color: #222222;font-family: 'Comic Sans MS'\"> [<a href=\"http:\/\/weblogs.madrimasd.org\/universo\/archive\/2006\/12\/09\/54568.aspx\">1<\/a>, <a href=\"http:\/\/weblogs.madrimasd.org\/universo\/archive\/2006\/12\/13\/55116.aspx\">2<\/a>, <a href=\"http:\/\/weblogs.madrimasd.org\/universo\/archive\/2006\/12\/17\/55441.aspx\"><span style=\"color: #800080\">3<\/span><\/a>, <a href=\"http:\/\/weblogs.madrimasd.org\/universo\/archive\/2006\/12\/17\/55451.aspx\">4<\/a>, <a href=\"http:\/\/weblogs.madrimasd.org\/universo\/archive\/2006\/12\/22\/55811.aspx\">5<\/a>, <a href=\"http:\/\/weblogs.madrimasd.org\/universo\/archive\/2006\/12\/23\/55843.aspx\">6<\/a>, <a href=\"http:\/\/weblogs.madrimasd.org\/universo\/archive\/2006\/12\/24\/55882.aspx\"><span style=\"color: purple\">7<\/span><\/a>, <a href=\"http:\/\/weblogs.madrimasd.org\/universo\/archive\/2007\/01\/03\/56466.aspx\"><span style=\"color: purple\">8<\/span><\/a>, <a href=\"http:\/\/weblogs.madrimasd.org\/universo\/archive\/2007\/01\/04\/56523.aspx\"><span style=\"color: purple\">9<\/span><\/a>, <a href=\"http:\/\/weblogs.madrimasd.org\/universo\/archive\/2007\/01\/06\/56646.aspx\"><span style=\"color: purple\">10<\/span><\/a>, <a href=\"http:\/\/weblogs.madrimasd.org\/universo\/archive\/2007\/01\/06\/56646.aspx\">11<\/a>, <a href=\"http:\/\/weblogs.madrimasd.org\/universo\/archive\/2007\/01\/27\/58211.aspx\">12<\/a>,<a href=\"http:\/\/weblogs.madrimasd.org\/universo\/archive\/2007\/01\/28\/58262.aspx\"> 13<\/a>,]<\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt\"><span lang=\"ES-TRAD\" style=\"font-size: 8pt;color: blue;font-family: 'Comic Sans MS'\">Filosof\u00eda de Karl Poper: El Falsacionismo<\/span><span lang=\"ES-TRAD\" style=\"font-size: 8pt;color: #222222;font-family: 'Comic Sans MS'\"> [<a href=\"http:\/\/weblogs.madrimasd.org\/universo\/archive\/2007\/02\/03\/58614.aspx\">14<\/a>, <a href=\"http:\/\/weblogs.madrimasd.org\/universo\/archive\/2007\/02\/10\/59009.aspx\">15<\/a>, <a href=\"http:\/\/weblogs.madrimasd.org\/universo\/archive\/2007\/02\/10\/59010.aspx\">16<\/a>, <a href=\"http:\/\/weblogs.madrimasd.org\/universo\/archive\/2007\/02\/17\/59475.aspx\">19<\/a>, <a href=\"http:\/\/weblogs.madrimasd.org\/universo\/archive\/2007\/02\/24\/59924.aspx\">20<\/a>, <a href=\"http:\/\/weblogs.madrimasd.org\/universo\/archive\/2007\/03\/03\/60326.aspx\">21<\/a>, <a href=\"http:\/\/weblogs.madrimasd.org\/universo\/archive\/2007\/03\/10\/60880.aspx\">23<\/a>, <a href=\"http:\/\/weblogs.madrimasd.org\/universo\/archive\/2007\/03\/17\/61558.aspx\">24<\/a>, <a href=\"http:\/\/weblogs.madrimasd.org\/universo\/archive\/2007\/03\/23\/62137.aspx\">25<\/a>, <a href=\"http:\/\/weblogs.madrimasd.org\/universo\/archive\/2007\/03\/23\/62145.aspx\">26<\/a>]<\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt\"><span lang=\"ES-TRAD\" style=\"font-size: 8pt;color: blue;font-family: 'Comic Sans MS'\">Filosof\u00eda de la Teor\u00eda de la Evoluci\u00f3n y Sociedad <\/span><span lang=\"ES-TRAD\" style=\"font-size: 8pt;color: #222222;font-family: 'Comic Sans MS'\">&nbsp;&nbsp;[<a href=\"http:\/\/weblogs.madrimasd.org\/universo\/archive\/2007\/02\/14\/59275.aspx\">17<\/a>, <a href=\"http:\/\/weblogs.madrimasd.org\/universo\/archive\/2007\/02\/14\/59285.aspx\">18<\/a>],<\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt;text-align: justify\"><span lang=\"ES-TRAD\" style=\"font-size: 8pt;color: blue;font-family: 'Comic Sans MS'\">Naturaleza y ense\u00f1anza de la Ciencia<\/span><span lang=\"ES-TRAD\" style=\"font-size: 8pt;font-family: 'Comic Sans MS'\"> [<a href=\"http:\/\/weblogs.madrimasd.org\/universo\/archive\/2007\/03\/03\/60332.aspx\">22<\/a>]<\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt;text-align: justify\"><span lang=\"ES-TRAD\" style=\"font-size: 8pt;font-family: 'Comic Sans MS'\"><a href=\"http:\/\/weblogs.madrimasd.org\/universo\/archive\/2007\/04\/01\/62705.aspx\">Las Teor\u00edas Cient\u00edficas Como Estructuras Complejas<\/a><\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt;text-align: justify\"><span lang=\"ES-TRAD\" style=\"font-size: 8pt;color: blue;font-family: 'Comic Sans MS'\">La Filosof\u00eda de Imre Lakatos<\/span><span lang=\"ES-TRAD\" style=\"font-size: 8pt;font-family: 'Comic Sans MS'\">&nbsp; [<a href=\"http:\/\/weblogs.madrimasd.org\/universo\/archive\/2007\/04\/15\/63581.aspx\">28<\/a>, <a href=\"http:\/\/weblogs.madrimasd.org\/universo\/archive\/2007\/04\/21\/64084.aspx\">29<\/a>, <a href=\"http:\/\/weblogs.madrimasd.org\/universo\/archive\/2007\/04\/28\/64566.aspx\">30<\/a>, <a href=\"http:\/\/weblogs.madrimasd.org\/universo\/archive\/2007\/05\/05\/64981.aspx\">31<\/a>, <a href=\"http:\/\/weblogs.madrimasd.org\/universo\/archive\/2007\/05\/12\/65443.aspx\">32<\/a>]<\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt\"><span lang=\"ES-TRAD\" style=\"font-size: 8pt;color: blue;font-family: 'Comic Sans MS'\">La Filosof\u00eda de Thom\u00e1s Kuhn<\/span> <span lang=\"ES-TRAD\" style=\"font-size: 8pt;font-family: 'Comic Sans MS'\">[<a href=\"http:\/\/weblogs.madrimasd.org\/universo\/archive\/2007\/05\/19\/65903.aspx\"><span style=\"color: #800080\">33<\/span><\/a>,<a href=\"http:\/\/weblogs.madrimasd.org\/universo\/archive\/2007\/05\/26\/66445.aspx\"><span style=\"color: #800080\"> 34<\/span><\/a>, <a href=\"http:\/\/weblogs.madrimasd.org\/universo\/archive\/2007\/06\/02\/66914.aspx\">35<\/a>, <a href=\"http:\/\/weblogs.madrimasd.org\/universo\/archive\/2007\/06\/10\/67410.aspx\">36<\/a>,<a href=\"http:\/\/weblogs.madrimasd.org\/universo\/archive\/2007\/06\/17\/67885.aspx\"><span style=\"color: #800080\"> 37<\/span><\/a>]<\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt;text-align: justify\"><span lang=\"ES-TRAD\" style=\"font-size: 10pt;font-family: 'Comic Sans MS'\">&nbsp;<\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt;text-align: justify\"><span lang=\"ES-TRAD\" style=\"font-size: 10pt;font-family: 'Comic Sans MS'\">&nbsp;<\/span><\/p>\n<h3>Im\u00e1genes Relacionadas:<\/h3>","protected":false},"excerpt":{"rendered":"<p>Hasta este post hemos venido narrando en nuestro \u201cCurso B\u00e1sico sobre filosof\u00eda y Sociolog\u00eda de la Ciencia\u201d, las posiciones de las distintas escuelas m\u00e1s o menos convencionales. Como se ha podido observar los conceptos de ciencia, m\u00e9todo cient\u00edfico, progreso y otros \u00edtems relacionados han ido relativiz\u00e1ndose, en vista de que ninguna escuela precedente ha sido capaz de ofrecer un modelo v\u00e1lido de c\u00f3mo funciona la ciencia y cuales son sus principios. La sociolog\u00eda de la ciencia ofrece una perspectiva del comportamiento de la(s) comunidad(es) cient\u00edfica(s) como empresas humanas. En consecuencia, a\u00f1aden m\u00e1s elementos, tanto para el debate como para la\u2026<\/p>\n","protected":false},"author":26,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0},"categories":[609,597,587],"tags":[],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":4}},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Hasta este post hemos venido narrando en nuestro \u201cCurso B\u00e1sico sobre filosof\u00eda y Sociolog\u00eda de la Ciencia\u201d, las posiciones de las distintas escuelas m\u00e1s o menos convencionales. Como se ha podido observar los conceptos de ciencia, m\u00e9todo cient\u00edfico, progreso y otros \u00edtems relacionados han ido relativiz\u00e1ndose, en vista de que ninguna escuela precedente ha sido\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Juan Jos\u00e9 Ib\u00e1\u00f1ez\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2007\/07\/08\/69567\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Un Universo invisible bajo nuestros pies - Los suelos y la vida\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Relativismo Radical en la Filosof\u00eda de la Ciencia: El Anarquismo de Paul Feyerabend - Un Universo invisible bajo nuestros pies\" \/>\n\t\t<meta property=\"og:description\" content=\"Hasta este post hemos venido narrando en nuestro \u201cCurso B\u00e1sico sobre filosof\u00eda y Sociolog\u00eda de la Ciencia\u201d, las posiciones de las distintas escuelas m\u00e1s o menos convencionales. Como se ha podido observar los conceptos de ciencia, m\u00e9todo cient\u00edfico, progreso y otros \u00edtems relacionados han ido relativiz\u00e1ndose, en vista de que ninguna escuela precedente ha sido\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2007\/07\/08\/69567\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2007-07-08T10:21:00+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2024-06-03T14:18:31+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/juan.j.marti.14\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Relativismo Radical en la Filosof\u00eda de la Ciencia: El Anarquismo de Paul Feyerabend - Un Universo invisible bajo nuestros pies\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Hasta este post hemos venido narrando en nuestro \u201cCurso B\u00e1sico sobre filosof\u00eda y Sociolog\u00eda de la Ciencia\u201d, las posiciones de las distintas escuelas m\u00e1s o menos convencionales. Como se ha podido observar los conceptos de ciencia, m\u00e9todo cient\u00edfico, progreso y otros \u00edtems relacionados han ido relativiz\u00e1ndose, en vista de que ninguna escuela precedente ha sido\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2007\\\/07\\\/08\\\/69567#blogposting\",\"name\":\"Relativismo Radical en la Filosof\\u00eda de la Ciencia: El Anarquismo de Paul Feyerabend - Un Universo invisible bajo nuestros pies\",\"headline\":\"Relativismo Radical en la Filosof\\u00eda de la Ciencia: El Anarquismo de Paul Feyerabend\",\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"\\\/blogs\\\/universo\\\/wp-content\\\/blogs.dir\\\/42\\\/files\\\/159\\\/o_Feyerabend.JPG\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2007\\\/07\\\/08\\\/69567\\\/#articleImage\"},\"datePublished\":\"2007-07-08T10:21:00+01:00\",\"dateModified\":\"2024-06-03T15:18:31+01:00\",\"inLanguage\":\"es-ES\",\"commentCount\":7,\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2007\\\/07\\\/08\\\/69567#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2007\\\/07\\\/08\\\/69567#webpage\"},\"articleSection\":\"Curso B\\u00e1sico Sobre Filosof\\u00eda y Sociolog\\u00eda de la Ciencia, Filosof\\u00eda, Historia y Sociolog\\u00eda de la Edafolog\\u00eda, La Crisis de la Edafolog\\u00eda\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2007\\\/07\\\/08\\\/69567#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/la-crisis-de-la-edafologia#listItem\",\"name\":\"La Crisis de la Edafolog\\u00eda\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/la-crisis-de-la-edafologia#listItem\",\"position\":2,\"name\":\"La Crisis de la Edafolog\\u00eda\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/la-crisis-de-la-edafologia\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2007\\\/07\\\/08\\\/69567#listItem\",\"name\":\"Relativismo Radical en la Filosof\\u00eda de la Ciencia: El Anarquismo de Paul Feyerabend\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2007\\\/07\\\/08\\\/69567#listItem\",\"position\":3,\"name\":\"Relativismo Radical en la Filosof\\u00eda de la Ciencia: El Anarquismo de Paul Feyerabend\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/la-crisis-de-la-edafologia#listItem\",\"name\":\"La Crisis de la Edafolog\\u00eda\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#organization\",\"name\":\"Un Universo invisible bajo nuestros pies\",\"description\":\"Los suelos y la vida\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/files\\\/2022\\\/02\\\/logo.png\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2007\\\/07\\\/08\\\/69567\\\/#organizationLogo\",\"width\":217,\"height\":72},\"image\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2007\\\/07\\\/08\\\/69567\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/juan.j.marti.14\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo\",\"name\":\"Juan Jos\\u00e9 Ib\\u00e1\\u00f1ez\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2007\\\/07\\\/08\\\/69567#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/387f3a100385573d8f42ce2a3211fd1c?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Juan Jos\\u00e9 Ib\\u00e1\\u00f1ez\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2007\\\/07\\\/08\\\/69567#webpage\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2007\\\/07\\\/08\\\/69567\",\"name\":\"Relativismo Radical en la Filosof\\u00eda de la Ciencia: El Anarquismo de Paul Feyerabend - Un Universo invisible bajo nuestros pies\",\"description\":\"Hasta este post hemos venido narrando en nuestro \\u201cCurso B\\u00e1sico sobre filosof\\u00eda y Sociolog\\u00eda de la Ciencia\\u201d, las posiciones de las distintas escuelas m\\u00e1s o menos convencionales. Como se ha podido observar los conceptos de ciencia, m\\u00e9todo cient\\u00edfico, progreso y otros \\u00edtems relacionados han ido relativiz\\u00e1ndose, en vista de que ninguna escuela precedente ha sido\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2007\\\/07\\\/08\\\/69567#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\"},\"datePublished\":\"2007-07-08T10:21:00+01:00\",\"dateModified\":\"2024-06-03T15:18:31+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#website\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/\",\"name\":\"Un Universo invisible bajo nuestros pies\",\"description\":\"Los suelos y la vida\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Relativismo Radical en la Filosof\u00eda de la Ciencia: El Anarquismo de Paul Feyerabend - Un Universo invisible bajo nuestros pies","description":"Hasta este post hemos venido narrando en nuestro \u201cCurso B\u00e1sico sobre filosof\u00eda y Sociolog\u00eda de la Ciencia\u201d, las posiciones de las distintas escuelas m\u00e1s o menos convencionales. Como se ha podido observar los conceptos de ciencia, m\u00e9todo cient\u00edfico, progreso y otros \u00edtems relacionados han ido relativiz\u00e1ndose, en vista de que ninguna escuela precedente ha sido","canonical_url":"https:\/\/www.madrimasd.org\/blogs\/universo\/2007\/07\/08\/69567","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2007\/07\/08\/69567#blogposting","name":"Relativismo Radical en la Filosof\u00eda de la Ciencia: El Anarquismo de Paul Feyerabend - Un Universo invisible bajo nuestros pies","headline":"Relativismo Radical en la Filosof\u00eda de la Ciencia: El Anarquismo de Paul Feyerabend","author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author"},"publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#organization"},"image":{"@type":"ImageObject","url":"\/blogs\/universo\/wp-content\/blogs.dir\/42\/files\/159\/o_Feyerabend.JPG","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2007\/07\/08\/69567\/#articleImage"},"datePublished":"2007-07-08T10:21:00+01:00","dateModified":"2024-06-03T15:18:31+01:00","inLanguage":"es-ES","commentCount":7,"mainEntityOfPage":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2007\/07\/08\/69567#webpage"},"isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2007\/07\/08\/69567#webpage"},"articleSection":"Curso B\u00e1sico Sobre Filosof\u00eda y Sociolog\u00eda de la Ciencia, Filosof\u00eda, Historia y Sociolog\u00eda de la Edafolog\u00eda, La Crisis de la Edafolog\u00eda"},{"@type":"BreadcrumbList","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2007\/07\/08\/69567#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo#listItem","position":1,"name":"Home","item":"https:\/\/www.madrimasd.org\/blogs\/universo","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/la-crisis-de-la-edafologia#listItem","name":"La Crisis de la Edafolog\u00eda"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/la-crisis-de-la-edafologia#listItem","position":2,"name":"La Crisis de la Edafolog\u00eda","item":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/la-crisis-de-la-edafologia","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2007\/07\/08\/69567#listItem","name":"Relativismo Radical en la Filosof\u00eda de la Ciencia: El Anarquismo de Paul Feyerabend"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2007\/07\/08\/69567#listItem","position":3,"name":"Relativismo Radical en la Filosof\u00eda de la Ciencia: El Anarquismo de Paul Feyerabend","previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/la-crisis-de-la-edafologia#listItem","name":"La Crisis de la Edafolog\u00eda"}}]},{"@type":"Organization","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#organization","name":"Un Universo invisible bajo nuestros pies","description":"Los suelos y la vida","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/","logo":{"@type":"ImageObject","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2007\/07\/08\/69567\/#organizationLogo","width":217,"height":72},"image":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2007\/07\/08\/69567\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/juan.j.marti.14"]},{"@type":"Person","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo","name":"Juan Jos\u00e9 Ib\u00e1\u00f1ez","image":{"@type":"ImageObject","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2007\/07\/08\/69567#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/387f3a100385573d8f42ce2a3211fd1c?s=96&d=mm&r=g","width":96,"height":96,"caption":"Juan Jos\u00e9 Ib\u00e1\u00f1ez"}},{"@type":"WebPage","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2007\/07\/08\/69567#webpage","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/2007\/07\/08\/69567","name":"Relativismo Radical en la Filosof\u00eda de la Ciencia: El Anarquismo de Paul Feyerabend - Un Universo invisible bajo nuestros pies","description":"Hasta este post hemos venido narrando en nuestro \u201cCurso B\u00e1sico sobre filosof\u00eda y Sociolog\u00eda de la Ciencia\u201d, las posiciones de las distintas escuelas m\u00e1s o menos convencionales. Como se ha podido observar los conceptos de ciencia, m\u00e9todo cient\u00edfico, progreso y otros \u00edtems relacionados han ido relativiz\u00e1ndose, en vista de que ninguna escuela precedente ha sido","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#website"},"breadcrumb":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2007\/07\/08\/69567#breadcrumblist"},"author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author"},"creator":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author"},"datePublished":"2007-07-08T10:21:00+01:00","dateModified":"2024-06-03T15:18:31+01:00"},{"@type":"WebSite","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#website","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/","name":"Un Universo invisible bajo nuestros pies","description":"Los suelos y la vida","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Un Universo invisible bajo nuestros pies - Los suelos y la vida","og:type":"article","og:title":"Relativismo Radical en la Filosof\u00eda de la Ciencia: El Anarquismo de Paul Feyerabend - Un Universo invisible bajo nuestros pies","og:description":"Hasta este post hemos venido narrando en nuestro \u201cCurso B\u00e1sico sobre filosof\u00eda y Sociolog\u00eda de la Ciencia\u201d, las posiciones de las distintas escuelas m\u00e1s o menos convencionales. Como se ha podido observar los conceptos de ciencia, m\u00e9todo cient\u00edfico, progreso y otros \u00edtems relacionados han ido relativiz\u00e1ndose, en vista de que ninguna escuela precedente ha sido","og:url":"https:\/\/www.madrimasd.org\/blogs\/universo\/2007\/07\/08\/69567","og:image":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png","og:image:secure_url":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png","article:published_time":"2007-07-08T10:21:00+00:00","article:modified_time":"2024-06-03T14:18:31+00:00","article:publisher":"https:\/\/www.facebook.com\/juan.j.marti.14","twitter:card":"summary","twitter:title":"Relativismo Radical en la Filosof\u00eda de la Ciencia: El Anarquismo de Paul Feyerabend - Un Universo invisible bajo nuestros pies","twitter:description":"Hasta este post hemos venido narrando en nuestro \u201cCurso B\u00e1sico sobre filosof\u00eda y Sociolog\u00eda de la Ciencia\u201d, las posiciones de las distintas escuelas m\u00e1s o menos convencionales. Como se ha podido observar los conceptos de ciencia, m\u00e9todo cient\u00edfico, progreso y otros \u00edtems relacionados han ido relativiz\u00e1ndose, en vista de que ninguna escuela precedente ha sido","twitter:image":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png"},"aioseo_meta_data":{"post_id":"69567","title":null,"description":null,"keywords":[],"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","tabs":null,"priority":0,"frequency":"default","local_seo":null,"created":"2022-06-03 14:26:36","updated":"2026-05-26 14:18:53","limit_modified_date":false,"ai":null,"breadcrumb_settings":null,"seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/la-crisis-de-la-edafologia\" title=\"La Crisis de la Edafolog\u00eda\">La Crisis de la Edafolog\u00eda<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tRelativismo Radical en la Filosof\u00eda de la Ciencia: El Anarquismo de Paul Feyerabend\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.madrimasd.org\/blogs\/universo"},{"label":"La Crisis de la Edafolog\u00eda","link":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/la-crisis-de-la-edafologia"},{"label":"Relativismo Radical en la Filosof\u00eda de la Ciencia: El Anarquismo de Paul Feyerabend","link":"https:\/\/www.madrimasd.org\/blogs\/universo\/2007\/07\/08\/69567"}],"_links":{"self":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts\/69567"}],"collection":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/comments?post=69567"}],"version-history":[{"count":5,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts\/69567\/revisions"}],"predecessor-version":[{"id":155583,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts\/69567\/revisions\/155583"}],"wp:attachment":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/media?parent=69567"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/categories?post=69567"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/tags?post=69567"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}