{"id":78269,"date":"2007-11-07T14:17:00","date_gmt":"2007-11-07T14:17:00","guid":{"rendered":"http:\/\/weblogs.madrimasd.org\/\/universo\/archive\/2007\/11\/07\/78269.aspx"},"modified":"2010-01-22T03:45:22","modified_gmt":"2010-01-22T02:45:22","slug":"los-errores-de-la-naturaleza-y-el-vocabulario-cientifico","status":"publish","type":"post","link":"https:\/\/www.madrimasd.org\/blogs\/universo\/2007\/11\/07\/78269","title":{"rendered":"Los Errores de la Naturaleza y el Vocabulario Cient\u00edfico"},"content":{"rendered":"<p><P class=MsoNormal style=\"MARGIN: 0cm 0cm 0pt; TEXT-ALIGN: justify\"><B style=\"mso-bidi-font-weight: normal\"><SPAN style=\"FONT-SIZE: 10pt; COLOR: #3366ff; FONT-FAMILY: 'Comic Sans MS'\">Se presume que el lenguaje de la ciencia es riguroso y objetivo, aunque<\/SPAN><\/B><SPAN style=\"FONT-SIZE: 10pt; FONT-FAMILY: 'Comic Sans MS'\"> actualmente muchos investigadores publicitan sus descubrimientos como si fueran lavadoras de \u00faltima generaci\u00f3n o perfumes en periodos navide\u00f1os. <B style=\"mso-bidi-font-weight: normal\"><SPAN style=\"COLOR: #3366ff\">Padecemos un mundo de merchandising<\/SPAN><\/B> y aqu\u00ed no se libra nadie. Sin embargo, con independencia de estas consideraciones, <B style=\"mso-bidi-font-weight: normal\"><SPAN style=\"COLOR: #3366ff\">existen ejemplos notables y gloriosos que<\/SPAN><\/B> muestran <B style=\"mso-bidi-font-weight: normal\"><SPAN style=\"COLOR: #3366ff\">como al encontrarse <\/SPAN><\/B>con alg\u00fan ente o proceso que no se ajusta a nuestros modelos conceptuales vigentes, patinamos ling\u00fc\u00edsticamente usando <B style=\"mso-bidi-font-weight: normal\"><SPAN style=\"COLOR: #3366ff\">antropocentrismos impropios de tal rigor<\/SPAN><\/B>. Tendemos a \u201c<B style=\"mso-bidi-font-weight: normal\"><SPAN style=\"COLOR: #3366ff\">acusar\u201d a la naturaleza de ser imperfecta cuando los \u00fanicos torpes somos nosotros<\/SPAN><\/B>. Veamos hoy dos casos palmarios. Nos referimos a los denominados <B style=\"mso-bidi-font-weight: normal\"><SPAN style=\"COLOR: #3366ff\">\u201chongos imperfectos\u201d (Fungi imperfecti) y al DNA basura<\/SPAN><\/B>. Mostraremos hasta que punto llega nuestra estupidez de manos de la arrogancia que propicia nuestra ignorancia. <B style=\"mso-bidi-font-weight: normal\"><SPAN style=\"COLOR: #3366ff\">\u00bfExisten Hongos imperfectos?, \u00bfla mayor parte de nuestro DNA es basura?<\/SPAN><\/B> Obviamente no. <\/SPAN><\/P> <P class=MsoNormal style=\"MARGIN: 0cm 0cm 0pt; TEXT-ALIGN: justify\"><SPAN style=\"FONT-SIZE: 10pt; FONT-FAMILY: 'Comic Sans MS'\"><o:p><\/o:p><\/SPAN>&nbsp;<\/P> <P class=MsoNormal style=\"MARGIN: 0cm 0cm 0pt\"><SPAN style=\"FONT-SIZE: 10pt; FONT-FAMILY: 'Comic Sans MS'\"><o:p>&nbsp;<IMG style=\"WIDTH: 185px; HEIGHT: 275px\" height=324 src=\"\/blogs\/universo\/wp-content\/blogs.dir\/42\/files\/163\/o_Galaxia%20de%20doble%20espiral.jpg\" width=274><IMG style=\"WIDTH: 172px; HEIGHT: 276px\" height=594 src=\"\/blogs\/universo\/wp-content\/blogs.dir\/42\/files\/163\/o_penicillium2.jpg\" width=608><\/o:p><\/SPAN><\/P> <P class=MsoNormal style=\"MARGIN: 0cm 0cm 0pt\"><SPAN style=\"FONT-SIZE: 10pt; FONT-FAMILY: 'Comic Sans MS'\"><o:p>&nbsp;<\/o:p><\/SPAN><\/P> <P class=MsoNormal style=\"MARGIN: 0cm 0cm 0pt\"><SPAN style=\"FONT-SIZE: 10pt; FONT-FAMILY: 'Comic Sans MS'\"><o:p>&nbsp;<\/o:p><\/SPAN><\/P> <P class=MsoNormal style=\"MARGIN: 0cm 0cm 0pt\"><SPAN style=\"FONT-SIZE: 8pt; FONT-FAMILY: 'Comic Sans MS'\"><A href=\"http:\/\/www.lagranepoca.com\/articles\/2007\/03\/15\/194.html\"><FONT color=#800080>de DNA Basura<\/FONT><\/A>, <SPAN style=\"FONT-SIZE: 8pt; COLOR: blue; FONT-FAMILY: 'Comic Sans MS'; mso-ansi-language: ES; mso-bidi-font-family: 'Times New Roman'; mso-fareast-font-family: 'Times New Roman'; mso-fareast-language: ES; mso-bidi-language: AR-SA\">Galaxia en doble h\u00e9lice y (\u2026) y una <\/SPAN>&nbsp;<\/SPAN><SPAN lang=EN-GB style=\"FONT-SIZE: 8pt; FONT-FAMILY: 'Comic Sans MS'; mso-ansi-language: EN-GB\"><A href=\"http:\/\/www.telmeds.org\/AVIM\/Amico\/hongos_contaminantes\/images\/penicillium\/penicillium2.jpg\"><SPAN lang=ES style=\"mso-ansi-language: ES\"><FONT color=#800080>foto de un \u201cimperfecto <I style=\"mso-bidi-font-style: normal\">Penicillum<\/I>\u201d<\/FONT><\/SPAN><\/A><\/SPAN><SPAN style=\"FONT-SIZE: 8pt; FONT-FAMILY: 'Comic Sans MS'\"><o:p><\/o:p><\/SPAN><\/P><!--more--><P class=MsoNormal style=\"MARGIN: 0cm 0cm 0pt\"><SPAN style=\"FONT-SIZE: 10pt; FONT-FAMILY: 'Comic Sans MS'\"><o:p>&nbsp;<\/o:p><\/SPAN><\/P> <P class=MsoNormal style=\"MARGIN: 0cm 0cm 0pt; TEXT-ALIGN: justify\"><SPAN style=\"FONT-SIZE: 10pt; FONT-FAMILY: 'Comic Sans MS'\">Ya en mis tiernos a\u00f1os universitarios me top\u00e9 con las clasificaciones bot\u00e1nicas que mentaban la existencia de \u201c<B style=\"mso-bidi-font-weight: normal\"><SPAN style=\"COLOR: #3366ff\">Hongos imperfectos<\/SPAN><\/B>\u201d, o para ser m\u00e1s rigurosos: \u201c<B style=\"mso-bidi-font-weight: normal\"><SPAN style=\"COLOR: #3366ff\">Fungi imperfecti<\/SPAN><\/B>\u201d Veamos que se nos dice al respecto en el siguiente enlace que aborda la <A href=\"http:\/\/www.educa.aragob.es\/iescarin\/depart\/biogeo\/varios\/BiologiaCurtis\/Seccion%205\/5%20-%20Capitulo%2029.htm\"><FONT color=#800080>Clasificaci\u00f3n<\/FONT><\/A> de estos organismos. Recordemos que, junto con las bacterias, se encargan en gran medida del reciclado de los nutrientes en el suelo<o:p><\/o:p><\/SPAN><\/P> <P class=MsoNormal style=\"MARGIN: 0cm 0cm 0pt\"><SPAN style=\"FONT-SIZE: 10pt; FONT-FAMILY: 'Comic Sans MS'\"><o:p>&nbsp;<\/o:p><\/SPAN><\/P> <P class=MsoNormal style=\"MARGIN: 0cm 0cm 0pt\"><SPAN style=\"FONT-SIZE: 10pt; FONT-FAMILY: 'Comic Sans MS'\"><o:p>&nbsp;<IMG src=\"\/blogs\/universo\/wp-content\/blogs.dir\/42\/files\/163\/o_Filogenia%20de%20Hongos.jpg\"><\/o:p><\/SPAN><\/P> <P class=MsoNormal style=\"MARGIN: 0cm 0cm 0pt\"><SPAN style=\"FONT-SIZE: 10pt; FONT-FAMILY: 'Comic Sans MS'\"><o:p>&nbsp;<\/o:p><\/SPAN><\/P> <P class=MsoNormal style=\"MARGIN: 0cm 0cm 0pt\"><SPAN style=\"FONT-SIZE: 8pt; FONT-FAMILY: 'Comic Sans MS'\"><A href=\"http:\/\/www.educa.aragob.es\/iescarin\/depart\/biogeo\/varios\/BiologiaCurtis\/Seccion%205\/5%20-%20Capitulo%2029.htm\"><FONT color=#800080>Filogenia de los hongos<\/FONT><\/A><o:p><\/o:p><\/SPAN><\/P> <P class=MsoNormal style=\"MARGIN: 0cm 0cm 0pt\"><SPAN style=\"FONT-SIZE: 10pt; FONT-FAMILY: 'Comic Sans MS'\"><o:p>&nbsp;<\/o:p><\/SPAN><\/P> <P class=MsoNormal style=\"MARGIN: 0cm 0cm 0pt; TEXT-ALIGN: justify\"><I style=\"mso-bidi-font-style: normal\"><SPAN style=\"FONT-SIZE: 9pt; FONT-FAMILY: 'Arial Narrow'\">Los miembros del reino Fungi (Hongos) se clasifican generalmente en cuatro grupos principales o phyla: Chytridiomycota -los quitridiomicetes-, Zygomycota -los zigomicetes-, Ascomycota -los ascomicetes- y Basidiomycota -los basidiomicetes-. Un grupo adicional, los Deuteromycota -deuteromycetes u Hongos Imperfectos (<A href=\"http:\/\/www.pollenuk.co.uk\/aero\/FUNGI\/types.htm\"><FONT color=#800080>Fungi Imperfecti<\/FONT><\/A>)-, <B style=\"mso-bidi-font-weight: normal\"><SPAN style=\"COLOR: #3366ff\">es un grupo que incluye hongos cuya reproducci\u00f3n sexual generalmente se desconoce, ya sea porque se ha perdido en el curso de la evoluci\u00f3n o porque no ha sido observada. Este grupo se considera arbitrario ya que agrupa a organismos por tener en com\u00fan una caracter\u00edstica que est\u00e1 ausente<\/SPAN><\/B>. Este criterio no responde a una relaci\u00f3n filogen\u00e9tica.<o:p><\/o:p><\/SPAN><\/I><\/P> <P class=MsoNormal style=\"MARGIN: 0cm 0cm 0pt; TEXT-ALIGN: justify\"><I style=\"mso-bidi-font-style: normal\"><SPAN style=\"FONT-SIZE: 9pt; FONT-FAMILY: 'Arial Narrow'\"><o:p>&nbsp;<\/o:p><\/SPAN><\/I><\/P> <P class=MsoNormal style=\"MARGIN: 0cm 0cm 0pt; TEXT-ALIGN: justify\"><I style=\"mso-bidi-font-style: normal\"><SPAN style=\"FONT-SIZE: 9pt; FONT-FAMILY: 'Arial Narrow'\">Hace un tiempo, se le hab\u00eda dado a este grupo la categor\u00eda de Divisi\u00f3n pero, se ha dejado de utilizar ya que en la actualidad se tiende a basar la clasificaci\u00f3n en las relaciones filogen\u00e9ticas entre las especies. Aunque se han reagrupado las especies de deuteromicetes dentro de los ascomicetes o Basidiomicetes asexuales, <B style=\"mso-bidi-font-weight: normal\"><SPAN style=\"COLOR: #3366ff\">el t\u00e9rmino \u00abhongos imperfectos\u00bb es ampliamente utilizado<\/SPAN><\/B>. <o:p><\/o:p><\/SPAN><\/I><\/P> <P class=MsoNormal style=\"MARGIN: 0cm 0cm 0pt\"><SPAN style=\"FONT-SIZE: 10pt; FONT-FAMILY: 'Comic Sans MS'\"><o:p>&nbsp;<\/o:p><\/SPAN><\/P> <P class=MsoNormal style=\"MARGIN: 0cm 0cm 0pt\"><SPAN style=\"FONT-SIZE: 10pt; FONT-FAMILY: 'Comic Sans MS'\">Para los amantes del suahili, Veamos tambi\u00e9n <A href=\"http:\/\/www.pollenuk.co.uk\/aero\/FUNGI\/types.htm\"><FONT color=#800080>en esta p\u00e1gina Web<\/FONT><\/A> que nos comentan de estos dichosos hongos tan imperfectos. <o:p><\/o:p><\/SPAN><\/P> <P class=MsoNormal style=\"MARGIN: 0cm 0cm 0pt\"><SPAN style=\"FONT-SIZE: 10pt; FONT-FAMILY: 'Comic Sans MS'\"><o:p>&nbsp;<\/o:p><\/SPAN><\/P> <P class=MsoNormal style=\"MARGIN: 0cm 0cm 0pt\"><SPAN style=\"FONT-SIZE: 10pt; FONT-FAMILY: 'Comic Sans MS'\"><o:p>&nbsp;<IMG src=\"\/blogs\/universo\/wp-content\/blogs.dir\/42\/files\/163\/o_Relaciones%20evol%20seres%20vivos.jpg\"><\/o:p><\/SPAN><\/P> <P class=MsoNormal style=\"MARGIN: 0cm 0cm 0pt\"><SPAN style=\"FONT-SIZE: 10pt; FONT-FAMILY: 'Comic Sans MS'\"><o:p>&nbsp;<\/o:p><\/SPAN><\/P> <P class=MsoNormal style=\"MARGIN: 0cm 0cm 0pt\"><SPAN style=\"FONT-SIZE: 8pt; FONT-FAMILY: 'Comic Sans MS'\"><A href=\"http:\/\/www.educa.aragob.es\/iescarin\/depart\/biogeo\/varios\/BiologiaCurtis\/Seccion%205\/5%20-%20Capitulo%2029.htm\"><FONT color=#800080>Relaciones evolutivas de los seres vivos<\/FONT><\/A><o:p><\/o:p><\/SPAN><\/P> <P class=MsoNormal style=\"MARGIN: 0cm 0cm 0pt\"><SPAN style=\"FONT-SIZE: 10pt; FONT-FAMILY: 'Comic Sans MS'\"><o:p>&nbsp;<\/o:p><\/SPAN><\/P> <P class=MsoNormal style=\"MARGIN: 0cm 0cm 0pt; TEXT-ALIGN: justify\"><B style=\"mso-bidi-font-weight: normal\"><I style=\"mso-bidi-font-style: normal\"><SPAN lang=EN-GB style=\"FONT-SIZE: 9pt; COLOR: #3366ff; FONT-FAMILY: 'Arial Narrow'; mso-ansi-language: EN-GB\">The form-division Fungi imperfecti or Deuteromycota is an artificial category. Members of this group were originally combined into a single group because they apparently lacked a sexual stage<\/SPAN><\/I><\/B><I style=\"mso-bidi-font-style: normal\"><SPAN lang=EN-GB style=\"FONT-SIZE: 9pt; FONT-FAMILY: 'Arial Narrow'; mso-ansi-language: EN-GB\">. <B style=\"mso-bidi-font-weight: normal\"><SPAN style=\"COLOR: #3366ff\">However, it is generally believed that the majority of fungi imperfecti represent the nonsexual stages (anamorphs) of sexually reproducing fungi that belong to the Ascomycetes or Basidiomycetes<\/SPAN><\/B>, with the majority from the former, (Moore-Landecker, 1996). Fungi imperfecti are divided into form-classes based upon morphological similarities (\u2026).<B style=\"mso-bidi-font-weight: normal\"><SPAN style=\"COLOR: #3366ff\">The effect of this is that unrelated fungi have been &#8216;lumped&#8217; together while possibly related fungi have been classified into different form-classes because<\/SPAN><\/B> of differences in the visual appearance of the spores. For example (\u2026). The difficulty is that for the majority of fungi placed within the Fungi imperfecti form-division only the asexual anamorph stage has been positively identified. <o:p><\/o:p><\/SPAN><\/I><\/P> <P class=MsoNormal style=\"MARGIN: 0cm 0cm 0pt; TEXT-ALIGN: justify\"><I style=\"mso-bidi-font-style: normal\"><SPAN lang=EN-GB style=\"FONT-SIZE: 9pt; FONT-FAMILY: 'Arial Narrow'; mso-ansi-language: EN-GB\"><o:p>&nbsp;<\/o:p><\/SPAN><\/I><\/P> <P class=MsoNormal style=\"MARGIN: 0cm 0cm 0pt; TEXT-ALIGN: justify\"><I style=\"mso-bidi-font-style: normal\"><SPAN lang=EN-GB style=\"FONT-SIZE: 9pt; FONT-FAMILY: 'Arial Narrow'; mso-ansi-language: EN-GB\">An important fungi imperfecti group is the form-class hyphomycetes. Hyphomycetes are those fungi imperfecti which form a mycelium but lack a sporocarp. The spores are borne on conidiophores. Hyphomycetes are also called moulds and a culture of hyphomycete can be recognized by the powdery or fluffy appearance of the colony. Examples of hyphomycetes include <B style=\"mso-bidi-font-weight: normal\"><SPAN style=\"COLOR: #3366ff\">Penicillium<\/SPAN><\/B>, Epicoccum and <B style=\"mso-bidi-font-weight: normal\"><SPAN style=\"COLOR: #3366ff\">Aspergillus<\/SPAN><\/B>.<o:p><\/o:p><\/SPAN><\/I><\/P> <P class=MsoNormal style=\"MARGIN: 0cm 0cm 0pt; TEXT-ALIGN: justify\"><I style=\"mso-bidi-font-style: normal\"><SPAN lang=EN-GB style=\"FONT-SIZE: 9pt; FONT-FAMILY: 'Arial Narrow'; mso-ansi-language: EN-GB\"><SPAN style=\"mso-spacerun: yes\">&nbsp;<\/SPAN><o:p><\/o:p><\/SPAN><\/I><\/P> <P class=MsoNormal style=\"MARGIN: 0cm 0cm 0pt; TEXT-ALIGN: justify\"><I style=\"mso-bidi-font-style: normal\"><SPAN lang=EN-GB style=\"FONT-SIZE: 9pt; FONT-FAMILY: 'Arial Narrow'; mso-ansi-language: EN-GB\">Many of the spores of the Fungi imperfecti have morphologically distinct features so that the spores from this group are some of the most easily identified. Many are also easily cultured so that more research has been conducted upon this group of fungi than for many other. Alternaria, Cladosporium, Curvularia, Drechslera (including Helminthosporium), Epicoccum, <B style=\"mso-bidi-font-weight: normal\"><SPAN style=\"COLOR: #3366ff\">Fusarium<\/SPAN><\/B>, Nigrospora and Stemphylium were listed by Kendrick (1990) as the &#8216;Big Eight&#8217; because of <B style=\"mso-bidi-font-weight: normal\"><SPAN style=\"COLOR: #3366ff\">their allergenicity and frequency in the air. In addition, Aspergillus and Penicillium are abundant Fungi Imperfecti<\/SPAN><\/B>. <o:p><\/o:p><\/SPAN><\/I><\/P> <P class=MsoNormal style=\"MARGIN: 0cm 0cm 0pt; TEXT-ALIGN: justify\"><I style=\"mso-bidi-font-style: normal\"><SPAN lang=EN-GB style=\"FONT-SIZE: 10pt; FONT-FAMILY: 'Arial Narrow'; mso-ansi-language: EN-GB\"><o:p>&nbsp;<\/o:p><\/SPAN><\/I><\/P> <P class=MsoNormal style=\"MARGIN: 0cm 0cm 0pt\"><SPAN lang=EN-GB style=\"FONT-SIZE: 10pt; FONT-FAMILY: 'Comic Sans MS'; mso-ansi-language: EN-GB\"><o:p>&nbsp;<IMG style=\"WIDTH: 217px; HEIGHT: 253px\" height=162 src=\"\/blogs\/universo\/wp-content\/blogs.dir\/42\/files\/163\/o_aspergillus.jpg\" width=312><IMG style=\"WIDTH: 209px; HEIGHT: 253px\" height=253 src=\"\/blogs\/universo\/wp-content\/blogs.dir\/42\/files\/163\/o_penicillium.jpg\" width=279><\/o:p><\/SPAN><\/P> <P class=MsoNormal style=\"MARGIN: 0cm 0cm 0pt\"><SPAN lang=EN-GB style=\"FONT-SIZE: 10pt; FONT-FAMILY: 'Comic Sans MS'; mso-ansi-language: EN-GB\"><o:p>&nbsp;<\/o:p><\/SPAN><\/P> <P class=MsoNormal style=\"MARGIN: 0cm 0cm 0pt\"><SPAN lang=EN-GB style=\"FONT-SIZE: 8pt; FONT-FAMILY: 'Comic Sans MS'; mso-ansi-language: EN-GB\"><A href=\"http:\/\/www.qfb.umich.mx\/hongos.htm\"><SPAN lang=ES style=\"mso-ansi-language: ES\"><FONT color=#800080>Fotos de Aspergillus y Penicillum<\/FONT><\/SPAN><\/A><\/SPAN><SPAN style=\"FONT-SIZE: 8pt; FONT-FAMILY: 'Comic Sans MS'\"><o:p><\/o:p><\/SPAN><\/P> <P class=MsoNormal style=\"MARGIN: 0cm 0cm 0pt\"><SPAN style=\"FONT-SIZE: 10pt; FONT-FAMILY: 'Comic Sans MS'\"><o:p>&nbsp;<\/o:p><\/SPAN><\/P> <P class=MsoNormal style=\"MARGIN: 0cm 0cm 0pt; TEXT-ALIGN: justify\"><SPAN style=\"FONT-SIZE: 10pt; FONT-FAMILY: 'Comic Sans MS'\">Resumiendo, son imperfectos porque no se reproducen sexualmente o porque \u201cno se han identificado\u201d sus estados sexuales. <B style=\"mso-bidi-font-weight: normal\"><SPAN style=\"COLOR: #3366ff\">\u00bfSon por eso imperfectos?<\/SPAN><\/B> Tambi\u00e9n pod\u00edan haberles denominado \u201c<B style=\"mso-bidi-font-weight: normal\"><SPAN style=\"COLOR: #3366ff\">Fungi castrati<\/SPAN><\/B>\u201d o cualquier otro barbarismo que se les antojara. Gracias a sus imperfecciones se salvaron millones de vidas en su momento, es decir tras el descubrimiento de la <B style=\"mso-bidi-font-weight: normal\"><SPAN style=\"COLOR: #3366ff\">Penicilina<\/SPAN><\/B>., si bien otros son m\u00e1s molestos para el ser humano, ya sea por ser alerg\u00f3genos, causar intoxicaciones alimentarias, enfermedades respiratorias, algunas de las cuales son de tipo hospitalario (nosocomiales), etc. Creo que con lo dicho basta para entender la impresentable imperfecci\u00f3n de estos malditos organismos<B style=\"mso-bidi-font-weight: normal\"><SPAN style=\"COLOR: #3366ff\">. Como no podemos clasificarlos (\u2026) ellos son los culpables, no nuestra falta de conocimientos<\/SPAN><\/B>. \u00a1Vaya por D\u00edos! Pero sigamos con nuestro idolatrado <B style=\"mso-bidi-font-weight: normal\"><SPAN style=\"COLOR: #3366ff\">genoma humano<\/SPAN><\/B>. <o:p><\/o:p><\/SPAN><\/P> <P class=MsoNormal style=\"MARGIN: 0cm 0cm 0pt; TEXT-ALIGN: justify\"><SPAN style=\"FONT-SIZE: 10pt; FONT-FAMILY: 'Comic Sans MS'\"><o:p>&nbsp;<\/o:p><\/SPAN><\/P> <P class=MsoNormal style=\"MARGIN: 0cm 0cm 0pt; TEXT-ALIGN: justify\"><B style=\"mso-bidi-font-weight: normal\"><SPAN style=\"FONT-SIZE: 10pt; COLOR: #3366ff; FONT-FAMILY: 'Comic Sans MS'\">Durante mucho tiempo los expertos proclamaron que el 95% del genoma humano era pura basura<\/SPAN><\/B><SPAN style=\"FONT-SIZE: 10pt; FONT-FAMILY: 'Comic Sans MS'\">. La verdad es que jam\u00e1s entend\u00ed <B style=\"mso-bidi-font-weight: normal\"><SPAN style=\"COLOR: #3366ff\">tal estupidez<\/SPAN><\/B>. La naturaleza puede que sea un poco <B style=\"mso-bidi-font-weight: normal\"><SPAN style=\"COLOR: #3366ff\">barroca<\/SPAN><\/B>, como dec\u00eda nuestro a\u00f1orado <B style=\"mso-bidi-font-weight: normal\"><SPAN style=\"COLOR: #3366ff\">Ram\u00f3n Margalef<\/SPAN><\/B>. Pero una cuesti\u00f3n es una ligera \u201cincompostura\u201d y otra bien distinta que, reiteremos, <B style=\"mso-bidi-font-weight: normal\"><SPAN style=\"COLOR: #3366ff\">el 95% del genoma no sirviera \u201cpa na<\/SPAN><\/B>\u201d, Como tal cifra resulta ser estad\u00edsticamente \u201csignificativa\u201d, con los c\u00e1nones actuales deber\u00edamos decir <B style=\"mso-bidi-font-weight: normal\"><SPAN style=\"COLOR: #3366ff\">que el material gen\u00e9tico humano es pura basura al 95%<\/SPAN><\/B>. \u00a1Ya se, ya se!, esto es una genuina y muy \u201cimperfecta\u201d demagogia, (m\u00e1s bien un abuso del lenguaje y un atentado contra el c\u00e1lculo de probabilidades), pero no lo es menos el vocablo que se utilizaba para <B style=\"mso-bidi-font-weight: normal\"><SPAN style=\"COLOR: #3366ff\">aquella parte del DNA cuyas funciones no se comprend\u00edan en un momento dado de la historia<\/SPAN><\/B> de una disciplina.<SPAN style=\"mso-spacerun: yes\">&nbsp;&nbsp;&nbsp; <\/SPAN><SPAN style=\"mso-spacerun: yes\">&nbsp;<\/SPAN><SPAN style=\"mso-spacerun: yes\">&nbsp;<\/SPAN><o:p><\/o:p><\/SPAN><\/P> <P class=MsoNormal style=\"MARGIN: 0cm 0cm 0pt\"><SPAN style=\"FONT-SIZE: 10pt; FONT-FAMILY: 'Comic Sans MS'\"><o:p>&nbsp;<\/o:p><\/SPAN><\/P> <P class=MsoNormal style=\"MARGIN: 0cm 0cm 0pt\"><SPAN style=\"FONT-SIZE: 10pt; FONT-FAMILY: 'Comic Sans MS'\"><o:p><IMG style=\"WIDTH: 405px; HEIGHT: 235px\" height=201 src=\"\/blogs\/universo\/wp-content\/blogs.dir\/42\/files\/163\/o_adn_basura.jpg\" width=333>&nbsp;<\/o:p><\/SPAN><\/P> <P class=MsoNormal style=\"MARGIN: 0cm 0cm 0pt\"><SPAN style=\"FONT-SIZE: 10pt; FONT-FAMILY: 'Comic Sans MS'\"><o:p><\/o:p><\/SPAN>&nbsp;<\/P> <P class=MsoNormal style=\"MARGIN: 0cm 0cm 0pt\"><SPAN lang=EN-GB style=\"FONT-SIZE: 8pt; FONT-FAMILY: 'Comic Sans MS'; mso-ansi-language: EN-GB\"><A href=\"http:\/\/neofronteras.com\/?p=862\"><SPAN lang=ES style=\"mso-ansi-language: ES\"><FONT color=#800080>DNA Basura<\/FONT><\/SPAN><\/A><\/SPAN><SPAN style=\"FONT-SIZE: 8pt; FONT-FAMILY: 'Comic Sans MS'\"><o:p><\/o:p><\/SPAN><\/P> <P class=MsoNormal style=\"MARGIN: 0cm 0cm 0pt\"><SPAN style=\"FONT-SIZE: 10pt; FONT-FAMILY: 'Comic Sans MS'\"><o:p>&nbsp;<\/o:p><\/SPAN><\/P> <P class=MsoNormal style=\"MARGIN: 0cm 0cm 0pt\"><SPAN style=\"FONT-SIZE: 10pt; FONT-FAMILY: 'Comic Sans MS'\">Y como dijo en una entrevista <B style=\"mso-bidi-font-weight: normal\"><SPAN style=\"COLOR: #3366ff\">Manuel Perucho<\/SPAN><\/B> (pinchar <A href=\"http:\/\/www.biomeds.net\/biomedia\/R12\/entrevista01.htm\"><FONT color=#800080>aqu\u00ed<\/FONT><\/A>):<o:p><\/o:p><\/SPAN><\/P> <P class=MsoNormal style=\"MARGIN: 0cm 0cm 0pt\"><SPAN style=\"FONT-SIZE: 10pt; FONT-FAMILY: 'Comic Sans MS'\"><o:p>&nbsp;<\/o:p><\/SPAN><\/P> <P class=MsoNormal style=\"MARGIN: 0cm 0cm 0pt; TEXT-ALIGN: justify\"><I style=\"mso-bidi-font-style: normal\"><SPAN style=\"FONT-SIZE: 9pt; FONT-FAMILY: 'Arial Narrow'\">Pregunta: Estas dotaciones, entonces, est\u00e1n dentro de los genes, <B style=\"mso-bidi-font-weight: normal\"><SPAN style=\"COLOR: #3366ff\">\u00bfno pertenecen al llamado DNA \u201cbasura\u201d?<\/SPAN><\/B><o:p><\/o:p><\/SPAN><\/I><\/P> <P class=MsoNormal style=\"MARGIN: 0cm 0cm 0pt; TEXT-ALIGN: justify\"><I style=\"mso-bidi-font-style: normal\"><SPAN style=\"FONT-SIZE: 9pt; FONT-FAMILY: 'Arial Narrow'\"><o:p>&nbsp;<\/o:p><\/SPAN><\/I><\/P> <P class=MsoNormal style=\"MARGIN: 0cm 0cm 0pt; TEXT-ALIGN: justify\"><I style=\"mso-bidi-font-style: normal\"><SPAN style=\"FONT-SIZE: 9pt; FONT-FAMILY: 'Arial Narrow'\">Respuesta: <B style=\"mso-bidi-font-weight: normal\"><SPAN style=\"COLOR: #3366ff\">El genoma est\u00e1 formado por los genes y el material que queda entre medio de los genes. Lo que existe entre medio de los genes puede ser DNA basura, o no<\/SPAN><\/B>, puede tratarse tambi\u00e9n de <B style=\"mso-bidi-font-weight: normal\"><SPAN style=\"COLOR: #3366ff\">los elementos que controlan y regulan la expresi\u00f3n de los genes. Por tanto no son tan \u201cbasura\u201d.<\/SPAN><\/B> Las secuencias repetitivas que hemos descrito est\u00e1n situadas en la regi\u00f3n codificante. De todos modos, hablar del gen es casi un problema filos\u00f3fico&#8230; <B style=\"mso-bidi-font-weight: normal\"><SPAN style=\"COLOR: #3366ff\">\u00bfqu\u00e9 es el gen?<\/SPAN><\/B> Si tienes un gen que puede medir 100 kilobases, pero el mensajero mide 1000 pares de bases&#8230; todo lo que no se traduce de DNA a RNA mensajero es basura, pero, al mismo tiempo forma parte del gen. <B style=\"mso-bidi-font-weight: normal\"><SPAN style=\"COLOR: #3366ff\">No se puede obviar que regulan el gen. Estas secuencias tambi\u00e9n pueden contribuir a<\/SPAN><\/B> que el gen se exprese un poquito m\u00e1s o menos, y, en consecuencia, que aparezca o no la enfermedad<B style=\"mso-bidi-font-weight: normal\">. <SPAN style=\"COLOR: #3366ff\">Pueden contribuir a<\/SPAN><\/B> <B style=\"mso-bidi-font-weight: normal\"><SPAN style=\"COLOR: #3366ff\">hacer que ciertas personas de la poblaci\u00f3n sean m\u00e1s resistentes al c\u00e1ncer<\/SPAN><\/B>&#8230; Al final se sabr\u00e1 que el componente hereditario es m\u00e1s importante, de nuevo, no como una condena, sino como una disposici\u00f3n, una susceptibilidad.(\u2026) Entrev\u00e9s realizada por <SPAN style=\"mso-spacerun: yes\">&nbsp;<\/SPAN><B style=\"mso-bidi-font-weight: normal\"><SPAN style=\"COLOR: #3366ff\">Cristina Junyent<\/SPAN><\/B> doctora en biolog\u00eda<o:p><\/o:p><\/SPAN><\/I><\/P> <P class=MsoNormal style=\"MARGIN: 0cm 0cm 0pt\"><SPAN style=\"FONT-SIZE: 10pt; FONT-FAMILY: 'Comic Sans MS'\"><o:p>&nbsp;<\/o:p><\/SPAN><\/P> <P class=MsoNormal style=\"MARGIN: 0cm 0cm 0pt\"><SPAN style=\"FONT-SIZE: 10pt; FONT-FAMILY: 'Comic Sans MS'\"><o:p>&nbsp;<IMG src=\"\/blogs\/universo\/wp-content\/blogs.dir\/42\/files\/163\/o_DNA%20Basura.jpg\"><\/o:p><\/SPAN><\/P> <P class=MsoNormal style=\"MARGIN: 0cm 0cm 0pt\"><SPAN style=\"FONT-SIZE: 10pt; FONT-FAMILY: 'Comic Sans MS'\"><o:p>&nbsp;<\/o:p><\/SPAN><\/P> <P class=MsoNormal style=\"MARGIN: 0cm 0cm 0pt\"><SPAN lang=EN-GB style=\"FONT-SIZE: 8pt; FONT-FAMILY: 'Comic Sans MS'; mso-ansi-language: EN-GB\"><A href=\"http:\/\/www.creces.cl\/new\/index.asp?imat=%20%20%3e%20%207&amp;tc=3&amp;nc=5&amp;art=1827\"><SPAN lang=ES style=\"mso-ansi-language: ES\">DNA \u00bfDivino o Basura?<\/SPAN><\/A><\/SPAN><SPAN style=\"FONT-SIZE: 8pt; FONT-FAMILY: 'Comic Sans MS'\"><o:p><\/o:p><\/SPAN><\/P> <P class=MsoNormal style=\"MARGIN: 0cm 0cm 0pt\"><SPAN style=\"FONT-SIZE: 10pt; FONT-FAMILY: 'Comic Sans MS'\"><o:p>&nbsp;<\/o:p><\/SPAN><\/P> <P class=MsoNormal style=\"MARGIN: 0cm 0cm 0pt; TEXT-ALIGN: justify\"><SPAN style=\"FONT-SIZE: 10pt; FONT-FAMILY: 'Comic Sans MS'\">Curiosamente, <B style=\"mso-bidi-font-weight: normal\"><SPAN style=\"COLOR: #3366ff\">ambos ejemplos proceden del \u00e1mbito de la biolog\u00eda<\/SPAN><\/B>. \u00bfSeremos los bi\u00f3logos, que tanto presumimos de ser los \u201creyes del mambo cient\u00edfico\u201d (\u201cdivinos\u201d), los \u00fanicos memos?: \u201c<B style=\"mso-bidi-font-weight: normal\"><SPAN style=\"COLOR: #3366ff\">Dime de que presumes y te dir\u00e9 de que careces<\/SPAN><\/B>\u201d. Por favor, citarme alg\u00fan otro ejemplo de otra disciplina, Seguro que los hay, y muchos. <o:p><\/o:p><\/SPAN><\/P> <P class=MsoNormal style=\"MARGIN: 0cm 0cm 0pt; TEXT-ALIGN: justify\"><SPAN style=\"FONT-SIZE: 10pt; FONT-FAMILY: 'Comic Sans MS'\"><o:p>&nbsp;<\/o:p><\/SPAN><\/P> <P class=MsoNormal style=\"MARGIN: 0cm 0cm 0pt; TEXT-ALIGN: justify\"><SPAN style=\"FONT-SIZE: 10pt; FONT-FAMILY: 'Comic Sans MS'\">La verdad es que conozco varios pertenecientes a los <B style=\"mso-bidi-font-weight: normal\"><SPAN style=\"COLOR: #3366ff\">h\u00e9roes actuales de la f\u00edsica<\/SPAN><\/B>. Sin embargo, me quedar\u00e9 con <B style=\"mso-bidi-font-weight: normal\"><SPAN style=\"COLOR: #3366ff\">una an\u00e9cdota<\/SPAN><\/B> <B style=\"mso-bidi-font-weight: normal\"><SPAN style=\"COLOR: #3366ff\">personal<\/SPAN><\/B> que me ocurri\u00f3 con <B style=\"mso-bidi-font-weight: normal\"><SPAN style=\"COLOR: #3366ff\">el Premio N\u00f3bel<\/SPAN><\/B> <B style=\"mso-bidi-font-weight: normal\"><SPAN style=\"COLOR: #3366ff\">Ilya Prigogine<\/SPAN><\/B>. Un mortal raramente disfruta de la posibilidad de rega\u00f1ar a un bar\u00f3n de la ciencia (este s\u00ed era un gran investigador, que quede claro) y menos a\u00fan que el aludido se disculpe ante ti en p\u00fablico, en lugar de solicitar que me echaran a patadas del aula.<o:p><\/o:p><\/SPAN><\/P> <P class=MsoNormal style=\"MARGIN: 0cm 0cm 0pt; TEXT-ALIGN: justify\"><SPAN style=\"FONT-SIZE: 10pt; FONT-FAMILY: 'Comic Sans MS'\"><o:p>&nbsp;<\/o:p><\/SPAN><\/P> <P class=MsoNormal style=\"MARGIN: 0cm 0cm 0pt; TEXT-ALIGN: justify\"><SPAN style=\"FONT-SIZE: 10pt; FONT-FAMILY: 'Comic Sans MS'\">Se trataba de un <B style=\"mso-bidi-font-weight: normal\"><SPAN style=\"COLOR: #3366ff\">curso de verano de la UCM en el Escorial<\/SPAN><\/B> (a finales de los a\u00f1os 80, si no recuerdo mal). <B style=\"mso-bidi-font-weight: normal\"><SPAN style=\"COLOR: #3366ff\">Lo dirig\u00eda el propio Ilya<\/SPAN><\/B>, que hab\u00eda tra\u00eddo parte de su equipo de Bruselas y otra parte de EE.UU. Pues bien, Ilya <B style=\"mso-bidi-font-weight: normal\"><SPAN style=\"COLOR: #3366ff\">era una persona temperamental<\/SPAN><\/B> (parec\u00eda casi latino), y se entusiasmaba mucho (casi vehementemente) cuando hablaba. Defend\u00eda la <B style=\"mso-bidi-font-weight: normal\"><SPAN style=\"COLOR: #3366ff\">no-linealidad de la mayor parte de los patrones y procesos de la naturaleza<\/SPAN><\/B>. En un momento dado de su charla espet\u00f3 que aquellos que no ten\u00edan tal propiedad eran \u201c<B style=\"mso-bidi-font-weight: normal\"><SPAN style=\"COLOR: #3366ff\">patol\u00f3gicos<\/SPAN><\/B>\u201d. Me pareci\u00f3 <B style=\"mso-bidi-font-weight: normal\"><SPAN style=\"COLOR: #3366ff\">un abuso del lenguaje, impropio de un cient\u00edfico de su talla<\/SPAN><\/B>. Cuando termin\u00f3 su disertaci\u00f3n, levant\u00e9 la mano y le hice notar que tal \u201c<B style=\"mso-bidi-font-weight: normal\"><SPAN style=\"COLOR: #3366ff\">antropomorfismo<\/SPAN>\u201d<\/B> me parec\u00eda desafortunado (ante el horror de sus pupilos), exponi\u00e9ndole un ejemplo. El <B style=\"mso-bidi-font-weight: normal\"><SPAN style=\"COLOR: #3366ff\">hombre entendi\u00f3 inmediatamente su error<\/SPAN><\/B> (eso los hace m\u00e1s grandes, al contrario que la soberbia) <B style=\"mso-bidi-font-weight: normal\"><SPAN style=\"COLOR: #3366ff\">y rectific\u00f3 p\u00fablicamente<\/SPAN><\/B>. Luego en el bar me invit\u00f3 a una cerveza y charlamos unos minutos (ante la at\u00f3nita mirada de sus correligionarios). <SPAN style=\"mso-spacerun: yes\">&nbsp;&nbsp;&nbsp;<\/SPAN><o:p><\/o:p><\/SPAN><\/P> <P class=MsoNormal style=\"MARGIN: 0cm 0cm 0pt\"><SPAN style=\"FONT-SIZE: 10pt; FONT-FAMILY: 'Comic Sans MS'\"><o:p>&nbsp;<\/o:p><\/SPAN><\/P> <P class=MsoNormal style=\"MARGIN: 0cm 0cm 0pt; TEXT-ALIGN: justify\"><SPAN style=\"FONT-SIZE: 10pt; FONT-FAMILY: 'Comic Sans MS'\">Y para finalizar, <B style=\"mso-bidi-font-weight: normal\"><SPAN style=\"COLOR: #3366ff\">hablando de rigor en el lenguaje<\/SPAN><\/B>, quiz\u00e1s los cient\u00edficos deber\u00edamos aplicarnos el dicho mentado, es decir: \u201c<B style=\"mso-bidi-font-weight: normal\"><SPAN style=\"COLOR: #3366ff\">dime de que presumes y te dir\u00e9 de que careces<\/SPAN><\/B>\u201d.<SPAN style=\"mso-spacerun: yes\">&nbsp; <\/SPAN><SPAN style=\"mso-spacerun: yes\">&nbsp;&nbsp;<\/SPAN><o:p><\/o:p><\/SPAN><\/P> <P class=MsoNormal style=\"MARGIN: 0cm 0cm 0pt; TEXT-ALIGN: justify\"><SPAN style=\"FONT-SIZE: 10pt; FONT-FAMILY: 'Comic Sans MS'\"><o:p>&nbsp;<\/o:p><\/SPAN><\/P> <P class=MsoNormal style=\"MARGIN: 0cm 0cm 0pt; TEXT-ALIGN: justify\"><B style=\"mso-bidi-font-weight: normal\"><SPAN style=\"FONT-SIZE: 8pt; COLOR: #3366ff; FONT-FAMILY: 'Comic Sans MS'\">PD<\/SPAN><\/B><SPAN style=\"FONT-SIZE: 8pt; FONT-FAMILY: 'Comic Sans MS'\">. En las fotos sobre el DNA, una corresponde <B style=\"mso-bidi-font-weight: normal\"><SPAN style=\"COLOR: #3366ff\">a una galaxia en doble espiral hermos\u00edsima<\/SPAN><\/B>. A pi\u00e9 de foto encontr\u00e9 este comentario: \u201c\u00bfMensaje divino? Galaxia en doble espiral (id\u00e9ntica a mol\u00e9cula de ADN) descubierta en marzo del 2006 a 300 a\u00f1os luz del centro de la V\u00eda Lactea. Foto en falso color\u201dNASA\/JPL-Caltech\/M. Morris (UCLA)\u201d. No veis las divinidades siguen entre nosotros alternando con lasimperfecciones. <o:p><\/o:p><\/SPAN><\/P> <P class=MsoNormal style=\"MARGIN: 0cm 0cm 0pt; TEXT-ALIGN: justify\"><SPAN style=\"FONT-SIZE: 10pt; FONT-FAMILY: 'Comic Sans MS'\"><o:p>&nbsp;<\/o:p><\/SPAN><\/P> <P class=MsoNormal style=\"MARGIN: 0cm 0cm 0pt; TEXT-ALIGN: justify\"><B style=\"mso-bidi-font-weight: normal\"><SPAN style=\"FONT-SIZE: 14pt; COLOR: #cc0000; FONT-FAMILY: 'Comic Sans MS'\">Juan Jos\u00e9 Ib\u00e1\u00f1ez<\/SPAN><\/B><\/P><\/p>\n<h3>Im\u00e1genes Relacionadas:<\/h3>","protected":false},"excerpt":{"rendered":"<p>Se presume que el lenguaje de la ciencia es riguroso y objetivo, aunque actualmente muchos investigadores publicitan sus descubrimientos como si fueran lavadoras de \u00faltima generaci\u00f3n o perfumes en periodos navide\u00f1os. Padecemos un mundo de merchandising y aqu\u00ed no se libra nadie. Sin embargo, con independencia de estas consideraciones, existen ejemplos notables y gloriosos que muestran como al encontrarse con alg\u00fan ente o proceso que no se ajusta a nuestros modelos conceptuales vigentes, patinamos ling\u00fc\u00edsticamente usando antropocentrismos impropios de tal rigor. Tendemos a \u201cacusar\u201d a la naturaleza de ser imperfecta cuando los \u00fanicos torpes somos nosotros. Veamos hoy dos casos\u2026<\/p>\n","protected":false},"author":26,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0},"categories":[596,584,597,606],"tags":[],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":4}},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Se presume que el lenguaje de la ciencia es riguroso y objetivo, aunque actualmente muchos investigadores publicitan sus descubrimientos como si fueran lavadoras de \u00faltima generaci\u00f3n o perfumes en periodos navide\u00f1os. Padecemos un mundo de merchandising y aqu\u00ed no se libra nadie. Sin embargo, con independencia de estas consideraciones, existen ejemplos notables y gloriosos que\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Juan Jos\u00e9 Ib\u00e1\u00f1ez\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2007\/11\/07\/78269\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Un Universo invisible bajo nuestros pies - Los suelos y la vida\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Los Errores de la Naturaleza y el Vocabulario Cient\u00edfico - Un Universo invisible bajo nuestros pies\" \/>\n\t\t<meta property=\"og:description\" content=\"Se presume que el lenguaje de la ciencia es riguroso y objetivo, aunque actualmente muchos investigadores publicitan sus descubrimientos como si fueran lavadoras de \u00faltima generaci\u00f3n o perfumes en periodos navide\u00f1os. Padecemos un mundo de merchandising y aqu\u00ed no se libra nadie. Sin embargo, con independencia de estas consideraciones, existen ejemplos notables y gloriosos que\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2007\/11\/07\/78269\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2007-11-07T14:17:00+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2010-01-22T02:45:22+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/juan.j.marti.14\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Los Errores de la Naturaleza y el Vocabulario Cient\u00edfico - Un Universo invisible bajo nuestros pies\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Se presume que el lenguaje de la ciencia es riguroso y objetivo, aunque actualmente muchos investigadores publicitan sus descubrimientos como si fueran lavadoras de \u00faltima generaci\u00f3n o perfumes en periodos navide\u00f1os. Padecemos un mundo de merchandising y aqu\u00ed no se libra nadie. Sin embargo, con independencia de estas consideraciones, existen ejemplos notables y gloriosos que\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2007\\\/11\\\/07\\\/78269#blogposting\",\"name\":\"Los Errores de la Naturaleza y el Vocabulario Cient\\u00edfico - Un Universo invisible bajo nuestros pies\",\"headline\":\"Los Errores de la Naturaleza y el Vocabulario Cient\\u00edfico\",\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/files\\\/2022\\\/02\\\/logo.png\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#articleImage\",\"width\":217,\"height\":72},\"datePublished\":\"2007-11-07T14:17:00+01:00\",\"dateModified\":\"2010-01-22T03:45:22+01:00\",\"inLanguage\":\"es-ES\",\"commentCount\":3,\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2007\\\/11\\\/07\\\/78269#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2007\\\/11\\\/07\\\/78269#webpage\"},\"articleSection\":\"Biolog\\u00eda y Ecolog\\u00eda del Suelo, Documentos sobre Edafolog\\u00eda + Instituciones + Enlaces, Filosof\\u00eda, Historia y Sociolog\\u00eda de la Edafolog\\u00eda, Prensa y Pol\\u00edtica Cient\\u00edfica\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2007\\\/11\\\/07\\\/78269#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/documentos-sobre-edafologia-instituciones-enlaces#listItem\",\"name\":\"Documentos sobre Edafolog\\u00eda + Instituciones + Enlaces\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/documentos-sobre-edafologia-instituciones-enlaces#listItem\",\"position\":2,\"name\":\"Documentos sobre Edafolog\\u00eda + Instituciones + Enlaces\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/documentos-sobre-edafologia-instituciones-enlaces\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2007\\\/11\\\/07\\\/78269#listItem\",\"name\":\"Los Errores de la Naturaleza y el Vocabulario Cient\\u00edfico\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2007\\\/11\\\/07\\\/78269#listItem\",\"position\":3,\"name\":\"Los Errores de la Naturaleza y el Vocabulario Cient\\u00edfico\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/documentos-sobre-edafologia-instituciones-enlaces#listItem\",\"name\":\"Documentos sobre Edafolog\\u00eda + Instituciones + Enlaces\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#organization\",\"name\":\"Un Universo invisible bajo nuestros pies\",\"description\":\"Los suelos y la vida\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/files\\\/2022\\\/02\\\/logo.png\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2007\\\/11\\\/07\\\/78269\\\/#organizationLogo\",\"width\":217,\"height\":72},\"image\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2007\\\/11\\\/07\\\/78269\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/juan.j.marti.14\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo\",\"name\":\"Juan Jos\\u00e9 Ib\\u00e1\\u00f1ez\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2007\\\/11\\\/07\\\/78269#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/387f3a100385573d8f42ce2a3211fd1c?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Juan Jos\\u00e9 Ib\\u00e1\\u00f1ez\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2007\\\/11\\\/07\\\/78269#webpage\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2007\\\/11\\\/07\\\/78269\",\"name\":\"Los Errores de la Naturaleza y el Vocabulario Cient\\u00edfico - Un Universo invisible bajo nuestros pies\",\"description\":\"Se presume que el lenguaje de la ciencia es riguroso y objetivo, aunque actualmente muchos investigadores publicitan sus descubrimientos como si fueran lavadoras de \\u00faltima generaci\\u00f3n o perfumes en periodos navide\\u00f1os. Padecemos un mundo de merchandising y aqu\\u00ed no se libra nadie. Sin embargo, con independencia de estas consideraciones, existen ejemplos notables y gloriosos que\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2007\\\/11\\\/07\\\/78269#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\"},\"datePublished\":\"2007-11-07T14:17:00+01:00\",\"dateModified\":\"2010-01-22T03:45:22+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#website\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/\",\"name\":\"Un Universo invisible bajo nuestros pies\",\"description\":\"Los suelos y la vida\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Los Errores de la Naturaleza y el Vocabulario Cient\u00edfico - Un Universo invisible bajo nuestros pies","description":"Se presume que el lenguaje de la ciencia es riguroso y objetivo, aunque actualmente muchos investigadores publicitan sus descubrimientos como si fueran lavadoras de \u00faltima generaci\u00f3n o perfumes en periodos navide\u00f1os. Padecemos un mundo de merchandising y aqu\u00ed no se libra nadie. Sin embargo, con independencia de estas consideraciones, existen ejemplos notables y gloriosos que","canonical_url":"https:\/\/www.madrimasd.org\/blogs\/universo\/2007\/11\/07\/78269","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2007\/11\/07\/78269#blogposting","name":"Los Errores de la Naturaleza y el Vocabulario Cient\u00edfico - Un Universo invisible bajo nuestros pies","headline":"Los Errores de la Naturaleza y el Vocabulario Cient\u00edfico","author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author"},"publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#articleImage","width":217,"height":72},"datePublished":"2007-11-07T14:17:00+01:00","dateModified":"2010-01-22T03:45:22+01:00","inLanguage":"es-ES","commentCount":3,"mainEntityOfPage":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2007\/11\/07\/78269#webpage"},"isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2007\/11\/07\/78269#webpage"},"articleSection":"Biolog\u00eda y Ecolog\u00eda del Suelo, Documentos sobre Edafolog\u00eda + Instituciones + Enlaces, Filosof\u00eda, Historia y Sociolog\u00eda de la Edafolog\u00eda, Prensa y Pol\u00edtica Cient\u00edfica"},{"@type":"BreadcrumbList","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2007\/11\/07\/78269#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo#listItem","position":1,"name":"Home","item":"https:\/\/www.madrimasd.org\/blogs\/universo","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/documentos-sobre-edafologia-instituciones-enlaces#listItem","name":"Documentos sobre Edafolog\u00eda + Instituciones + Enlaces"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/documentos-sobre-edafologia-instituciones-enlaces#listItem","position":2,"name":"Documentos sobre Edafolog\u00eda + Instituciones + Enlaces","item":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/documentos-sobre-edafologia-instituciones-enlaces","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2007\/11\/07\/78269#listItem","name":"Los Errores de la Naturaleza y el Vocabulario Cient\u00edfico"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2007\/11\/07\/78269#listItem","position":3,"name":"Los Errores de la Naturaleza y el Vocabulario Cient\u00edfico","previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/documentos-sobre-edafologia-instituciones-enlaces#listItem","name":"Documentos sobre Edafolog\u00eda + Instituciones + Enlaces"}}]},{"@type":"Organization","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#organization","name":"Un Universo invisible bajo nuestros pies","description":"Los suelos y la vida","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/","logo":{"@type":"ImageObject","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2007\/11\/07\/78269\/#organizationLogo","width":217,"height":72},"image":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2007\/11\/07\/78269\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/juan.j.marti.14"]},{"@type":"Person","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo","name":"Juan Jos\u00e9 Ib\u00e1\u00f1ez","image":{"@type":"ImageObject","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2007\/11\/07\/78269#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/387f3a100385573d8f42ce2a3211fd1c?s=96&d=mm&r=g","width":96,"height":96,"caption":"Juan Jos\u00e9 Ib\u00e1\u00f1ez"}},{"@type":"WebPage","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2007\/11\/07\/78269#webpage","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/2007\/11\/07\/78269","name":"Los Errores de la Naturaleza y el Vocabulario Cient\u00edfico - Un Universo invisible bajo nuestros pies","description":"Se presume que el lenguaje de la ciencia es riguroso y objetivo, aunque actualmente muchos investigadores publicitan sus descubrimientos como si fueran lavadoras de \u00faltima generaci\u00f3n o perfumes en periodos navide\u00f1os. Padecemos un mundo de merchandising y aqu\u00ed no se libra nadie. Sin embargo, con independencia de estas consideraciones, existen ejemplos notables y gloriosos que","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#website"},"breadcrumb":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2007\/11\/07\/78269#breadcrumblist"},"author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author"},"creator":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author"},"datePublished":"2007-11-07T14:17:00+01:00","dateModified":"2010-01-22T03:45:22+01:00"},{"@type":"WebSite","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#website","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/","name":"Un Universo invisible bajo nuestros pies","description":"Los suelos y la vida","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Un Universo invisible bajo nuestros pies - Los suelos y la vida","og:type":"article","og:title":"Los Errores de la Naturaleza y el Vocabulario Cient\u00edfico - Un Universo invisible bajo nuestros pies","og:description":"Se presume que el lenguaje de la ciencia es riguroso y objetivo, aunque actualmente muchos investigadores publicitan sus descubrimientos como si fueran lavadoras de \u00faltima generaci\u00f3n o perfumes en periodos navide\u00f1os. Padecemos un mundo de merchandising y aqu\u00ed no se libra nadie. Sin embargo, con independencia de estas consideraciones, existen ejemplos notables y gloriosos que","og:url":"https:\/\/www.madrimasd.org\/blogs\/universo\/2007\/11\/07\/78269","og:image":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png","og:image:secure_url":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png","article:published_time":"2007-11-07T14:17:00+00:00","article:modified_time":"2010-01-22T02:45:22+00:00","article:publisher":"https:\/\/www.facebook.com\/juan.j.marti.14","twitter:card":"summary","twitter:title":"Los Errores de la Naturaleza y el Vocabulario Cient\u00edfico - Un Universo invisible bajo nuestros pies","twitter:description":"Se presume que el lenguaje de la ciencia es riguroso y objetivo, aunque actualmente muchos investigadores publicitan sus descubrimientos como si fueran lavadoras de \u00faltima generaci\u00f3n o perfumes en periodos navide\u00f1os. Padecemos un mundo de merchandising y aqu\u00ed no se libra nadie. Sin embargo, con independencia de estas consideraciones, existen ejemplos notables y gloriosos que","twitter:image":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png"},"aioseo_meta_data":{"post_id":"78269","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":null,"isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","tabs":null,"priority":null,"frequency":null,"local_seo":null,"created":"2022-06-03 14:36:43","updated":"2026-05-26 14:33:57","limit_modified_date":false,"ai":null,"breadcrumb_settings":null,"seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/documentos-sobre-edafologia-instituciones-enlaces\" title=\"Documentos sobre Edafolog\u00eda + Instituciones + Enlaces\">Documentos sobre Edafolog\u00eda + Instituciones + Enlaces<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tLos Errores de la Naturaleza y el Vocabulario Cient\u00edfico\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.madrimasd.org\/blogs\/universo"},{"label":"Documentos sobre Edafolog\u00eda + Instituciones + Enlaces","link":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/documentos-sobre-edafologia-instituciones-enlaces"},{"label":"Los Errores de la Naturaleza y el Vocabulario Cient\u00edfico","link":"https:\/\/www.madrimasd.org\/blogs\/universo\/2007\/11\/07\/78269"}],"_links":{"self":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts\/78269"}],"collection":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/comments?post=78269"}],"version-history":[{"count":3,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts\/78269\/revisions"}],"predecessor-version":[{"id":134514,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts\/78269\/revisions\/134514"}],"wp:attachment":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/media?parent=78269"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/categories?post=78269"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/tags?post=78269"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}