{"id":92581,"date":"2008-05-22T10:33:00","date_gmt":"2008-05-22T10:33:00","guid":{"rendered":"http:\/\/weblogs.madrimasd.org\/\/universo\/archive\/2008\/05\/22\/92581.aspx"},"modified":"2010-01-22T03:47:42","modified_gmt":"2010-01-22T02:47:42","slug":"sistemas-agroforestales-y-sistemas-agrosilvopastorales-%c2%bfcuales-son-las-diferencias","status":"publish","type":"post","link":"https:\/\/www.madrimasd.org\/blogs\/universo\/2008\/05\/22\/92581","title":{"rendered":"Sistemas Agroforestales y Sistemas Agrosilvopastorales: \u00bfCu\u00e1les son las Diferencias?"},"content":{"rendered":"<p><P class=MsoNormal style=\"MARGIN: 0cm 0cm 0pt; TEXT-ALIGN: justify\"><SPAN style=\"FONT-SIZE: 10pt; FONT-FAMILY: 'Comic Sans MS'\">Desde hace algunas d\u00e9cadas, se han popularizado los estudios y el valor de los denominados <B style=\"mso-bidi-font-weight: normal\"><SPAN style=\"COLOR: #3366ff\">sistemas agroforestales<\/SPAN><\/B>, como alternativas a otros modos de producci\u00f3n agraria en diversos pa\u00edses subdesarrollados o en v\u00edas de desarrollo. Somos partidarios de este tipo de explotaciones por cuanto <B style=\"mso-bidi-font-weight: normal\"><SPAN style=\"COLOR: #3366ff\">atesoran un gran inter\u00e9s, entre los cuales destaca la diversificaci\u00f3n de las producciones para el abastecimiento de las poblaciones locales<\/SPAN><\/B>.<SPAN style=\"mso-spacerun: yes\">&nbsp; <\/SPAN>De hecho se trata de <B style=\"mso-bidi-font-weight: normal\"><SPAN style=\"COLOR: #3366ff\">sistemas muy antiguos, que ya utilizaban los abor\u00edgenes en diversos lugares del mundo<\/SPAN><\/B>. Nada nuevo bajo el sol. No es inusual tampoco que los expertos jueguen a generar tales modos de explotaci\u00f3n con nuevas especies, en lugar de <B style=\"mso-bidi-font-weight: normal\"><SPAN style=\"COLOR: #3366ff\">aprovechar el conocimiento etnogr\u00e1fico y ecol\u00f3gico que ya atesoramos de muchos de ellos<\/SPAN><\/B>.<SPAN style=\"mso-spacerun: yes\">&nbsp;&nbsp; <\/SPAN><o:p><\/o:p><\/SPAN><\/P> <P class=MsoNormal style=\"MARGIN: 0cm 0cm 0pt; TEXT-ALIGN: justify\"><SPAN style=\"FONT-SIZE: 10pt; FONT-FAMILY: 'Comic Sans MS'\"><o:p>&nbsp;<\/o:p><\/SPAN><\/P> <P class=MsoNormal style=\"MARGIN: 0cm 0cm 0pt; TEXT-ALIGN: justify\"><SPAN style=\"FONT-SIZE: 10pt; FONT-FAMILY: 'Comic Sans MS'\"><o:p>&nbsp;<IMG style=\"WIDTH: 420px; HEIGHT: 295px\" height=899 src=\"\/blogs\/universo\/wp-content\/blogs.dir\/42\/files\/255\/o_Dehesa%20Salmantina.JPG\" width=1305><\/o:p><\/SPAN><\/P> <P class=MsoNormal style=\"MARGIN: 0cm 0cm 0pt; TEXT-ALIGN: justify\"><SPAN style=\"FONT-SIZE: 10pt; FONT-FAMILY: 'Comic Sans MS'\"><o:p>&nbsp;<\/o:p><\/SPAN><\/P> <P class=MsoNormal style=\"MARGIN: 0cm 0cm 0pt; TEXT-ALIGN: justify\"><B style=\"mso-bidi-font-weight: normal\"><SPAN style=\"FONT-SIZE: 8pt; COLOR: #3366ff; FONT-FAMILY: 'Comic Sans MS'\">Dehesa Salmantina Espa\u00f1ola de Encinas:<o:p><\/o:p><\/SPAN><\/B><\/P> <P class=MsoNormal style=\"MARGIN: 0cm 0cm 0pt; TEXT-ALIGN: justify\"><B style=\"mso-bidi-font-weight: normal\"><SPAN style=\"FONT-SIZE: 8pt; COLOR: #3366ff; FONT-FAMILY: 'Comic Sans MS'\">Foto: Juanjo Ib\u00e1\u00f1ez y Yolanda Baquero<o:p><\/o:p><\/SPAN><\/B><\/P> <P class=MsoNormal style=\"MARGIN: 0cm 0cm 0pt; TEXT-ALIGN: justify\"><B style=\"mso-bidi-font-weight: normal\"><SPAN style=\"FONT-SIZE: 8pt; COLOR: #3366ff; FONT-FAMILY: 'Comic Sans MS'\">16 de mayo de 2008-05-22<o:p><\/o:p><\/SPAN><\/B><\/P> <P class=MsoNormal style=\"MARGIN: 0cm 0cm 0pt; TEXT-ALIGN: justify\"><SPAN style=\"FONT-SIZE: 10pt; FONT-FAMILY: 'Comic Sans MS'\"><o:p>&nbsp;<\/o:p><\/SPAN><\/P><!--more--><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt; text-align: justify;\"><span style=\"font-size: 10pt; font-family: 'Comic Sans MS';\"><o:p><\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt; text-align: justify;\"><span style=\"font-size: 10pt; font-family: 'Comic Sans MS';\"><o:p>&nbsp;<\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt; text-align: justify;\"><span style=\"font-size: 10pt; font-family: 'Comic Sans MS';\">Sin embargo, <b style=\"\"><span style=\"color: rgb(51, 102, 255);\">el vocablo agroforestal abarca tal cantidad y disparidad de sistemas de gesti\u00f3n diferentes que usarlo no nos informa debidamente<\/span><\/b> de lo que se pretende describir o introducir. As\u00ed, por ejemplo, <b style=\"\"><span style=\"color: rgb(51, 102, 255);\">entre las fotos que exponemos podemos observar un sistema mixto de cultivos arb\u00f3reos cacao-bananeras-cedros, y otro que incluso utiliza el riego<\/span><\/b>. De hecho, <b style=\"\"><span style=\"color: rgb(51, 102, 255);\">la Wikipedia Espa\u00f1ola<\/span><\/b> define del siguiente modo la <a href=\"http:\/\/es.wikipedia.org\/wiki\/Ingenier%C3%83%C2%ADa_agroforestal\">ingenier\u00eda agroforestal:<\/a><o:p><\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt; text-align: justify;\"><span style=\"font-size: 10pt; font-family: 'Comic Sans MS';\"><o:p>&nbsp;<\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt; text-align: justify;\"><span style=\"font-size: 10pt; font-family: 'Comic Sans MS';\"><o:p><img decoding=\"async\" style=\"width: 431px; height: 266px;\" src=\"\/blogs\/universo\/wp-content\/blogs.dir\/42\/files\/255\/o_TRANSICION%20MONTE%20DEHESA%20MONFRAGUE.PNG\" height=\"299\" width=\"439\"><\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt; text-align: justify;\"><span style=\"font-size: 10pt; font-family: 'Comic Sans MS';\"><o:p>&nbsp;<\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt;\"><span style=\"font-size: 8pt; font-family: 'Comic Sans MS';\"><a href=\"http:\/\/www.revistaecosistemas.net\/pdfs\/193.pdf\"><font color=\"#800080\">Transici\u00f3n bosque mediterr\u00e1neo-dehesa<\/font><\/a> <o:p><\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt;\"><span style=\"font-size: 8pt; color: blue; font-family: 'Comic Sans MS';\">(Monfrague, Espa\u00f1a, Fuente Unex)<o:p><\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt; text-align: justify;\"><span style=\"font-size: 10pt; font-family: 'Comic Sans MS';\"><o:p>&nbsp;<\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt; text-align: justify;\"><span style=\"font-size: 9pt; font-family: Arial;\"><o:p>&nbsp;<\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt; text-align: justify;\"><span style=\"font-size: 9pt; font-family: Arial;\">La ingenier\u00eda <b style=\"\"><span style=\"color: rgb(51, 102, 255);\">agroforestal e<\/span><\/b>s rama de las ciencias agropecuarias que <b style=\"\"><span style=\"color: rgb(51, 102, 255);\">se encarga del conocimiento de las recursos naturales y los agroecosistemas, especialmente de las relaciones que se establecen cuando se combinan \u00e1rboles, cultivos y animales-pastos <\/span><\/b>en la misma unidad de terreno manteniendo los<b style=\"\"><span style=\"color: rgb(51, 102, 255);\"> principios de sostenibilidad, productividad y adoptabilidad<\/span><\/b>.<o:p><\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt; text-align: justify;\"><span style=\"font-size: 10pt; font-family: 'Comic Sans MS';\"><o:p>&nbsp;<\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt; text-align: justify;\"><span style=\"font-size: 10pt; font-family: 'Comic Sans MS';\">No es una buena definici\u00f3n. Resulta conveniente precisar m\u00e1s que se entiende por sistemas <b style=\"\"><span style=\"color: rgb(51, 102, 255);\">agroforestales y\/o agrosilvopastorales<\/span><\/b>, por cuanto, se trata de gestiones del territorio que pueden llegar a ser totalmente distintas.<b style=\"\"><span style=\"color: rgb(51, 102, 255);\"> No es lo mismo un cultivo mixto de varias especies arb\u00f3reas <\/span><\/b>(cuya coexistencia les favorece mutuamente), <b style=\"\"><span style=\"color: rgb(51, 102, 255);\">que otro en el que a la producci\u00f3n agraria adquiere el valor a\u00f1adido, tanto por<\/span><\/b> el efecto beneficioso del arbolado sobre los cultivos, como de los propios productos que se pueden obtener de la foresta. <b style=\"\"><span style=\"color: rgb(51, 102, 255);\">Muchos m\u00e1s complejos, son las dehesas y montados tradicionales que se dispersan por Espa\u00f1a y Portugal<\/span><\/b>, respectivamente.<o:p><\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt; text-align: justify;\"><span style=\"font-size: 10pt; font-family: 'Comic Sans MS';\"><o:p>&nbsp;<\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt; text-align: justify;\"><span style=\"font-size: 10pt; font-family: 'Comic Sans MS';\">Por tanto, en una primera aproximaci\u00f3n podr\u00edamos <b style=\"\"><span style=\"color: rgb(51, 102, 255);\">definir sistemas agroforestales<\/span><\/b>, como todos aquellos en los que la producci\u00f3n agraria se sustenta en un policultivo de especies arb\u00f3reas, con otras de naturaleza herb\u00e1cea.<o:p><\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt; text-align: justify;\"><span style=\"font-size: 10pt; font-family: 'Comic Sans MS';\"><o:p>&nbsp;<\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt; text-align: justify;\"><span style=\"font-size: 10pt; font-family: 'Comic Sans MS';\">Del mismo modo, estos deber\u00edan diferenciarse de los <b style=\"\"><span style=\"color: rgb(51, 102, 255);\">policultivos forestales<\/span><\/b> que incorporan varias especies le\u00f1osas de inter\u00e9s. <o:p><\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt; text-align: justify;\"><span style=\"font-size: 10pt; font-family: 'Comic Sans MS';\"><o:p>&nbsp;<\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt; text-align: justify;\"><span style=\"font-size: 10pt; font-family: 'Comic Sans MS';\">Finalmente, estos dos tipos de gesti\u00f3n son diferentes de los <b style=\"\"><span style=\"color: rgb(51, 102, 255);\">sistemas agrosilvopastorales<\/span><\/b>, en los cuales la producci\u00f3n agraria y forestal se compagina con la ganader\u00eda extensiva. En este \u00faltimo caso, nos encontramos con arbolado, pastos-ganados y varios cultivos simult\u00e1neamente.<span style=\"\">&nbsp; <\/span><o:p><\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt; text-align: justify;\"><span style=\"font-size: 10pt; font-family: 'Comic Sans MS';\"><o:p>&nbsp;<\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt; text-align: justify;\"><b style=\"\"><span style=\"font-size: 10pt; color: rgb(51, 102, 255); font-family: 'Comic Sans MS';\">A nivel paisaj\u00edstico su fisonom\u00eda puede ser muy variada. Por ejemplo, los policultivos forestales tienden a formar masas densas<\/span><\/b><span style=\"font-size: 10pt; font-family: 'Comic Sans MS';\"> de \u00e1rboles, <b style=\"\"><span style=\"color: rgb(51, 102, 255);\">mientras que algunos agroforestales y la mayor\u00eda de los agrosilvopastorales conforman paisajes abiertos de aspecto sabanoide<\/span><\/b>. <o:p><\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt; text-align: justify;\"><span style=\"font-size: 10pt; font-family: 'Comic Sans MS';\"><o:p>&nbsp;<\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt; text-align: justify;\"><span style=\"font-size: 10pt; font-family: 'Comic Sans MS';\">Con vistas a clarificar y precisar las propiedades de la entidad de la que estamos hablando, <b style=\"\"><span style=\"color: rgb(51, 102, 255);\">tambi\u00e9n cabr\u00eda discernir entre \u201csistema y gesti\u00f3n<\/span><\/b>\u201d. Una finca o hacienda puede consistir en un policultivo de diversa \u00edndole, en la que los elementos mencionados: cultivo, \u00e1rbol-pasto ganado se presentan en combinaciones distintas, ya sea en el espacio o alternando en el tiempo (rotaciones de alg\u00fan tipo). <o:p><\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt; text-align: justify;\"><span style=\"font-size: 10pt; font-family: 'Comic Sans MS';\"><o:p>&nbsp;<\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt; text-align: justify;\"><span style=\"font-size: 10pt; font-family: 'Comic Sans MS';\"><o:p>&nbsp;<img decoding=\"async\" src=\"\/blogs\/universo\/wp-content\/blogs.dir\/42\/files\/255\/o_Agroforestal%20platano%20cacao%20cedro.jpg\" height=\"539\" width=\"433\"><\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt; text-align: justify;\"><span style=\"font-size: 10pt; font-family: 'Comic Sans MS';\"><o:p>&nbsp;<\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt;\"><span style=\"font-size: 8pt; font-family: 'Comic Sans MS';\"><a href=\"http:\/\/www.devida.gob.pe\/Fotos%20Medio%20Ambiente\/Proyecto%20Monzon\/arles_gallery\/imagepages\/image10.html\"><font color=\"#800080\">Sistema agroforestal cacao-platano-cedro<\/font><\/a><o:p><\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt; text-align: justify;\"><span style=\"font-size: 10pt; font-family: 'Comic Sans MS';\"><o:p>&nbsp;<\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt; text-align: justify;\"><span style=\"font-size: 10pt; font-family: 'Comic Sans MS';\"><o:p>&nbsp;<\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt; text-align: justify;\"><span style=\"font-size: 10pt; font-family: 'Comic Sans MS';\">Como ya hemos comentado, <b style=\"\"><span style=\"color: rgb(51, 102, 255);\">en la Pen\u00ednsula Ib\u00e9rica, existen unas haciendas \u201cy\u201d sistemas ancestrales cuya gesti\u00f3n permite el uso sustentable de tierras marginales, con suelos \u00e1cidos y frecuentemente someros que dif\u00edcilmente ser\u00edan rentables bajo otros tipos de aprovechamiento<\/span><\/b>. La<b style=\"\"><span style=\"color: rgb(51, 102, 255);\"> diversificaci\u00f3n<\/span><\/b> de los productos que se extraen de ellas puede ser <b style=\"\"><span style=\"color: rgb(51, 102, 255);\">extraordinaria<\/span><\/b>. Han mostrado ser <b style=\"\"><span style=\"color: rgb(51, 102, 255);\">sustentables<\/span><\/b> durante milenios, a la par que<b style=\"\"> <span style=\"color: rgb(51, 102, 255);\">conservan<\/span><\/b> correctamente <b style=\"\"><span style=\"color: rgb(51, 102, 255);\">el suelo<\/span><\/b>, actuando a la par como <b style=\"\"><span style=\"color: rgb(51, 102, 255);\">sumideros de carbono<\/span><\/b>. M\u00e1s aun, <b style=\"\"><span style=\"color: rgb(51, 102, 255);\">atesoran m\u00e1s biodiversidad que los bosques mediterr\u00e1neos naturales<\/span><\/b>. Tanto es as\u00ed que su biodiversidad en plantas vasculares, de acuerdo a algunos expertos, se acerca a la de los bosques tropicales. La \u00fanica diferencia es que tal riqueza en especies aparece en el tapiz herb\u00e1ceo, m\u00e1s que en la foresta, lianas, etc. Finalmente, comentar que<b style=\"\"><span style=\"color: rgb(51, 102, 255);\"> los ganados que pacen en sus campos simult\u00e1neamente<\/span><\/b> (es decir en la misma hacienda) pueden llegar a ser <b style=\"\"><span style=\"color: rgb(51, 102, 255);\">muy variados<\/span><\/b> (ovejas, cabras, cerdos, vacas, toros bravos, etc.), consistiendo \u201cidealmente\u201d en <b style=\"\"><span style=\"color: rgb(51, 102, 255);\">razas aut\u00f3ctonas<\/span><\/b> (muy bien adaptadas a sus respectivos ambientes) <b style=\"\"><span style=\"color: rgb(51, 102, 255);\">que se hubieran extinguido<\/span><\/b> debido a su escasa rentabilidad <b style=\"\"><span style=\"color: rgb(51, 102, 255);\">bajo otros tipos de usos del suelo<\/span><\/b>. Son de unos <b style=\"\"><span style=\"color: rgb(51, 102, 255);\">sistemas tan sorprendentes, complejos, hermosos y \u201cexportables<\/span><\/b>\u201d, como para ser motivo de una serie de post, que iremos desgranando en su momento. <o:p><\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt; text-align: justify;\"><span style=\"font-size: 10pt; font-family: 'Comic Sans MS';\"><o:p>&nbsp;<\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt; text-align: justify;\"><span style=\"font-size: 10pt; font-family: 'Comic Sans MS';\"><o:p>&nbsp;<img decoding=\"async\" style=\"width: 405px; height: 256px;\" src=\"\/blogs\/universo\/wp-content\/blogs.dir\/42\/files\/255\/o_agroforestal%20M%C3%A9xico%20con%20riego.jpg\" height=\"235\" width=\"358\"><\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt; text-align: justify;\"><span style=\"font-size: 10pt; font-family: 'Comic Sans MS';\"><o:p>&nbsp;<\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt;\"><span style=\"font-size: 8pt; font-family: 'Comic Sans MS';\"><a href=\"http:\/\/www.sagarpa.gob.mx\/sdr\/pesa\/fase_piloto\/resultados_nacionales\/apoyo_tecnologico\/apoyo_tecnologico.htm\"><font color=\"#800080\">Sistema agroforestal en M\u00e9xico bajo riego<\/font><\/a><o:p><\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt; text-align: justify;\"><span style=\"font-size: 10pt; font-family: 'Comic Sans MS';\"><o:p>&nbsp;<\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt; text-align: justify;\"><span style=\"font-size: 10pt; font-family: 'Comic Sans MS';\">Finalmente se\u00f1alar que no pretendo acu\u00f1ar vocablos nuevos. Todos los aqu\u00ed incluidos ya se encuentran en la literatura. El prop\u00f3sito fundamental de este post es clarificar todos los <b style=\"\"><span style=\"color: rgb(51, 102, 255);\">sistemas de usos del suelo y gesti\u00f3n<\/span><\/b> que actualmente se incluyen bajo el <b style=\"\"><span style=\"color: rgb(51, 102, 255);\">vocablo agroforestal<\/span><\/b>. Reiteramos que estos <b style=\"\"><span style=\"color: rgb(51, 102, 255);\">son tan diferentes que terminan por convertir a este \u00faltimo como un t\u00e9rmino confundente que se antoja una caja de pandora<\/span><\/b>. <span style=\"\">&nbsp;&nbsp;<\/span><span style=\"\">&nbsp;<\/span><span style=\"\">&nbsp;&nbsp;<\/span><o:p><\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt; text-align: justify;\"><span style=\"font-size: 10pt; font-family: 'Comic Sans MS';\"><o:p>&nbsp;<\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt; text-align: justify;\"><span style=\"font-size: 10pt; font-family: 'Comic Sans MS';\"><o:p>&nbsp;<img decoding=\"async\" style=\"width: 383px; height: 340px;\" src=\"\/blogs\/universo\/wp-content\/blogs.dir\/42\/files\/255\/o_aLCORNOQUEDEHESA%20uNEX.jpg\" height=\"340\" width=\"350\"><\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt; text-align: justify;\"><span style=\"font-size: 10pt; font-family: 'Comic Sans MS';\"><o:p>&nbsp;<\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt;\"><span style=\"font-size: 8pt; font-family: 'Comic Sans MS';\"><a href=\"http:\/\/www.unex.es\/polen\/plantaex\/alcornoc.htm\"><font color=\"#800080\">Alcornoque: extrayendo el corcho: Unex<\/font><\/a><o:p><\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt; text-align: justify;\"><span style=\"font-size: 8pt; color: blue; font-family: 'Comic Sans MS';\">Dehesa de Alcornoques de Extremadura, Espa\u00f1a<o:p><\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt; text-align: justify;\"><span style=\"font-size: 10pt; font-family: 'Comic Sans MS';\"><o:p>&nbsp;<\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt; text-align: justify;\"><span style=\"font-size: 10pt; font-family: 'Comic Sans MS';\">Comenzamos as\u00ed, a editar nuevos post que se incluir\u00e1n en nuestra categor\u00eda \u201c<A href=\"http:\/\/weblogs.madrimasd.org\/universo\/category\/254.aspx\"><font color=\"#800080\">etnoedafolog\u00eda y conocimiento campesino<\/font><\/a>\u201d. Hasta ahora hemos hablado fundamentalmente de los latinoamericanos (y lo seguiremos haciendo). No obstante, <b style=\"\"><span style=\"color: rgb(51, 102, 255);\">a este lado del charco tambi\u00e9n atesoramos verdaderas maravillas que pueden ser de vuestro inter\u00e9s con <\/span><\/b>vistas a servir como <b style=\"\"><span style=\"color: rgb(51, 102, 255);\">alternativas a otros que se proponen actualmente en las Am\u00e9ricas<\/span><\/b>. Estoy seguro de ello.<span style=\"\">&nbsp;&nbsp;&nbsp;&nbsp; <\/span><o:p><\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt;\"><span style=\"font-size: 10pt; font-family: 'Comic Sans MS';\"><o:p>&nbsp;<\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt;\"><span style=\"font-size: 10pt; font-family: 'Comic Sans MS';\">M\u00e1s informaci\u00f3n sobre <b style=\"\"><span style=\"color: rgb(51, 102, 255);\">sistemas agroforestales<\/span><\/b> la pod\u00e9is obtener del <a href=\"http:\/\/www.fs.fed.us\/research\/publications\/producci%C3%B3n_forestal_para_am%C3%A9rica_tropical\/cap.8.pdf\">siguiente documento<\/a>. <o:p><\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt;\"><span style=\"font-size: 10pt; font-family: 'Comic Sans MS';\"><o:p>&nbsp;<\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt;\"><span style=\"font-size: 10pt; font-family: 'Comic Sans MS';\"><o:p>&nbsp;<\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt;\"><span style=\"color: rgb(204, 0, 0); font-family: 'Comic Sans MS';\"><font size=\"3\">Juan Jos\u00e9 Ib\u00e1\u00f1ez<o:p><\/o:p><\/font><\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt; text-align: justify;\">\n<h3>Im\u00e1genes Relacionadas:<\/h3>","protected":false},"excerpt":{"rendered":"<p>Desde hace algunas d\u00e9cadas, se han popularizado los estudios y el valor de los denominados sistemas agroforestales, como alternativas a otros modos de producci\u00f3n agraria en diversos pa\u00edses subdesarrollados o en v\u00edas de desarrollo. Somos partidarios de este tipo de explotaciones por cuanto atesoran un gran inter\u00e9s, entre los cuales destaca la diversificaci\u00f3n de las producciones para el abastecimiento de las poblaciones locales.&nbsp; De hecho se trata de sistemas muy antiguos, que ya utilizaban los abor\u00edgenes en diversos lugares del mundo. Nada nuevo bajo el sol. No es inusual tampoco que los expertos jueguen a generar tales modos de explotaci\u00f3n\u2026<\/p>\n","protected":false},"author":26,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0},"categories":[603,586,599,600],"tags":[],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":4}},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Desde hace algunas d\u00e9cadas, se han popularizado los estudios y el valor de los denominados sistemas agroforestales, como alternativas a otros modos de producci\u00f3n agraria en diversos pa\u00edses subdesarrollados o en v\u00edas de desarrollo. Somos partidarios de este tipo de explotaciones por cuanto atesoran un gran inter\u00e9s, entre los cuales destaca la diversificaci\u00f3n de las\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Juan Jos\u00e9 Ib\u00e1\u00f1ez\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2008\/05\/22\/92581\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Un Universo invisible bajo nuestros pies - Los suelos y la vida\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Sistemas Agroforestales y Sistemas Agrosilvopastorales: \u00bfCu\u00e1les son las Diferencias? - Un Universo invisible bajo nuestros pies\" \/>\n\t\t<meta property=\"og:description\" content=\"Desde hace algunas d\u00e9cadas, se han popularizado los estudios y el valor de los denominados sistemas agroforestales, como alternativas a otros modos de producci\u00f3n agraria en diversos pa\u00edses subdesarrollados o en v\u00edas de desarrollo. Somos partidarios de este tipo de explotaciones por cuanto atesoran un gran inter\u00e9s, entre los cuales destaca la diversificaci\u00f3n de las\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/2008\/05\/22\/92581\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2008-05-22T10:33:00+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2010-01-22T02:47:42+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/juan.j.marti.14\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Sistemas Agroforestales y Sistemas Agrosilvopastorales: \u00bfCu\u00e1les son las Diferencias? - Un Universo invisible bajo nuestros pies\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Desde hace algunas d\u00e9cadas, se han popularizado los estudios y el valor de los denominados sistemas agroforestales, como alternativas a otros modos de producci\u00f3n agraria en diversos pa\u00edses subdesarrollados o en v\u00edas de desarrollo. Somos partidarios de este tipo de explotaciones por cuanto atesoran un gran inter\u00e9s, entre los cuales destaca la diversificaci\u00f3n de las\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2008\\\/05\\\/22\\\/92581#blogposting\",\"name\":\"Sistemas Agroforestales y Sistemas Agrosilvopastorales: \\u00bfCu\\u00e1les son las Diferencias? - Un Universo invisible bajo nuestros pies\",\"headline\":\"Sistemas Agroforestales y Sistemas Agrosilvopastorales: \\u00bfCu\\u00e1les son las Diferencias?\",\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"\\\/blogs\\\/universo\\\/wp-content\\\/blogs.dir\\\/42\\\/files\\\/255\\\/o_TRANSICION%20MONTE%20DEHESA%20MONFRAGUE.PNG\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2008\\\/05\\\/22\\\/92581\\\/#articleImage\"},\"datePublished\":\"2008-05-22T10:33:00+01:00\",\"dateModified\":\"2010-01-22T03:47:42+01:00\",\"inLanguage\":\"es-ES\",\"commentCount\":19,\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2008\\\/05\\\/22\\\/92581#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2008\\\/05\\\/22\\\/92581#webpage\"},\"articleSection\":\"Carpeta sobre Paisajes de Suelos y los Suelos en el Paisaje, Diversidad, Complejidad y Fractales, Etnoedafolog\\u00eda y Conocimiento Campesino, Los Suelos las Plantas y la Vegetaci\\u00f3n\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2008\\\/05\\\/22\\\/92581#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/diversidad-complejidad-y-fractales#listItem\",\"name\":\"Diversidad, Complejidad y Fractales\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/diversidad-complejidad-y-fractales#listItem\",\"position\":2,\"name\":\"Diversidad, Complejidad y Fractales\",\"item\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/diversidad-complejidad-y-fractales\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2008\\\/05\\\/22\\\/92581#listItem\",\"name\":\"Sistemas Agroforestales y Sistemas Agrosilvopastorales: \\u00bfCu\\u00e1les son las Diferencias?\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2008\\\/05\\\/22\\\/92581#listItem\",\"position\":3,\"name\":\"Sistemas Agroforestales y Sistemas Agrosilvopastorales: \\u00bfCu\\u00e1les son las Diferencias?\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/category\\\/diversidad-complejidad-y-fractales#listItem\",\"name\":\"Diversidad, Complejidad y Fractales\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#organization\",\"name\":\"Un Universo invisible bajo nuestros pies\",\"description\":\"Los suelos y la vida\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/files\\\/2022\\\/02\\\/logo.png\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2008\\\/05\\\/22\\\/92581\\\/#organizationLogo\",\"width\":217,\"height\":72},\"image\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2008\\\/05\\\/22\\\/92581\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/juan.j.marti.14\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo\",\"name\":\"Juan Jos\\u00e9 Ib\\u00e1\\u00f1ez\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2008\\\/05\\\/22\\\/92581#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/387f3a100385573d8f42ce2a3211fd1c?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Juan Jos\\u00e9 Ib\\u00e1\\u00f1ez\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2008\\\/05\\\/22\\\/92581#webpage\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2008\\\/05\\\/22\\\/92581\",\"name\":\"Sistemas Agroforestales y Sistemas Agrosilvopastorales: \\u00bfCu\\u00e1les son las Diferencias? - Un Universo invisible bajo nuestros pies\",\"description\":\"Desde hace algunas d\\u00e9cadas, se han popularizado los estudios y el valor de los denominados sistemas agroforestales, como alternativas a otros modos de producci\\u00f3n agraria en diversos pa\\u00edses subdesarrollados o en v\\u00edas de desarrollo. Somos partidarios de este tipo de explotaciones por cuanto atesoran un gran inter\\u00e9s, entre los cuales destaca la diversificaci\\u00f3n de las\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/2008\\\/05\\\/22\\\/92581#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/author\\\/universo#author\"},\"datePublished\":\"2008-05-22T10:33:00+01:00\",\"dateModified\":\"2010-01-22T03:47:42+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#website\",\"url\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/\",\"name\":\"Un Universo invisible bajo nuestros pies\",\"description\":\"Los suelos y la vida\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.madrimasd.org\\\/blogs\\\/universo\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Sistemas Agroforestales y Sistemas Agrosilvopastorales: \u00bfCu\u00e1les son las Diferencias? - Un Universo invisible bajo nuestros pies","description":"Desde hace algunas d\u00e9cadas, se han popularizado los estudios y el valor de los denominados sistemas agroforestales, como alternativas a otros modos de producci\u00f3n agraria en diversos pa\u00edses subdesarrollados o en v\u00edas de desarrollo. Somos partidarios de este tipo de explotaciones por cuanto atesoran un gran inter\u00e9s, entre los cuales destaca la diversificaci\u00f3n de las","canonical_url":"https:\/\/www.madrimasd.org\/blogs\/universo\/2008\/05\/22\/92581","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2008\/05\/22\/92581#blogposting","name":"Sistemas Agroforestales y Sistemas Agrosilvopastorales: \u00bfCu\u00e1les son las Diferencias? - Un Universo invisible bajo nuestros pies","headline":"Sistemas Agroforestales y Sistemas Agrosilvopastorales: \u00bfCu\u00e1les son las Diferencias?","author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author"},"publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#organization"},"image":{"@type":"ImageObject","url":"\/blogs\/universo\/wp-content\/blogs.dir\/42\/files\/255\/o_TRANSICION%20MONTE%20DEHESA%20MONFRAGUE.PNG","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2008\/05\/22\/92581\/#articleImage"},"datePublished":"2008-05-22T10:33:00+01:00","dateModified":"2010-01-22T03:47:42+01:00","inLanguage":"es-ES","commentCount":19,"mainEntityOfPage":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2008\/05\/22\/92581#webpage"},"isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2008\/05\/22\/92581#webpage"},"articleSection":"Carpeta sobre Paisajes de Suelos y los Suelos en el Paisaje, Diversidad, Complejidad y Fractales, Etnoedafolog\u00eda y Conocimiento Campesino, Los Suelos las Plantas y la Vegetaci\u00f3n"},{"@type":"BreadcrumbList","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2008\/05\/22\/92581#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo#listItem","position":1,"name":"Home","item":"https:\/\/www.madrimasd.org\/blogs\/universo","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/diversidad-complejidad-y-fractales#listItem","name":"Diversidad, Complejidad y Fractales"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/diversidad-complejidad-y-fractales#listItem","position":2,"name":"Diversidad, Complejidad y Fractales","item":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/diversidad-complejidad-y-fractales","nextItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2008\/05\/22\/92581#listItem","name":"Sistemas Agroforestales y Sistemas Agrosilvopastorales: \u00bfCu\u00e1les son las Diferencias?"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2008\/05\/22\/92581#listItem","position":3,"name":"Sistemas Agroforestales y Sistemas Agrosilvopastorales: \u00bfCu\u00e1les son las Diferencias?","previousItem":{"@type":"ListItem","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/diversidad-complejidad-y-fractales#listItem","name":"Diversidad, Complejidad y Fractales"}}]},{"@type":"Organization","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#organization","name":"Un Universo invisible bajo nuestros pies","description":"Los suelos y la vida","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/","logo":{"@type":"ImageObject","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2008\/05\/22\/92581\/#organizationLogo","width":217,"height":72},"image":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2008\/05\/22\/92581\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/juan.j.marti.14"]},{"@type":"Person","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo","name":"Juan Jos\u00e9 Ib\u00e1\u00f1ez","image":{"@type":"ImageObject","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2008\/05\/22\/92581#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/387f3a100385573d8f42ce2a3211fd1c?s=96&d=mm&r=g","width":96,"height":96,"caption":"Juan Jos\u00e9 Ib\u00e1\u00f1ez"}},{"@type":"WebPage","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2008\/05\/22\/92581#webpage","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/2008\/05\/22\/92581","name":"Sistemas Agroforestales y Sistemas Agrosilvopastorales: \u00bfCu\u00e1les son las Diferencias? - Un Universo invisible bajo nuestros pies","description":"Desde hace algunas d\u00e9cadas, se han popularizado los estudios y el valor de los denominados sistemas agroforestales, como alternativas a otros modos de producci\u00f3n agraria en diversos pa\u00edses subdesarrollados o en v\u00edas de desarrollo. Somos partidarios de este tipo de explotaciones por cuanto atesoran un gran inter\u00e9s, entre los cuales destaca la diversificaci\u00f3n de las","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#website"},"breadcrumb":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/2008\/05\/22\/92581#breadcrumblist"},"author":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author"},"creator":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/author\/universo#author"},"datePublished":"2008-05-22T10:33:00+01:00","dateModified":"2010-01-22T03:47:42+01:00"},{"@type":"WebSite","@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#website","url":"https:\/\/www.madrimasd.org\/blogs\/universo\/","name":"Un Universo invisible bajo nuestros pies","description":"Los suelos y la vida","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.madrimasd.org\/blogs\/universo\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Un Universo invisible bajo nuestros pies - Los suelos y la vida","og:type":"article","og:title":"Sistemas Agroforestales y Sistemas Agrosilvopastorales: \u00bfCu\u00e1les son las Diferencias? - Un Universo invisible bajo nuestros pies","og:description":"Desde hace algunas d\u00e9cadas, se han popularizado los estudios y el valor de los denominados sistemas agroforestales, como alternativas a otros modos de producci\u00f3n agraria en diversos pa\u00edses subdesarrollados o en v\u00edas de desarrollo. Somos partidarios de este tipo de explotaciones por cuanto atesoran un gran inter\u00e9s, entre los cuales destaca la diversificaci\u00f3n de las","og:url":"https:\/\/www.madrimasd.org\/blogs\/universo\/2008\/05\/22\/92581","og:image":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png","og:image:secure_url":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png","article:published_time":"2008-05-22T10:33:00+00:00","article:modified_time":"2010-01-22T02:47:42+00:00","article:publisher":"https:\/\/www.facebook.com\/juan.j.marti.14","twitter:card":"summary","twitter:title":"Sistemas Agroforestales y Sistemas Agrosilvopastorales: \u00bfCu\u00e1les son las Diferencias? - Un Universo invisible bajo nuestros pies","twitter:description":"Desde hace algunas d\u00e9cadas, se han popularizado los estudios y el valor de los denominados sistemas agroforestales, como alternativas a otros modos de producci\u00f3n agraria en diversos pa\u00edses subdesarrollados o en v\u00edas de desarrollo. Somos partidarios de este tipo de explotaciones por cuanto atesoran un gran inter\u00e9s, entre los cuales destaca la diversificaci\u00f3n de las","twitter:image":"https:\/\/www.madrimasd.org\/blogs\/universo\/files\/2022\/02\/logo.png"},"aioseo_meta_data":{"post_id":"92581","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":null,"isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","tabs":null,"priority":null,"frequency":null,"local_seo":null,"created":"2022-06-03 14:21:30","updated":"2026-05-26 15:00:49","limit_modified_date":false,"ai":null,"breadcrumb_settings":null,"seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/diversidad-complejidad-y-fractales\" title=\"Diversidad, Complejidad y Fractales\">Diversidad, Complejidad y Fractales<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tSistemas Agroforestales y Sistemas Agrosilvopastorales: \u00bfCu\u00e1les son las Diferencias?\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.madrimasd.org\/blogs\/universo"},{"label":"Diversidad, Complejidad y Fractales","link":"https:\/\/www.madrimasd.org\/blogs\/universo\/category\/diversidad-complejidad-y-fractales"},{"label":"Sistemas Agroforestales y Sistemas Agrosilvopastorales: \u00bfCu\u00e1les son las Diferencias?","link":"https:\/\/www.madrimasd.org\/blogs\/universo\/2008\/05\/22\/92581"}],"_links":{"self":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts\/92581"}],"collection":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/comments?post=92581"}],"version-history":[{"count":3,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts\/92581\/revisions"}],"predecessor-version":[{"id":134671,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/posts\/92581\/revisions\/134671"}],"wp:attachment":[{"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/media?parent=92581"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/categories?post=92581"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.madrimasd.org\/blogs\/universo\/wp-json\/wp\/v2\/tags?post=92581"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}